{"id":1445193,"date":"2024-02-10T01:33:41","date_gmt":"2024-02-10T09:33:41","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1445193"},"modified":"2024-02-10T01:33:41","modified_gmt":"2024-02-10T09:33:41","slug":"avioneta-se-accidenta-contra-autopista-en-naples-florida-y-deja-al-menos-dos-muertos-2","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2024\/02\/10\/avioneta-se-accidenta-contra-autopista-en-naples-florida-y-deja-al-menos-dos-muertos-2\/","title":{"rendered":"Avioneta se accidenta contra autopista en Naples, Florida, y deja al menos dos muertos"},"content":{"rendered":"<p>(CNN) \u2013\u2013 Al menos dos personas murieron despu\u00e9s de que una avioneta se accidentara y chocara contra un veh\u00edculo en la autopista I-75 en Naples, Florida, este viernes, seg\u00fan las autoridades locales.<\/p>\n<p>La aeronave privada se estrell\u00f3 en los carriles en direcci\u00f3n sur cerca de Pine Ridge Road, seg\u00fan la Patrulla de Carreteras de Florida.<\/p>\n<p>La Administraci\u00f3n Federal de Aviaci\u00f3n (FAA, por sus siglas en ingl\u00e9s) dijo que cinco personas estaban a bordo del Bombardier Challenger 600 cuando se accident\u00f3 alrededor de las 3:15 p.m. La FAA y la Junta Nacional de Seguridad en el Transporte est\u00e1n investigando el incidente.<\/p>\n<p>Los datos de seguimiento de FlightAware muestran que la avioneta despeg\u00f3 del Aeropuerto de la Universidad Estatal de Ohio poco despu\u00e9s de la 1:00 p. m. del viernes y deb\u00eda aterrizar en el Aeropuerto Municipal de Naples antes de partir nuevamente hacia el aeropuerto ejecutivo de Fort Lauderdale.<\/p>\n<p>En una publicaci\u00f3n de Facebook, la Oficina del Sheriff del condado de Collier dijo que hab\u00eda \u201cdos muertes confirmadas\u201d.<\/p>\n<p>Tres personas sobrevivieron al accidente, dijo a CNN Robin King, director de comunicaciones de la Autoridad del Aeropuerto de Naples. King no conoc\u00eda las condiciones de los tres supervivientes.<\/p>\n<p>\u201cLa Administraci\u00f3n Federal de Aviaci\u00f3n cerr\u00f3 una gran secci\u00f3n de la Interestatal 75 en el condado de Collier para investigar el accidente de una aeronave con dos muertes confirmadas&#187;, se le\u00eda en la publicaci\u00f3n.<\/p>\n<p>La oficina del sheriff no especific\u00f3 cu\u00e1ndo reabrir\u00e1 la interestatal.<\/p>\n<p>Poco antes de que los datos de seguimiento de la avioneta mostraran que se hab\u00eda estrellado contra la carretera, un piloto llam\u00f3 por radio a los controladores de tr\u00e1fico a\u00e9reo para informar una emergencia.<\/p>\n<p>\u201cPerd\u00ed ambos motores. Emergencia\u201d, dijo un piloto en transmisiones capturadas por LiveATC.net. &#171;Realice un aterrizaje de emergencia&#187;.<\/p>\n<p>Un controlador de tr\u00e1fico a\u00e9reo autoriz\u00f3 el ingreso de la avioneta a la pista y orden\u00f3 a otro avi\u00f3n que se mantuviera cerca de la pista.<\/p>\n<p>El piloto respondi\u00f3 en la \u00faltima grabaci\u00f3n escuchada desde la aeronave: \u201cAutorizado a aterrizar, pero no vamos a llegar a la pista\u201d.<\/p>\n<p>La aeronave figura en el sitio web Hop-a-jet, con sede en Fort Lauderdale, que dice que puede trasladar hasta 12 pasajeros.<\/p>\n<p>Greg Wallace y Jillian Sykes, los dos de CNN, contribuyeron a este informe.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) \u2013\u2013 Al menos dos personas murieron despu\u00e9s de que una avioneta se accidentara y chocara contra un veh\u00edculo en la autopista I-75 en Naples, Florida, este viernes, seg\u00fan las autoridades locales. La aeronave privada se estrell\u00f3 en los carriles en direcci\u00f3n sur cerca de Pine Ridge Road, seg\u00fan la Patrulla de Carreteras de Florida. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1445193","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Avioneta se accidenta contra autopista en Naples, Florida, y deja al menos dos muertos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/10\/avioneta-se-accidenta-contra-autopista-en-naples-florida-y-deja-al-menos-dos-muertos-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avioneta se accidenta contra autopista en Naples, Florida, y deja al menos dos muertos - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) \u2013\u2013 Al menos dos personas murieron despu\u00e9s de que una avioneta se accidentara y chocara contra un veh\u00edculo en la autopista I-75 en Naples, Florida, este viernes, seg\u00fan las autoridades locales. La aeronave privada se estrell\u00f3 en los carriles en direcci\u00f3n sur cerca de Pine Ridge Road, seg\u00fan la Patrulla de Carreteras de Florida. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/10\/avioneta-se-accidenta-contra-autopista-en-naples-florida-y-deja-al-menos-dos-muertos-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-10T09:33:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/10\/avioneta-se-accidenta-contra-autopista-en-naples-florida-y-deja-al-menos-dos-muertos-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/10\/avioneta-se-accidenta-contra-autopista-en-naples-florida-y-deja-al-menos-dos-muertos-2\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Avioneta se accidenta contra autopista en Naples, Florida, y deja al menos dos muertos\",\"datePublished\":\"2024-02-10T09:33:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/10\/avioneta-se-accidenta-contra-autopista-en-naples-florida-y-deja-al-menos-dos-muertos-2\/\"},\"wordCount\":424,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/10\/avioneta-se-accidenta-contra-autopista-en-naples-florida-y-deja-al-menos-dos-muertos-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/10\/avioneta-se-accidenta-contra-autopista-en-naples-florida-y-deja-al-menos-dos-muertos-2\/\",\"url\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/10\/avioneta-se-accidenta-contra-autopista-en-naples-florida-y-deja-al-menos-dos-muertos-2\/\",\"name\":\"Avioneta se accidenta contra autopista en Naples, Florida, y deja al menos dos muertos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-02-10T09:33:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/10\/avioneta-se-accidenta-contra-autopista-en-naples-florida-y-deja-al-menos-dos-muertos-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/10\/avioneta-se-accidenta-contra-autopista-en-naples-florida-y-deja-al-menos-dos-muertos-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/10\/avioneta-se-accidenta-contra-autopista-en-naples-florida-y-deja-al-menos-dos-muertos-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avioneta se accidenta contra autopista en Naples, Florida, y deja al menos dos muertos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avioneta se accidenta contra autopista en Naples, Florida, y deja al menos dos muertos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/10\/avioneta-se-accidenta-contra-autopista-en-naples-florida-y-deja-al-menos-dos-muertos-2\/","og_locale":"es_ES","og_type":"article","og_title":"Avioneta se accidenta contra autopista en Naples, Florida, y deja al menos dos muertos - Noticias","og_description":"(CNN) \u2013\u2013 Al menos dos personas murieron despu\u00e9s de que una avioneta se accidentara y chocara contra un veh\u00edculo en la autopista I-75 en Naples, Florida, este viernes, seg\u00fan las autoridades locales. La aeronave privada se estrell\u00f3 en los carriles en direcci\u00f3n sur cerca de Pine Ridge Road, seg\u00fan la Patrulla de Carreteras de Florida. [&hellip;]","og_url":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/10\/avioneta-se-accidenta-contra-autopista-en-naples-florida-y-deja-al-menos-dos-muertos-2\/","og_site_name":"Noticias","article_published_time":"2024-02-10T09:33:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/10\/avioneta-se-accidenta-contra-autopista-en-naples-florida-y-deja-al-menos-dos-muertos-2\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/10\/avioneta-se-accidenta-contra-autopista-en-naples-florida-y-deja-al-menos-dos-muertos-2\/"},"author":{"name":"","@id":""},"headline":"Avioneta se accidenta contra autopista en Naples, Florida, y deja al menos dos muertos","datePublished":"2024-02-10T09:33:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/10\/avioneta-se-accidenta-contra-autopista-en-naples-florida-y-deja-al-menos-dos-muertos-2\/"},"wordCount":424,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/el-centro\/2024\/02\/10\/avioneta-se-accidenta-contra-autopista-en-naples-florida-y-deja-al-menos-dos-muertos-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/10\/avioneta-se-accidenta-contra-autopista-en-naples-florida-y-deja-al-menos-dos-muertos-2\/","url":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/10\/avioneta-se-accidenta-contra-autopista-en-naples-florida-y-deja-al-menos-dos-muertos-2\/","name":"Avioneta se accidenta contra autopista en Naples, Florida, y deja al menos dos muertos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-02-10T09:33:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/10\/avioneta-se-accidenta-contra-autopista-en-naples-florida-y-deja-al-menos-dos-muertos-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/el-centro\/2024\/02\/10\/avioneta-se-accidenta-contra-autopista-en-naples-florida-y-deja-al-menos-dos-muertos-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/10\/avioneta-se-accidenta-contra-autopista-en-naples-florida-y-deja-al-menos-dos-muertos-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Avioneta se accidenta contra autopista en Naples, Florida, y deja al menos dos muertos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/10\/avioneta-se-accidenta-contra-autopista-en-naples-florida-y-deja-al-menos-dos-muertos-2\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Avioneta se accidenta contra autopista en Naples, Florida, y deja al menos dos muertos","url":"http:\/\/noticiasya.com\/colorado\/2024\/02\/10\/avioneta-se-accidenta-contra-autopista-en-naples-florida-y-deja-al-menos-dos-muertos-2\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2024\/02\/10\/avioneta-se-accidenta-contra-autopista-en-naples-florida-y-deja-al-menos-dos-muertos-2\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-02-10T09:33:41Z","datePublished":"2024-02-10T09:33:41Z","dateModified":"2024-02-10T09:33:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Avioneta se accidenta contra autopista en Naples, Florida, y deja al menos dos muertos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2024\\\/02\\\/10\\\/avioneta-se-accidenta-contra-autopista-en-naples-florida-y-deja-al-menos-dos-muertos-2\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2024\\\/02\\\/10\\\/avioneta-se-accidenta-contra-autopista-en-naples-florida-y-deja-al-menos-dos-muertos-2\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-02-10T09:33:41Z\",\"datePublished\":\"2024-02-10T09:33:41Z\",\"dateModified\":\"2024-02-10T09:33:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1445241,"url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/11\/avioneta-se-accidenta-en-una-autopista-en-naples-florida-y-deja-dos-personas-muertas\/","url_meta":{"origin":1445193,"position":0},"title":"Avioneta se accidenta en una autopista en Naples, Florida, y deja dos personas muertas","author":"","date":"febrero 11, 2024","format":false,"excerpt":"(CNN) \u2013Dos personas murieron luego de que una avioneta se estrellara el viernes por la tarde en la Interestatal 75 cerca de la ciudad de Naples, en Florida, y chocara con un veh\u00edculo, dijeron las autoridades.\u00a0 El accidente que ocurri\u00f3 poco despu\u00e9s de que un piloto informara de una emergencia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445188,"url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/09\/avioneta-se-accidenta-contra-autopista-en-naples-florida-y-deja-al-menos-dos-muertos\/","url_meta":{"origin":1445193,"position":1},"title":"Avioneta se accidenta contra autopista en Naples, Florida, y deja al menos dos muertos","author":"","date":"febrero 9, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Al menos dos personas murieron despu\u00e9s de que una avioneta se estrellara en la autopista I75 en Naples, Florida, inform\u00f3 la Oficina del Sheriff del condado de Collier en una publicaci\u00f3n de Facebook.\u201cLa Administraci\u00f3n Federal de Aviaci\u00f3n cerr\u00f3 una gran secci\u00f3n de la Interestatal 75 en el condado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461075,"url":"https:\/\/noticiasya.com\/colorado\/2025\/04\/11\/avioneta-se-estrella-fuego-concurrida-calle-boca-raton-florida-trax\/","url_meta":{"origin":1445193,"position":2},"title":"Avioneta se estrella y se prende fuego en una concurrida calle de Boca Rat\u00f3n, Florida","author":"","date":"abril 11, 2025","format":false,"excerpt":"Una avioneta se estrell\u00f3 y se prendi\u00f3 fuego este viernes a las afueras del aeropuerto de Boca Rat\u00f3n, Florida, en una concurrida calle de la ciudad, dijo la Polic\u00eda a CNN.\u201cEstamos profundamente tristes de confirmar que un accidente a\u00e9reo ocurri\u00f3 hoy temprano dentro de nuestra comunidad\u201d, dijo el alcalde de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458393,"url":"https:\/\/noticiasya.com\/colorado\/2025\/02\/07\/choque-avioneta-autobus-sao-paulo-brasil-al-menos-2-muertos-trax\/","url_meta":{"origin":1445193,"position":3},"title":"Mueren dos personas al estrellarse una avioneta contra un autob\u00fas en una avenida de Sao Paulo","author":"","date":"febrero 7, 2025","format":false,"excerpt":"Al menos dos personas murieron este viernes despu\u00e9s de que una avioneta se precipitara sobre una carretera muy transitada y chocara con un autob\u00fas en Sao Paulo, en el sur de Brasil, dejando heridas a varias personas m\u00e1s.El accidente tuvo lugar alrededor de las 7:20 a.m. hora local (5:20 a.m.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460594,"url":"https:\/\/noticiasya.com\/colorado\/2025\/03\/29\/avioneta-estrella-casa-incendio-minneapolis-trax\/","url_meta":{"origin":1445193,"position":4},"title":"Una avioneta se estrella contra una casa cerca de Minneapolis y provoca un incendio, seg\u00fan las autoridades","author":"","date":"marzo 29, 2025","format":false,"excerpt":"Una avioneta se estrell\u00f3 contra una vivienda en Brooklyn Park, Minnesota, este s\u00e1bado por la tarde, incendiando la casa, seg\u00fan informaron las autoridades.La aeronave, un peque\u00f1o avi\u00f3n de transporte ejecutivo con capacidad para seis personas, choc\u00f3 contra la vivienda sobre las 12:20 p.m. (hora local) cuando se dirig\u00eda al aeropuerto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463366,"url":"https:\/\/noticiasya.com\/colorado\/2025\/06\/09\/mueren-seis-personas-avioneta-estrellada-san-diego-trax\/","url_meta":{"origin":1445193,"position":5},"title":"Mueren seis personas al estrellarse una avioneta frente a San Diego","author":"","date":"junio 9, 2025","format":false,"excerpt":"Seis personas murieron al estrellarse una avioneta en el oc\u00e9ano frente a San Diego el domingo por la tarde, inform\u00f3 el lunes la Administraci\u00f3n Federal de Aviaci\u00f3n.Los \u00faltimos momentos antes de que el bimotor Cessna se estrellara -lo que desencaden\u00f3 una gran b\u00fasqueda en el oc\u00e9ano Pac\u00edfico cerca de San\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1445193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1445193"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1445193\/revisions"}],"predecessor-version":[{"id":1445211,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1445193\/revisions\/1445211"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1445193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1445193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1445193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}