{"id":1446537,"date":"2024-03-05T15:22:40","date_gmt":"2024-03-05T23:22:40","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/05\/haiti-primer-ministro-puerto-rico-ariel-henry-trax\/"},"modified":"2024-03-07T04:45:12","modified_gmt":"2024-03-07T12:45:12","slug":"haiti-primer-ministro-puerto-rico-ariel-henry-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2024\/03\/05\/haiti-primer-ministro-puerto-rico-ariel-henry-trax\/","title":{"rendered":"El primer ministro de Hait\u00ed, Ariel Henry, aterriza en Puerto Rico"},"content":{"rendered":"<p>(CNN) \u2013\u2013 Un avi\u00f3n que transportaba al primer ministro de Hait\u00ed, Ariel Henry, aterriz\u00f3 este martes en Puerto Rico, confirm\u00f3 Sheila Angler\u00f3 Mojica, portavoz del gobernador Pedro Pierluisi, a CNN.<\/p>\n<p>Angler\u00f3 indic\u00f3 que no ten\u00eda detalles adicionales sobre el asunto pero agreg\u00f3 que &#171;agentes federales de la Oficina Aduanas y Protecci\u00f3n Fronteriza de Estados Unidos (CBP, por sus siglas en ingl\u00e9s) est\u00e1n a cargo&#187;, sin proporcionar m\u00e1s informaci\u00f3n.<\/p>\n<p>Miles y miles de desplazados en Hait\u00ed<\/p>\n<p>El viaje de Henry ocurre mientras una ola de violencia en Hait\u00ed ha obligado a aproximadamente 15.000 personas a huir de sus hogares en Puerto Pr\u00edncipe, la capital, seg\u00fan inform\u00f3 St\u00e9phane Dujarric, portavoz de la ONU, citando a la Oficina de Coordinaci\u00f3n de Asuntos Humanitarios.<\/p>\n<p>&#171;La mayor\u00eda de estas personas ya hab\u00edan sido desplazadas anteriormente&#187;, explic\u00f3 Dujarric.<\/p>\n<p>A pesar de las preocupaciones de seguridad, los socios humanitarios de la ONU han distribuido colchones, kits de higiene, alimentos, l\u00e1mparas y otra ayuda necesaria, dijo el portavoz.<\/p>\n<p>Las pandillas controlan la capital de Hait\u00ed. Algunos dicen que tambi\u00e9n est\u00e1n dispuestos a derrocar al Gobierno<\/p>\n<p>El Programa Mundial de Alimentos ha entregado alrededor de 5.500 comidas calientes a personas que viven en tres nuevos sitios de desplazamiento, mientras que la Organizaci\u00f3n Internacional para las Migraciones ha distribuido materiales para refugios de emergencia a m\u00e1s de 300 familias, a\u00f1adi\u00f3 Dujarric.<\/p>\n<p>La mitad de la poblaci\u00f3n de Hait\u00ed, 5,5 millones de personas, necesita asistencia humanitaria, destac\u00f3 la ONU.<\/p>\n<p>La situaci\u00f3n que se desat\u00f3 en Puerto Pr\u00edncipe la semana pasada incluy\u00f3 una fuga masiva de prisi\u00f3n y un aumento de la violencia de pandillas, lo que promovi\u00f3 una declaraci\u00f3n de estado de emergencia por parte del Gobierno.<\/p>\n<p>Cara a cara con el l\u00edder pandillero m\u00e1s notorio de Hait\u00ed<\/p>\n<p>El secretario general de la ONU, Ant\u00f3nio Guterres, dijo que est\u00e1 \u201cprofundamente preocupado\u201d por el r\u00e1pido deterioro de la situaci\u00f3n de seguridad en Hait\u00ed y su impacto en la poblaci\u00f3n civil de Hait\u00ed, afirm\u00f3 Dujjaric.<\/p>\n<p>Rep\u00fablica Dominicana suspende operaciones a\u00e9reas desde y hacia Hait\u00ed<\/p>\n<p>Rep\u00fablica Dominicana suspendi\u00f3 este martes con efecto inmediato las operaciones a\u00e9reas de pasajeros y carga desde y hacia Hait\u00ed, seg\u00fan un comunicado que cita la resoluci\u00f3n No.46-2024 emitida por la Junta de Aviaci\u00f3n Civil de Rep\u00fablica Dominicana (JAC).<\/p>\n<p>En el mismo, el presidente de la JAC, Jos\u00e9 Ernesto Marte Piantini, explica que &#171;las circunstancias excepcionales, durante un per\u00edodo de emergencia o en inter\u00e9s de la seguridad p\u00fablica, a restringir o prohibir temporalmente y con efecto inmediato los vuelos sobre todo su territorio o parte del mismo&#187;.<\/p>\n<p>Apenas este lunes, el presidente de Rep\u00fablica Dominicana, Luis Abinader, inform\u00f3 que rige un nivel extremo de seguridad en la frontera con Hait\u00ed luego de la fuga de m\u00e1s de 3.500 presos en el vecino pa\u00eds durante el fin de semana.<\/p>\n<p>Aunque el jefe de Estado no revel\u00f3 en qu\u00e9 consiste el incremento de la seguridad fronteriza advirti\u00f3 que cualquier reo haitiano fugado que ingrese al pa\u00eds tendr\u00e1 \u201cuna respuesta dr\u00e1stica\u201d.<\/p>\n<p>Los soldados desplegados en la frontera &#171;est\u00e1n preparados para prevenir o disuadir cualquier incidente&#187; que arriesgue la tranquilidad de la zona, seg\u00fan inform\u00f3 este martes el ministro de Defensa, teniente general Carlos Luciano D\u00edaz Morfa.<\/p>\n<p>Noticia en desarrollo&#8230;<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) \u2013\u2013 Un avi\u00f3n que transportaba al primer ministro de Hait\u00ed, Ariel Henry, aterriz\u00f3 este martes en Puerto Rico, confirm\u00f3 Sheila Angler\u00f3 Mojica, portavoz del gobernador Pedro Pierluisi, a CNN. Angler\u00f3 indic\u00f3 que no ten\u00eda detalles adicionales sobre el asunto pero agreg\u00f3 que &#171;agentes federales de la Oficina Aduanas y Protecci\u00f3n Fronteriza de Estados Unidos [&hellip;]<\/p>\n","protected":false},"author":186172566,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1446537","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El primer ministro de Hait\u00ed, Ariel Henry, aterriza en Puerto Rico - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/03\/05\/haiti-primer-ministro-puerto-rico-ariel-henry-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El primer ministro de Hait\u00ed, Ariel Henry, aterriza en Puerto Rico - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) \u2013\u2013 Un avi\u00f3n que transportaba al primer ministro de Hait\u00ed, Ariel Henry, aterriz\u00f3 este martes en Puerto Rico, confirm\u00f3 Sheila Angler\u00f3 Mojica, portavoz del gobernador Pedro Pierluisi, a CNN. Angler\u00f3 indic\u00f3 que no ten\u00eda detalles adicionales sobre el asunto pero agreg\u00f3 que &#171;agentes federales de la Oficina Aduanas y Protecci\u00f3n Fronteriza de Estados Unidos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/03\/05\/haiti-primer-ministro-puerto-rico-ariel-henry-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-05T23:22:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-07T12:45:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/03\/05\/haiti-primer-ministro-puerto-rico-ariel-henry-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/03\/05\/haiti-primer-ministro-puerto-rico-ariel-henry-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El primer ministro de Hait\u00ed, Ariel Henry, aterriza en Puerto Rico\",\"datePublished\":\"2024-03-05T23:22:40+00:00\",\"dateModified\":\"2024-03-07T12:45:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/03\/05\/haiti-primer-ministro-puerto-rico-ariel-henry-trax\/\"},\"wordCount\":597,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/03\/05\/haiti-primer-ministro-puerto-rico-ariel-henry-trax\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/03\/05\/haiti-primer-ministro-puerto-rico-ariel-henry-trax\/\",\"name\":\"El primer ministro de Hait\u00ed, Ariel Henry, aterriza en Puerto Rico - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-05T23:22:40+00:00\",\"dateModified\":\"2024-03-07T12:45:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/03\/05\/haiti-primer-ministro-puerto-rico-ariel-henry-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/03\/05\/haiti-primer-ministro-puerto-rico-ariel-henry-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/03\/05\/haiti-primer-ministro-puerto-rico-ariel-henry-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El primer ministro de Hait\u00ed, Ariel Henry, aterriza en Puerto Rico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/noticiasya.com\/colorado\/author\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El primer ministro de Hait\u00ed, Ariel Henry, aterriza en Puerto Rico - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/03\/05\/haiti-primer-ministro-puerto-rico-ariel-henry-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El primer ministro de Hait\u00ed, Ariel Henry, aterriza en Puerto Rico - Noticias","og_description":"(CNN) \u2013\u2013 Un avi\u00f3n que transportaba al primer ministro de Hait\u00ed, Ariel Henry, aterriz\u00f3 este martes en Puerto Rico, confirm\u00f3 Sheila Angler\u00f3 Mojica, portavoz del gobernador Pedro Pierluisi, a CNN. Angler\u00f3 indic\u00f3 que no ten\u00eda detalles adicionales sobre el asunto pero agreg\u00f3 que &#171;agentes federales de la Oficina Aduanas y Protecci\u00f3n Fronteriza de Estados Unidos [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/03\/05\/haiti-primer-ministro-puerto-rico-ariel-henry-trax\/","og_site_name":"Noticias","article_published_time":"2024-03-05T23:22:40+00:00","article_modified_time":"2024-03-07T12:45:12+00:00","twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/03\/05\/haiti-primer-ministro-puerto-rico-ariel-henry-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/03\/05\/haiti-primer-ministro-puerto-rico-ariel-henry-trax\/"},"author":{"name":"","@id":""},"headline":"El primer ministro de Hait\u00ed, Ariel Henry, aterriza en Puerto Rico","datePublished":"2024-03-05T23:22:40+00:00","dateModified":"2024-03-07T12:45:12+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/03\/05\/haiti-primer-ministro-puerto-rico-ariel-henry-trax\/"},"wordCount":597,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/03\/05\/haiti-primer-ministro-puerto-rico-ariel-henry-trax\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/03\/05\/haiti-primer-ministro-puerto-rico-ariel-henry-trax\/","name":"El primer ministro de Hait\u00ed, Ariel Henry, aterriza en Puerto Rico - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-05T23:22:40+00:00","dateModified":"2024-03-07T12:45:12+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/03\/05\/haiti-primer-ministro-puerto-rico-ariel-henry-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/03\/05\/haiti-primer-ministro-puerto-rico-ariel-henry-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/03\/05\/haiti-primer-ministro-puerto-rico-ariel-henry-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El primer ministro de Hait\u00ed, Ariel Henry, aterriza en Puerto Rico"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/noticiasya.com\/colorado\/author"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2024\/03\/05\/haiti-primer-ministro-puerto-rico-ariel-henry-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El primer ministro de Hait\u00ed, Ariel Henry, aterriza en Puerto Rico","url":"http:\/\/noticiasya.com\/colorado\/2024\/03\/05\/haiti-primer-ministro-puerto-rico-ariel-henry-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2024\/03\/05\/haiti-primer-ministro-puerto-rico-ariel-henry-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-05T23:22:40Z","datePublished":"2024-03-05T23:22:40Z","dateModified":"2024-03-07T12:45:12Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El primer ministro de Hait\\u00ed, Ariel Henry, aterriza en Puerto Rico\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2024\\\/03\\\/05\\\/haiti-primer-ministro-puerto-rico-ariel-henry-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2024\\\/03\\\/05\\\/haiti-primer-ministro-puerto-rico-ariel-henry-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-05T23:22:40Z\",\"datePublished\":\"2024-03-05T23:22:40Z\",\"dateModified\":\"2024-03-07T12:45:12Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1446921,"url":"https:\/\/noticiasya.com\/colorado\/2024\/03\/13\/haiti-ariel-henry-consejo-de-transicion-constitucion-violencia-pandillas-trax\/","url_meta":{"origin":1446537,"position":0},"title":"La Constituci\u00f3n exige que el primer ministro apruebe el consejo de transici\u00f3n, dice la oficina de Ariel Henry, que podr\u00eda regresar a Hait\u00ed","author":"","date":"marzo 13, 2024","format":false,"excerpt":"(CNN) -- El asediado primer ministro de Hait\u00ed, Ariel Henry, sostiene que seg\u00fan la constituci\u00f3n del pa\u00eds, s\u00f3lo el primer ministro, junto con el gabinete, puede nombrar un consejo presentador para una transici\u00f3n de poder, dijo la oficina de Henry en un comunicado exclusivo a CNN el mi\u00e9rcoles.\u201cSeg\u00fan la Constituci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446871,"url":"https:\/\/noticiasya.com\/colorado\/2024\/03\/11\/dimite-ariel-henry-primer-ministro-haiti-trax\/","url_meta":{"origin":1446537,"position":1},"title":"Dimite el primer ministro de Hait\u00ed, Ariel Henry, mientras las bandas se desplazan a sus anchas por un pa\u00eds sumido en la crisis","author":"","date":"marzo 11, 2024","format":false,"excerpt":"(CNN) -- El asediado l\u00edder de Hait\u00ed, Ariel Henry, present\u00f3 su dimisi\u00f3n este lunes en la noche, seg\u00fan l\u00edderes regionales, tras semanas de caos creciente en la naci\u00f3n caribe\u00f1a, donde las bandas han estado atacando las estructuras gubernamentales y el orden social est\u00e1 al borde del colapso.El asesor del primer\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446905,"url":"https:\/\/noticiasya.com\/colorado\/2024\/03\/12\/que-sigue-haiti-tras-dimision-primer-ministro-ariel-henry-pandillas-trax\/","url_meta":{"origin":1446537,"position":2},"title":"\u00bfQu\u00e9 sigue para Hait\u00ed tras la dimisi\u00f3n del primer ministro de Ariel Henry?","author":"","date":"marzo 12, 2024","format":false,"excerpt":"(CNN) -- El primer ministro de Hait\u00ed, Ariel Henry, anunci\u00f3 su dimisi\u00f3n luego de una reuni\u00f3n de l\u00edderes regionales del Caribe el lunes, cediendo ante lo inevitable a medida que la ley y el orden en el pa\u00eds colapsaban y crec\u00eda la presi\u00f3n internacional para que dejara el cargo.Henry se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446258,"url":"https:\/\/noticiasya.com\/colorado\/2024\/03\/03\/fuga-presos-carcel-puerto-principe-haiti-pandillas-trax\/","url_meta":{"origin":1446537,"position":3},"title":"Se estima que m\u00e1s de 3.000 reclusos escaparon de la prisi\u00f3n de Hait\u00ed en medio de la violencia en Puerto Pr\u00edncipe","author":"","date":"marzo 3, 2024","format":false,"excerpt":"(CNN) --\u00a0Se cree que alrededor de 3.500 prisioneros escaparon de la Penitenciar\u00eda Nacional de Hait\u00ed durante un brote de violencia este fin de semana, seg\u00fan estimaciones de la ONU, aunque las condiciones no han permitido realizar un recuento completo, dijo el domingo una fuente de la ONU.Seg\u00fan la fuente, hab\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446403,"url":"https:\/\/noticiasya.com\/colorado\/2024\/03\/04\/fuga-presos-carcel-puerto-principe-haiti-pandillas-trax-2\/","url_meta":{"origin":1446537,"position":4},"title":"Se estima que m\u00e1s de 3.000 reclusos escaparon de una prisi\u00f3n de Hait\u00ed en medio de la violencia en Puerto Pr\u00edncipe","author":"agomez","date":"marzo 4, 2024","format":false,"excerpt":"(CNN) --\u00a0 El gobierno de Hait\u00ed declar\u00f3 el estado de emergencia este domingo por la noche y un toque de queda en medio de la creciente violencia de las pandillas y dos fugas de prisi\u00f3n durante el fin de semana.El gobierno cit\u00f3 el \"deterioro de la seguridad\", en particular en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446927,"url":"https:\/\/noticiasya.com\/colorado\/2024\/03\/13\/gobierno-biden-guantanamo-inmigrantes-haitianos-trax\/","url_meta":{"origin":1446537,"position":5},"title":"El Gobierno de Biden eval\u00faa utilizar Guant\u00e1namo ante la posible llegada de inmigrantes haitianos","author":"agomez","date":"marzo 13, 2024","format":false,"excerpt":"(CNN) -- El Gobierno del presidente Joe Biden eval\u00faa la posibilidad de utilizar la Bah\u00eda de Guant\u00e1namo para procesar a los posibles migrantes haitianos que lleguen, ante la preocupaci\u00f3n de un \u00e9xodo masivo en medio del la ola de violencia que atraviesa el pa\u00eds, seg\u00fan un funcionario estadounidense.Desde hace a\u00f1os,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1446537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/users\/186172566"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1446537"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1446537\/revisions"}],"predecessor-version":[{"id":1446584,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1446537\/revisions\/1446584"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1446537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1446537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1446537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}