{"id":1468414,"date":"2025-11-17T01:03:52","date_gmt":"2025-11-17T09:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/17\/reverendo-jesse-jackson-hospitalizado-presion-arterial-trax\/"},"modified":"2025-11-17T01:03:52","modified_gmt":"2025-11-17T09:03:52","slug":"reverendo-jesse-jackson-hospitalizado-presion-arterial-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2025\/11\/17\/reverendo-jesse-jackson-hospitalizado-presion-arterial-trax\/","title":{"rendered":"Seg\u00fan fuentes, el reverendo Jesse Jackson permanece hospitalizado tras recibir tratamiento para estabilizar presi\u00f3n arterial"},"content":{"rendered":"<p>El l\u00edder de los derechos civiles, el reverendo Jesse Jackson, permanece hospitalizado y estuvo recibiendo atenci\u00f3n para controlar su presi\u00f3n arterial, seg\u00fan informaron el domingo a CNN fuentes cercanas a la familia de Jackson.<\/p>\n<p>En un comunicado difundido el domingo por la tarde, la familia inform\u00f3 que respira por s\u00ed mismo sin ayuda de m\u00e1quinas y que no est\u00e1 conectado a un respirador artificial. Otra fuente a\u00f1adi\u00f3 que, previamente, hab\u00eda estado recibiendo medicaci\u00f3n para elevar su presi\u00f3n arterial, lo cual constituye una forma de soporte vital.<\/p>\n<p>En las \u00faltimas 24 horas, el estado de Jackson ha mejorado y ha podido mantener una presi\u00f3n arterial estable sin la ayuda de medicamentos.<\/p>\n<p>Jackson, de 84 a\u00f1os, un protegido del reverendo Martin Luther King Jr., ha estado bajo observaci\u00f3n por par\u00e1lisis supranuclear progresiva (PSP), dijo la Coalici\u00f3n Rainbow PUSH el mi\u00e9rcoles por la noche.<\/p>\n<p>No se han facilitado m\u00e1s detalles sobre su estado de salud.<\/p>\n<p>Seg\u00fan una fuente familiar, Jackson ha tenido breves momentos de energ\u00eda debido a un medicamento que ha estado tomando durante dos d\u00edas. La fuente a\u00f1adi\u00f3 que Jackson sufri\u00f3 una bajada importante de la presi\u00f3n arterial el s\u00e1bado por la noche, pero un equipo m\u00e9dico lo atendi\u00f3 de inmediato.<\/p>\n<p>Incluso estando bajo tratamiento, ha mostrado breves pero significativas se\u00f1ales de respuesta, dijo la fuente.<\/p>\n<p>En el comunicado emitido el domingo por la tarde, su hijo Yusef dijo: \u201cDe hecho, hoy pidi\u00f3 a 2.000 iglesias que preparen 2.000 cestas de alimentos para prevenir la desnutrici\u00f3n durante la temporada navide\u00f1a\u201d.<\/p>\n<p>La semana pasada se hab\u00eda producido una \u201cmejora significativa\u201d en el estado de salud del l\u00edder de los derechos civiles bajo atenci\u00f3n m\u00e9dica, dijo su hijo Jesse Jackson Jr. el jueves en un segmento de su programa de radio diario.<\/p>\n<p>La PSP es \u201cun trastorno neurol\u00f3gico poco com\u00fan que afecta los movimientos corporales, la marcha y el equilibrio, y los movimientos oculares\u201d, seg\u00fan el <a href=\"https:\/\/www.ninds.nih.gov\/health-information\/disorders\/progressive-supranuclear-palsy-psp\">Instituto Nacional de Trastornos Neurol\u00f3gicos y Accidentes Cerebrovasculares de Estados Unidos<\/a>.<\/p>\n<p>La enfermedad suele comenzar alrededor de los 60 a\u00f1os y presenta algunos s\u00edntomas similares a los de la enfermedad de Parkinson. La mayor\u00eda de las personas con PSP desarrollan una discapacidad grave en un plazo de tres a cinco a\u00f1os.<\/p>\n<p>Jackson \u201clleva m\u00e1s de una d\u00e9cada lidiando con esta enfermedad neurodegenerativa\u201d, seg\u00fan inform\u00f3 la organizaci\u00f3n en un comunicado. \u201cInicialmente se le diagnostic\u00f3 la enfermedad de Parkinson <strong>;<\/strong> sin embargo, en abril del a\u00f1o pasado se confirm\u00f3 que padec\u00eda par\u00e1lisis supranuclear progresiva (PSP)\u201d.<\/p>\n<p>Jackson alcanz\u00f3 notoriedad nacional en la d\u00e9cada de 1960 como estrecho colaborador de King. Tras el asesinato de King en 1968, Jackson se convirti\u00f3 en uno de los l\u00edderes de los derechos civiles m\u00e1s influyentes de Estados Unidos.<\/p>\n<p>En 1971, fund\u00f3 Operation PUSH como una forma de mejorar las condiciones econ\u00f3micas de las comunidades negras en todo Estados Unidos. Posteriormente, en 1984, Jackson lanz\u00f3 la National Rainbow Coalition con el objetivo de obtener la igualdad de derechos para todos los estadounidenses, seg\u00fan la Rainbow PUSH Coalition.<\/p>\n<p>Doce a\u00f1os despu\u00e9s, las dos organizaciones se fusionaron para formar la Coalici\u00f3n Rainbow PUSH.<\/p>\n<p>Una de las frases caracter\u00edsticas de Jackson ha sido \u201cMantengan viva la esperanza\u201d, y fue una fuerza impulsora de la justicia social durante tres \u00e9pocas: el per\u00edodo de Jim Crow, la era de los derechos civiles y la era posterior a los derechos civiles, que culmin\u00f3 con la elecci\u00f3n de Barack Obama y el movimiento Black Lives Matter.<\/p>\n<p><em>Esta noticia ha sido actualizada con informaci\u00f3n adicional.<\/em><\/p>\n<p><em>Amanda Musa, de CNN, contribuy\u00f3 a este informe.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El l\u00edder de los derechos civiles, el reverendo Jesse Jackson, permanece hospitalizado y estuvo recibiendo atenci\u00f3n para controlar su presi\u00f3n arterial, seg\u00fan informaron el domingo a CNN fuentes cercanas a la familia de Jackson. En un comunicado difundido el domingo por la tarde, la familia inform\u00f3 que respira por s\u00ed mismo sin ayuda de m\u00e1quinas [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468414","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Seg\u00fan fuentes, el reverendo Jesse Jackson permanece hospitalizado tras recibir tratamiento para estabilizar presi\u00f3n arterial - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/17\/reverendo-jesse-jackson-hospitalizado-presion-arterial-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Seg\u00fan fuentes, el reverendo Jesse Jackson permanece hospitalizado tras recibir tratamiento para estabilizar presi\u00f3n arterial - Noticias\" \/>\n<meta property=\"og:description\" content=\"El l\u00edder de los derechos civiles, el reverendo Jesse Jackson, permanece hospitalizado y estuvo recibiendo atenci\u00f3n para controlar su presi\u00f3n arterial, seg\u00fan informaron el domingo a CNN fuentes cercanas a la familia de Jackson. En un comunicado difundido el domingo por la tarde, la familia inform\u00f3 que respira por s\u00ed mismo sin ayuda de m\u00e1quinas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/17\/reverendo-jesse-jackson-hospitalizado-presion-arterial-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-17T09:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/17\/reverendo-jesse-jackson-hospitalizado-presion-arterial-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/17\/reverendo-jesse-jackson-hospitalizado-presion-arterial-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Seg\u00fan fuentes, el reverendo Jesse Jackson permanece hospitalizado tras recibir tratamiento para estabilizar presi\u00f3n arterial\",\"datePublished\":\"2025-11-17T09:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/17\/reverendo-jesse-jackson-hospitalizado-presion-arterial-trax\/\"},\"wordCount\":660,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/17\/reverendo-jesse-jackson-hospitalizado-presion-arterial-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/17\/reverendo-jesse-jackson-hospitalizado-presion-arterial-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/17\/reverendo-jesse-jackson-hospitalizado-presion-arterial-trax\/\",\"name\":\"Seg\u00fan fuentes, el reverendo Jesse Jackson permanece hospitalizado tras recibir tratamiento para estabilizar presi\u00f3n arterial - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-17T09:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/17\/reverendo-jesse-jackson-hospitalizado-presion-arterial-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/17\/reverendo-jesse-jackson-hospitalizado-presion-arterial-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/17\/reverendo-jesse-jackson-hospitalizado-presion-arterial-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Seg\u00fan fuentes, el reverendo Jesse Jackson permanece hospitalizado tras recibir tratamiento para estabilizar presi\u00f3n arterial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Seg\u00fan fuentes, el reverendo Jesse Jackson permanece hospitalizado tras recibir tratamiento para estabilizar presi\u00f3n arterial - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/17\/reverendo-jesse-jackson-hospitalizado-presion-arterial-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Seg\u00fan fuentes, el reverendo Jesse Jackson permanece hospitalizado tras recibir tratamiento para estabilizar presi\u00f3n arterial - Noticias","og_description":"El l\u00edder de los derechos civiles, el reverendo Jesse Jackson, permanece hospitalizado y estuvo recibiendo atenci\u00f3n para controlar su presi\u00f3n arterial, seg\u00fan informaron el domingo a CNN fuentes cercanas a la familia de Jackson. En un comunicado difundido el domingo por la tarde, la familia inform\u00f3 que respira por s\u00ed mismo sin ayuda de m\u00e1quinas [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/17\/reverendo-jesse-jackson-hospitalizado-presion-arterial-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-17T09:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/17\/reverendo-jesse-jackson-hospitalizado-presion-arterial-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/17\/reverendo-jesse-jackson-hospitalizado-presion-arterial-trax\/"},"author":{"name":"","@id":""},"headline":"Seg\u00fan fuentes, el reverendo Jesse Jackson permanece hospitalizado tras recibir tratamiento para estabilizar presi\u00f3n arterial","datePublished":"2025-11-17T09:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/17\/reverendo-jesse-jackson-hospitalizado-presion-arterial-trax\/"},"wordCount":660,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/17\/reverendo-jesse-jackson-hospitalizado-presion-arterial-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/17\/reverendo-jesse-jackson-hospitalizado-presion-arterial-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/17\/reverendo-jesse-jackson-hospitalizado-presion-arterial-trax\/","name":"Seg\u00fan fuentes, el reverendo Jesse Jackson permanece hospitalizado tras recibir tratamiento para estabilizar presi\u00f3n arterial - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-17T09:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/17\/reverendo-jesse-jackson-hospitalizado-presion-arterial-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/17\/reverendo-jesse-jackson-hospitalizado-presion-arterial-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/17\/reverendo-jesse-jackson-hospitalizado-presion-arterial-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Seg\u00fan fuentes, el reverendo Jesse Jackson permanece hospitalizado tras recibir tratamiento para estabilizar presi\u00f3n arterial"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/17\/reverendo-jesse-jackson-hospitalizado-presion-arterial-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Seg\u00fan fuentes, el reverendo Jesse Jackson permanece hospitalizado tras recibir tratamiento para estabilizar presi\u00f3n arterial","url":"http:\/\/noticiasya.com\/colorado\/2025\/11\/17\/reverendo-jesse-jackson-hospitalizado-presion-arterial-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2025\/11\/17\/reverendo-jesse-jackson-hospitalizado-presion-arterial-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-17T09:03:52Z","datePublished":"2025-11-17T09:03:52Z","dateModified":"2025-11-17T09:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Seg\\u00fan fuentes, el reverendo Jesse Jackson permanece hospitalizado tras recibir tratamiento para estabilizar presi\\u00f3n arterial\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2025\\\/11\\\/17\\\/reverendo-jesse-jackson-hospitalizado-presion-arterial-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2025\\\/11\\\/17\\\/reverendo-jesse-jackson-hospitalizado-presion-arterial-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-17T09:03:52Z\",\"datePublished\":\"2025-11-17T09:03:52Z\",\"dateModified\":\"2025-11-17T09:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1468680,"url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/25\/jesse-jackson-sale-hospital-trax\/","url_meta":{"origin":1468414,"position":0},"title":"Sale del hospital el l\u00edder de derechos civiles Jesse Jackson tras un tratamiento en la UCI","author":"","date":"noviembre 25, 2025","format":false,"excerpt":"El reverendo Jesse Jackson, l\u00edder de derechos civiles, fue dado de alta del Hospital Northwestern Memorial el lunes, seg\u00fan inform\u00f3 la Organizaci\u00f3n Rainbow PUSH, despu\u00e9s de que fuentes indicaran que estaba recibiendo atenci\u00f3n para controlar su presi\u00f3n arterial.Jackson, de 84 a\u00f1os, protegido del reverendo Martin Luther King Jr., ha estado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468446,"url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/17\/jesse-jackson-salud-hospitalizado-trax\/","url_meta":{"origin":1468414,"position":1},"title":"El reverendo Jesse Jackson, l\u00edder de derechos civiles, saldr\u00e1 de cuidados intensivos, pero permanecer\u00e1 hospitalizado","author":"","date":"noviembre 17, 2025","format":false,"excerpt":"El l\u00edder de derechos civiles, el reverendo Jesse Jackson, permanece en condici\u00f3n estable este lunes y ser\u00e1 trasladado fuera de la Unidad de Cuidados Intensivos (UCI), seg\u00fan una actualizaci\u00f3n de la Rainbow Push Coalition.Jackson, de 84 a\u00f1os, protegido del reverendo Martin Luther King Jr., permanecer\u00e1 en el Northwestern Memorial Hospital\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468286,"url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/13\/hospitalizan-lider-derechos-civiles-jesse-jackson-trax\/","url_meta":{"origin":1468414,"position":2},"title":"Hospitalizan al l\u00edder de los derechos civiles Jesse Jackson, de 84 a\u00f1os","author":"","date":"noviembre 13, 2025","format":false,"excerpt":"El l\u00edder de los derechos civiles, el reverendo Jesse Jackson, ha sido hospitalizado, seg\u00fan un comunicado obtenido por CNN.Jackson, de 84 a\u00f1os, un protegido del reverendo Martin Luther King Jr., est\u00e1 bajo observaci\u00f3n por par\u00e1lisis supranuclear progresiva (PSP), dijo la Coalici\u00f3n Rainbow PUSH el mi\u00e9rcoles por la noche.\u201cHa estado controlando\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471306,"url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/17\/muere-reverendo-jesse-jackson-activista-derechos-civiles-trax\/","url_meta":{"origin":1468414,"position":3},"title":"Muere el reverendo Jesse Jackson, activista pionero de los derechos civiles, a los 84 a\u00f1os","author":"","date":"febrero 17, 2026","format":false,"excerpt":"El reverendo Jesse Louis Jackson, el destacado l\u00edder de los derechos civiles cuya visi\u00f3n moral y apasionada oratoria transformaron el Partido Dem\u00f3crata y Estados Unidos, falleci\u00f3, seg\u00fan confirm\u00f3 a CNN un portavoz de la Coalici\u00f3n Rainbow Push. Ten\u00eda 84 a\u00f1os.Jackson, un protegido del reverendo Martin Luther King Jr., hab\u00eda sido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471305,"url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/17\/quien-fue-jesse-jackson-trax\/","url_meta":{"origin":1468414,"position":4},"title":"Qui\u00e9n fue Jesse Jackson, el predicador que transform\u00f3 el Partido Dem\u00f3crata y la pol\u00edtica estadounidense","author":"","date":"febrero 17, 2026","format":false,"excerpt":"La muerte del reverendo Jesse Louis Jackson a los 84 a\u00f1os significa una gran p\u00e9rdida para el movimiento por los derechos civiles y raciales y la pol\u00edtica reciente en EE.UU.Jackson fue un imponente l\u00edder y activista democr\u00e1tico cuya visi\u00f3n moral y apasionada oratoria transformaron el Partido Dem\u00f3crata y Estados Unidos.Disc\u00edpulo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466525,"url":"https:\/\/noticiasya.com\/colorado\/2025\/09\/16\/bolsonaro-llevado-hospital-brasil-trax\/","url_meta":{"origin":1468414,"position":5},"title":"Llevan a Bolsonaro al hospital tras &#171;sentirse mal&#187;, dice su hijo","author":"","date":"septiembre 16, 2025","format":false,"excerpt":"El expresidente de Brasil, Jair Bolsonaro, fue llevado al hospital el martes despu\u00e9s de sentirse mal, seg\u00fan dijo su hijo mayor, el senador Fl\u00e1vio Bolsonaro, en X.Seg\u00fan su hijo, el exmandatario sufr\u00eda un fuerte ataque de hipo, v\u00f3mitos y presi\u00f3n arterial baja.\u201cPido las oraciones de todos para que no sea\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1468414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1468414"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1468414\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1468414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1468414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1468414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}