{"id":1468418,"date":"2025-11-17T03:03:41","date_gmt":"2025-11-17T11:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/17\/charlotte-ofensiva-migratoria-dhs-trax\/"},"modified":"2025-11-17T03:03:41","modified_gmt":"2025-11-17T11:03:41","slug":"charlotte-ofensiva-migratoria-dhs-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2025\/11\/17\/charlotte-ofensiva-migratoria-dhs-trax\/","title":{"rendered":"Charlotte es la \u00faltima parada de la ofensiva migratoria del Departamento de Seguridad Nacional. Esto dicen los residentes"},"content":{"rendered":"<p>Tras la detenci\u00f3n de decenas de personas en la ciudad m\u00e1s grande de Carolina del Norte durante la <a href=\"https:\/\/www.cnn.com\/2025\/11\/15\/us\/federal-immigration-raids-begin-in-charlotte\">\u00faltima operaci\u00f3n antiinmigraci\u00f3n selectiva<\/a> del Departamento de Seguridad Nacional, una pregunta ha surgido para muchos de sus residentes y l\u00edderes: \u00bfPor qu\u00e9 Charlotte?<\/p>\n<p>La ciudad no hab\u00eda sido se\u00f1alada p\u00fablicamente por la administraci\u00f3n Trump como objetivo de mayor control migratorio, a diferencia de otras ciudades como <a href=\"https:\/\/www.cnn.com\/2025\/10\/17\/us\/chicago-immigration-crackdown\">Chicago<\/a> y <a href=\"https:\/\/www.cnn.com\/2025\/10\/14\/us\/los-angeles-state-of-emergency-immigration\">Los \u00c1ngeles<\/a>. Es una ciudad gobernada por dem\u00f3cratas, pero se encuentra a cientos de kil\u00f3metros de las fronteras norte y sur. Adem\u00e1s, la delincuencia ha disminuido un 8 % con respecto al a\u00f1o pasado, y los delitos violentos un 20 %, <a href=\"https:\/\/www.charlottenc.gov\/cmpd\/News-Information\/Newsroom\/CMPD-Third-Quarter-Report-2025\">seg\u00fan datos<\/a> publicados por la ciudad en octubre.<\/p>\n<p>Incluso antes de comenzar, el anuncio de que un operativo de control migratorio llegar\u00eda a Charlotte \u2014justo despu\u00e9s de un operativo de varias semanas que result\u00f3 en <a href=\"https:\/\/www.cnn.com\/2025\/11\/12\/us\/chicago-ice-arrests-hearing\">cientos de arrestos<\/a> y <a href=\"https:\/\/www.cnn.com\/2025\/11\/10\/us\/dhs-ice-immigrants-chicago-shooting\">feroces protestas<\/a> en Chicago\u2014 provoc\u00f3 temor y ansiedad en la ciudad.<\/p>\n<p>Los l\u00edderes dem\u00f3cratas en Charlotte han calificado en gran medida la operaci\u00f3n \u2014que sorprendi\u00f3 a los funcionarios locales\u2014 como una distracci\u00f3n pol\u00edtica de cara a <a href=\"https:\/\/www.cnn.com\/2025\/11\/03\/politics\/trump-elections-virginia-new-jersey-new-york-california\">las elecciones de mitad de mandato<\/a> del pr\u00f3ximo a\u00f1o.<\/p>\n<p>\u201cEsta administraci\u00f3n bas\u00f3 su campa\u00f1a en una ret\u00f3rica antiinmigrante para obtener r\u00e9ditos pol\u00edticos\u201d, declar\u00f3 la concejala Dimple Ajmera, dem\u00f3crata. \u201cSe avecinan elecciones muy importantes para el Senado de Estados Unidos en 2026. Y pretenden sacar provecho pol\u00edtico y usar el miedo para dividir a nuestra comunidad\u201d.<\/p>\n<p>Los dem\u00f3cratas esperan arrebatarle a Carolina del Norte uno de sus esca\u00f1os en el Senado estatal tras <a href=\"https:\/\/www.cnn.com\/2025\/06\/29\/politics\/thom-tillis-not-seeking-reelection\">la retirada del senador republicano Thom Tillis de la contienda,<\/a> luego de las cr\u00edticas del presidente, quien amenaz\u00f3 con respaldar a un rival en las primarias. El exgobernador de Carolina del Norte <a href=\"https:\/\/www.cnn.com\/2025\/07\/23\/politics\/roy-cooper-democrats-us-senate\">Roy Cooper<\/a>, muy popular en todo el estado, <a href=\"https:\/\/www.cnn.com\/2025\/07\/29\/politics\/senate-democrats-michigan-texas\">lanz\u00f3<\/a> su campa\u00f1a en julio.<\/p>\n<p>De igual manera, el senador estatal Caleb Theodros, dem\u00f3crata, calific\u00f3 la operaci\u00f3n como una maniobra pol\u00edtica republicana. \u201cLa verdad es que esta acci\u00f3n del Gobierno federal, y el silencio de los l\u00edderes estatales republicanos que la permiten, forman parte de la misma estrategia de distracci\u00f3n pol\u00edtica\u201d, declar\u00f3 a CNN. \u201cEst\u00e1n intentando desviar la atenci\u00f3n de sus propios fracasos, porque no tienen ning\u00fan plan para reducir los costos, hacer que la vivienda sea asequible ni ampliar las oportunidades reales para los trabajadores\u201d.<\/p>\n<p>El Departamento de Seguridad Nacional declar\u00f3 en un comunicado que el aumento de efectivos \u201ctendr\u00eda como objetivo a los inmigrantes ilegales delincuentes que acudieron en masa al estado de Carolina del Norte porque sab\u00edan que los pol\u00edticos santuario los proteger\u00edan y les permitir\u00edan deambular libremente por las calles estadounidenses\u201d.<\/p>\n<p>La agencia afirm\u00f3 que \u201ccasi 1.400 \u00f3rdenes de detenci\u00f3n en Carolina del Norte no se han cumplido, lo que ha permitido la liberaci\u00f3n de inmigrantes indocumentados con antecedentes penales en los vecindarios de Carolina del Norte\u201d. Charlotte no es una \u201cciudad santuario\u201d, pero s\u00ed es una <a href=\"https:\/\/www.charlottenc.gov\/City-Government\/Initiatives-and-Involvement\/Charlotte-for-All\">\u201cciudad acogedora certificada\u201d,<\/a> una designaci\u00f3n para ciudades comprometidas con la inclusi\u00f3n de los inmigrantes.<\/p>\n<p>La inmigraci\u00f3n a la ciudad ha aumentado en los \u00faltimos a\u00f1os. Alrededor del 18,2 % de la poblaci\u00f3n de la ciudad era extranjera en 2023, seg\u00fan <a href=\"https:\/\/censusreporter.org\/profiles\/16000US3712000-charlotte-nc\/\">datos del Censo de EE.UU.<\/a>, casi el doble que en el resto de Carolina del Norte. Adem\u00e1s, en el pasado ha habido desacuerdos en la ciudad sobre la aplicaci\u00f3n de las leyes de inmigraci\u00f3n. El sheriff del condado de Mecklenburg, Garry McFadden, puso fin en 2018 a la colaboraci\u00f3n del condado con el ICE en el marco del programa <a href=\"https:\/\/www.cnn.com\/2025\/04\/28\/us\/ice-immigrant-arrests-287g-program\">287(g)<\/a>, que llevaba una d\u00e9cada vigente , para disgusto de los funcionarios republicanos.<\/p>\n<p>En septiembre, la ciudad se convirti\u00f3 en un foco de debates sobre la vigilancia policial y la seguridad p\u00fablica en las ciudades gobernadas por dem\u00f3cratas, despu\u00e9s de que <a href=\"https:\/\/www.cnn.com\/2025\/09\/09\/us\/charlotte-train-stabbing-ukrainian-victim\">una refugiada ucraniana de 23 a\u00f1os<\/a> fuera apu\u00f1alada hasta la muerte en el transporte p\u00fablico de Charlotte por un hombre con un largo historial de arrestos y problemas de salud mental.<\/p>\n<p>Aunque el sospechoso arrestado en ese caso es ciudadano estadounidense, el presidente Donald Trump aprovech\u00f3 el asesinato como ejemplo de lo que \u00e9l describi\u00f3 como delincuencia descontrolada, y prometi\u00f3 enviar la Guardia Nacional a ciudades dem\u00f3cratas de todo el pa\u00eds. Tres congresistas republicanos del estado, que representan distritos aleda\u00f1os a Charlotte, <a href=\"https:\/\/markharris.house.gov\/sites\/evo-subsites\/markharris.house.gov\/files\/evo-media-document\/11.05.25_letter-to-gov-stein-re-national-guard.pdf\">solicitaron al gobernador<\/a> a principios de este mes el despliegue de la Guardia Nacional para combatir la delincuencia.<\/p>\n<p><a href=\"https:\/\/www.cnn.com\/2025\/11\/06\/us\/gregory-bovino-deposition-chicago-immigration\">Gregory Bovino<\/a>, alto funcionario de la Patrulla Fronteriza originario de Carolina del Norte, tiene su propia respuesta. En <a href=\"https:\/\/www.instagram.com\/p\/DRHkKePDdBe\/?igsh=MTA1NWl0a2FxN25waA%3D%3D\">una publicaci\u00f3n de Instagram<\/a> con la foto de un hombre que, seg\u00fan \u00e9l, era un \u201cinmigrante ilegal con antecedentes penales violentos\u201d, escribi\u00f3: \u201cPor esto es importante la seguridad fronteriza. Por esto estamos en Charlotte\u201d.<\/p>\n<p>Agentes de la Patrulla Fronteriza arrestaron a 81 personas en Charlotte el s\u00e1bado, <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fx.com%2FCMDROpAtLargeCA%2Fstatus%2F1990056755284545873&#038;data=05%7C02%7Czoe.sottile%40cnn.com%7C8a4707bc0f1849228a9d08de25350ce5%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638989107175517605%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=a9pekthuFXGH9saHV4gY6mWSOSdOES5uhcyd52EQRyo%3D&#038;reserved=0\">dijo Bovino el domingo<\/a>, en una operaci\u00f3n que el DHS denomin\u00f3 \u201cCharlotte\u2019s Web\u201d (La telara\u00f1a de Charlotte). No especific\u00f3 las razones de los arrestos ni los nombres de los detenidos, pero dijo que muchos ten\u00edan \u201cantecedentes penales y migratorios significativos\u201d.<\/p>\n<p>Bovino, quien fue criticado por un juez federal por <a href=\"https:\/\/www.cnn.com\/2025\/11\/06\/us\/gregory-bovino-deposition-chicago-immigration\">el uso de la fuerza que \u00e9l y sus agentes hicieron<\/a> en Chicago, fue visto en un video durante la detenci\u00f3n de una persona afuera de una tienda de comestibles en Pineville, a unos 16 km al sur de Charlotte.<\/p>\n<p>Un hombre con <a href=\"https:\/\/www.cnn.com\/2025\/04\/30\/travel\/real-id-tsa-questions-answers\">una identificaci\u00f3n REAL ID,<\/a> quien afirma haberse nacionalizado estadounidense en 2019, se vio involucrado en el altercado. Agentes federales rompieron la ventanilla del auto de Willy Wender Aceituno Medina, un inmigrante hondure\u00f1o residente de Charlotte, y lo detuvieron, aunque lo liberaron poco despu\u00e9s. Medina declar\u00f3 que, tras su arresto, suplic\u00f3 a los agentes federales que revisaran su identificaci\u00f3n.<\/p>\n<p>En una declaraci\u00f3n a CNN, un agente de Aduanas y Protecci\u00f3n Fronteriza dijo que los agentes se hab\u00edan acercado a un individuo que actuaba de forma cada vez m\u00e1s err\u00e1tica. El individuo agrav\u00f3 la situaci\u00f3n y se neg\u00f3 a cumplir las \u00f3rdenes legales de los agentes.<\/p>\n<p>El alcalde interino Dant\u00e9 Anderson, en una entrevista concedida el s\u00e1bado a CNN, dijo que hay \u201cmiedo y ansiedad generalizados\u201d en toda la ciudad.<\/p>\n<p>La Carolina Migrant Network, una organizaci\u00f3n sin fines de lucro de defensa legal, dijo haber visto agentes federales con \u201cropa de camuflaje y equipo t\u00e1ctico operando desde veh\u00edculos sin identificaci\u00f3n\u201d, una imagen que se ha <a href=\"https:\/\/www.cnn.com\/2025\/08\/25\/us\/masks-arrests-ice-tactics-immigration\">vuelto caracter\u00edstica<\/a> de las operaciones del DHS en todo el pa\u00eds.<\/p>\n<p>\u201cTambi\u00e9n hemos presenciado una escalada en las acciones hostiles, incluyendo el arresto de ciudadanos estadounidenses, agresiones f\u00edsicas contra miembros de la comunidad y la interrupci\u00f3n de lugares de culto, negocios y restaurantes donde se ha interrogado a las personas sobre su estatus migratorio\u201d, dijo el grupo en un comunicado.<\/p>\n<p>El DHS no respondi\u00f3 a las preguntas sobre las afirmaciones de la organizaci\u00f3n sin fines de lucro, pero envi\u00f3 a CNN una declaraci\u00f3n que inclu\u00eda las fotos y los nombres de personas que, seg\u00fan dijo, eran inmigrantes con antecedentes penales liberados en Carolina del Norte.<\/p>\n<p>El s\u00e1bado, manifestantes que protestaban contra la operaci\u00f3n llenaron un parque de Charlotte y luego marcharon por las calles del centro de la ciudad.<\/p>\n<p>Varios negocios cerraron temporalmente tras el anuncio de la operaci\u00f3n, entre ellos una popular panader\u00eda colombiana que solo hab\u00eda cerrado sus puertas una vez en los \u00faltimos 28 a\u00f1os.<\/p>\n<p>Manuel \u201cManolo\u201d Betancur cerr\u00f3 su panader\u00eda familiar el s\u00e1bado despu\u00e9s de que hombres con uniformes verdes persiguieran y derribaran a personas afuera del local, seg\u00fan declar\u00f3 a CNN. Dijo que no sabe cu\u00e1ndo podr\u00e1 reabrir.<\/p>\n<p>El s\u00e1bado por la ma\u00f1ana, los agentes salieron de camionetas sin distintivos y \u201cempezaron a detener a la gente en la calle, a personas que se parec\u00edan a m\u00ed\u201d, seg\u00fan cont\u00f3 Betancur. \u00c9l es ciudadano estadounidense naturalizado y dijo que ahora lleva su pasaporte consigo a todas partes, porque no quiere meterse en l\u00edos. \u201cLe promet\u00ed a mi esposa y a mis hijos que esta noche estar\u00eda de vuelta en casa\u201d.<\/p>\n<p>Betancur dijo que no quiere que sus clientes corran el riesgo de tener un encuentro similar con agentes federales, no cuando simplemente est\u00e1n tratando de comprar pasteles o dulces.<\/p>\n<p>Una empresa que gestiona varios bares y restaurantes en Charlotte anunci\u00f3 el cierre de sus establecimientos el s\u00e1bado por la noche tras el anuncio del Departamento de Seguridad Nacional (DHS). Dubai Nightlife Charlotte justific\u00f3 esta decisi\u00f3n preventiva por la \u201cseguridad, la tranquilidad y la protecci\u00f3n de nuestros clientes\u201d, seg\u00fan una publicaci\u00f3n en espa\u00f1ol en Facebook.<\/p>\n<p>La C\u00e1mara de Comercio Colombo-Estadounidense de las Carolinas tambi\u00e9n <a href=\"https:\/\/www.facebook.com\/p\/Colombian-American-Chamber-of-Commerce-of-the-Carolinas-61557374752181\/\">anunci\u00f3<\/a> que pospon\u00eda un evento programado para el s\u00e1bado \u201cdebido a las recientes medidas para reforzar las operaciones de inmigraci\u00f3n en varias ciudades del pa\u00eds\u201d.<\/p>\n<p>El anuncio de que Charlotte ser\u00eda la pr\u00f3xima ciudad objetivo de los funcionarios federales de inmigraci\u00f3n <a href=\"https:\/\/www.cnn.com\/2025\/11\/13\/us\/charlotte-gregory-bovino-border-patrol\">fue inesperado<\/a>, incluso para el Gobierno local.<\/p>\n<p>Ninguno de los funcionarios de Charlotte con los que CNN se puso en contacto el martes o el mi\u00e9rcoles para obtener informaci\u00f3n sobre la supuesta medida dijo estar al tanto del plan.<\/p>\n<p>El concejal Malcolm Graham, quien dijo desconocer la operaci\u00f3n planeada antes de que CNN lo contactara, declar\u00f3: \u201cEs algo habitual en la forma de actuar de esta administraci\u00f3n. Uno se entera de las cosas a trav\u00e9s de tuits e informes de prensa, sin comunicaci\u00f3n directa de ninguna autoridad. Eso, para m\u00ed, es frustrante\u201d.<\/p>\n<p>No fue hasta el jueves por la tarde que un funcionario de Charlotte confirm\u00f3 por primera vez que hab\u00edan hablado con funcionarios federales sobre los planes. McFadden declar\u00f3 el jueves por la tarde que dos funcionarios federales lo contactaron para informarle sobre la llegada de agentes de la Patrulla Fronteriza, pero aclar\u00f3 que no se hab\u00edan compartido detalles sobre la operaci\u00f3n federal con la oficina del sheriff y que no se les hab\u00eda solicitado asistencia para ninguna acci\u00f3n policial.<\/p>\n<p>Incluso el nombre de la operaci\u00f3n ha generado pol\u00e9mica: Martha White, nieta del autor de \u201cCharlotte\u2019s Web\u201d (La telara\u00f1a de Charlotte), E.B. White, y su albacea literario, la critic\u00f3 duramente en declaraciones a CNN, calific\u00e1ndola de intento de aprovecharse del \u00e9xito del querido libro infantil sin su autorizaci\u00f3n. A\u00f1adi\u00f3 que su abuelo \u201cno cre\u00eda en absoluto en hombres enmascarados, en veh\u00edculos sin distintivos, allanando casas y lugares de trabajo sin identificaci\u00f3n ni citaci\u00f3n\u201d.<\/p>\n<p>El gobernador de Carolina del Norte, Josh Stein, se\u00f1al\u00f3 <a href=\"https:\/\/x.com\/NC_Governor\/status\/1989474629006881238?s=20\">en un comunicado en redes sociales<\/a> que la Patrulla Fronteriza ha detenido a muchas personas sin antecedentes penales en Chicago. Inst\u00f3 a los residentes a usar sus tel\u00e9fonos para grabar \u201csi ven que ocurre algo malo\u201d.<\/p>\n<p>\u201cLas fuerzas del orden locales seguir\u00e1n aqu\u00ed protegiendo a la gente de este estado mucho despu\u00e9s de que estos agentes federales se marchen a otro lugar\u201d, dijo.<\/p>\n<p>Stefan\u00eda Arteaga, cofundadora de la Red de Migrantes de Carolina, sugiri\u00f3 que el creciente n\u00famero de inmigrantes en Charlotte podr\u00eda ser una posible raz\u00f3n por la que la ciudad est\u00e1 siendo atacada. La ciudad alberga el Tribunal de Inmigraci\u00f3n de Charlotte y una importante oficina de campo del ICE, dijo. La medida tambi\u00e9n podr\u00eda interpretarse como una represalia por la decisi\u00f3n del sheriff de poner fin a la colaboraci\u00f3n con el ICE, a\u00f1adi\u00f3.<\/p>\n<p>\u201cCreo que tambi\u00e9n hay un cierto grado de \u2018a\u00f1adamos otra ciudad a la lista, sembremos el caos y sigamos adelante\u2019\u201d, dijo.<\/p>\n<p>Mientras tanto, algunos republicanos del estado y de la ciudad han acogido con satisfacci\u00f3n esta ofensiva.<\/p>\n<p>\u201cAgradecemos ver a estos valientes hombres y mujeres de las fuerzas del orden federales cumpliendo la promesa del presidente Trump de expulsar a los delincuentes ilegales violentos de nuestro pa\u00eds, y quienes fomentan el miedo sobre estas operaciones selectivas deben cesar de inmediato\u201d, dijo Matt Mercer, director de Comunicaciones del Partido Republicano de Carolina del Norte, en un comunicado.<\/p>\n<p>Kyle Kirby, presidente del Partido Republicano del condado de Mecklenburg, declar\u00f3 a CNN que cre\u00eda que Charlotte fue blanco de ataques debido a su gran tribunal de inmigraci\u00f3n y a la negativa del sheriff a colaborar con el ICE. \u201cCuando los l\u00edderes locales liberan a personas se\u00f1aladas para su detenci\u00f3n federal y las reintegran a la comunidad, simplemente obligan a las agencias federales a intervenir\u201d, dijo.<\/p>\n<p>Al menos un republicano ten\u00eda sentimientos encontrados. Ed Driggs, quien, tras la victoria dem\u00f3crata en las elecciones de este mes, ser\u00e1 el \u00fanico republicano en el Ayuntamiento de Charlotte el pr\u00f3ximo a\u00f1o, declar\u00f3 a principios de semana que le sorprendi\u00f3 saber que se trataba de la Patrulla Fronteriza la que se enviar\u00eda a Charlotte.<\/p>\n<p>\u201cEstoy en un dilema. Soy firme en mi postura de identificar y deportar a los inmigrantes indocumentados que cometen delitos, pero no estoy seguro de que esta sea la manera correcta de hacerlo\u201d, dijo Driggs. \u201cLo correcto es deportar a los delincuentes violentos. Pero est\u00e1n socavando el Gobierno local y eso preocupa a los ciudadanos legales, tanto estadounidenses como inmigrantes legales\u201d.<\/p>\n<p>Driggs dijo que si hubiera habido una mayor coordinaci\u00f3n local con antelaci\u00f3n, en lugar de enterarse a trav\u00e9s de \u201cfuentes an\u00f3nimas de los medios de comunicaci\u00f3n\u201d, la operaci\u00f3n de la Patrulla Fronteriza podr\u00eda no haber provocado tanto miedo y confusi\u00f3n inicial entre los residentes de la ciudad.<\/p>\n<p>\u201cLa participaci\u00f3n de personas elegidas localmente brinda tranquilidad a los residentes legales. De lo contrario, esto podr\u00eda sentirse como una invasi\u00f3n\u201d.<\/p>\n<p>Se prev\u00e9 que la represi\u00f3n de Bovino contra la inmigraci\u00f3n contin\u00fae a buen ritmo en otras ciudades gobernadas por dem\u00f3cratas despu\u00e9s de Charlotte.<\/p>\n<p>La pr\u00f3xima parada: Nueva Orleans, seg\u00fan dos funcionarios estadounidenses familiarizados con la planificaci\u00f3n.<\/p>\n<p>El presidente habl\u00f3 de enviar la Guardia Nacional a Nueva Orleans, una ciudad gobernada por dem\u00f3cratas en un estado gobernado por republicanos, <a href=\"https:\/\/apnews.com\/article\/trump-national-guard-new-orleans-chicago-baltimore-c9df92974b9fbb2f3be0bb015a512eff\">ya en septiembre<\/a>. Dijo que la ciudad tiene un \u201cproblema de delincuencia\u201d. Pero el plan de la Guardia Nacional no se ha materializado, ya que los esfuerzos para desplegarla en <a href=\"https:\/\/www.cnn.com\/2025\/11\/15\/us\/national-guard-troops-chicago-portland\">Chicago<\/a> y <a href=\"https:\/\/www.cnn.com\/2025\/11\/02\/us\/portland-oregon-national-guard-ruling\">Portland<\/a> se han visto obstaculizados en gran medida por los tribunales.<\/p>\n<p>Tampoco han prosperado las ideas del presidente de enviar tropas a <a href=\"https:\/\/www.cnn.com\/2025\/09\/07\/politics\/video\/baltimore-mayor-brandon-scott-trump-national-guard-contd-digvid\">Baltimore<\/a> y <a href=\"https:\/\/www.cnn.com\/2025\/09\/06\/politics\/video\/mamdani-national-guard-new-york-vrtc\">Nueva York<\/a>.<\/p>\n<p>La oficina del alcalde de Nueva Orleans no ha respondido a la solicitud de CNN para contactarlo sobre posibles operaciones futuras de la Patrulla Fronteriza en la zona.<\/p>\n<p>En declaraciones a Fox News el jueves desde Virginia Occidental \u2014antes de que se anunciara oficialmente la operaci\u00f3n en Charlotte\u2014 Bovino mencion\u00f3 algunas ciudades a las que la Patrulla Fronteriza podr\u00eda dirigirse pr\u00f3ximamente.<\/p>\n<p>\u201cNos ver\u00e1n redesplegarnos a\u2026 podr\u00eda ser Nueva York, podr\u00eda ser Chicago, podr\u00eda ser Charlotte\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras la detenci\u00f3n de decenas de personas en la ciudad m\u00e1s grande de Carolina del Norte durante la \u00faltima operaci\u00f3n antiinmigraci\u00f3n selectiva del Departamento de Seguridad Nacional, una pregunta ha surgido para muchos de sus residentes y l\u00edderes: \u00bfPor qu\u00e9 Charlotte? La ciudad no hab\u00eda sido se\u00f1alada p\u00fablicamente por la administraci\u00f3n Trump como objetivo de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468418","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Charlotte es la \u00faltima parada de la ofensiva migratoria del Departamento de Seguridad Nacional. Esto dicen los residentes - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/17\/charlotte-ofensiva-migratoria-dhs-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Charlotte es la \u00faltima parada de la ofensiva migratoria del Departamento de Seguridad Nacional. Esto dicen los residentes - Noticias\" \/>\n<meta property=\"og:description\" content=\"Tras la detenci\u00f3n de decenas de personas en la ciudad m\u00e1s grande de Carolina del Norte durante la \u00faltima operaci\u00f3n antiinmigraci\u00f3n selectiva del Departamento de Seguridad Nacional, una pregunta ha surgido para muchos de sus residentes y l\u00edderes: \u00bfPor qu\u00e9 Charlotte? La ciudad no hab\u00eda sido se\u00f1alada p\u00fablicamente por la administraci\u00f3n Trump como objetivo de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/17\/charlotte-ofensiva-migratoria-dhs-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-17T11:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/17\/charlotte-ofensiva-migratoria-dhs-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/17\/charlotte-ofensiva-migratoria-dhs-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Charlotte es la \u00faltima parada de la ofensiva migratoria del Departamento de Seguridad Nacional. Esto dicen los residentes\",\"datePublished\":\"2025-11-17T11:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/17\/charlotte-ofensiva-migratoria-dhs-trax\/\"},\"wordCount\":2592,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/17\/charlotte-ofensiva-migratoria-dhs-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/17\/charlotte-ofensiva-migratoria-dhs-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/17\/charlotte-ofensiva-migratoria-dhs-trax\/\",\"name\":\"Charlotte es la \u00faltima parada de la ofensiva migratoria del Departamento de Seguridad Nacional. Esto dicen los residentes - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-17T11:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/17\/charlotte-ofensiva-migratoria-dhs-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/17\/charlotte-ofensiva-migratoria-dhs-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/17\/charlotte-ofensiva-migratoria-dhs-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Charlotte es la \u00faltima parada de la ofensiva migratoria del Departamento de Seguridad Nacional. Esto dicen los residentes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Charlotte es la \u00faltima parada de la ofensiva migratoria del Departamento de Seguridad Nacional. Esto dicen los residentes - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/17\/charlotte-ofensiva-migratoria-dhs-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Charlotte es la \u00faltima parada de la ofensiva migratoria del Departamento de Seguridad Nacional. Esto dicen los residentes - Noticias","og_description":"Tras la detenci\u00f3n de decenas de personas en la ciudad m\u00e1s grande de Carolina del Norte durante la \u00faltima operaci\u00f3n antiinmigraci\u00f3n selectiva del Departamento de Seguridad Nacional, una pregunta ha surgido para muchos de sus residentes y l\u00edderes: \u00bfPor qu\u00e9 Charlotte? La ciudad no hab\u00eda sido se\u00f1alada p\u00fablicamente por la administraci\u00f3n Trump como objetivo de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/17\/charlotte-ofensiva-migratoria-dhs-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-17T11:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/17\/charlotte-ofensiva-migratoria-dhs-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/17\/charlotte-ofensiva-migratoria-dhs-trax\/"},"author":{"name":"","@id":""},"headline":"Charlotte es la \u00faltima parada de la ofensiva migratoria del Departamento de Seguridad Nacional. Esto dicen los residentes","datePublished":"2025-11-17T11:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/17\/charlotte-ofensiva-migratoria-dhs-trax\/"},"wordCount":2592,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/17\/charlotte-ofensiva-migratoria-dhs-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/17\/charlotte-ofensiva-migratoria-dhs-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/17\/charlotte-ofensiva-migratoria-dhs-trax\/","name":"Charlotte es la \u00faltima parada de la ofensiva migratoria del Departamento de Seguridad Nacional. Esto dicen los residentes - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-17T11:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/17\/charlotte-ofensiva-migratoria-dhs-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/17\/charlotte-ofensiva-migratoria-dhs-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/17\/charlotte-ofensiva-migratoria-dhs-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Charlotte es la \u00faltima parada de la ofensiva migratoria del Departamento de Seguridad Nacional. Esto dicen los residentes"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/17\/charlotte-ofensiva-migratoria-dhs-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Charlotte es la \u00faltima parada de la ofensiva migratoria del Departamento de Seguridad Nacional. Esto dicen los residentes","url":"http:\/\/noticiasya.com\/colorado\/2025\/11\/17\/charlotte-ofensiva-migratoria-dhs-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2025\/11\/17\/charlotte-ofensiva-migratoria-dhs-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-17T11:03:41Z","datePublished":"2025-11-17T11:03:41Z","dateModified":"2025-11-17T11:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Charlotte es la \\u00faltima parada de la ofensiva migratoria del Departamento de Seguridad Nacional. Esto dicen los residentes\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2025\\\/11\\\/17\\\/charlotte-ofensiva-migratoria-dhs-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2025\\\/11\\\/17\\\/charlotte-ofensiva-migratoria-dhs-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-17T11:03:41Z\",\"datePublished\":\"2025-11-17T11:03:41Z\",\"dateModified\":\"2025-11-17T11:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1468320,"url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/13\/gregory-bovino-patrulla-fronteriza-charlotte-trax\/","url_meta":{"origin":1468418,"position":0},"title":"Gregory Bovino y la Patrulla Fronteriza se dirigen a Charlotte y sorprenden a las autoridades locales","author":"","date":"noviembre 13, 2025","format":false,"excerpt":"Antes de recibir una llamada esta semana de CNN sobre reportes de que agentes de la Patrulla Fronteriza podr\u00edan llegar a Charlotte, Carolina del Norte, el concejal Malcolm Graham no ten\u00eda idea de que existiera tal plan.Ninguna de las autoridades de Charlotte contactadas por CNN el martes o mi\u00e9rcoles sobre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457524,"url":"https:\/\/noticiasya.com\/colorado\/2025\/01\/14\/bomberos-angeles-escasos-personal-trax\/","url_meta":{"origin":1468418,"position":1},"title":"El Departamento de Bomberos de Los \u00c1ngeles, entre los m\u00e1s escasos de personal en EE.UU, seg\u00fan an\u00e1lisis de datos","author":"","date":"enero 14, 2025","format":false,"excerpt":"Menos de un mes antes de que los incendios arrasaran Los \u00c1ngeles, un grupo de bomberos veteranos se reuni\u00f3 en el Ayuntamiento para pedir m\u00e1s recursos. Estaban en un \u201cpunto de quiebre,\u201d dijo uno. Otro revel\u00f3 que camiones de bomberos de US$ 1 mill\u00f3n estaban inactivos porque los recortes presupuestarios\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468496,"url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/19\/intensifican-controles-inmigratorios-carolina-del-norte-nueva-orleans-trax\/","url_meta":{"origin":1468418,"position":2},"title":"Se intensifican las redadas de inmigraci\u00f3n en Carolina del Norte, y Nueva Orleans podr\u00eda ser la siguiente","author":"","date":"noviembre 19, 2025","format":false,"excerpt":"Rheba Hamilton estaba tomando caf\u00e9 en su porche el s\u00e1bado por la ma\u00f1ana mientras observaba a los dos trabajadores que hab\u00eda contratado comenzar a adornar con luces el \u00e1rbol de su jard\u00edn delantero en su tranquilo barrio de Charlotte, Carolina del Norte.De repente, una minivan gris \u2014con las puertas ya\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468997,"url":"https:\/\/noticiasya.com\/colorado\/2025\/12\/05\/manual-ciudades-ofensiva-inmigratoria-trump-trax\/","url_meta":{"origin":1468418,"position":3},"title":"Qu\u00e9 hacer cuando llegan los federales: el manual compartido por las ciudades blanco de la ofensiva inmigratoria de Trump","author":"","date":"diciembre 5, 2025","format":false,"excerpt":"Mientras Chad Curry transporta afanosamente a sus hijos adolescentes por las calles de su barrio de West Ridge en Chicago, observa los veh\u00edculos que pasan con un escepticismo que no ten\u00eda hace apenas unos meses.Sabe fijarse bien si un coche que pasa tiene ventanas tintadas, placas de otro estado o\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465768,"url":"https:\/\/noticiasya.com\/colorado\/2025\/08\/22\/trump-chicago-proxima-ciudad-lucha-crimen-trax\/","url_meta":{"origin":1468418,"position":4},"title":"Trump dice que Chicago ser\u00e1 la pr\u00f3xima ciudad en la que el Gobierno federal intensificar\u00e1 la lucha contra el crimen","author":"","date":"agosto 22, 2025","format":false,"excerpt":"El presidente Donald Trump afirm\u00f3 este viernes que Chicago ser\u00e1 la pr\u00f3xima ciudad en la que su Gobierno enfocar\u00e1 una ofensiva federal contra el crimen y sugiri\u00f3 una campa\u00f1a m\u00e1s prolongada e intensa en la capital del pa\u00eds.\u201cVamos a arreglar esa ciudad, probablemente ser\u00e1 la pr\u00f3xima, ser\u00e1 nuestro siguiente objetivo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465793,"url":"https:\/\/noticiasya.com\/colorado\/2025\/08\/23\/trump-washington-detenciones-inmigrantes-trax\/","url_meta":{"origin":1468418,"position":5},"title":"Trump tom\u00f3 el control de la ciudad de Washington y se redujo el crimen. Tambi\u00e9n aumentaron las detenciones de inmigrantes","author":"","date":"agosto 23, 2025","format":false,"excerpt":"Tras la toma de control de la fuerza policial de la ciudad de Washington y el despliegue de agentes federales y tropas en el distrito, la capital experiment\u00f3 una ca\u00edda moderada en los delitos reportados \u2014y un aumento mucho mayor en las detenciones de inmigrantes\u2014, seg\u00fan un an\u00e1lisis de CNN\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1468418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1468418"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1468418\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1468418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1468418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1468418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}