{"id":1468419,"date":"2025-11-17T03:03:41","date_gmt":"2025-11-17T11:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/17\/5-cosas-17-noviembre-orix\/"},"modified":"2025-11-17T03:03:41","modified_gmt":"2025-11-17T11:03:41","slug":"5-cosas-17-noviembre-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2025\/11\/17\/5-cosas-17-noviembre-orix\/","title":{"rendered":"Las 5 cosas que debes saber este 17 de noviembre: elecciones en Chile, refer\u00e9ndum en Ecuador, Cartel de los Soles"},"content":{"rendered":"<p>Los ecuatorianos rechazan las propuestas de Noboa en refer\u00e9ndum. EE.UU. designar\u00e1 al Cartel de los Soles como organizaci\u00f3n terrorista extranjera. Trump insta a los republicanos a votar a favor de la publicaci\u00f3n de los archivos de Epstein.<em> Esto es lo que debes saber para comenzar el d\u00eda.<\/em> <strong>Primero la verdad.<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fedition.cnn.com%2Fnewsletters%2F5-cosas&#038;data=05%7C02%7Cvaleria.ordonez%40cnn.com%7C9ec798f942354a2636cd08de09f24f89%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638959133542743266%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=VqfMGB8mDMd3FBUF95vH7FLUndISkeGdgrocYbhA1tA%3D&#038;reserved=0\">Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo<\/a><\/li>\n<li><a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fedition.cnn.com%2Faudio%2Fpodcasts%2F5-cosas&#038;data=05%7C02%7Cvaleria.ordonez%40cnn.com%7C9ec798f942354a2636cd08de09f24f89%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638959133542765449%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=I%2BVr%2FWQ0M6ieTk%2ByGz5nq3itdzVQ%2Fv9lyGFnOqj1BRk%3D&#038;reserved=0\">\ud83c\udf99 Escucha las 5 cosas de CNN<\/a><\/li>\n<\/ul>\n<p>La candidata oficialista Jeannette Jara y el opositor Jos\u00e9 Antonio Kast <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/11\/16\/latinoamerica\/elecciones-chile-jara-kast-segunda-vuelta-orix\">avanzar\u00e1n a la segunda vuelta de las elecciones presidenciales de Chile,<\/a> que se realizar\u00e1 el 14 de diciembre, seg\u00fan los resultados preliminares de la autoridad electoral. De cara al pr\u00f3ximo balotaje, las encuestas perfilan una contienda muy cerrada. <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/11\/16\/latinoamerica\/chile-jara-kast-segunda-vuelta-claves-orix\">Esto es lo que debes saber.<\/a><\/p>\n<ul>\n<li><a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fcnnespanol.cnn.com%2F2025%2F11%2F16%2Flatinoamerica%2Fmapa-resultados-primera-vuelta-elecciones-chile-orix&#038;data=05%7C02%7Cgonzalo.jimenez%40wbdcontractor.com%7C17b80a0f800347410bf408de258dadb2%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638989487601725659%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=c%2B2DAyvA0s6o%2B8BQES%2FPKPBnmCMlbY7EOkpRBMVFDP4%3D&#038;reserved=0\">Mapa de resultados de la primera vuelta de las elecciones presidenciales en Chile 2025: d\u00f3nde gana cada candidato<\/a><\/li>\n<li><a href=\"https:\/\/cnnespanol.cnn.com\/2025\/11\/15\/latinoamerica\/propuestas-jeanette-jara-chile-orix\">Las propuestas de Jeannette Jara, la candidata del oficialismo que busca mantener el poder en Chile<\/a><\/li>\n<li><a href=\"https:\/\/cnnespanol.cnn.com\/2025\/11\/15\/latinoamerica\/propuestas-jose-antonio-kast-ultraderechista-chile-orix\">Las propuestas de Jos\u00e9 Antonio Kast, el ultraderechista que busca gobernar Chile con \u201cmano dura\u201d contra la migraci\u00f3n<\/a><\/li>\n<\/ul>\n<p>Millones de ecuatorianos rechazaron el domingo el permiso a la instalaci\u00f3n de bases militares extranjeras en el pa\u00eds y la elaboraci\u00f3n de una nueva Constituci\u00f3n nacional, <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fcnnespanol.cnn.com%2F2025%2F11%2F16%2Flatinoamerica%2Fmala-eleccion-para-noboa-los-ecuatorianos-le-dicen-que-no-a-sus-propuestas-clave&#038;data=05%7C02%7Cgonzalo.jimenez%40wbdcontractor.com%7C17b80a0f800347410bf408de258dadb2%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638989487601761306%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=f%2BoLUeWMNYGFgVhIuBpFqPURedOqc9ian3UHJszKl4Y%3D&#038;reserved=0\">en un refer\u00e9ndum impulsado por el Gobierno del presidente Daniel Noboa.<\/a> La consulta popular tambi\u00e9n incluy\u00f3 preguntas sobre una reducci\u00f3n del n\u00famero de congresistas en la Asamblea Nacional y la eliminaci\u00f3n de financiamiento p\u00fablico a los partidos pol\u00edticos, iniciativas que tambi\u00e9n fueron rechazadas en la votaci\u00f3n.<\/p>\n<ul>\n<li><a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fcnnespanol.cnn.com%2F2025%2F11%2F16%2Flatinoamerica%2Fesultados-referendum-ecuador-2025-orix&#038;data=05%7C02%7Cgonzalo.jimenez%40wbdcontractor.com%7C17b80a0f800347410bf408de258dadb2%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638989487601779197%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=EvwJ1SYYTzMOXt8hU2%2BwFJlSlLppuQEelG30hJLgYR0%3D&#038;reserved=0\">Resultados del refer\u00e9ndum en Ecuador 2025: se aprueba o se rechaza<\/a><\/li>\n<li><a href=\"https:\/\/cnnespanol.cnn.com\/2025\/11\/16\/latinoamerica\/detienen-espana-pipo-lider-organizacion-criminal-los-lobos-ecuador-orix\">Detienen en Espa\u00f1a a \u201cPipo\u201d, supuesto l\u00edder de la organizaci\u00f3n criminal Los Lobos de Ecuador<\/a><\/li>\n<\/ul>\n<p>El secretario de Estado de EE.UU., Marco Rubio, anunci\u00f3 el domingo que Estados Unidos <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fcnnespanol.cnn.com%2F2025%2F11%2F16%2Feeuu%2Fcartel-soles-venezuela-organizacion-terrorista-extranjera-trax&#038;data=05%7C02%7Cgonzalo.jimenez%40wbdcontractor.com%7C17b80a0f800347410bf408de258dadb2%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638989487601797059%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=ulDXFeEghAjyIW2C7lUlnqvAX41MWRyM%2BHC9L7o5c%2FM%3D&#038;reserved=0\">designar\u00e1 al Cartel de los Soles como organizaci\u00f3n terrorista extranjera, medida que entrar\u00e1 en vigor a partir del 24 de noviembre.<\/a> Estados Unidos alega que el cartel venezolano est\u00e1 dirigido por el presidente de Venezuela, Nicol\u00e1s Maduro, y otros altos funcionarios del Gobierno, algo que el mandatario venezolano ha rechazado rotundamente.<\/p>\n<ul>\n<li><a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fcnnespanol.cnn.com%2F2025%2F11%2F16%2Feeuu%2Fportaaviones-us-gerald-ford-caribe-tensiones-venezuela-trax&#038;data=05%7C02%7Cgonzalo.jimenez%40wbdcontractor.com%7C17b80a0f800347410bf408de258dadb2%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638989487601814675%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=DNcMTEYvSGGg6M3tANZtisUqKMyKBL5eP9R1%2BZgyiew%3D&#038;reserved=0\">El portaaviones m\u00e1s grande de EE.UU. llega al Caribe en medio de las tensiones con Venezuela<\/a><\/li>\n<li><a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fcnnespanol.cnn.com%2F2025%2F11%2F16%2Feeuu%2Ffuerzas-armadas-eeuu-accion-venezuela-trump-trax&#038;data=05%7C02%7Cgonzalo.jimenez%40wbdcontractor.com%7C17b80a0f800347410bf408de258dadb2%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638989487601832513%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=Mnl6T8ndVJkg5MdqxEr88r7QwG1aqDvBVd%2F1WW7uqCs%3D&#038;reserved=0\">El secretario del Ej\u00e9rcito dice que las Fuerzas Armadas de EE.UU. est\u00e1n \u201clistas, si se les pide\u201d, para actuar en Venezuela<\/a><\/li>\n<\/ul>\n<p>El presidente Donald Trump alent\u00f3 el domingo por la noche a los republicanos de la C\u00e1mara de Representantes a votar a favor de la publicaci\u00f3n de los archivos de Jeffrey Epstein y a dejar atr\u00e1s lo que \u00e9l llama un \u201cenga\u00f1o dem\u00f3crata\u201d, lo que supone<a href=\"https:\/\/cnnespanol.cnn.com\/2025\/11\/17\/eeuu\/trump-republicanos-archivos-epstein-giro-radical-trax\"> un giro radical respecto a sus esfuerzos por desacreditar la iniciativa.<\/a><\/p>\n<p>Un breve video, que fue publicado en redes sociales y geolocalizado por CNN a solo unos kil\u00f3metros de Pokrovsk, <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fcnnespanol.cnn.com%2F2025%2F11%2F16%2Fmundo%2Frusia-replantea-forma-guerra-ucrania-trax&#038;data=05%7C02%7Cgonzalo.jimenez%40wbdcontractor.com%7C17b80a0f800347410bf408de258dadb2%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638989487601850318%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=GVx8roCE5xrwDfuaS8LEIA2Phx2UDoFbxmCOBOjtOKE%3D&#038;reserved=0\">ofrece un vistazo a las formas cambiantes con que Rusia est\u00e1 librando su guerra en Ucrania.<\/a> Si Pokrovsk cae en manos de las fuerzas rusas, como parece cada vez m\u00e1s probable, ser\u00e1 la ciudad m\u00e1s grande tomada por Mosc\u00fa desde la captura de Bakhmut en mayo de 2023.<\/p>\n<p><strong>\u00bfQui\u00e9n se convirti\u00f3 en el nuevo campe\u00f3n de peso w\u00e9lter en la UFC 322?<\/strong><\/p>\n<p>A. Dillon Danis.<\/p>\n<p>B. Islam Makhachev.<\/p>\n<p>C. Jack Della Maddalena.<\/p>\n<p>D. Conor McGregor.<\/p>\n<p>\u2b07\ufe0f <em>Conoce la respuesta m\u00e1s abajo.<\/em><\/p>\n<p><strong>Im\u00e1genes espont\u00e1neas captadas por la hermana de Selena son el coraz\u00f3n de un nuevo documental<\/strong><\/p>\n<p>El documental \u201cSelena y Los Dinos\u201d se estrena este lunes en Netflix. Se trata de la historia de la reina del Tex-Mex, Selena Quintanilla P\u00e9rez, <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fcnnespanol.cnn.com%2F2025%2F11%2F16%2Fentretenimiento%2Fselena-y-los-dinos-documental-trax&#038;data=05%7C02%7Cgonzalo.jimenez%40wbdcontractor.com%7C17b80a0f800347410bf408de258dadb2%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638989487601888647%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=TlrytBuF9KF6R5tf9avylc1BGCdNgeFV9e52%2FU4Le%2F0%3D&#038;reserved=0\">contada directamente por su familia y compa\u00f1eros de banda.<\/a><\/p>\n<p><strong>Portugal y Noruega golean y consiguen su boleto al Mundial 2026<\/strong><\/p>\n<p>El Mundial de 48 selecciones sum\u00f3 el domingo dos nuevos participantes. Portugal y Noruega sacaron boleto directo para el torneo, y <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fcnnespanol.cnn.com%2F2025%2F11%2F16%2Fdeportes%2Fclasificados-uefa-portugal-noruega-mundial-2026-orix&#038;data=05%7C02%7Cgonzalo.jimenez%40wbdcontractor.com%7C17b80a0f800347410bf408de258dadb2%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638989487601906837%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=RMQiBL07ZDc3jx3FmLir%2Fwhm0%2F8vyLRaDuslFS9BIis%3D&#038;reserved=0\">se sumaron a las otras selecciones de la UEFA con participaci\u00f3n asegurada<\/a>: Inglaterra, Francia y Croacia.<\/p>\n<p><strong>La explosi\u00f3n de esta estrella podr\u00eda destruir la atm\u00f3sfera de un planeta<\/strong><\/p>\n<p>Por primera vez, astr\u00f3nomos afirman haber detectado una enorme explosi\u00f3n liberada por una estrella fuera de nuestro sistema solar. La erupci\u00f3n fue similar en algunos aspectos a las de nuestro Sol, <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fcnnespanol.cnn.com%2F2025%2F11%2F16%2Fciencia%2Fexplosion-estrella-acabar-atmosfera-planeta-trax&#038;data=05%7C02%7Cgonzalo.jimenez%40wbdcontractor.com%7C17b80a0f800347410bf408de258dadb2%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638989487601924917%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=YE3V1mhmAwCsrmO1V7xd7ytjJkvQiflHTBMzAhTJtBc%3D&#038;reserved=0\">pero a una escala mucho mayor y preocupante.<\/a><\/p>\n<p><strong>21<\/strong><\/p>\n<p>El Pent\u00e1gono ejecut\u00f3 este fin de semana el <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/11\/16\/eeuu\/mueren-tres-personas-21-ataque-narcobote-trax\">ataque n\u00famero 21 contra una presunta embarcaci\u00f3n de narcotr\u00e1fico<\/a>, matando a tres personas que iban a bordo, inform\u00f3 el Comando Sur de Estados Unidos.<\/p>\n<p><strong>\u201cMe gustar\u00eda decir, humildemente, lo siento por participar en la pol\u00edtica t\u00f3xica; es muy malo para nuestro pa\u00eds\u201d<\/strong><\/p>\n<p><strong>\u2014 Lo dijo Marjorie Taylor Greene, <\/strong>representante republicana de Georgia que hizo un cambio dr\u00e1stico a sus caracter\u00edsticos comentarios despectivos <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fcnnespanol.cnn.com%2F2025%2F11%2F16%2Feeuu%2Fentrevista-marjorie-taylor-greene-politica-toxica-trax&#038;data=05%7C02%7Cgonzalo.jimenez%40wbdcontractor.com%7C17b80a0f800347410bf408de258dadb2%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638989487601960464%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=Wnl5pYD9seLfGDv8K95HdsnlMfc5Gu7WjPXgm1FOIfA%3D&#038;reserved=0\">tras tener una ruptura p\u00fablica con el presidente Donald Trump.<\/a><\/p>\n<p><strong>El mexicano que cuida la vida de los acr\u00f3batas en Cirque du Soleil OVO<\/strong><\/p>\n<p>Detr\u00e1s de las luces y la acrobacia de OVO, un mexicano se encarga de que los artistas vuelen con total seguridad. \u00c9l es Esteban Mart\u00ednez, jefe de automatizaci\u00f3n del Cirque du Soleil, un t\u00e9cnico que ha recorrido 26 pa\u00edses <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fcnnespanol.cnn.com%2F2025%2F11%2F16%2Fentretenimiento%2Fvideo%2Fcirque-du-soleil-ovo-ciudad-de-mexico-perspectivas-mexico-tv&#038;data=05%7C02%7Cgonzalo.jimenez%40wbdcontractor.com%7C17b80a0f800347410bf408de258dadb2%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638989487601978606%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=tlGPyyvAmSs2%2FJhq2SLJQI6zcyE453%2BNDmgHu1iYzWA%3D&#038;reserved=0\">y tiene la tarea nada f\u00e1cil de cuidar la vida de los artistas.<\/a><\/p>\n<p>\ud83d\udc4b Nos vemos ma\u00f1ana.<\/p>\n<p><strong>\ud83e\udde0 La respuesta del quiz es: B. <\/strong>El peleador ruso Islam Makhachev arrebat\u00f3 el cetro del peso w\u00e9lter al australiano Jack Della Maddalena tras una brillante actuaci\u00f3n en la <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fcnnespanol.cnn.com%2F2025%2F11%2F16%2Fdeportes%2Fresultado-ufc-322-makhachev-della-maddalena-orix&#038;data=05%7C02%7Cgonzalo.jimenez%40wbdcontractor.com%7C17b80a0f800347410bf408de258dadb2%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638989487601996333%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=bop%2F45vLPyfhgNex%2B5y8n3bdfb36AvT6xEDoHbHmN5M%3D&#038;reserved=0\">pelea estelar de la UFC 322.<\/a><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los ecuatorianos rechazan las propuestas de Noboa en refer\u00e9ndum. EE.UU. designar\u00e1 al Cartel de los Soles como organizaci\u00f3n terrorista extranjera. Trump insta a los republicanos a votar a favor de la publicaci\u00f3n de los archivos de Epstein. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad. Suscr\u00edbete aqu\u00ed para recibir el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468419","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las 5 cosas que debes saber este 17 de noviembre: elecciones en Chile, refer\u00e9ndum en Ecuador, Cartel de los Soles - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/17\/5-cosas-17-noviembre-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las 5 cosas que debes saber este 17 de noviembre: elecciones en Chile, refer\u00e9ndum en Ecuador, Cartel de los Soles - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los ecuatorianos rechazan las propuestas de Noboa en refer\u00e9ndum. EE.UU. designar\u00e1 al Cartel de los Soles como organizaci\u00f3n terrorista extranjera. Trump insta a los republicanos a votar a favor de la publicaci\u00f3n de los archivos de Epstein. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad. Suscr\u00edbete aqu\u00ed para recibir el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/17\/5-cosas-17-noviembre-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-17T11:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/17\/5-cosas-17-noviembre-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/17\/5-cosas-17-noviembre-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Las 5 cosas que debes saber este 17 de noviembre: elecciones en Chile, refer\u00e9ndum en Ecuador, Cartel de los Soles\",\"datePublished\":\"2025-11-17T11:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/17\/5-cosas-17-noviembre-orix\/\"},\"wordCount\":964,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/17\/5-cosas-17-noviembre-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/17\/5-cosas-17-noviembre-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/17\/5-cosas-17-noviembre-orix\/\",\"name\":\"Las 5 cosas que debes saber este 17 de noviembre: elecciones en Chile, refer\u00e9ndum en Ecuador, Cartel de los Soles - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-17T11:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/17\/5-cosas-17-noviembre-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/17\/5-cosas-17-noviembre-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/17\/5-cosas-17-noviembre-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las 5 cosas que debes saber este 17 de noviembre: elecciones en Chile, refer\u00e9ndum en Ecuador, Cartel de los Soles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las 5 cosas que debes saber este 17 de noviembre: elecciones en Chile, refer\u00e9ndum en Ecuador, Cartel de los Soles - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/17\/5-cosas-17-noviembre-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Las 5 cosas que debes saber este 17 de noviembre: elecciones en Chile, refer\u00e9ndum en Ecuador, Cartel de los Soles - Noticias","og_description":"Los ecuatorianos rechazan las propuestas de Noboa en refer\u00e9ndum. EE.UU. designar\u00e1 al Cartel de los Soles como organizaci\u00f3n terrorista extranjera. Trump insta a los republicanos a votar a favor de la publicaci\u00f3n de los archivos de Epstein. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad. Suscr\u00edbete aqu\u00ed para recibir el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/17\/5-cosas-17-noviembre-orix\/","og_site_name":"Noticias","article_published_time":"2025-11-17T11:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/17\/5-cosas-17-noviembre-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/17\/5-cosas-17-noviembre-orix\/"},"author":{"name":"","@id":""},"headline":"Las 5 cosas que debes saber este 17 de noviembre: elecciones en Chile, refer\u00e9ndum en Ecuador, Cartel de los Soles","datePublished":"2025-11-17T11:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/17\/5-cosas-17-noviembre-orix\/"},"wordCount":964,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/17\/5-cosas-17-noviembre-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/17\/5-cosas-17-noviembre-orix\/","url":"https:\/\/noticiasya.com\/2025\/11\/17\/5-cosas-17-noviembre-orix\/","name":"Las 5 cosas que debes saber este 17 de noviembre: elecciones en Chile, refer\u00e9ndum en Ecuador, Cartel de los Soles - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-17T11:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/17\/5-cosas-17-noviembre-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/17\/5-cosas-17-noviembre-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/17\/5-cosas-17-noviembre-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Las 5 cosas que debes saber este 17 de noviembre: elecciones en Chile, refer\u00e9ndum en Ecuador, Cartel de los Soles"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/17\/5-cosas-17-noviembre-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Las 5 cosas que debes saber este 17 de noviembre: elecciones en Chile, refer\u00e9ndum en Ecuador, Cartel de los Soles","url":"http:\/\/noticiasya.com\/colorado\/2025\/11\/17\/5-cosas-17-noviembre-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2025\/11\/17\/5-cosas-17-noviembre-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-17T11:03:41Z","datePublished":"2025-11-17T11:03:41Z","dateModified":"2025-11-17T11:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Las 5 cosas que debes saber este 17 de noviembre: elecciones en Chile, refer\\u00e9ndum en Ecuador, Cartel de los Soles\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2025\\\/11\\\/17\\\/5-cosas-17-noviembre-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2025\\\/11\\\/17\\\/5-cosas-17-noviembre-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-17T11:03:41Z\",\"datePublished\":\"2025-11-17T11:03:41Z\",\"dateModified\":\"2025-11-17T11:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1464875,"url":"https:\/\/noticiasya.com\/colorado\/2025\/07\/26\/eeuu-cartel-soles-organizacion-terrorista-orix\/","url_meta":{"origin":1468419,"position":0},"title":"Estados Unidos designa al Cartel de los Soles como organizaci\u00f3n terrorista internacional","author":"","date":"julio 26, 2025","format":false,"excerpt":"El Departamento del Tesoro de EE.UU. design\u00f3 este viernes al Cartel de los Soles como una organizaci\u00f3n terrorista internacional, seg\u00fan declaraciones del Departamento y de la Oficina de Control de Activos Extranjeros (OFAC, en ingl\u00e9s).El Cartel de los Soles es un presunto grupo criminal que, seg\u00fan Washington, ha corrompido las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468410,"url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/16\/cartel-soles-venezuela-organizacion-terrorista-extranjera-trax\/","url_meta":{"origin":1468419,"position":1},"title":"El Departamento de Estado de EE.UU. designar\u00e1 al Cartel de los Soles como organizaci\u00f3n terrorista extranjera","author":"","date":"noviembre 16, 2025","format":false,"excerpt":"El secretario de Estado de EE.UU., Marco Rubio, anunci\u00f3 este domingo que Estados Unidos designar\u00e1 al Cartel de los Soles como organizaci\u00f3n terrorista extranjera, con efecto a partir del 24 de noviembre. Estados Unidos alega que el cartel venezolano est\u00e1 dirigido por el presidente de Venezuela Nicol\u00e1s Maduro y otros\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468646,"url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/24\/que-es-cartel-de-los-soles-organizacion-terrorista-venezuela-eeuu-orix\/","url_meta":{"origin":1468419,"position":2},"title":"\u00bfExiste el Cartel de los Soles? Esto se sabe sobre una pieza clave en la crisis entre EE.UU. y Venezuela","author":"","date":"noviembre 24, 2025","format":false,"excerpt":"Este lunes entr\u00f3 en vigor la designaci\u00f3n del Cartel de los Soles como Organizaci\u00f3n Terrorista Extranjera (FTO, por sus siglas en ingl\u00e9s), un nuevo paso del Gobierno del presidente Donald Trump, en medio de lo que sostiene ser una campa\u00f1a para acabar con el narcoterrorismo en Am\u00e9rica Latina.La designaci\u00f3n se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465523,"url":"https:\/\/noticiasya.com\/colorado\/2025\/08\/14\/noboa-cartel-soles-terrorista-orix\/","url_meta":{"origin":1468419,"position":3},"title":"Ecuador designa al Cartel de los Soles como organizaci\u00f3n terrorista","author":"","date":"agosto 14, 2025","format":false,"excerpt":"El presidente de Ecuador, Daniel Noboa, design\u00f3 al Cartel de los Soles como \u201cgrupo terrorista del crimen organizado\u201d al considerarlo \u201cuna amenaza para la poblaci\u00f3n nacional\u201d, anunci\u00f3 este jueves la Presidencia ecuatoriana.A trav\u00e9s del Decreto Ejecutivo No. 93, el presidente identific\u00f3 al grupo criminal como organizaci\u00f3n terrorista por \u201cconstituir una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465854,"url":"https:\/\/noticiasya.com\/colorado\/2025\/08\/25\/petro-cartel-soles-tension-eeuu-venezuela-orix\/","url_meta":{"origin":1468419,"position":4},"title":"Petro dice que el Cartel de los Soles &#171;no existe&#187; en medio de la tensi\u00f3n entre EE.UU. y Venezuela","author":"","date":"agosto 25, 2025","format":false,"excerpt":"En medio de las crecientes tensiones entre Estados Unidos y Venezuela, el presidente de Colombia, Gustavo Petro, neg\u00f3 la existencia del Cartel de los Soles, un presunto grupo criminal acusado por Washington de infiltrar el poder en Caracas desde los a\u00f1os noventa para enviar drogas hacia su territorio.\u201cEl cartel de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468644,"url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/24\/venezuela-reaccion-designacion-cartel-de-los-soles-organizacion-terrorista-orix\/","url_meta":{"origin":1468419,"position":5},"title":"Gobierno de Venezuela califica de &#171;rid\u00edcula patra\u00f1a&#187; la designaci\u00f3n del Cartel de los Soles como organizaci\u00f3n terrorista","author":"","date":"noviembre 24, 2025","format":false,"excerpt":"El Gobierno de Venezuela reaccion\u00f3 a la entrada en vigor de la designaci\u00f3n del llamado Cartel de los Soles como organizaci\u00f3n terrorista extranjera, acci\u00f3n que consider\u00f3 una \u201crid\u00edcula patra\u00f1a\u201d.\u201cLa Rep\u00fablica Bolivariana de Venezuela rechaza de manera categ\u00f3rica, firme y absoluta la nueva y rid\u00edcula patra\u00f1a del secretario del Departamento de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1468419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1468419"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1468419\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1468419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1468419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1468419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}