{"id":1468423,"date":"2025-11-17T06:03:38","date_gmt":"2025-11-17T14:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/17\/arctic-frost-cierre-gobierno-republicanos-trax\/"},"modified":"2025-11-17T06:03:38","modified_gmt":"2025-11-17T14:03:38","slug":"arctic-frost-cierre-gobierno-republicanos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2025\/11\/17\/arctic-frost-cierre-gobierno-republicanos-trax\/","title":{"rendered":"La pol\u00e9mica cl\u00e1usula &#171;Arctic Frost&#187; incluida en el proyecto de ley de financiaci\u00f3n que divide a los legisladores republicanos"},"content":{"rendered":"<p>El proyecto de ley que puso fin al cierre del Gobierno inclu\u00eda una cl\u00e1usula que obliga al Departamento de Justicia y al FBI a notificar al Senado cuando un legislador est\u00e1 siendo investigado y si se le solicita informaci\u00f3n personal mediante citaci\u00f3n judicial.<\/p>\n<p>Los legisladores tambi\u00e9n pueden demandar al Departamento de Justicia en virtud de esta cl\u00e1usula y pueden recibir una indemnizaci\u00f3n de US$ 500.000 o m\u00e1s por cada infracci\u00f3n cometida por el Gobierno si sus casos prosperan.<\/p>\n<p>La cl\u00e1usula, incluida en uno de los proyectos de ley de asignaciones presupuestarias, surge despu\u00e9s de que los senadores republicanos publicaran registros del FBI relacionados con la investigaci\u00f3n denominada \u201cArctic Frost\u201d, que se refer\u00eda al esquema de electores falsos de 2020. En este caso, aliados de Donald Trump presionaron a los electores republicanos para que registraran votos del Colegio Electoral a favor de Trump en estados que el expresidente Joe Biden hab\u00eda ganado.<\/p>\n<p>La disposici\u00f3n provoc\u00f3 indignaci\u00f3n bipartidista en el Capitolio, donde los cr\u00edticos la calificaron de medida oportunista que enriquecer\u00eda a los senadores a costa de los contribuyentes.<\/p>\n<p>Finalmente, los republicanos votaron a favor del proyecto de ley de financiaci\u00f3n para poner fin al hist\u00f3rico cierre del Gobierno de 43 d\u00edas. Ahora, afirman que presentar\u00e1n un proyecto de ley independiente para derogarlo.<\/p>\n<p>Esto es lo que se sabe sobre la controversia en el Capitolio:<\/p>\n<p>Los senadores republicanos acusan al exfiscal especial Jack Smith y a los l\u00edderes del FBI de tener motivaciones pol\u00edticas para obtener los registros telef\u00f3nicos de nueve legisladores republicanos mediante citaciones judiciales.<\/p>\n<p>Los registros contienen datos de los cuatro d\u00edas previos y posteriores al ataque del 6 de enero de 2021 contra el Capitolio de EE.UU., pero no incluyen el contenido de las llamadas. Smith ha declarado que las citaciones formaban parte de investigaciones rutinarias.<\/p>\n<p>La ley que Trump promulg\u00f3 como parte del proyecto de ley de financiaci\u00f3n provisional establece expl\u00edcitamente las diversas situaciones y par\u00e1metros bajo los cuales los investigadores federales est\u00e1n obligados a notificar al Congreso, incluyendo cu\u00e1ndo se citan los registros electr\u00f3nicos personales de los senadores, cu\u00e1ndo un senador es objeto de una investigaci\u00f3n penal y cu\u00e1ndo se necesitan datos de una oficina del Senado.<\/p>\n<p>Tambi\u00e9n indica que cualquier senador que no sea notificado sobre el uso de sus datos en una investigaci\u00f3n o sobre su condici\u00f3n de objeto de una investigaci\u00f3n puede interponer una demanda alegando que los investigadores no cumplieron con la ley federal.<\/p>\n<p>\u201cCualquier senador cuyos datos del Senado, o los datos de su oficina en el Senado, hayan sido adquiridos, requeridos mediante citaci\u00f3n judicial, registrados, consultados o divulgados en violaci\u00f3n de esta secci\u00f3n, podr\u00e1 interponer una demanda civil contra los Estados Unidos si la violaci\u00f3n fue cometida por un funcionario, empleado o agente de los Estados Unidos o de cualquier departamento o agencia federal\u201d, establece la legislaci\u00f3n.<\/p>\n<p>La ley se aplica retroactivamente a 2022.<\/p>\n<p>El presidente de la C\u00e1mara de Representantes, Mike Johnson, declar\u00f3 el mi\u00e9rcoles que la medida a\u00f1adida al proyecto de ley por los republicanos del Senado lo tom\u00f3 por sorpresa y que el Partido Republicano de la C\u00e1mara redactar\u00eda un proyecto de ley aparte para eliminar dicha disposici\u00f3n, el cual se someter\u00e1 a votaci\u00f3n en una fecha posterior.<\/p>\n<p>El asunto se mencion\u00f3 por primera vez en una reuni\u00f3n del Comit\u00e9 de Reglas de la C\u00e1mara de Representantes, cuando el panel estaba analizando el proyecto de ley de financiamiento.<\/p>\n<p>El presidente del Comit\u00e9 de Asignaciones de la C\u00e1mara de Representantes, Tom Cole, afirm\u00f3 estar \u201csorprendido\u201d al ver la disposici\u00f3n. Mientras tanto, la principal dem\u00f3crata del comit\u00e9, la representante de Connecticut Rosa DeLauro, critic\u00f3 duramente la medida, afirmando que proporcionar\u00eda millones de d\u00f3lares a los senadores investigados en la pesquisa sobre el fraude electoral de las elecciones presidenciales de 2020.<\/p>\n<p>Los representantes republicanos Austin Scott, Chip Roy y Morgan Griffith manifestaron durante la reuni\u00f3n su preocupaci\u00f3n por una cl\u00e1usula. \u201cHe estado preguntando sobre esto desde anoche, y les dir\u00e9 que no creo que la direcci\u00f3n del Senado compartiera con la direcci\u00f3n de la C\u00e1mara lo que estaban haciendo\u201d, declar\u00f3 Scott en ese momento.<\/p>\n<p>M\u00e1s tarde, Scott declar\u00f3 a CNN: \u201cCreo que est\u00e1 mal redactada, pero me alegra que otras personas hayan prestado atenci\u00f3n, hayan le\u00eddo la legislaci\u00f3n y hayan podido explicar a los ciudadanos estadounidenses su contenido\u201d.<\/p>\n<p>Varios republicanos de la C\u00e1mara ya apoyan la eliminaci\u00f3n de dicha cl\u00e1usula.<\/p>\n<p>\u201cFue una estupidez, sinceramente, incluir esa cl\u00e1usula en este proyecto de ley\u201d, afirm\u00f3 el representante republicano Troy Nehls.<\/p>\n<p>Algunos senadores republicanos cuyos registros telef\u00f3nicos fueron confiscados en el marco del caso \u201cArctic Frost\u201d afirman que no buscar\u00e1n compensaci\u00f3n econ\u00f3mica, en medio de una fuerte reacci\u00f3n negativa a la cl\u00e1usula que les permite demandar.<\/p>\n<p>Un portavoz del senador Dan Sullivan, uno de los senadores cuyos registros telef\u00f3nicos fueron confiscados en la investigaci\u00f3n de Smith, declar\u00f3 a CNN el viernes que \u201cno planea demandar y apoya el proyecto de ley de la C\u00e1mara de Representantes para derogar la cl\u00e1usula\u201d. El asesor se\u00f1al\u00f3 que el senador se enter\u00f3 de ella al revisar el acuerdo de financiaci\u00f3n.<\/p>\n<p>El senador Bill Hagerty dijo en una publicaci\u00f3n en X el jueves que estaba \u201ca favor de que Jack Smith y todos los c\u00f3mplices de este abuso de poder rindieran cuentas\u201d, y luego agreg\u00f3: \u201cNo quiero ni busco una indemnizaci\u00f3n para m\u00ed mismo pagada con el dinero de los contribuyentes\u201d.<\/p>\n<p>El senador Josh Hawley tambi\u00e9n pidi\u00f3 rendici\u00f3n de cuentas, pero calific\u00f3 la medida de \u201cmala idea\u201d.<\/p>\n<p>\u201cCreo que la disposici\u00f3n del Senado es una mala idea. Debe haber rendici\u00f3n de cuentas por el escandaloso abuso de la separaci\u00f3n de poderes por parte del Departamento de Justicia de Biden, pero la manera correcta de hacerlo es mediante audiencias p\u00fablicas, una supervisi\u00f3n estricta, incluyendo a las compa\u00f1\u00edas de telecomunicaciones c\u00f3mplices, y el enjuiciamiento cuando corresponda\u201d, afirm\u00f3.<\/p>\n<p>La oficina de la senadora Marsha Blackburn inform\u00f3 a WBIR esta semana que ten\u00eda la intenci\u00f3n de demandar. En un comunicado a CNN el viernes, su oficina declar\u00f3: \u201cEl plan de la senadora Blackburn siempre ha sido buscar una sentencia declaratoria \u2014no una indemnizaci\u00f3n monetaria\u2014 para impedir que la izquierda viole los derechos constitucionales de los conservadores\u201d.<\/p>\n<p>Blackburn, quien se postula para gobernador de Tennessee en 2026, tambi\u00e9n enfrenta la presi\u00f3n del representante republicano John Rose, quien tambi\u00e9n aspira al cargo. Esta semana, Rose critic\u00f3 la disposici\u00f3n, calific\u00e1ndola de \u201ccl\u00e1usula venenosa\u201d.<\/p>\n<p>El senador Ron Johnson declar\u00f3 a CNN que \u201cpor el momento no tiene planes\u201d de demandar, y a\u00f1adi\u00f3: \u201cSi lo hiciera, ser\u00eda \u00fanicamente para utilizar los tribunales y exponer la instrumentalizaci\u00f3n corrupta de las fuerzas del orden federales por parte de las administraciones de Biden y Obama. Con la plena cooperaci\u00f3n del Departamento de Justicia y el FBI de Trump en nuestras investigaciones del Congreso, esto no deber\u00eda ser necesario\u201d.<\/p>\n<p>Anteriormente, Johnson hab\u00eda manifestado su apoyo a la disposici\u00f3n \u201ccomo medida disuasoria para prevenir futuros abusos de las agencias federales\u201d.<\/p>\n<p>El senador Tommy Tuberville declar\u00f3 el jueves en una publicaci\u00f3n en X que demandar\u00eda si un juez federal involucrado en la investigaci\u00f3n no fuera sometido a juicio pol\u00edtico y si Smith no fuera inhabilitado y encarcelado. Escribi\u00f3: \u201cSi no lo son, demandar\u00e9 con todo el rigor de la ley a cada funcionario de Biden involucrado para asegurarme de que esto NUNCA vuelva a sucederle a un conservador\u201d.<\/p>\n<p>No especific\u00f3 qu\u00e9 tipo de compensaci\u00f3n buscar\u00eda.<\/p>\n<p>No todos renuncian a la compensaci\u00f3n econ\u00f3mica.<\/p>\n<p>El senador Lindsey Graham respald\u00f3 esta disposici\u00f3n al hablar con periodistas en Carolina del Sur el mi\u00e9rcoles, afirmando que \u201capoya firmemente la idea de que si alguien ha sido agraviado, debe haber una reparaci\u00f3n\u201d.<\/p>\n<p>Al pregunt\u00e1rsele si presentar\u00eda una demanda, respondi\u00f3: \u201cPor supuesto. \u00bfY creen que voy a llegar a un acuerdo por US$ 1.000.000? No. Quiero que sea tan doloroso que nadie vuelva a hacer esto jam\u00e1s\u201d.<\/p>\n<p>CNN se comunic\u00f3 con su oficina el viernes.<\/p>\n<p>CNN tambi\u00e9n se comunic\u00f3 con la oficina de la senadora Cynthia Lummis, quien no respondi\u00f3 de inmediato a la solicitud de comentarios.<\/p>\n<p>Tras la reacci\u00f3n negativa de los republicanos de la C\u00e1mara de Representantes por la inclusi\u00f3n en el presupuesto gubernamental de una disposici\u00f3n que permitir\u00eda a los senadores demandar al Departamento de Justicia si se obtienen sus registros telef\u00f3nicos sin su consentimiento, una fuente republicana del Senado, familiarizada con el tema, defendi\u00f3 la legislaci\u00f3n como apropiada.<\/p>\n<p>La persona, que solicit\u00f3 el anonimato para hablar libremente sobre el razonamiento detr\u00e1s de la disposici\u00f3n, se\u00f1al\u00f3 una excepci\u00f3n en caso de que un senador est\u00e9 bajo investigaci\u00f3n penal y otras razones para la medida. La fuente se neg\u00f3 a comentar sobre las repercusiones pol\u00edticas y qu\u00e9 podr\u00eda hacer el Senado con la legislaci\u00f3n que los republicanos de la C\u00e1mara planean impulsar para revocar la pol\u00edtica.<\/p>\n<p>Detallaron:<\/p>\n<ul>\n<li>Exist\u00eda un fuerte inter\u00e9s entre los republicanos del Senado por responder a la investigaci\u00f3n de \u201cArctic Frost\u201d y a la ofensiva legal del Departamento de Justicia de Biden cuando el equipo de Jack Smith atac\u00f3 a senadores republicanos sin notificaci\u00f3n previa, en violaci\u00f3n de la ley vigente.<\/li>\n<li>El l\u00edder de la mayor\u00eda del Senado, John Thune, incluy\u00f3 esta disposici\u00f3n en la legislaci\u00f3n. El senador aprob\u00f3 el proyecto de ley a petici\u00f3n de los miembros de su bancada.<\/li>\n<li>Solo se aplica a los senadores porque modifica la ley vigente (2 U.S.C. 6628), que solo les aplica a ellos.<\/li>\n<li>Seg\u00fan esta disposici\u00f3n, los senadores deber\u00e1n ser notificados cuando el Departamento de Justicia solicite sus datos.<\/li>\n<li>Existe una excepci\u00f3n si la solicitud se debe a que el senador es objeto de una investigaci\u00f3n penal.<\/li>\n<li>Esto no es un asunto pol\u00edtico, sino de separaci\u00f3n de poderes.<\/li>\n<li>Esta disposici\u00f3n es vinculante y permite a los senadores demandar si no reciben la notificaci\u00f3n.<\/li>\n<li>Esto impide que futuras administraciones de cualquier partido utilicen al Departamento de Justicia como arma contra sus adversarios pol\u00edticos en el Senado.<\/li>\n<\/ul>\n<p>Todas las miradas est\u00e1n puestas en la C\u00e1mara de Representantes, que se espera que presente un proyecto de ley para anular la disposici\u00f3n.<\/p>\n<p>Si el proyecto de ley se aprueba en la C\u00e1mara, queda por ver si el l\u00edder republicano del Senado, John Thune, lo someter\u00e1 a votaci\u00f3n y cu\u00e1ndo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El proyecto de ley que puso fin al cierre del Gobierno inclu\u00eda una cl\u00e1usula que obliga al Departamento de Justicia y al FBI a notificar al Senado cuando un legislador est\u00e1 siendo investigado y si se le solicita informaci\u00f3n personal mediante citaci\u00f3n judicial. Los legisladores tambi\u00e9n pueden demandar al Departamento de Justicia en virtud de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468423","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La pol\u00e9mica cl\u00e1usula &quot;Arctic Frost&quot; incluida en el proyecto de ley de financiaci\u00f3n que divide a los legisladores republicanos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/17\/arctic-frost-cierre-gobierno-republicanos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La pol\u00e9mica cl\u00e1usula &quot;Arctic Frost&quot; incluida en el proyecto de ley de financiaci\u00f3n que divide a los legisladores republicanos - Noticias\" \/>\n<meta property=\"og:description\" content=\"El proyecto de ley que puso fin al cierre del Gobierno inclu\u00eda una cl\u00e1usula que obliga al Departamento de Justicia y al FBI a notificar al Senado cuando un legislador est\u00e1 siendo investigado y si se le solicita informaci\u00f3n personal mediante citaci\u00f3n judicial. Los legisladores tambi\u00e9n pueden demandar al Departamento de Justicia en virtud de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/17\/arctic-frost-cierre-gobierno-republicanos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-17T14:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/17\/arctic-frost-cierre-gobierno-republicanos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/17\/arctic-frost-cierre-gobierno-republicanos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La pol\u00e9mica cl\u00e1usula &#171;Arctic Frost&#187; incluida en el proyecto de ley de financiaci\u00f3n que divide a los legisladores republicanos\",\"datePublished\":\"2025-11-17T14:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/17\/arctic-frost-cierre-gobierno-republicanos-trax\/\"},\"wordCount\":1868,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/17\/arctic-frost-cierre-gobierno-republicanos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/17\/arctic-frost-cierre-gobierno-republicanos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/17\/arctic-frost-cierre-gobierno-republicanos-trax\/\",\"name\":\"La pol\u00e9mica cl\u00e1usula \\\"Arctic Frost\\\" incluida en el proyecto de ley de financiaci\u00f3n que divide a los legisladores republicanos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-17T14:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/17\/arctic-frost-cierre-gobierno-republicanos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/17\/arctic-frost-cierre-gobierno-republicanos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/17\/arctic-frost-cierre-gobierno-republicanos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La pol\u00e9mica cl\u00e1usula &#171;Arctic Frost&#187; incluida en el proyecto de ley de financiaci\u00f3n que divide a los legisladores republicanos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La pol\u00e9mica cl\u00e1usula \"Arctic Frost\" incluida en el proyecto de ley de financiaci\u00f3n que divide a los legisladores republicanos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/17\/arctic-frost-cierre-gobierno-republicanos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La pol\u00e9mica cl\u00e1usula \"Arctic Frost\" incluida en el proyecto de ley de financiaci\u00f3n que divide a los legisladores republicanos - Noticias","og_description":"El proyecto de ley que puso fin al cierre del Gobierno inclu\u00eda una cl\u00e1usula que obliga al Departamento de Justicia y al FBI a notificar al Senado cuando un legislador est\u00e1 siendo investigado y si se le solicita informaci\u00f3n personal mediante citaci\u00f3n judicial. Los legisladores tambi\u00e9n pueden demandar al Departamento de Justicia en virtud de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/17\/arctic-frost-cierre-gobierno-republicanos-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-17T14:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/17\/arctic-frost-cierre-gobierno-republicanos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/17\/arctic-frost-cierre-gobierno-republicanos-trax\/"},"author":{"name":"","@id":""},"headline":"La pol\u00e9mica cl\u00e1usula &#171;Arctic Frost&#187; incluida en el proyecto de ley de financiaci\u00f3n que divide a los legisladores republicanos","datePublished":"2025-11-17T14:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/17\/arctic-frost-cierre-gobierno-republicanos-trax\/"},"wordCount":1868,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/17\/arctic-frost-cierre-gobierno-republicanos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/17\/arctic-frost-cierre-gobierno-republicanos-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/17\/arctic-frost-cierre-gobierno-republicanos-trax\/","name":"La pol\u00e9mica cl\u00e1usula \"Arctic Frost\" incluida en el proyecto de ley de financiaci\u00f3n que divide a los legisladores republicanos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-17T14:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/17\/arctic-frost-cierre-gobierno-republicanos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/17\/arctic-frost-cierre-gobierno-republicanos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/17\/arctic-frost-cierre-gobierno-republicanos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La pol\u00e9mica cl\u00e1usula &#171;Arctic Frost&#187; incluida en el proyecto de ley de financiaci\u00f3n que divide a los legisladores republicanos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/17\/arctic-frost-cierre-gobierno-republicanos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La pol\u00e9mica cl\u00e1usula &#171;Arctic Frost&#187; incluida en el proyecto de ley de financiaci\u00f3n que divide a los legisladores republicanos","url":"http:\/\/noticiasya.com\/colorado\/2025\/11\/17\/arctic-frost-cierre-gobierno-republicanos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2025\/11\/17\/arctic-frost-cierre-gobierno-republicanos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-17T14:03:38Z","datePublished":"2025-11-17T14:03:38Z","dateModified":"2025-11-17T14:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La pol\\u00e9mica cl\\u00e1usula &#171;Arctic Frost&#187; incluida en el proyecto de ley de financiaci\\u00f3n que divide a los legisladores republicanos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2025\\\/11\\\/17\\\/arctic-frost-cierre-gobierno-republicanos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2025\\\/11\\\/17\\\/arctic-frost-cierre-gobierno-republicanos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-17T14:03:38Z\",\"datePublished\":\"2025-11-17T14:03:38Z\",\"dateModified\":\"2025-11-17T14:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1468283,"url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/12\/congreso-paquete-financiacion-reabrir-gobierno-trump-trax\/","url_meta":{"origin":1468423,"position":0},"title":"El Congreso aprueba paquete de financiamiento para reabrir el Gobierno federal y lo env\u00eda a Trump para su firma","author":"","date":"noviembre 12, 2025","format":false,"excerpt":"Ambas c\u00e1maras del Congreso han votado a favor de poner fin al cierre federal m\u00e1s largo de la historia, y enviaron un proyecto de ley de financiamiento para reabrir el Gobierno al presidente Donald Trump para su firma.La C\u00e1mara de Representantes vot\u00f3 este mi\u00e9rcoles por la noche para dar la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472334,"url":"https:\/\/noticiasya.com\/colorado\/2026\/03\/19\/archivos-epstein-legisladores-victimas-exigen-publiquen-mas-trax\/","url_meta":{"origin":1468423,"position":1},"title":"\u00bfHemos visto ya los \u00faltimos archivos de Epstein? Legisladores y v\u00edctimas exigen que se publiquen m\u00e1s","author":"","date":"marzo 19, 2026","format":false,"excerpt":"Una ley de transparencia aprobada por el Congreso ha obligado a publicar m\u00e1s archivos de Epstein que nunca, pero algunos legisladores y v\u00edctimas est\u00e1n explorando formas de presionar al Departamento de Justicia para que revele a\u00fan m\u00e1s informaci\u00f3n del voluminoso material que se mantiene oculto.Unos 2,5 millones de documentos de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463486,"url":"https:\/\/noticiasya.com\/colorado\/2025\/06\/12\/fbi-allano-casa-equivocada-corte-familia-demanda-trax\/","url_meta":{"origin":1468423,"position":2},"title":"El FBI allan\u00f3 la casa equivocada. La Corte Suprema dictamina que la familia puede demandar","author":"","date":"junio 12, 2025","format":false,"excerpt":"Hace ocho a\u00f1os, el FBI allan\u00f3 una casa incorrecta por error en mitad de la noche. A la familia afectada se le permitir\u00e1 continuar con su demanda por da\u00f1os y perjuicios despu\u00e9s de que este jueves la Corte Suprema enviara su caso de regreso a un tribunal federal de apelaciones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470835,"url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/04\/trump-republicanos-nacionalicen-elecciones-ee-uu-trax\/","url_meta":{"origin":1468423,"position":3},"title":"Trump quiere que los republicanos &#171;nacionalicen&#187; las elecciones en EE.UU. La Constituci\u00f3n podr\u00eda evitarlo","author":"","date":"febrero 4, 2026","format":false,"excerpt":"Una amplia gama de expertos electorales afirman que el llamado del presidente Donald Trump a los republicanos a \u201cnacionalizar el voto\u201d es una escalada alarmante y potencialmente peligrosa de sus continuos esfuerzos por transformar el modo en que se administran las elecciones en EE.UU.Los comentarios de Trump fueron notables tanto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466179,"url":"https:\/\/noticiasya.com\/colorado\/2025\/09\/05\/saga-archivos-epstein-victimas-trump-trax\/","url_meta":{"origin":1468423,"position":4},"title":"Qu\u00e9 sigue en la saga de los archivos de Epstein","author":"","date":"septiembre 5, 2025","format":false,"excerpt":"El furor pol\u00edtico nacional en torno a los archivos del caso Jeffrey Epstein se ha intensificado en los \u00faltimos d\u00edas, incluso cuando el presidente Donald Trump ha tratado de desestimar los reclamos de mayor transparencia como un \u201cenga\u00f1o dem\u00f3crata\u201d.En el Capitolio, el esfuerzo por obtener m\u00e1s registros de los archivos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468248,"url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/11\/que-contiene-proyecto-ley-fin-cierre-gobierno-trax\/","url_meta":{"origin":1468423,"position":5},"title":"\u00bfQu\u00e9 contiene el proyecto de ley que pondr\u00eda fin al cierre del Gobierno m\u00e1s largo en la historia de EE.UU.?","author":"","date":"noviembre 11, 2025","format":false,"excerpt":"El Congreso se est\u00e1 moviendo r\u00e1pidamente para aprobar un paquete de financiamiento que pondr\u00eda fin al cierre federal m\u00e1s largo en la historia de Estados Unidos.La C\u00e1mara tiene previsto votar el mi\u00e9rcoles sobre un proyecto de ley de compromiso despu\u00e9s de que el Senado aprobara el paquete la noche del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1468423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1468423"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1468423\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1468423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1468423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1468423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}