{"id":1468441,"date":"2025-11-17T17:03:55","date_gmt":"2025-11-18T01:03:55","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/17\/quien-es-pipo-lobos-ecuador-orix\/"},"modified":"2025-11-17T17:03:55","modified_gmt":"2025-11-18T01:03:55","slug":"quien-es-pipo-lobos-ecuador-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2025\/11\/17\/quien-es-pipo-lobos-ecuador-orix\/","title":{"rendered":"\u00bfQui\u00e9n es alias &#171;Pipo&#187;, el supuesto l\u00edder de la banda ecuatoriana Los Lobos que habr\u00eda fingido su propia muerte?"},"content":{"rendered":"<p>Wilmer Geovanny Chavarr\u00eda Barre, alias \u201cPipo\u201d, se\u00f1alado por el Gobierno de Ecuador como el delincuente m\u00e1s buscado de la regi\u00f3n y considerado el m\u00e1ximo l\u00edder de Los Lobos, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/11\/16\/latinoamerica\/detienen-espana-pipo-lider-organizacion-criminal-los-lobos-ecuador-orix\">fue detenido este domingo en M\u00e1laga, Espa\u00f1a.<\/a> Su captura pone fin a a\u00f1os de b\u00fasqueda internacional que se complicaron, seg\u00fan autoridades ecuatorianas, cuando el capo fingi\u00f3 su muerte en 2021, cambi\u00f3 de identidad y se someti\u00f3 a siete cirug\u00edas faciales para evadir a la justicia.<\/p>\n<p>\u201cHemos capturado al objetivo de m\u00e1s alto valor. Hoy las mafias retroceden.<br \/>Hoy gana el Ecuador\u201d, <a href=\"https:\/\/x.com\/DanielNoboaOk\/status\/1990030648287858909?s=20\">anunci\u00f3 el presidente Daniel Noboa en X<\/a>. Su ministro del Interior, John Reimberg, dijo que el l\u00edder criminal es responsable de al menos 400 muertes y de coordinar atentados, narcotr\u00e1fico y miner\u00eda ilegal desde el extranjero.<\/p>\n<p>Reimberg <a href=\"https:\/\/x.com\/JohnReimberg\/status\/1990042592529031197\">explic\u00f3 <\/a>que Chavarr\u00eda estuvo recluido entre 2011 y 2019 en la Penitenciar\u00eda del Litoral y en la c\u00e1rcel de Turi, desde donde manej\u00f3 \u201cdurante a\u00f1os\u201d operaciones criminales para Los Lobos.<\/p>\n<p>Tras salir en libertad, su estructura se expandi\u00f3 y, seg\u00fan el ministro, lleg\u00f3 a superar a la de Adolfo Mac\u00edas, alias \u2018Fito\u2019, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/06\/25\/latinoamerica\/quien-es-alias-fito-lider-choneros-ecuador-orix\">l\u00edder hist\u00f3rico de Los Choneros<\/a> y quien actualmente <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/09\/19\/eeuu\/fito-regresa-tribunal-nueva-york-defensa-fiscalia-efe\">enfrenta un juicio en una corte de Nueva York<\/a> por cargos federales de narcotr\u00e1fico y tr\u00e1fico de armas<\/p>\n<p>\u201cEste individuo \u2014para quien Fito no es m\u00e1s que un aprendiz\u2014 fingi\u00f3 su muerte en 2021\u201d, escribi\u00f3 el ministro en su cuenta de X.<\/p>\n<p>De acuerdo con el ministro, despu\u00e9s de presentar el acta de defunci\u00f3n falsa por covid-19, Chavarr\u00eda obtuvo una nueva identidad en Venezuela, luego se registr\u00f3 en Colombia, obtuvo un pasaporte colombiano y viaj\u00f3 con ese documento a Espa\u00f1a en 2022, donde instal\u00f3 una base de operaciones criminales.<\/p>\n<p>Desde Europa \u2014principalmente en Espa\u00f1a, Pa\u00edses Bajos e Italia\u2014, y con conexiones en M\u00e9xico y Colombia, \u201cPipo\u201d habr\u00eda dirigido un esquema de narcotr\u00e1fico y lavado de dinero vinculado al Cartel Nueva Generaci\u00f3n Ecuador y a carteles mexicanos, colombianos y europeos.<\/p>\n<p>\u201cEstaba como muerto. Ten\u00eda un acta de defunci\u00f3n de 2021. Pedimos peritaje y se determin\u00f3 que era falsa\u201d, <a href=\"https:\/\/www.youtube.com\/watch?v=sLxDo-G9nRY\">explic\u00f3 el ministro en el programa Sucre Radio<\/a>, quien a\u00f1adi\u00f3 que el capo adopt\u00f3 una nueva identidad y operaba desde Europa mientras ordenaba asesinatos en Ecuador.<\/p>\n<p>Reimberg, quien se encontraba este domingo en Madrid, tambi\u00e9n sostiene que \u201cPipo\u201d se someti\u00f3 a siete cirug\u00edas de rostro, y que viv\u00eda entre Espa\u00f1a y Dub\u00e1i, un destino que autoridades describen como un punto de refugio para redes criminales que controlan la miner\u00eda ilegal y el tr\u00e1fico de oro.<\/p>\n<p>La localizaci\u00f3n de Chavarr\u00eda requiri\u00f3 un trabajo conjunto entre la Polic\u00eda de Ecuador y la Polic\u00eda Nacional de Espa\u00f1a que dur\u00f3 varios a\u00f1os, seg\u00fan Reimberg. Un equipo de Ecuador se instal\u00f3 en Espa\u00f1a para seguir cada una de sus identidades y movimientos.<\/p>\n<p>\u201cEl trabajo con la Policia espa\u00f1ola fue fundamental para poder seguir el rastro. Enviamos un equipo que ha estado trabajando todo este tiempo en conjunto con la Policia de Espa\u00f1a haciendo el seguimiento hasta lograr obtener la ubicaci\u00f3n de cuando ven\u00eda a espa\u00f1a donde se quedaba\u201d, afirm\u00f3 Reimberg. Seg\u00fan su versi\u00f3n, \u201cPipo\u201d frecuentaba mansiones y hoteles de lujo.<\/p>\n<p>Su captura se produjo en M\u00e1laga, donde las autoridades espa\u00f1olas lograron confirmar su verdadera identidad tras el cruce de informaci\u00f3n enviado por Ecuador, seg\u00fan el ministro.<\/p>\n<p>\u201cCon cada una de las identidades que \u00e9l ten\u00eda se hizo el seguimiento pertinente hasta poder llegar a saber que estaba ac\u00e1 en Europa\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Chavarr\u00eda se convirti\u00f3 en el delincuente m\u00e1s buscado de Ecuador despu\u00e9s de que, en junio de 2025, las autoridades <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/06\/25\/latinoamerica\/capturan-adolfo-macias-fito-lider-banda-choneros-ecuador-orix\">recapturaran <\/a>a Jos\u00e9 Adolfo Mac\u00edas Villamar, alias \u201cFito\u201d, l\u00edder de Los Choneros, quien hab\u00eda permanecido pr\u00f3fugo durante un a\u00f1o y medio tras escapar de la C\u00e1rcel Regional de Guayaquil, donde cumpl\u00eda una condena de 34 a\u00f1os por narcotr\u00e1fico, asesinato y delincuencia organizada.<\/p>\n<p>Bajo el mando de \u201cPipo\u201d, Los Lobos desplazaron a Los Choneros como la organizaci\u00f3n criminal m\u00e1s poderosa del pa\u00eds. Lo hicieron mediante alianzas con el C\u00e1rtel Jalisco Nueva Generaci\u00f3n (CJNG), la expansi\u00f3n del control territorial y la incursi\u00f3n en la miner\u00eda ilegal.<\/p>\n<p>En 2024, el Departamento del Tesoro de Estados Unidos <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/06\/06\/tesoro-sanciona-banda-los-lobos-pipo-orix\">sancion\u00f3<\/a> a Los Lobos, describi\u00e9ndolos como una estructura con \u201cmiles de miembros\u201d que ha impulsado la escalada de violencia en Ecuador. Washington identific\u00f3 a Chavarr\u00eda como su m\u00e1ximo l\u00edder, involucrado en tr\u00e1fico de drogas, asesinatos por encargo y miner\u00eda ilegal.<\/p>\n<p>El Tesoro tambi\u00e9n se\u00f1al\u00f3 que, mientras estaba encarcelado entre 2011 y 2018, \u201cPipo\u201d dirig\u00eda grupos de sicarios que en ese entonces operaban bajo la \u00f3rbita de Los Choneros, antes de convertirse en su rival. Seg\u00fan las autoridades estadounidenses, en 2022 orden\u00f3 la muerte de dos l\u00edderes de esa organizaci\u00f3n.<\/p>\n<p>Adem\u00e1s, el Departamento del Tesoro dice que Los Lobos han sido se\u00f1alados en Ecuador por planificar el asesinato del candidato presidencial Fernando Villavicencio el 9 de agosto de 2023 tras un mitin en Quito. El Departamento de Estado de EE.UU. ofreci\u00f3 una recompensa de US$ 6 millones por informaci\u00f3n sobre los responsables de este crimen que conmovi\u00f3 al pa\u00eds.<\/p>\n<p>Tras su captura, Estados Unidos felicit\u00f3 a Ecuador por el operativo. \u201cRecuerden: si los gobiernos no combaten el crimen, es porque son C\u00d3MPLICES; tolerar el crimen es una DECISI\u00d3N, no un DESTINO. \u00a1Fuerte abrazo a nuestros amigos ecuatorianos por esta gran haza\u00f1a y todo mi respeto!\u201d, <a href=\"https:\/\/x.com\/DeputySecState\/status\/1990100193492992042\">escribi\u00f3 <\/a>el subsecretario de Estado de EE.UU., Christopher Landau, en su cuenta de X.<\/p>\n<p>La detenci\u00f3n de \u201cPipo\u201d se anunci\u00f3 el mismo d\u00eda en que el presidente Noboa <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/11\/16\/latinoamerica\/referendum-ecuador-resultados-noboa-orix\">enfrent\u00f3 un rev\u00e9s pol\u00edtico<\/a>: los ecuatorianos rechazaron en un refer\u00e9ndum la instalaci\u00f3n de bases militares extranjeras, una medida que el gobierno ve\u00eda como clave para combatir al crimen organizado.<\/p>\n<p>Aunque la captura fue celebrada como un avance importante, el resultado del refer\u00e9ndum dej\u00f3 dudas sobre el margen pol\u00edtico del Ejecutivo para sostener su estrategia de seguridad.<\/p>\n<p>El ministro de Defensa Nacional de Ecuador, Gian Carlo Loffredo, <a href=\"https:\/\/www.instagram.com\/reel\/DRID0eMkfM2\/\">confirm\u00f3 <\/a>a la prensa local que Ecuador solicitar\u00e1 la extradici\u00f3n de Chavarr\u00eda. Una vez en el pa\u00eds, dijo, podr\u00eda ser trasladado a El Encuentro, la nueva c\u00e1rcel de m\u00e1xima seguridad que el gobierno describe como el centro de su pol\u00edtica de combate al crimen organizado.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wilmer Geovanny Chavarr\u00eda Barre, alias \u201cPipo\u201d, se\u00f1alado por el Gobierno de Ecuador como el delincuente m\u00e1s buscado de la regi\u00f3n y considerado el m\u00e1ximo l\u00edder de Los Lobos, fue detenido este domingo en M\u00e1laga, Espa\u00f1a. Su captura pone fin a a\u00f1os de b\u00fasqueda internacional que se complicaron, seg\u00fan autoridades ecuatorianas, cuando el capo fingi\u00f3 su [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468441","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQui\u00e9n es alias &quot;Pipo&quot;, el supuesto l\u00edder de la banda ecuatoriana Los Lobos que habr\u00eda fingido su propia muerte? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/17\/quien-es-pipo-lobos-ecuador-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQui\u00e9n es alias &quot;Pipo&quot;, el supuesto l\u00edder de la banda ecuatoriana Los Lobos que habr\u00eda fingido su propia muerte? - Noticias\" \/>\n<meta property=\"og:description\" content=\"Wilmer Geovanny Chavarr\u00eda Barre, alias \u201cPipo\u201d, se\u00f1alado por el Gobierno de Ecuador como el delincuente m\u00e1s buscado de la regi\u00f3n y considerado el m\u00e1ximo l\u00edder de Los Lobos, fue detenido este domingo en M\u00e1laga, Espa\u00f1a. Su captura pone fin a a\u00f1os de b\u00fasqueda internacional que se complicaron, seg\u00fan autoridades ecuatorianas, cuando el capo fingi\u00f3 su [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/17\/quien-es-pipo-lobos-ecuador-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-18T01:03:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/17\/quien-es-pipo-lobos-ecuador-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/17\/quien-es-pipo-lobos-ecuador-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfQui\u00e9n es alias &#171;Pipo&#187;, el supuesto l\u00edder de la banda ecuatoriana Los Lobos que habr\u00eda fingido su propia muerte?\",\"datePublished\":\"2025-11-18T01:03:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/17\/quien-es-pipo-lobos-ecuador-orix\/\"},\"wordCount\":1151,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/17\/quien-es-pipo-lobos-ecuador-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/17\/quien-es-pipo-lobos-ecuador-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/17\/quien-es-pipo-lobos-ecuador-orix\/\",\"name\":\"\u00bfQui\u00e9n es alias \\\"Pipo\\\", el supuesto l\u00edder de la banda ecuatoriana Los Lobos que habr\u00eda fingido su propia muerte? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-18T01:03:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/17\/quien-es-pipo-lobos-ecuador-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/17\/quien-es-pipo-lobos-ecuador-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/17\/quien-es-pipo-lobos-ecuador-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQui\u00e9n es alias &#171;Pipo&#187;, el supuesto l\u00edder de la banda ecuatoriana Los Lobos que habr\u00eda fingido su propia muerte?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQui\u00e9n es alias \"Pipo\", el supuesto l\u00edder de la banda ecuatoriana Los Lobos que habr\u00eda fingido su propia muerte? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/17\/quien-es-pipo-lobos-ecuador-orix\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQui\u00e9n es alias \"Pipo\", el supuesto l\u00edder de la banda ecuatoriana Los Lobos que habr\u00eda fingido su propia muerte? - Noticias","og_description":"Wilmer Geovanny Chavarr\u00eda Barre, alias \u201cPipo\u201d, se\u00f1alado por el Gobierno de Ecuador como el delincuente m\u00e1s buscado de la regi\u00f3n y considerado el m\u00e1ximo l\u00edder de Los Lobos, fue detenido este domingo en M\u00e1laga, Espa\u00f1a. Su captura pone fin a a\u00f1os de b\u00fasqueda internacional que se complicaron, seg\u00fan autoridades ecuatorianas, cuando el capo fingi\u00f3 su [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/17\/quien-es-pipo-lobos-ecuador-orix\/","og_site_name":"Noticias","article_published_time":"2025-11-18T01:03:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/17\/quien-es-pipo-lobos-ecuador-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/17\/quien-es-pipo-lobos-ecuador-orix\/"},"author":{"name":"","@id":""},"headline":"\u00bfQui\u00e9n es alias &#171;Pipo&#187;, el supuesto l\u00edder de la banda ecuatoriana Los Lobos que habr\u00eda fingido su propia muerte?","datePublished":"2025-11-18T01:03:55+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/17\/quien-es-pipo-lobos-ecuador-orix\/"},"wordCount":1151,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/17\/quien-es-pipo-lobos-ecuador-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/17\/quien-es-pipo-lobos-ecuador-orix\/","url":"https:\/\/noticiasya.com\/2025\/11\/17\/quien-es-pipo-lobos-ecuador-orix\/","name":"\u00bfQui\u00e9n es alias \"Pipo\", el supuesto l\u00edder de la banda ecuatoriana Los Lobos que habr\u00eda fingido su propia muerte? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-18T01:03:55+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/17\/quien-es-pipo-lobos-ecuador-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/17\/quien-es-pipo-lobos-ecuador-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/17\/quien-es-pipo-lobos-ecuador-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQui\u00e9n es alias &#171;Pipo&#187;, el supuesto l\u00edder de la banda ecuatoriana Los Lobos que habr\u00eda fingido su propia muerte?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/17\/quien-es-pipo-lobos-ecuador-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfQui\u00e9n es alias &#171;Pipo&#187;, el supuesto l\u00edder de la banda ecuatoriana Los Lobos que habr\u00eda fingido su propia muerte?","url":"http:\/\/noticiasya.com\/colorado\/2025\/11\/17\/quien-es-pipo-lobos-ecuador-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2025\/11\/17\/quien-es-pipo-lobos-ecuador-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-18T01:03:55Z","datePublished":"2025-11-18T01:03:55Z","dateModified":"2025-11-18T01:03:55Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfQui\\u00e9n es alias &#171;Pipo&#187;, el supuesto l\\u00edder de la banda ecuatoriana Los Lobos que habr\\u00eda fingido su propia muerte?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2025\\\/11\\\/17\\\/quien-es-pipo-lobos-ecuador-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2025\\\/11\\\/17\\\/quien-es-pipo-lobos-ecuador-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-18T01:03:55Z\",\"datePublished\":\"2025-11-18T01:03:55Z\",\"dateModified\":\"2025-11-18T01:03:55Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1468394,"url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/16\/detienen-espana-pipo-lider-organizacion-criminal-los-lobos-ecuador-orix\/","url_meta":{"origin":1468441,"position":0},"title":"Detienen en Espa\u00f1a a &#171;Pipo&#187;, l\u00edder de la organizaci\u00f3n criminal Los Lobos de Ecuador","author":"","date":"noviembre 16, 2025","format":false,"excerpt":"Wilmer Chavarr\u00eda, alias \u201cPipo\u201d, supuesto l\u00edder de Los Lobos, la banda criminal m\u00e1s grande y poderosa de Ecuador, fue detenido este domingo, seg\u00fan inform\u00f3 el presidente Daniel Noboa. El anuncio ocurre el mismo d\u00eda en que los ecuatorianos votan en un refer\u00e9ndum que incluye medidas que el Gobierno considera clave\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466154,"url":"https:\/\/noticiasya.com\/colorado\/2025\/09\/04\/eeuu-lobos-choneros-ecuador-grupos-terroristas-orix\/","url_meta":{"origin":1468441,"position":1},"title":"EE.UU. designa a las bandas ecuatorianas Los Lobos y Los Choneros como grupos terroristas","author":"","date":"septiembre 4, 2025","format":false,"excerpt":"El Departamento de Estado de EE.UU. design\u00f3 a Los Lobos y Los Choneros, dos de los principales grupos criminales de Ecuador, como organizaciones terroristas extranjeras, seg\u00fan dio a conocer este jueves en una nota p\u00fablica.La banda Los Choneros es una de las pandillas m\u00e1s temidas del pa\u00eds sudamericano y ha\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443408,"url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/09\/fuga-de-alias-fito-lider-de-una-banda-criminal-de-ecuador-tensa-la-seguridad-mientras-se-intensifica-su-busqueda\/","url_meta":{"origin":1468441,"position":2},"title":"Fuga de alias \u201cFito\u201d, l\u00edder de una banda criminal de Ecuador, tensa la seguridad mientras se intensifica su b\u00fasqueda","author":"","date":"enero 9, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Luego de que la Fiscal\u00eda y el Gobierno de Ecuador confirmaran el domingo la fuga de Adolfo Mac\u00edas, alias \u201cFito\u201d, de la c\u00e1rcel regional de Guayaquil, m\u00e1s de 3.000 integrantes de la Polic\u00eda y las Fuerzas Armadas se han desplegado para dar con su paradero, seg\u00fan el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471568,"url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/23\/impacto-mencho-violencia-carteles-ecuador-colombia-orix\/","url_meta":{"origin":1468441,"position":3},"title":"El impacto m\u00e1s all\u00e1 de M\u00e9xico: \u00bfpodr\u00e1 la ca\u00edda del Mencho extender tambi\u00e9n la violencia entre carteles de Ecuador y Colombia?","author":"","date":"febrero 23, 2026","format":false,"excerpt":"La muerte del capo mexicano Nemesio Oseguera Cervantes, alias \u201cEl Mencho\u201d, l\u00edder del Cartel Jalisco Nueva Generaci\u00f3n (CJNG), no solo marca un punto de quiebre en el mapa criminal de M\u00e9xico, sino que proyecta un posible efecto domin\u00f3 sobre los pa\u00edses del sur de Am\u00e9rica Latina que forman parte de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471485,"url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/20\/aplazan-audiencia-alias-fito-eeuu-ecuador-versiones-negociacion-orix\/","url_meta":{"origin":1468441,"position":4},"title":"Aplazan la audiencia de alias &#171;Fito&#187; en EE.UU. y crecen versiones de una posible negociaci\u00f3n con fiscales","author":"","date":"febrero 20, 2026","format":false,"excerpt":"La audiencia del narcotraficante ecuatoriano Jos\u00e9 Adolfo Mac\u00edas Villamar, alias \u201cFito\u201d, prevista para el 26 de febrero en la corte federal del Distrito Este de Nueva York , fue aplazada hasta el 17 de septiembre, una decisi\u00f3n que ha generado interrogantes sobre una posible negociaci\u00f3n entre el acusado y la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463955,"url":"https:\/\/noticiasya.com\/colorado\/2025\/06\/25\/quien-es-alias-fito-lider-choneros-ecuador-orix\/","url_meta":{"origin":1468441,"position":5},"title":"\u00bfQui\u00e9n es alias Fito? Estos son los hechos que han marcado su vida criminal en Ecuador","author":"","date":"junio 25, 2025","format":false,"excerpt":"Hablar de Jos\u00e9 Adolfo Mac\u00edas Villamar, m\u00e1s conocido como Fito, es hablar de uno de los criminales m\u00e1s temidos del Ecuador. Fue capturado por las autoridades de Ecuador el 25 de junio, seg\u00fan inform\u00f3 el presidente Daniel Noboa.El criminal logr\u00f3 poner en jaque al sistema de seguridad desde hace varios\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1468441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1468441"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1468441\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1468441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1468441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1468441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}