{"id":1468471,"date":"2025-11-18T10:03:44","date_gmt":"2025-11-18T18:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/18\/desplome-criptomonedas-acciones-mercado-trax\/"},"modified":"2025-11-18T10:03:44","modified_gmt":"2025-11-18T18:03:44","slug":"desplome-criptomonedas-acciones-mercado-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2025\/11\/18\/desplome-criptomonedas-acciones-mercado-trax\/","title":{"rendered":"Por qu\u00e9 las criptomonedas se est\u00e1n desplomando y las acciones siguen cayendo"},"content":{"rendered":"<p>El bitcoin y las acciones est\u00e1n en ca\u00edda y los inversionistas dicen que podr\u00eda haber m\u00e1s turbulencia en el futuro.<\/p>\n<p>Las acciones en EE.UU. bajaron el martes, extendiendo una reciente <a href=\"https:\/\/www.cnn.com\/2025\/11\/17\/investing\/us-stock-market\">racha de ca\u00eddas<\/a>.<br \/>El Dow cay\u00f3 413 puntos, o 0,89 %. El S&#038;P 500 baj\u00f3 0,6 %. El Nasdaq Composite, de fuerte presencia tecnol\u00f3gica, retrocedi\u00f3 0,9 %.<\/p>\n<p>En las \u00faltimas semanas, los inversionistas han evitado cada vez m\u00e1s los activos de riesgo como las acciones de IA y las criptomonedas. No ayuda la incertidumbre sobre si la Reserva Federal recortar\u00e1 las tasas de inter\u00e9s el pr\u00f3ximo mes. Esta actitud de aversi\u00f3n al riesgo est\u00e1 afectando al bitcoin, una inversi\u00f3n altamente especulativa y vol\u00e1til.<\/p>\n<p>Apenas seis semanas despu\u00e9s de alcanzar un m\u00e1ximo hist\u00f3rico por encima de US$ 126.000, el bitcoin se ha desplomado m\u00e1s de 26 %. La criptomoneda, la ma\u00f1ana del martes, se negociaba justo por debajo de los US$ 93.000, borrando todas sus ganancias de este a\u00f1o.<\/p>\n<p>El lunes por la noche, el bitcoin cay\u00f3 por <a href=\"https:\/\/www.cnn.com\/2025\/11\/17\/investing\/us-stock-market\">debajo de los US$ 90.000<\/a> por primera vez en siete meses, antes de recuperar parte de las p\u00e9rdidas el martes por la ma\u00f1ana.<\/p>\n<p>En t\u00e9rminos de Wall Street, el bitcoin est\u00e1 en un mercado bajista (cuando un precio cae m\u00e1s de 20 % desde un tope reciente). El bitcoin ha perdido m\u00e1s de US$ 600.000 millones en valor de mercado durante su ca\u00edda, seg\u00fan datos de CoinMarketCap.<\/p>\n<p>\u201cLa correcci\u00f3n del bitcoin es parte de un cambio m\u00e1s amplio en el sentimiento de riesgo\u201d, dijo Haider Rafique, socio gerente global de OKX, una casa de cambio de criptomonedas.<\/p>\n<p>Tras un fuerte repunte de seis meses en las acciones, aumentan las preocupaciones sobre valoraciones caras y enormes planes de gasto por parte de las grandes empresas tecnol\u00f3gicas. Una amplia gama de acciones tecnol\u00f3gicas y de IA bajaron el martes: las acciones de Nvidia (NVDA) cayeron 2,3 %. Las de Amazon (AMZN) bajaron 3,1 % y las de Microsoft (MSFT) retrocedieron 3,3 %.<\/p>\n<p>El Nasdaq, de fuerte presencia tecnol\u00f3gica, ha ca\u00eddo m\u00e1s de 6 % desde que alcanz\u00f3 un m\u00e1ximo hist\u00f3rico a finales de octubre y ha perdido aproximadamente US$ 2,5 billones en valor de mercado durante su descenso.<\/p>\n<p>El \u00edndice de miedo de Wall Street, el VIX, subi\u00f3 11 % el martes. El <a href=\"https:\/\/www.cnn.com\/markets\/fear-and-greed?utm_source=hp\">\u00edndice de Miedo y Avaricia<\/a> de CNN se mantuvo en \u201cmiedo extremo\u201d y descendi\u00f3 a su nivel m\u00e1s bajo desde principios de abril.<\/p>\n<p>A la presi\u00f3n sobre el bitcoin se suma que los inversionistas a largo plazo podr\u00edan estar cerrando sus posiciones para asegurar ganancias tras los mete\u00f3ricos aumentos de los \u00faltimos a\u00f1os.<\/p>\n<p>\u201cEl bitcoin ha tenido dificultades debido a la presi\u00f3n de venta de los tenedores a largo plazo que toman ganancias, pero tambi\u00e9n por la incertidumbre en torno a la pol\u00edtica de la Fed, el entorno de liquidez y otras condiciones macroecon\u00f3micas\u201d, dijo Gerry O\u2019Shea, jefe de an\u00e1lisis global de mercados en Hashdex Asset Management.<\/p>\n<p>El bitcoin ha tenido problemas para recuperarse significativamente desde un <a href=\"https:\/\/www.cnn.com\/2025\/10\/13\/business\/crypto-bitcoin-price-drop-trump-tariffs\">desplome <\/a>repentino el 10 de octubre, cuando el presidente Donald Trump reaviv\u00f3 su guerra comercial con China. Algunos compradores y vendedores han abandonado el mercado desde entonces, por lo que hay menos \u00f3rdenes para el bitcoin, dejando el precio m\u00e1s susceptible a la volatilidad, seg\u00fan Peter Chung, jefe de Presto Research.<\/p>\n<p>\u201cEl bitcoin est\u00e1 bajo presi\u00f3n al igual que otros activos de riesgo (v\u00e9anse los movimientos de precios de las acciones de IA), pero su ca\u00edda se amplifica por un factor espec\u00edfico de las criptomonedas: los libros de \u00f3rdenes se han adelgazado tras las liquidaciones del 10 de octubre, lo que perjudic\u00f3 a muchos formadores de mercado en el sector\u201d, dijo Chung en un correo electr\u00f3nico.<\/p>\n<p>Hasta hace pocas semanas, hab\u00eda sido un a\u00f1o relativamente fuerte para el bitcoin. La criptomoneda cotizaba alrededor de US$ 69.000 antes de la reelecci\u00f3n de Trump en noviembre, antes de dispararse cerca de 83 % \u2014 entre episodios de volatilidad \u2014 hasta su m\u00e1ximo hist\u00f3rico por encima de US$ 126.000 a principios de octubre.<\/p>\n<p>El bitcoin <a href=\"https:\/\/www.cnn.com\/2024\/12\/04\/tech\/bitcoin-100k-trump-hnk-intl\">super\u00f3 los US$ 100.000<\/a> por primera vez a principios de diciembre de 2024, cuando los inversionistas apostaron por el optimismo de que el Gobierno de Trump impulsar\u00eda regulaciones favorables a las criptomonedas.<\/p>\n<p>Trump ha apoyado al sector de las criptomonedas y su gobierno ha flexibilizado la supervisi\u00f3n y defendido leyes procripto. La <a href=\"https:\/\/www.cnn.com\/2025\/07\/17\/politics\/genius-act-cryptocurrency-bill-house\">Ley GENIUS<\/a> fue aprobada por el Congreso y promulgada por Trump en julio, marcando una nueva era de regulaci\u00f3n para las <a href=\"https:\/\/www.cnn.com\/2025\/06\/05\/business\/stablecoins-crypto-genius-act\">stablecoins<\/a>, otro tipo de criptomoneda.<\/p>\n<p>Trump nombr\u00f3 a Paul Atkins, un regulador favorable a las criptomonedas, como presidente de la Comisi\u00f3n de Bolsa y Valores, y las criptomonedas siguen entrando en la corriente principal, con nuevos productos cotizados en bolsa que facilitan a los inversionistas la compra y venta de cripto.<\/p>\n<p>El bitcoin cotizaba alrededor de US$ 94.000 al comenzar el a\u00f1o. Ahora borr\u00f3 sus ganancias de los \u00faltimos 11 meses. En comparaci\u00f3n, el \u00edndice de referencia S&#038;P 500 ha subido un 13,4 % en lo que va del a\u00f1o. Los precios del oro han aumentado un 53 %.<\/p>\n<p>Aunque las acciones tecnol\u00f3gicas tambi\u00e9n han estado bajo presi\u00f3n, los inversionistas han aprovechado para comprar en la baja. Nvidia el viernes cay\u00f3 hasta un 3,36 % antes de terminar el d\u00eda con un alza del 1,77 %. El lunes, Nvidia baj\u00f3 hasta un 3,08 % antes de cerrar el d\u00eda con una ca\u00edda de solo un 1,88 %.<\/p>\n<p>Mientras tanto, el bitcoin sigue estancado alrededor de US$ 92.000 y a\u00fan no muestra una recuperaci\u00f3n significativa. Algunos analistas dicen que el mercado de criptomonedas est\u00e1 en un punto de inflexi\u00f3n, donde los catalizadores positivos de este a\u00f1o ya han sido incorporados en los precios, y con una incertidumbre creciente sobre las perspectivas.<\/p>\n<p>\u201cLa manera en que se comporte el mercado en los pr\u00f3ximos d\u00edas se\u00f1alar\u00e1 si esto se convierte en un ajuste m\u00e1s profundo o solo en una ca\u00edda aguda y temporal en un ciclo que por lo dem\u00e1s se mantiene intacto\u201d, dijo Rafique de OKX.<\/p>\n<p>Algunos inversionistas en criptomonedas siguen siendo optimistas. El bitcoin en abril cay\u00f3 hasta unos US$ 74.500 antes de dispararse por encima de los US$ 126.000 a principios de octubre.<\/p>\n<p>\u201cEn este momento, algunos inversionistas ven el estancamiento lateral y se asustan\u201d, dijo Ryan Rasmussen, jefe de investigaci\u00f3n en Bitwise Asset Management. \u201cPero en nuestra opini\u00f3n es la oportunidad perfecta para que los inversionistas aumenten sus posiciones existentes en bitcoin, y para que aquellos que han estado al margen entren al mercado\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El bitcoin y las acciones est\u00e1n en ca\u00edda y los inversionistas dicen que podr\u00eda haber m\u00e1s turbulencia en el futuro. Las acciones en EE.UU. bajaron el martes, extendiendo una reciente racha de ca\u00eddas.El Dow cay\u00f3 413 puntos, o 0,89 %. El S&#038;P 500 baj\u00f3 0,6 %. El Nasdaq Composite, de fuerte presencia tecnol\u00f3gica, retrocedi\u00f3 0,9 [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468471","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Por qu\u00e9 las criptomonedas se est\u00e1n desplomando y las acciones siguen cayendo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/18\/desplome-criptomonedas-acciones-mercado-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Por qu\u00e9 las criptomonedas se est\u00e1n desplomando y las acciones siguen cayendo - Noticias\" \/>\n<meta property=\"og:description\" content=\"El bitcoin y las acciones est\u00e1n en ca\u00edda y los inversionistas dicen que podr\u00eda haber m\u00e1s turbulencia en el futuro. Las acciones en EE.UU. bajaron el martes, extendiendo una reciente racha de ca\u00eddas.El Dow cay\u00f3 413 puntos, o 0,89 %. El S&#038;P 500 baj\u00f3 0,6 %. El Nasdaq Composite, de fuerte presencia tecnol\u00f3gica, retrocedi\u00f3 0,9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/18\/desplome-criptomonedas-acciones-mercado-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-18T18:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/18\/desplome-criptomonedas-acciones-mercado-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/18\/desplome-criptomonedas-acciones-mercado-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Por qu\u00e9 las criptomonedas se est\u00e1n desplomando y las acciones siguen cayendo\",\"datePublished\":\"2025-11-18T18:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/18\/desplome-criptomonedas-acciones-mercado-trax\/\"},\"wordCount\":1134,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/18\/desplome-criptomonedas-acciones-mercado-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/18\/desplome-criptomonedas-acciones-mercado-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/18\/desplome-criptomonedas-acciones-mercado-trax\/\",\"name\":\"Por qu\u00e9 las criptomonedas se est\u00e1n desplomando y las acciones siguen cayendo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-18T18:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/18\/desplome-criptomonedas-acciones-mercado-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/18\/desplome-criptomonedas-acciones-mercado-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/18\/desplome-criptomonedas-acciones-mercado-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Por qu\u00e9 las criptomonedas se est\u00e1n desplomando y las acciones siguen cayendo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Por qu\u00e9 las criptomonedas se est\u00e1n desplomando y las acciones siguen cayendo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/18\/desplome-criptomonedas-acciones-mercado-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Por qu\u00e9 las criptomonedas se est\u00e1n desplomando y las acciones siguen cayendo - Noticias","og_description":"El bitcoin y las acciones est\u00e1n en ca\u00edda y los inversionistas dicen que podr\u00eda haber m\u00e1s turbulencia en el futuro. Las acciones en EE.UU. bajaron el martes, extendiendo una reciente racha de ca\u00eddas.El Dow cay\u00f3 413 puntos, o 0,89 %. El S&#038;P 500 baj\u00f3 0,6 %. El Nasdaq Composite, de fuerte presencia tecnol\u00f3gica, retrocedi\u00f3 0,9 [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/18\/desplome-criptomonedas-acciones-mercado-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-18T18:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/18\/desplome-criptomonedas-acciones-mercado-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/18\/desplome-criptomonedas-acciones-mercado-trax\/"},"author":{"name":"","@id":""},"headline":"Por qu\u00e9 las criptomonedas se est\u00e1n desplomando y las acciones siguen cayendo","datePublished":"2025-11-18T18:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/18\/desplome-criptomonedas-acciones-mercado-trax\/"},"wordCount":1134,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/18\/desplome-criptomonedas-acciones-mercado-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/18\/desplome-criptomonedas-acciones-mercado-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/18\/desplome-criptomonedas-acciones-mercado-trax\/","name":"Por qu\u00e9 las criptomonedas se est\u00e1n desplomando y las acciones siguen cayendo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-18T18:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/18\/desplome-criptomonedas-acciones-mercado-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/18\/desplome-criptomonedas-acciones-mercado-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/18\/desplome-criptomonedas-acciones-mercado-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Por qu\u00e9 las criptomonedas se est\u00e1n desplomando y las acciones siguen cayendo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/18\/desplome-criptomonedas-acciones-mercado-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Por qu\u00e9 las criptomonedas se est\u00e1n desplomando y las acciones siguen cayendo","url":"http:\/\/noticiasya.com\/colorado\/2025\/11\/18\/desplome-criptomonedas-acciones-mercado-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2025\/11\/18\/desplome-criptomonedas-acciones-mercado-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-18T18:03:44Z","datePublished":"2025-11-18T18:03:44Z","dateModified":"2025-11-18T18:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Por qu\\u00e9 las criptomonedas se est\\u00e1n desplomando y las acciones siguen cayendo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2025\\\/11\\\/18\\\/desplome-criptomonedas-acciones-mercado-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2025\\\/11\\\/18\\\/desplome-criptomonedas-acciones-mercado-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-18T18:03:44Z\",\"datePublished\":\"2025-11-18T18:03:44Z\",\"dateModified\":\"2025-11-18T18:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1470896,"url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/05\/que-esta-pasando-bitcoin-trax\/","url_meta":{"origin":1468471,"position":0},"title":"No, pero en serio: \u00bfqu\u00e9 est\u00e1 pasando con el bitcoin?","author":"","date":"febrero 5, 2026","format":false,"excerpt":"El bitcoin est\u00e1 actuando de forma extra\u00f1a.La criptomoneda m\u00e1s famosa del mundo ha ca\u00eddo un 44 % desde su pico de octubre, al bajar el jueves de los US$ 70.000 por primera vez en 15 meses.Ese descenso en realidad no es inusual. Las criptomonedas son notoriamente vol\u00e1tiles y han atravesado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470900,"url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/05\/acciones-caen-empleo-ia-trax\/","url_meta":{"origin":1468471,"position":1},"title":"Caen las acciones ante datos d\u00e9biles del mercado laboral y preocupaciones por la IA","author":"","date":"febrero 5, 2026","format":false,"excerpt":"Las acciones en Estados Unidos bajaron este jueves, prolongando un reciente periodo de volatilidad, mientras Wall Street lidia con la persistente inquietud en torno a la inteligencia artificial y datos econ\u00f3micos mostraron que el mercado laboral se debilit\u00f3 en los \u00faltimos dos meses.El Dow cay\u00f3 637 puntos, o 1,29 %.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470821,"url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/03\/bitcoin-nivel-mas-bajo-desde-2024-trax\/","url_meta":{"origin":1468471,"position":2},"title":"Bitcoin cae a su nivel m\u00e1s bajo desde 2024 y las acciones se desploman ante temores por la IA y la incertidumbre geopol\u00edtica","author":"","date":"febrero 3, 2026","format":false,"excerpt":"Un ambiente de nerviosismo se apoder\u00f3 de los mercados este martes, cuando las acciones se desplomaron y el bitcoin cay\u00f3 a su nivel m\u00e1s bajo desde noviembre de 2024.El Dow Jones perdi\u00f3 360 puntos, un 0,73%. El S&P 500 cay\u00f3 1,25%, retrocediendo despu\u00e9s de acercarse brevemente a un r\u00e9cord hist\u00f3rico.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455950,"url":"https:\/\/noticiasya.com\/colorado\/2024\/11\/20\/bitcoin-rompiendo-records-invertir-trax\/","url_meta":{"origin":1468471,"position":3},"title":"El bitcoin rompe r\u00e9cords, \u00bfes buen momento para invertir?","author":"","date":"noviembre 20, 2024","format":false,"excerpt":"(CNN) -- En el primer trimestre de este a\u00f1o, el precio del bitcoin bati\u00f3 r\u00e9cords tras la aprobaci\u00f3n por parte de la Comisi\u00f3n del Mercado de Valores de los primeros fondos de bitcoin al contado cotizados en bolsa. La criptomoneda super\u00f3 los US$ 70.000 en marzo, seg\u00fan coinmarketcap.com.Despu\u00e9s, con los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460439,"url":"https:\/\/noticiasya.com\/colorado\/2025\/03\/26\/gamestop-numero-tiendas-invertira-bitcoin-trax\/","url_meta":{"origin":1468471,"position":4},"title":"GameStop cerrar\u00e1 un &#8216;n\u00famero significativo&#8217; de tiendas e invertir\u00e1 fuertemente en bitcoin","author":"","date":"marzo 26, 2025","format":false,"excerpt":"Tras el cierre de aproximadamente una cuarta parte de sus sucursales durante el \u00faltimo a\u00f1o, alrededor de 1.000 tiendas en todo el mundo, GameStop afirma que a\u00fan no ha terminado. A medida que la empresa en dificultades clausura locales, anuncia que invertir\u00e1 su dinero en criptomonedas.GameStop revel\u00f3 en una presentaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443509,"url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/11\/la-comision-de-bolsa-y-valores-da-luz-verde-a-los-fondos-cotizados-de-bitcoin\/","url_meta":{"origin":1468471,"position":5},"title":"La Comisi\u00f3n de Bolsa y Valores da luz verde a los fondos cotizados de bitcoin","author":"","date":"enero 11, 2024","format":false,"excerpt":"Nueva York (CNN) -- Despu\u00e9s de una salida en falso el martes, la Comisi\u00f3n de Bolsa y Valores (SEC, por sus siglas en ingl\u00e9s) dio su aprobaci\u00f3n este mi\u00e9rcoles para que algunas empresas de inversi\u00f3n ofrezcan fondos cotizados (ETF) en bolsa de \"bitcoin al contado\".Con esta medida tan esperada, se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1468471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1468471"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1468471\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1468471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1468471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1468471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}