{"id":1468502,"date":"2025-11-19T07:03:49","date_gmt":"2025-11-19T15:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/19\/trump-khashoggi-defiende-principe-heredero-saudi-trax\/"},"modified":"2025-11-19T07:03:49","modified_gmt":"2025-11-19T15:03:49","slug":"trump-khashoggi-defiende-principe-heredero-saudi-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2025\/11\/19\/trump-khashoggi-defiende-principe-heredero-saudi-trax\/","title":{"rendered":"Trump afirma que Khashoggi, el periodista asesinado, era &#171;extremadamente controvertido&#187; y defiende al pr\u00edncipe heredero saud\u00ed"},"content":{"rendered":"<p>El presidente Donald Trump rechaz\u00f3 airadamente el martes una pregunta sobre el asesinato de <a href=\"https:\/\/www.cnn.com\/world\/middleeast\/jamal-khashoggi-fast-facts\">Jamal Khashoggi<\/a> en 2018, al alegar que el periodista disidente saudita era \u201cextremadamente controvertido\u201d e insistir en que el tema solo se mencionaba durante su reuni\u00f3n con el pr\u00edncipe heredero saudita Mohammed bin Salman para avergonzar a su visita.<\/p>\n<p>\u201cEst\u00e1s mencionando a alguien que fue extremadamente pol\u00e9mico. A mucha gente no le ca\u00eda bien ese se\u00f1or del que hablas. Te guste o no, las cosas pasan\u201d, dijo Trump en el Despacho Oval mientras presid\u00eda una visita llena de pompa para el l\u00edder de facto saud\u00ed.<\/p>\n<p>Trump insisti\u00f3 en que el pr\u00edncipe Bin Salman \u2014a quien la CIA consider\u00f3 <a href=\"https:\/\/www.cnn.com\/2021\/02\/26\/politics\/biden-administration-khashoggi-report\/index.html\">el probable autor de la orden de asesinato\u2014<\/a> no estaba involucrado.<\/p>\n<p>\u201c\u00c9l no sab\u00eda nada al respecto, y podemos dejarlo as\u00ed\u201d, dijo Trump, volvi\u00e9ndose hacia el pr\u00edncipe heredero.<\/p>\n<p>El momento fue la mejor prueba hasta ahora de que el per\u00edodo de aislamiento diplom\u00e1tico que sufri\u00f3 el pr\u00edncipe bin Salman tras el asesinato de Khashoggi ha terminado. En su primera visita a la Casa Blanca en m\u00e1s de siete a\u00f1os, el pr\u00edncipe heredero fue recibido con <a href=\"https:\/\/www.cnn.com\/2025\/11\/16\/politics\/saudi-crown-prince-trump-white-house\">todos los honores de una visita de Estado<\/a>, la m\u00e1xima expresi\u00f3n de una recepci\u00f3n diplom\u00e1tica estadounidense.<\/p>\n<p>Su limusina Mercedes negra fue escoltada hasta el Jard\u00edn Sur por un equipo de pilotos de patrulla, mientras una banda militar anunciaba su llegada con trompetas. Un sobrevuelo de aviones de combate, incluidos los F-35 \u2014los mismos que Trump afirma que vender\u00e1 a Riad\u2014, reson\u00f3 en el cielo. M\u00e1s tarde, Trump ofrecer\u00e1 una cena de gala en el Sal\u00f3n Este.<\/p>\n<p>Sentado en el Despacho Oval, Trump colm\u00f3 de elogios al pr\u00edncipe heredero, incluyendo lo que calific\u00f3 como su \u201cincre\u00edble\u201d historial en materia de derechos humanos. El presidente destac\u00f3 nuevos acuerdos de inversi\u00f3n saud\u00ed en Estados Unidos y reafirm\u00f3 sus planes de vender aviones de fabricaci\u00f3n estadounidense, si bien el pr\u00edncipe heredero evit\u00f3 comprometerse con algunas de las prioridades de Trump.<\/p>\n<p>Y en lugar de simplemente pasar por alto el asesinato de 2018, que tuvo lugar en el consulado saud\u00ed en Estambul, Trump se ofendi\u00f3 porque se mencionara el tema durante lo que \u00e9l pretend\u00eda que fuera una ostentosa muestra de respeto.<\/p>\n<p>\u201cNo tiene por qu\u00e9 avergonzar a nuestro invitado con una pregunta como esa\u201d, le dijo Trump a la reportera, Mary Bruce, corresponsal de la Casa Blanca de ABC desde hace mucho tiempo, quien le pregunt\u00f3 sobre el asesinato.<\/p>\n<p>Sentado junto a Trump, el pr\u00edncipe heredero pareci\u00f3 impasible ante la discusi\u00f3n sobre su presunto papel en el asesinato, cometido por agentes saud\u00edes que posteriormente desmembraron al residente estadounidense y columnista de The Washington Post.<\/p>\n<p>\u201cEs doloroso y es un gran error\u201d, dijo el pr\u00edncipe Bin Salman, para luego defender la investigaci\u00f3n saud\u00ed.<\/p>\n<p>\u201cEn cuanto al periodista, es realmente doloroso escuchar que alguien haya perdido la vida sin un prop\u00f3sito real o de manera no legal, y ha sido doloroso para nosotros en Arabia Saudita\u201d, dijo.<\/p>\n<p>El pr\u00edncipe heredero a\u00f1adi\u00f3 que Arabia Saud\u00ed \u201ctom\u00f3 todas las medidas correctas en la investigaci\u00f3n\u201d y dijo que estaban haciendo \u201ctodo lo posible para que esto no vuelva a ocurrir\u201d.<\/p>\n<p>Hanan Elatr Khashoggi, viuda de Jamal Khashoggi, respondi\u00f3 a la afirmaci\u00f3n de Trump de que su difunto esposo era \u201cextremadamente pol\u00e9mico\u201d, diciendo que esa no era raz\u00f3n suficiente para que lo hubieran asesinado.<\/p>\n<p>\u201cEsto no justifica su asesinato. Jamal era un hombre bueno, transparente y valiente\u201d, declar\u00f3 a CNN, y a\u00f1adi\u00f3 que \u201cmuchos quiz\u00e1s no compart\u00edan sus opiniones ni su defensa de la libertad de prensa. El pr\u00edncipe heredero expres\u00f3 sus disculpas, por lo que deber\u00eda reunirse conmigo, pedirme perd\u00f3n e indemnizarme por el asesinato de mi esposo\u201d.<\/p>\n<p>En <a href=\"https:\/\/www.washingtonpost.com\/opinions\/2025\/11\/18\/jamal-khashoggi-trump-mohammed-bin-salman-saudi-arabia\/\">un editorial<\/a>, The Post escribi\u00f3 que los comentarios de Trump \u201cdeshonran el legado de Khashoggi, contradicen los hechos y no son dignos del cargo de presidente\u201d.<\/p>\n<p>La evaluaci\u00f3n de la CIA publicada en 2021 concluy\u00f3 que el pr\u00edncipe aprob\u00f3 el asesinato del columnista del Washington Post, aunque \u00e9l ha negado durante mucho tiempo cualquier implicaci\u00f3n.<\/p>\n<p>\u201cBasamos esta evaluaci\u00f3n en el control del pr\u00edncipe heredero sobre la toma de decisiones en el Reino, la participaci\u00f3n directa de un asesor clave y miembros del equipo de protecci\u00f3n de Muhammad bin Salman en la operaci\u00f3n, y el apoyo del pr\u00edncipe heredero al uso de medidas violentas para silenciar a los disidentes en el extranjero, incluido Khashoggi\u201d, se\u00f1ala el informe.<\/p>\n<p>Durante su primer mandato, Trump rest\u00f3 importancia en gran medida al posible papel del pr\u00edncipe Bin Salman en el asesinato de Khashoggi, aunque se describi\u00f3 a s\u00ed mismo como \u201cextremadamente enojado y muy descontento\u201d por el crimen.<\/p>\n<p>Su sucesor, el presidente Joe Biden, prometi\u00f3 durante su campa\u00f1a convertir a Arabia Saudita en un \u201cparia\u201d. Pero incluso Biden lleg\u00f3 a reconocer que el reino y su pr\u00edncipe heredero eran demasiado poderosos e influyentes como para ignorarlos por completo. Viaj\u00f3 al pa\u00eds en 2022 en un intento \u2014en gran medida infructuoso\u2014, de convencer a Arabia Saudita de que aumentara su producci\u00f3n petrolera.<\/p>\n<p>Durante su segundo mandato, Trump ha buscado activamente fortalecer su relaci\u00f3n con el reino, y para eso ha visitado Riad en mayo para discutir nuevas inversiones y acuerdos de seguridad. Su inter\u00e9s en el reino ha generado escrutinio debido a los intereses financieros de su familia en el pa\u00eds, aunque el martes desestim\u00f3 esas preocupaciones. \u201cNo tengo nada que ver con los negocios familiares. Me he desvinculado\u201d, declar\u00f3 el presidente.<\/p>\n<p>La esperanza de Trump es que Arabia Saudita finalmente se una a los Acuerdos de Abraham, su logro diplom\u00e1tico m\u00e1s emblem\u00e1tico, que normalizar\u00eda sus relaciones con Israel.<\/p>\n<p>Pero el pr\u00edncipe bBin Salman dej\u00f3 claro que eso no ocurrir\u00eda el martes, ni en ning\u00fan otro momento antes de que exista una v\u00eda clara para un Estado palestino independiente.<\/p>\n<p>\u201cQueremos formar parte de los Acuerdos de Abraham\u201d, dijo el pr\u00edncipe heredero. \u201cPero tambi\u00e9n queremos asegurarnos de garantizar una ruta clara hacia una soluci\u00f3n de dos Estados\u201d.<\/p>\n<p>El pr\u00edncipe Bin Salman tambi\u00e9n se mostr\u00f3 indeciso respecto al financiamiento para la reconstrucci\u00f3n de Gaza. Dijo que estaba \u201cdiscutiendo\u201d el asunto antes de que Trump interviniera para insistir en que \u201cser\u00e1 mucho\u201d.<\/p>\n<p>El pr\u00edncipe heredero s\u00ed afirm\u00f3 que aumentar\u00eda el compromiso de inversi\u00f3n de Arabia Saud\u00ed en Estados Unidos de los US$ 600.000 millones anunciados en mayo a un bill\u00f3n de d\u00f3lares, una cifra enorme que representa casi la totalidad de la producci\u00f3n econ\u00f3mica anual del reino.<\/p>\n<p>Mientras tanto, Trump parec\u00eda ansioso por brindar nueva ayuda estadounidense a Arabia Saudita, incluyendo un pacto de defensa y un acuerdo que ayudar\u00eda al reino a desarrollar un programa nuclear civil.<\/p>\n<p>Sin embargo, parec\u00eda tener como principal objetivo honrar al pr\u00edncipe heredero, quien ha consolidado el poder y ahora es el gobernante cotidiano del reino.<\/p>\n<p>\u201cSolo quiero darles las gracias\u201d, dijo Trump. \u201cHemos sido muy buenos amigos durante mucho tiempo. Siempre hemos estado del mismo lado en todos los temas\u201d.<\/p>\n<p><em>Esta noticia ha sido actualizada con informaci\u00f3n adicional.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Donald Trump rechaz\u00f3 airadamente el martes una pregunta sobre el asesinato de Jamal Khashoggi en 2018, al alegar que el periodista disidente saudita era \u201cextremadamente controvertido\u201d e insistir en que el tema solo se mencionaba durante su reuni\u00f3n con el pr\u00edncipe heredero saudita Mohammed bin Salman para avergonzar a su visita. \u201cEst\u00e1s mencionando [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468502","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump afirma que Khashoggi, el periodista asesinado, era &quot;extremadamente controvertido&quot; y defiende al pr\u00edncipe heredero saud\u00ed - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/19\/trump-khashoggi-defiende-principe-heredero-saudi-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump afirma que Khashoggi, el periodista asesinado, era &quot;extremadamente controvertido&quot; y defiende al pr\u00edncipe heredero saud\u00ed - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente Donald Trump rechaz\u00f3 airadamente el martes una pregunta sobre el asesinato de Jamal Khashoggi en 2018, al alegar que el periodista disidente saudita era \u201cextremadamente controvertido\u201d e insistir en que el tema solo se mencionaba durante su reuni\u00f3n con el pr\u00edncipe heredero saudita Mohammed bin Salman para avergonzar a su visita. \u201cEst\u00e1s mencionando [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/19\/trump-khashoggi-defiende-principe-heredero-saudi-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-19T15:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/19\/trump-khashoggi-defiende-principe-heredero-saudi-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/19\/trump-khashoggi-defiende-principe-heredero-saudi-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump afirma que Khashoggi, el periodista asesinado, era &#171;extremadamente controvertido&#187; y defiende al pr\u00edncipe heredero saud\u00ed\",\"datePublished\":\"2025-11-19T15:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/19\/trump-khashoggi-defiende-principe-heredero-saudi-trax\/\"},\"wordCount\":1264,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/19\/trump-khashoggi-defiende-principe-heredero-saudi-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/19\/trump-khashoggi-defiende-principe-heredero-saudi-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/19\/trump-khashoggi-defiende-principe-heredero-saudi-trax\/\",\"name\":\"Trump afirma que Khashoggi, el periodista asesinado, era \\\"extremadamente controvertido\\\" y defiende al pr\u00edncipe heredero saud\u00ed - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-19T15:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/19\/trump-khashoggi-defiende-principe-heredero-saudi-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/19\/trump-khashoggi-defiende-principe-heredero-saudi-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/19\/trump-khashoggi-defiende-principe-heredero-saudi-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump afirma que Khashoggi, el periodista asesinado, era &#171;extremadamente controvertido&#187; y defiende al pr\u00edncipe heredero saud\u00ed\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump afirma que Khashoggi, el periodista asesinado, era \"extremadamente controvertido\" y defiende al pr\u00edncipe heredero saud\u00ed - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/19\/trump-khashoggi-defiende-principe-heredero-saudi-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trump afirma que Khashoggi, el periodista asesinado, era \"extremadamente controvertido\" y defiende al pr\u00edncipe heredero saud\u00ed - Noticias","og_description":"El presidente Donald Trump rechaz\u00f3 airadamente el martes una pregunta sobre el asesinato de Jamal Khashoggi en 2018, al alegar que el periodista disidente saudita era \u201cextremadamente controvertido\u201d e insistir en que el tema solo se mencionaba durante su reuni\u00f3n con el pr\u00edncipe heredero saudita Mohammed bin Salman para avergonzar a su visita. \u201cEst\u00e1s mencionando [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/19\/trump-khashoggi-defiende-principe-heredero-saudi-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-19T15:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/19\/trump-khashoggi-defiende-principe-heredero-saudi-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/19\/trump-khashoggi-defiende-principe-heredero-saudi-trax\/"},"author":{"name":"","@id":""},"headline":"Trump afirma que Khashoggi, el periodista asesinado, era &#171;extremadamente controvertido&#187; y defiende al pr\u00edncipe heredero saud\u00ed","datePublished":"2025-11-19T15:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/19\/trump-khashoggi-defiende-principe-heredero-saudi-trax\/"},"wordCount":1264,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/19\/trump-khashoggi-defiende-principe-heredero-saudi-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/19\/trump-khashoggi-defiende-principe-heredero-saudi-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/19\/trump-khashoggi-defiende-principe-heredero-saudi-trax\/","name":"Trump afirma que Khashoggi, el periodista asesinado, era \"extremadamente controvertido\" y defiende al pr\u00edncipe heredero saud\u00ed - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-19T15:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/19\/trump-khashoggi-defiende-principe-heredero-saudi-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/19\/trump-khashoggi-defiende-principe-heredero-saudi-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/19\/trump-khashoggi-defiende-principe-heredero-saudi-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump afirma que Khashoggi, el periodista asesinado, era &#171;extremadamente controvertido&#187; y defiende al pr\u00edncipe heredero saud\u00ed"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/19\/trump-khashoggi-defiende-principe-heredero-saudi-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump afirma que Khashoggi, el periodista asesinado, era &#171;extremadamente controvertido&#187; y defiende al pr\u00edncipe heredero saud\u00ed","url":"http:\/\/noticiasya.com\/colorado\/2025\/11\/19\/trump-khashoggi-defiende-principe-heredero-saudi-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2025\/11\/19\/trump-khashoggi-defiende-principe-heredero-saudi-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-19T15:03:49Z","datePublished":"2025-11-19T15:03:49Z","dateModified":"2025-11-19T15:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump afirma que Khashoggi, el periodista asesinado, era &#171;extremadamente controvertido&#187; y defiende al pr\\u00edncipe heredero saud\\u00ed\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2025\\\/11\\\/19\\\/trump-khashoggi-defiende-principe-heredero-saudi-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2025\\\/11\\\/19\\\/trump-khashoggi-defiende-principe-heredero-saudi-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-19T15:03:49Z\",\"datePublished\":\"2025-11-19T15:03:49Z\",\"dateModified\":\"2025-11-19T15:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1405946,"url":"https:\/\/noticiasya.com\/colorado\/2022\/06\/14\/joe-biden-visitara-arabia-saudita-que-implica-este-viaje\/","url_meta":{"origin":1468502,"position":0},"title":"Joe Biden visitar\u00e1 Arabia Saudita: \u00bfQu\u00e9 implica este viaje?","author":"agomez","date":"junio 14, 2022","format":false,"excerpt":"Aunque el motivo principal de la visita sea abordar temas sobre los derechos humanos, funcionarios destacan otros objetivos.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/colorado\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468501,"url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/19\/analisis-arrebato-trump-prensa-impacto-principe-saudi-trax\/","url_meta":{"origin":1468502,"position":1},"title":"El arrebato de Trump contra la prensa tiene un impacto distinto con el pr\u00edncipe saudita a su lado","author":"agomez","date":"noviembre 19, 2025","format":false,"excerpt":"El presidente Trump demuestra con frecuencia su desd\u00e9n por los periodistas. Expresa su admiraci\u00f3n por los autoritarios casi con la misma frecuencia.El martes qued\u00f3 demostrado cu\u00e1n entrelazados est\u00e1n realmente esos dos instintos.Trump se opuso repetidamente a las preguntas de la prensa durante una sesi\u00f3n fotogr\u00e1fica en la Oficina Oval con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458852,"url":"https:\/\/noticiasya.com\/colorado\/2025\/02\/17\/analisis-arabia-saudita-conversaciones-estados-unidos-rusia-trax\/","url_meta":{"origin":1468502,"position":2},"title":"AN\u00c1LISIS | \u00bfPor qu\u00e9 aloja Arabia Saudita las conversaciones entre Estados Unidos y Rusia?","author":"","date":"febrero 17, 2025","format":false,"excerpt":"Arabia Saudita alojar\u00e1 este martes a altos funcionarios estadounidenses y rusos en una reuni\u00f3n de acercamiento de alto nivel, un papel que subraya las aspiraciones del reino de convertirse en un actor global capaz de mediar con \u00e9xito en conflictos internacionales. Otro objetivo probable: aumentar la influencia de Riad en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458847,"url":"https:\/\/noticiasya.com\/colorado\/2025\/02\/17\/trump-lazos-principe-saudi-ucrania-trax\/","url_meta":{"origin":1468502,"position":3},"title":"Trump se apoya en sus lazos con el pr\u00edncipe saud\u00ed mientras busca un acuerdo sobre Ucrania","author":"","date":"febrero 17, 2025","format":false,"excerpt":"El presidente Donald Trump, en su intento de poner fin a la guerra en Ucrania, se apoya en un viejo aliado: el poderoso pr\u00edncipe heredero de Arabia Saudita, Mohammed bin Salman, cuyo \u00e9xito en la mediaci\u00f3n para poner fin al conflicto podr\u00eda profundizar sus ya estrechos lazos con el nuevo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470260,"url":"https:\/\/noticiasya.com\/colorado\/2026\/01\/20\/momentos-despacho-oval-primer-ano-trump-2-0-trax\/","url_meta":{"origin":1468502,"position":4},"title":"Los dram\u00e1ticos e inusuales momentos del primer a\u00f1o de Trump 2.0 en la Oficina Oval","author":"","date":"enero 20, 2026","format":false,"excerpt":"Desde una explosiva reuni\u00f3n con el l\u00edder de una Ucrania devastada por la guerra hasta un encuentro inesperadamente amistoso con un alcalde electo socialista democr\u00e1tico, la Oficina Oval ha sido sede de algunos de los momentos m\u00e1s dram\u00e1ticos del primer a\u00f1o de regreso al cargo del presidente de EE.UU., Donald\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458702,"url":"https:\/\/noticiasya.com\/colorado\/2025\/02\/13\/trump-arabia-saudita-cumbre-putin-trax\/","url_meta":{"origin":1468502,"position":5},"title":"Por qu\u00e9 Trump piensa en Arabia Saudita como anfitriona de su cumbre con Putin","author":"","date":"febrero 13, 2025","format":false,"excerpt":"El anuncio del presidente Donald Trump el mi\u00e9rcoles de que Arabia Saudita probablemente ser\u00e1 la anfitriona de su cumbre de paz con Vladimir Putin puede haber parecido una elecci\u00f3n inusual.Pero para Trump y sus asesores, la elecci\u00f3n del reino del Golfo tiene todo el sentido.En el pasado, presidentes estadounidenses han\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1468502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1468502"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1468502\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1468502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1468502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1468502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}