{"id":1468506,"date":"2025-11-19T10:03:39","date_gmt":"2025-11-19T18:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/19\/robo-louvre-joyas-corona-francia-sospechosos-trax\/"},"modified":"2025-11-19T10:03:39","modified_gmt":"2025-11-19T18:03:39","slug":"robo-louvre-joyas-corona-francia-sospechosos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2025\/11\/19\/robo-louvre-joyas-corona-francia-sospechosos-trax\/","title":{"rendered":"Los ladrones irrumpieron en el Louvre hace un mes. As\u00ed fue como la Polic\u00eda logr\u00f3 acercarse a los sospechosos"},"content":{"rendered":"<p>Era el atardecer del s\u00e1bado 25 de octubre, el cuarto d\u00eda en que el equipo de vigilancia segu\u00eda a un sospechoso argelino, de 34 a\u00f1os, en Seine-Saint-Denis, a las afueras de Par\u00eds.<\/p>\n<p>El trabajo hab\u00eda sido tenso y tedioso. Una zona diversa, Seine-Saint-Denis alberga a personas de m\u00e1s de 130 nacionalidades, muchas de ellas de origen norteafricano. Para el equipo de vigilancia \u2014una unidad de la Prefectura de Polic\u00eda de Par\u00eds conocida como la Brigada de B\u00fasqueda e Intervenci\u00f3n, o BRI\u2014 mezclarse entre los residentes de barrios muy cohesionados era un reto.<\/p>\n<p>Ahora, el sospechoso iba por la autopista. El equipo no sab\u00eda hacia d\u00f3nde se dirig\u00eda, pero por su ruta parec\u00eda que iba al aeropuerto Charles de Gaulle.<\/p>\n<p>Tambi\u00e9n llevaba una bolsa. Dentro podr\u00eda tener perfectamente las joyas de la Corona de Francia.<\/p>\n<p>Seis d\u00edas antes, un robo en el Museo del Louvre hab\u00eda sorprendido al mundo. Cuatro ladrones que se mov\u00edan con precisi\u00f3n y rapidez irrumpieron en el museo m\u00e1s visitado del mundo y se llevaron una colecci\u00f3n de joyas con un valor estimado de m\u00e1s de US$ 100 millones.<\/p>\n<p>Pero esto era m\u00e1s que dinero. Era un golpe al coraz\u00f3n de la historia francesa. Entre los objetos robados hab\u00eda un collar de esmeraldas con m\u00e1s de 1.000 diamantes que Napole\u00f3n regal\u00f3 a su segunda esposa y un juego de joyas de diamantes y zafiros que usaron la reina Mar\u00eda Amelia y la reina Hortensia.<\/p>\n<p>Siguiendo al sospechoso en la autopista, la BRI fue haciendo relevos, comunic\u00e1ndose por radio para coordinar la cuidadosa coreograf\u00eda de cambiar de veh\u00edculo de seguimiento, de modo que ning\u00fan veh\u00edculo estuviera detr\u00e1s del argelino por demasiado tiempo.<\/p>\n<p>El jefe del equipo pregunt\u00f3 a la cadena de mando: si el objetivo entra al aeropuerto, \u00bflo detenemos?<\/p>\n<p>Mant\u00e9nganse con \u00e9l, fue la instrucci\u00f3n de regreso. D\u00e9jenlo llegar tan lejos como puedan.<\/p>\n<p>El equipo de vigilancia se dispers\u00f3. En poco tiempo, el sospechoso ten\u00eda un pasaje, pas\u00f3 por seguridad y se dirigi\u00f3 a una puerta de embarque. Estaba reservado en el siguiente vuelo a Argel.<\/p>\n<p>A las 8 p.m., sin que nadie pareciera acercarse a \u00e9l, lleg\u00f3 la orden: det\u00e9nganlo.<\/p>\n<p>Tras su arresto, un registro de sus bolsas no revel\u00f3 ninguna de las joyas.<\/p>\n<p>Tendemos a romantizar a las personas que cometen estos delitos. Imaginamos a los culpables como hombres apuestos, elegantes y sofisticados que descienden por una claraboya con cuellos de tortuga negros, sorteando una telara\u00f1a de sensores de movimiento l\u00e1ser. Las obras de arte y joyas invaluables que roban terminan en la colecci\u00f3n de un supervillano en un castillo remoto en una monta\u00f1a. Quiz\u00e1 las obras de Rembrandt, Vermeer y Degas robadas del Museo Isabella Stewart Gardner, de Boston, en 1990, cuelguen all\u00ed, mientras sus marcos vac\u00edos persisten en las paredes del Gardner, esperando que regresen.<\/p>\n<p>Pero eso es cosa de Hollywood. En este caso, los fiscales de Par\u00eds han descrito a los cuatro sospechosos actualmente detenidos \u2014tres de los cuales se cree que participaron directamente en el robo\u2014 como delincuentes locales de poca monta sin conexi\u00f3n con el crimen organizado. Ninguno ha sido identificado p\u00fablicamente por las autoridades.<\/p>\n<p>La cacer\u00eda de los sospechosos del Louvre ha dependido de investigadores como los de la BRI, con quienes pas\u00e9 tiempo despu\u00e9s de los atentados terroristas de Par\u00eds de 2015, cuando era subcomisionado de Inteligencia del Departamento de Polic\u00eda de Nueva York. Me impresion\u00f3 su dominio para pasar desapercibidos mientras segu\u00edan a sospechosos para atraparlos en el acto, utilizando integrantes de etnias diversas que rastreaban a sus objetivos por cualquier medio que mejor se ajustara a la situaci\u00f3n: en autos discretos, furgonetas, taxis, <em>scooters <\/em>o motocicletas, o a pie por la calle o en el metro de Par\u00eds.<\/p>\n<p>La investigaci\u00f3n tambi\u00e9n ha involucrado a la brigada de robos de la Polic\u00eda de Par\u00eds, la Brigade de R\u00e9pression du Banditisme, o BRB. Estos detectives investigan a bandas como la pandilla Pink Panther, sospechosa de robar diamantes por todo el continente y venderlos en un mercado negro en Amberes, B\u00e9lgica. Y han resuelto muchos casos de alto perfil, incluido el robo a mano armada de 2016 contra Kim Kardashian en Par\u00eds, en el que los ladrones escaparon con casi US$ 10 millones en efectivo y joyas. El trabajo de la BRB en ese caso llev\u00f3 a la condena de ocho personas.<\/p>\n<p>Con una amplia red de informantes en el mundo del hampa parisino, los detectives de la BRB pod\u00edan recurrir a sus contactos para obtener teor\u00edas inmediatas (y quiz\u00e1 uno o dos nombres) en el caso del Louvre. Pero todos pod\u00edan terminar en callejones sin salida.<\/p>\n<p>En cambio, la BRB se centr\u00f3 en la investigaci\u00f3n forense. Una huella dactilar, un cabello, un rastro de ADN: cualquiera de estos pod\u00eda llevar potencialmente a un nombre real a trav\u00e9s de la base nacional de datos de ADN de Francia, que contiene muestras tomadas de delincuentes condenados y sospechosos.<\/p>\n<p>El robo estaba dise\u00f1ado para ser r\u00e1pido: entrar y salir.<\/p>\n<p>Hace un mes, el domingo 19 de octubre, cuatro ladrones condujeron un cami\u00f3n montacargas, robado d\u00edas antes, hasta debajo de las ventanas de la Galer\u00eda Apolo del Louvre, donde estaban expuestas las joyas. Para que su presencia pareciera leg\u00edtima, colocaron conos naranjas alrededor del cami\u00f3n y llevaban chalecos de alta visibilidad.<\/p>\n<p>Dos se quedaron en el suelo, mientras que los otros dos subieron en una canastilla elevada por la torre extensible del cami\u00f3n. Con amoladoras angulares, forzaron una ventana y entraron a la galer\u00eda. All\u00ed, rompieron dos vitrinas de alta seguridad y se llevaron nueve piezas, blandiendo las amoladoras cada vez que los guardias se acercaban. En cuatro minutos, la pareja ya estaba de vuelta por la ventana, descendiendo en la plataforma.<\/p>\n<p>Luego, ocurri\u00f3 el percance: la corona imperial de la emperatriz Eugenia se resbal\u00f3 y cay\u00f3 casi dos pisos con sus 1.354 diamantes y 56 esmeraldas verde intenso. Cay\u00f3 entre dos vallas, en un foso seco, seg\u00fan una fuente que dijo a CNN que un video grabado por un testigo, donde se ve a dos hombres inclinados mirando hacia abajo desde la plataforma, captur\u00f3 el momento en que la corona cay\u00f3.<\/p>\n<p>Tendr\u00edan que irse sin la corona de las joyas de la Corona.<\/p>\n<p>Testigos dijeron que los ladrones intentaron incendiar el cami\u00f3n montacargas con un soplete manual y gasolina, pero un agente de seguridad del museo los interrumpi\u00f3.<\/p>\n<p>Pronto se quedaron sin tiempo. Subieron a <em>scooters <\/em>Yamaha TMAX y huyeron.<\/p>\n<p>Todo el asalto tom\u00f3 solo siete minutos, dijo el ministro del Interior franc\u00e9s, Laurent Nu\u00f1ez.<\/p>\n<p>El primer d\u00eda de la investigaci\u00f3n, el equipo forense de la Polic\u00eda de Par\u00eds trabaj\u00f3 de forma lenta y meticulosa: fotografiaron la escena, tomaron muestras de ADN, buscaron huellas dactilares y aseguraron las pistas que hab\u00edan quedado: una amoladora, un casco blanco, un soplete, los conos naranjas.<\/p>\n<p>Mientras tanto, la BRB trabajaba con el centro de mando de la Polic\u00eda, que controla miles de c\u00e1maras y lectores de matr\u00edculas en todo Par\u00eds. Los investigadores encontraron im\u00e1genes de los sospechosos en <em>scooters <\/em>escapando por la ribera del Sena a velocidades de unos 160 km\/h, antes de abandonar los <em>scooters <\/em>y cambiar a autos en direcci\u00f3n al este.<\/p>\n<p>Uno de esos <em>scooters <\/em>fue recuperado y procesado para obtener ADN y huellas. La Polic\u00eda iba a aprovechar cualquier oportunidad para recolectar evidencia forense.<\/p>\n<p>Sus esfuerzos dieron resultado. El ADN recuperado del <em>scooter <\/em>de huida coincid\u00eda con el del argelino, de 34 a\u00f1os, y ya estaba en la base de datos criminal, lo que llev\u00f3 a su arresto en el aeropuerto la noche del 25 de octubre.<\/p>\n<p>Y, seg\u00fan los fiscales, el ADN de la amoladora y de la ventana del Louvre coincid\u00eda con el de otro individuo: un taxista, de 39 a\u00f1os, sin licencia, conocido previamente por la Polic\u00eda por hurto agravado y que estaba bajo supervisi\u00f3n judicial por embestir un cajero autom\u00e1tico con un auto para obtener el dinero.<\/p>\n<p>Aun as\u00ed, los antecedentes de ambos hombres parec\u00edan quedar cortos frente al audaz robo del Louvre, que en un principio parec\u00eda obra de profesionales experimentados.<\/p>\n<p>Pero los investigadores estaban seguros de que ten\u00edan a los sospechosos correctos. La evidencia de ADN les daba un grado s\u00f3lido de certeza.<\/p>\n<p>Poco despu\u00e9s de detener al argelino en el aeropuerto, las autoridades se enfrentaron a otra decisi\u00f3n. Una vez que el taxista \u2014ya bajo vigilancia de la BRI\u2014 supiera que su presunto c\u00f3mplice estaba detenido, tambi\u00e9n podr\u00eda intentar huir.<\/p>\n<p>La orden que recibi\u00f3 el equipo fue arrestarlo de inmediato.<\/p>\n<p>Cuatro d\u00edas despu\u00e9s, el 29 de octubre, los fiscales franceses afirmaron que los dos hombres hab\u00edan hecho admisiones \u201cparciales\u201d relacionadas con el robo. Fuentes dijeron a CNN que esas admisiones surgieron cuando los sospechosos intentaban explicar por qu\u00e9 su ADN habr\u00eda sido encontrado en la escena, en las herramientas o en un veh\u00edculo de huida.<\/p>\n<p>A partir de esas declaraciones \u2014junto con informaci\u00f3n obtenida de los tel\u00e9fonos celulares de ambos sospechosos y otras observaciones hechas durante la operaci\u00f3n de vigilancia\u2014, los investigadores identificaron a otras personas relevantes para la investigaci\u00f3n.<\/p>\n<p>Poco despu\u00e9s, los detectives de la BRB comenzaron a extender su red. Arrestaron a varias personas m\u00e1s en Par\u00eds y en Seine-Saint-Denis, aunque todas, excepto dos, fueron liberadas sin cargos en cuesti\u00f3n de d\u00edas.<\/p>\n<p>Uno de esos dos detenidos, un hombre, de 37 a\u00f1os, se cree que es el tercer integrante del equipo del robo al Louvre. La cuarta persona es una mujer, de 38 a\u00f1os, quien, seg\u00fan se indica, mantiene una relaci\u00f3n con uno de los sospechosos. No est\u00e1 claro si los investigadores creen que particip\u00f3 en la planificaci\u00f3n o que supuestamente ayud\u00f3 a los sospechosos despu\u00e9s del hecho. Ambos han negado cualquier implicaci\u00f3n, seg\u00fan los fiscales.<\/p>\n<p>Los cuatro sospechosos han sido puestos bajo investigaci\u00f3n formal por robo organizado y asociaci\u00f3n delictuosa.<\/p>\n<p>En conjunto, los arrestos significan que la Polic\u00eda podr\u00eda tener bajo custodia a tres de los cuatro presuntos ladrones. Aun as\u00ed, las joyas no han aparecido.<\/p>\n<p>Ha habido casos con mejores desenlaces tras grandes robos. Est\u00e1, por ejemplo, el caso de 1964 que se convirti\u00f3 en prototipo de gran parte de la ficci\u00f3n sobre robos de arte que vino despu\u00e9s.<\/p>\n<p>Ese a\u00f1o, Jack \u201cMurph the Surf\u201d Murphy \u2014violinista autoproclamado, surfista radicado en Miami y ladr\u00f3n de joyas profesional\u2014 lleg\u00f3 a Nueva York con un plan audaz para robar la Estrella de la India, el zafiro estrella m\u00e1s grande del mundo, y media docena de otros diamantes y rub\u00edes guardados en vitrinas del Museo Americano de Historia Natural.<\/p>\n<p>Con un vigilante apostado afuera, Murphy y un c\u00f3mplice descendieron con una cuerda desde arriba, recogieron las gemas y desaparecieron en la noche, sin ser detectados por alarmas ni personal de seguridad. En ese sentido, fue \u201ccomo en las pel\u00edculas\u201d.<\/p>\n<p>Pero en dos d\u00edas, la Polic\u00eda de Nueva York arrest\u00f3 al primer sospechoso y, poco despu\u00e9s, a los otros dos, incluido Murphy. Meses m\u00e1s tarde, Murphy lleg\u00f3 a un acuerdo con la Fiscal\u00eda: si devolv\u00edan las joyas, la condena ser\u00eda corta. Y as\u00ed fue: Murphy y su equipo pasaron solo tres a\u00f1os en la prisi\u00f3n de Rikers Island, en Nueva York, despu\u00e9s de que las gemas fueran recuperadas de un casillero en una terminal de autobuses en Miami. Hoy, la Estrella de la  India vuelve a exhibirse en el museo.<\/p>\n<p>\u00bfPodr\u00eda ocurrir algo similar en el caso del Louvre? \u00bfSer\u00e1n devueltas las joyas, o las tiaras y collares ser\u00e1n rescatados por un tercero? \u00bfO ya se fundi\u00f3 el oro y los diamantes, rub\u00edes y zafiros fueron arrancados de sus monturas y vendidos por separado?<\/p>\n<p>Que eso haya ocurrido antes de los r\u00e1pidos arrestos, resultar\u00eda poco probable. Habr\u00eda implicado tener un joyero lo suficientemente h\u00e1bil para hacer el trabajo y lo bastante inescrupuloso como para querer hacerlo. Tambi\u00e9n podr\u00eda haber requerido un comprador ya asegurado. Incluso as\u00ed, con el robo en los titulares y la Polic\u00eda tras la pista, las joyas \u2014en cualquier forma\u2014 probablemente habr\u00edan sido demasiado peligrosas de manejar, incluso en el mercado negro.<\/p>\n<p>Eso puede significar que a\u00fan hay esperanza para las joyas de la Corona de Francia. La historia demuestra que, con el acuerdo adecuado, pueden volver a aparecer.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Era el atardecer del s\u00e1bado 25 de octubre, el cuarto d\u00eda en que el equipo de vigilancia segu\u00eda a un sospechoso argelino, de 34 a\u00f1os, en Seine-Saint-Denis, a las afueras de Par\u00eds. El trabajo hab\u00eda sido tenso y tedioso. Una zona diversa, Seine-Saint-Denis alberga a personas de m\u00e1s de 130 nacionalidades, muchas de ellas de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468506","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los ladrones irrumpieron en el Louvre hace un mes. As\u00ed fue como la Polic\u00eda logr\u00f3 acercarse a los sospechosos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/19\/robo-louvre-joyas-corona-francia-sospechosos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los ladrones irrumpieron en el Louvre hace un mes. As\u00ed fue como la Polic\u00eda logr\u00f3 acercarse a los sospechosos - Noticias\" \/>\n<meta property=\"og:description\" content=\"Era el atardecer del s\u00e1bado 25 de octubre, el cuarto d\u00eda en que el equipo de vigilancia segu\u00eda a un sospechoso argelino, de 34 a\u00f1os, en Seine-Saint-Denis, a las afueras de Par\u00eds. El trabajo hab\u00eda sido tenso y tedioso. Una zona diversa, Seine-Saint-Denis alberga a personas de m\u00e1s de 130 nacionalidades, muchas de ellas de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/19\/robo-louvre-joyas-corona-francia-sospechosos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-19T18:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/19\/robo-louvre-joyas-corona-francia-sospechosos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/19\/robo-louvre-joyas-corona-francia-sospechosos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Los ladrones irrumpieron en el Louvre hace un mes. As\u00ed fue como la Polic\u00eda logr\u00f3 acercarse a los sospechosos\",\"datePublished\":\"2025-11-19T18:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/19\/robo-louvre-joyas-corona-francia-sospechosos-trax\/\"},\"wordCount\":2185,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/19\/robo-louvre-joyas-corona-francia-sospechosos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/19\/robo-louvre-joyas-corona-francia-sospechosos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/19\/robo-louvre-joyas-corona-francia-sospechosos-trax\/\",\"name\":\"Los ladrones irrumpieron en el Louvre hace un mes. As\u00ed fue como la Polic\u00eda logr\u00f3 acercarse a los sospechosos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-19T18:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/19\/robo-louvre-joyas-corona-francia-sospechosos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/19\/robo-louvre-joyas-corona-francia-sospechosos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/19\/robo-louvre-joyas-corona-francia-sospechosos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los ladrones irrumpieron en el Louvre hace un mes. As\u00ed fue como la Polic\u00eda logr\u00f3 acercarse a los sospechosos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los ladrones irrumpieron en el Louvre hace un mes. As\u00ed fue como la Polic\u00eda logr\u00f3 acercarse a los sospechosos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/19\/robo-louvre-joyas-corona-francia-sospechosos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Los ladrones irrumpieron en el Louvre hace un mes. As\u00ed fue como la Polic\u00eda logr\u00f3 acercarse a los sospechosos - Noticias","og_description":"Era el atardecer del s\u00e1bado 25 de octubre, el cuarto d\u00eda en que el equipo de vigilancia segu\u00eda a un sospechoso argelino, de 34 a\u00f1os, en Seine-Saint-Denis, a las afueras de Par\u00eds. El trabajo hab\u00eda sido tenso y tedioso. Una zona diversa, Seine-Saint-Denis alberga a personas de m\u00e1s de 130 nacionalidades, muchas de ellas de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/19\/robo-louvre-joyas-corona-francia-sospechosos-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-19T18:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/19\/robo-louvre-joyas-corona-francia-sospechosos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/19\/robo-louvre-joyas-corona-francia-sospechosos-trax\/"},"author":{"name":"","@id":""},"headline":"Los ladrones irrumpieron en el Louvre hace un mes. As\u00ed fue como la Polic\u00eda logr\u00f3 acercarse a los sospechosos","datePublished":"2025-11-19T18:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/19\/robo-louvre-joyas-corona-francia-sospechosos-trax\/"},"wordCount":2185,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/19\/robo-louvre-joyas-corona-francia-sospechosos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/19\/robo-louvre-joyas-corona-francia-sospechosos-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/19\/robo-louvre-joyas-corona-francia-sospechosos-trax\/","name":"Los ladrones irrumpieron en el Louvre hace un mes. As\u00ed fue como la Polic\u00eda logr\u00f3 acercarse a los sospechosos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-19T18:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/19\/robo-louvre-joyas-corona-francia-sospechosos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/19\/robo-louvre-joyas-corona-francia-sospechosos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/19\/robo-louvre-joyas-corona-francia-sospechosos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Los ladrones irrumpieron en el Louvre hace un mes. As\u00ed fue como la Polic\u00eda logr\u00f3 acercarse a los sospechosos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/19\/robo-louvre-joyas-corona-francia-sospechosos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Los ladrones irrumpieron en el Louvre hace un mes. As\u00ed fue como la Polic\u00eda logr\u00f3 acercarse a los sospechosos","url":"http:\/\/noticiasya.com\/colorado\/2025\/11\/19\/robo-louvre-joyas-corona-francia-sospechosos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2025\/11\/19\/robo-louvre-joyas-corona-francia-sospechosos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-19T18:03:39Z","datePublished":"2025-11-19T18:03:39Z","dateModified":"2025-11-19T18:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Los ladrones irrumpieron en el Louvre hace un mes. As\\u00ed fue como la Polic\\u00eda logr\\u00f3 acercarse a los sospechosos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2025\\\/11\\\/19\\\/robo-louvre-joyas-corona-francia-sospechosos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2025\\\/11\\\/19\\\/robo-louvre-joyas-corona-francia-sospechosos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-19T18:03:39Z\",\"datePublished\":\"2025-11-19T18:03:39Z\",\"dateModified\":\"2025-11-19T18:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1436144,"url":"https:\/\/noticiasya.com\/colorado\/2022\/12\/12\/arrestan-sospechoso-de-disparar-contra-policia-de-san-diego-durante-una-persecucion\/","url_meta":{"origin":1468506,"position":0},"title":"Arrestan sospechoso de disparar contra polic\u00eda de San Diego durante una persecuci\u00f3n","author":"agomez","date":"diciembre 12, 2022","format":false,"excerpt":"El largo enfrentamiento entre el equipo t\u00e1ctico SWAT y el sospechoso que se atrincher\u00f3 dentro de una casa, dur\u00f3 m\u00e1s de 9 horas.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/colorado\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467606,"url":"https:\/\/noticiasya.com\/colorado\/2025\/10\/21\/heridos-arma-agente-ice-los-angeles-trax\/","url_meta":{"origin":1468506,"position":1},"title":"Dos heridos, incluido un alguacil, tras dispararse el arma de un agente de ICE en  operaci\u00f3n migratoria en Los \u00c1ngeles","author":"agomez","date":"octubre 21, 2025","format":false,"excerpt":"Dos personas resultaron heridas, incluido un alguacil de EE.UU., durante una operaci\u00f3n de control migratorio la madrugada de martes en Los \u00c1ngeles, seg\u00fan inform\u00f3 a CNN una fuente policial.El arma de un agente del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) se dispar\u00f3 despu\u00e9s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456417,"url":"https:\/\/noticiasya.com\/colorado\/2024\/12\/10\/luigi-mangione-sospechoso-unitedhealthcare-ceo-trax\/","url_meta":{"origin":1468506,"position":2},"title":"El presunto asesino del CEO de UnitedHealthcare plane\u00f3 bien su ataque, pero cometi\u00f3 errores cruciales, seg\u00fan los expertos","author":"","date":"diciembre 10, 2024","format":false,"excerpt":"A primera vista, el asesino parec\u00eda demasiado meticuloso para ser un aficionado y demasiado descuidado para ser un profesional.Sin embargo, el sospechoso de asesinar a Brian Thompson, CEO de UnitedHealthcare, en una acera de Nueva York logr\u00f3 eludir su captura durante d\u00edas, lo que desconcert\u00f3 incluso a los expertos en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456925,"url":"https:\/\/noticiasya.com\/colorado\/2024\/12\/24\/sospechoso-fuego-mujer-metro-nueva-york-trax\/","url_meta":{"origin":1468506,"position":3},"title":"\u00bfQui\u00e9n es el sospechoso de prender fuego a una mujer en el metro de Nueva York y qu\u00e9 pas\u00f3? Esto sabemos","author":"","date":"diciembre 24, 2024","format":false,"excerpt":"Los fiscales acusaron este lunes a Sebasti\u00e1n Zapeta-Calil, de 33 a\u00f1os, de homicidio calificado, homicidio intencional sin premeditaci\u00f3n e incendio premeditado en relaci\u00f3n con la muerte de una mujer que falleci\u00f3 tras ser prendida en fuego en un vag\u00f3n del metro de la ciudad de Nueva York un d\u00eda antes.El\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456287,"url":"https:\/\/noticiasya.com\/colorado\/2024\/12\/05\/asesinato-ceo-unitedhealthcare-nueva-york-lo-que-sabemos\/","url_meta":{"origin":1468506,"position":4},"title":"Esto es lo que pas\u00f3 en el asesinato del CEO de UnitedHealthcare en Nueva York y lo que sabemos del sospechoso","author":"","date":"diciembre 5, 2024","format":false,"excerpt":"La Polic\u00eda est\u00e1 buscando a un atacante que dispar\u00f3 y mat\u00f3 al CEO de UnitedHealthcare, Brian Thompson, en lo que la Polic\u00eda describi\u00f3 como un ataque audaz y deliberado en el coraz\u00f3n de la ciudad de Nueva York.El atacante enmascarado estaba \u201cacechando\u201d afuera del Hilton Midtown poco antes de las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469413,"url":"https:\/\/noticiasya.com\/colorado\/2025\/12\/19\/investigacion-sospechoso-tiroteo-universidad-brown-trax\/","url_meta":{"origin":1468506,"position":5},"title":"C\u00f3mo dieron con el sospechoso del tiroteo en la Universidad de Brown y lo vincularon con el asesinato de un profesor del MIT","author":"","date":"diciembre 19, 2025","format":false,"excerpt":"Cinco d\u00edas despu\u00e9s de que comenzara una extensa b\u00fasqueda, la polic\u00eda se acerc\u00f3 al sospechoso del tiroteo en la Universidad de Brown tras surgir aparentes v\u00ednculos entre el ataque del s\u00e1bado en la escuela de Providence, Rhode Island, y la muerte dos d\u00edas m\u00e1s tarde de un profesor del MIT\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1468506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1468506"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1468506\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1468506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1468506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1468506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}