{"id":1468554,"date":"2025-11-20T14:03:39","date_gmt":"2025-11-20T22:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/20\/accidente-avion-ups-louisville-fotos-trax\/"},"modified":"2025-11-20T14:03:39","modified_gmt":"2025-11-20T22:03:39","slug":"accidente-avion-ups-louisville-fotos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2025\/11\/20\/accidente-avion-ups-louisville-fotos-trax\/","title":{"rendered":"Autoridades de EE.UU. dan a conocer fotograf\u00edas a detalle del accidente del avi\u00f3n de UPS en Louisville"},"content":{"rendered":"<p>La Junta Nacional de Seguridad en el Transporte de Estados Unidos (NTSB por sus siglas en ingl\u00e9s), ofreci\u00f3 un nuevo informe sobre el accidente del avi\u00f3n de UPS registrado a principios de este mes que se estrell\u00f3 en Louisville tan solo unos instantes despu\u00e9s del despegue.<\/p>\n<p>El reporte presentado muestra una serie de seis fotograf\u00edas obtenidas por un equipo de investigaci\u00f3n que muestran c\u00f3mo el motor izquierdo del McDonnell Douglas MD-11F  se separ\u00f3 del avi\u00f3n y se eleva por encima del ala, provocando una bola de fuego.<\/p>\n<p>Los tres pilotos del vuelo 2976 de UPS y 11 personas en tierra fallecieron cuando el avi\u00f3n se desplom\u00f3 y dej\u00f3 un rastro de escombros de m\u00e1s de medio kil\u00f3metro de largo al pasar por una planta de reciclaje de petr\u00f3leo y un almac\u00e9n de UPS, causando un enorme incendio y una columna de humo negro que fue visible a varios kil\u00f3metros de distancia.<\/p>\n<p>El informe destaca la existencia de grietas encontradas en los herrajes que fijan el motor al ala, adem\u00e1s de una posible sobrecarga en el vuelo. La agencia federal a\u00fan est\u00e1 realizando una investigaci\u00f3n m\u00e1s exhaustiva que podr\u00eda generar nuevos detalles.<\/p>\n<p>El avi\u00f3n de carga pertenec\u00eda a la empresa UPS, contaba con 34 a\u00f1os de antig\u00fcedad y se encontraba en proceso de ser retirado por la compa\u00f1\u00eda de transporte.<\/p>\n<p>Tras el accidente, la Administraci\u00f3n Federal de Aviaci\u00f3n (FAA, por sus siglas en ingl\u00e9s) <a href=\"https:\/\/www.cnn.com\/2025\/11\/08\/us\/ups-crash-fleets-grounded-investigation-lawsuit\">inmoviliz\u00f3 todos los aviones<\/a> MD-11 y MD-11F hasta que cada uno de ellos se someta a una inspecci\u00f3n exhaustiva. UPS cuenta con otros 25 modelos MD-11 en servicio y seis aeronaves que han estado almacenadas al menos durante los \u00faltimos 3 meses, de acuerdo con informaci\u00f3n de la empresa de an\u00e1lisis de aviaci\u00f3n Cirium.<\/p>\n<p>Los investigadores que revisaron la pista poco despu\u00e9s del accidente dijeron que recuperaron piezas met\u00e1licas del lugar. Entre ellas encontraron un par de accesorios estructurales que manten\u00edan el pil\u00f3n del motor, que es una pieza de metal muy resistente que sujeta a los motores del avi\u00f3n con las alas. De acuerdo con el reporte, los accesorios conocidos como orejetas mostraron grietas causadas por la fatiga y el sobreesfuerzo, como lo demostraron \u201csus posiciones a las 2 y a las 9 en punto\u201d, de acuerdo con los investigadores.<\/p>\n<p>El informe presenta una nueva cronolog\u00eda de la secuencia del accidente, junto a nuevos datos que muestran que el avi\u00f3n no logr\u00f3 elevarse por m\u00e1s de 30 pies por encima de la pista 17 derecha del Aeropuerto Internacional Muhammad Ali de Louisville.<\/p>\n<p>De acuerdo con el informe preliminar, un testigo que se encontraba en la torre de control dijo que la velocidad del despegue parec\u00eda normal para ese tipo de aeronave; sin embargo, asegur\u00f3 que el ascenso no lo era. Otro testigo coment\u00f3 que el avi\u00f3n dej\u00f3 de ascender y comenz\u00f3 a perder altitud antes de dar una vuelta hacia la izquierda.<\/p>\n<p>El avi\u00f3n MD-11 est\u00e1 equipado con tres motores: uno en cada ala y otro en la cola. El avi\u00f3n pas\u00f3 por mantenimiento previo en San Antonio que lo dej\u00f3 fuera de servicio por seis semanas, de acuerdo con los investigadores. Sin embargo, continuar\u00e1n revisando todos los registros de servicio por los que pas\u00f3.<\/p>\n<p>Las grabadoras de voz de la cabina, el motor y el pil\u00f3n que se desprendi\u00f3 del ala del avi\u00f3n fueron trasladados a unas instalaciones seguras donde se est\u00e1n examinando, as\u00ed lo inform\u00f3 la NTSB.<\/p>\n<p>De acuerdo con la Junta Nacional de Seguridad en el Transporte, la grabadora de voz conten\u00eda dos horas y cuatro minutos de \u201caudio digital de buena calidad\u201d. Y los datos de vuelo registraron 63 horas que abarcan m\u00e1s de 24 vuelos, incluido el del accidente.<\/p>\n<p>Tambi\u00e9n la NTSB, en una medida poco com\u00fan, estableci\u00f3 una relaci\u00f3n con un desastre anterior: el accidente del vuelo 191 de American Airlines en 1979, en Chicago, en el que murieron 271 personas a bordo y dos m\u00e1s en tierra. El avi\u00f3n era un McDonnell Douglas DC-10, que es precursor del MD-11.<\/p>\n<p>En aquella ocasi\u00f3n, durante la rotaci\u00f3n de despegue de la aeronave, el motor izquierdo, en conjunto con el pil\u00f3n y aproximadamente un metro del borde delantero del ala izquierdo, se separaron del avi\u00f3n y cayeron sobre la pista. El avi\u00f3n se desvi\u00f3 hacia la izquierda y se estrell\u00f3.<\/p>\n<p>Tras el accidente, fueron desplegados una gran cantidad de especialistas y expertos en control de tr\u00e1fico a\u00e9reo para investigar las causas del accidente.<\/p>\n<p>Cabe destacar que las 12 p\u00e1ginas con nuevos hallazgos fueron publicadas tras poco m\u00e1s de dos semanas desde que ocurri\u00f3 el accidente el 4 de noviembre, lo que supone un plazo considerablemente m\u00e1s r\u00e1pido que los 30 d\u00edas que suele tardar la NTSB en publicar un informe preliminar.<\/p>\n<p>\u201cAgradecemos la r\u00e1pida publicaci\u00f3n de los hallazgos preliminares por parte de la Junta Nacional de Seguridad en el Transporte y apoyaremos plenamente la investigaci\u00f3n hasta su conclusi\u00f3n\u201d, dijo UPS en un comunicado.<\/p>\n<p>Por su parte, Boeing, que hace tiempo se fusion\u00f3 con el fabricante de los aviones, McDonnell Douglas, declar\u00f3: \u201cSeguimos apoyando la investigaci\u00f3n dirigida por la NTSB. Transmitimos nuestro m\u00e1s sentido p\u00e9same a las familias que han perdido a sus seres queridos y nuestros pensamientos est\u00e1n con todos los afectados\u201d.<\/p>\n<p>Se espera que la NTSB publique un informe final en un plazo de 18 a 24 meses en el que se detallar\u00e1n las causas probables del accidente. La agencia no atribuye responsabilidades, sino que ofrece recomendaciones para mejorar la seguridad en el transporte a\u00e9reo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Junta Nacional de Seguridad en el Transporte de Estados Unidos (NTSB por sus siglas en ingl\u00e9s), ofreci\u00f3 un nuevo informe sobre el accidente del avi\u00f3n de UPS registrado a principios de este mes que se estrell\u00f3 en Louisville tan solo unos instantes despu\u00e9s del despegue. El reporte presentado muestra una serie de seis fotograf\u00edas [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468554","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Autoridades de EE.UU. dan a conocer fotograf\u00edas a detalle del accidente del avi\u00f3n de UPS en Louisville - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/20\/accidente-avion-ups-louisville-fotos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Autoridades de EE.UU. dan a conocer fotograf\u00edas a detalle del accidente del avi\u00f3n de UPS en Louisville - Noticias\" \/>\n<meta property=\"og:description\" content=\"La Junta Nacional de Seguridad en el Transporte de Estados Unidos (NTSB por sus siglas en ingl\u00e9s), ofreci\u00f3 un nuevo informe sobre el accidente del avi\u00f3n de UPS registrado a principios de este mes que se estrell\u00f3 en Louisville tan solo unos instantes despu\u00e9s del despegue. El reporte presentado muestra una serie de seis fotograf\u00edas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/20\/accidente-avion-ups-louisville-fotos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-20T22:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/20\/accidente-avion-ups-louisville-fotos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/20\/accidente-avion-ups-louisville-fotos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Autoridades de EE.UU. dan a conocer fotograf\u00edas a detalle del accidente del avi\u00f3n de UPS en Louisville\",\"datePublished\":\"2025-11-20T22:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/20\/accidente-avion-ups-louisville-fotos-trax\/\"},\"wordCount\":998,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/20\/accidente-avion-ups-louisville-fotos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/20\/accidente-avion-ups-louisville-fotos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/20\/accidente-avion-ups-louisville-fotos-trax\/\",\"name\":\"Autoridades de EE.UU. dan a conocer fotograf\u00edas a detalle del accidente del avi\u00f3n de UPS en Louisville - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-20T22:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/20\/accidente-avion-ups-louisville-fotos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/20\/accidente-avion-ups-louisville-fotos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/20\/accidente-avion-ups-louisville-fotos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Autoridades de EE.UU. dan a conocer fotograf\u00edas a detalle del accidente del avi\u00f3n de UPS en Louisville\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Autoridades de EE.UU. dan a conocer fotograf\u00edas a detalle del accidente del avi\u00f3n de UPS en Louisville - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/20\/accidente-avion-ups-louisville-fotos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Autoridades de EE.UU. dan a conocer fotograf\u00edas a detalle del accidente del avi\u00f3n de UPS en Louisville - Noticias","og_description":"La Junta Nacional de Seguridad en el Transporte de Estados Unidos (NTSB por sus siglas en ingl\u00e9s), ofreci\u00f3 un nuevo informe sobre el accidente del avi\u00f3n de UPS registrado a principios de este mes que se estrell\u00f3 en Louisville tan solo unos instantes despu\u00e9s del despegue. El reporte presentado muestra una serie de seis fotograf\u00edas [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/20\/accidente-avion-ups-louisville-fotos-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-20T22:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/20\/accidente-avion-ups-louisville-fotos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/20\/accidente-avion-ups-louisville-fotos-trax\/"},"author":{"name":"","@id":""},"headline":"Autoridades de EE.UU. dan a conocer fotograf\u00edas a detalle del accidente del avi\u00f3n de UPS en Louisville","datePublished":"2025-11-20T22:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/20\/accidente-avion-ups-louisville-fotos-trax\/"},"wordCount":998,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/20\/accidente-avion-ups-louisville-fotos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/20\/accidente-avion-ups-louisville-fotos-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/20\/accidente-avion-ups-louisville-fotos-trax\/","name":"Autoridades de EE.UU. dan a conocer fotograf\u00edas a detalle del accidente del avi\u00f3n de UPS en Louisville - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-20T22:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/20\/accidente-avion-ups-louisville-fotos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/20\/accidente-avion-ups-louisville-fotos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/20\/accidente-avion-ups-louisville-fotos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Autoridades de EE.UU. dan a conocer fotograf\u00edas a detalle del accidente del avi\u00f3n de UPS en Louisville"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/20\/accidente-avion-ups-louisville-fotos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Autoridades de EE.UU. dan a conocer fotograf\u00edas a detalle del accidente del avi\u00f3n de UPS en Louisville","url":"http:\/\/noticiasya.com\/colorado\/2025\/11\/20\/accidente-avion-ups-louisville-fotos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2025\/11\/20\/accidente-avion-ups-louisville-fotos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-20T22:03:39Z","datePublished":"2025-11-20T22:03:39Z","dateModified":"2025-11-20T22:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Autoridades de EE.UU. dan a conocer fotograf\\u00edas a detalle del accidente del avi\\u00f3n de UPS en Louisville\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2025\\\/11\\\/20\\\/accidente-avion-ups-louisville-fotos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2025\\\/11\\\/20\\\/accidente-avion-ups-louisville-fotos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-20T22:03:39Z\",\"datePublished\":\"2025-11-20T22:03:39Z\",\"dateModified\":\"2025-11-20T22:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1468028,"url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/04\/accidente-avion-ups-aeropuerto-louisville-trax\/","url_meta":{"origin":1468554,"position":0},"title":"Un avi\u00f3n de UPS se estrell\u00f3 cerca del aeropuerto de Louisville, seg\u00fan una fuente","author":"","date":"noviembre 4, 2025","format":false,"excerpt":"Un avi\u00f3n MD-11 de UPS se estrell\u00f3 cerca del aeropuerto de Louisville, Kentucky, seg\u00fan informaci\u00f3n preliminar, dice una fuente.The-CNN-Wire\u2122 & \u00a9 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468047,"url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/05\/accidente-avion-ups-devasta-louisville-trax\/","url_meta":{"origin":1468554,"position":1},"title":"El accidente de un avi\u00f3n de carga de UPS devasta Louisville, donde los lazos con el gigante del transporte son profundos","author":"","date":"noviembre 5, 2025","format":false,"excerpt":"Cuando los negocios empezaban a cerrar en Louisville, Kentucky, este martes, al atardecer, la calma se vio repentinamente interrumpida por una explosi\u00f3n gigantesca cerca del aeropuerto de la ciudad.Un avi\u00f3n de carga de UPS se estrell\u00f3 poco despu\u00e9s de despegar del Aeropuerto Internacional Muhammad Ali de Louisville, arrasando varios negocios,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468069,"url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/05\/ups-avion-md11-accidente-louisville-34-anios-trax\/","url_meta":{"origin":1468554,"position":2},"title":"Por qu\u00e9 UPS segu\u00eda volando el avi\u00f3n MD-11 de 34 a\u00f1os que se estrell\u00f3 cerca del aeropuerto de Louisville","author":"","date":"noviembre 5, 2025","format":false,"excerpt":"El avi\u00f3n de UPS que se estrell\u00f3 en Louisville era un jet de 34 a\u00f1os. Aunque eso es viejo para un avi\u00f3n de pasajeros, no lo es tanto en el mundo de la carga a\u00e9rea.En principio, no hay indicios de que la edad del McDonnell Douglas MD-11 haya sido de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468079,"url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/06\/investigacion-accidente-aereo-ups-louisville-trax\/","url_meta":{"origin":1468554,"position":3},"title":"\u00bfQu\u00e9 factores ayudan (o perjudican) la investigaci\u00f3n del accidente a\u00e9reo de UPS en Louisville?","author":"","date":"noviembre 6, 2025","format":false,"excerpt":"Un equipo de investigadores lleg\u00f3 este mi\u00e9rcoles a Louisville, Kentucky, para investigar las causas del accidente de un avi\u00f3n de carga de UPS poco despu\u00e9s de despegar del aeropuerto de Louisville este martes, que caus\u00f3 la muerte de al menos 12 personas y destruy\u00f3 negocios y otras estructuras en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468159,"url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/08\/faa-vuelos-aviones-carga-md-11-ups-trax\/","url_meta":{"origin":1468554,"position":4},"title":"La FAA detiene vuelos de aviones de carga MD-11 y exige inspecciones tras accidente de UPS que deja a una comunidad de luto","author":"","date":"noviembre 8, 2025","format":false,"excerpt":"Las cenizas se han asentado sobre el vecindario calcinado de Louisville, donde nueve personas siguen desaparecidas y las familias se aferran a la esperanza mientras los investigadores examinan los restos del mortal accidente del avi\u00f3n de carga de UPS ocurrido el martes.Una aeronave McDonnell Douglas MD-11 se precipit\u00f3 desde el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468151,"url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/08\/desastre-aereo-ups-conmociona-bar-local-trax\/","url_meta":{"origin":1468554,"position":5},"title":"La aleatoriedad del desastre a\u00e9reo de UPS conmociona a los clientes del &#171;happy hour&#187; de un popular bar local","author":"","date":"noviembre 8, 2025","format":false,"excerpt":"Los clientes habituales del \u201chappy hour\u201d ya se estaban reuniendo en Stooges Bar & Grill menos de dos horas antes del inicio del partido inaugural de la temporada de baloncesto masculino de la Universidad de Kentucky el martes por la noche.Unos 30 clientes ocupaban los taburetes de madera del local\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1468554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1468554"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1468554\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1468554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1468554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1468554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}