{"id":1468569,"date":"2025-11-21T02:03:49","date_gmt":"2025-11-21T10:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/21\/analisis-democratas-ordenes-ilegales-trump-trax\/"},"modified":"2025-11-21T02:03:49","modified_gmt":"2025-11-21T10:03:49","slug":"analisis-democratas-ordenes-ilegales-trump-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2025\/11\/21\/analisis-democratas-ordenes-ilegales-trump-trax\/","title":{"rendered":"\u00bfPor qu\u00e9 los dem\u00f3cratas advierten sobre las \u00f3rdenes ilegales de Trump?"},"content":{"rendered":"<p>El presidente Donald Trump ha vuelto a sugerir que sus <a href=\"https:\/\/www.cnn.com\/2024\/11\/01\/politics\/donald-trump-liz-cheney-war-hawk-battle\">oponentes <\/a><a href=\"https:\/\/www.cnn.com\/2023\/09\/28\/politics\/milley-donald-trump-execution-comment\">pol\u00edticos<\/a> merecen ser ejecutados. Y, una vez m\u00e1s, basa su argumento en una teor\u00eda legal bastante novedosa y una interpretaci\u00f3n dudosa de los hechos.<\/p>\n<p>Esta semana, media docena de congresistas dem\u00f3cratas grabaron un video instando a los miembros de las fuerzas armadas <a href=\"https:\/\/www.cnn.com\/2025\/11\/19\/politics\/democratic-lawmakers-urge-troops-to-disobey-illegal-orders\">a no obedecer \u00f3rdenes ilegales<\/a> que Trump pudiera emitir.<\/p>\n<p>Trump respondi\u00f3 publicando una serie de mensajes en redes sociales sugiriendo que estos miembros hab\u00edan cometido sedici\u00f3n y que posiblemente incluso merec\u00edan morir.<\/p>\n<p>Trump pas\u00f3 de decir que deber\u00edan ser arrestados, a republicar a alguien que dijo que George Washington los \u201cAHORCAR\u00cdA\u201d, para luego decir \u201c\u00a1CONDUCTA SEDICIARIA, castigada con la MUERTE!\u201d.<\/p>\n<p>La secretaria de prensa de la Casa Blanca, Karoline Leavitt, aclar\u00f3 el jueves que Trump<a href=\"https:\/\/www.cnn.com\/2025\/11\/19\/politics\/democratic-lawmakers-urge-troops-to-disobey-illegal-orders\">, de hecho, no quiere que se ejecute a los miembros del Congreso<\/a>.<\/p>\n<p>Pero, por lo dem\u00e1s, mantuvo su postura de que estos miembros actuaban de forma peligrosa y socavaban al comandante en jefe. Afirm\u00f3 que los miembros instaban a los militares a \u201cdesafiar la cadena de mando\u201d.<\/p>\n<p>\u201cLiteralmente les est\u00e1n diciendo a 1,3 millones de militares en servicio activo que desaf\u00eden la cadena de mando, que no sigan las \u00f3rdenes legales\u201d, manifest\u00f3 Leavitt.<\/p>\n<p>Pero eso no es lo que estaban diciendo literalmente.<\/p>\n<p>De hecho, los miembros no estaban instando a nadie a desobedecer \u201c\u00f3rdenes legales\u201d. En el video se refer\u00edan expl\u00edcitamente solo a \u00f3rdenes <em>ilegales<\/em>, y lo hicieron repetidamente.<\/p>\n<p>El otro problema es que \u201cdesafiar la cadena de mando\u201d no es solo algo que los miembros del servicio militar tienen <em>permitido<\/em> hacer en estos casos; es algo que a menudo se les <em>exige<\/em> hacer.<\/p>\n<p>El art\u00edculo 92 del C\u00f3digo Uniforme de Justicia Militar, relativo al incumplimiento de \u00f3rdenes, establece que los miembros solo pueden ser sancionados por desobedecer \u00f3rdenes leg\u00edtimas. En general, los militares est\u00e1n obligados a no acatar \u00f3rdenes manifiestamente ilegales.<\/p>\n<p>Si existe una objeci\u00f3n potencialmente m\u00e1s leg\u00edtima al video de los dem\u00f3cratas, es que est\u00e1n creando un hombre de paja. B\u00e1sicamente, que est\u00e1n inventando de la nada la posibilidad de que Trump emita \u00f3rdenes ilegales para hacer que los miembros del servicio militar duden en acatar sus directrices.<\/p>\n<p>Este es el argumento que algunos aliados de Trump han esgrimido en Fox News.<\/p>\n<p>\u201cSi no puedes nombrar las \u00f3rdenes ilegales que estos tipos mencionan en su video, eso me demuestra que ni siquiera tienes el valor de denunciar de qu\u00e9 est\u00e1s hablando\u201d, indic\u00f3 el representante republicano Eli Crane de Arizona.<\/p>\n<p>En un segmento aparte, la presentadora de Fox News, Martha MacCallum, presion\u00f3 repetidamente al representante dem\u00f3crata Jason Crow, uno de los legisladores que aparecen en el video, sobre el mismo tema.<\/p>\n<p>\u201c\u00bfA qu\u00e9 orden espec\u00edfica del comandante en jefe que pide a nuestras fuerzas armadas que cumplan se opone usted?\u201d, pregunt\u00f3 MacCallum. \u201cEsto es muy, muy vago\u201d.<\/p>\n<p>Pero no es que esta sea una posibilidad que los dem\u00f3cratas se hayan inventado de la nada. Trump les ha dado mucho material para trabajar, incluyendo algunas cosas que <a href=\"https:\/\/x.com\/atrupar\/status\/1991252880917926202\">Crow mencion\u00f3 en la entrevista<\/a>.<\/p>\n<p>Trump ha propuesto repetidamente realizar acciones \u2014tanto militares como de otra \u00edndole\u2014que parecen ser ilegales. Personas que sirvieron con \u00e9l han declarado que sugiri\u00f3 acciones ilegales. Y, sin duda, Trump est\u00e1 poniendo a prueba los l\u00edmites de la ley con el uso que hace de las fuerzas armadas incluso en este mismo momento.<\/p>\n<p>El ejemplo m\u00e1s claro en este momento son los ataques de Trump contra supuestos buques narcotraficantes en el Mar Caribe y el Oc\u00e9ano Pac\u00edfico, ataques que han <a href=\"https:\/\/www.cnn.com\/2025\/11\/13\/politics\/20th-strike-us-military-boats-caribbean\">matado a m\u00e1s de 80 personas<\/a> sin un proceso legal.<\/p>\n<p>CNN ha informado que tanto las Naciones Unidas como aliados clave como el Reino Unido consideran los ataques <a href=\"https:\/\/www.cnn.com\/2025\/11\/11\/politics\/uk-suspends-caribbean-intelligence-sharing-us\">como ejecuciones extrajudiciales ilegales<\/a>.<\/p>\n<p>El senador republicano Rand Paul, de Kentucky, se ha hecho eco de estas afirmaciones, mientras que otros senadores republicanos tambi\u00e9n han cuestionado su legalidad.<\/p>\n<p>El Gobierno se ha negado a detallar p\u00fablicamente su justificaci\u00f3n legal, incluso cuando el Departamento de Justicia ha emitido una <a href=\"https:\/\/www.cnn.com\/2025\/10\/06\/politics\/classified-justice-department-memo-cartel-strikes\">opini\u00f3n legal clasificada<\/a> que autoriza los ataques.<\/p>\n<p>La administraci\u00f3n ha liberado a los supervivientes de los ataques, quienes, de haber permanecido bajo custodia estadounidense, podr\u00edan haber <a href=\"https:\/\/www.cnn.com\/2025\/10\/20\/politics\/us-strike-alleged-drug-smugglers-release\">obligado al Gobierno a defenderse ante los tribunales<\/a>.<\/p>\n<p>Adem\u00e1s, un alto comandante que, seg\u00fan CNN, plante\u00f3 <a href=\"https:\/\/www.cnn.com\/2025\/10\/16\/politics\/southern-command-caribbean-strikes-holsey\">dudas sobre la legalidad de los ataques,<\/a> ha decidido jubilarse anticipadamente.<\/p>\n<p>Existe una duda muy real sobre si los militares involucrados en esos ataques estaban cumpliendo \u00f3rdenes ilegales. Y la administraci\u00f3n ha evitado de forma proactiva un proceso legal m\u00e1s riguroso que podr\u00eda esclarecer esa cuesti\u00f3n.<\/p>\n<p>Pero eso no es todo. Aqu\u00ed hay otros datos clave:<\/p>\n<ul>\n<li>Durante la campa\u00f1a de 2016, Trump insinu\u00f3 que el ej\u00e9rcito torturar\u00eda a personas y asesinar\u00eda a familiares de terroristas. Cuando se le plante\u00f3 que las tropas no acatar\u00edan \u00f3rdenes tan ilegales, Trump respondi\u00f3: \u201c<a href=\"https:\/\/www.nytimes.com\/2016\/03\/04\/us\/politics\/transcript-of-the-republican-presidential-debate-in-detroit.html\">Si yo digo que lo hagan, lo har\u00e1n<\/a>\u201d. (<a href=\"https:\/\/www.cnn.com\/2016\/03\/04\/politics\/donald-trump-reverses-on-torture\">Posteriormente se retract\u00f3<\/a>, afirmando que no ordenar\u00eda violar el derecho internacional).<\/li>\n<li>En 2020, Trump le dijo a Ir\u00e1n que Estados Unidos estaba <a href=\"https:\/\/www.cnn.com\/2020\/01\/05\/world\/trump-iran-cultural-sites-war-crime\">preparado para atacar sitios culturales iran\u00edes<\/a>, lo que probablemente se habr\u00eda considerado un crimen de guerra si se hubiera llevado a cabo.<\/li>\n<li>En 2018, el primer secretario de Estado de Trump, Rex Tillerson, manifest\u00f3 p\u00fablicamente despu\u00e9s de su partida que Trump hab\u00eda <a href=\"https:\/\/www.cnn.com\/videos\/politics\/2018\/12\/07\/rex-tillerson-trump-comments-cbs-orig-vstop-bdk.cnn\">intentado repetidamente hacer cosas ilegales<\/a>.<\/li>\n<li>En 2019, la secretaria de Seguridad Nacional, Kirstjen Nielsen, dimiti\u00f3 tras enfrentarse con Trump por sus <a href=\"https:\/\/www.cnn.com\/2019\/04\/09\/politics\/donald-trump-kirstjen-nielsen-immigration\">repetidos deseos de hacer cosas que ella consideraba que podr\u00edan ser ilegales.<\/a><\/li>\n<li>El exsecretario de Defensa de Trump, Mark Esper, ha dicho que en 2020 Trump consider\u00f3 la posibilidad de que los militares <a href=\"https:\/\/www.cnn.com\/2022\/05\/02\/politics\/esper-trump-protesters\">dispararan en las piernas a los manifestantes que protestaban por la justicia racial cerca de la Casa Blanca<\/a>.<\/li>\n<li>Este a\u00f1o, varios jueces han indicado que la administraci\u00f3n ha desobedecido o violado \u00f3rdenes judiciales <a href=\"https:\/\/www.cnn.com\/2025\/05\/21\/politics\/deportation-flight-south-sudan-controversy\">con sus <\/a><a href=\"https:\/\/www.cnn.com\/2025\/11\/14\/politics\/appeals-court-declines-probable-cause-order-trump-officials-contempt\">deportaciones<\/a> o con el uso de la <a href=\"https:\/\/www.cnn.com\/2025\/10\/06\/us\/oregon-national-guard-trump-ruling-portland-hnk\">Guardia Nacional en territorio nacional<\/a>.<\/li>\n<li>Esos despliegues de la Guardia Nacional representan un <a href=\"https:\/\/www.cnn.com\/2025\/08\/11\/politics\/washington-dc-troops-trump\">uso extraordinario de las fuerzas armadas,<\/a> cuya legalidad a\u00fan se est\u00e1 debatiendo en los tribunales de todo el pa\u00eds.<\/li>\n<li>Trump ha coqueteado repetidamente con un escenario en el que <a href=\"https:\/\/www.washingtonpost.com\/politics\/2025\/02\/18\/trumps-napoleon-quote-ups-anti-democratic-ante\/\">las leyes no se aplican a \u00e9l<\/a> porque es todopoderoso y est\u00e1 haciendo cosas buenas por el pa\u00eds.<\/li>\n<\/ul>\n<p>Sin duda, es provocador que los dem\u00f3cratas planteen este tema de la forma en que lo han hecho. Pero no es que se lo hayan inventado de la nada.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Donald Trump ha vuelto a sugerir que sus oponentes pol\u00edticos merecen ser ejecutados. Y, una vez m\u00e1s, basa su argumento en una teor\u00eda legal bastante novedosa y una interpretaci\u00f3n dudosa de los hechos. Esta semana, media docena de congresistas dem\u00f3cratas grabaron un video instando a los miembros de las fuerzas armadas a no [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468569","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfPor qu\u00e9 los dem\u00f3cratas advierten sobre las \u00f3rdenes ilegales de Trump? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/21\/analisis-democratas-ordenes-ilegales-trump-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPor qu\u00e9 los dem\u00f3cratas advierten sobre las \u00f3rdenes ilegales de Trump? - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente Donald Trump ha vuelto a sugerir que sus oponentes pol\u00edticos merecen ser ejecutados. Y, una vez m\u00e1s, basa su argumento en una teor\u00eda legal bastante novedosa y una interpretaci\u00f3n dudosa de los hechos. Esta semana, media docena de congresistas dem\u00f3cratas grabaron un video instando a los miembros de las fuerzas armadas a no [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/21\/analisis-democratas-ordenes-ilegales-trump-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-21T10:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/21\/analisis-democratas-ordenes-ilegales-trump-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/21\/analisis-democratas-ordenes-ilegales-trump-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfPor qu\u00e9 los dem\u00f3cratas advierten sobre las \u00f3rdenes ilegales de Trump?\",\"datePublished\":\"2025-11-21T10:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/21\/analisis-democratas-ordenes-ilegales-trump-trax\/\"},\"wordCount\":1132,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/21\/analisis-democratas-ordenes-ilegales-trump-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/21\/analisis-democratas-ordenes-ilegales-trump-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/21\/analisis-democratas-ordenes-ilegales-trump-trax\/\",\"name\":\"\u00bfPor qu\u00e9 los dem\u00f3cratas advierten sobre las \u00f3rdenes ilegales de Trump? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-21T10:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/21\/analisis-democratas-ordenes-ilegales-trump-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/21\/analisis-democratas-ordenes-ilegales-trump-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/21\/analisis-democratas-ordenes-ilegales-trump-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfPor qu\u00e9 los dem\u00f3cratas advierten sobre las \u00f3rdenes ilegales de Trump?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPor qu\u00e9 los dem\u00f3cratas advierten sobre las \u00f3rdenes ilegales de Trump? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/21\/analisis-democratas-ordenes-ilegales-trump-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfPor qu\u00e9 los dem\u00f3cratas advierten sobre las \u00f3rdenes ilegales de Trump? - Noticias","og_description":"El presidente Donald Trump ha vuelto a sugerir que sus oponentes pol\u00edticos merecen ser ejecutados. Y, una vez m\u00e1s, basa su argumento en una teor\u00eda legal bastante novedosa y una interpretaci\u00f3n dudosa de los hechos. Esta semana, media docena de congresistas dem\u00f3cratas grabaron un video instando a los miembros de las fuerzas armadas a no [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/21\/analisis-democratas-ordenes-ilegales-trump-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-21T10:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/21\/analisis-democratas-ordenes-ilegales-trump-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/21\/analisis-democratas-ordenes-ilegales-trump-trax\/"},"author":{"name":"","@id":""},"headline":"\u00bfPor qu\u00e9 los dem\u00f3cratas advierten sobre las \u00f3rdenes ilegales de Trump?","datePublished":"2025-11-21T10:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/21\/analisis-democratas-ordenes-ilegales-trump-trax\/"},"wordCount":1132,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/21\/analisis-democratas-ordenes-ilegales-trump-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/21\/analisis-democratas-ordenes-ilegales-trump-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/21\/analisis-democratas-ordenes-ilegales-trump-trax\/","name":"\u00bfPor qu\u00e9 los dem\u00f3cratas advierten sobre las \u00f3rdenes ilegales de Trump? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-21T10:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/21\/analisis-democratas-ordenes-ilegales-trump-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/21\/analisis-democratas-ordenes-ilegales-trump-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/21\/analisis-democratas-ordenes-ilegales-trump-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfPor qu\u00e9 los dem\u00f3cratas advierten sobre las \u00f3rdenes ilegales de Trump?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/21\/analisis-democratas-ordenes-ilegales-trump-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfPor qu\u00e9 los dem\u00f3cratas advierten sobre las \u00f3rdenes ilegales de Trump?","url":"http:\/\/noticiasya.com\/colorado\/2025\/11\/21\/analisis-democratas-ordenes-ilegales-trump-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2025\/11\/21\/analisis-democratas-ordenes-ilegales-trump-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-21T10:03:49Z","datePublished":"2025-11-21T10:03:49Z","dateModified":"2025-11-21T10:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfPor qu\\u00e9 los dem\\u00f3cratas advierten sobre las \\u00f3rdenes ilegales de Trump?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2025\\\/11\\\/21\\\/analisis-democratas-ordenes-ilegales-trump-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2025\\\/11\\\/21\\\/analisis-democratas-ordenes-ilegales-trump-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-21T10:03:49Z\",\"datePublished\":\"2025-11-21T10:03:49Z\",\"dateModified\":\"2025-11-21T10:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1468549,"url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/20\/trump-acusa-legisladores-democratas-conducta-sediciosa-trax\/","url_meta":{"origin":1468569,"position":0},"title":"Trump acusa a legisladores dem\u00f3cratas de &#171;conducta sediciosa&#187; y habla de &#171;pena de muerte&#187;","author":"","date":"noviembre 20, 2025","format":false,"excerpt":"El presidente Donald Trump pidi\u00f3 este jueves el arresto de legisladores dem\u00f3cratas que instaron a integrantes de las Fuerzas Armadas y de la comunidad de inteligencia a desobedecer \u00f3rdenes ilegales que pudiera emitir el Gobierno, calific\u00e1ndolo como \u201cSEDITIOUS BEHAVIOR, punishable by DEATH!\u201d (\u201cCONDUCTA SEDICIOSA, castigada con la PENA DE MUERTE\u201d).\u201cSe\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469223,"url":"https:\/\/noticiasya.com\/colorado\/2025\/12\/12\/marina-castigo-senador-kelly-video-ordenes-ilegales-trax\/","url_meta":{"origin":1468569,"position":1},"title":"La Marina entrega informe a Hegseth sobre posible castigo para el senador Mark Kelly por el video de &#171;\u00f3rdenes ilegales&#187;","author":"","date":"diciembre 12, 2025","format":false,"excerpt":"La Marina de EE.UU. present\u00f3 sus recomendaciones sobre posibles castigos, si los hubiera, para el senador dem\u00f3crata Mark Kelly por su participaci\u00f3n en un video que recordaba a las fuerzas militares estadounidenses que tienen el deber de rechazar \u00f3rdenes ilegales, dijo un funcionario del Pent\u00e1gono a CNN el jueves.Esas recomendaciones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468904,"url":"https:\/\/noticiasya.com\/colorado\/2025\/12\/02\/hegseth-fuerzas-armadas-no-seguiran-ordenes-ilegales-presidente-trax\/","url_meta":{"origin":1468569,"position":2},"title":"En un video de 2016, Hegseth afirm\u00f3 que las Fuerzas Armadas de EE.UU. &#171;no seguir\u00e1n \u00f3rdenes ilegales&#187; del presidente","author":"","date":"diciembre 2, 2025","format":false,"excerpt":"El secretario de Defensa Pete Hegseth dijo a la audiencia en un video de 2016, no reportado anteriormente, que las Fuerzas Armadas de Estados Unidos \u201cno seguir\u00e1n \u00f3rdenes ilegales de su comandante en jefe\u201d, y describi\u00f3 la negativa a acatar \u00f3rdenes ilegales como parte del ethos y los est\u00e1ndares militares,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469971,"url":"https:\/\/noticiasya.com\/colorado\/2026\/01\/10\/politica-exterior-trump-suena-monarquia-trax\/","url_meta":{"origin":1468569,"position":3},"title":"La pol\u00edtica exterior de Trump  tiene rasgos que recuerdan a la de una monarqu\u00eda","author":"","date":"enero 10, 2026","format":false,"excerpt":"Hace dos meses, el presidente Donald Trump y sus aliados ridiculizaron a sus cr\u00edticos por las multitudinarias protestas \u201cNo Kings\u201d. Consideraron melodram\u00e1tico comparar las acciones y los objetivos de Trump con los de un rey.Sin embargo, a medida que Trump ha emprendido un esfuerzo cada vez m\u00e1s descarado por ejercer\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468719,"url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/26\/hegseth-castigos-kelly-ordenes-ilegales-trax\/","url_meta":{"origin":1468569,"position":4},"title":"Hegseth eval\u00faa posibles castigos para el senador Kelly por el video en el que se llama a desobedecer las &#171;\u00f3rdenes ilegales&#187;","author":"","date":"noviembre 26, 2025","format":false,"excerpt":"P\u00fablicamente, el secretario de Defensa, Pete Hegseth, ha criticado duramente a los seis legisladores dem\u00f3cratas que publicaron un video la semana pasada instando a los miembros del servicio militar a desobedecer \u00f3rdenes ilegales, llamando a los legisladores los \u201cSeis sediciosos\u201d y categorizando su mensaje como \u201cdespreciable, imprudente y falso\u201d.Esa cr\u00edtica\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468674,"url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/24\/medida-pentagono-contra-mark-kelly-venganza-trump-trax\/","url_meta":{"origin":1468569,"position":5},"title":"La medida del Pent\u00e1gono contra el h\u00e9roe de guerra Mark Kelly demuestra que la sed de venganza de Trump no tiene fin","author":"","date":"noviembre 24, 2025","format":false,"excerpt":"La campa\u00f1a de represalias pol\u00edticas del presidente de EE.UU., Donald Trump, acaba de dar dos pasos embarazosos hacia atr\u00e1s y un salto gigante hacia adelante.El colapso de los casos penales contra el exjefe del FBI James Comey y la fiscal general de Nueva York, Letitia James, plante\u00f3 dudas sobre la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1468569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1468569"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1468569\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1468569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1468569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1468569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}