{"id":1468573,"date":"2025-11-21T06:03:51","date_gmt":"2025-11-21T14:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/21\/muere-piloto-estrellarse-caza-indio-dubai-trax\/"},"modified":"2025-11-21T06:03:51","modified_gmt":"2025-11-21T14:03:51","slug":"muere-piloto-estrellarse-caza-indio-dubai-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2025\/11\/21\/muere-piloto-estrellarse-caza-indio-dubai-trax\/","title":{"rendered":"Muere piloto tras estrellarse un caza indio en el Sal\u00f3n Aeron\u00e1utico de Dub\u00e1i"},"content":{"rendered":"<p>Un piloto muri\u00f3 tras estrellarse un caza indio Tejas durante una exhibici\u00f3n a\u00e9rea en el Sal\u00f3n Aeron\u00e1utico de Dubai, seg\u00fan inform\u00f3 este viernes la Oficina de Medios de Comunicaci\u00f3n de Dubai.<\/p>\n<p>Los servicios de emergencia y los bomberos est\u00e1n gestionando la situaci\u00f3n <em>in situ<\/em>, seg\u00fan se ha informado.<\/p>\n<p>El Sal\u00f3n Aeron\u00e1utico de Dub\u00e1i es una de las ferias de aviaci\u00f3n y defensa m\u00e1s grandes del mundo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un piloto muri\u00f3 tras estrellarse un caza indio Tejas durante una exhibici\u00f3n a\u00e9rea en el Sal\u00f3n Aeron\u00e1utico de Dubai, seg\u00fan inform\u00f3 este viernes la Oficina de Medios de Comunicaci\u00f3n de Dubai. Los servicios de emergencia y los bomberos est\u00e1n gestionando la situaci\u00f3n in situ, seg\u00fan se ha informado. El Sal\u00f3n Aeron\u00e1utico de Dub\u00e1i es una [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468573","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Muere piloto tras estrellarse un caza indio en el Sal\u00f3n Aeron\u00e1utico de Dub\u00e1i - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/21\/muere-piloto-estrellarse-caza-indio-dubai-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Muere piloto tras estrellarse un caza indio en el Sal\u00f3n Aeron\u00e1utico de Dub\u00e1i - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un piloto muri\u00f3 tras estrellarse un caza indio Tejas durante una exhibici\u00f3n a\u00e9rea en el Sal\u00f3n Aeron\u00e1utico de Dubai, seg\u00fan inform\u00f3 este viernes la Oficina de Medios de Comunicaci\u00f3n de Dubai. Los servicios de emergencia y los bomberos est\u00e1n gestionando la situaci\u00f3n in situ, seg\u00fan se ha informado. El Sal\u00f3n Aeron\u00e1utico de Dub\u00e1i es una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/21\/muere-piloto-estrellarse-caza-indio-dubai-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-21T14:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/21\/muere-piloto-estrellarse-caza-indio-dubai-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/21\/muere-piloto-estrellarse-caza-indio-dubai-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Muere piloto tras estrellarse un caza indio en el Sal\u00f3n Aeron\u00e1utico de Dub\u00e1i\",\"datePublished\":\"2025-11-21T14:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/21\/muere-piloto-estrellarse-caza-indio-dubai-trax\/\"},\"wordCount\":112,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/21\/muere-piloto-estrellarse-caza-indio-dubai-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/21\/muere-piloto-estrellarse-caza-indio-dubai-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/21\/muere-piloto-estrellarse-caza-indio-dubai-trax\/\",\"name\":\"Muere piloto tras estrellarse un caza indio en el Sal\u00f3n Aeron\u00e1utico de Dub\u00e1i - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-21T14:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/21\/muere-piloto-estrellarse-caza-indio-dubai-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/21\/muere-piloto-estrellarse-caza-indio-dubai-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/21\/muere-piloto-estrellarse-caza-indio-dubai-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Muere piloto tras estrellarse un caza indio en el Sal\u00f3n Aeron\u00e1utico de Dub\u00e1i\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Muere piloto tras estrellarse un caza indio en el Sal\u00f3n Aeron\u00e1utico de Dub\u00e1i - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/21\/muere-piloto-estrellarse-caza-indio-dubai-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Muere piloto tras estrellarse un caza indio en el Sal\u00f3n Aeron\u00e1utico de Dub\u00e1i - Noticias","og_description":"Un piloto muri\u00f3 tras estrellarse un caza indio Tejas durante una exhibici\u00f3n a\u00e9rea en el Sal\u00f3n Aeron\u00e1utico de Dubai, seg\u00fan inform\u00f3 este viernes la Oficina de Medios de Comunicaci\u00f3n de Dubai. Los servicios de emergencia y los bomberos est\u00e1n gestionando la situaci\u00f3n in situ, seg\u00fan se ha informado. El Sal\u00f3n Aeron\u00e1utico de Dub\u00e1i es una [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/21\/muere-piloto-estrellarse-caza-indio-dubai-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-21T14:03:51+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/21\/muere-piloto-estrellarse-caza-indio-dubai-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/21\/muere-piloto-estrellarse-caza-indio-dubai-trax\/"},"author":{"name":"","@id":""},"headline":"Muere piloto tras estrellarse un caza indio en el Sal\u00f3n Aeron\u00e1utico de Dub\u00e1i","datePublished":"2025-11-21T14:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/21\/muere-piloto-estrellarse-caza-indio-dubai-trax\/"},"wordCount":112,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/21\/muere-piloto-estrellarse-caza-indio-dubai-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/21\/muere-piloto-estrellarse-caza-indio-dubai-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/21\/muere-piloto-estrellarse-caza-indio-dubai-trax\/","name":"Muere piloto tras estrellarse un caza indio en el Sal\u00f3n Aeron\u00e1utico de Dub\u00e1i - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-21T14:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/21\/muere-piloto-estrellarse-caza-indio-dubai-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/21\/muere-piloto-estrellarse-caza-indio-dubai-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/21\/muere-piloto-estrellarse-caza-indio-dubai-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Muere piloto tras estrellarse un caza indio en el Sal\u00f3n Aeron\u00e1utico de Dub\u00e1i"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/21\/muere-piloto-estrellarse-caza-indio-dubai-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Muere piloto tras estrellarse un caza indio en el Sal\u00f3n Aeron\u00e1utico de Dub\u00e1i","url":"http:\/\/noticiasya.com\/colorado\/2025\/11\/21\/muere-piloto-estrellarse-caza-indio-dubai-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2025\/11\/21\/muere-piloto-estrellarse-caza-indio-dubai-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-21T14:03:51Z","datePublished":"2025-11-21T14:03:51Z","dateModified":"2025-11-21T14:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Muere piloto tras estrellarse un caza indio en el Sal\\u00f3n Aeron\\u00e1utico de Dub\\u00e1i\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2025\\\/11\\\/21\\\/muere-piloto-estrellarse-caza-indio-dubai-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2025\\\/11\\\/21\\\/muere-piloto-estrellarse-caza-indio-dubai-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-21T14:03:51Z\",\"datePublished\":\"2025-11-21T14:03:51Z\",\"dateModified\":\"2025-11-21T14:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1463476,"url":"https:\/\/noticiasya.com\/colorado\/2025\/06\/12\/carlos-rinzelli-piloto-de-avion-y-analista-aeronautico-el-avion-nunca-volo\/","url_meta":{"origin":1468573,"position":0},"title":"Carlos Rinzelli, piloto de avi\u00f3n y analista aeron\u00e1utico: &#171;El avi\u00f3n nunca vol\u00f3&#187;","author":"","date":"junio 12, 2025","format":false,"excerpt":"Carlos Rinzelli, piloto de avi\u00f3n y analista aeron\u00e1utico, se refiri\u00f3 al accidente del Boeing 787-800 Dreamliner, que dej\u00f3 242 muertos en India.En CNN Primera Ma\u00f1ana, afirm\u00f3 que el hecho resulta \u201csorprendente, no solo por el modelo de avi\u00f3n, sino tambi\u00e9n por la forma en la que ocurri\u00f3\u201d.Destac\u00f3 que es \u201cun\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464146,"url":"https:\/\/noticiasya.com\/colorado\/2025\/07\/02\/influencer-ethan-guo-arraigo-aterrizar-antartida-orix\/","url_meta":{"origin":1468573,"position":1},"title":"El influencer estadounidense Ethan Guo queda con arraigo nacional en Chile tras aterrizar sin permiso en la Ant\u00e1rtida","author":"","date":"julio 2, 2025","format":false,"excerpt":"El influencer y piloto estadounidense Ethan Guo, de 19 a\u00f1os, quien llam\u00f3 la atenci\u00f3n al aterrizar una peque\u00f1a aeronave en la Ant\u00e1rtida sin permiso, continuaba detenido este martes luego de que la Fiscal\u00eda de Magallanes y la Ant\u00e1rtica Chilena determinara el domingo que el joven debe permanecer en el sector\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464163,"url":"https:\/\/noticiasya.com\/colorado\/2025\/07\/02\/fiscalia-chilena-ethan-guo-antartica-vuelo-punta-arenas-orix\/","url_meta":{"origin":1468573,"position":2},"title":"Fiscal\u00eda chilena confirma que Ethan Guo permanece en la Ant\u00e1rtica esperando un vuelo comercial para volver a Punta Arenas","author":"","date":"julio 2, 2025","format":false,"excerpt":"La Fiscal\u00eda de Magallanes y la Ant\u00e1rtica Chilena confirm\u00f3 este mi\u00e9rcoles a CNN que el piloto e influencer estadounidense de 19 a\u00f1os, Ethan Guo, permanece en la Ant\u00e1rtica a la espera de un vuelo comercial para regresar a la ciudad de Punta Arenas, lugar desde donde el 28 de junio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446063,"url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/27\/paro-aeronautico-argentina-vuelos-afectados-orix\/","url_meta":{"origin":1468573,"position":3},"title":"Este mi\u00e9rcoles hay paro aeron\u00e1utico en Argentina y los vuelos se ver\u00e1n afectados","author":"","date":"febrero 27, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Los gremios aeron\u00e1uticos Asociaci\u00f3n del Personal Aeron\u00e1utico (APA), Asociaci\u00f3n Pilotos de L\u00edneas A\u00e9reas (APLA) y la Uni\u00f3n del Personal Superior y Profesional de Empresas Aerocomerciales (UPSA) ratificaron el paro de 24 horas para este mi\u00e9rcoles 28 de febrero.La medida fue confirmada luego de una reuni\u00f3n en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466642,"url":"https:\/\/noticiasya.com\/colorado\/2025\/09\/20\/cinco-latinos-grandes-ligas-orix\/","url_meta":{"origin":1468573,"position":4},"title":"Cinco latinos que dejaron su huella en las Grandes Ligas","author":"","date":"septiembre 20, 2025","format":false,"excerpt":"El b\u00e9isbol es uno de los deportes con m\u00e1s arraigo en los Estados Unidos. La tradici\u00f3n, sin embargo, est\u00e1 cada d\u00eda m\u00e1s empapada por el sabor proveniente del aporte de los peloteros hispanos.Y aunque el ingreso del primer pelotero latino al Sal\u00f3n de la Fama no se dio hasta el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463366,"url":"https:\/\/noticiasya.com\/colorado\/2025\/06\/09\/mueren-seis-personas-avioneta-estrellada-san-diego-trax\/","url_meta":{"origin":1468573,"position":5},"title":"Mueren seis personas al estrellarse una avioneta frente a San Diego","author":"","date":"junio 9, 2025","format":false,"excerpt":"Seis personas murieron al estrellarse una avioneta en el oc\u00e9ano frente a San Diego el domingo por la tarde, inform\u00f3 el lunes la Administraci\u00f3n Federal de Aviaci\u00f3n.Los \u00faltimos momentos antes de que el bimotor Cessna se estrellara -lo que desencaden\u00f3 una gran b\u00fasqueda en el oc\u00e9ano Pac\u00edfico cerca de San\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1468573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1468573"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1468573\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1468573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1468573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1468573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}