{"id":1468665,"date":"2025-11-24T15:03:51","date_gmt":"2025-11-24T23:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/24\/champions-league-chelsea-barcelona-jornada-5-orix\/"},"modified":"2025-11-24T15:03:51","modified_gmt":"2025-11-24T23:03:51","slug":"champions-league-chelsea-barcelona-jornada-5-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2025\/11\/24\/champions-league-chelsea-barcelona-jornada-5-orix\/","title":{"rendered":"Chelsea vs. Barcelona por la Champions League 2025\/2026: previa, posibles alineaciones, hora y c\u00f3mo ver por TV e internet"},"content":{"rendered":"<p>La quinta jornada de la Liga de Campeones de la UEFA tiene reservado un plato fuerte: Chelsea vs. FC Barcelona. Tanto el conjunto ingl\u00e9s como el espa\u00f1ol son grandes candidatos para dejar huella en esta edici\u00f3n de la competencia y, hasta ahora, no han decepcionado.<\/p>\n<p>Los de Londres vienen con una excelente racha positiva de cinco partidos sin derrotas y de ocho triunfos en sus \u00faltimas 10 presentaciones, contabilizando todas las competencias. El blaugrana, por su parte, recuper\u00f3 terreno en LaLiga en las \u00faltimas dos fechas con dos triunfos y ahora apuesta a hacer lo mismo en la fase de liga de la Champions.<\/p>\n<p>Y es que, ante todo, este ser\u00e1 un duelo directo para evitar la primera ronda de playoffs.<br \/>Ambos equipos tienen siete puntos (producto de dos victorias, un empate y una derrota) y est\u00e1n hoy fuera de las primeras ocho posiciones, por lo que, si se cerrara la primera fase ahora mismo, los dos deber\u00edan jugar una eliminatoria de 180 minutos si quieren ingresar a los octavos de final. Por eso, los tres puntos valen oro.<\/p>\n<p>Chelsea tendr\u00e1 que seguir supliendo la ausencia de Cole Palmer, el jugador m\u00e1s distintivo que tiene en la plantilla, mientras que, en el FC Barcelona, Pedri y Gavi seguir\u00e1n fuera de competencia.<\/p>\n<p>La buena noticia para los catalanes es que de a poco parecen ir recuperando la mejor versi\u00f3n de su jugador estrella Lamine Yamal, quien se anot\u00f3 dos goles y otras dos asistencias en los \u00faltimos tres encuentros, dejando atr\u00e1s una pubalgia que lo tuvo a maltraer f\u00edsicamente, y que tambi\u00e9n desat\u00f3 una pol\u00e9mica entre el club y la selecci\u00f3n de Espa\u00f1a en la \u00faltima convocatoria. Adem\u00e1s, Raphinha podr\u00eda ver m\u00e1s minutos, como parte de su puesta a punto tras una larga lesi\u00f3n. Volvi\u00f3 el \u00faltimo fin de semana en la goleada ante el Celta, aunque solo jug\u00f3 unos 10 minutos.<\/p>\n<p>\u201cLo pas\u00e9 muy mal, han sido momentos complicados. Quiero estar jugando en el campo y estar dos meses fuera sin jugar es complicado. Estar tanto tiempo parado es complicado y me ha costado mucho. Espero poder volver a jugar en este estadio, ayudar en los minutos que est\u00e9 en el campo y ayudar al equipo. Necesito ritmo de juego y espero r\u00e1pidamente recuperar mi mejor versi\u00f3n\u201d, dijo el delantero brasile\u00f1o en la previa del partido ante el Chelsea.<\/p>\n<p>Otro de los que habl\u00f3 fue el entrenador del equipo cul\u00e9, Hansi Flick quien se deshizo en elogios para el actual campe\u00f3n del Mundial de Clubes: \u201cEl Chelsea es uno de los mejores equipos del mundo, tiene grandes jugadores j\u00f3venes, un gran entrenador que le ha dado una identidad, los partidos que he visto ha estado genial. Tenemos que tener fe en nosotros y luchar ma\u00f1ana\u201d.<\/p>\n<p>\u201cEllos quieren presionar alto, nosotros tambi\u00e9n. Quieren la pelota, nosotros tambi\u00e9n. Cuando ve\u00edas al Barcelona jugar con Pep (Guardiola), todos estaban enamorados de ese equipo, todos se fijaban en ese estilo, en c\u00f3mo entrenaba\u201d, se\u00f1al\u00f3.<\/p>\n<p>En la vereda de enfrente, el que tom\u00f3 el micr\u00f3fono fue el lateral espa\u00f1ol Marc Cucurella, quien palpit\u00f3 el cruce con Yamal: \u201cSiempre es dif\u00edcil jugar con esta clase de futbolistas, pero lo de ma\u00f1ana no es un Lamine contra Cucurella. La clave ser\u00e1 quitarles el bal\u00f3n, ellos quieren siempre someterte, tenerte cerca de tu \u00e1rea. Y tambi\u00e9n el tema f\u00edsico, los duelos, si ganamos esos primeros balones tendremos muchas posibilidades de ganar el partido\u201d.<\/p>\n<p><strong>Chelsea<\/strong>: Robert S\u00e1nchez; James, Adarabioyo, Chalobah, Cucurella; Caicedo, Enzo Fern\u00e1ndez; Neto, Jo\u00e3o Pedro, Estevao; y Delap.<\/p>\n<p><strong>Barcelona<\/strong>: Joan Garc\u00eda; Kound\u00e9, Araujo, Cubars\u00ed, Balde; Eric Garc\u00eda, De Jong; Lamine Yamal, Ferm\u00edn L\u00f3pez, Ferran Torres; y Lewandowski.<\/p>\n<ul>\n<li>3 p.m. de Miami<\/li>\n<li>3 p.m. de Bogot\u00e1<\/li>\n<li>2 p.m. de Ciudad de M\u00e9xico<\/li>\n<li>5 p.m. de Buenos Aires<\/li>\n<li>9 p.m. de Espa\u00f1a<\/li>\n<\/ul>\n<p>Estados Unidos: TUDN USA, Univision, ViX Premium y Paramount+.<\/p>\n<p>M\u00e9xico: TNT Sports y HBO Max.<\/p>\n<p>Espa\u00f1a: Movistar y Movistar+.<\/p>\n<p>Colombia: ESPN y Disney+.<\/p>\n<p>Argentina: ESPN y Disney+.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La quinta jornada de la Liga de Campeones de la UEFA tiene reservado un plato fuerte: Chelsea vs. FC Barcelona. Tanto el conjunto ingl\u00e9s como el espa\u00f1ol son grandes candidatos para dejar huella en esta edici\u00f3n de la competencia y, hasta ahora, no han decepcionado. Los de Londres vienen con una excelente racha positiva de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468665","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Chelsea vs. Barcelona por la Champions League 2025\/2026: previa, posibles alineaciones, hora y c\u00f3mo ver por TV e internet - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/24\/champions-league-chelsea-barcelona-jornada-5-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chelsea vs. Barcelona por la Champions League 2025\/2026: previa, posibles alineaciones, hora y c\u00f3mo ver por TV e internet - Noticias\" \/>\n<meta property=\"og:description\" content=\"La quinta jornada de la Liga de Campeones de la UEFA tiene reservado un plato fuerte: Chelsea vs. FC Barcelona. Tanto el conjunto ingl\u00e9s como el espa\u00f1ol son grandes candidatos para dejar huella en esta edici\u00f3n de la competencia y, hasta ahora, no han decepcionado. Los de Londres vienen con una excelente racha positiva de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/24\/champions-league-chelsea-barcelona-jornada-5-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-24T23:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/24\/champions-league-chelsea-barcelona-jornada-5-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/24\/champions-league-chelsea-barcelona-jornada-5-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Chelsea vs. Barcelona por la Champions League 2025\/2026: previa, posibles alineaciones, hora y c\u00f3mo ver por TV e internet\",\"datePublished\":\"2025-11-24T23:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/24\/champions-league-chelsea-barcelona-jornada-5-orix\/\"},\"wordCount\":729,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/24\/champions-league-chelsea-barcelona-jornada-5-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/24\/champions-league-chelsea-barcelona-jornada-5-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/24\/champions-league-chelsea-barcelona-jornada-5-orix\/\",\"name\":\"Chelsea vs. Barcelona por la Champions League 2025\/2026: previa, posibles alineaciones, hora y c\u00f3mo ver por TV e internet - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-24T23:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/24\/champions-league-chelsea-barcelona-jornada-5-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/24\/champions-league-chelsea-barcelona-jornada-5-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/24\/champions-league-chelsea-barcelona-jornada-5-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chelsea vs. Barcelona por la Champions League 2025\/2026: previa, posibles alineaciones, hora y c\u00f3mo ver por TV e internet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chelsea vs. Barcelona por la Champions League 2025\/2026: previa, posibles alineaciones, hora y c\u00f3mo ver por TV e internet - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/24\/champions-league-chelsea-barcelona-jornada-5-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Chelsea vs. Barcelona por la Champions League 2025\/2026: previa, posibles alineaciones, hora y c\u00f3mo ver por TV e internet - Noticias","og_description":"La quinta jornada de la Liga de Campeones de la UEFA tiene reservado un plato fuerte: Chelsea vs. FC Barcelona. Tanto el conjunto ingl\u00e9s como el espa\u00f1ol son grandes candidatos para dejar huella en esta edici\u00f3n de la competencia y, hasta ahora, no han decepcionado. Los de Londres vienen con una excelente racha positiva de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/24\/champions-league-chelsea-barcelona-jornada-5-orix\/","og_site_name":"Noticias","article_published_time":"2025-11-24T23:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/24\/champions-league-chelsea-barcelona-jornada-5-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/24\/champions-league-chelsea-barcelona-jornada-5-orix\/"},"author":{"name":"","@id":""},"headline":"Chelsea vs. Barcelona por la Champions League 2025\/2026: previa, posibles alineaciones, hora y c\u00f3mo ver por TV e internet","datePublished":"2025-11-24T23:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/24\/champions-league-chelsea-barcelona-jornada-5-orix\/"},"wordCount":729,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/24\/champions-league-chelsea-barcelona-jornada-5-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/24\/champions-league-chelsea-barcelona-jornada-5-orix\/","url":"https:\/\/noticiasya.com\/2025\/11\/24\/champions-league-chelsea-barcelona-jornada-5-orix\/","name":"Chelsea vs. Barcelona por la Champions League 2025\/2026: previa, posibles alineaciones, hora y c\u00f3mo ver por TV e internet - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-24T23:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/24\/champions-league-chelsea-barcelona-jornada-5-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/24\/champions-league-chelsea-barcelona-jornada-5-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/24\/champions-league-chelsea-barcelona-jornada-5-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Chelsea vs. Barcelona por la Champions League 2025\/2026: previa, posibles alineaciones, hora y c\u00f3mo ver por TV e internet"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/24\/champions-league-chelsea-barcelona-jornada-5-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Chelsea vs. Barcelona por la Champions League 2025\/2026: previa, posibles alineaciones, hora y c\u00f3mo ver por TV e internet","url":"http:\/\/noticiasya.com\/colorado\/2025\/11\/24\/champions-league-chelsea-barcelona-jornada-5-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2025\/11\/24\/champions-league-chelsea-barcelona-jornada-5-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-24T23:03:51Z","datePublished":"2025-11-24T23:03:51Z","dateModified":"2025-11-24T23:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Chelsea vs. Barcelona por la Champions League 2025\\\/2026: previa, posibles alineaciones, hora y c\\u00f3mo ver por TV e internet\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2025\\\/11\\\/24\\\/champions-league-chelsea-barcelona-jornada-5-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2025\\\/11\\\/24\\\/champions-league-chelsea-barcelona-jornada-5-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-24T23:03:51Z\",\"datePublished\":\"2025-11-24T23:03:51Z\",\"dateModified\":\"2025-11-24T23:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1469842,"url":"https:\/\/noticiasya.com\/colorado\/2026\/01\/06\/supercopa-espana-2026-formato-partidos-equipos-orix\/","url_meta":{"origin":1468665,"position":0},"title":"Supercopa de Espa\u00f1a: Real Madrid, FC Barcelona, Atl\u00e9tico de Madrid y Athletic Club buscan su primer t\u00edtulo de 2026","author":"","date":"enero 6, 2026","format":false,"excerpt":"Espa\u00f1a entregar\u00e1 esta semana a su primer campe\u00f3n del a\u00f1o. Lo har\u00e1 a m\u00e1s de 4.500 kil\u00f3metros de distancia, en Arabia Saudita, nuevamente sede de la Supercopa que disputan los equipos m\u00e1s destacados de la pasada campa\u00f1a. No ser\u00e1, sin embargo, el primer campe\u00f3n del 2026 de las cinco principales\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471293,"url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/16\/barcelona-girona-lamine-yamal-penal-orix\/","url_meta":{"origin":1468665,"position":1},"title":"Lamine Yamal err\u00f3 un penal y el Barcelona se &#171;pincha&#187; en LaLiga: Real Madrid, nuevo l\u00edder","author":"","date":"febrero 16, 2026","format":false,"excerpt":"Dice el dicho que un tropez\u00f3n no es ca\u00edda, pero dos\u2026El Barcelona ten\u00eda una prueba de car\u00e1cter este lunes en Montilivi con el objetivo de recuperar el liderato en LaLiga, entonces provisoriamente a manos del Real Madrid tras su triunfo por 4 a 1 ante la Real Sociedad del s\u00e1bado.Vencer\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472319,"url":"https:\/\/noticiasya.com\/colorado\/2026\/03\/18\/cruces-cuartos-final-champions-league-orix\/","url_meta":{"origin":1468665,"position":2},"title":"As\u00ed quedaron los cuartos de final de la Champions League 2025\/2026","author":"","date":"marzo 18, 2026","format":false,"excerpt":"Ocho equipos siguen con vida en la Champions League 2025\/2026 y Espa\u00f1a es el pa\u00eds con m\u00e1s representantes, tres: Real Madrid, FC, Barcelona y el Atl\u00e9tico de Madrid. Le sigue la Premier League de Inglaterra, con dos: Arsenal y Liverpool. Portugal, con el Sporting de Lisboa, Francia, con el PSG\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469875,"url":"https:\/\/noticiasya.com\/colorado\/2026\/01\/07\/barcelona-golea-athletic-club-supercopa-espana-orix\/","url_meta":{"origin":1468665,"position":3},"title":"El FC Barcelona gana, gusta y golea, y espera por Real Madrid o Atl\u00e9tico de Madrid en la final de la Supercopa de Espa\u00f1a","author":"","date":"enero 7, 2026","format":false,"excerpt":"Caminando. As\u00ed lleg\u00f3 el FC Barcelona a la final de la Supercopa de Espa\u00f1a 2026, tras una goleada lapidaria ante el Athletic Club de Bilbao por 5 a 0. El ganador del partido ya estaba puesto antes de los primeros 40 minutos de partido, cuando el cuadro azulgrana ya ten\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470574,"url":"https:\/\/noticiasya.com\/colorado\/2026\/01\/28\/real-madrid-playoff-champions-league-orix\/","url_meta":{"origin":1468665,"position":4},"title":"Los dos rivales que podr\u00edan tocarle al Real Madrid en los playoff de la Champions League","author":"","date":"enero 28, 2026","format":false,"excerpt":"El Real Madrid pas\u00f3 una noche de terror en Portugal, y a pesar de que parec\u00eda que ten\u00eda servida la clasificaci\u00f3n a octavos de final al comienzo del d\u00eda, acab\u00f3 goleado por el Benfica de Jos\u00e9 Mourinho. Lo peor es que, a la derrota propia se le sumaron los triunfos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466495,"url":"https:\/\/noticiasya.com\/colorado\/2025\/09\/15\/real-madrid-marsella-champions-league-orix\/","url_meta":{"origin":1468665,"position":5},"title":"Real Madrid vs. Olympique Marsella, por la Champions League: previa, alineaciones, horario y c\u00f3mo ver por TV e internet","author":"","date":"septiembre 15, 2025","format":false,"excerpt":"Comienza un nuevo sue\u00f1o europeo para el Real Madrid. El Merengue debuta este martes en la Champions League 2025\/2026 con un solo objetivo: empezar con el pie derecho en su camino a la ansiada decimosexta \u201corejona\u201d.El equipo blanco comenz\u00f3 la temporada de manera perfecta. Lleva cuatro triunfos en cuatro partidos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1468665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1468665"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1468665\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1468665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1468665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1468665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}