{"id":1468708,"date":"2025-11-26T01:03:38","date_gmt":"2025-11-26T09:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/26\/gobierno-kristi-noem-vuelos-deportacion-el-salvador-trax\/"},"modified":"2025-11-26T01:03:38","modified_gmt":"2025-11-26T09:03:38","slug":"gobierno-kristi-noem-vuelos-deportacion-el-salvador-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2025\/11\/26\/gobierno-kristi-noem-vuelos-deportacion-el-salvador-trax\/","title":{"rendered":"Gobierno reconoce que Kristi Noem decidi\u00f3 continuar con los vuelos de deportaci\u00f3n a El Salvador a pesar de la orden del juez"},"content":{"rendered":"<p>El Departamento de Justicia admiti\u00f3 en una nueva presentaci\u00f3n judicial este martes que la secretaria de Seguridad Nacional, <a href=\"https:\/\/www.cnn.com\/2025\/03\/26\/americas\/kristi-noem-salvador-prison-visit-intl-latam\">Kristi Noem,<\/a> tom\u00f3 la decisi\u00f3n de continuar con los vuelos de deportaci\u00f3n que transportaban inmigrantes a una mega prisi\u00f3n en El Salvador, a pesar de la orden de un juez federal de hacer regresar los aviones.<\/p>\n<p>El Departamento de Justicia reconoci\u00f3 en la presentaci\u00f3n que fue Noem quien tom\u00f3 la decisi\u00f3n en marzo de mantener los aviones rumbo a la prisi\u00f3n conocida como CECOT, despu\u00e9s de que el juez de distrito estadounidense James Boasberg <a href=\"https:\/\/www.cnn.com\/2025\/11\/19\/politics\/boasberg-contempt-of-court-alien-enemies-act-flights\">reanudara la semana pasada su investigaci\u00f3n por desacato<\/a> para averiguar qu\u00e9 funcionarios de la administraci\u00f3n Trump fueron responsables de desobedecer sus \u00f3rdenes.<\/p>\n<p>El caso inmigratorio de alto riesgo involucra el uso por parte del presidente Donald Trump de la Ley de Enemigos Extranjeros para acelerar las deportaciones de presuntos miembros de una pandilla venezolana.<\/p>\n<p>Esto ha marcado un importante punto de conflicto pol\u00edtico y legal para la Casa Blanca de Trump en sus esfuerzos por llevar a cabo una hist\u00f3rica campa\u00f1a de deportaci\u00f3n, y la decisi\u00f3n de Noem finalmente llev\u00f3 a los migrantes a pasar meses en la infame prisi\u00f3n de El Salvador, donde <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.cnn.com%2F2025%2F11%2F12%2Famericas%2Fel-salvador-prison-cecot-venezuela-hrw-cristosal-latam-intl&#038;data=05%7C02%7Cclay.voytek%40cnn.com%7C9c525a983aaf43b8c18e08de2caf902a%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638997329719084952%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=h%2F%2F8%2Bc1eWQfBdRVdFqWMlo%2FU4SmBqTkGDlPreVgnq3o%3D&#038;reserved=0\" rel=\"noopener noreferrer\" target=\"_blank\">grupos de derechos humanos<\/a> han denunciado que fueron sometidos a tortura y otros abusos.<\/p>\n<p>\u201cLos subsecretarios de Justicia Todd Blanche y Emil Bove brindaron asesor\u00eda legal al DHS sobre la orden de la Corte relativa a los vuelos que hab\u00edan salido de Estados Unidos antes de la emisi\u00f3n de la orden\u201d, escribi\u00f3 el Gobierno en el documento.<\/p>\n<p>\u201cTras recibir dicha asesor\u00eda legal, la secretaria Noem orden\u00f3 que los detenidos de la AEA que hab\u00edan sido expulsados \u200b\u200bde Estados Unidos antes de la orden de la Corte pudieran ser transferidos a la custodia de El Salvador\u201d, agrega el texto judicial.<\/p>\n<p>El Departamento de Justicia argument\u00f3 en la presentaci\u00f3n que \u201cesa decisi\u00f3n era legal y consistente con una interpretaci\u00f3n razonable de la orden del Tribunal\u201d.<\/p>\n<p>\u201cSi bien el contenido del asesoramiento legal brindado al DHS y a la secretaria Noem es confidencial, el Gobierno ha explicado repetidamente\u2026 por qu\u00e9 sus acciones no violaron la orden del Tribunal, y mucho menos constituyeron desacato\u201d, escribi\u00f3 el gobierno.<\/p>\n<p>Y agrega: \u201cEn concreto, la orden escrita del Tribunal no pretend\u00eda exigir el regreso de los detenidos que ya hab\u00edan sido expulsados, y la directiva oral previa no constitu\u00eda una orden judicial vinculante, especialmente despu\u00e9s de la orden escrita\u201d.<\/p>\n<p>Politico fue <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.politico.com%2Fnews%2F2025%2F11%2F25%2Fkristi-noem-made-call-to-hand-over-deported-men-to-el-salvador-doj-says-00669461&#038;data=05%7C02%7Cclay.voytek%40cnn.com%7C9c525a983aaf43b8c18e08de2caf902a%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638997329719107018%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=fIGkEQE9ARw%2FeEazsatSQXGpAbyMj4WZRRTjqOGBTn0%3D&#038;reserved=0\">el primero en informar<\/a> sobre la nueva presentaci\u00f3n.<\/p>\n<p>Boasberg, designado por el ex presidente Barack Obama, hab\u00eda ordenado a mediados de marzo al gobierno que devolviera el control de los aviones que transportaban inmigrantes que estaban siendo deportados bajo la AEA, una amplia autoridad en tiempos de guerra del siglo XVIII.<\/p>\n<p>Sin embargo, los vuelos continuaron y los migrantes fueron retenidos en la prisi\u00f3n durante varios meses antes de ser liberados este verano como parte de un intercambio de prisioneros con Venezuela.<\/p>\n<p>\u201cSin duda tengo la intenci\u00f3n de averiguar qu\u00e9 sucedi\u00f3 ese d\u00eda\u201d, manifest\u00f3 Boasberg en una audiencia la semana pasada.<\/p>\n<p>En una decisi\u00f3n impactante emitida en abril, Boasberg, el juez principal del tribunal federal de primera instancia en Washington, indic\u00f3 que \u201cexiste causa probable para encontrar al Gobierno en desacato penal\u201d.<\/p>\n<p>Pero antes de que pudiera avanzar con la investigaci\u00f3n del responsable de desobedecer sus \u00f3rdenes, el Tribunal de Apelaciones del Circuito de EE.UU. de Washington suspendi\u00f3 el proceso.<\/p>\n<p>A principios de este mes, dicho tribunal allan\u00f3 el camino para que Boasberg reiniciara su investigaci\u00f3n.<\/p>\n<p>Boasberg hab\u00eda sugerido que parte de su investigaci\u00f3n podr\u00eda incluir declaraciones de funcionarios de la administraci\u00f3n o el arresto de funcionarios en su sala para que presten testimonio bajo juramento. Dichas audiencias, dijo, podr\u00edan comenzar el 1 de diciembre.<\/p>\n<p>Entre aquellos a quienes le interesa escuchar se encuentra un exabogado del Departamento de Justicia que aleg\u00f3 en una denuncia a principios de este a\u00f1o que un entonces alto funcionario del Departamento de Justicia les dijo a sus colegas en marzo que la administraci\u00f3n <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.cnn.com%2F2025%2F07%2F10%2Fpolitics%2Fjustice-department-ignore-court-orders-emil-bove-erez-reuveni&#038;data=05%7C02%7Cclay.voytek%40cnn.com%7C9c525a983aaf43b8c18e08de2caf902a%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638997329719123885%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=Eb%2FXJJF8PE8mTStHlFSw1X55nzUmBJSJc1%2FLdLtT3%2BE%3D&#038;reserved=0\">ten\u00eda la intenci\u00f3n de ignorar las \u00f3rdenes judiciales<\/a> como parte del agresivo esfuerzo de deportaci\u00f3n del Gobierno.<\/p>\n<p>Las decisiones de Boasberg este a\u00f1o en el caso <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.cnn.com%2F2025%2F03%2F18%2Fpolitics%2Fjohn-roberts-donald-trump-impeachment&#038;data=05%7C02%7Cclay.voytek%40cnn.com%7C9c525a983aaf43b8c18e08de2caf902a%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638997329719139788%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=aG3Qike%2BjXXK3c0%2FNQ7DcaxSYXOkFe5uivY3pC31ZAw%3D&#038;reserved=0\">provocaron la ira de Trump<\/a>, quien a principios de este a\u00f1o solicit\u00f3 el impeachment del juez, lo que provoc\u00f3 una inusual reprimenda del presidente del Tribunal Supremo, John Roberts. El presidente afirm\u00f3 que la manera correcta de responder a una decisi\u00f3n judicial desagradable es apelarla.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Departamento de Justicia admiti\u00f3 en una nueva presentaci\u00f3n judicial este martes que la secretaria de Seguridad Nacional, Kristi Noem, tom\u00f3 la decisi\u00f3n de continuar con los vuelos de deportaci\u00f3n que transportaban inmigrantes a una mega prisi\u00f3n en El Salvador, a pesar de la orden de un juez federal de hacer regresar los aviones. El [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468708","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gobierno reconoce que Kristi Noem decidi\u00f3 continuar con los vuelos de deportaci\u00f3n a El Salvador a pesar de la orden del juez - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/26\/gobierno-kristi-noem-vuelos-deportacion-el-salvador-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gobierno reconoce que Kristi Noem decidi\u00f3 continuar con los vuelos de deportaci\u00f3n a El Salvador a pesar de la orden del juez - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Departamento de Justicia admiti\u00f3 en una nueva presentaci\u00f3n judicial este martes que la secretaria de Seguridad Nacional, Kristi Noem, tom\u00f3 la decisi\u00f3n de continuar con los vuelos de deportaci\u00f3n que transportaban inmigrantes a una mega prisi\u00f3n en El Salvador, a pesar de la orden de un juez federal de hacer regresar los aviones. El [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/26\/gobierno-kristi-noem-vuelos-deportacion-el-salvador-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-26T09:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/26\/gobierno-kristi-noem-vuelos-deportacion-el-salvador-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/26\/gobierno-kristi-noem-vuelos-deportacion-el-salvador-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Gobierno reconoce que Kristi Noem decidi\u00f3 continuar con los vuelos de deportaci\u00f3n a El Salvador a pesar de la orden del juez\",\"datePublished\":\"2025-11-26T09:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/26\/gobierno-kristi-noem-vuelos-deportacion-el-salvador-trax\/\"},\"wordCount\":818,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/26\/gobierno-kristi-noem-vuelos-deportacion-el-salvador-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/26\/gobierno-kristi-noem-vuelos-deportacion-el-salvador-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/26\/gobierno-kristi-noem-vuelos-deportacion-el-salvador-trax\/\",\"name\":\"Gobierno reconoce que Kristi Noem decidi\u00f3 continuar con los vuelos de deportaci\u00f3n a El Salvador a pesar de la orden del juez - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-26T09:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/26\/gobierno-kristi-noem-vuelos-deportacion-el-salvador-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/26\/gobierno-kristi-noem-vuelos-deportacion-el-salvador-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/26\/gobierno-kristi-noem-vuelos-deportacion-el-salvador-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gobierno reconoce que Kristi Noem decidi\u00f3 continuar con los vuelos de deportaci\u00f3n a El Salvador a pesar de la orden del juez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gobierno reconoce que Kristi Noem decidi\u00f3 continuar con los vuelos de deportaci\u00f3n a El Salvador a pesar de la orden del juez - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/26\/gobierno-kristi-noem-vuelos-deportacion-el-salvador-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Gobierno reconoce que Kristi Noem decidi\u00f3 continuar con los vuelos de deportaci\u00f3n a El Salvador a pesar de la orden del juez - Noticias","og_description":"El Departamento de Justicia admiti\u00f3 en una nueva presentaci\u00f3n judicial este martes que la secretaria de Seguridad Nacional, Kristi Noem, tom\u00f3 la decisi\u00f3n de continuar con los vuelos de deportaci\u00f3n que transportaban inmigrantes a una mega prisi\u00f3n en El Salvador, a pesar de la orden de un juez federal de hacer regresar los aviones. El [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/26\/gobierno-kristi-noem-vuelos-deportacion-el-salvador-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-26T09:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/26\/gobierno-kristi-noem-vuelos-deportacion-el-salvador-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/26\/gobierno-kristi-noem-vuelos-deportacion-el-salvador-trax\/"},"author":{"name":"","@id":""},"headline":"Gobierno reconoce que Kristi Noem decidi\u00f3 continuar con los vuelos de deportaci\u00f3n a El Salvador a pesar de la orden del juez","datePublished":"2025-11-26T09:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/26\/gobierno-kristi-noem-vuelos-deportacion-el-salvador-trax\/"},"wordCount":818,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/26\/gobierno-kristi-noem-vuelos-deportacion-el-salvador-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/26\/gobierno-kristi-noem-vuelos-deportacion-el-salvador-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/26\/gobierno-kristi-noem-vuelos-deportacion-el-salvador-trax\/","name":"Gobierno reconoce que Kristi Noem decidi\u00f3 continuar con los vuelos de deportaci\u00f3n a El Salvador a pesar de la orden del juez - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-26T09:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/26\/gobierno-kristi-noem-vuelos-deportacion-el-salvador-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/26\/gobierno-kristi-noem-vuelos-deportacion-el-salvador-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/26\/gobierno-kristi-noem-vuelos-deportacion-el-salvador-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Gobierno reconoce que Kristi Noem decidi\u00f3 continuar con los vuelos de deportaci\u00f3n a El Salvador a pesar de la orden del juez"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2025\/11\/26\/gobierno-kristi-noem-vuelos-deportacion-el-salvador-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Gobierno reconoce que Kristi Noem decidi\u00f3 continuar con los vuelos de deportaci\u00f3n a El Salvador a pesar de la orden del juez","url":"http:\/\/noticiasya.com\/colorado\/2025\/11\/26\/gobierno-kristi-noem-vuelos-deportacion-el-salvador-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2025\/11\/26\/gobierno-kristi-noem-vuelos-deportacion-el-salvador-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-26T09:03:38Z","datePublished":"2025-11-26T09:03:38Z","dateModified":"2025-11-26T09:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Gobierno reconoce que Kristi Noem decidi\\u00f3 continuar con los vuelos de deportaci\\u00f3n a El Salvador a pesar de la orden del juez\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2025\\\/11\\\/26\\\/gobierno-kristi-noem-vuelos-deportacion-el-salvador-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2025\\\/11\\\/26\\\/gobierno-kristi-noem-vuelos-deportacion-el-salvador-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-26T09:03:38Z\",\"datePublished\":\"2025-11-26T09:03:38Z\",\"dateModified\":\"2025-11-26T09:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1469093,"url":"https:\/\/noticiasya.com\/colorado\/2025\/12\/08\/investigacion-desacato-vuelos-deportacion-trax\/","url_meta":{"origin":1468708,"position":0},"title":"Juez ampl\u00eda la investigaci\u00f3n por desacato penal en los vuelos de deportaci\u00f3n y dice que Kristi Noem no proporcion\u00f3 respuestas","author":"","date":"diciembre 8, 2025","format":false,"excerpt":"D\u00edas despu\u00e9s de que la secretaria de Seguridad Nacional, Kristi Noem, proporcionara poca informaci\u00f3n sobre sus acciones en un caso de deportaci\u00f3n de alto riesgo, un juez federal ampli\u00f3 el lunes su investigaci\u00f3n por desacato penal en el asunto, ordenando a un alto abogado del Departamento de Justicia que testifique\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460467,"url":"https:\/\/noticiasya.com\/colorado\/2025\/03\/26\/ee-uu-aumentar-deportaciones-salvador-kristi-noem-orix\/","url_meta":{"origin":1468708,"position":1},"title":"EE.UU. busca aumentar deportaciones a El Salvador, dice secretaria de Seguridad Nacional Kristi Noem","author":"","date":"marzo 26, 2025","format":false,"excerpt":"La secretaria de Seguridad Nacional de EE.UU., Kristi Noem, arrib\u00f3 este mi\u00e9rcoles a El Salvador para sostener una reuni\u00f3n con el presidente Nayib Bukele. La funcionaria adelant\u00f3 en una publicaci\u00f3n en la red social X que busca un aumento de vuelos con deportados y de expulsiones de personas de otras\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460141,"url":"https:\/\/noticiasya.com\/colorado\/2025\/03\/19\/trump-deportaciones-vuelos-ley-enemigo-extranjero-trax\/","url_meta":{"origin":1468708,"position":2},"title":"Gobierno de Trump dice que continuar\u00e1 con deportaciones, pero no planea tener m\u00e1s vuelos bajo Ley de Enemigos Extranjeros","author":"","date":"marzo 19, 2025","format":false,"excerpt":"La secretaria de prensa de la Casa Blanca, Karoline Leavitt, dijo este mi\u00e9rcoles a la prensa que los estadounidenses ver\u00e1n m\u00e1s deportaciones, pero no lleg\u00f3 a afirmar que el Gobierno continuar\u00e1 con los vuelos de deportaci\u00f3n bajo la Ley de Enemigos Extranjeros como los que se llevaron a cabo a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460029,"url":"https:\/\/noticiasya.com\/colorado\/2025\/03\/17\/cronologia-vuelos-de-deportacion-presuntos-miembros-tren-de-aragua-trax\/","url_meta":{"origin":1468708,"position":3},"title":"C\u00f3mo se desarrollaron los pol\u00e9micos vuelos de deportaci\u00f3n y la labor de un juez por detenerlos, minuto a minuto","author":"","date":"marzo 17, 2025","format":false,"excerpt":"Durante el fin de semana, el gobierno de Trump invoc\u00f3 poderes de guerra para deportar a cientos de presuntos miembros de una pandilla venezolana desde Estados Unidos a El Salvador. Tras la presentaci\u00f3n de una demanda, un juez federal orden\u00f3 al Gobierno detener temporalmente esas deportaciones.A continuaci\u00f3n, una cronolog\u00eda de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460209,"url":"https:\/\/noticiasya.com\/colorado\/2025\/03\/20\/juez-boasberg-respuesta-doj-vuelos-deportacion-trax\/","url_meta":{"origin":1468708,"position":4},"title":"Juez afirma que la respuesta del Departamento de Justicia sobre los vuelos de deportaci\u00f3n es &#171;lamentablemente insuficiente&#187;","author":"","date":"marzo 20, 2025","format":false,"excerpt":"El juez federal de distrito James Boasberg reprendi\u00f3 al Departamento de Justicia el jueves. Dijo que no se obedeci\u00f3 su orden de entregar informaci\u00f3n sobre las deportaciones que la administraci\u00f3n de Trump llev\u00f3 a cabo el fin de semana pasado.Su respuesta es la \u00faltima de un intercambio de opiniones entre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460662,"url":"https:\/\/noticiasya.com\/colorado\/2025\/03\/31\/juez-impide-gobierno-trump-termine-tps-venezolanos-trax\/","url_meta":{"origin":1468708,"position":5},"title":"Juez impide que el Gobierno de Trump anule el Estatus de Protecci\u00f3n Temporal (TPS) para venezolanos","author":"","date":"marzo 31, 2025","format":false,"excerpt":"Un juez federal impidi\u00f3 temporalmente este lunes que el Gobierno de Trump termine con las protecciones de deportaci\u00f3n para 350.000 migrantes venezolanos en Estados Unidos.A principios de este a\u00f1o, la secretaria de Seguridad Nacional, Kristi Noem, impuls\u00f3 el acabar con una forma de alivio humanitario conocida como Estatus de Protecci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1468708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1468708"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1468708\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1468708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1468708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1468708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}