{"id":1471523,"date":"2026-02-21T16:03:38","date_gmt":"2026-02-22T00:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/21\/adn-cigarrillo-asesino-adolescente-44-anos-muerte-trax\/"},"modified":"2026-02-21T16:03:38","modified_gmt":"2026-02-22T00:03:38","slug":"adn-cigarrillo-asesino-adolescente-44-anos-muerte-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2026\/02\/21\/adn-cigarrillo-asesino-adolescente-44-anos-muerte-trax\/","title":{"rendered":"El ADN de un cigarrillo ayuda a identificar al asesino de una adolescente casi 44 a\u00f1os despu\u00e9s de su muerte"},"content":{"rendered":"<p>M\u00e1s de cuatro d\u00e9cadas despu\u00e9s de que una adolescente fuera asesinada en California, el ADN encontrado en un cigarrillo desechado ayud\u00f3 a las autoridades a capturar a su asesino.<\/p>\n<p>Sarah Geer, de 13 a\u00f1os, fue vista por \u00faltima vez saliendo de la casa de una amiga en Cloverdale, California, la noche del 23 de mayo de 1982.<\/p>\n<p>A la ma\u00f1ana siguiente, un bombero que caminaba a casa despu\u00e9s del trabajo encontr\u00f3 su cuerpo, inform\u00f3 la Fiscal\u00eda del Condado de Sonoma en <a href=\"https:\/\/da.sonomacounty.ca.gov\/sonoma-county-jury-returns-guilty-verdict-on-1982-cloverdale-murder\">un comunicado<\/a>. Seg\u00fan las autoridades, hab\u00eda sido arrastrada por un callej\u00f3n hasta un \u00e1rea apartada cerca de un edificio de apartamentos y detr\u00e1s de una cerca, donde fue violada y estrangulada.<\/p>\n<p>Su muerte fue declarada homicidio, pero debido a las \u201climitadas t\u00e9cnicas forenses de la \u00e9poca\u201d, no se identific\u00f3 a ning\u00fan sospechoso y el caso qued\u00f3 sin resolver durante d\u00e9cadas, dijeron los fiscales.<\/p>\n<p>Casi 44 a\u00f1os despu\u00e9s del asesinato de Sarah, un jurado declar\u00f3 a James Unick, de 64 a\u00f1os, culpable de matarla el 13 de febrero. Ese d\u00eda habr\u00eda sido el cumplea\u00f1os n\u00famero 57 de la v\u00edctima, inform\u00f3 la Fiscal\u00eda del Condado de Sonoma a CNN.<\/p>\n<p>La genealog\u00eda gen\u00e9tica, que combina evidencia de ADN y genealog\u00eda tradicional, ayud\u00f3 a vincular el ADN de Unick obtenido de la colilla de un cigarrillo con el ADN hallado en la ropa de Sarah, seg\u00fan los fiscales.<\/p>\n<p>\u201cEste veredicto de culpabilidad es testimonio de todos los que nunca dejaron de buscar al asesino de Sarah\u201d, dijo la fiscal del distrito Carla Rodr\u00edguez en el comunicado. \u201cEste es el caso m\u00e1s antiguo presentado ante un jurado del Condado de Sonoma. Aunque 44 a\u00f1os es demasiado tiempo para esperar, finalmente se ha hecho justicia, tanto para los seres queridos de Sarah como para su comunidad\u201d.<\/p>\n<p>El primer avance en el caso se produjo en 2003, cuando los investigadores desarrollaron un perfil de ADN basado en semen recolectado de la ropa interior de Sarah, dijeron los fiscales.<\/p>\n<p>Sin embargo, el perfil no coincid\u00eda con ninguna persona cuyo ADN estuviera disponible para comparaci\u00f3n en las bases de datos de las fuerzas del orden en ese momento, seg\u00fan el comunicado, y la investigaci\u00f3n volvi\u00f3 a estancarse. Esas bases de datos incluyen informaci\u00f3n de delincuentes conocidos.<\/p>\n<p>En 2021, el Departamento de Polic\u00eda de Cloverdale <a href=\"https:\/\/www.facebook.com\/CloverdalePoliceDepartment\/posts\/pfbid02H2Z9LEwj2XXS5EvcT4KSk7zHwgLZsK2Bwvyd3z225LE8wTE12zanYw8VZizksD3kl\">reabri\u00f3 la investigaci\u00f3n sobre la muerte de Sarah<\/a>. El departamento indic\u00f3 que hab\u00eda estado en comunicaci\u00f3n con una firma privada de investigaci\u00f3n a finales de 2019 y que se asoci\u00f3 con ella con la esperanza de que pudiera revisar la evidencia del caso \u201ccon los \u00faltimos avances tecnol\u00f3gicos en el trabajo de casos archivados\u201d.<\/p>\n<p>La investigaci\u00f3n tambi\u00e9n cont\u00f3 con la colaboraci\u00f3n del FBI para ayudar a identificar una posible coincidencia con el perfil de ADN de 2003.<\/p>\n<p>\u201cEl FBI, con acceso a bases de datos geneal\u00f3gicas familiares, concluy\u00f3 que la fuente de la evidencia de ADN recolectada de Sarah pertenec\u00eda a uno de cuatro hermanos, incluido James Unick\u201d, dijeron los fiscales.<\/p>\n<p>Una vez que los investigadores redujeron la lista de sospechosos a los cuatro hermanos Unick, el FBI \u201cvigil\u00f3 al acusado y recolect\u00f3 un cigarrillo desechado que hab\u00eda estado fumando\u201d, dijeron los fiscales.<\/p>\n<p>Un an\u00e1lisis de ADN del cigarrillo confirm\u00f3 que el ADN de James Unick coincid\u00eda con el perfil de 2003, as\u00ed como con otras muestras de ADN recolectadas de la ropa de Sarah el d\u00eda en que muri\u00f3.<\/p>\n<p>Los investigadores lograron resolver el caso gracias al campo emergente de la <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/19\/eeuu\/adn-caso-guthrie-investigadores-genealogia-genetica-trax\">genealog\u00eda gen\u00e9tica<\/a>, que combina el an\u00e1lisis de ADN y la investigaci\u00f3n de \u00e1rboles familiares.<\/p>\n<p>B\u00e1sicamente, una muestra de ADN se compara con bases de datos de acceso p\u00fablico de millones de personas que han aportado su perfil gen\u00e9tico, y los investigadores pueden reconstruir un \u00e1rbol geneal\u00f3gico que conduce a un sospechoso.<\/p>\n<p>En 2018, la genealog\u00eda gen\u00e9tica llev\u00f3 al arresto del llamado <a href=\"https:\/\/www.cnn.com\/2019\/06\/12\/us\/cold-case-genetic-genealogy-washington\/index.html\">\u201cGolden State Killer\u201d<\/a>, y recientemente ha ayudado a resolver otros casos, incluido un <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/11\/09\/mujer-asesinada-1974-autostop-chicago-50-anos-asesino-trax\">asesinato de 1974 en Wisconsin<\/a> y otro de 1988 en Washington. Investigadores del caso de la desaparici\u00f3n de Nancy Guthrie anunciaron recientemente que recurrir\u00e1n a la genealog\u00eda gen\u00e9tica para analizar ADN desconocido hallado en su casa.<\/p>\n<p>La polic\u00eda arrest\u00f3 a Unick en julio de 2024 en su vivienda en Willows, California.<\/p>\n<p>\u201cHoy representa una victoria agridulce para la justicia\u201d, dijo el jefe de polic\u00eda de Cloverdale, Chris Parker, en <a href=\"https:\/\/www.facebook.com\/CloverdalePoliceDepartment\/posts\/pfbid0YoJ5QQ3LrdqT2kZ2nQtk1p48SUBAjF83LVvHv5rCPUu6BLkwj3JRjCaecq4Wo4xQl\">un comunicado de 2024<\/a> tras el arresto de Unick. \u201cAunque nada puede deshacer el dolor infligido a la familia Geer y a nuestra comunidad, finalmente podemos ofrecer algo de consuelo al saber que el responsable rendir\u00e1 cuentas\u201d.<\/p>\n<p>En el momento de su arresto, Unick sostuvo que no conoc\u00eda a Sarah ni recordaba los hechos de la noche de su muerte. Durante el juicio, que dur\u00f3 un mes, su versi\u00f3n cambi\u00f3.<\/p>\n<p>Unick testific\u00f3 que la adolescente \u201cle propuso tener relaciones sexuales mientras \u00e9l jugaba un videojuego\u201d en una sala de juegos en Cloverdale, y afirm\u00f3 que ambos mantuvieron relaciones sexuales consensuadas en una colina cerca de un r\u00edo local, seg\u00fan los fiscales.<\/p>\n<p>Los fiscales tambi\u00e9n se\u00f1alaron que Unick insinu\u00f3 que Sarah fue agredida y asesinada por otra persona m\u00e1s tarde esa noche.<\/p>\n<p>Los miembros del jurado tambi\u00e9n escucharon a los amigos de Sarah que hab\u00edan pasado tiempo con ella durante su \u00faltimo fin de semana con vida en 1982.<\/p>\n<p>Tras dos horas de deliberaciones, el jurado rechaz\u00f3 la versi\u00f3n de Unick y lo declar\u00f3 culpable de asesinato, dijeron los fiscales.<\/p>\n<p>Como resultado del veredicto de culpabilidad, y despu\u00e9s de que el jurado determinara que \u201cel acusado cometi\u00f3 una circunstancia especial relacionada con la agresi\u00f3n sexual durante la comisi\u00f3n del asesinato\u201d, Unick ser\u00e1 condenado a cadena perpetua sin posibilidad de libertad condicional, seg\u00fan los fiscales.<\/p>\n<p>La sentencia est\u00e1 programada para el 23 de abril.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s de cuatro d\u00e9cadas despu\u00e9s de que una adolescente fuera asesinada en California, el ADN encontrado en un cigarrillo desechado ayud\u00f3 a las autoridades a capturar a su asesino. Sarah Geer, de 13 a\u00f1os, fue vista por \u00faltima vez saliendo de la casa de una amiga en Cloverdale, California, la noche del 23 de mayo [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1471523","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El ADN de un cigarrillo ayuda a identificar al asesino de una adolescente casi 44 a\u00f1os despu\u00e9s de su muerte - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/21\/adn-cigarrillo-asesino-adolescente-44-anos-muerte-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El ADN de un cigarrillo ayuda a identificar al asesino de una adolescente casi 44 a\u00f1os despu\u00e9s de su muerte - Noticias\" \/>\n<meta property=\"og:description\" content=\"M\u00e1s de cuatro d\u00e9cadas despu\u00e9s de que una adolescente fuera asesinada en California, el ADN encontrado en un cigarrillo desechado ayud\u00f3 a las autoridades a capturar a su asesino. Sarah Geer, de 13 a\u00f1os, fue vista por \u00faltima vez saliendo de la casa de una amiga en Cloverdale, California, la noche del 23 de mayo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/21\/adn-cigarrillo-asesino-adolescente-44-anos-muerte-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-22T00:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/21\/adn-cigarrillo-asesino-adolescente-44-anos-muerte-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/21\/adn-cigarrillo-asesino-adolescente-44-anos-muerte-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El ADN de un cigarrillo ayuda a identificar al asesino de una adolescente casi 44 a\u00f1os despu\u00e9s de su muerte\",\"datePublished\":\"2026-02-22T00:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/21\/adn-cigarrillo-asesino-adolescente-44-anos-muerte-trax\/\"},\"wordCount\":1040,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/21\/adn-cigarrillo-asesino-adolescente-44-anos-muerte-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/21\/adn-cigarrillo-asesino-adolescente-44-anos-muerte-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/21\/adn-cigarrillo-asesino-adolescente-44-anos-muerte-trax\/\",\"name\":\"El ADN de un cigarrillo ayuda a identificar al asesino de una adolescente casi 44 a\u00f1os despu\u00e9s de su muerte - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-22T00:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/21\/adn-cigarrillo-asesino-adolescente-44-anos-muerte-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/21\/adn-cigarrillo-asesino-adolescente-44-anos-muerte-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/21\/adn-cigarrillo-asesino-adolescente-44-anos-muerte-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El ADN de un cigarrillo ayuda a identificar al asesino de una adolescente casi 44 a\u00f1os despu\u00e9s de su muerte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El ADN de un cigarrillo ayuda a identificar al asesino de una adolescente casi 44 a\u00f1os despu\u00e9s de su muerte - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/21\/adn-cigarrillo-asesino-adolescente-44-anos-muerte-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El ADN de un cigarrillo ayuda a identificar al asesino de una adolescente casi 44 a\u00f1os despu\u00e9s de su muerte - Noticias","og_description":"M\u00e1s de cuatro d\u00e9cadas despu\u00e9s de que una adolescente fuera asesinada en California, el ADN encontrado en un cigarrillo desechado ayud\u00f3 a las autoridades a capturar a su asesino. Sarah Geer, de 13 a\u00f1os, fue vista por \u00faltima vez saliendo de la casa de una amiga en Cloverdale, California, la noche del 23 de mayo [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/21\/adn-cigarrillo-asesino-adolescente-44-anos-muerte-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-22T00:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/21\/adn-cigarrillo-asesino-adolescente-44-anos-muerte-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/21\/adn-cigarrillo-asesino-adolescente-44-anos-muerte-trax\/"},"author":{"name":"","@id":""},"headline":"El ADN de un cigarrillo ayuda a identificar al asesino de una adolescente casi 44 a\u00f1os despu\u00e9s de su muerte","datePublished":"2026-02-22T00:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/21\/adn-cigarrillo-asesino-adolescente-44-anos-muerte-trax\/"},"wordCount":1040,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/21\/adn-cigarrillo-asesino-adolescente-44-anos-muerte-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/21\/adn-cigarrillo-asesino-adolescente-44-anos-muerte-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/21\/adn-cigarrillo-asesino-adolescente-44-anos-muerte-trax\/","name":"El ADN de un cigarrillo ayuda a identificar al asesino de una adolescente casi 44 a\u00f1os despu\u00e9s de su muerte - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-22T00:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/21\/adn-cigarrillo-asesino-adolescente-44-anos-muerte-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/21\/adn-cigarrillo-asesino-adolescente-44-anos-muerte-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/21\/adn-cigarrillo-asesino-adolescente-44-anos-muerte-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El ADN de un cigarrillo ayuda a identificar al asesino de una adolescente casi 44 a\u00f1os despu\u00e9s de su muerte"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/21\/adn-cigarrillo-asesino-adolescente-44-anos-muerte-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El ADN de un cigarrillo ayuda a identificar al asesino de una adolescente casi 44 a\u00f1os despu\u00e9s de su muerte","url":"http:\/\/noticiasya.com\/colorado\/2026\/02\/21\/adn-cigarrillo-asesino-adolescente-44-anos-muerte-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2026\/02\/21\/adn-cigarrillo-asesino-adolescente-44-anos-muerte-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-22T00:03:38Z","datePublished":"2026-02-22T00:03:38Z","dateModified":"2026-02-22T00:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El ADN de un cigarrillo ayuda a identificar al asesino de una adolescente casi 44 a\\u00f1os despu\\u00e9s de su muerte\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/02\\\/21\\\/adn-cigarrillo-asesino-adolescente-44-anos-muerte-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/02\\\/21\\\/adn-cigarrillo-asesino-adolescente-44-anos-muerte-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-22T00:03:38Z\",\"datePublished\":\"2026-02-22T00:03:38Z\",\"dateModified\":\"2026-02-22T00:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1457901,"url":"https:\/\/noticiasya.com\/colorado\/2025\/01\/26\/asesinato-adolescente-honolulu-adn-arresto-trax\/","url_meta":{"origin":1471523,"position":0},"title":"Casi medio siglo despu\u00e9s del asesinato de una adolescente en Honolulu, modernas pruebas de ADN llevan a un arresto","author":"","date":"enero 26, 2025","format":false,"excerpt":"Susie Chun Oakland era una estudiante de segundo a\u00f1o cuando lleg\u00f3 a la Escuela Secundaria McKinley en Honolulu \u2014la escena del crimen\u2014 una ma\u00f1ana de lunes hace casi medio siglo.Uno de sus maestros acababa de encontrar el cuerpo de otra estudiante en el segundo piso del edificio de ingl\u00e9s, dijo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445995,"url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/25\/adolescente-oregon-mas-50-anos-se-identifican-despues-de-cargo-genealogia-trax\/","url_meta":{"origin":1471523,"position":1},"title":"Los restos de un adolescente de Oreg\u00f3n que desapareci\u00f3 hace m\u00e1s de 50 a\u00f1os se identifican despu\u00e9s de que alguien carg\u00f3 su ADN en un sitio de genealog\u00eda.","author":"","date":"febrero 25, 2024","format":false,"excerpt":"(CNN) -- Los restos de una adolescente de Portland, Oreg\u00f3n, que desapareci\u00f3 a finales de la d\u00e9cada de 1960 han sido identificados mediante pruebas de ADN avanzadas m\u00e1s de 50 a\u00f1os despu\u00e9s de su desaparici\u00f3n, dijeron las autoridades.En 1970, un l\u00edder de una tropa de Boy Scouts descubri\u00f3 los restos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456053,"url":"https:\/\/noticiasya.com\/colorado\/2024\/11\/24\/adn-hombre-poligrafo-sospechoso-homicidio-caso-sin-resolver-trax\/","url_meta":{"origin":1471523,"position":2},"title":"Prueba de ADN confirma que un hombre que pas\u00f3 la prueba del pol\u00edgrafo es sospechoso de homicidio en un caso sin resolver de 1979","author":"","date":"noviembre 24, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Despu\u00e9s de 45 a\u00f1os, las autoridades de California finalmente pudieron decirle a la familia Gonz\u00e1lez qui\u00e9n creen que mat\u00f3 a su ser querido. La Oficina del Sheriff del Condado de Riverside utiliz\u00f3 ADN y genealog\u00eda forense para identificar al presunto asesino, que result\u00f3 ser el mismo hombre que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473337,"url":"https:\/\/noticiasya.com\/colorado\/2026\/04\/20\/d4vd-asesinato-rivas-tesla-trax\/","url_meta":{"origin":1471523,"position":3},"title":"Acusan de asesinato a d4vd por la muerte de la adolescente cuyo cuerpo fue hallado en el Tesla del artista","author":"","date":"abril 20, 2026","format":false,"excerpt":"David Anthony Burke, m\u00e1s conocido como el artista de pop alternativo d4vd, est\u00e1 siendo acusado en relaci\u00f3n con el homicidio de Celeste Rivas Hern\u00e1ndez, de 14 a\u00f1os, siete meses despu\u00e9s de que el cuerpo en descomposici\u00f3n de la ni\u00f1a fuera descubierto en su Tesla aparentemente abandonado, seg\u00fan anunci\u00f3 el lunes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455351,"url":"https:\/\/noticiasya.com\/colorado\/2024\/10\/25\/illinois-chicago-area-craneo-identificado-1866-trax\/","url_meta":{"origin":1471523,"position":4},"title":"El cr\u00e1neo hallado en 1978 durante las reformas de una casa se identifica con el de una mujer que muri\u00f3 hace m\u00e1s de 150 a\u00f1os","author":"","date":"octubre 25, 2024","format":false,"excerpt":"(CNN) --\u00a0 Hace m\u00e1s de 45 a\u00f1os se encontr\u00f3 el cr\u00e1neo de una adolescente del siglo XIX durante las obras de reforma de una casa en los suburbios de Chicago. Gracias a los avances de la tecnolog\u00eda del ADN, por fin sabemos su nombre.La oficina forense del condado de Kane\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455058,"url":"https:\/\/noticiasya.com\/colorado\/2024\/10\/12\/colorado-identifican-restos-humanos-congelador-chica-desaparecida-2005-trax\/","url_meta":{"origin":1471523,"position":5},"title":"Identifican restos humanos hallados en un congelador en Colorado como los de una chica de 16 a\u00f1os desaparecida durante casi 20 a\u00f1os","author":"","date":"octubre 12, 2024","format":false,"excerpt":"(CNN) -- La cabeza y las manos humanas descubiertas en el congelador de una casa de Colorado en enero fueron identificadas como pertenecientes a una chica de 16 a\u00f1os que llevaba casi 20 a\u00f1os desaparecida, seg\u00fan las autoridades locales.Amanda Overstreet fue identificada como la v\u00edctima mediante pruebas de ADN, seg\u00fan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1471523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1471523"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1471523\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1471523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1471523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1471523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}