{"id":1471564,"date":"2026-02-23T13:03:38","date_gmt":"2026-02-23T21:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/23\/nick-reiner-se-declara-inocente-homicidio-rob-michele-reiner-trax\/"},"modified":"2026-02-23T13:03:38","modified_gmt":"2026-02-23T21:03:38","slug":"nick-reiner-se-declara-inocente-homicidio-rob-michele-reiner-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2026\/02\/23\/nick-reiner-se-declara-inocente-homicidio-rob-michele-reiner-trax\/","title":{"rendered":"Nick Reiner se declara inocente de los cargos de homicidio por la muerte de sus padres, Rob y Michele Reiner"},"content":{"rendered":"<p><a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/15\/entretenimiento\/quien-es-nick-reiner-hijo-rob-y-michele-trax\">Nick Reiner<\/a>, el hombre de 32 a\u00f1os acusado de dos cargos de homicidio premeditado en relaci\u00f3n con el mortal apu\u00f1alamiento de sus padres, el famoso director Rob Reiner y la fot\u00f3grafa Michele Singer Reiner, se declar\u00f3 inocente en un tribunal de Los \u00c1ngeles el lunes.<\/p>\n<p>Reiner renunci\u00f3 a su derecho a una audiencia preliminar r\u00e1pida y no se le concedi\u00f3 fianza. Reiner, que ten\u00eda la cabeza rapada, vest\u00eda un overol marr\u00f3n proporcionado por la prisi\u00f3n y llevaba grilletes en las mu\u00f1ecas durante su comparecencia.<\/p>\n<p>Una audiencia preliminar est\u00e1 provisionalmente programada para el 29 de abril.<\/p>\n<p>Rob y Michele Reiner<a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/18\/eeuu\/que-ocurrio-antes-y-despues-muerte-rob-michele-reiner-trax\"> fueron encontrados tras ser apu\u00f1alados<\/a> hasta la muerte en su casa de Los \u00c1ngeles a finales del a\u00f1o pasado.<\/p>\n<p>Reiner ha estado bajo custodia desde su arresto inicial en diciembre.<\/p>\n<p>Los cargos conllevan una pena m\u00e1xima de cadena perpetua sin libertad condicional o la pena de muerte.<\/p>\n<p>El fiscal de distrito del condado de Los \u00c1ngeles, Nathan Hochman, dijo a los periodistas fuera del tribunal despu\u00e9s de la audiencia que su oficina a\u00fan no ha determinado si buscar\u00e1n la pena de muerte.<\/p>\n<p>\u201cNos tomamos el proceso en el que determinamos si se debe solicitar la pena de muerte extremadamente en serio, y pasa por un proceso muy riguroso\u201d, dijo. \u201cAnalizaremos todas las circunstancias agravantes y atenuantes, e invitamos a la defensa a presentar, tanto por escrito como oralmente en una reuni\u00f3n, cualquier argumento que deseen considerar para decidir si seguimos adelante o no con la pena de muerte\u201d.<\/p>\n<p><a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/16\/entretenimiento\/que-paso-muertes-rob-reiner-michele-claves-orix\">Rob y Michele Reiner<\/a> ten\u00edan tres hijos juntos: Jake, Romy y Nick.<\/p>\n<p>CNN se ha puesto en contacto con un portavoz de Romy y Jake Reiner para obtener comentarios.<\/p>\n<p>El mes pasado, Reiner <a href=\"https:\/\/www.cnn.com\/2026\/01\/07\/entertainment\/nick-rob-michele-reiner-arraignment\">no present\u00f3 una declaraci\u00f3n durante su primera comparecencia<\/a> porque su abogado de alto perfil, Alan Jackson, se retir\u00f3 como su defensor. La defensora p\u00fablica adjunta Kimberly Greene lo representa ahora, seg\u00fan la Oficina del Defensor P\u00fablico del Condado de Los \u00c1ngeles.<\/p>\n<p>\u201cLa Oficina del Defensor P\u00fablico reconoce la tragedia inimaginable que esto representa para la familia Reiner y la comunidad de Los \u00c1ngeles. Nuestros corazones est\u00e1n con la familia Reiner mientras atraviesan este momento dif\u00edcil\u201d, dijo Garcia <a href=\"https:\/\/pubdef.lacounty.gov\/news\/media-release-la-public-defender-issues-statement-on-appointment-to-represent-nick-reiner\/\">en un comunicado<\/a> en ese momento. \u201cPedimos su paciencia y compasi\u00f3n mientras el caso avanza en el proceso legal, ya que estos asuntos son complicados y requieren consideraci\u00f3n cuidadosa\u201d.<\/p>\n<p>Jackson dijo a los periodistas en ese momento que, aunque su equipo sigue comprometido con Reiner y sus mejores intereses, circunstancias fuera de su control o del control de Reiner \u201chicieron imposible\u201d que su equipo continuara represent\u00e1ndolo.<\/p>\n<p>Jackson tambi\u00e9n dijo que, tras investigar el asunto, creen que \u201cde acuerdo con las leyes de este estado, conforme a la ley de California, Nick Reiner no es culpable de homicidio\u201d.<\/p>\n<p>Los fiscales dicen que Reiner apu\u00f1al\u00f3 a sus padres hasta la muerte en las primeras horas de la ma\u00f1ana en el dormitorio principal de la casa familiar. Un miembro de la familia hab\u00eda dicho previamente a los detectives que Reiner tambi\u00e9n hab\u00eda estado viviendo en la propiedad en una casa de hu\u00e9spedes y que discuti\u00f3 con su padre en la fiesta navide\u00f1a de Conan O\u2019Brien la noche anterior.<\/p>\n<p>Reiner ha sido abierto sobre <a href=\"https:\/\/www.cnn.com\/2025\/12\/15\/entertainment\/nick-reiner-wwk-being-charlie\">sus problemas con la adicci\u00f3n, la salud mental<\/a> y su experiencia en m\u00faltiples periodos de rehabilitaci\u00f3n. En 2015, canaliz\u00f3 sus experiencias en una pel\u00edcula que coescribi\u00f3 acerca de una familia que lucha con la adicci\u00f3n de un hijo, que fue dirigida por su padre.<\/p>\n<p>Rob Reiner fue una figura querida y m\u00e1s grande que la vida en Hollywood. Su papel revelaci\u00f3n como actor lleg\u00f3 en 1971 en la televisi\u00f3n con \u201cAll in the Family\u201d, en la que interpret\u00f3 a Mike Stivic, el yerno de Archie y Edith Bunker. Rob Reiner gan\u00f3 dos premios Emmy por ese papel.<\/p>\n<p>Como actor y director a lo largo de su estimada carrera de d\u00e9cadas, su obra incluy\u00f3 de todo, desde comedias de culto como \u201cThe Princess Bride\u201d hasta cl\u00e1sicos del cine rom\u00e1ntico como \u201cWhen Harry Met Sally\u201d y el drama legal nominado al Oscar \u201cA Few Good Men\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nick Reiner, el hombre de 32 a\u00f1os acusado de dos cargos de homicidio premeditado en relaci\u00f3n con el mortal apu\u00f1alamiento de sus padres, el famoso director Rob Reiner y la fot\u00f3grafa Michele Singer Reiner, se declar\u00f3 inocente en un tribunal de Los \u00c1ngeles el lunes. Reiner renunci\u00f3 a su derecho a una audiencia preliminar r\u00e1pida [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1471564","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nick Reiner se declara inocente de los cargos de homicidio por la muerte de sus padres, Rob y Michele Reiner - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/23\/nick-reiner-se-declara-inocente-homicidio-rob-michele-reiner-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nick Reiner se declara inocente de los cargos de homicidio por la muerte de sus padres, Rob y Michele Reiner - Noticias\" \/>\n<meta property=\"og:description\" content=\"Nick Reiner, el hombre de 32 a\u00f1os acusado de dos cargos de homicidio premeditado en relaci\u00f3n con el mortal apu\u00f1alamiento de sus padres, el famoso director Rob Reiner y la fot\u00f3grafa Michele Singer Reiner, se declar\u00f3 inocente en un tribunal de Los \u00c1ngeles el lunes. Reiner renunci\u00f3 a su derecho a una audiencia preliminar r\u00e1pida [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/23\/nick-reiner-se-declara-inocente-homicidio-rob-michele-reiner-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-23T21:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/23\/nick-reiner-se-declara-inocente-homicidio-rob-michele-reiner-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/23\/nick-reiner-se-declara-inocente-homicidio-rob-michele-reiner-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Nick Reiner se declara inocente de los cargos de homicidio por la muerte de sus padres, Rob y Michele Reiner\",\"datePublished\":\"2026-02-23T21:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/23\/nick-reiner-se-declara-inocente-homicidio-rob-michele-reiner-trax\/\"},\"wordCount\":751,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/23\/nick-reiner-se-declara-inocente-homicidio-rob-michele-reiner-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/23\/nick-reiner-se-declara-inocente-homicidio-rob-michele-reiner-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/23\/nick-reiner-se-declara-inocente-homicidio-rob-michele-reiner-trax\/\",\"name\":\"Nick Reiner se declara inocente de los cargos de homicidio por la muerte de sus padres, Rob y Michele Reiner - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-23T21:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/23\/nick-reiner-se-declara-inocente-homicidio-rob-michele-reiner-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/23\/nick-reiner-se-declara-inocente-homicidio-rob-michele-reiner-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/23\/nick-reiner-se-declara-inocente-homicidio-rob-michele-reiner-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nick Reiner se declara inocente de los cargos de homicidio por la muerte de sus padres, Rob y Michele Reiner\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nick Reiner se declara inocente de los cargos de homicidio por la muerte de sus padres, Rob y Michele Reiner - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/23\/nick-reiner-se-declara-inocente-homicidio-rob-michele-reiner-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Nick Reiner se declara inocente de los cargos de homicidio por la muerte de sus padres, Rob y Michele Reiner - Noticias","og_description":"Nick Reiner, el hombre de 32 a\u00f1os acusado de dos cargos de homicidio premeditado en relaci\u00f3n con el mortal apu\u00f1alamiento de sus padres, el famoso director Rob Reiner y la fot\u00f3grafa Michele Singer Reiner, se declar\u00f3 inocente en un tribunal de Los \u00c1ngeles el lunes. Reiner renunci\u00f3 a su derecho a una audiencia preliminar r\u00e1pida [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/23\/nick-reiner-se-declara-inocente-homicidio-rob-michele-reiner-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-23T21:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/23\/nick-reiner-se-declara-inocente-homicidio-rob-michele-reiner-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/23\/nick-reiner-se-declara-inocente-homicidio-rob-michele-reiner-trax\/"},"author":{"name":"","@id":""},"headline":"Nick Reiner se declara inocente de los cargos de homicidio por la muerte de sus padres, Rob y Michele Reiner","datePublished":"2026-02-23T21:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/23\/nick-reiner-se-declara-inocente-homicidio-rob-michele-reiner-trax\/"},"wordCount":751,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/23\/nick-reiner-se-declara-inocente-homicidio-rob-michele-reiner-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/23\/nick-reiner-se-declara-inocente-homicidio-rob-michele-reiner-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/23\/nick-reiner-se-declara-inocente-homicidio-rob-michele-reiner-trax\/","name":"Nick Reiner se declara inocente de los cargos de homicidio por la muerte de sus padres, Rob y Michele Reiner - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-23T21:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/23\/nick-reiner-se-declara-inocente-homicidio-rob-michele-reiner-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/23\/nick-reiner-se-declara-inocente-homicidio-rob-michele-reiner-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/23\/nick-reiner-se-declara-inocente-homicidio-rob-michele-reiner-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Nick Reiner se declara inocente de los cargos de homicidio por la muerte de sus padres, Rob y Michele Reiner"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/23\/nick-reiner-se-declara-inocente-homicidio-rob-michele-reiner-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Nick Reiner se declara inocente de los cargos de homicidio por la muerte de sus padres, Rob y Michele Reiner","url":"http:\/\/noticiasya.com\/colorado\/2026\/02\/23\/nick-reiner-se-declara-inocente-homicidio-rob-michele-reiner-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2026\/02\/23\/nick-reiner-se-declara-inocente-homicidio-rob-michele-reiner-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-23T21:03:38Z","datePublished":"2026-02-23T21:03:38Z","dateModified":"2026-02-23T21:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Nick Reiner se declara inocente de los cargos de homicidio por la muerte de sus padres, Rob y Michele Reiner\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/02\\\/23\\\/nick-reiner-se-declara-inocente-homicidio-rob-michele-reiner-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/02\\\/23\\\/nick-reiner-se-declara-inocente-homicidio-rob-michele-reiner-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-23T21:03:38Z\",\"datePublished\":\"2026-02-23T21:03:38Z\",\"dateModified\":\"2026-02-23T21:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1469316,"url":"https:\/\/noticiasya.com\/colorado\/2025\/12\/16\/homicidio-premeditado-nick-reiner-muerte-rob-reiner-trax\/","url_meta":{"origin":1471564,"position":0},"title":"Acusan a Nick Reiner de homicidio premeditado tras la muerte de sus padres, Rob y Michele","author":"","date":"diciembre 16, 2025","format":false,"excerpt":"El fiscal de distrito del condado de Los \u00c1ngeles, Nathan Hochman, anunci\u00f3 dos cargos penales, incluido homicidio premeditado, contra Nick Reiner, quien est\u00e1 acusado de matar a sus padres.Los cargos conllevan una sentencia m\u00e1xima de cadena perpetua sin posibilidad de libertad condicional o la pena de muerte. Hochman dijo que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469307,"url":"https:\/\/noticiasya.com\/colorado\/2025\/12\/16\/que-paso-muertes-rob-reiner-michele-claves-orix\/","url_meta":{"origin":1471564,"position":1},"title":"\u00bfQu\u00e9 pas\u00f3 en la muerte de Rob Reiner y su esposa, de qu\u00e9 acusan al hijo y c\u00f3mo habr\u00edan sido los homicidios?","author":"","date":"diciembre 16, 2025","format":false,"excerpt":"Nick Reiner, de 32 a\u00f1os, est\u00e1 detenido sin derecho a fianza despu\u00e9s de que sus padres \u2014el actor y director de Hollywood Rob Reiner, de 78 a\u00f1os, y su esposa, Michele Singer Reiner, de 67\u2014 fueran encontrados muertos en la casa familiar de Brentwood, en Los \u00c1ngeles, un d\u00eda despu\u00e9s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469409,"url":"https:\/\/noticiasya.com\/colorado\/2025\/12\/18\/que-ocurrio-antes-y-despues-muerte-rob-michele-reiner-trax\/","url_meta":{"origin":1471564,"position":2},"title":"Qu\u00e9 ocurri\u00f3 en las horas previas y posteriores a la muerte de Rob y Michele Reiner","author":"","date":"diciembre 18, 2025","format":false,"excerpt":"En las horas posteriores a que la polic\u00eda encontrara los cuerpos de Rob Reiner y Michele Singer Reiner dentro de su casa en Brentwood, California, se intensific\u00f3 la especulaci\u00f3n sobre qu\u00e9 pudo haber llevado a alguien a asesinar al querido director de Hollywood y de su esposa, una carism\u00e1tica fot\u00f3grafa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469368,"url":"https:\/\/noticiasya.com\/colorado\/2025\/12\/17\/rob-michele-reiner-amor-hijo-homicidio-trax\/","url_meta":{"origin":1471564,"position":3},"title":"Lo que Rob y Michele Reiner dec\u00edan del amor que le ten\u00edan a su hijo Nick, acusado de homicidio premeditado tras su muerte","author":"","date":"diciembre 17, 2025","format":false,"excerpt":"Durante un tiempo, en los a\u00f1os 90, el cineasta Rob Reiner apart\u00f3 su atenci\u00f3n de las pel\u00edculas que lo hab\u00edan hecho famoso para enfocarse en un proyecto que lo apasionaba.La teor\u00eda del apego estaba en pleno auge: la idea de que un ni\u00f1o necesita formar lazos seguros con un cuidador\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469276,"url":"https:\/\/noticiasya.com\/colorado\/2025\/12\/15\/quien-es-nick-reiner-hijo-rob-y-michele-trax\/","url_meta":{"origin":1471564,"position":4},"title":"\u00bfQui\u00e9n es Nick Reiner, el hijo de Rob y Michele Reiner?","author":"","date":"diciembre 15, 2025","format":false,"excerpt":"Nick Reiner, quien actualmente se encuentra encarcelado en Los \u00c1ngeles por un delito grave no especificado tras la muerte de sus padres en su domicilio, hablaba con frecuencia sobre su lucha contra la adicci\u00f3n a las drogas.Reiner, de 32 a\u00f1os, coescribi\u00f3 la pel\u00edcula de 2015 \u201cBeing Charlie\u201d, inspirada en sus\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469279,"url":"https:\/\/noticiasya.com\/colorado\/2025\/12\/15\/detienen-nick-hijo-rob-reiner-muerte-trax\/","url_meta":{"origin":1471564,"position":5},"title":"Detienen al hijo de Rob Reiner tras la muerte del cineasta y su esposa","author":"","date":"diciembre 15, 2025","format":false,"excerpt":"Nick Reiner, hijo de Rob y Michele Singer Reiner, fue ingresado en una c\u00e1rcel de Los \u00c1ngeles el lunes, despu\u00e9s de que sus padres fueran encontrados muertos en su casa de Brentwood, seg\u00fan consta en los registros penitenciarios.Sin embargo, los registros no especifican el cargo que enfrenta Nick Reiner. El\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1471564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1471564"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1471564\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1471564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1471564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1471564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}