{"id":1471641,"date":"2026-02-25T09:03:43","date_gmt":"2026-02-25T17:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/25\/fuga-masiva-siria-campamento-isis-trax\/"},"modified":"2026-02-25T09:03:43","modified_gmt":"2026-02-25T17:03:43","slug":"fuga-masiva-siria-campamento-isis-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2026\/02\/25\/fuga-masiva-siria-campamento-isis-trax\/","title":{"rendered":"Siria reporta &#171;fuga masiva&#187; de un campamento de detenci\u00f3n con familias vinculadas a ISIS"},"content":{"rendered":"<p>Una \u201cfuga masiva\u201d tuvo lugar el mes pasado en el campamento de al-Hol en Siria, donde est\u00e1n detenidas familias vinculadas a ISIS, tras la retirada de las fuerzas kurdas, inform\u00f3 la televisi\u00f3n estatal siria en medio de reportes de que miles de personas podr\u00edan haber huido.<\/p>\n<p>Nureddin Baba, portavoz del Ministerio del Interior, fue citado diciendo que las Fuerzas Democr\u00e1ticas Sirias (SDF, por sus siglas en ingl\u00e9s) se retiraron del campamento sin coordinaci\u00f3n con el Gobierno de Siria ni con la coalici\u00f3n liderada por Estados Unidos contra ISIS.<\/p>\n<p>En enero, las SDF dijeron que se retiraron del campamento de al-Hol debido a la \u201cindiferencia internacional\u201d frente a ISIS y al \u201cfracaso de la comunidad internacional para asumir sus responsabilidades en abordar este grave asunto\u201d.<\/p>\n<p>Baba dijo que las autoridades sirias \u201cidentificaron m\u00e1s de 100 brechas en el muro perimetral del campamento, lo que facilit\u00f3 operaciones de contrabando\u201d, y a\u00f1adi\u00f3 que el n\u00famero de fugitivos a\u00fan debe verificarse.<\/p>\n<p>Un memorando interno enviado a los Estados miembros de la Uni\u00f3n Europea plante\u00f3 preocupaciones de seguridad ante la posibilidad de que miles de personas \u2014la mayor\u00eda de quienes viv\u00edan en el campamento\u2014 hayan escapado, inform\u00f3 Reuters y confirm\u00f3 a CNN un funcionario de la UE.<\/p>\n<p>El memorando se\u00f1al\u00f3 que el estatus de los ciudadanos de terceros pa\u00edses que huyeron del campamento de al-Hol \u201csegu\u00eda sin estar claro\u201d.<\/p>\n<p>The Wall Street Journal inform\u00f3 que entre 15.000 y 20.000 personas, incluidos afiliados a ISIS, se encuentran ahora en libertad dentro del pa\u00eds tras el \u00e9xodo del campamento de al-Hol, citando a agencias de inteligencia de Estados Unidos. CNN no ha verificado esa cifra.<\/p>\n<p>La Organizaci\u00f3n de las Naciones Unidas dice que el campamento de al-Hol alberga a m\u00e1s de 30.000 personas.<\/p>\n<p>Han surgido interrogantes sobre el destino de miles de prisioneros del Estado Isl\u00e1mico y sus familias en el noreste de Siria despu\u00e9s de que fuerzas gubernamentales tomaran el mes pasado extensas zonas de territorio que durante mucho tiempo hab\u00edan estado bajo control de fuerzas kurdas que custodiaban las prisiones.<\/p>\n<p>En ese momento, detenidos tambi\u00e9n hab\u00edan escapado previamente de la prisi\u00f3n de al-Shaddadi, que las SDF dijeron que albergaba a \u201cmiles\u201d de prisioneros de ISIS.<\/p>\n<p>Las SDF hab\u00edan sido socias de Washington en Siria, pero la reducci\u00f3n de tropas de Estados Unidos en el pa\u00eds en 2019 dej\u00f3 al grupo kurdo en una posici\u00f3n vulnerable, particularmente tras la ca\u00edda del r\u00e9gimen de Bashar al-Assad a finales de 2024 y el ascenso al poder del presidente Ahmad al-Sharaa. La coalici\u00f3n liderada por Estados Unidos que combate a ISIS en Siria hab\u00eda dependido durante mucho tiempo de las SDF para custodiar las prisiones de ISIS.<\/p>\n<p>Las SDF acusaron a la coalici\u00f3n de no intervenir para frenar el avance de fuerzas aliadas al Gobierno.<\/p>\n<p>ISIS surgi\u00f3 de los remanentes de Al Qaeda en Iraq. En el apogeo de su poder, control\u00f3 cerca de un tercio de Siria, con Raqqa como su capital. En 2017, las SDF declararon la \u201cliberaci\u00f3n total\u201d de Raqqa, trabajando junto a fuerzas de la coalici\u00f3n liderada por Estados Unidos para recuperar territorio de manos de ISIS.<\/p>\n<p>El grupo fue en gran medida derrotado en 2019, pero algunos elementos a\u00fan operan de forma clandestina en Siria e Iraq. Cuando cay\u00f3 el r\u00e9gimen de Assad, varios pa\u00edses de Medio Oriente y sus aliados occidentales advirtieron que ISIS podr\u00eda aprovechar el caos y orquestar un resurgimiento.<\/p>\n<p>En noviembre, al-Sharaa se uni\u00f3 a la coalici\u00f3n contra ISIS liderada por Estados Unidos, y sus fuerzas contin\u00faan persiguiendo a elementos del grupo.<\/p>\n<p>Mientras tanto, ha ido en aumento la presi\u00f3n sobre Australia, Estados Unidos, Reino Unido y otros pa\u00edses para que repatr\u00eden a miles de sus ciudadanos, en su mayor\u00eda mujeres y ni\u00f1os, que han permanecido atrapados en campamentos de detenci\u00f3n en Siria desde la ca\u00edda del califato hace m\u00e1s de cinco a\u00f1os.<\/p>\n<p>CNN inform\u00f3 previamente que m\u00e1s de la mitad de la poblaci\u00f3n del campamento de al-Hol son ni\u00f1os, la mayor\u00eda menores de 12 a\u00f1os.<\/p>\n<p>El primer ministro de Australia, Anthony Albanese, dijo la semana pasada que su pa\u00eds no repatriar\u00e1 a sus ciudadanos con v\u00ednculos con miembros del Estado Isl\u00e1mico. Sus comentarios siguieron a reportes de que 34 mujeres y ni\u00f1os australianos fueron rechazados por autoridades sirias despu\u00e9s de haber salido del campamento de detenci\u00f3n de Al-Roj, que alberga a combatientes de ISIS y sus familias.<\/p>\n<p>Muchos gobiernos se han mostrado reacios a repatriar a sus ciudadanos debido a preocupaciones de seguridad nacional y a la oposici\u00f3n interna. El campamento de Al-Roj tambi\u00e9n alberga a Shamima Begum, la estudiante londinense que huy\u00f3 a los 15 a\u00f1os para unirse a ISIS en 2015 y posteriormente fue despojada de su ciudadan\u00eda brit\u00e1nica.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una \u201cfuga masiva\u201d tuvo lugar el mes pasado en el campamento de al-Hol en Siria, donde est\u00e1n detenidas familias vinculadas a ISIS, tras la retirada de las fuerzas kurdas, inform\u00f3 la televisi\u00f3n estatal siria en medio de reportes de que miles de personas podr\u00edan haber huido. Nureddin Baba, portavoz del Ministerio del Interior, fue citado [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1471641","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Siria reporta &quot;fuga masiva&quot; de un campamento de detenci\u00f3n con familias vinculadas a ISIS - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/25\/fuga-masiva-siria-campamento-isis-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Siria reporta &quot;fuga masiva&quot; de un campamento de detenci\u00f3n con familias vinculadas a ISIS - Noticias\" \/>\n<meta property=\"og:description\" content=\"Una \u201cfuga masiva\u201d tuvo lugar el mes pasado en el campamento de al-Hol en Siria, donde est\u00e1n detenidas familias vinculadas a ISIS, tras la retirada de las fuerzas kurdas, inform\u00f3 la televisi\u00f3n estatal siria en medio de reportes de que miles de personas podr\u00edan haber huido. Nureddin Baba, portavoz del Ministerio del Interior, fue citado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/25\/fuga-masiva-siria-campamento-isis-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-25T17:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/25\/fuga-masiva-siria-campamento-isis-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/25\/fuga-masiva-siria-campamento-isis-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Siria reporta &#171;fuga masiva&#187; de un campamento de detenci\u00f3n con familias vinculadas a ISIS\",\"datePublished\":\"2026-02-25T17:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/25\/fuga-masiva-siria-campamento-isis-trax\/\"},\"wordCount\":859,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/25\/fuga-masiva-siria-campamento-isis-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/25\/fuga-masiva-siria-campamento-isis-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/25\/fuga-masiva-siria-campamento-isis-trax\/\",\"name\":\"Siria reporta \\\"fuga masiva\\\" de un campamento de detenci\u00f3n con familias vinculadas a ISIS - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-25T17:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/25\/fuga-masiva-siria-campamento-isis-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/25\/fuga-masiva-siria-campamento-isis-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/25\/fuga-masiva-siria-campamento-isis-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Siria reporta &#171;fuga masiva&#187; de un campamento de detenci\u00f3n con familias vinculadas a ISIS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Siria reporta \"fuga masiva\" de un campamento de detenci\u00f3n con familias vinculadas a ISIS - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/25\/fuga-masiva-siria-campamento-isis-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Siria reporta \"fuga masiva\" de un campamento de detenci\u00f3n con familias vinculadas a ISIS - Noticias","og_description":"Una \u201cfuga masiva\u201d tuvo lugar el mes pasado en el campamento de al-Hol en Siria, donde est\u00e1n detenidas familias vinculadas a ISIS, tras la retirada de las fuerzas kurdas, inform\u00f3 la televisi\u00f3n estatal siria en medio de reportes de que miles de personas podr\u00edan haber huido. Nureddin Baba, portavoz del Ministerio del Interior, fue citado [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/25\/fuga-masiva-siria-campamento-isis-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-25T17:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/25\/fuga-masiva-siria-campamento-isis-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/25\/fuga-masiva-siria-campamento-isis-trax\/"},"author":{"name":"","@id":""},"headline":"Siria reporta &#171;fuga masiva&#187; de un campamento de detenci\u00f3n con familias vinculadas a ISIS","datePublished":"2026-02-25T17:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/25\/fuga-masiva-siria-campamento-isis-trax\/"},"wordCount":859,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/25\/fuga-masiva-siria-campamento-isis-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/25\/fuga-masiva-siria-campamento-isis-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/25\/fuga-masiva-siria-campamento-isis-trax\/","name":"Siria reporta \"fuga masiva\" de un campamento de detenci\u00f3n con familias vinculadas a ISIS - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-25T17:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/25\/fuga-masiva-siria-campamento-isis-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/25\/fuga-masiva-siria-campamento-isis-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/25\/fuga-masiva-siria-campamento-isis-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Siria reporta &#171;fuga masiva&#187; de un campamento de detenci\u00f3n con familias vinculadas a ISIS"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/25\/fuga-masiva-siria-campamento-isis-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Siria reporta &#171;fuga masiva&#187; de un campamento de detenci\u00f3n con familias vinculadas a ISIS","url":"http:\/\/noticiasya.com\/colorado\/2026\/02\/25\/fuga-masiva-siria-campamento-isis-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2026\/02\/25\/fuga-masiva-siria-campamento-isis-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-25T17:03:43Z","datePublished":"2026-02-25T17:03:43Z","dateModified":"2026-02-25T17:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Siria reporta &#171;fuga masiva&#187; de un campamento de detenci\\u00f3n con familias vinculadas a ISIS\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/02\\\/25\\\/fuga-masiva-siria-campamento-isis-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/02\\\/25\\\/fuga-masiva-siria-campamento-isis-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-25T17:03:43Z\",\"datePublished\":\"2026-02-25T17:03:43Z\",\"dateModified\":\"2026-02-25T17:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1471304,"url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/17\/australia-niega-repatriar-ciudadanos-vinculados-isis-siria-trax\/","url_meta":{"origin":1471641,"position":0},"title":"Australia se niega a repatriar a ciudadanos vinculados con ISIS en Siria tras fracaso de intento de fuga","author":"","date":"febrero 17, 2026","format":false,"excerpt":"Australia no repatriar\u00e1 a sus ciudadanos con v\u00ednculos con miembros del Estado Isl\u00e1mico, declar\u00f3 el primer ministro Anthony Albanese a la emisora \u200b\u200bnacional ABC el martes, con un consejo directo a las familias varadas en Siria: \u201cSi haces tu cama, te acuestas en ella\u201d.Sus comentarios siguieron a informes de que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470211,"url":"https:\/\/noticiasya.com\/colorado\/2026\/01\/18\/siria-fuerzas-armadas-territorio-kurdo-trax\/","url_meta":{"origin":1471641,"position":1},"title":"Las Fuerzas Armadas de Siria se han apoderado de amplias zonas bajo control kurdo. \u00bfQu\u00e9 pas\u00f3?","author":"","date":"enero 18, 2026","format":false,"excerpt":"En el espacio de dos d\u00edas, las Fuerzas Armadas de Siria, con apoyo de milicias tribales, han expulsado a fuerzas kurdas de extensas \u00e1reas del norte del pa\u00eds que controlaban desde hace m\u00e1s de una d\u00e9cada.Entre las ciudades que, seg\u00fan reportes, han ca\u00eddo se encuentra Raqqa, que fue la tristemente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456495,"url":"https:\/\/noticiasya.com\/colorado\/2024\/12\/11\/estados-unidos-sofocar-resurgimiento-isis-siria-trax\/","url_meta":{"origin":1471641,"position":2},"title":"Estados Unidos se esfuerza por sofocar el resurgimiento de ISIS en Siria tras la ca\u00edda de Assad","author":"","date":"diciembre 11, 2024","format":false,"excerpt":"Los principales socios de Estados Unidos en la lucha contra ISIS en Siria dijeron el mi\u00e9rcoles que los centros de detenci\u00f3n de ISIS que custodian est\u00e1n siendo atacados y que se han visto obligados a detener las operaciones contra ISIS, lo que complica los esfuerzos del ej\u00e9rcito estadounidense para evitar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450237,"url":"https:\/\/noticiasya.com\/colorado\/2024\/06\/11\/hijos-combatientes-isis-mayoria-edad-prision-trax\/","url_meta":{"origin":1471641,"position":3},"title":"&#171;En prisi\u00f3n por culpa de nuestros padres&#187;: hijos de combatientes de ISIS llegan a la mayor\u00eda de edad detenidos y preguntan por qu\u00e9 son castigados","author":"","date":"junio 11, 2024","format":false,"excerpt":"Noreste de Siria (CNN) -- Solo hab\u00eda recibido visitas una vez antes, hace a\u00f1os, cuando lleg\u00f3 por primera vez a la prisi\u00f3n a los 14 a\u00f1os. Un guardia enmascarado le vend\u00f3 los ojos y lo llev\u00f3 a una habitaci\u00f3n, donde le hicieron sentarse en una silla de pl\u00e1stico bajo una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456787,"url":"https:\/\/noticiasya.com\/colorado\/2024\/12\/20\/soldados-estados-unidos-siria-damasco-trax\/","url_meta":{"origin":1471641,"position":4},"title":"EE.UU. admite que tiene el doble de soldados en Siria mientras Biden env\u00eda funcionarios a Damasco","author":"","date":"diciembre 20, 2024","format":false,"excerpt":"El Pent\u00e1gono anunci\u00f3 que EE.UU. tiene actualmente \u201caproximadamente 2.000\u201d soldados en Siria, m\u00e1s del doble del n\u00famero previamente revelado de 900, dijo un portavoz del Departamento de Defensa en una rueda de prensa de este jueves.\u201cHay consideraciones de seguridad diplom\u00e1ticas y operativas a menudo con nuestros despliegues y algunos de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456717,"url":"https:\/\/noticiasya.com\/colorado\/2024\/12\/18\/por-que-otros-paises-atacan-siria-assad-isis-trax\/","url_meta":{"origin":1471641,"position":5},"title":"Por qu\u00e9 las potencias extranjeras siguen apuntando a Siria tras la ca\u00edda del r\u00e9gimen de Assad","author":"","date":"diciembre 18, 2024","format":false,"excerpt":"Pese a que Bashar al-Assad y su r\u00e9gimen de a\u00f1os de duraci\u00f3n cay\u00f3 en Siria, el pa\u00eds sigue siendo un campo de batalla para una serie de actores que buscan asegurar sus intereses en lo que puede convertirse en un peligroso vac\u00edo de poder.Mientras el Hayat Tahrir al-Sham (HTS) asume\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1471641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1471641"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1471641\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1471641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1471641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1471641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}