{"id":1471672,"date":"2026-02-26T04:03:47","date_gmt":"2026-02-26T12:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/26\/personas-desaparecida-tucson-arizona-guthrie-trax\/"},"modified":"2026-02-26T04:03:47","modified_gmt":"2026-02-26T12:03:47","slug":"personas-desaparecida-tucson-arizona-guthrie-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2026\/02\/26\/personas-desaparecida-tucson-arizona-guthrie-trax\/","title":{"rendered":"Se acerca el mes de la desaparici\u00f3n de Nancy Guthrie, mientras otras familias de Tucson llevan d\u00e9cadas esperando respuestas"},"content":{"rendered":"<p>El 12 de junio de 1991 es un d\u00eda que Tammy Tacho jam\u00e1s olvidar\u00e1. Fue el \u00faltimo d\u00eda que vio a su hermano peque\u00f1o de 12 a\u00f1os antes de que desapareciera cuando ella y su madre salieron de la entrada.<\/p>\n<p>James Hendrickson, conocido como Jimmy en su familia, se acerc\u00f3 al auto para besar a su madre y despedirse, record\u00f3 Tacho.<\/p>\n<p>\u201cPara m\u00ed y para mi madre, eso es una pel\u00edcula de terror, porque ese es el \u00faltimo beso, o ese es el \u00faltimo abrazo, y ese es el \u00faltimo toque que ella le hizo en el cabello\u201d, le dijo a CNN.<\/p>\n<p>M\u00e1s de tres d\u00e9cadas despu\u00e9s, Jimmy nunca ha sido encontrado y su caso de persona desaparecida sigue abierto y sin resolver.<\/p>\n<p>Jimmy es s\u00f3lo una de varias personas en el <a href=\"https:\/\/www.cnn.com\/2026\/02\/24\/americas\/mexico-searching-mothers-nancy-guthrie-latam-intl\">\u00e1rea de Tucson<\/a> que han estado desaparecidas durante m\u00e1s de una d\u00e9cada sin respuestas.<\/p>\n<p>Una desaparici\u00f3n m\u00e1s reciente en la zona ha <a href=\"https:\/\/www.cnn.com\/2026\/02\/25\/us\/nancy-guthrie-reward-strategy\">atra\u00eddo la atenci\u00f3n nacional<\/a>: la de Nancy Guthrie, la madre de 84 a\u00f1os de la presentadora de \u201cToday\u201d, Savannah Guthrie.<\/p>\n<p>Nancy Guthrie desapareci\u00f3 de su acomodado vecindario en <a href=\"https:\/\/www.cnn.com\/2026\/02\/04\/us\/tucson-arizona-nancy-guthrie-home\">Catalina Foothills<\/a> el <a href=\"https:\/\/www.cnn.com\/us\/timeline-nancy-guthrie-search\">1 de febrero<\/a> , y casi un mes despu\u00e9s de su desaparici\u00f3n, las autoridades a\u00fan no han encontrado a la mujer desaparecida ni han acusado a alguien en relaci\u00f3n con su aparente secuestro.<\/p>\n<p>El presidente Donald Trump public\u00f3 en Truth Social que estaba desplegando todos los recursos para encontrarla, y el sheriff del condado de Pima afirm\u00f3 tener a m\u00e1s de 400 polic\u00edas trabajando a toda hora en el caso. Su familia anunci\u00f3 el martes que ofrece hasta un mill\u00f3n de d\u00f3lares por informaci\u00f3n que conduzca a su recuperaci\u00f3n, y Savannah Guthrie tambi\u00e9n anunci\u00f3 una donaci\u00f3n de US$ 500.000 al <a href=\"https:\/\/www.missingkids.org\/blog\/2026\/standing-with-families-in-their-hardest-moments\">Centro Nacional para Ni\u00f1os Desaparecidos y Explotados<\/a>, expresando su esperanza de que la atenci\u00f3n prestada a su familia se extienda a otros que a\u00fan se encuentran en el limbo.<\/p>\n<p>Mientras la b\u00fasqueda de Nancy Guthrie se extiende a su cuarta semana, familias como la de Jimmy han estado esperando a\u00f1os por alguna nueva informaci\u00f3n sobre sus seres queridos.<\/p>\n<p>Ese d\u00eda de verano en Tucson, Tacho y su madre se dirig\u00edan a Douglas, Arizona, para reunirse con la familia de su entonces novio, dijo ella. Jimmy no quer\u00eda ir.<\/p>\n<p>\u201cTen\u00eda esa edad. Era verano y quer\u00eda salir a jugar y hacer lo que hacen los chicos, as\u00ed que se qued\u00f3\u201d, dijo.<\/p>\n<p>Tacho recuerda a su hermano como un \u201cni\u00f1o de mam\u00e1\u201d que amaba ir a la iglesia, jugar al aire libre y usualmente usaba pantalones deportivos rojos, su color favorito.<\/p>\n<p>\u201cLo peor es salir en coche y verlo salud\u00e1ndonos\u201d, dijo Tacho.<\/p>\n<p>Lo dejaron con un amigo de la familia que conoc\u00edan desde que se mudaron a Tucson en 1987, dijo Tacho, y su viaje de dos d\u00edas se extendi\u00f3 a tres despu\u00e9s de que el auto se averi\u00f3.<\/p>\n<p>Cuando finalmente regresaron a la ciudad, fue cuando \u201ccomienza la pesadilla\u201d, dijo Tacho.<\/p>\n<p>La madre de Jimmy present\u00f3 una denuncia policial inmediatamente al enterarse de la desaparici\u00f3n de su hijo, pero Tacho dijo que el caso no se tom\u00f3 en serio de inmediato. Record\u00f3 que la polic\u00eda pens\u00f3 que Jimmy simplemente se hab\u00eda fugado, pero que su familia sab\u00eda que no era cierto. Tardaron varias semanas en reconocer la desaparici\u00f3n de su hermano, coment\u00f3.<\/p>\n<p>\u201cDurante la investigaci\u00f3n inicial y las teor\u00edas posteriores se plante\u00f3 que Jimmy se march\u00f3 por voluntad propia y simplemente se fug\u00f3. Eso no es en absoluto lo que ocurri\u00f3 en este caso. No abandon\u00f3 a su familia por voluntad propia. No ten\u00eda dinero para mantenerse ni transporte\u201d, <a href=\"https:\/\/www.kold.com\/2025\/07\/02\/13-crime-files-disappearance-james-jimmy-hendrickson\/\">declar\u00f3 el detective David Miller del Departamento de Polic\u00eda de Tucson a KOLD, afiliada de CNN,<\/a> el a\u00f1o pasado.<\/p>\n<p>Hay varias historias sobre lo que sucedi\u00f3 la noche del 11 de junio y la ma\u00f1ana siguiente, dijo Tacho, lo que ha dejado a su familia con m\u00e1s preguntas que respuestas.<\/p>\n<p>La amiga de la familia que cuidaba a Jimmy lo dej\u00f3 ir con otro ni\u00f1o a la casa de su pariente a arreglar una cerca, dijo Tacho. El otro ni\u00f1o le dijo a la polic\u00eda que Jimmy estaba jugando videojuegos cuando se acost\u00f3 y escuch\u00f3 ruidos durante la noche, pero no le dio importancia, seg\u00fan Tacho. La adulta que estaba en la casa dijo que Jimmy sali\u00f3 por la ma\u00f1ana a desayunar a una escuela cercana, algo que no era inusual para ella y sus hermanos.<\/p>\n<p>Ahora, casi 35 a\u00f1os despu\u00e9s, Tacho sigue luchando por respuestas. Sigue llamando a la polic\u00eda y ha organizado vigilias y eventos para visibilizar el caso de su hermano, dijo.<\/p>\n<p>\u201cTrabaj\u00e9 en el mismo trabajo que mi mam\u00e1 y espero que alg\u00fan d\u00eda Jimmy entre ah\u00ed\u201d, dijo Tacho. \u201cHe llegado a aceptarlo\u2026 No lo voy a encontrar con vida, pero tenemos que encontrarlo\u201d.<\/p>\n<p>Cuando su madre muri\u00f3 hace unos a\u00f1os, se fue sin saber qu\u00e9 le hab\u00eda pasado a Jimmy. \u201cNo quiero irme de este mundo sin saberlo\u201d, dijo Tacho.<\/p>\n<p>Ella dijo que todav\u00eda vive en Tucson, en caso de que Jimmy alguna vez regrese.<\/p>\n<p>Es una carga pesada la que tambi\u00e9n soporta la familia de Karen Grajeda, quien ten\u00eda 7 a\u00f1os cuando desapareci\u00f3 de su complejo de apartamentos en Tucson en 1996: tener que equilibrar la esperanza y tratar de superar el duelo.<\/p>\n<p>\u201cSigo colgando nuestra foto de Navidad todos los a\u00f1os\u201d, escribi\u00f3 su hermana menor, Alejandra, en un mensaje a Karen publicado por el <a href=\"https:\/\/www.missingkids.org\/blog\/2026\/well-always-be-waiting-for-you-30-years-without-karen?fbclid=IwY2xjawP_PMtleHRuA2FlbQIxMABicmlkETJrRUpzWU1hZVIzTUVtTUh5c3J0YwZhcHBfaWQQMjIyMDM5MTc4ODIwMDg5MgABHgJNLZOJ7qWTeCQ7l7cnhpnuNnB6hHTGjyIgGofJEqYUG_ss2XVyePhZ-iEc_aem_ukj8UeprkxeQKtSO9pUC5w\">Centro Nacional para Ni\u00f1os Desaparecidos y Explotados<\/a> . \u201cMi hija lleva tu nombre. Si est\u00e1s ah\u00ed fuera, si est\u00e1s viva, aqu\u00ed estamos. Toda tu familia te quiere y, si puedes volver a casa, por favor, hazlo. Siempre te estaremos esperando\u201d.<\/p>\n<p>Karen fue vista por \u00faltima vez jugando afuera de su casa el 11 de enero de 1996, seg\u00fan <a href=\"https:\/\/www.kold.com\/story\/30946093\/tucsons-most-wanted-20-yrs-later-karen-grajeda-still-missing\/\">KOLD, afiliada de CNN<\/a> .<\/p>\n<p>El FBI y el Departamento de Polic\u00eda de Tucson comenzaron a buscarla de inmediato, y familiares y miembros de la comunidad se unieron a la iniciativa. Sin embargo, tras meses con pocas pistas, a\u00fan no hay rastro de lo ocurrido, seg\u00fan el NCMEC. La organizaci\u00f3n colabora con las fuerzas del orden y otros funcionarios para encontrar a los ni\u00f1os desaparecidos, incluyendo la publicaci\u00f3n de im\u00e1genes de progresi\u00f3n de edad.<\/p>\n<p>\u201cEra solo una ni\u00f1a inocente. Ese es el recuerdo que tengo de ella, una ni\u00f1a inocente que siempre sonre\u00eda. Como su padre, esa es la imagen que conservo\u201d, declar\u00f3 Andr\u00e9s, el padre de Karen, a la organizaci\u00f3n.<\/p>\n<p>El caso de Karen est\u00e1 \u201cen estado de persona desaparecida a largo plazo\u201d, dijo el Departamento de Polic\u00eda de Tucson a CNN, y la polic\u00eda contin\u00faa investigando el caso como un secuestro no familiar y pide a la gente que presente informaci\u00f3n, seg\u00fan NCMEC.<\/p>\n<p>\u201cNo hay nada m\u00e1s inocente que un ni\u00f1o, y son las personas m\u00e1s vulnerables que ten\u00edan todo por delante para ser felices, y se lo arrebataron a ellos, a sus familias\u201d, <a href=\"https:\/\/www.kold.com\/video\/2023\/11\/22\/13-crime-files-disappearance-karen-grajeda\/\">declar\u00f3 Miller, el detective de Tucson, a KOLD<\/a> sobre el caso en 2023. \u201cCualquiera que tenga hijos probablemente sienta lo mismo, y creo que ese nivel de confianza en una comunidad, cuando algo as\u00ed sucede, se ve mermado\u201d.<\/p>\n<p>Seg\u00fan el <a href=\"https:\/\/www.missingkids.org\/\">NCMEC<\/a> , en 2024 se inform\u00f3 de la desaparici\u00f3n de casi 30.000 ni\u00f1os .<\/p>\n<p>Los adultos de entre 20 y 39 a\u00f1os tambi\u00e9n corren riesgo de sufrir secuestros en Estados Unidos, <a href=\"https:\/\/cde.ucr.cjis.gov\/LATEST\/webapp\/#\/pages\/explorer\/crime\/crime-trend\">seg\u00fan datos del FBI<\/a> . Entre febrero de 2025 y febrero de 2026, el 53 % de los secuestros se produjeron entre personas de ese rango de edad. Casi la mitad de los secuestros ocurrieron entre parejas actuales o anteriores, seg\u00fan los datos.<\/p>\n<p>La familia de Marlana McElvaine cree que ella ya no est\u00e1 viva, pero a\u00fan as\u00ed pide al p\u00fablico que se presente para ayudarlos a descansar.<\/p>\n<p>La joven de 28 a\u00f1os, madre de dos hijos, manten\u00eda una relaci\u00f3n donde sufr\u00eda violencia dom\u00e9stica cuando desapareci\u00f3 en 2010, seg\u00fan declar\u00f3 su hermana a <a href=\"https:\/\/www.kgun9.com\/news\/local-news\/tucson-family-still-seeking-answers-on-12-year-anniversary-of-missing-daughter\">KGUN, afiliada de CNN<\/a> . Su novio, con quien viv\u00eda al momento de su desaparici\u00f3n, se encuentra en prisi\u00f3n por cargos no relacionados, <a href=\"https:\/\/www.youtube.com\/watch?v=_ZyR_8ELKhE\">inform\u00f3 KOLD<\/a> .<\/p>\n<p>\u201cSe trata de que alguien se presente, sea valiente y brinde informaci\u00f3n. Les pedimos que, si fue su hermana, su hija, la madre de su hijo, se pongan en nuestro lugar\u201d, declar\u00f3 Janean McElvaine, su hermana, a KOLD en 2023.<\/p>\n<p>El autom\u00f3vil de Marlana McElvaine fue encontrado abandonado, con sus llaves y su placa de trabajo todav\u00eda dentro, inform\u00f3 la estaci\u00f3n.<\/p>\n<p>\u201cNo hay cierre y hay un vac\u00edo en nuestros corazones. Seguimos adelante, hacemos lo que tenemos que hacer, pero no tenemos respuestas y solo esperamos que alg\u00fan d\u00eda\u2026 podamos darle la despedida que se merece\u201d, dijo su madre, Dian McElvaine, a KOLD.<\/p>\n<p>Dian McElvaine dijo que en 2023 la familia estaba trabajando para obtener una declaraci\u00f3n de defunci\u00f3n para facilitar el proceso de duelo. La polic\u00eda de Tucson inform\u00f3 a KOLD en ese momento que, una vez firmada, el caso pasar\u00eda de ser un caso de persona desaparecida a un caso de homicidio.<\/p>\n<p>La polic\u00eda de Tucson dijo a CNN que el caso todav\u00eda est\u00e1 clasificado como \u201cpersona desaparecida a largo plazo\u201d.<\/p>\n<p>La gente desaparece, <a href=\"https:\/\/www.kold.com\/story\/15238880\/police-suspect-foul-play-in-missing-woman-case\/\">dijo el detective de la polic\u00eda de Tucson Doug Musick a KOLD en el momento<\/a> de su desaparici\u00f3n, pero \u201ces bastante raro que la gente simplemente abandone a sus hijos, su trabajo, su familia, su vida\u201d.<\/p>\n<p>La familia de Marlana McElvaine tambi\u00e9n lo piensa.<\/p>\n<p>\u201cDesde el momento en que recib\u00ed esa llamada, supe que se hab\u00eda ido. Porque sab\u00eda que no se habr\u00eda alejado de su vida, que no se habr\u00eda alejado de sus hijos, que no nos habr\u00eda abandonado; somos tan cercanos. Lo supe desde ese momento, y desde ese momento comenc\u00e9 a lamentar porque, \u00bfsabes qu\u00e9?, de ninguna manera se habr\u00eda ido as\u00ed como as\u00ed\u201d, dijo Dian McElvaine a KOLD.<\/p>\n<p>Su familia a\u00fan habla de ella y celebra su cumplea\u00f1os, seg\u00fan cont\u00f3 su hermana a KOLD. Tambi\u00e9n plantaron un \u00e1rbol en su honor.<\/p>\n<p>Las familias, incluidos los Guthrie, est\u00e1n pasando por un trauma que s\u00f3lo otras familias que han estado esperando respuestas pueden entender, dijo la hermana mayor de Jimmy, Tacho, buscando alg\u00fan tipo de cierre.<\/p>\n<p>\u201cNadie sabe c\u00f3mo nos sentimos a menos que estemos pasando por eso\u201d, dijo. \u201cEs un dolor muy grande\u201d.<\/p>\n<p>\u201cBusco respuestas como si fuera el primer d\u00eda, el segundo d\u00eda, seis meses, un a\u00f1o, ya sabes, simplemente nunca nos rendiremos. Nunca nos rendiremos\u201d, dijo Tacho.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 12 de junio de 1991 es un d\u00eda que Tammy Tacho jam\u00e1s olvidar\u00e1. Fue el \u00faltimo d\u00eda que vio a su hermano peque\u00f1o de 12 a\u00f1os antes de que desapareciera cuando ella y su madre salieron de la entrada. James Hendrickson, conocido como Jimmy en su familia, se acerc\u00f3 al auto para besar a [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1471672","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Se acerca el mes de la desaparici\u00f3n de Nancy Guthrie, mientras otras familias de Tucson llevan d\u00e9cadas esperando respuestas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/26\/personas-desaparecida-tucson-arizona-guthrie-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se acerca el mes de la desaparici\u00f3n de Nancy Guthrie, mientras otras familias de Tucson llevan d\u00e9cadas esperando respuestas - Noticias\" \/>\n<meta property=\"og:description\" content=\"El 12 de junio de 1991 es un d\u00eda que Tammy Tacho jam\u00e1s olvidar\u00e1. Fue el \u00faltimo d\u00eda que vio a su hermano peque\u00f1o de 12 a\u00f1os antes de que desapareciera cuando ella y su madre salieron de la entrada. James Hendrickson, conocido como Jimmy en su familia, se acerc\u00f3 al auto para besar a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/26\/personas-desaparecida-tucson-arizona-guthrie-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-26T12:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/26\/personas-desaparecida-tucson-arizona-guthrie-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/26\/personas-desaparecida-tucson-arizona-guthrie-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Se acerca el mes de la desaparici\u00f3n de Nancy Guthrie, mientras otras familias de Tucson llevan d\u00e9cadas esperando respuestas\",\"datePublished\":\"2026-02-26T12:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/26\/personas-desaparecida-tucson-arizona-guthrie-trax\/\"},\"wordCount\":1869,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/26\/personas-desaparecida-tucson-arizona-guthrie-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/26\/personas-desaparecida-tucson-arizona-guthrie-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/26\/personas-desaparecida-tucson-arizona-guthrie-trax\/\",\"name\":\"Se acerca el mes de la desaparici\u00f3n de Nancy Guthrie, mientras otras familias de Tucson llevan d\u00e9cadas esperando respuestas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-26T12:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/26\/personas-desaparecida-tucson-arizona-guthrie-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/26\/personas-desaparecida-tucson-arizona-guthrie-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/26\/personas-desaparecida-tucson-arizona-guthrie-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se acerca el mes de la desaparici\u00f3n de Nancy Guthrie, mientras otras familias de Tucson llevan d\u00e9cadas esperando respuestas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se acerca el mes de la desaparici\u00f3n de Nancy Guthrie, mientras otras familias de Tucson llevan d\u00e9cadas esperando respuestas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/26\/personas-desaparecida-tucson-arizona-guthrie-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Se acerca el mes de la desaparici\u00f3n de Nancy Guthrie, mientras otras familias de Tucson llevan d\u00e9cadas esperando respuestas - Noticias","og_description":"El 12 de junio de 1991 es un d\u00eda que Tammy Tacho jam\u00e1s olvidar\u00e1. Fue el \u00faltimo d\u00eda que vio a su hermano peque\u00f1o de 12 a\u00f1os antes de que desapareciera cuando ella y su madre salieron de la entrada. James Hendrickson, conocido como Jimmy en su familia, se acerc\u00f3 al auto para besar a [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/26\/personas-desaparecida-tucson-arizona-guthrie-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-26T12:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/26\/personas-desaparecida-tucson-arizona-guthrie-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/26\/personas-desaparecida-tucson-arizona-guthrie-trax\/"},"author":{"name":"","@id":""},"headline":"Se acerca el mes de la desaparici\u00f3n de Nancy Guthrie, mientras otras familias de Tucson llevan d\u00e9cadas esperando respuestas","datePublished":"2026-02-26T12:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/26\/personas-desaparecida-tucson-arizona-guthrie-trax\/"},"wordCount":1869,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/26\/personas-desaparecida-tucson-arizona-guthrie-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/26\/personas-desaparecida-tucson-arizona-guthrie-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/26\/personas-desaparecida-tucson-arizona-guthrie-trax\/","name":"Se acerca el mes de la desaparici\u00f3n de Nancy Guthrie, mientras otras familias de Tucson llevan d\u00e9cadas esperando respuestas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-26T12:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/26\/personas-desaparecida-tucson-arizona-guthrie-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/26\/personas-desaparecida-tucson-arizona-guthrie-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/26\/personas-desaparecida-tucson-arizona-guthrie-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Se acerca el mes de la desaparici\u00f3n de Nancy Guthrie, mientras otras familias de Tucson llevan d\u00e9cadas esperando respuestas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/26\/personas-desaparecida-tucson-arizona-guthrie-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Se acerca el mes de la desaparici\u00f3n de Nancy Guthrie, mientras otras familias de Tucson llevan d\u00e9cadas esperando respuestas","url":"http:\/\/noticiasya.com\/colorado\/2026\/02\/26\/personas-desaparecida-tucson-arizona-guthrie-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2026\/02\/26\/personas-desaparecida-tucson-arizona-guthrie-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-26T12:03:47Z","datePublished":"2026-02-26T12:03:47Z","dateModified":"2026-02-26T12:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Se acerca el mes de la desaparici\\u00f3n de Nancy Guthrie, mientras otras familias de Tucson llevan d\\u00e9cadas esperando respuestas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/02\\\/26\\\/personas-desaparecida-tucson-arizona-guthrie-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/02\\\/26\\\/personas-desaparecida-tucson-arizona-guthrie-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-26T12:03:47Z\",\"datePublished\":\"2026-02-26T12:03:47Z\",\"dateModified\":\"2026-02-26T12:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1467065,"url":"https:\/\/noticiasya.com\/colorado\/2025\/10\/02\/peor-vuelo-vida-conocio-futura-esposa-trax\/","url_meta":{"origin":1471672,"position":0},"title":"Era el peor vuelo de su vida. Y entonces conoci\u00f3 a su futura esposa","author":"","date":"octubre 2, 2025","format":false,"excerpt":"Para Anesu Masube ese vuelo estaba destinado a ser el peor de su vida.El d\u00eda anterior, hab\u00eda recibido la dolorosa noticia de que su madre hab\u00eda fallecido. Anesu viv\u00eda en Washington. Su familia viv\u00eda a m\u00e1s de 11.000 kil\u00f3metros de distancia en Zimbabwe. Sumido en el dolor, tuvo que hacer\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471007,"url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/08\/estafa-mortal-uber-ohio-trax\/","url_meta":{"origin":1471672,"position":1},"title":"De una clase de cocina por FaceTime a una estafa mortal: el \u00faltimo adi\u00f3s de una madre a su hijo","author":"","date":"febrero 8, 2026","format":false,"excerpt":"Lo que comenz\u00f3 como una cotidiana lecci\u00f3n de cocina entre madre e hijo termin\u00f3 siendo su \u00faltima conexi\u00f3n. Mario Hall recuerda la carne con pimientos que preparaba siguiendo las instrucciones de su madre a trav\u00e9s de una pantalla.Desde su hogar en Columbia, Carolina del Sur, Mario observaba con atenci\u00f3n cada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461885,"url":"https:\/\/noticiasya.com\/colorado\/2025\/05\/02\/madre-maikelys-venezolana-ee-uu-orix\/","url_meta":{"origin":1471672,"position":2},"title":"&#171;Lo \u00fanico que pienso es en recuperarla&#187;, dice la madre de Maikelys, la ni\u00f1a venezolana en poder de autoridades de EE.UU.","author":"","date":"mayo 2, 2025","format":false,"excerpt":"Estados Unidos era el pa\u00eds al que la venezolana Yorelys Bernal so\u00f1aba escapar para lograr una mejor vida con toda su familia. Ahora es el pa\u00eds de donde suplica sacar a su hija de dos a\u00f1os, Maikelys Antonella Espinoza Bernal, de quien fue separada en mayo de 2024 luego de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470626,"url":"https:\/\/noticiasya.com\/colorado\/2026\/01\/29\/madre-hijo-juntos-juegos-olimpicos-invierno-orix\/","url_meta":{"origin":1471672,"position":3},"title":"Un caso \u00fanico: madre e hijo hablan antes de competir juntos en los Juegos Ol\u00edmpicos de Invierno Mil\u00e1n-Cortina 2026","author":"","date":"enero 29, 2026","format":false,"excerpt":"Cuando se encienda la llama ol\u00edmpica del pebetero ubicado en el estadio de San Siro el pr\u00f3ximo 6 de febrero, marcando el inicio de la vigesimoquinta edici\u00f3n de los Juegos Ol\u00edmpicos de Invierno, M\u00e9xico ser\u00e1 protagonista de una de las historias m\u00e1s conmovedoras y significativas del olimpismo: una madre y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452143,"url":"https:\/\/noticiasya.com\/colorado\/2024\/08\/25\/muerte-turista-estdounidense-omar-watson-colombia-trax\/","url_meta":{"origin":1471672,"position":4},"title":"Un hombre de Nueva York muri\u00f3 durante un viaje a Colombia; su madre tard\u00f3 cinco meses en enterarse qu\u00e9 ocurri\u00f3","author":"","date":"agosto 25, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Omar Watson le hizo una promesa a su madre antes de partir desde la ciudad de Nueva York hacia Colombia a fines de febrero.Momentos antes de subirse a un veh\u00edculo compartido para ir al aeropuerto, se abrazaron en la cocina de su casa de Brooklyn. Ella le record\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470883,"url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/05\/savannah-guthrie-pruebas-madre-viva-trax\/","url_meta":{"origin":1471672,"position":5},"title":"Savannah Guthrie pide pruebas de que su madre est\u00e1 viva mientras la b\u00fasqueda entra en su quinto d\u00eda","author":"","date":"febrero 5, 2026","format":false,"excerpt":"La b\u00fasqueda de Nancy Guthrie, la madre de 84 a\u00f1os de la presentadora de \u201cToday\u201d Savannah Guthrie, entra en el quinto d\u00eda sin que los investigadores hayan podido identificar un sospechoso.Mientras los hijos de Nancy hacen una s\u00faplica entre l\u00e1grimas para que regrese sana y salva, un pitido en mitad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1471672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1471672"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1471672\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1471672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1471672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1471672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}