{"id":1471680,"date":"2026-02-26T08:04:00","date_gmt":"2026-02-26T16:04:00","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/26\/operativo-cuba-lancha-muertos-orix\/"},"modified":"2026-02-26T08:04:00","modified_gmt":"2026-02-26T16:04:00","slug":"operativo-cuba-lancha-muertos-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2026\/02\/26\/operativo-cuba-lancha-muertos-orix\/","title":{"rendered":"Qu\u00e9 pas\u00f3 en el operativo en Cuba contra una &#171;lancha infractora&#187; en el que murieron cuatro personas"},"content":{"rendered":"<p>El canciller de Cuba, Bruno Rodr\u00edguez, afirm\u00f3 este jueves que el Gobierno est\u00e1 realizando \u201cuna investigaci\u00f3n rigurosa para esclarecer los hechos\u201d tras el operativo que dej\u00f3 al menos cuatro muertos y siete heridos por un enfrentamiento con una \u201clancha infractora\u201d proveniente de Florida que, seg\u00fan las autoridades de la isla, busca infiltrarse \u201ccon fines terroristas\u201d.<\/p>\n<p>El Gobierno del presidente Miguel D\u00edaz-Canel detall\u00f3 la lista de tripulantes, mientras que el Departamento de Estado de EE.UU. indic\u00f3 que tambi\u00e9n buscar\u00e1 averiguar lo que pas\u00f3 y responder\u00e1 \u201cen consecuencia\u201d.<\/p>\n<p>En su primer reporte, el Ministerio del Interior cubano inform\u00f3 la detecci\u00f3n de una lancha r\u00e1pida con matr\u00edcula de Florida en sus aguas territoriales, a una milla n\u00e1utica al noreste de Cayo Falcones, en la provincia de Villa Clara.<\/p>\n<p>El comunicado detall\u00f3 que desde la lancha abrieron fuego cuando una unidad de las Tropas Guardafronteras se acercaron para su identificaci\u00f3n, dejando herido al comandante de la nave cubana. En el enfrentamiento \u201ccuatro agresores resultaron abatidos y seis lesionados, quienes fueron evacuados y recibieron asistencia m\u00e9dica\u201d, agreg\u00f3 el Ministerio.<\/p>\n<p>Posteriormente, las autoridades dijeron en otro comunicado que la lancha transportaba 10 personas armadas y que, seg\u00fan declaraciones preliminares, \u201cten\u00edan intenciones de realizar una infiltraci\u00f3n con fines terrorista\u201d.<\/p>\n<p>Adem\u00e1s, informaron la incautaci\u00f3n de fusiles de asalto, armas cortas, bombas molotov, chalecos antibalas, mirillas telesc\u00f3picas y uniformes de camuflaje.<\/p>\n<p>\u201cCuba no agrede, ni amenaza.  Lo hemos planteado en reiteradas ocasiones y lo ratificamos hoy: Cuba se defender\u00e1 con determinaci\u00f3n y firmeza frente a cualquier agresi\u00f3n terrorista y mercenaria que pretenda afectar su soberan\u00eda y estabilidad nacional\u201d, public\u00f3 en su cuenta de X D\u00edaz-Canel.<\/p>\n<p>El segundo comunicado incluy\u00f3 una lista de nombres de personas que viajaban en la lancha, con matr\u00edcula FL7726SH. \u201cTodos los participantes son cubanos residentes en los Estados Unidos. La mayor\u00eda de ellos con un historial conocido de actividad delictiva y violenta\u201d, asegur\u00f3 el Ministerio.<\/p>\n<p>El comunicado agreg\u00f3 que dos de ellos figuran en la <a href=\"https:\/\/cubaminrex.cu\/sites\/default\/files\/2025-07\/GAceta%209%20de%20julio%20goc-2025-ex34_0.pdf\">lista nacional<\/a> de personas que han sido sometidas a investigaciones penales y se encuentran buscadas \u201ca partir de su implicaci\u00f3n en la promoci\u00f3n, planificaci\u00f3n, organizaci\u00f3n, financiamiento, apoyo o comisi\u00f3n de acciones materializadas en el territorio nacional o en otros pa\u00edses, en funci\u00f3n de actos de terrorismo\u201d.<\/p>\n<p>Entre los cuatro muertos, las autoridades nombraron a uno y agregaron que est\u00e1n trabajando para la identificaci\u00f3n de los otros tres.<\/p>\n<p>Adem\u00e1s, informaron de la detenci\u00f3n de un hombre que, seg\u00fan el Ministerio, fue \u201cenviado desde los Estados Unidos para garantizar la recepci\u00f3n de la infiltraci\u00f3n armada\u201d. CNN solicit\u00f3 comentarios a la Casa Blanca por la declaraci\u00f3n cubana.<\/p>\n<p>El secretario de Estado de EE.UU., Marco Rubio, declar\u00f3 el mi\u00e9rcoles que su pa\u00eds responder\u00e1 \u201cen consecuencia\u201d cuando disponga de los detalles del operativo.<\/p>\n<p>\u201cNo voy a especular ni a opinar. Vamos a averiguar exactamente qu\u00e9 sucedi\u00f3 y responderemos como corresponde\u201d, declar\u00f3 a la prensa durante una cumbre de la Comunidad del Caribe en San Crist\u00f3bal y Nieves.<\/p>\n<p>El jefe de la diplomacia estadounidense descart\u00f3 la participaci\u00f3n de personal del Gobierno de Estados Unidos en el tiroteo y dijo que la embajada estadounidense en La Habana solicit\u00f3 acceso a los sobrevivientes de la lancha, presuntamente ciudadanos estadounidenses o con residencia permanente, para conocer su situaci\u00f3n.<\/p>\n<p>Rubio enfatiz\u00f3 que Washington busca \u201cinformaci\u00f3n independiente\u201d para verificar los hechos y neg\u00f3 que haya conversado del tema con las autoridades cubanas.<\/p>\n<p>Por su parte, el fiscal general de Florida, James Uthmeier, anunci\u00f3 la apertura de una investigaci\u00f3n sobre elasunto. \u201cNo se puede confiar en el Gobierno cubano y haremos todo lo que est\u00e9 en nuestro poder para que estos comunistas rindan cuentas\u201d, dijo en sus redes sociales.<\/p>\n<p>El incidente se produjo en medio de una fuerte tensi\u00f3n entre Estados Unidos y Cuba, luego de que la Casa Blanca impusiera un bloqueo petrolero e instase al Gobierno de D\u00edaz Canel a alcanzar un acuerdo.<\/p>\n<p>Sin embargo, no es un caso at\u00edpico en la zona. El Ministerio del Interior de Cuba dijo que en 2022 intercept\u00f3 13 lanchas r\u00e1pidas estadounidenses con 23 tripulantes, a quienes acus\u00f3 de \u201crealizar operaciones de tr\u00e1fico de personas\u201d que llevaban personas de Cuba a Estados Unidos. En uno de esos operativos, el 18 de junio, las autoridades <a href=\"https:\/\/misiones.cubaminrex.cu\/es\/articulo\/ministerio-del-interior-informa-sobre-incidentes-violentos-relacionados-con-salidas\">informaron<\/a> que un tripulante de una \u201clancha intrusa\u201d abri\u00f3 fuego con un fusil autom\u00e1tico e hiri\u00f3 a uno de los oficiales.<\/p>\n<p>\u201cCuba ha debido enfrentar numerosas infiltraciones terroristas y agresivas procedentes de EEUU desde 1959, con un alto costo en vidas, heridos y da\u00f1os materiales\u201d, dijo el canciller Rodr\u00edguez este jueves.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El canciller de Cuba, Bruno Rodr\u00edguez, afirm\u00f3 este jueves que el Gobierno est\u00e1 realizando \u201cuna investigaci\u00f3n rigurosa para esclarecer los hechos\u201d tras el operativo que dej\u00f3 al menos cuatro muertos y siete heridos por un enfrentamiento con una \u201clancha infractora\u201d proveniente de Florida que, seg\u00fan las autoridades de la isla, busca infiltrarse \u201ccon fines terroristas\u201d. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1471680","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Qu\u00e9 pas\u00f3 en el operativo en Cuba contra una &quot;lancha infractora&quot; en el que murieron cuatro personas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/26\/operativo-cuba-lancha-muertos-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qu\u00e9 pas\u00f3 en el operativo en Cuba contra una &quot;lancha infractora&quot; en el que murieron cuatro personas - Noticias\" \/>\n<meta property=\"og:description\" content=\"El canciller de Cuba, Bruno Rodr\u00edguez, afirm\u00f3 este jueves que el Gobierno est\u00e1 realizando \u201cuna investigaci\u00f3n rigurosa para esclarecer los hechos\u201d tras el operativo que dej\u00f3 al menos cuatro muertos y siete heridos por un enfrentamiento con una \u201clancha infractora\u201d proveniente de Florida que, seg\u00fan las autoridades de la isla, busca infiltrarse \u201ccon fines terroristas\u201d. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/26\/operativo-cuba-lancha-muertos-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-26T16:04:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/26\/operativo-cuba-lancha-muertos-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/26\/operativo-cuba-lancha-muertos-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Qu\u00e9 pas\u00f3 en el operativo en Cuba contra una &#171;lancha infractora&#187; en el que murieron cuatro personas\",\"datePublished\":\"2026-02-26T16:04:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/26\/operativo-cuba-lancha-muertos-orix\/\"},\"wordCount\":824,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/26\/operativo-cuba-lancha-muertos-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/26\/operativo-cuba-lancha-muertos-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/26\/operativo-cuba-lancha-muertos-orix\/\",\"name\":\"Qu\u00e9 pas\u00f3 en el operativo en Cuba contra una \\\"lancha infractora\\\" en el que murieron cuatro personas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-26T16:04:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/26\/operativo-cuba-lancha-muertos-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/26\/operativo-cuba-lancha-muertos-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/26\/operativo-cuba-lancha-muertos-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qu\u00e9 pas\u00f3 en el operativo en Cuba contra una &#171;lancha infractora&#187; en el que murieron cuatro personas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qu\u00e9 pas\u00f3 en el operativo en Cuba contra una \"lancha infractora\" en el que murieron cuatro personas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/26\/operativo-cuba-lancha-muertos-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Qu\u00e9 pas\u00f3 en el operativo en Cuba contra una \"lancha infractora\" en el que murieron cuatro personas - Noticias","og_description":"El canciller de Cuba, Bruno Rodr\u00edguez, afirm\u00f3 este jueves que el Gobierno est\u00e1 realizando \u201cuna investigaci\u00f3n rigurosa para esclarecer los hechos\u201d tras el operativo que dej\u00f3 al menos cuatro muertos y siete heridos por un enfrentamiento con una \u201clancha infractora\u201d proveniente de Florida que, seg\u00fan las autoridades de la isla, busca infiltrarse \u201ccon fines terroristas\u201d. [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/26\/operativo-cuba-lancha-muertos-orix\/","og_site_name":"Noticias","article_published_time":"2026-02-26T16:04:00+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/26\/operativo-cuba-lancha-muertos-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/26\/operativo-cuba-lancha-muertos-orix\/"},"author":{"name":"","@id":""},"headline":"Qu\u00e9 pas\u00f3 en el operativo en Cuba contra una &#171;lancha infractora&#187; en el que murieron cuatro personas","datePublished":"2026-02-26T16:04:00+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/26\/operativo-cuba-lancha-muertos-orix\/"},"wordCount":824,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/26\/operativo-cuba-lancha-muertos-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/26\/operativo-cuba-lancha-muertos-orix\/","url":"https:\/\/noticiasya.com\/2026\/02\/26\/operativo-cuba-lancha-muertos-orix\/","name":"Qu\u00e9 pas\u00f3 en el operativo en Cuba contra una \"lancha infractora\" en el que murieron cuatro personas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-26T16:04:00+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/26\/operativo-cuba-lancha-muertos-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/26\/operativo-cuba-lancha-muertos-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/26\/operativo-cuba-lancha-muertos-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Qu\u00e9 pas\u00f3 en el operativo en Cuba contra una &#171;lancha infractora&#187; en el que murieron cuatro personas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/26\/operativo-cuba-lancha-muertos-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Qu\u00e9 pas\u00f3 en el operativo en Cuba contra una &#171;lancha infractora&#187; en el que murieron cuatro personas","url":"http:\/\/noticiasya.com\/colorado\/2026\/02\/26\/operativo-cuba-lancha-muertos-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2026\/02\/26\/operativo-cuba-lancha-muertos-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-26T16:04:00Z","datePublished":"2026-02-26T16:04:00Z","dateModified":"2026-02-26T16:04:00Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Qu\\u00e9 pas\\u00f3 en el operativo en Cuba contra una &#171;lancha infractora&#187; en el que murieron cuatro personas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/02\\\/26\\\/operativo-cuba-lancha-muertos-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/02\\\/26\\\/operativo-cuba-lancha-muertos-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-26T16:04:00Z\",\"datePublished\":\"2026-02-26T16:04:00Z\",\"dateModified\":\"2026-02-26T16:04:00Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1471667,"url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/26\/cuba-eeuu-enfrentamiento-lancha-muertos-orix\/","url_meta":{"origin":1471680,"position":0},"title":"Cuba dice que sus fuerzas matan a cuatro en tiroteo despu\u00e9s de que una lancha r\u00e1pida de Florida intentara &#171;infiltrarse&#187;","author":"","date":"febrero 26, 2026","format":false,"excerpt":"Cuba dijo que sus fuerzas dispararon fatalmente a cuatro personas fuertemente armadas que intentaban \u201cinfiltrarse\u201d en su territorio en una lancha r\u00e1pida registrada en Florida el mi\u00e9rcoles, en medio de tensiones latentes entre la isla comunista y Estados Unidos.Efectivos de la guardia fronteriza cubana se acercaron a la embarcaci\u00f3n luego\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471690,"url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/26\/cuba-vicecanciller-lancha-cooperacion-estados-unidos-orix\/","url_meta":{"origin":1471680,"position":1},"title":"EE.UU. &#171;muestra disposici\u00f3n a cooperar&#187; con Cuba tras el incidente de la lancha r\u00e1pida, asegura vicecanciller cubano","author":"","date":"febrero 26, 2026","format":false,"excerpt":"El vicecanciller de Cuba, Carlos Fern\u00e1ndez de Coss\u00edo, dijo este jueves que Estados Unidos \u201cha mostrado disposici\u00f3n a cooperar\u201d un d\u00eda despu\u00e9s de que fuerzas cubanas mataron a 4 personas a bordo de una lancha que intentaba \u201cinfiltrarse\u201d en su territorio en una lancha r\u00e1pida registrada en Florida.Durante una breve\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471936,"url":"https:\/\/noticiasya.com\/colorado\/2026\/03\/06\/cuba-ataque-lancha-eeuu-muerto-efe\/","url_meta":{"origin":1471680,"position":2},"title":"Cuba anuncia la muerte de uno de los seis detenidos en el operativo de la lancha de EE.UU.","author":"","date":"marzo 6, 2026","format":false,"excerpt":"El Ministerio del Interior de Cuba (Minint) anunci\u00f3 este jueves que uno de los seis detenidos por el operativo de la lancha r\u00e1pida procedente de EE.UU. la semana pasada ha muerto a causa de las heridas que sufri\u00f3 en el tiroteo con las tropas guardafronteras.En el \u00faltimo p\u00e1rrafo de un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472766,"url":"https:\/\/noticiasya.com\/colorado\/2026\/04\/01\/fbi-cuba-investiga-ataque-lancha-rapida-orix\/","url_meta":{"origin":1471680,"position":3},"title":"El FBI visita Cuba para investigar ataque a lancha r\u00e1pida de Florida. Los sobrevivientes enfrentan cargos de terrorismo","author":"","date":"abril 1, 2026","format":false,"excerpt":"Un equipo t\u00e9cnico del FBI se encuentra en Cuba para investigar un tiroteo ocurrido en febrero entre soldados cubanos y la tripulaci\u00f3n de una embarcaci\u00f3n procedente de Florida, seg\u00fan ha sabido CNN por dos fuentes familiarizadas con la visita.La inusual visita de fuerzas del orden estadounidenses a la isla gobernada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471694,"url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/26\/ciudadano-eeuu-murio-herido-lancha-cuba-trax\/","url_meta":{"origin":1471680,"position":4},"title":"Un ciudadano de EE.UU. muri\u00f3 y otro result\u00f3 herido en tiroteo entre una lancha r\u00e1pida y autoridades cubanas, dice funcionario","author":"","date":"febrero 26, 2026","format":false,"excerpt":"Un ciudadano de EE.UU. muri\u00f3 y otro result\u00f3 herido en el tiroteo entre una lancha r\u00e1pida y autoridades cubanas ocurrido este mi\u00e9rcoles, dijo a CNN el jueves un funcionario estadounidense.El ciudadano de EE.UU. herido est\u00e1 recibiendo tratamiento m\u00e9dico en Cuba, de acuerdo con el funcionario.Una tercera persona en la lancha\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471669,"url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/26\/5-cosas-26-febrero-orix\/","url_meta":{"origin":1471680,"position":5},"title":"Las 5 cosas que debes saber este 26 de febrero","author":"","date":"febrero 26, 2026","format":false,"excerpt":"Cuba dice que sus fuerzas mataron a cuatro personas despu\u00e9s de que una lancha r\u00e1pida de Florida intentara \u201cinfiltrarse\u201d. Lo que hab\u00eda en el interior del escondite del Mencho. Nominan a Shakira al Sal\u00f3n de la Fama del Rock & Roll. Esto es lo que debes saber para comenzar el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1471680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1471680"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1471680\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1471680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1471680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1471680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}