{"id":1471696,"date":"2026-02-26T16:03:45","date_gmt":"2026-02-27T00:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/26\/netflix-ted-sarandos-casa-blanca-acuerdo-warner-trax\/"},"modified":"2026-02-26T16:03:45","modified_gmt":"2026-02-27T00:03:45","slug":"netflix-ted-sarandos-casa-blanca-acuerdo-warner-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2026\/02\/26\/netflix-ted-sarandos-casa-blanca-acuerdo-warner-trax\/","title":{"rendered":"Netflix se retira de la puja por Warner Bros. despu\u00e9s de que WBD considerara la oferta de Paramount como &#171;superior&#187;"},"content":{"rendered":"<p>Netflix dijo en la tarde de este jueves que ha \u201cdecidido no aumentar su oferta por Warner Bros.\u201d despu\u00e9s de que la junta directiva de Warner Bros. Discovery determinara que Paramount ha presentado una oferta \u201csuperior\u201d.<\/p>\n<p>El anuncio significa que Paramount se ha acercado repentinamente mucho m\u00e1s a tomar el control de CNN y el resto de los activos propiedad de WBD.<\/p>\n<p>\u201cLa transacci\u00f3n que negociamos habr\u00eda creado valor para los accionistas con un camino claro hacia la aprobaci\u00f3n regulatoria\u201d, dijeron los codirectores ejecutivos de Netflix, Ted Sarandos y Greg Peters. \u201cSin embargo, siempre hemos sido disciplinados, y al precio requerido para igualar la \u00faltima oferta de Paramount Skydance, el acuerdo ya no es financieramente atractivo, por lo que hemos decidido no igualar la oferta de Paramount Skydance\u201d.<\/p>\n<p>Las acciones de Netflix subieron m\u00e1s de un 8 % tras la noticia, mostrando que algunos inversores se sintieron aliviados por la decisi\u00f3n de la compa\u00f1\u00eda.<\/p>\n<p>Anteriormente, la junta directiva de Warner Bros. Discovery hab\u00eda considerado que la m\u00e1s reciente oferta de adquisici\u00f3n de Paramount era \u201c<a href=\"https:\/\/www.prnewswire.com\/news-releases\/warner-bros-discovery-board-of-directors-determines-revised-proposal-from-paramount-skydance-constitutes-a-company-superior-proposal-302699009.html\">superior<\/a>\u201d al acuerdo existente con Netflix para la compra de Warner Bros y HBO. Netflix ten\u00eda cuatro d\u00edas h\u00e1biles para revisar su propia oferta y responder.<\/p>\n<p>La oferta m\u00e1s reciente de Paramount, anunciada el martes, valor\u00f3 la totalidad de WBD, incluyendo CNN, en US$ 31 por acci\u00f3n. Paramount adjunt\u00f3 varios incentivos al acuerdo que atrajeron a la junta de WBD, incluyendo una \u201ctarifa de terminaci\u00f3n regulatoria\u201d de US$ 7.000 millones.<\/p>\n<p>Cuando WBD public\u00f3 sus resultados trimestrales el jueves por la ma\u00f1ana, el CEO David Zaslav dijo que la guerra de ofertas ha \u201cllevado a ocho aumentos de precio\u201d y \u201chasta ahora ha logrado un aumento del 63 % en el valor frente a la primera oferta recibida en septiembre, generando un valor significativo para los accionistas de WBD durante todo el proceso\u201d.<\/p>\n<p>\u201cNos complace que la junta de WBD haya afirmado por unanimidad el valor superior de nuestra oferta, que brinda a los accionistas de WBD un valor superior, certeza y rapidez para cerrar\u201d, dijo el CEO de Paramount, David Ellison, en un comunicado.<\/p>\n<p>El codirector ejecutivo de Netflix, Ted Sarandos, visit\u00f3 la Casa Blanca el jueves para reuniones \u2014aunque no con el presidente\u2014 justo antes de que WBD anunciara el nuevo giro en la saga de la mega-fusi\u00f3n.<\/p>\n<p>El presidente Trump ha indicado previamente que est\u00e1 a favor de Paramount. Y el fin de semana pasado, dijo p\u00fablicamente a Netflix que retirara de su junta directiva a Susan Rice, ex asesora de Obama, o \u201cpagar\u00e1 las consecuencias\u201d, renovando la posibilidad de que intervenga en la balanza corporativa.<\/p>\n<p>Si la fusi\u00f3n con Netflix sigue adelante, algunos analistas de la industria esperan que el Departamento de Justicia de Trump demande para bloquear el acuerdo, lo que podr\u00eda llevar a un prolongado per\u00edodo de litigio.<\/p>\n<p>Pero Sarandos ha mostrado confianza en la capacidad de Netflix para concretar el acuerdo.<\/p>\n<p>Un informe de Politico del mi\u00e9rcoles sobre la pr\u00f3xima visita de Sarandos gener\u00f3 especulaciones sobre si el jefe de Netflix se reunir\u00eda cara a cara con el presidente. Eso aparentemente llev\u00f3 a la Casa Blanca a aclarar el jueves que Sarandos no se reunir\u00eda directamente con Trump.<\/p>\n<p>\u201cNetflix se est\u00e1 reuniendo con miembros del personal en la Casa Blanca\u201d, dijo un funcionario de la Casa Blanca a CNN.<\/p>\n<p>Eso coincidi\u00f3 con la versi\u00f3n de un portavoz de Netflix, quien dijo que la direcci\u00f3n de la compa\u00f1\u00eda no solicit\u00f3 una reuni\u00f3n con Trump en primer lugar.<\/p>\n<p>El portavoz de Netflix tambi\u00e9n dijo que la visita con los miembros del personal fue organizada hace dos semanas y media.<\/p>\n<p>Con la aprobaci\u00f3n original de Netflix, WBD hab\u00eda abierto una ventana para nuevas conversaciones con Paramount la semana pasada, y el martes, la junta directiva de WBD confirm\u00f3 que Paramount hab\u00eda aumentado su oferta a US$ 31 por acci\u00f3n.<\/p>\n<p>Paramount hizo otras promesas para hacer la oferta todav\u00eda m\u00e1s atractiva, incluyendo una \u201ctarifa de terminaci\u00f3n regulatoria de US$ 7.000 millones\u201d, enfatizando la confianza de Paramount en que su acuerdo no ser\u00eda bloqueado por la administraci\u00f3n Trump.<\/p>\n<p>El CEO de Paramount, David Ellison, ha tomado varias medidas para forjar una relaci\u00f3n cercana con Trump. Los dos tuvieron una reuni\u00f3n privada en la Casa Blanca a principios de este mes, como inform\u00f3 previamente CNN.<\/p>\n<p>Poco despu\u00e9s de la reuni\u00f3n con Ellison, Trump <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/12\/eeuu\/trump-david-ellison-reunion-paramount-netflix-trax\">dijo en una entrevista<\/a> que \u201cno he estado involucrado\u201d en la batalla sobre WBD, a pesar de que previamente hab\u00eda dicho sobre el acuerdo con Netflix: \u201cYo tambi\u00e9n estar\u00e9 involucrado en esa decisi\u00f3n\u201d.<\/p>\n<p>Trump tambi\u00e9n ha dicho que es \u201c<a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/10\/eeuu\/trump-disputa-warner-bros-discovery-venta-cnn-trax\">imperativo que CNN sea vendida<\/a>\u201d, y lo cierto es que el acuerdo actual con Netflix no implica la venta de CNN; en cambio, se escindir\u00eda en una nueva entidad junto con otros activos de cable de WBD.<\/p>\n<p>Sarandos ha estado en la Casa Blancaen varias ocasiones en los \u00faltimos meses, aunque no siempre para reunirse con el presidente.<\/p>\n<p>Trump ha elogiado a Sarandos como una \u201cgran persona\u201d, pero ha publicado cr\u00edticas a Netflix en Truth Social.<\/p>\n<p>Sarandos, por su parte, ha elogiado el inter\u00e9s de Trump en la industria del entretenimiento y ha minimizado las cr\u00edticas.<\/p>\n<p>Cuando la BBC le pregunt\u00f3 sobre la publicaci\u00f3n de Trumpen la que ataca a Rice, Sarandos dijo: \u201ceste es un acuerdo comercial. No es un acuerdo pol\u00edtico. Este acuerdo est\u00e1 dirigido por el Departamento de Justicia de EE.UU. y los reguladores de toda Europa y el mundo\u201d.<\/p>\n<p>El siguiente movimiento le corresponder\u00e1 a Netflix, dada la determinaci\u00f3n de la junta directiva de WBD el jueves por la tarde.<\/p>\n<p>El CEO de Paramount, David Ellison, dijo en respuesta: \u201cnos complace que la Junta Directiva de WBD haya afirmado por unanimidad el valor superior de nuestra oferta, que brinda a los accionistas de WBD un valor superior, certeza y rapidez en el cierre\u201d.<\/p>\n<p>M\u00e1s temprano el jueves, cuando WBD public\u00f3 las ganancias trimestrales, el CEO David Zaslav dijo que la actual guerra de ofertas ha \u201cllevado a ocho aumentos de precio\u201d y \u201chasta ahora ha logrado un aumento del 63% en el valor frente a la primera oferta recibida en septiembre, entregando un valor significativo para los accionistas de WBD a lo largo del proceso\u201d.<\/p>\n<p>\u201cNuestro enfoque ha sido y siempre ser\u00e1 maximizar el valor y la certeza mientras mitigamos los riesgos a la baja\u201d, dijo, \u201cy la junta evaluar\u00e1 cualquier propuesta seg\u00fan ese est\u00e1ndar, con el objetivo de lograr el mejor acuerdo para nuestros accionistas\u201d.<\/p>\n<p><em>Alejandra Jaramillo y Liam Reilly contribuyeron con este informe.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Netflix dijo en la tarde de este jueves que ha \u201cdecidido no aumentar su oferta por Warner Bros.\u201d despu\u00e9s de que la junta directiva de Warner Bros. Discovery determinara que Paramount ha presentado una oferta \u201csuperior\u201d. El anuncio significa que Paramount se ha acercado repentinamente mucho m\u00e1s a tomar el control de CNN y el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1471696","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Netflix se retira de la puja por Warner Bros. despu\u00e9s de que WBD considerara la oferta de Paramount como &quot;superior&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/26\/netflix-ted-sarandos-casa-blanca-acuerdo-warner-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Netflix se retira de la puja por Warner Bros. despu\u00e9s de que WBD considerara la oferta de Paramount como &quot;superior&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"Netflix dijo en la tarde de este jueves que ha \u201cdecidido no aumentar su oferta por Warner Bros.\u201d despu\u00e9s de que la junta directiva de Warner Bros. Discovery determinara que Paramount ha presentado una oferta \u201csuperior\u201d. El anuncio significa que Paramount se ha acercado repentinamente mucho m\u00e1s a tomar el control de CNN y el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/26\/netflix-ted-sarandos-casa-blanca-acuerdo-warner-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-27T00:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/26\/netflix-ted-sarandos-casa-blanca-acuerdo-warner-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/26\/netflix-ted-sarandos-casa-blanca-acuerdo-warner-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Netflix se retira de la puja por Warner Bros. despu\u00e9s de que WBD considerara la oferta de Paramount como &#171;superior&#187;\",\"datePublished\":\"2026-02-27T00:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/26\/netflix-ted-sarandos-casa-blanca-acuerdo-warner-trax\/\"},\"wordCount\":1163,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/26\/netflix-ted-sarandos-casa-blanca-acuerdo-warner-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/26\/netflix-ted-sarandos-casa-blanca-acuerdo-warner-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/26\/netflix-ted-sarandos-casa-blanca-acuerdo-warner-trax\/\",\"name\":\"Netflix se retira de la puja por Warner Bros. despu\u00e9s de que WBD considerara la oferta de Paramount como \\\"superior\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-27T00:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/26\/netflix-ted-sarandos-casa-blanca-acuerdo-warner-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/26\/netflix-ted-sarandos-casa-blanca-acuerdo-warner-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/26\/netflix-ted-sarandos-casa-blanca-acuerdo-warner-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Netflix se retira de la puja por Warner Bros. despu\u00e9s de que WBD considerara la oferta de Paramount como &#171;superior&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Netflix se retira de la puja por Warner Bros. despu\u00e9s de que WBD considerara la oferta de Paramount como \"superior\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/26\/netflix-ted-sarandos-casa-blanca-acuerdo-warner-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Netflix se retira de la puja por Warner Bros. despu\u00e9s de que WBD considerara la oferta de Paramount como \"superior\" - Noticias","og_description":"Netflix dijo en la tarde de este jueves que ha \u201cdecidido no aumentar su oferta por Warner Bros.\u201d despu\u00e9s de que la junta directiva de Warner Bros. Discovery determinara que Paramount ha presentado una oferta \u201csuperior\u201d. El anuncio significa que Paramount se ha acercado repentinamente mucho m\u00e1s a tomar el control de CNN y el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/26\/netflix-ted-sarandos-casa-blanca-acuerdo-warner-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-27T00:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/26\/netflix-ted-sarandos-casa-blanca-acuerdo-warner-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/26\/netflix-ted-sarandos-casa-blanca-acuerdo-warner-trax\/"},"author":{"name":"","@id":""},"headline":"Netflix se retira de la puja por Warner Bros. despu\u00e9s de que WBD considerara la oferta de Paramount como &#171;superior&#187;","datePublished":"2026-02-27T00:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/26\/netflix-ted-sarandos-casa-blanca-acuerdo-warner-trax\/"},"wordCount":1163,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/26\/netflix-ted-sarandos-casa-blanca-acuerdo-warner-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/26\/netflix-ted-sarandos-casa-blanca-acuerdo-warner-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/26\/netflix-ted-sarandos-casa-blanca-acuerdo-warner-trax\/","name":"Netflix se retira de la puja por Warner Bros. despu\u00e9s de que WBD considerara la oferta de Paramount como \"superior\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-27T00:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/26\/netflix-ted-sarandos-casa-blanca-acuerdo-warner-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/26\/netflix-ted-sarandos-casa-blanca-acuerdo-warner-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/26\/netflix-ted-sarandos-casa-blanca-acuerdo-warner-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Netflix se retira de la puja por Warner Bros. despu\u00e9s de que WBD considerara la oferta de Paramount como &#171;superior&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/26\/netflix-ted-sarandos-casa-blanca-acuerdo-warner-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Netflix se retira de la puja por Warner Bros. despu\u00e9s de que WBD considerara la oferta de Paramount como &#171;superior&#187;","url":"http:\/\/noticiasya.com\/colorado\/2026\/02\/26\/netflix-ted-sarandos-casa-blanca-acuerdo-warner-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2026\/02\/26\/netflix-ted-sarandos-casa-blanca-acuerdo-warner-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-27T00:03:45Z","datePublished":"2026-02-27T00:03:45Z","dateModified":"2026-02-27T00:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Netflix se retira de la puja por Warner Bros. despu\\u00e9s de que WBD considerara la oferta de Paramount como &#171;superior&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/02\\\/26\\\/netflix-ted-sarandos-casa-blanca-acuerdo-warner-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/02\\\/26\\\/netflix-ted-sarandos-casa-blanca-acuerdo-warner-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-27T00:03:45Z\",\"datePublished\":\"2026-02-27T00:03:45Z\",\"dateModified\":\"2026-02-27T00:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1469074,"url":"https:\/\/noticiasya.com\/colorado\/2025\/12\/08\/paramount-lanza-oferta-publica-adquisicion-warner-wbd-trax\/","url_meta":{"origin":1471696,"position":0},"title":"Paramount lanza una oferta p\u00fablica de adquisici\u00f3n hostil sobre Warner Bros. Discovery","author":"","date":"diciembre 8, 2025","format":false,"excerpt":"Paramount se ha dirigido directamente a los accionistas de Warner Bros. Discovery con una oferta en efectivo por la empresa que, seg\u00fan afirma, es m\u00e1s valiosa que el acuerdo de Netflix anunciado el viernes.Se esperaba ampliamente que Paramount fuera el favorito para Warner Bros. Pero WBD \u2014que es la empresa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470256,"url":"https:\/\/noticiasya.com\/colorado\/2026\/01\/20\/netflix-oferta-warner-bros-discovery-efectivo-trax\/","url_meta":{"origin":1471696,"position":1},"title":"Netflix revisa su oferta por Warner Bros. Discovery. Ahora, es todo en efectivo","author":"","date":"enero 20, 2026","format":false,"excerpt":"En la lucha por el futuro de Warner Bros. Discovery, Netflix dice que est\u00e1 dispuesto a pagar todo en efectivo por Warner Bros. y HBO, en lugar de una combinaci\u00f3n de efectivo y acciones.Netflix y Warner Bros. Discovery \u2014WBD para abreviar\u2014 anunciaron el plan modificado este martes por la ma\u00f1ana,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471311,"url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/17\/warner-bros-discovery-fusion-netflix-paramount-trax\/","url_meta":{"origin":1471696,"position":2},"title":"Warner Bros. Discovery respalda la fusi\u00f3n con Netflix mientras reabre la conversaci\u00f3n con Paramount","author":"","date":"febrero 17, 2026","format":false,"excerpt":"Warner Bros. Discovery quiere escuchar la \u201cmejor y \u00faltima propuesta\u201d de Paramount para la empresa de medios, y est\u00e1 abriendo una breve ventana para discutir una oferta, al tiempo que avanza con su fusi\u00f3n con Netflix e insta a los accionistas a rechazar la actual oferta hostil de Paramount.Si esto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470014,"url":"https:\/\/noticiasya.com\/colorado\/2026\/01\/12\/paramount-demanda-warner-bros-discovery-netflix-trax\/","url_meta":{"origin":1471696,"position":3},"title":"Paramount presenta una demanda contra Warner Bros. Discovery y amenaza con una batalla por el control de la compa\u00f1\u00eda","author":"","date":"enero 12, 2026","format":false,"excerpt":"Paramount decidi\u00f3 llevar a los tribunales su intento de adquirir Warner Bros. Discovery, la empresa matriz de CNN.El lunes, el CEO de Paramount, David Ellison, anunci\u00f3 una demanda ante el tribunal de equidad de Delaware, donde habitualmente se resuelven las disputas corporativas entre accionistas, en su intento de compra hostil\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469912,"url":"https:\/\/noticiasya.com\/colorado\/2026\/01\/08\/paramount-respuesta-wbd-oferta-fusion-medios-trax\/","url_meta":{"origin":1471696,"position":4},"title":"Paramount se mantiene firme en su oferta de US$ 30 por acci\u00f3n, mientras que WBD respalda el acuerdo con Netflix","author":"","date":"enero 8, 2026","format":false,"excerpt":"Paramount no est\u00e1 aumentando su oferta por Warner Bros. Discovery por encima de US$ 30 por acci\u00f3n, al menos por ahora.Este jueves, Paramount respondi\u00f3 a la \u00faltima carta de rechazo de WBD reiterando su opini\u00f3n de que los accionistas deber\u00edan apoyar su oferta de toma de control hostil.\u201cLa oferta de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469491,"url":"https:\/\/noticiasya.com\/colorado\/2025\/12\/22\/paramount-nueva-oferta-warner-ellison-trax\/","url_meta":{"origin":1471696,"position":5},"title":"Nueva oferta hostil de Paramount a Warner Bros. Discovery: Larry Ellison garantizar\u00e1 personalmente US$ 40.000 millones","author":"","date":"diciembre 22, 2025","format":false,"excerpt":"Paramount ha reforzado su oferta de adquisici\u00f3n de Warner Bros. Discovery, al anunciar este lunes que Larry Ellison garantizar\u00e1 personalmente las decenas de miles de millones de d\u00f3lares para financiar la transacci\u00f3n. La familia Ellison tambi\u00e9n permitir\u00e1 que los accionistas examinen las finanzas del fideicomiso familiar.El consejo de administraci\u00f3n de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1471696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1471696"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1471696\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1471696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1471696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1471696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}