{"id":1471738,"date":"2026-02-27T16:03:41","date_gmt":"2026-02-28T00:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/27\/gobierno-ordena-militares-agencias-federales-no-trabajar-anthropic-trax\/"},"modified":"2026-02-27T16:03:41","modified_gmt":"2026-02-28T00:03:41","slug":"gobierno-ordena-militares-agencias-federales-no-trabajar-anthropic-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2026\/02\/27\/gobierno-ordena-militares-agencias-federales-no-trabajar-anthropic-trax\/","title":{"rendered":"El Gobierno de Trump ordena a contratistas militares y agencias federales cesar negocios con Anthropic"},"content":{"rendered":"<p>El Gobierno de Trump orden\u00f3 a las agencias federales y a los contratistas que trabajan con las Fuerzas Armadas que dejen de hacer negocios con Anthropic, despu\u00e9s de que la empresa se negara a permitir que el Pent\u00e1gono utilizara su tecnolog\u00eda de inteligencia artificial sin restricciones.<\/p>\n<p>Las agencias gubernamentales, incluido el Pent\u00e1gono, tienen seis meses para eliminar gradualmente el uso de los productos de Anthropic, dijo el presidente Donald Trump en una <a href=\"https:\/\/truthsocial.com\/@realDonaldTrump\/posts\/116144552969293195\">publicaci\u00f3n en Truth Social <\/a>este viernes por la tarde. El secretario de Defensa, Pete Hegseth, dijo m\u00e1s tarde<a href=\"https:\/\/x.com\/secwar\/status\/2027507717469049070?s=46&#038;t=w3_umnYjt1oZp7aUdyD1Cw\"> en X<\/a> que Anthropic ser\u00e1 considerado un \u201criesgo para la cadena de suministro\u201d, una designaci\u00f3n que por lo general se reserva para empresas consideradas extensiones de adversarios extranjeros.<\/p>\n<p>La medida culmina un enfrentamiento de una semana entre una empresa l\u00edder de IA y el Gobierno, que podr\u00eda definir el futuro de c\u00f3mo se utiliza esta tecnolog\u00eda en r\u00e1pido desarrollo.<\/p>\n<p>Anthropic ha estado en desacuerdo con el Pent\u00e1gono por las restricciones impuestas a su popular modelo de IA.<\/p>\n<p>El Pent\u00e1gono, que utiliza el sistema Claude de Anthropic en sus redes clasificadas, quiere poder usarlo para \u201ctodos los fines legales\u201d. Pero Anthropic tiene dos l\u00edneas rojas para el Pent\u00e1gono: que Claude no se use en armas aut\u00f3nomas y que no se use en la vigilancia masiva de ciudadanos de Estados Unidos.<\/p>\n<p>El Pent\u00e1gono sostiene que no tiene inter\u00e9s en usar la IA para esos fines y que necesita libertad para utilizar la tecnolog\u00eda que est\u00e1 licenciando.<\/p>\n<p>El estancamiento lleg\u00f3 a su punto m\u00e1ximo el martes en una reuni\u00f3n de alto nivel en el Pent\u00e1gono entre Hegseth y el CEO de Anthropic, Dario Amodei. Aunque una fuente familiarizada con el asunto dijo que la reuni\u00f3n fue cordial, los comentarios de Trump este viernes sugieren que la situaci\u00f3n cambi\u00f3.<\/p>\n<p>Anthropic anunci\u00f3 el jueves que no ten\u00eda intenci\u00f3n de acceder a las exigencias del Pent\u00e1gono.<\/p>\n<p>\u201cLas amenazas no cambian nuestra posici\u00f3n: no podemos, en buena conciencia, acceder a su solicitud\u201d, dijo Amodei en un comunicado.<\/p>\n<p>Emil Michael, subsecretario de Investigaci\u00f3n e Ingenier\u00eda del Pent\u00e1gono, dijo en una entrevista <a href=\"https:\/\/x.com\/DoWCTO\/status\/2027389934106034248\">con Bloomberg<\/a> que estaban \u201cen las etapas finales\u201d de un acuerdo con Anthropic que habr\u00eda \u201caceptado en sustancia lo que ellos quer\u00edan\u201d cuando la empresa emiti\u00f3 su comunicado del jueves.<\/p>\n<p>\u201cEsta es una solicitud simple y de sentido com\u00fan que evitar\u00e1 que Anthropic ponga en peligro operaciones militares cr\u00edticas y potencialmente ponga en riesgo a nuestros combatientes\u201d, escribi\u00f3 el portavoz del Pent\u00e1gono, Sean Parnell, en X. \u201cNo permitiremos que NINGUNA empresa dicte los t\u00e9rminos sobre c\u00f3mo tomamos decisiones operativas\u201d.<\/p>\n<p>Trump dijo en Truth Social este viernes que Anthropic ha cometido un \u201cerror desastroso\u201d y la acus\u00f3 de intentar dictar c\u00f3mo operan las Fuerzas Armadas. Poco despu\u00e9s de la publicaci\u00f3n de Trump, la Administraci\u00f3n de Servicios Generales dijo que eliminar\u00eda a Anthropic de <a href=\"http:\/\/usai.gov\/\">USAi.gov, <\/a>el campo de pruebas centralizado del Gobierno federal para herramientas de IA.<\/p>\n<p>\u201cNing\u00fan contratista, proveedor o socio que haga negocios con las Fuerzas Armadas de Estados Unidos\u201d tendr\u00e1 permitido hacer negocios con Anthropic, dijo Hegseth este viernes.<\/p>\n<p>La industria de la IA en gran medida sali\u00f3 en defensa de Anthropic esta semana, y el CEO de OpenAI, Sam Altman, dijo que comparte las preocupaciones de Anthropic cuando se trata de trabajar con el Pent\u00e1gono.<\/p>\n<p>Anthropic y OpenAI no respondieron de inmediato a la solicitud de comentarios de CNN.<\/p>\n<p>Claude, de Anthropic, fue el primer modelo de IA que trabaj\u00f3 en las redes clasificadas de las Fuerzas Armadas. La empresa firm\u00f3 un contrato por hasta US$ 200 millones con el Pent\u00e1gono el verano pasado. Otras grandes empresas de IA como OpenAI solo han firmado acuerdos con el Pent\u00e1gono en sus redes no clasificadas.<\/p>\n<p>La \u201cpol\u00edtica de uso aceptable\u201d de Anthropic, incluida en el contrato, proh\u00edbe el uso de Claude en vigilancia masiva y armas aut\u00f3nomas.<\/p>\n<p>\u201cEsta disputa surge en un momento delicado porque, por un lado, la base de usuarios dentro del Departamento de Defensa ama Anthropic, ama Claude, y dice que sus restricciones de uso, al menos en las conversaciones que he tenido, nunca se han activado\u201d, dijo Gregory Allen, asesor principal del Centro de Estudios Estrat\u00e9gicos e Internacionales, en Bloomberg Radio.<\/p>\n<p>Sin embargo, el Pent\u00e1gono no quiere estar limitado por las pol\u00edticas de una empresa. Un funcionario del Pent\u00e1gono asegur\u00f3 a CNN: \u201cNo se puede liderar operaciones t\u00e1cticas por excepci\u00f3n\u201d y \u201cla legalidad es responsabilidad del Pent\u00e1gono como usuario final\u201d.<\/p>\n<p>Desde la perspectiva del Pent\u00e1gono, no quiere estar en medio de una situaci\u00f3n de seguridad nacional, tener que pedir permiso a una empresa y que se eliminen las restricciones.<\/p>\n<p>Romper lazos con Anthropic podr\u00eda ser un problema para el Pent\u00e1gono si se considera que tendr\u00edan que reemplazar cualquier sistema interno que utilice Claude. Aunque un funcionario del Pent\u00e1gono dijo que el sistema de IA Grok de Elon Musk \u201cest\u00e1 dispuesto a ser utilizado en un entorno clasificado\u201d, Grok no es considerado tan avanzado como Claude.<\/p>\n<p>Perder un contrato de US$ 200 millones no representar\u00eda una amenaza existencial para Anthropic, que recientemente fue valorada en alrededor de US$ 380.000 millones. El mayor riesgo es que se le considere como un riesgo en la cadena de suministro, lo que significa que cualquier empresa que trabaje con las Fuerzas Armadas de Estados Unidos tendr\u00eda que demostrar que no tiene relaci\u00f3n con Anthropic en su trabajo con el Pent\u00e1gono.<\/p>\n<p>Gran parte del \u00e9xito de Anthropic proviene de sus contratos empresariales con grandes compa\u00f1\u00edas, muchas de las cuales pueden tener contratos con el Pent\u00e1gono.<\/p>\n<p>\u201cEsto significa que una gran parte de la base de clientes actual de Anthropic podr\u00eda desaparecer, ya sea porque tienen contratos gubernamentales o porque podr\u00edan desearlos en el futuro\u201d, declar\u00f3 Adam Connor, vicepresidente de pol\u00edtica tecnol\u00f3gica del <a href=\"https:\/\/www.americanprogress.org\/article\/the-trump-administration-is-trying-to-make-an-example-of-the-ai-giant-anthropic\/\">Center for American Progress<\/a>, un centro de estudios con sede en Washington.<\/p>\n<p>Jensen Huang, CEO del importante fabricante de chips de IA Nvidia, dijo que, aunque espera que el Pent\u00e1gono y Anthropic puedan llegar a un acuerdo, \u201csi no se resuelve, tampoco es el fin del mundo\u201d, ya que hay otras empresas de IA con las que el Pent\u00e1gono puede trabajar y Anthropic tiene otros clientes.<\/p>\n<p>A principios de esta semana, el Pent\u00e1gono dijo que tambi\u00e9n considerar\u00eda obligar a Anthropic a trabajar con ellos a trav\u00e9s de la Ley de Producci\u00f3n de Defensa, una legislaci\u00f3n de 1950 que \u201cle da al presidente una autoridad de emergencia para controlar las industrias nacionales\u201d, seg\u00fan el Consejo de Relaciones Exteriores. No est\u00e1 claro si el Pent\u00e1gono podr\u00eda tanto obligar a Anthropic a trabajar con ellos a trav\u00e9s de la DPA como considerarlos un riesgo en la cadena de suministro, ni c\u00f3mo.<\/p>\n<p>Connor dijo que Anthropic no es la \u00fanica empresa bajo amenaza. La medida del Pent\u00e1gono es una se\u00f1al para otras empresas de IA que buscan ganar millones vendiendo sus servicios al Gobierno.<\/p>\n<p>\u201cCreo que, en un sentido m\u00e1s amplio, esto env\u00eda un mensaje a las otras empresas de IA con las que est\u00e1n negociando para asegurarse de que no intenten imponer ning\u00fan tipo de restricci\u00f3n sobre los usos de la IA\u201d, dijo Connor.<\/p>\n<p>Si el Pent\u00e1gono simplemente estuviera insatisfecho con las condiciones de Anthropic para su modelo, podr\u00eda terminar el contrato y conseguir el modelo de IA que quiere de otra empresa, dijo Alan Rozenshtein, profesor de derecho en la Universidad de Minnesota.<\/p>\n<p>\u201cLo que realmente quiere el Gobierno es seguir usando la tecnolog\u00eda de Anthropic, y est\u00e1 usando todas las fuentes de presi\u00f3n posibles\u201d, dijo. \u201cEsta es una fuente de presi\u00f3n muy poderosa\u201d.<\/p>\n<p>No est\u00e1 claro c\u00f3mo las Fuerzas Armadas reemplazar\u00edan los sistemas de Anthropic, o si el Gobierno planea tomar m\u00e1s medidas por el momento.<\/p>\n<p>\u201cTomar a un campe\u00f3n nacional de IA en un momento en que la Casa Blanca dice que la carrera de IA con China es equivalente a la carrera espacial durante la Guerra Fr\u00eda con la Uni\u00f3n Sovi\u00e9tica, no quieres tomar una de las joyas de la corona de tu industria y prenderle fuego por algo as\u00ed\u201d, dijo Allen en Bloomberg.<\/p>\n<p>\u201cHay una mejor manera de resolver esta disputa que la postura absolutista que ha tomado el Gobierno\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno de Trump orden\u00f3 a las agencias federales y a los contratistas que trabajan con las Fuerzas Armadas que dejen de hacer negocios con Anthropic, despu\u00e9s de que la empresa se negara a permitir que el Pent\u00e1gono utilizara su tecnolog\u00eda de inteligencia artificial sin restricciones. Las agencias gubernamentales, incluido el Pent\u00e1gono, tienen seis meses [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1471738","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Gobierno de Trump ordena a contratistas militares y agencias federales cesar negocios con Anthropic - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/27\/gobierno-ordena-militares-agencias-federales-no-trabajar-anthropic-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Gobierno de Trump ordena a contratistas militares y agencias federales cesar negocios con Anthropic - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Gobierno de Trump orden\u00f3 a las agencias federales y a los contratistas que trabajan con las Fuerzas Armadas que dejen de hacer negocios con Anthropic, despu\u00e9s de que la empresa se negara a permitir que el Pent\u00e1gono utilizara su tecnolog\u00eda de inteligencia artificial sin restricciones. Las agencias gubernamentales, incluido el Pent\u00e1gono, tienen seis meses [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/27\/gobierno-ordena-militares-agencias-federales-no-trabajar-anthropic-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-28T00:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/27\/gobierno-ordena-militares-agencias-federales-no-trabajar-anthropic-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/27\/gobierno-ordena-militares-agencias-federales-no-trabajar-anthropic-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El Gobierno de Trump ordena a contratistas militares y agencias federales cesar negocios con Anthropic\",\"datePublished\":\"2026-02-28T00:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/27\/gobierno-ordena-militares-agencias-federales-no-trabajar-anthropic-trax\/\"},\"wordCount\":1469,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/27\/gobierno-ordena-militares-agencias-federales-no-trabajar-anthropic-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/27\/gobierno-ordena-militares-agencias-federales-no-trabajar-anthropic-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/27\/gobierno-ordena-militares-agencias-federales-no-trabajar-anthropic-trax\/\",\"name\":\"El Gobierno de Trump ordena a contratistas militares y agencias federales cesar negocios con Anthropic - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-28T00:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/27\/gobierno-ordena-militares-agencias-federales-no-trabajar-anthropic-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/27\/gobierno-ordena-militares-agencias-federales-no-trabajar-anthropic-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/27\/gobierno-ordena-militares-agencias-federales-no-trabajar-anthropic-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Gobierno de Trump ordena a contratistas militares y agencias federales cesar negocios con Anthropic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Gobierno de Trump ordena a contratistas militares y agencias federales cesar negocios con Anthropic - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/27\/gobierno-ordena-militares-agencias-federales-no-trabajar-anthropic-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El Gobierno de Trump ordena a contratistas militares y agencias federales cesar negocios con Anthropic - Noticias","og_description":"El Gobierno de Trump orden\u00f3 a las agencias federales y a los contratistas que trabajan con las Fuerzas Armadas que dejen de hacer negocios con Anthropic, despu\u00e9s de que la empresa se negara a permitir que el Pent\u00e1gono utilizara su tecnolog\u00eda de inteligencia artificial sin restricciones. Las agencias gubernamentales, incluido el Pent\u00e1gono, tienen seis meses [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/27\/gobierno-ordena-militares-agencias-federales-no-trabajar-anthropic-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-28T00:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/27\/gobierno-ordena-militares-agencias-federales-no-trabajar-anthropic-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/27\/gobierno-ordena-militares-agencias-federales-no-trabajar-anthropic-trax\/"},"author":{"name":"","@id":""},"headline":"El Gobierno de Trump ordena a contratistas militares y agencias federales cesar negocios con Anthropic","datePublished":"2026-02-28T00:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/27\/gobierno-ordena-militares-agencias-federales-no-trabajar-anthropic-trax\/"},"wordCount":1469,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/27\/gobierno-ordena-militares-agencias-federales-no-trabajar-anthropic-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/27\/gobierno-ordena-militares-agencias-federales-no-trabajar-anthropic-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/27\/gobierno-ordena-militares-agencias-federales-no-trabajar-anthropic-trax\/","name":"El Gobierno de Trump ordena a contratistas militares y agencias federales cesar negocios con Anthropic - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-28T00:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/27\/gobierno-ordena-militares-agencias-federales-no-trabajar-anthropic-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/27\/gobierno-ordena-militares-agencias-federales-no-trabajar-anthropic-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/27\/gobierno-ordena-militares-agencias-federales-no-trabajar-anthropic-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El Gobierno de Trump ordena a contratistas militares y agencias federales cesar negocios con Anthropic"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/27\/gobierno-ordena-militares-agencias-federales-no-trabajar-anthropic-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El Gobierno de Trump ordena a contratistas militares y agencias federales cesar negocios con Anthropic","url":"http:\/\/noticiasya.com\/colorado\/2026\/02\/27\/gobierno-ordena-militares-agencias-federales-no-trabajar-anthropic-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2026\/02\/27\/gobierno-ordena-militares-agencias-federales-no-trabajar-anthropic-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-28T00:03:41Z","datePublished":"2026-02-28T00:03:41Z","dateModified":"2026-02-28T00:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El Gobierno de Trump ordena a contratistas militares y agencias federales cesar negocios con Anthropic\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/02\\\/27\\\/gobierno-ordena-militares-agencias-federales-no-trabajar-anthropic-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/02\\\/27\\\/gobierno-ordena-militares-agencias-federales-no-trabajar-anthropic-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-28T00:03:41Z\",\"datePublished\":\"2026-02-28T00:03:41Z\",\"dateModified\":\"2026-02-28T00:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1472016,"url":"https:\/\/noticiasya.com\/colorado\/2026\/03\/09\/anthropic-demanda-gobierno-trump-trax\/","url_meta":{"origin":1471738,"position":0},"title":"Anthropic demanda al Gobierno de Trump tras ser designada como riesgo para la cadena de suministro","author":"","date":"marzo 9, 2026","format":false,"excerpt":"Anthropic demand\u00f3 el lunes al Departamento de Defensa y a otras agencias federales por la decisi\u00f3n de la administraci\u00f3n Trump de etiquetar a la empresa de IA como un \u201criesgo para la cadena de suministro\u201d.La demanda es el \u00faltimo avance en el conflicto entre el Pent\u00e1gono y una de las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472297,"url":"https:\/\/noticiasya.com\/colorado\/2026\/03\/17\/exjueces-apoyan-anthropic-pentagono-riesgo-trax\/","url_meta":{"origin":1471738,"position":1},"title":"Exjueces apoyan a Anthropic y expresan recelos por el uso del Pent\u00e1gono de la etiqueta de riesgo en la cadena de suministro","author":"","date":"marzo 17, 2026","format":false,"excerpt":"Casi 150 jueces federales y estatales jubilados presentaron el martes un escrito amicus curiae en apoyo a la empresa de IA, Anthropic, en su demanda contra el Gobierno de Trump por designarla como un \u201criesgo en la cadena de suministro\u201d, seg\u00fan ha sabido CNN.Los exjueces, nombrados tanto por republicanos como\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471752,"url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/28\/openai-pentagono-trump-prohibe-anthropic-trax\/","url_meta":{"origin":1471738,"position":2},"title":"OpenAI llega a un acuerdo con el Pent\u00e1gono horas despu\u00e9s de que el Gobierno de Trump prohibiera a Anthropic","author":"","date":"febrero 28, 2026","format":false,"excerpt":"El CEO de OpenAI, Sam Altman, anunci\u00f3 el viernes por la noche que la compa\u00f1\u00eda hab\u00eda firmado un acuerdo con el Pent\u00e1gono para que sus herramientas de IA se utilizaran en los sistemas clasificados militares, pero con restricciones aparentemente similares a las que su rival Anthropic tambi\u00e9n hab\u00eda solicitado.El acuerdo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472596,"url":"https:\/\/noticiasya.com\/colorado\/2026\/03\/26\/jueza-bloquea-pentagono-castigar-anthropic-trax\/","url_meta":{"origin":1471738,"position":3},"title":"Jueza bloquea el esfuerzo del Pent\u00e1gono por &#171;castigar&#187; a Anthropic al catalogarla como un riesgo para la cadena de suministro","author":"","date":"marzo 26, 2026","format":false,"excerpt":"Una jueza federal en California bloque\u00f3 indefinidamente el esfuerzo del Pent\u00e1gono por \u201ccastigar\u201d a Anthropic al etiquetarla como un riesgo para la cadena de suministro e intentar cortar los v\u00ednculos del Gobierno con la empresa de Inteligencia Artificial (IA), al dictaminar que esas medidas atropellaban sus derechos constitucionales.\u201cNada en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471637,"url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/25\/anthropic-abandona-seguridad-ia-pentagono-trax\/","url_meta":{"origin":1471738,"position":4},"title":"Anthropic abandona su principal promesa de seguridad en medio de una pelea por los l\u00edmites de su IA con el Pent\u00e1gono","author":"","date":"febrero 25, 2026","format":false,"excerpt":"Anthropic, una empresa fundada por exiliados de OpenAI preocupados por los peligros de la inteligencia artificial (IA), est\u00e1 relajando su principio b\u00e1sico de seguridad en respuesta a la competencia.En lugar de restricciones autoimpuestas que limiten el desarrollo de sus modelos de IA, Anthropic est\u00e1 adoptando un marco de seguridad no\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471716,"url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/27\/anthropic-rechaza-pentagono-trax\/","url_meta":{"origin":1471738,"position":5},"title":"Anthropic rechaza la \u00faltima oferta del Pent\u00e1gono: &#171;No podemos, con conciencia, acceder a su solicitud&#187;","author":"","date":"febrero 27, 2026","format":false,"excerpt":"Anthropic rechaz\u00f3 la \u00faltima oferta del Pent\u00e1gono para modificar su contrato, alegando que los cambios no cumplen con las preocupaciones de la compa\u00f1\u00eda sobre el uso de la IA para la vigilancia masiva o para armas totalmente aut\u00f3nomas.El Pent\u00e1gono y Anthropic discrepan sobre las restricciones que la compa\u00f1\u00eda impone al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1471738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1471738"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1471738\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1471738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1471738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1471738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}