{"id":1471740,"date":"2026-02-27T17:03:52","date_gmt":"2026-02-28T01:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/27\/medalla-honor-piloto-operacion-contra-maduro-trax\/"},"modified":"2026-02-27T17:03:52","modified_gmt":"2026-02-28T01:03:52","slug":"medalla-honor-piloto-operacion-contra-maduro-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2026\/02\/27\/medalla-honor-piloto-operacion-contra-maduro-trax\/","title":{"rendered":"La carrera contrarreloj para otorgar la Medalla de Honor al piloto que lider\u00f3 la operaci\u00f3n contra Maduro"},"content":{"rendered":"<p>Cuando el presidente Donald Trump visit\u00f3 Fort Bragg, Carolina del Norte, a principios de este mes, el comandante de la \u00e9lite Delta Force del Ej\u00e9rcito, responsable de ejecutar la operaci\u00f3n para capturar al presidente de Venezuela, Nicol\u00e1s Maduro, dijo que hab\u00eda un hombre en particular que merec\u00eda la m\u00e1xima condecoraci\u00f3n militar: el suboficial en Jefe 5 Eric Slover.<\/p>\n<p>Slover, piloto de operaciones especiales del Ej\u00e9rcito, guiaba su helic\u00f3ptero MH-47 hacia un aterrizaje en Caracas cuando la aeronave fue inmediatamente atacada por varias ametralladoras a corta distancia, seg\u00fan la menci\u00f3n que acompa\u00f1ar\u00eda eventualmente la condecoraci\u00f3n. La cabina recibi\u00f3 15 impactos de proyectiles perforantes, cuatro de los cuales alcanzaron a Slover en la pierna.<\/p>\n<p>A pesar de las heridas, Slover mantuvo el control del helic\u00f3ptero para garantizar la seguridad de los soldados de las Fuerzas Especiales a bordo mientras completaban la misi\u00f3n.<\/p>\n<p>El comandante le dijo a Trump que Slover deb\u00eda recibir la Medalla de Honor por sus acciones, seg\u00fan un funcionario familiarizado con el caso. Trump se convenci\u00f3 r\u00e1pidamente y se\u00f1al\u00f3 al equipo que har\u00eda precisamente eso, dijeron a CNN dos altos funcionarios de la Casa Blanca.<\/p>\n<p>Menos de dos semanas despu\u00e9s, Slover, quien hab\u00eda resultado gravemente herido durante la operaci\u00f3n, se mantuvo erguido durante el <a href=\"https:\/\/cnnespanol.cnn.com\/eeuu\/live-news\/discurso-trump-estado-union-en-vivo-aranceles-inmigracion-orix\">discurso del Estado de la Uni\u00f3n <\/a>mientras la reconocible cinta azul claro de la Medalla de Honor se colocaba alrededor de su cuello, con la medalla centrada sobre la corbata de su uniforme de gala.<\/p>\n<p>La velocidad con la que se aprob\u00f3 la Medalla de Honor es altamente inusual. La aprobaci\u00f3n normalmente puede tardar a\u00f1os debido al proceso burocr\u00e1tico intenso. Adem\u00e1s, a veces existe debate sobre si se debe otorgar la medalla o no. En este caso, \u201cel presidente tom\u00f3 la decisi\u00f3n y todo el equipo trabaj\u00f3 junto para ejecutarla\u201d, dijo un alto funcionario de la Casa Blanca.<\/p>\n<p>La condecoraci\u00f3n se aceler\u00f3 por indicaci\u00f3n de Trump, quien estaba ansioso por anunciarla durante el Estado de la Uni\u00f3n, un discurso cuidadosamente preparado para incluir historias inspiradoras que cautivaran a la audiencia, dijeron los funcionarios.<\/p>\n<p>Dos fuentes familiarizadas con la situaci\u00f3n se\u00f1alaron que todos los tr\u00e1mites y procesos oficiales se siguieron, pero en un plazo mucho m\u00e1s corto, gracias a la disposici\u00f3n de los l\u00edderes militares de apoyar la recomendaci\u00f3n en persona. Una de las fuentes reconoci\u00f3 que el proceso fue \u201cmuy r\u00e1pido\u201d, pero dijo que las aprobaciones verbales y los informes aceleraron las cosas mientras los documentos se pon\u00edan al d\u00eda. Un portavoz del Ej\u00e9rcito afirm\u00f3 que el servicio se siente \u201cincre\u00edblemente orgulloso\u201d de Slover y confirm\u00f3 que se cumplieron todos los requisitos legales para otorgar la medalla.<\/p>\n<p>Un funcionario de Trump encargado de agilizar el proceso trabaj\u00f3 intensamente tras la visita presidencial a Fort Bragg para apresurar la documentaci\u00f3n, dijeron los funcionarios. El momento frente a c\u00e1maras en el que Trump solicit\u00f3 la medalla para Slover fue incluido en el primer borrador de su discurso, a\u00f1adieron. Sin embargo, hasta el martes, d\u00eda del discurso, no estaba claro si la Casa Blanca podr\u00eda completar el proceso a tiempo.<\/p>\n<p>\u201cLa Casa Blanca y el Pent\u00e1gono trabajaron de manera expedita bajo la direcci\u00f3n del presidente para asegurar que este gran h\u00e9roe estadounidense recibiera la condecoraci\u00f3n que sin duda merece\u201d, dijo a CNN la secretaria de prensa de la Casa Blanca, Karoline Leavitt.<\/p>\n<p>Aun as\u00ed, Slover tuvo que aceptar participar en un evento tan p\u00fablico. El costo f\u00edsico de la operaci\u00f3n para capturar a Maduro fue significativo; Trump se\u00f1al\u00f3 durante el discurso que Slover fue alcanzado \u201cmuy gravemente en la pierna y la cadera\u201d por proyectiles perforantes que \u201cdestruyeron su pierna\u201d. Aunque Slover se mantuvo firme mientras era homenajeado, cuando Trump continu\u00f3 con su discurso, el teniente general Jonathan Braga, comandante del Mando Conjunto de Operaciones Especiales, se inclin\u00f3 para ayudarlo a sentarse en una silla de ruedas ubicada detr\u00e1s de \u00e9l.<\/p>\n<p>Una segunda fuente familiar con la situaci\u00f3n dijo que, pendiente de su recuperaci\u00f3n f\u00edsica, Slover desea continuar su carrera como piloto operativo, aunque no est\u00e1 claro si ser\u00e1 posible, tanto por razones f\u00edsicas como por la necesidad de mantener en secreto las operaciones especiales en las que suele participar. Esa consideraci\u00f3n seguramente influy\u00f3 en su decisi\u00f3n como soldado acostumbrado a trabajar en las sombras y en operaciones encubiertas, pero repentinamente expuesto a un foco nacional.<\/p>\n<p>Slover es \u201cincre\u00edblemente humilde y estoico\u201d, dijo la segunda fuente, y alguien que \u201cnunca habr\u00eda esperado recibir esta medalla por sus acciones\u201d. Agreg\u00f3 que el reconocimiento p\u00fablico no es algo que \u00e9l haya buscado ni, francamente, disfrute.<\/p>\n<p>\u201cPara \u00e9l, esto es para lo que se prepar\u00f3\u201d, dijo la fuente. \u201cEst\u00e1 honrado por recibirla, pero esto es simplemente lo que habr\u00eda hecho, con o sin medalla al final\u201d.<\/p>\n<p>Ha habido conversaciones sobre realizar otra ceremonia m\u00e1s privada con Trump y la familia y amigos de Slover, quienes tradicionalmente participan en eventos de entrega de la Medalla de Honor, seg\u00fan la segunda fuente. Trump tambi\u00e9n mencion\u00f3 que otros 10 soldados de la misi\u00f3n recibir\u00e1n condecoraciones, aunque no se sabe cu\u00e1les ni cu\u00e1ndo se realizar\u00eda la ceremonia.<\/p>\n<p>La Casa Blanca llevar\u00e1 a cabo otra ceremonia de la Medalla de Honor el lunes para honrar a miembros del servicio de varios conflictos, aunque los beneficiarios de esa ceremonia no incluir\u00e1n a los participantes de la reciente operaci\u00f3n en Venezuela.<\/p>\n<p>Si bien los detalles del servicio de Slover son escasos, probablemente por la naturaleza sensible de sus unidades y despliegues, sus condecoraciones reflejan una carrera desafiante.<\/p>\n<p>Slover se enlist\u00f3 en el Ej\u00e9rcito en 2005, asisti\u00f3 a la Escuela de Candidatos a Suboficiales y a la Escuela de Vuelo, convirti\u00e9ndose en piloto de Chinook. Los suboficiales del Ej\u00e9rcito son considerados expertos m\u00e1ximos en su \u00e1rea, y solo entre 3 y 4\u202f% alcanza el rango de CW5, como Slover,<a href=\"https:\/\/www.army.mil\/article\/263117\/afc_warrant_officer_achieves_cw5_rank\"> indic\u00f3 el Ej\u00e9rcito en 2023<\/a>.<\/p>\n<p>Una lista de sus premios proporcionada por el Comando de Operaciones Especiales del Ej\u00e9rcito muestra que ha recibido dos Cruces de Vuelo Distinguida, una con distintivo de valor y otra sin \u00e9l, medallas altamente prestigiosas por hero\u00edsmo en combate a\u00e9reo. La \u201cV\u201d indica actos de hero\u00edsmo \u201cm\u00e1s all\u00e1 de lo esperado\u201d durante enfrentamientos con enemigos de EE.\u202fUU.<\/p>\n<p>Slover tambi\u00e9n ha recibido la Estrella de Bronce con un racimo de roble, la Purple Heart, la Medalla de Servicio Meritorio con un racimo de roble, entre otras.<\/p>\n<p>El 3 de enero, pilotaba un MH-47 \u2014variante de Operaciones Especiales del helic\u00f3ptero CH-47 Chinook\u2014 durante la operaci\u00f3n en Venezuela, denominada Operaci\u00f3n Resoluci\u00f3n Absoluta. Seg\u00fan la citaci\u00f3n de su Medalla de Honor, Slover \u201ccondujo h\u00e1bilmente el helic\u00f3ptero por un valle selv\u00e1tico en una regi\u00f3n monta\u00f1osa\u201d enfrentando \u201camenazas de superficie a aire casi insuperables\u201d.<\/p>\n<p>Trump, al contar la historia del hero\u00edsmo de Slover en el discurso sobre el Estado de la Uni\u00f3n, dijo que, tras aterrizar el helic\u00f3ptero con seguridad, Slover le indic\u00f3 a su copiloto, tambi\u00e9n herido, que tomara el control, diciendo: \u201cEstoy a punto de desmayarme\u201d.<\/p>\n<p>\u201cLas heroicas acciones del Suboficial en Jefe 5 Slover sin duda salvaron incontables vidas estadounidenses y garantizaron el \u00e9xito total y abrumador de la misi\u00f3n\u201d, dice la menci\u00f3n. \u201cSu valent\u00eda bajo el fuego enemigo y hero\u00edsmo extraordinario est\u00e1n en l\u00ednea con las m\u00e1s altas tradiciones del servicio militar y reflejan gran honor para \u00e9l mismo y para el Ej\u00e9rcito de Estados Unidos\u201d.<\/p>\n<p>El proceso de recomendaci\u00f3n para la Medalla de Honor, seg\u00fan los diagramas de flujo de <a href=\"https:\/\/www.army.mil\/medalofhonor\/steps.html\">un sitio web del Ej\u00e9rcito<\/a> que describen los detalles, implica la revisi\u00f3n de la acci\u00f3n valerosa por parte de la cadena de mando del miembro del servicio, una junta de condecoraciones que determina si la Medalla de Honor est\u00e1 justificada o no, la consulta con el jefe del servicio y el secretario del servicio y, finalmente, el env\u00edo del paquete al secretario de Defensa, quien puede recomendar el premio al presidente. El presidente tiene que dar la aprobaci\u00f3n final para otorgar la Medalla de Honor.<\/p>\n<p>Aunque el proceso se aceler\u00f3 al llevar la recomendaci\u00f3n de los l\u00edderes directamente al presidente, en persona, Slover a\u00fan ten\u00eda que aceptar participar en un acto tan p\u00fablico. La segunda fuente familiarizada con la situaci\u00f3n dijo que acept\u00f3 despu\u00e9s de hablar con otros l\u00edderes al respecto, aproximadamente una semana antes del discurso sobre el Estado de la Uni\u00f3n.<\/p>\n<p>Todos los elementos se alinearon y, el martes por la noche, en el Capitolio, Slover se puso de pie con la ayuda de un andador y mir\u00f3 al frente mientras Braga, comandante del Comando Conjunto de Operaciones Especiales, le colocaba alrededor del cuello la medalla m\u00e1s alta del pa\u00eds por su valor militar.<\/p>\n<p>Mientras el p\u00fablico aplaud\u00eda y coreaba \u201c\u00a1USA!\u201d, Slover asinti\u00f3 y agradeci\u00f3, mostrando poca emoci\u00f3n m\u00e1s all\u00e1 de un breve momento con su esposa, a quien mir\u00f3 y apret\u00f3 la mano.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando el presidente Donald Trump visit\u00f3 Fort Bragg, Carolina del Norte, a principios de este mes, el comandante de la \u00e9lite Delta Force del Ej\u00e9rcito, responsable de ejecutar la operaci\u00f3n para capturar al presidente de Venezuela, Nicol\u00e1s Maduro, dijo que hab\u00eda un hombre en particular que merec\u00eda la m\u00e1xima condecoraci\u00f3n militar: el suboficial en Jefe [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1471740","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La carrera contrarreloj para otorgar la Medalla de Honor al piloto que lider\u00f3 la operaci\u00f3n contra Maduro - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/27\/medalla-honor-piloto-operacion-contra-maduro-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La carrera contrarreloj para otorgar la Medalla de Honor al piloto que lider\u00f3 la operaci\u00f3n contra Maduro - Noticias\" \/>\n<meta property=\"og:description\" content=\"Cuando el presidente Donald Trump visit\u00f3 Fort Bragg, Carolina del Norte, a principios de este mes, el comandante de la \u00e9lite Delta Force del Ej\u00e9rcito, responsable de ejecutar la operaci\u00f3n para capturar al presidente de Venezuela, Nicol\u00e1s Maduro, dijo que hab\u00eda un hombre en particular que merec\u00eda la m\u00e1xima condecoraci\u00f3n militar: el suboficial en Jefe [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/27\/medalla-honor-piloto-operacion-contra-maduro-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-28T01:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/27\/medalla-honor-piloto-operacion-contra-maduro-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/27\/medalla-honor-piloto-operacion-contra-maduro-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La carrera contrarreloj para otorgar la Medalla de Honor al piloto que lider\u00f3 la operaci\u00f3n contra Maduro\",\"datePublished\":\"2026-02-28T01:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/27\/medalla-honor-piloto-operacion-contra-maduro-trax\/\"},\"wordCount\":1601,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/27\/medalla-honor-piloto-operacion-contra-maduro-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/27\/medalla-honor-piloto-operacion-contra-maduro-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/27\/medalla-honor-piloto-operacion-contra-maduro-trax\/\",\"name\":\"La carrera contrarreloj para otorgar la Medalla de Honor al piloto que lider\u00f3 la operaci\u00f3n contra Maduro - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-28T01:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/27\/medalla-honor-piloto-operacion-contra-maduro-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/27\/medalla-honor-piloto-operacion-contra-maduro-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/27\/medalla-honor-piloto-operacion-contra-maduro-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La carrera contrarreloj para otorgar la Medalla de Honor al piloto que lider\u00f3 la operaci\u00f3n contra Maduro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La carrera contrarreloj para otorgar la Medalla de Honor al piloto que lider\u00f3 la operaci\u00f3n contra Maduro - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/27\/medalla-honor-piloto-operacion-contra-maduro-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La carrera contrarreloj para otorgar la Medalla de Honor al piloto que lider\u00f3 la operaci\u00f3n contra Maduro - Noticias","og_description":"Cuando el presidente Donald Trump visit\u00f3 Fort Bragg, Carolina del Norte, a principios de este mes, el comandante de la \u00e9lite Delta Force del Ej\u00e9rcito, responsable de ejecutar la operaci\u00f3n para capturar al presidente de Venezuela, Nicol\u00e1s Maduro, dijo que hab\u00eda un hombre en particular que merec\u00eda la m\u00e1xima condecoraci\u00f3n militar: el suboficial en Jefe [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/27\/medalla-honor-piloto-operacion-contra-maduro-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-28T01:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/27\/medalla-honor-piloto-operacion-contra-maduro-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/27\/medalla-honor-piloto-operacion-contra-maduro-trax\/"},"author":{"name":"","@id":""},"headline":"La carrera contrarreloj para otorgar la Medalla de Honor al piloto que lider\u00f3 la operaci\u00f3n contra Maduro","datePublished":"2026-02-28T01:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/27\/medalla-honor-piloto-operacion-contra-maduro-trax\/"},"wordCount":1601,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/27\/medalla-honor-piloto-operacion-contra-maduro-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/27\/medalla-honor-piloto-operacion-contra-maduro-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/27\/medalla-honor-piloto-operacion-contra-maduro-trax\/","name":"La carrera contrarreloj para otorgar la Medalla de Honor al piloto que lider\u00f3 la operaci\u00f3n contra Maduro - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-28T01:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/27\/medalla-honor-piloto-operacion-contra-maduro-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/27\/medalla-honor-piloto-operacion-contra-maduro-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/27\/medalla-honor-piloto-operacion-contra-maduro-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La carrera contrarreloj para otorgar la Medalla de Honor al piloto que lider\u00f3 la operaci\u00f3n contra Maduro"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/27\/medalla-honor-piloto-operacion-contra-maduro-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La carrera contrarreloj para otorgar la Medalla de Honor al piloto que lider\u00f3 la operaci\u00f3n contra Maduro","url":"http:\/\/noticiasya.com\/colorado\/2026\/02\/27\/medalla-honor-piloto-operacion-contra-maduro-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2026\/02\/27\/medalla-honor-piloto-operacion-contra-maduro-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-28T01:03:52Z","datePublished":"2026-02-28T01:03:52Z","dateModified":"2026-02-28T01:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La carrera contrarreloj para otorgar la Medalla de Honor al piloto que lider\\u00f3 la operaci\\u00f3n contra Maduro\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/02\\\/27\\\/medalla-honor-piloto-operacion-contra-maduro-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/02\\\/27\\\/medalla-honor-piloto-operacion-contra-maduro-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-28T01:03:52Z\",\"datePublished\":\"2026-02-28T01:03:52Z\",\"dateModified\":\"2026-02-28T01:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1471080,"url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/10\/trump-reunion-ejercito-captura-maduro-trax\/","url_meta":{"origin":1471740,"position":0},"title":"Trump se reunir\u00e1 el viernes con miembros las fuerzas armadas de EE.UU. que participaron en la captura de Maduro","author":"","date":"febrero 10, 2026","format":false,"excerpt":"El presidente de EE.UU., Donald Trump, se reunir\u00e1 el viernes con miembros de las fuerzas armadas estadounidenses que participaron en la \u201cOperation Absolute Resolve\u201d (Operaci\u00f3n Resoluci\u00f3n Absoluta, en espa\u00f1ol) del mes pasado para capturar al presidente de Venezuela, Nicol\u00e1s Maduro, en Caracas, anunci\u00f3 este martes la Casa Blanca.La secretaria de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470467,"url":"https:\/\/noticiasya.com\/colorado\/2026\/01\/25\/trump-discombobulator-arma-secreta-captura-maduro-trax\/","url_meta":{"origin":1471740,"position":1},"title":"Trump afirma que se us\u00f3 un arma secreta para ayudar a capturar a Maduro","author":"","date":"enero 25, 2026","format":false,"excerpt":"El presidente Donald Trump afirm\u00f3 que Estados Unidos utiliz\u00f3 un arma a la que se refiri\u00f3 como un \u201cdiscombobulator\u201d para capturar este mes al entonces presidente de Venezuela, Nicol\u00e1s Maduro, pero un alto funcionario estadounidense dijo que probablemente est\u00e1 confundiendo distintas herramientas usadas por el Ej\u00e9rcito de EE.UU.\u201cEl \u2018discombobulator\u2019, no\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469828,"url":"https:\/\/noticiasya.com\/colorado\/2026\/01\/06\/tras-captura-maduro-democratas-foco-costo-vida-trax\/","url_meta":{"origin":1471740,"position":2},"title":"Incluso tras la captura de Maduro, los dem\u00f3cratas intentan mantener el foco en el costo de vida","author":"","date":"enero 6, 2026","format":false,"excerpt":"Los dem\u00f3cratas lidian con c\u00f3mo responder mejor a la intervenci\u00f3n militar del Gobierno de Trump en Venezuela, mientras la operaci\u00f3n para capturar a Nicol\u00e1s Maduro puso de relieve diferencias de pol\u00edtica exterior dentro del partido y desvi\u00f3 la atenci\u00f3n de su \u00e9nfasis en el costo de vida.La captura de Maduro\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470051,"url":"https:\/\/noticiasya.com\/colorado\/2026\/01\/13\/memorando-legal-clasificado-trump-maduro-trax\/","url_meta":{"origin":1471740,"position":3},"title":"Memorando legal clasificado sostiene que Trump no estaba limitado por leyes de EE.UU. o internacionales en captura de Maduro","author":"","date":"enero 13, 2026","format":false,"excerpt":"Un nuevo dictamen legal clasificado elaborado por el Departamento de Justicia sostiene que el presidente de EE.UU. Donald Trump no estaba limitado por la legislaci\u00f3n interna cuando aprob\u00f3 la operaci\u00f3n de Estados Unidos para capturar al entonces presidente de Venezuela, Nicol\u00e1s Maduro, debido a su autoridad constitucional como comandante en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452693,"url":"https:\/\/noticiasya.com\/colorado\/2024\/09\/14\/venezuela-dice-que-un-infante-de-marina-de-ee-uu-esta-entre-los-extranjeros-detenidos-por-una-supuesta-operacion-de-la-cia-para-matar-a-maduro\/","url_meta":{"origin":1471740,"position":4},"title":"Venezuela afirma que un infante de Marina de EE.UU. est\u00e1 entre los extranjeros detenidos por una supuesta &#171;operaci\u00f3n&#187; de la CIA para matar a Maduro","author":"","date":"septiembre 14, 2024","format":false,"excerpt":"(CNN) -- Venezuela inform\u00f3 que detuvo a seis extranjeros, incluido un infante de Marina de Estados Unidos, por un supuesto complot para \u201cdesestabilizar\u201d el pa\u00eds que ha estado en crisis desde las elecciones disputadas a principios de este a\u00f1o.El ministro del Interior de Venezuela, Diosdado Cabello, afirm\u00f3 que el supuesto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469764,"url":"https:\/\/noticiasya.com\/colorado\/2026\/01\/03\/asi-captura-nicolas-maduro-venezuela-trax\/","url_meta":{"origin":1471740,"position":5},"title":"De la orden a la extracci\u00f3n: as\u00ed fue la captura de Nicol\u00e1s Maduro por parte de EE.UU.","author":"","date":"enero 3, 2026","format":false,"excerpt":"Fue como ver la televisi\u00f3n.Reunido en una sala apartada con cortinas en Mar-a-Lago alrededor de pantallas dispuestas para su placer visual \u2014incluyendo, seg\u00fan fotos publicadas por la Casa Blanca, una transmisi\u00f3n en vivo de mensajes en redes sociales en X\u2014 el presidente Donald Trump observ\u00f3 y escuch\u00f3 mientras soldados estadounidenses\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1471740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1471740"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1471740\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1471740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1471740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1471740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}