{"id":1472619,"date":"2026-03-27T12:03:58","date_gmt":"2026-03-27T19:03:58","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/27\/lobos-eutanasia-reino-unido-trax\/"},"modified":"2026-03-27T12:03:58","modified_gmt":"2026-03-27T19:03:58","slug":"lobos-eutanasia-reino-unido-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2026\/03\/27\/lobos-eutanasia-reino-unido-trax\/","title":{"rendered":"Un parque de vida silvestre del Reino Unido sacrifica a toda una manada de lobos despu\u00e9s de que se atacaran entre s\u00ed"},"content":{"rendered":"<p>Un parque de vida silvestre en el sureste de Inglaterra ha sacrificado a toda una manada de lobos despu\u00e9s de que la din\u00e1mica del grupo se rompiera, lo que provoc\u00f3 una escalada de conflictos.<\/p>\n<p>La manada de cinco lobos fue sacrificada despu\u00e9s de que tres de ellos sufrieran heridas potencialmente mortales en medio de una violencia creciente, seg\u00fan inform\u00f3 Wildwood Trust en un comunicado compartido con CNN este viernes.<\/p>\n<p>Despu\u00e9s de que otras intervenciones no lograran detener las peleas, y tras mantener conversaciones entre cuidadores de animales experimentados y especialistas veterinarios, el parque \u2014situado a las afueras de la ciudad de Canterbury\u2014 decidi\u00f3 sacrificar a los lobos \u2014llamados Odin, Nuna, Minimus, Tiberius y Maximus\u2014 para evitarles m\u00e1s sufrimiento.<\/p>\n<p>\u201cNuestros cuidadores sienten un enorme afecto por estos animales e hicieron todo lo posible por encontrar una soluci\u00f3n\u201d, declar\u00f3 en el comunicado Paul Whitfield, director general de Wildwood Trust.<\/p>\n<p>\u201cLos lobos son animales altamente sociales que viven dentro de complejas estructuras familiares; cuando esas din\u00e1micas se rompen, el conflicto y el rechazo pueden intensificarse. En este caso, la situaci\u00f3n deriv\u00f3 en preocupaciones constantes sobre su bienestar y en un riesgo inaceptable de sufrir lesiones graves\u201d, continu\u00f3.<\/p>\n<p>\u201cLa eutanasia nunca se decide a la ligera; sin embargo, en el \u00e1mbito del cuidado responsable de los animales, a veces puede ser la opci\u00f3n m\u00e1s humana cuando ya no es posible garantizar su bienestar\u201d, a\u00f1adi\u00f3 Whitfield.<\/p>\n<p>\u201cEsta decisi\u00f3n fue un recurso absolutamente de \u00faltima instancia, priorizando siempre el bienestar de los animales\u201d, afirm\u00f3. \u201cHa sido incre\u00edblemente dif\u00edcil, pero, en \u00faltima instancia, era lo correcto para evitarles m\u00e1s sufrimiento\u201d.<\/p>\n<p>Dado que los lobos mantienen v\u00ednculos muy estrechos con su manada, mantenerlos aislados o separados a largo plazo habr\u00eda generado nuevas preocupaciones en cuanto a su bienestar, seg\u00fan explic\u00f3 el parque.<\/p>\n<p>Integrar a los lobos en otras manadas tampoco era una opci\u00f3n viable, ya que esto podr\u00eda haber provocado m\u00e1s conflictos y lesiones, o incluso la desintegraci\u00f3n de otra manada, se\u00f1alaron.<\/p>\n<p>En una publicaci\u00f3n de <a href=\"https:\/\/www.instagram.com\/p\/DWT17VIEQoJ\/?utm_source=ig_web_copy_link&#038;igsh=MzRlODBiNWFlZA%3D%3D\">Instagram <\/a>realizada el jueves, el equipo de la organizaci\u00f3n inform\u00f3 que cerraron la reserva mientras se proced\u00eda al sacrificio de los animales y que todo el personal se encontraba \u201ccon el coraz\u00f3n roto\u201d, a\u00f1adiendo: \u201cMuchos de nuestros empleados han cuidado de estos lobos durante un largo periodo de tiempo, por lo que esta p\u00e9rdida se sentir\u00e1 profundamente\u201d.<\/p>\n<p>\u201cReconocemos que esta noticia resulta profundamente dolorosa y comprendemos por qu\u00e9 tantas personas se sienten angustiadas\u201d, declar\u00f3 la organizaci\u00f3n a CNN en un comunicado adicional. \u201cEsta decisi\u00f3n se tom\u00f3 con gran cuidado y solo tras una exhaustiva consulta con destacados especialistas en lobos de toda Europa, experimentados profesionales veterinarios y una revisi\u00f3n \u00e9tica independiente\u201d, a\u00f1adi\u00f3.<\/p>\n<p>La eutanasia se lleva a cabo en grupos de animales por diversas razones.<\/p>\n<p>El a\u00f1o pasado, funcionarios de vida silvestre de Australia practicaron la eutanasia a 90 ballenas que hab\u00edan quedado varadas en una remota playa de Tasmania, despu\u00e9s de que el fuerte oleaje hiciera imposible devolverlas al mar.<\/p>\n<p>En julio, un zool\u00f3gico alem\u00e1n sacrific\u00f3 a 12 babuinos \u2014a pesar de las protestas\u2014, dado que no dispon\u00eda de espacio suficiente para albergarlos y no pudo encontrarles un alojamiento alternativo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un parque de vida silvestre en el sureste de Inglaterra ha sacrificado a toda una manada de lobos despu\u00e9s de que la din\u00e1mica del grupo se rompiera, lo que provoc\u00f3 una escalada de conflictos. La manada de cinco lobos fue sacrificada despu\u00e9s de que tres de ellos sufrieran heridas potencialmente mortales en medio de una [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472619","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un parque de vida silvestre del Reino Unido sacrifica a toda una manada de lobos despu\u00e9s de que se atacaran entre s\u00ed - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/27\/lobos-eutanasia-reino-unido-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un parque de vida silvestre del Reino Unido sacrifica a toda una manada de lobos despu\u00e9s de que se atacaran entre s\u00ed - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un parque de vida silvestre en el sureste de Inglaterra ha sacrificado a toda una manada de lobos despu\u00e9s de que la din\u00e1mica del grupo se rompiera, lo que provoc\u00f3 una escalada de conflictos. La manada de cinco lobos fue sacrificada despu\u00e9s de que tres de ellos sufrieran heridas potencialmente mortales en medio de una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/27\/lobos-eutanasia-reino-unido-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-27T19:03:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/27\/lobos-eutanasia-reino-unido-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/27\/lobos-eutanasia-reino-unido-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un parque de vida silvestre del Reino Unido sacrifica a toda una manada de lobos despu\u00e9s de que se atacaran entre s\u00ed\",\"datePublished\":\"2026-03-27T19:03:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/27\/lobos-eutanasia-reino-unido-trax\/\"},\"wordCount\":596,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/27\/lobos-eutanasia-reino-unido-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/27\/lobos-eutanasia-reino-unido-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/27\/lobos-eutanasia-reino-unido-trax\/\",\"name\":\"Un parque de vida silvestre del Reino Unido sacrifica a toda una manada de lobos despu\u00e9s de que se atacaran entre s\u00ed - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-27T19:03:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/27\/lobos-eutanasia-reino-unido-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/27\/lobos-eutanasia-reino-unido-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/27\/lobos-eutanasia-reino-unido-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un parque de vida silvestre del Reino Unido sacrifica a toda una manada de lobos despu\u00e9s de que se atacaran entre s\u00ed\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un parque de vida silvestre del Reino Unido sacrifica a toda una manada de lobos despu\u00e9s de que se atacaran entre s\u00ed - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/27\/lobos-eutanasia-reino-unido-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Un parque de vida silvestre del Reino Unido sacrifica a toda una manada de lobos despu\u00e9s de que se atacaran entre s\u00ed - Noticias","og_description":"Un parque de vida silvestre en el sureste de Inglaterra ha sacrificado a toda una manada de lobos despu\u00e9s de que la din\u00e1mica del grupo se rompiera, lo que provoc\u00f3 una escalada de conflictos. La manada de cinco lobos fue sacrificada despu\u00e9s de que tres de ellos sufrieran heridas potencialmente mortales en medio de una [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/27\/lobos-eutanasia-reino-unido-trax\/","og_site_name":"Noticias","article_published_time":"2026-03-27T19:03:58+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/27\/lobos-eutanasia-reino-unido-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/27\/lobos-eutanasia-reino-unido-trax\/"},"author":{"name":"","@id":""},"headline":"Un parque de vida silvestre del Reino Unido sacrifica a toda una manada de lobos despu\u00e9s de que se atacaran entre s\u00ed","datePublished":"2026-03-27T19:03:58+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/27\/lobos-eutanasia-reino-unido-trax\/"},"wordCount":596,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/27\/lobos-eutanasia-reino-unido-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/27\/lobos-eutanasia-reino-unido-trax\/","url":"https:\/\/noticiasya.com\/2026\/03\/27\/lobos-eutanasia-reino-unido-trax\/","name":"Un parque de vida silvestre del Reino Unido sacrifica a toda una manada de lobos despu\u00e9s de que se atacaran entre s\u00ed - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-27T19:03:58+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/27\/lobos-eutanasia-reino-unido-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/27\/lobos-eutanasia-reino-unido-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/27\/lobos-eutanasia-reino-unido-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un parque de vida silvestre del Reino Unido sacrifica a toda una manada de lobos despu\u00e9s de que se atacaran entre s\u00ed"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2026\/03\/27\/lobos-eutanasia-reino-unido-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un parque de vida silvestre del Reino Unido sacrifica a toda una manada de lobos despu\u00e9s de que se atacaran entre s\u00ed","url":"http:\/\/noticiasya.com\/colorado\/2026\/03\/27\/lobos-eutanasia-reino-unido-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2026\/03\/27\/lobos-eutanasia-reino-unido-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-27T19:03:58Z","datePublished":"2026-03-27T19:03:58Z","dateModified":"2026-03-27T19:03:58Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un parque de vida silvestre del Reino Unido sacrifica a toda una manada de lobos despu\\u00e9s de que se atacaran entre s\\u00ed\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/03\\\/27\\\/lobos-eutanasia-reino-unido-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/03\\\/27\\\/lobos-eutanasia-reino-unido-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-27T19:03:58Z\",\"datePublished\":\"2026-03-27T19:03:58Z\",\"dateModified\":\"2026-03-27T19:03:58Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1445258,"url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/11\/se-ofrece-recompensa-de-us-50-000-por-informacion-sobre-la-muerte-de-tres-lobos-grises-en-peligro-de-extincion-en-oregon\/","url_meta":{"origin":1472619,"position":0},"title":"Se ofrece recompensa de US$ 50.000 por informaci\u00f3n sobre la muerte de tres lobos grises en peligro de extinci\u00f3n en Oreg\u00f3n","author":"","date":"febrero 11, 2024","format":false,"excerpt":"(CNN) --Un tr\u00edo de lobos grises en peligro de extinci\u00f3n fueron encontrados muertos en el sur de Oreg\u00f3n y los funcionarios federales ofrecen una recompensa de 50.000 d\u00f3lares por informaci\u00f3n sobre sus muertes.Los cuerpos fueron encontrados despu\u00e9s de que los collares de dos de los lobos emitieran una \u201cse\u00f1al de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463562,"url":"https:\/\/noticiasya.com\/colorado\/2025\/06\/14\/cachorras-momificadas-no-eran-perras-trax\/","url_meta":{"origin":1472619,"position":1},"title":"Nueva investigaci\u00f3n muestra que dos &#171;cachorras&#187; momificadas de 14.000 a\u00f1os de antig\u00fcedad no eran mascotas dom\u00e9sticas","author":"","date":"junio 14, 2025","format":false,"excerpt":"Dos \u201ccachorras\u201d de la Edad de Hielo bien conservados encontrados en el norte de Siberia podr\u00edan no ser perros en absoluto, seg\u00fan una nueva investigaci\u00f3n.Todav\u00eda cubiertos de pelo y preservados naturalmente en hielo durante miles de a\u00f1os, los \u201cCachorros Tumat\u201d, como se los conoce, contienen indicios de una \u00faltima comida\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458985,"url":"https:\/\/noticiasya.com\/colorado\/2025\/02\/20\/mueren-6-elefantes-tren-chocara-manada-sri-lanka-orix\/","url_meta":{"origin":1472619,"position":2},"title":"Mueren al menos 6 elefantes luego de que un tren chocara con una manada en Sri Lanka, dice la Polic\u00eda","author":"","date":"febrero 20, 2025","format":false,"excerpt":"Un tren choc\u00f3 con una manada de elefantes en Sri Lanka el mi\u00e9rcoles por la noche, matando al menos a seis de ellos, seg\u00fan la Polic\u00eda de Sri Lanka.Ning\u00fan pasajero result\u00f3 herido, pero los veterinarios de animales salvajes est\u00e1n tratando a una hembra de elefante y a una cr\u00eda herida\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451020,"url":"https:\/\/noticiasya.com\/colorado\/2024\/07\/10\/turista-espanola-muere-atropellada-elefantes-foto-sudafrica-trax\/","url_meta":{"origin":1472619,"position":3},"title":"Turista espa\u00f1ol muere atropellado por elefantes mientras tomaba una foto en Sud\u00e1frica","author":"","date":"julio 10, 2024","format":false,"excerpt":"(CNN) -- Un turista espa\u00f1ol fue aplastado hasta la muerte por una manada de elefantes dentro del Parque Nacional Pilanesberg, en Sud\u00e1frica, despu\u00e9s de que saliera de su veh\u00edculo para tomar una fotograf\u00eda de cerca de los animales, dijo la polic\u00eda local.El europeo, cuyo nombre no se dio a conocer\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457221,"url":"https:\/\/noticiasya.com\/colorado\/2025\/01\/04\/suecia-reduccion-poblacion-lobos-trax\/","url_meta":{"origin":1472619,"position":4},"title":"Suecia permite que casi el 10% de la poblaci\u00f3n de lobos sea eliminada, pero el Gobierno quiere una reducci\u00f3n a\u00fan m\u00e1s dr\u00e1stica","author":"","date":"enero 4, 2025","format":false,"excerpt":"Suecia comenz\u00f3 su caza anual de lobos esta semana, permitiendo que casi el 10% de la poblaci\u00f3n de esta especie en peligro sea eliminada, mientras los conservacionistas expresan preocupaciones sobre la controvertida pol\u00edtica.Desde 2010, Suecia ha permitido la caza de lobos bajo un sistema de cuotas con licencia. Los conservacionistas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460176,"url":"https:\/\/noticiasya.com\/colorado\/2025\/03\/20\/shakira-reencuentro-loba-concierto-mexico-orix\/","url_meta":{"origin":1472619,"position":5},"title":"Shakira: &#171;No hay mejor reencuentro de una loba con su manada mexicana&#187;","author":"","date":"marzo 20, 2025","format":false,"excerpt":"Shakira abri\u00f3 el primero de los siete conciertos que ofrece en la capital mexicana ante m\u00e1s de 60.000 personas reunidas en el Estadio GNP en la Ciudad de Mexico la noche de este mi\u00e9rcoles.Con las canciones \u201cLa Fuerte\u201d, \u201cGirl like Me\u201d y \u201cLatinas\u201d, la cantante colombiana subi\u00f3 al escenario a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1472619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1472619"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1472619\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1472619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1472619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1472619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}