{"id":1472629,"date":"2026-03-27T19:03:51","date_gmt":"2026-03-28T02:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/27\/tripulacion-artemis-ii-nasa-espacio-luna-trax\/"},"modified":"2026-03-27T19:03:51","modified_gmt":"2026-03-28T02:03:51","slug":"tripulacion-artemis-ii-nasa-espacio-luna-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2026\/03\/27\/tripulacion-artemis-ii-nasa-espacio-luna-trax\/","title":{"rendered":"Conoce a la tripulaci\u00f3n de Artemis II de la NASA, que marcar\u00e1 el inicio de una nueva era de exploraci\u00f3n del espacio profundo"},"content":{"rendered":"<p>La primera mujer. La primera persona negra. El primer canadiense.<\/p>\n<p>Las cuatro personas que pronto embarcar\u00e1n en una nave espacial para la primera misi\u00f3n tripulada a la Luna en m\u00e1s de medio siglo representan un conjunto de hitos hist\u00f3ricos. Se espera que la tripulaci\u00f3n de la misi\u00f3n Artemis II, liderada por la NASA, ampl\u00ede la lista de exploradores del espacio profundo m\u00e1s all\u00e1 del estrecho perfil de los astronautas de la era Apolo, un grupo compuesto exclusivamente por hombres estadounidenses blancos, casi todos con antecedentes militares.<\/p>\n<p>Sin embargo, aunque los astronautas inaugurar\u00e1n una era de diversidad para la exploraci\u00f3n del espacio profundo, sus credenciales se parecen a las de sus hom\u00f3logos del Apolo.<\/p>\n<p>La tripulaci\u00f3n incluye a Reid Wiseman, de la NASA, un piloto de pruebas de la Marina de Estados Unidos y padre soltero que se desempe\u00f1ar\u00e1 como comandante de la misi\u00f3n; Victor Glover, un piloto de pruebas naval que se convertir\u00e1 en la primera persona negra en viajar al espacio profundo; Christina Koch, una ingeniera y astronauta poseedora de r\u00e9cords que se convertir\u00e1 en la primera mujer en viajar a la Luna; y Jeremy Hansen, de la Agencia Espacial Canadiense (CSA, por sus siglas en ingl\u00e9s), un piloto de combate que ser\u00e1 el primer astronauta no perteneciente a la NASA en integrarse a una misi\u00f3n lunar.<\/p>\n<p>El viaje de alto riesgo a las cercan\u00edas de la Luna los llevar\u00e1 m\u00e1s all\u00e1 de su cara oculta \u2014m\u00e1s adentro del espacio que cualquier ser humano haya llegado antes\u2014 y plantear\u00e1 innumerables riesgos para los astronautas.<\/p>\n<p>El viaje de 10 d\u00edas, <a href=\"https:\/\/www.nasa.gov\/news-release\/nasa-invites-media-to-learn-about-artemis-moon-mission-recovery\/\">de aproximadamente 965.600 kil\u00f3metros<\/a>, cuyo lanzamiento est\u00e1 previsto tan pronto como en abril, expondr\u00e1 a la tripulaci\u00f3n a niveles peligrosos de radiaci\u00f3n. En varios puntos cruciales del trayecto, la tripulaci\u00f3n espera perder el contacto con el control de la misi\u00f3n debido a la enorme distancia y a la f\u00edsica implicada en el vuelo. Los apagones de comunicaciones inesperados tambi\u00e9n son una posibilidad real.<\/p>\n<p>Y los astronautas ser\u00e1n los primeros seres humanos en volar a bordo de la nave espacial Orion y del cohete Space Launch System, piezas de hardware que la NASA ha pasado dos d\u00e9cadas y m\u00e1s de <a href=\"https:\/\/www.planetary.org\/space-policy\/cost-of-sls-and-orion\">US$ 40.000 millones<\/a> desarrollando y que a\u00fan presentan problemas conocidos.<\/p>\n<p>En entrevistas, los miembros de la tripulaci\u00f3n de Artemis II han expresado sus esperanzas y optimismo, al tiempo que han hecho menciones sorprendentemente francas a las realidades del riesgo.<\/p>\n<p>\u201cEs posible que no podamos comunicarnos con la Tierra y que estemos teniendo problemas con la nave espacial\u201d, dijo Hansen a la<a href=\"https:\/\/www.youtube.com\/watch?v=K6p5rhKm8ps\"> Canadian Broadcasting Corp.<\/a> sobre su entrenamiento para la misi\u00f3n.<\/p>\n<p>\u201c\u00bfCu\u00e1les son los aspectos m\u00e1s b\u00e1sicos para darnos una oportunidad de seguir respirando y de caer en alg\u00fan lugar del planeta e idealmente en el oc\u00e9ano Pac\u00edfico? Obviamente, he tenido esa conversaci\u00f3n con mi esposa y mis hijos\u201d.<\/p>\n<p>Aun as\u00ed, los cuatro tambi\u00e9n han hablado abiertamente sobre lo que esta misi\u00f3n significar\u00e1 para ellos y para la NASA y sus socios internacionales, la CSA y la Agencia Espacial Europea, que compiten por devolver a los seres humanos a la superficie lunar en medio de una nueva carrera espacial con China.<\/p>\n<p>Desde hace mucho tiempo, la NASA ha presentado el programa de exploraci\u00f3n lunar Artemis como un trampol\u00edn para explorar m\u00e1s profundamente el cosmos.<\/p>\n<p>Artemis II es un vuelo de prueba que circunnavegar\u00e1 la Luna y no aterrizar\u00e1 en su superficie, pero servir\u00e1 como misi\u00f3n precursora de Artemis III, que se espera que toque suelo cerca del polo sur de la Luna, en gran medida inexplorado.<\/p>\n<p>El objetivo general del programa Artemis es determinar c\u00f3mo los seres humanos pueden vivir y trabajar de forma permanente en la superficie lunar. Y esa haza\u00f1a, seg\u00fan la agencia espacial, ayudar\u00e1 a la NASA a descubrir c\u00f3mo las personas pueden sobrevivir a viajes de meses a Marte.<\/p>\n<p>\u201cNecesitamos celebrar este momento en la historia humana\u201d, dijo Glover tras su selecci\u00f3n para la misi\u00f3n Artemis II en 2023. \u201cEs el siguiente paso en el viaje que llevar\u00e1 a la humanidad a Marte\u201d.<\/p>\n<p><strong>Ciudad natal: <\/strong>Baltimore.<\/p>\n<p><strong>Experiencia previa en vuelos espaciales:<\/strong> viaj\u00f3 a bordo de una c\u00e1psula rusa Soyuz para pasar 165 d\u00edas en la Estaci\u00f3n Espacial Internacional en 2014.<\/p>\n<p><strong>Rol en Artemis II:<\/strong> comandante.<\/p>\n<p><strong>Lleva consigo: <\/strong>una tarjeta en blanco para anotar sus pensamientos.<\/p>\n<p><a href=\"https:\/\/www.nasa.gov\/astronauts\/biographies\/g-reid-wiseman\/biography\">Wiseman <\/a>es un aviador naval condecorado y piloto de pruebas de 50 a\u00f1os que se uni\u00f3 al cuerpo de astronautas de la NASA en 2009. M\u00e1s recientemente, Wiseman fue jefe de la oficina de astronautas, un cargo que ha sido descrito como ingrato, pero ventajoso porque permite a quienes lo ocupan asignarse a s\u00ed mismos a la misi\u00f3n que deseen al dejar el puesto.<\/p>\n<p>Cuando se le pregunta por qu\u00e9 la NASA est\u00e1 regresando a la Luna, Wiseman es directo: \u201cPorque queremos ver humanos en Marte\u201d, <a href=\"https:\/\/www.youtube.com\/watch?v=5AC5h4zKU4o\">dijo<\/a> en 2023 en \u201cThe Late Show With Stephen Colbert\u201d.<\/p>\n<p>La difunta esposa de Wiseman, Carroll Taylor Wiseman, era enfermera en una unidad de cuidados intensivos neonatales y muri\u00f3 en 2020 tras una batalla contra el c\u00e1ncer.<\/p>\n<p>Wiseman ha dicho que prest\u00f3 mucha atenci\u00f3n a sus dos hijas en preparaci\u00f3n para su viaje de 10 d\u00edas a la Luna.<\/p>\n<p>\u201cMe fui a caminar con mis hijas. Les dije: \u2018Aqu\u00ed es donde est\u00e1 el testamento, aqu\u00ed es donde est\u00e1n los documentos del fideicomiso, y si me pasa algo, esto es lo que les va a pasar a ustedes\u2019\u201d, dijo Wiseman. \u201cDe hecho, desear\u00eda que m\u00e1s gente en la vida cotidiana hablara con sus familias de esa manera porque nunca sabes qu\u00e9 va a traer el d\u00eda siguiente\u201d.<\/p>\n<p><strong>Ciudad natal: <\/strong>Pomona, California.<\/p>\n<p><strong>Experiencia previa en vuelos espaciales:<\/strong> pilot\u00f3 la misi\u00f3n SpaceX Crew-1, la primera misi\u00f3n rutinaria de seis meses a la Estaci\u00f3n Espacial Internacional a bordo de la nave Crew Dragon, que se lanz\u00f3 en 2020.<\/p>\n<p><strong>Rol en Artemis II: <\/strong>piloto.<\/p>\n<p><strong>Lleva consigo: <\/strong>una Biblia y una reliquia familiar para los miembros de su familia.<\/p>\n<p><a href=\"https:\/\/www.nasa.gov\/people\/victor-j-glover-jr\/\">Glover,<\/a> de 49 a\u00f1os, a menudo parece el m\u00e1s reservado del grupo y rara vez muestra emoci\u00f3n.<\/p>\n<p>\u201cLa emoci\u00f3n, por ejemplo, es algo sobre lo que me preguntan mucho y no la muestro a menudo\u201d, <a href=\"https:\/\/www.youtube.com\/watch?v=gGtZGSK_7ds&#038;t=1s\">dijo <\/a>Glover durante una conferencia de prensa el 17 de enero. \u201cCreo que puede convertirse en una distracci\u00f3n\u201d.<\/p>\n<p>Glover <a href=\"https:\/\/www.nasa.gov\/people\/victor-j-glover-jr\/\">tiene varios t\u00edtulos de maestr\u00eda,<\/a> incluida una maestr\u00eda en Ciencias en Ingenier\u00eda de Pruebas de Vuelo de Air University en la Base de la Fuerza A\u00e9rea Edwards, en California; una maestr\u00eda en Ciencias en Ingenier\u00eda de Sistemas de la Naval Postgraduate School; y una maestr\u00eda en Arte y Ciencia Operacional Militar de Air University, en Alabama.<\/p>\n<p>El mundo de los pilotos de pruebas es uno en el que se valora enormemente el manejo manual y h\u00e1bil de m\u00e1quinas complejas, y quienes trasladan su experiencia como pilotos de pruebas al mundo de la astron\u00e1utica a menudo se enfrentan a preguntas sobre c\u00f3mo se sienten al entrar en una nave espacial que est\u00e1 en gran medida automatizada.<\/p>\n<p>El legendario piloto de pruebas Chuck Yeager, por ejemplo, describi\u00f3 famosamente a los astronautas del programa Mercury de la NASA de principios de la d\u00e9cada de 1960 como \u201cSpam en una lata\u201d.<\/p>\n<p>Cuando se le pregunt\u00f3 sobre esa l\u00ednea de cuestionamiento de larga data (en su mayor\u00eda de buen humor), Glover brome\u00f3 diciendo que es \u201cun poco ludita\u201d.<\/p>\n<p>\u201cMe encantan los mandos o los controles que puedo, ya sabes, agarrar con las manos\u201d, dijo Glover, pero tambi\u00e9n acepta la automatizaci\u00f3n como el futuro, se\u00f1alando: \u201cNo vamos a deshacer todo eso\u201d.<\/p>\n<p>Pero lo que no ha cambiado son las necesidades y los deseos de los humanos a bordo de estas naves, algo que dijo que se dio cuenta mientras le\u00eda informes antiguos de astronautas de Mercury, Gemini y Apolo.<\/p>\n<p>\u201cDicen las mismas cosas que decimos nosotros: que tener una ventana es importante, tener la capacidad de realizar funciones cr\u00edticas es importante, y simplemente c\u00f3mo implementamos eso va a cambiar con el estado de la tecnolog\u00eda\u201d.<\/p>\n<p>Glover est\u00e1 casado con <a href=\"https:\/\/www.nasa.gov\/learning-resources\/behind-the-blue-suit-teamwork-as-an-astronauts-wife\/\">Dionna Odom Glover,<\/a> y tienen cuatro hijas. Ha dicho que est\u00e1 contento de que a las familias de la tripulaci\u00f3n se les asignar\u00e1 un astronauta en la Tierra para mantenerse en estrecho contacto y consolarlas durante la misi\u00f3n.<\/p>\n<p>El despegue \u201cpuede ser un momento magn\u00edfico y aterrador al mismo tiempo, y por eso estoy realmente agradecido con ese equipo que nos ayuda a prepararnos\u201d, dijo Glover.<\/p>\n<p><strong>Ciudad natal: <\/strong>Jacksonville, Carolina del Norte.<\/p>\n<p><strong>Experiencia previa en vuelos espaciales:<\/strong> despu\u00e9s de despegar hacia la Estaci\u00f3n Espacial Internacional a bordo de una c\u00e1psula Soyuz rusa en 2019, Koch pas\u00f3 328 d\u00edas en \u00f3rbita terrestre baja, un r\u00e9cord por la mayor cantidad de d\u00edas consecutivos en el espacio para una mujer. Ese a\u00f1o, tambi\u00e9n particip\u00f3 en el primer paseo espacial exclusivamente femenino.<\/p>\n<p><strong>Rol en Artemis II:<\/strong> especialista de misi\u00f3n.<\/p>\n<p><strong>Lleva consigo:<\/strong> notas manuscritas de sus seres queridos. Durante la misi\u00f3n, \u201cpuedo sostener en mis manos algo que ellos sostuvieron en sus manos\u201d, dijo Koch.<\/p>\n<p><a href=\"https:\/\/www.nasa.gov\/people\/christina-koch\/\">Koch <\/a>\u2014cuyo apellido se pronuncia \u201ccook\u201d\u2014 tiene una maestr\u00eda en Ingenier\u00eda el\u00e9ctrica de la Universidad Estatal de Carolina del Norte. Anteriormente, trabaj\u00f3 en sat\u00e9lites de observaci\u00f3n de la Tierra en el Centro de Vuelo Espacial Goddard de la NASA en Greenbelt, Maryland, y realiz\u00f3 estancias en algunos de los laboratorios m\u00e1s remotos del planeta, incluida la Estaci\u00f3n Amundsen-Scott del Polo Sur y la Estaci\u00f3n Palmer en la Ant\u00e1rtida.<\/p>\n<p>\u201cMe encantaban las cosas que me hac\u00edan sentir peque\u00f1a, cosas que me hac\u00edan reflexionar sobre el tama\u00f1o del universo, mi lugar en \u00e9l\u201d, dijo Koch en un <a href=\"https:\/\/www.youtube.com\/watch?v=IdP-RFD9Plc\">video de la NASA <\/a>de 2020.<\/p>\n<p>Se uni\u00f3 al cuerpo de astronautas en 2013.<\/p>\n<p>Koch afirm\u00f3 que desde hace mucho tiempo admira a los astronautas del Apolo, que parec\u00edan disfrutar reuni\u00e9ndose en eventos de la NASA, incluso d\u00e9cadas despu\u00e9s de retirarse del cuerpo.<\/p>\n<p>\u201cLo que vivieron juntos y c\u00f3mo eso los uni\u00f3 ha sido realmente fundamental para m\u00ed para apreciar cada d\u00eda con mi tripulaci\u00f3n\u201d, asegur\u00f3 Koch en una <a href=\"https:\/\/www.youtube.com\/watch?v=gGtZGSK_7ds\">conferencia de prensa<\/a> el 17 de enero.<\/p>\n<p>Dijo que nunca olvidar\u00eda estar en un evento y ver al astronauta del Apolo 13 Fred Haise, quien afirm\u00f3 sin rodeos: \u201cEscuch\u00e9 que van a romper nuestro r\u00e9cord\u201d de la mayor distancia que los humanos han viajado jam\u00e1s en el espacio. La tripulaci\u00f3n del Apolo 13 alcanz\u00f3 400.171 kil\u00f3metros de la Tierra en 1970, pero Artemis II podr\u00eda romper ese r\u00e9cord, ya que se espera que viaje m\u00e1s de 402.000 kil\u00f3metros.<\/p>\n<p>\u201cEn ese momento\u201d, dijo Koch refiri\u00e9ndose a Haise, \u201c\u00e9l me introdujo en ese grupo de camarader\u00eda\u201d.<\/p>\n<p>Y aunque Koch asegur\u00f3 que est\u00e1 emocionada y preparada para romper m\u00e1s r\u00e9cords con sus compa\u00f1eros de tripulaci\u00f3n de Artemis, ha lidiado con las cuestiones pr\u00e1cticas de dejar a su esposo en casa sin una forma sencilla de comunicarse con ella durante la misi\u00f3n.<\/p>\n<p>\u201cRealmente tengo que asegurarme de que \u00e9l sepa que no es como la Estaci\u00f3n Espacial Internacional, donde podemos simplemente hacer una llamada telef\u00f3nica, as\u00ed que no va a poder llamarme y preguntarme d\u00f3nde est\u00e1 algo en la casa\u201d, brome\u00f3 Koch. \u201cVa a tener que encontrarlo\u201d.<\/p>\n<p><strong>Ciudad natal:<\/strong> London, Ontario.<\/p>\n<p><strong>Experiencia previa de vuelo espacial:<\/strong> ninguna.<\/p>\n<p><strong>Rol en Artemis II: <\/strong>especialista de misi\u00f3n.<\/p>\n<p><strong>Lleva consigo: c<\/strong>uatro colgantes de luna que dio como regalos a su esposa e hijos.<\/p>\n<p>La misi\u00f3n Artemis II marcar\u00e1 el primer viaje al espacio para Hansen, una haza\u00f1a impresionante, ya que la mayor\u00eda de los que vuelan por primera vez se mantienen cerca de casa en misiones a la \u00f3rbita terrestre baja, donde se encuentra la Estaci\u00f3n Espacial Internacional. En Artemis II, Hansen viajar\u00e1 aproximadamente 1.000 veces m\u00e1s lejos.<\/p>\n<p>Hansen creci\u00f3 en una granja, y dijo que sol\u00eda arar la alfombra de la sala con tractores de juguete y fingir que su casa del \u00e1rbol era una nave espacial, pero tambi\u00e9n so\u00f1aba con volar aviones, jets y naves espaciales antes de convertirse en piloto de caza de la Real Fuerza A\u00e9rea Canadiense.<\/p>\n<p>Aunque no tiene experiencia previa como astronauta, Hansen s\u00ed ostenta los t\u00edtulos de <a href=\"https:\/\/www.esa.int\/Science_Exploration\/Human_and_Robotic_Exploration\/Cavenauts_return_to_Earth\">cavenauta<\/a> y acuanauta.<\/p>\n<p>Su entrenamiento de espeleolog\u00eda provino del programa<a href=\"https:\/\/www.esa.int\/Science_Exploration\/Human_and_Robotic_Exploration\/CAVES_and_Pangaea\/What_is_CAVES\"> CAVES de la Agencia Espacial Europea,<\/a> en el que explor\u00f3 bajo tierra durante seis d\u00edas en la isla italiana de Cerde\u00f1a para prepararse para vivir y trabajar con otros en condiciones remotas y aislantes.<\/p>\n<p>Hansen fue miembro de la excursi\u00f3n NASA Extreme Environment Mission Operations, o NEEMO 19, y pas\u00f3 una semana en un h\u00e1bitat submarino cerca de Key Largo, Florida.<\/p>\n<p>\u201cEn realidad es muy peligroso\u201d, dijo Hansen a la CBC sobre su entrenamiento como acuanauta, se\u00f1alando que cualquier intento de regresar r\u00e1pidamente a la superficie podr\u00eda ser letal debido a la enfermedad por descompresi\u00f3n.<\/p>\n<p>\u201cEstamos all\u00e1 abajo durante una semana. Estamos completamente saturados\u201d, record\u00f3 Hansen. \u201cAs\u00ed que, si tienes un problema all\u00e1 abajo y simplemente decides subir a la superficie, est\u00e1s muerto\u201d.<\/p>\n<p>Cuando un reportero pregunt\u00f3 a sus colegas estadounidenses qu\u00e9 podr\u00eda aportar el astronauta novato, Hansen, a quien se considera el comediante del grupo, <a href=\"https:\/\/www.youtube.com\/watch?v=9mq_lb_SmKE\">brome\u00f3: <\/a>\u201cBueno, solo tienes una pregunta\u201d.<\/p>\n<p>\u201c\u00c9l es el gracioso\u201d, confirm\u00f3 Glover entre risas.<\/p>\n<p>Hansen tambi\u00e9n es inusualmente alto para un astronauta: mide cerca de 1,88 metros. Durante una conferencia de prensa en septiembre, Wiseman brome\u00f3 diciendo que su nave espacial Orion, de unos 5 metros de ancho, se sentir\u00e1 lo suficientemente grande para la mayor parte de su viaje de 10 d\u00edas, \u201chasta que Jeremy empiece a hacer ejercicio\u201d, dijo Wiseman. \u201cEntonces va a volver a sentirse peque\u00f1a\u201d.<\/p>\n<p>Cuando se le pregunt\u00f3 sobre los peligros implicados en su hist\u00f3rica misi\u00f3n al espacio profundo, Hansen dijo que la tripulaci\u00f3n de Artemis II est\u00e1 \u201casumiendo riesgos calculados\u201d.<\/p>\n<p>\u201cVamos a asumir algunos riesgos apropiados, y vamos a lograr algunas cosas extraordinarias\u201d, se\u00f1al\u00f3. \u201cVamos a tener algunos fracasos, algunos contratiempos en el camino, y luego nos levantaremos de nuevo y seguiremos adelante\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La primera mujer. La primera persona negra. El primer canadiense. Las cuatro personas que pronto embarcar\u00e1n en una nave espacial para la primera misi\u00f3n tripulada a la Luna en m\u00e1s de medio siglo representan un conjunto de hitos hist\u00f3ricos. Se espera que la tripulaci\u00f3n de la misi\u00f3n Artemis II, liderada por la NASA, ampl\u00ede la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472629","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Conoce a la tripulaci\u00f3n de Artemis II de la NASA, que marcar\u00e1 el inicio de una nueva era de exploraci\u00f3n del espacio profundo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/27\/tripulacion-artemis-ii-nasa-espacio-luna-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conoce a la tripulaci\u00f3n de Artemis II de la NASA, que marcar\u00e1 el inicio de una nueva era de exploraci\u00f3n del espacio profundo - Noticias\" \/>\n<meta property=\"og:description\" content=\"La primera mujer. La primera persona negra. El primer canadiense. Las cuatro personas que pronto embarcar\u00e1n en una nave espacial para la primera misi\u00f3n tripulada a la Luna en m\u00e1s de medio siglo representan un conjunto de hitos hist\u00f3ricos. Se espera que la tripulaci\u00f3n de la misi\u00f3n Artemis II, liderada por la NASA, ampl\u00ede la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/27\/tripulacion-artemis-ii-nasa-espacio-luna-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-28T02:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/27\/tripulacion-artemis-ii-nasa-espacio-luna-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/27\/tripulacion-artemis-ii-nasa-espacio-luna-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Conoce a la tripulaci\u00f3n de Artemis II de la NASA, que marcar\u00e1 el inicio de una nueva era de exploraci\u00f3n del espacio profundo\",\"datePublished\":\"2026-03-28T02:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/27\/tripulacion-artemis-ii-nasa-espacio-luna-trax\/\"},\"wordCount\":2458,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/27\/tripulacion-artemis-ii-nasa-espacio-luna-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/27\/tripulacion-artemis-ii-nasa-espacio-luna-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/27\/tripulacion-artemis-ii-nasa-espacio-luna-trax\/\",\"name\":\"Conoce a la tripulaci\u00f3n de Artemis II de la NASA, que marcar\u00e1 el inicio de una nueva era de exploraci\u00f3n del espacio profundo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-28T02:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/27\/tripulacion-artemis-ii-nasa-espacio-luna-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/27\/tripulacion-artemis-ii-nasa-espacio-luna-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/27\/tripulacion-artemis-ii-nasa-espacio-luna-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conoce a la tripulaci\u00f3n de Artemis II de la NASA, que marcar\u00e1 el inicio de una nueva era de exploraci\u00f3n del espacio profundo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conoce a la tripulaci\u00f3n de Artemis II de la NASA, que marcar\u00e1 el inicio de una nueva era de exploraci\u00f3n del espacio profundo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/27\/tripulacion-artemis-ii-nasa-espacio-luna-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Conoce a la tripulaci\u00f3n de Artemis II de la NASA, que marcar\u00e1 el inicio de una nueva era de exploraci\u00f3n del espacio profundo - Noticias","og_description":"La primera mujer. La primera persona negra. El primer canadiense. Las cuatro personas que pronto embarcar\u00e1n en una nave espacial para la primera misi\u00f3n tripulada a la Luna en m\u00e1s de medio siglo representan un conjunto de hitos hist\u00f3ricos. Se espera que la tripulaci\u00f3n de la misi\u00f3n Artemis II, liderada por la NASA, ampl\u00ede la [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/27\/tripulacion-artemis-ii-nasa-espacio-luna-trax\/","og_site_name":"Noticias","article_published_time":"2026-03-28T02:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/27\/tripulacion-artemis-ii-nasa-espacio-luna-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/27\/tripulacion-artemis-ii-nasa-espacio-luna-trax\/"},"author":{"name":"","@id":""},"headline":"Conoce a la tripulaci\u00f3n de Artemis II de la NASA, que marcar\u00e1 el inicio de una nueva era de exploraci\u00f3n del espacio profundo","datePublished":"2026-03-28T02:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/27\/tripulacion-artemis-ii-nasa-espacio-luna-trax\/"},"wordCount":2458,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/27\/tripulacion-artemis-ii-nasa-espacio-luna-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/27\/tripulacion-artemis-ii-nasa-espacio-luna-trax\/","url":"https:\/\/noticiasya.com\/2026\/03\/27\/tripulacion-artemis-ii-nasa-espacio-luna-trax\/","name":"Conoce a la tripulaci\u00f3n de Artemis II de la NASA, que marcar\u00e1 el inicio de una nueva era de exploraci\u00f3n del espacio profundo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-28T02:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/27\/tripulacion-artemis-ii-nasa-espacio-luna-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/27\/tripulacion-artemis-ii-nasa-espacio-luna-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/27\/tripulacion-artemis-ii-nasa-espacio-luna-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Conoce a la tripulaci\u00f3n de Artemis II de la NASA, que marcar\u00e1 el inicio de una nueva era de exploraci\u00f3n del espacio profundo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2026\/03\/27\/tripulacion-artemis-ii-nasa-espacio-luna-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Conoce a la tripulaci\u00f3n de Artemis II de la NASA, que marcar\u00e1 el inicio de una nueva era de exploraci\u00f3n del espacio profundo","url":"http:\/\/noticiasya.com\/colorado\/2026\/03\/27\/tripulacion-artemis-ii-nasa-espacio-luna-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2026\/03\/27\/tripulacion-artemis-ii-nasa-espacio-luna-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-28T02:03:51Z","datePublished":"2026-03-28T02:03:51Z","dateModified":"2026-03-28T02:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Conoce a la tripulaci\\u00f3n de Artemis II de la NASA, que marcar\\u00e1 el inicio de una nueva era de exploraci\\u00f3n del espacio profundo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/03\\\/27\\\/tripulacion-artemis-ii-nasa-espacio-luna-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/03\\\/27\\\/tripulacion-artemis-ii-nasa-espacio-luna-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-28T02:03:51Z\",\"datePublished\":\"2026-03-28T02:03:51Z\",\"dateModified\":\"2026-03-28T02:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1469701,"url":"https:\/\/noticiasya.com\/colorado\/2025\/12\/31\/nasa-luna-mision-artemis-2-trax\/","url_meta":{"origin":1472629,"position":0},"title":"La NASA estar\u00eda a semanas de su mayor desaf\u00edo en d\u00e9cadas: un viaje tripulado a la Luna","author":"","date":"diciembre 31, 2025","format":false,"excerpt":"La aspiraci\u00f3n de devolver astronautas estadounidenses a la Luna ha estado en limbo durante d\u00e9cadas, debido a que los planes han sido adoptados y rechazados de una administraci\u00f3n presidencial a otra. Sin embargo, en 2026, ese objetivo cobrar\u00e1 un enfoque m\u00e1s claro.El programa Artemis de la NASA \u2014una iniciativa anunciada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472760,"url":"https:\/\/noticiasya.com\/colorado\/2026\/04\/01\/quienes-son-tripulantes-artemis-ii-trax\/","url_meta":{"origin":1472629,"position":1},"title":"\u00bfQui\u00e9nes son los tripulantes de la misi\u00f3n Artemis II de la NASA que viajar\u00e1 a la Luna?","author":"","date":"abril 1, 2026","format":false,"excerpt":"La primera mujer. La primera persona negra. El primer canadiense.Las cuatro personas que pronto embarcar\u00e1n en una nave espacial para la primera misi\u00f3n tripulada a la Luna en m\u00e1s de medio siglo representan un conjunto de hitos hist\u00f3ricos. Se espera que la tripulaci\u00f3n de la misi\u00f3n Artemis II, liderada por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452861,"url":"https:\/\/noticiasya.com\/colorado\/2024\/09\/19\/maniquies-luna-camino-astronautas-espacio-trax\/","url_meta":{"origin":1472629,"position":2},"title":"Dos maniqu\u00edes volaron alrededor de la Luna; los cient\u00edficos acaban de revelar c\u00f3mo les fue y c\u00f3mo podr\u00eda afectar a los astronautas","author":"","date":"septiembre 19, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 A medida que se acerca Artemis II, la misi\u00f3n de la NASA que enviar\u00e1 cuatro astronautas a circunnavegar la Luna el a\u00f1o pr\u00f3ximo, un nuevo estudio revela qu\u00e9 tan bien proteger\u00e1 a la tripulaci\u00f3n su nave espacial Orion.Los hallazgos se basan en datos de Artemis I, un viaje\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473067,"url":"https:\/\/noticiasya.com\/colorado\/2026\/04\/11\/astronautas-artemis-ii-publico-amerizaje-trax\/","url_meta":{"origin":1472629,"position":3},"title":"&#171;Estamos unidos para siempre&#187;: astronautas de Artemis II aparecen p\u00fablicamente por primera vez tras su regreso a la Tierra","author":"","date":"abril 11, 2026","format":false,"excerpt":"Fue una bienvenida de h\u00e9roes para la tripulaci\u00f3n de cuatro personas de Artemis II tras un amerizaje impecable en el oc\u00e9ano Pac\u00edfico el viernes por la noche.Los astronautas llegaron este s\u00e1bado a Ellington Field, en el Centro Espacial Johnson en Houston, entre v\u00edtores, una ovaci\u00f3n de pie y abrazos del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472871,"url":"https:\/\/noticiasya.com\/colorado\/2026\/04\/04\/camino-luna-astronautas-problema-bano-trax\/","url_meta":{"origin":1472629,"position":4},"title":"A m\u00e1s de la mitad del camino hacia la Luna, los astronautas de Artemis II enfrentan un problema con el inodoro","author":"","date":"abril 4, 2026","format":false,"excerpt":"Los cuatro astronautas de la misi\u00f3n Artemis II, que actualmente avanzan a gran velocidad por el espacio, han tenido, hasta ahora, un viaje en gran medida tranquilo. Han surgido muy pocos problemas en vuelo que puedan alterar su tranquilidad.Excepto, claro, por el ba\u00f1o.La tripulaci\u00f3n de Artemis II, a bordo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472845,"url":"https:\/\/noticiasya.com\/colorado\/2026\/04\/03\/donde-esta-orion-que-sigue-artemis-ii-luna-trax\/","url_meta":{"origin":1472629,"position":5},"title":"D\u00f3nde est\u00e1 la nave Orion y qu\u00e9 sigue para la misi\u00f3n Artemis II en su camino a la Luna","author":"","date":"abril 3, 2026","format":false,"excerpt":"La misi\u00f3n Artemis II cruz\u00f3 un umbral crucial e hist\u00f3rico el jueves, cuando la nave espacial Orion encendi\u00f3 su motor e impuls\u00f3 a cuatro astronautas hacia la Luna, en un viaje de varios d\u00edas que los llevar\u00e1 m\u00e1s lejos en el espacio de lo que cualquier ser humano ha viajado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1472629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1472629"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1472629\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1472629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1472629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1472629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}