{"id":1472694,"date":"2026-03-30T12:03:45","date_gmt":"2026-03-30T19:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/30\/religion-corte-suprema-ciudadania-nacimiento-trax\/"},"modified":"2026-03-30T12:03:45","modified_gmt":"2026-03-30T19:03:45","slug":"religion-corte-suprema-ciudadania-nacimiento-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2026\/03\/30\/religion-corte-suprema-ciudadania-nacimiento-trax\/","title":{"rendered":"La religi\u00f3n entra al debate de la ciudadan\u00eda por nacimiento ante la Corte Suprema"},"content":{"rendered":"<p>Mientras la Corte Suprema analiza el futuro de la ciudadan\u00eda por derecho de nacimiento, algunos defensores que luchan contra el presidente Donald Trump se dirigen directamente a los jueces conservadores para explicarles cu\u00e1n fundamental puede ser la fe para la identidad y la ciudadan\u00eda.<\/p>\n<p>Varios grupos han presentado escritos en el caso que se debatir\u00e1 el mi\u00e9rcoles, que hacen referencia al imperativo moral de acoger a los extranjeros (con alusiones a las Sagradas Escrituras) y llaman la atenci\u00f3n sobre el tipo de dilemas pr\u00e1cticos a los que podr\u00edan enfrentarse los creyentes si el Gobierno de Trump restringiera la garant\u00eda de la Decimocuarta Enmienda de que todos los ni\u00f1os nacidos en Estados Unidos son ciudadanos.<\/p>\n<p>Se dirigen a la mayor\u00eda cat\u00f3lica de los tribunales, que ha favorecido los intereses religiosos en disputas sobre el financiamiento de la educaci\u00f3n, las manifestaciones cristianas y diversas pol\u00edticas gubernamentales.<\/p>\n<p>Muchos analistas jur\u00eddicos de todo el espectro ideol\u00f3gico creen que las ideas de Trump son radicales y est\u00e1n condenadas al fracaso. Sin embargo, el Tribunal Supremo se ha mostrado receptivo a otros aspectos de la audaz agenda de Trump, y los defensores de los derechos de los inmigrantes y otros demandantes han presentado diversos argumentos, incluso relacionados con la religi\u00f3n.<\/p>\n<p>Los abogados del Proyecto Rousseau, que atiende a j\u00f3venes vulnerables, argumentan que los jueces deber\u00edan considerar a los ni\u00f1os que no pueden probar su paternidad ni su ciudadan\u00eda. Esto incluir\u00eda a algunos beb\u00e9s nacidos de miembros de sectas religiosas, como los amish y los menonitas, que rechazan los documentos de nacimiento formales.<\/p>\n<p><a href=\"https:\/\/www.supremecourt.gov\/DocketPDF\/25\/25-365\/399441\/20260226165623799_25-365%20Amicus%20Brief.pdf\">Seg\u00fan Project Rousseau<\/a>, si el Gobierno de Trump prevalece, esas familias religiosas se ver\u00edan obligadas a \u201cdecidir entre sus derechos de libre ejercicio de la religi\u00f3n y sus derechos de ciudadan\u00eda por nacimiento\u201d.<\/p>\n<p>Ilan Rosenberg, abogado principal del escrito, tambi\u00e9n hizo referencia al reciente inter\u00e9s de los magistrados en las \u201cLeyes de Refugio Seguro\u201d, consideradas a veces como una alternativa al aborto, ya que el grupo se centr\u00f3 en los beb\u00e9s abandonados al nacer.<\/p>\n<p>Cit\u00f3 la observaci\u00f3n de la jueza Amy Coney Barrett de <a href=\"https:\/\/www.documentcloud.org\/documents\/21122957-dobbs-v-jackson-womens-health-transcript\/\">los argumentos orales<\/a> de 2022 en el caso Dobbs vs. Jackson Women\u2019s Health Organization, seg\u00fan la cual \u201cen los 50 estados, se pueden rescindir los derechos parentales renunciando a un ni\u00f1o\u201d despu\u00e9s del nacimiento y, tal vez, dejando al ni\u00f1o en un hospital o una estaci\u00f3n de bomberos.<\/p>\n<p>Rosenberg declar\u00f3 ante los magistrados que un ni\u00f1o entregado an\u00f3nimamente en virtud de una Ley de Refugio Seguro \u201cnunca podr\u00eda demostrar lo que el Gobierno propone como esencial para la ciudadan\u00eda seg\u00fan la 14\u00aa Enmienda: la condici\u00f3n de ciudadano de sus padres\u201d.<\/p>\n<p>En el caso Dobbs, la Corte Suprema revoc\u00f3 el derecho constitucional al aborto garantizado en la decisi\u00f3n Roe vs. Wade de 1973.<\/p>\n<p>La mayor\u00eda del tribunal se ha alineado cada vez m\u00e1s con los conservadores religiosos en otros \u00e1mbitos, incluso para respaldar la oraci\u00f3n de un entrenador en los partidos de f\u00fatbol americano de las escuelas p\u00fablicas, para ampliar el financiamiento estatal de la educaci\u00f3n confesional y para mantener los s\u00edmbolos cristianos en propiedades gubernamentales.<\/p>\n<p>Un breve art\u00edculo destaca que las colonias americanas fueron fundadas por personas que hu\u00edan de la persecuci\u00f3n por sus pr\u00e1cticas religiosas.<\/p>\n<p>\u201cLa consagraci\u00f3n de la ciudadan\u00eda por derecho de nacimiento en la Decimocuarta Enmienda\u201d, escribi\u00f3 un grupo de <a href=\"https:\/\/www.supremecourt.gov\/DocketPDF\/25\/25-365\/400017\/20260304175230895_25-365%20Amicus%20Brief.pdf\">57 organizaciones religiosas<\/a>, \u201ctiene una profunda conexi\u00f3n con la historia de la Naci\u00f3n como refugio para quienes hu\u00edan de la persecuci\u00f3n religiosa, incluidos los antepasados \u200b\u200by los miembros actuales de muchos de los grupos religiosos representados por los <em>amici curiae<\/em>. Varias de las Trece Colonias fueron fundadas por grupos, como los cu\u00e1queros, que escapaban de la persecuci\u00f3n religiosa o buscaban garantizar la libertad religiosa\u201d.<\/p>\n<p>Entre las organizaciones que se sumaron al informe, adem\u00e1s de la Conferencia General de los Amigos (Cu\u00e1queros), se encuentran la Alianza de Bautistas, el Comit\u00e9 Jud\u00edo Estadounidense, el Consejo de Relaciones Americano-Isl\u00e1micas, el Consejo Nacional de Iglesias y el Comit\u00e9 de Servicio Unitario Universalista.<\/p>\n<p>Estos escritos con tintes religiosos se encuentran entre los m\u00e1s de 60 documentos presentados como <em>amicus curiae<\/em> en el caso Trump v. Barbara, que ponen a prueba el significado de la Decimocuarta Enmienda, la cual establece que \u201cTodas las personas nacidas o naturalizadas en Estados Unidos y sujetas a su jurisdicci\u00f3n son ciudadanos de Estados Unidos\u201d.<\/p>\n<p>Aproximadamente dos tercios de esos escritos de <em>amicus curiae<\/em> apoyan a los demandantes. Sostienen que la historia de la Decimocuarta Enmienda y la jurisprudencia consolidaron una ciudadan\u00eda por derecho de nacimiento pr\u00e1cticamente ilimitada.<\/p>\n<p>Los abogados de Trump se han aferrado a la frase \u201csujeto a la jurisdicci\u00f3n\u201d y sostienen que cualquier persona que se encuentre en el pa\u00eds de forma ilegal o temporal, como por ejemplo con una visa de estudiante, no est\u00e1 completamente sujeta a la jurisdicci\u00f3n estadounidense.<\/p>\n<p>Algunos grupos que respaldaron al Gobierno de Trump ofrecieron interpretaciones alternativas de la historia y la tradici\u00f3n de la Decimocuarta Enmienda. Una de las solicitudes, con tem\u00e1tica religiosa, provino de la <a href=\"https:\/\/www.supremecourt.gov\/DocketPDF\/25\/25-365\/381028\/20251029155657867_25-364%20and%2025-365%20Amicus%20Brief.pdf\">Coalici\u00f3n de Familias Cristianas de Florida<\/a>. Esta argument\u00f3 que otorgar la ciudadan\u00eda por derecho de nacimiento a \u201cinmigrantes indocumentados y personas sin domicilio fijo\u201d atraer\u00eda a personas que promueven la intolerancia religiosa.<\/p>\n<p>Los jueces de primera instancia fallaron en contra de la iniciativa de Trump para limitar la ciudadan\u00eda por derecho de nacimiento, al considerar que contraven\u00eda el texto de la Decimocuarta Enmienda y entraba en conflicto con un hito de 1898. En el caso <a href=\"https:\/\/constitutioncenter.org\/the-constitution\/supreme-court-case-library\/united-states-v-wong-kim-ark-1898\">Estados Unidos vs. Wong Kim Ark<\/a>, el tribunal dictamin\u00f3 que un hombre nacido de ciudadanos chinos residentes en Estados Unidos era ciudadano estadounidense.<\/p>\n<p>Muchos de los escritos de <em>amicus curiae<\/em> que se oponen a Trump refuerzan los argumentos relativos a la larga historia y tradici\u00f3n de la Decimocuarta Enmienda.<\/p>\n<p>Entre los diversos informes presentados por los opositores que abordan temas religiosos, destaca un argumento provocador que recuerda la hostilidad anticat\u00f3lica y antiinmigrante de los <em>Know Nothings<\/em> a mediados del siglo XIX.<\/p>\n<p>El informe, liderado por el historiador Tyler Anbinder, sostiene que, a pesar del importante poder pol\u00edtico que ten\u00edan los <em>Know Nothings<\/em> en aquel momento, el grupo acept\u00f3 la ciudadan\u00eda por derecho de nacimiento y nunca propuso limitarla, ni siquiera para los hijos de los inmigrantes que quer\u00edan deportar.<\/p>\n<p>\u201cEl Gobierno pide al Tribunal que adopte una postura que ni siquiera los <em>Know Nothings<\/em> \u2014el movimiento pol\u00edtico antiinmigrante m\u00e1s exitoso y extremo de la historia estadounidense\u2014 buscaron jam\u00e1s: restringir la ciudadan\u00eda por derecho de nacimiento bas\u00e1ndose en la afiliaci\u00f3n pol\u00edtica de los padres del ni\u00f1o\u201d, <a href=\"https:\/\/www.supremecourt.gov\/DocketPDF\/25\/25-365\/399347\/20260226105344219_390798_Amicus%20Brief.pdf\">escribieron los profesores de historia y derecho<\/a>.<\/p>\n<p>Por otra parte, el escrito presentado por 57 organizaciones religiosas que abarcan a cat\u00f3licos, protestantes, musulmanes, hind\u00faes y jud\u00edos, se\u00f1ala la tradici\u00f3n religiosa de acoger a los extranjeros.<\/p>\n<p>\u201cEn el cristianismo\u201d, dice este breve documento, \u201cel Nuevo Testamento ense\u00f1a: \u2018Porque tuve hambre, y me diste de comer; tuve sed, y me diste de beber; fui forastero, y me acogieron\u2019. Mateo 25:35\u201d.<\/p>\n<p>El juez Brett Kavanaugh hizo hincapi\u00e9 en el mensaje b\u00edblico de Mateo durante sus audiencias de confirmaci\u00f3n en 2018, dici\u00e9ndoles a los senadores al comienzo: \u201cTengo presente el mensaje de Mateo 25 y trato de servir a los menos afortunados entre nosotros\u201d.<\/p>\n<p>Tras sus pol\u00e9micas audiencias en el Senado, Kavanaugh volvi\u00f3 a referirse al Evangelio de Mateo en <a href=\"https:\/\/trumpwhitehouse.archives.gov\/briefings-statements\/remarks-president-trump-swearing-ceremony-honorable-brett-m-kavanaugh-associate-justice-supreme-court-united-states\/\">una ceremonia en la Casa Blanca<\/a>. \u201cA ra\u00edz del proceso de confirmaci\u00f3n en el Senado, mi enfoque de la vida sigue siendo el mismo. Continuar\u00e9 teniendo presente el mensaje de Mateo 25. Continuar\u00e9 ofreciendo mi ayuda como voluntario y sirviendo a los m\u00e1s necesitados\u201d.<\/p>\n<p>Kavanaugh es uno de los seis magistrados del ala conservadora que son cat\u00f3licos practicantes o fueron criados en la fe cat\u00f3lica. Los otros son el presidente del Tribunal Supremo, John Roberts, y los magistrados Clarence Thomas, Samuel Alito y Amy Coney Barrett; Neil Gorsuch fue criado en la fe cat\u00f3lica y ahora es episcopaliano.<\/p>\n<p>La s\u00e9ptima jueza cat\u00f3lica, Sonia Sotomayor, encabeza el ala liberal junto con Elena Kagan, una jueza jud\u00eda, y Ketanji Brown Jackson, una protestante.<\/p>\n<p>En ese contexto predominantemente cat\u00f3lico, los abogados de la Conferencia de Obispos Cat\u00f3licos de Estados Unidos presentaron un en\u00e9rgico escrito argumentando la inmoralidad del decreto de Trump que restringe la ciudadan\u00eda por derecho de nacimiento.<\/p>\n<p>\u201cLos efectos, tanto previstos como imprevistos, del decreto\u201d, <a href=\"https:\/\/www.supremecourt.gov\/DocketPDF\/25\/25-365\/399395\/20260226144523582_25-365%20bsac%20United%20States%20Conference%20of%20Catholic%20Bishops.pdf\">afirma el informe de los obispos cat\u00f3licos<\/a>, \u201cson inmorales y contrarios a las creencias y ense\u00f1anzas fundamentales de la Iglesia cat\u00f3lica con respecto a la vida y la dignidad de las personas humanas, el trato a las personas vulnerables, en particular a los migrantes y los ni\u00f1os, y la unidad familiar\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mientras la Corte Suprema analiza el futuro de la ciudadan\u00eda por derecho de nacimiento, algunos defensores que luchan contra el presidente Donald Trump se dirigen directamente a los jueces conservadores para explicarles cu\u00e1n fundamental puede ser la fe para la identidad y la ciudadan\u00eda. Varios grupos han presentado escritos en el caso que se debatir\u00e1 [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472694","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La religi\u00f3n entra al debate de la ciudadan\u00eda por nacimiento ante la Corte Suprema - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/30\/religion-corte-suprema-ciudadania-nacimiento-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La religi\u00f3n entra al debate de la ciudadan\u00eda por nacimiento ante la Corte Suprema - Noticias\" \/>\n<meta property=\"og:description\" content=\"Mientras la Corte Suprema analiza el futuro de la ciudadan\u00eda por derecho de nacimiento, algunos defensores que luchan contra el presidente Donald Trump se dirigen directamente a los jueces conservadores para explicarles cu\u00e1n fundamental puede ser la fe para la identidad y la ciudadan\u00eda. Varios grupos han presentado escritos en el caso que se debatir\u00e1 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/30\/religion-corte-suprema-ciudadania-nacimiento-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-30T19:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/30\/religion-corte-suprema-ciudadania-nacimiento-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/30\/religion-corte-suprema-ciudadania-nacimiento-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La religi\u00f3n entra al debate de la ciudadan\u00eda por nacimiento ante la Corte Suprema\",\"datePublished\":\"2026-03-30T19:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/30\/religion-corte-suprema-ciudadania-nacimiento-trax\/\"},\"wordCount\":1550,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/30\/religion-corte-suprema-ciudadania-nacimiento-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/30\/religion-corte-suprema-ciudadania-nacimiento-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/30\/religion-corte-suprema-ciudadania-nacimiento-trax\/\",\"name\":\"La religi\u00f3n entra al debate de la ciudadan\u00eda por nacimiento ante la Corte Suprema - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-30T19:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/30\/religion-corte-suprema-ciudadania-nacimiento-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/30\/religion-corte-suprema-ciudadania-nacimiento-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/30\/religion-corte-suprema-ciudadania-nacimiento-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La religi\u00f3n entra al debate de la ciudadan\u00eda por nacimiento ante la Corte Suprema\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La religi\u00f3n entra al debate de la ciudadan\u00eda por nacimiento ante la Corte Suprema - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/30\/religion-corte-suprema-ciudadania-nacimiento-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La religi\u00f3n entra al debate de la ciudadan\u00eda por nacimiento ante la Corte Suprema - Noticias","og_description":"Mientras la Corte Suprema analiza el futuro de la ciudadan\u00eda por derecho de nacimiento, algunos defensores que luchan contra el presidente Donald Trump se dirigen directamente a los jueces conservadores para explicarles cu\u00e1n fundamental puede ser la fe para la identidad y la ciudadan\u00eda. Varios grupos han presentado escritos en el caso que se debatir\u00e1 [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/30\/religion-corte-suprema-ciudadania-nacimiento-trax\/","og_site_name":"Noticias","article_published_time":"2026-03-30T19:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/30\/religion-corte-suprema-ciudadania-nacimiento-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/30\/religion-corte-suprema-ciudadania-nacimiento-trax\/"},"author":{"name":"","@id":""},"headline":"La religi\u00f3n entra al debate de la ciudadan\u00eda por nacimiento ante la Corte Suprema","datePublished":"2026-03-30T19:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/30\/religion-corte-suprema-ciudadania-nacimiento-trax\/"},"wordCount":1550,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/30\/religion-corte-suprema-ciudadania-nacimiento-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/30\/religion-corte-suprema-ciudadania-nacimiento-trax\/","url":"https:\/\/noticiasya.com\/2026\/03\/30\/religion-corte-suprema-ciudadania-nacimiento-trax\/","name":"La religi\u00f3n entra al debate de la ciudadan\u00eda por nacimiento ante la Corte Suprema - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-30T19:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/30\/religion-corte-suprema-ciudadania-nacimiento-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/30\/religion-corte-suprema-ciudadania-nacimiento-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/30\/religion-corte-suprema-ciudadania-nacimiento-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La religi\u00f3n entra al debate de la ciudadan\u00eda por nacimiento ante la Corte Suprema"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2026\/03\/30\/religion-corte-suprema-ciudadania-nacimiento-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La religi\u00f3n entra al debate de la ciudadan\u00eda por nacimiento ante la Corte Suprema","url":"http:\/\/noticiasya.com\/colorado\/2026\/03\/30\/religion-corte-suprema-ciudadania-nacimiento-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2026\/03\/30\/religion-corte-suprema-ciudadania-nacimiento-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-30T19:03:45Z","datePublished":"2026-03-30T19:03:45Z","dateModified":"2026-03-30T19:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La religi\\u00f3n entra al debate de la ciudadan\\u00eda por nacimiento ante la Corte Suprema\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/03\\\/30\\\/religion-corte-suprema-ciudadania-nacimiento-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/03\\\/30\\\/religion-corte-suprema-ciudadania-nacimiento-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-30T19:03:45Z\",\"datePublished\":\"2026-03-30T19:03:45Z\",\"dateModified\":\"2026-03-30T19:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1471553,"url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/23\/trump-corte-suprema-ciudadania-nacimiento-trax\/","url_meta":{"origin":1472694,"position":0},"title":"Trump dice que la Corte Suprema llegar\u00e1 a una &#171;conclusi\u00f3n equivocada&#187; sobre la ciudadan\u00eda por nacimiento","author":"","date":"febrero 23, 2026","format":false,"excerpt":"El presidente Donald Trump escribi\u00f3 el lunes en redes sociales que cree que la Corte Suprema llegar\u00e1 a una \u201cconclusi\u00f3n equivocada\u201d sobre la ciudadan\u00eda por nacimiento.\u201cLo siguiente ser\u00e1 que fallen a favor de China y otros pa\u00edses, que est\u00e1n haciendo fortunas con la ciudadan\u00eda por nacimiento, al afirmar que la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466879,"url":"https:\/\/noticiasya.com\/colorado\/2025\/09\/26\/trump-corte-suprema-poner-fin-ciudadania-por-nacimiento-trax\/","url_meta":{"origin":1472694,"position":1},"title":"Trump pide a la Corte Suprema que decida si puede poner fin a la ciudadan\u00eda por nacimiento","author":"","date":"septiembre 26, 2025","format":false,"excerpt":"El Gobierno de Trump pidi\u00f3 este viernes a la Corte Suprema de Estados Unidos que revise la constitucionalidad del decreto del presidente Donald Trump que busca poner fin a la ciudadan\u00eda por derecho de nacimiento, llevando el tema nuevamente ante los jueces por segunda vez este a\u00f1o.A pesar de m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465190,"url":"https:\/\/noticiasya.com\/colorado\/2025\/08\/06\/gobierno-trump-presionara-fallo-ciudadania-por-nacimiento-trax\/","url_meta":{"origin":1472694,"position":2},"title":"Gobierno de Trump presionar\u00e1 a la Corte Suprema para que se pronuncie r\u00e1pido sobre la ciudadan\u00eda por nacimiento","author":"","date":"agosto 6, 2025","format":false,"excerpt":"El Gobierno de Trump planea solicitar r\u00e1pidamente a la Corte Suprema que revise la constitucionalidad del decreto del presidente Donald Trump que busca poner fin a la ciudadan\u00eda por nacimiento.Abogados del Departamento de Justicia informaron a un juez federal en Seattle sobre estos planes el mi\u00e9rcoles, como parte de una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463979,"url":"https:\/\/noticiasya.com\/colorado\/2025\/06\/26\/corte-suprema-opinion-ciudadania-por-nacimiento-trax\/","url_meta":{"origin":1472694,"position":3},"title":"Se espera que la Corte Suprema de EE.UU. emita su opini\u00f3n sobre la ciudadan\u00eda por nacimiento este viernes","author":"","date":"junio 26, 2025","format":false,"excerpt":"La Corte Suprema emitir\u00e1 sus decisiones finales de legislatura el viernes, incluyendo un fallo de alto perfil sobre si el presidente Donald Trump puede hacer cumplir su divisivo decreto que restringe la ciudadan\u00eda por nacimiento.Como es tradici\u00f3n, el presidente del Tribunal Supremo, John Roberts, anunci\u00f3 el \u00faltimo d\u00eda desde el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462334,"url":"https:\/\/noticiasya.com\/colorado\/2025\/05\/14\/ciudadania-por-nacimiento-corte-suprema-orix\/","url_meta":{"origin":1472694,"position":4},"title":"El derecho a la ciudadan\u00eda por nacimiento llega a la Corte Suprema. \u00bfQu\u00e9 est\u00e1 en juego?","author":"","date":"mayo 14, 2025","format":false,"excerpt":"La Corte Suprema escuchar\u00e1 este jueves argumentos en tres casos que impugnan una orden ejecutiva del presidente Donald Trump que pretende limitar qui\u00e9n tiene derecho a la \u201cciudadan\u00eda por nacimiento\u201d.La voluntad de Trump de poner fin a esa pr\u00e1ctica de casi 160 a\u00f1os y que est\u00e1 garantizada por la 14\u00aa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456854,"url":"https:\/\/noticiasya.com\/colorado\/2024\/12\/22\/trump-ciudadania-derecho-nacimiento-trax\/","url_meta":{"origin":1472694,"position":5},"title":"Un vistazo por dentro a los planes de Trump para acabar con la ciudadan\u00eda por derecho de nacimiento","author":"","date":"diciembre 22, 2024","format":false,"excerpt":"El equipo del presidente electo Donald Trump est\u00e1 evaluando m\u00faltiples opciones para cumplir con su promesa de poner fin a la ciudadan\u00eda por derecho de nacimiento, seg\u00fan dos fuentes familiarizadas con las discusiones, preparando una batalla legal con la expectativa de que la Corte Suprema finalmente tenga que decidir sobre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1472694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1472694"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1472694\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1472694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1472694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1472694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}