{"id":1472696,"date":"2026-03-30T13:03:44","date_gmt":"2026-03-30T20:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/30\/cuba-petroleo-carguero-rusia-orix\/"},"modified":"2026-03-30T13:03:44","modified_gmt":"2026-03-30T20:03:44","slug":"cuba-petroleo-carguero-rusia-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2026\/03\/30\/cuba-petroleo-carguero-rusia-orix\/","title":{"rendered":"Cu\u00e1ntos d\u00edas le puede durar a Cuba el petr\u00f3leo que llegar\u00e1 en un carguero de Rusia y por qu\u00e9 el alivio no ser\u00e1 inmediato"},"content":{"rendered":"<p>La dura crisis energ\u00e9tica que atraviesa Cuba, agravada en los \u00faltimos tres meses por las pol\u00edticas del Gobierno de Estados Unidos, tendr\u00e1 un alivio con las 100.000 toneladas (unos 730.000 barriles) de petr\u00f3leo que <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/30\/latinoamerica\/petrolero-ruso-llega-cuba-efe\">lleg\u00f3 esta semana a aguas cubanas desde Rusia<\/a>, pero se trata de un parche breve y cuyo efecto reci\u00e9n impactar\u00eda en casi un mes.<\/p>\n<p>\u201cB\u00e1sicamente, representa muy poco. Hay personas que le dan mucha importancia, pero tiene una vida econ\u00f3mica y humanitaria muy limitada\u201d, dijo a CNN el investigador cubanoestadounidense Jorge Pi\u00f1\u00f3n, director para Am\u00e9rica Latina del Programa de Energ\u00eda de la Universidad de Texas.<\/p>\n<p>El experto explic\u00f3 que no es crudo lo que m\u00e1s necesita Cuba, sino di\u00e9sel, por lo que la carga que arribar\u00e1 pr\u00f3ximamente al puerto de Matanzas debe ser trasladada en peque\u00f1os tanqueros a una refiner\u00eda en La Habana para su tratamiento, lo que lleva de cinco a siete d\u00edas. \u201cEs una antigua refiner\u00eda de Exxon, construida en los a\u00f1os \u201950, es ineficiente. Eso tomar\u00e1 20 d\u00edas\u201d, calcul\u00f3.<\/p>\n<p>Por su parte, el investigador mexicano Rams\u00e9s Pech, analista del sector energ\u00e9tico, apunt\u00f3 que el crudo tiene que pasar por una evaluaci\u00f3n antes de ser procesado. \u201cDebe hacerse un reacondicionamiento. No es \u2018llegar y meterlo\u2019. Es un an\u00e1lisis de laboratorio, ver qu\u00e9 calidad tiene, comprobar que no tenga agua\u201d, repas\u00f3 en di\u00e1logo con CNN.<\/p>\n<p>Una vez refinado, el combustible pasar\u00e1 a su distribuci\u00f3n, seg\u00fan el orden de prioridades que establezca el Gobierno.<\/p>\n<p>Cuba, que cuenta con escasas reservas propias y <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/18\/latinoamerica\/cuba-comida-combustible-presion-eeuu-orix\">sufre apagones diarios<\/a> desde hace varios meses, necesita unos 100.000 barriles diarios, de los cuales solo cubre cerca del 40 % con la producci\u00f3n nacional y otra peque\u00f1a porci\u00f3n del suministro energ\u00e9tico proviene de paneles solares. Las 100.000 toneladas del buque petrolero Anatoli Kolodkin, que se espera que llegue al puerto de Matanzas entre hoy y ma\u00f1ana, representan unos 740.000 barriles.<\/p>\n<p>\u201cTodo ese di\u00e9sel va a durar unos 10 a 15 d\u00edas y ya, se termin\u00f3 el libro\u201d, consider\u00f3 Pi\u00f1\u00f3n.<\/p>\n<p>A su vez, Pech afirm\u00f3 que el di\u00e9sel refinado podr\u00eda durar \u201cunos 15 a 30 d\u00edas\u201d, y Cuba \u201cluego volver\u00eda a lo mismo\u201d, una <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/14\/latinoamerica\/cuba-petroleo-energia-afectaciones-presion-eeuu-orix\">escasez energ\u00e9tica que tiene paralizada a la econom\u00eda<\/a>.<\/p>\n<p>El Gobierno del presidente Miguel D\u00edaz-Canel no se ha pronunciado sobre los planes para el crudo ruso o un posible racionamiento para intentar que dure m\u00e1s semanas.<\/p>\n<p>Entre los sectores m\u00e1s urgidos est\u00e1n los hospitales, con generadores el\u00e9ctricos que necesitan di\u00e9sel para su funcionamiento. El pa\u00eds tambi\u00e9n necesita del transporte para la log\u00edstica m\u00e1s urgente, mientras que industrias y hogares podr\u00edan verse rezagados.<\/p>\n<p>\u201cMi prioridad ser\u00edan los hospitales. El transporte selectivo tambi\u00e9n es urgente\u201d, dijo Pil\u00f3n. \u201cEn el puerto de Mariel tenemos miles de toneladas de env\u00edos de cubanoamericanos. En Santiago de Cuba tienes a la Iglesia Cat\u00f3lica que tiene cientos de toneladas de ayuda humanitaria que tiene que distribuir fuera de la ciudad y no lo ha podido hacer\u201d, coment\u00f3.<\/p>\n<p>El analista tambi\u00e9n mencion\u00f3 la posibilidad de que el castrismo, que se vio sorprendido por la captura del presidente de Venezuela, Nicol\u00e1s Maduro, y la consiguiente interrupci\u00f3n de los env\u00edos de Caracas, guarde una reserva estrat\u00e9gica en medio de la tensi\u00f3n con Estados Unidos. \u201cNo debemos ser ingenuos. Necesitan reservas en caso de un conflicto\u201d, apunt\u00f3.<\/p>\n<p>\u201cNo nos molesta que alguien reciba una carga de petr\u00f3leo, porque tienen que sobrevivir\u201d, dijo a periodistas el domingo el presidente de EE.UU., Donald Trump, quien a fines de enero hab\u00eda <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/29\/eeuu\/trump-amenaza-aranceles-paises-petroleo-cuba-orix\">amenazado con aranceles<\/a> a quien proporcione combustible a Cuba. \u201cSi un pa\u00eds quiere enviar algo de petr\u00f3leo a Cuba en este momento, no tengo problema. Prefiero dejarlo pasar, ya sea Rusia u otro pa\u00eds, porque la gente necesita calefacci\u00f3n, refrigeraci\u00f3n y todas las dem\u00e1s cosas que se necesitan\u201d, agreg\u00f3 el presidente.<\/p>\n<p>Para Pi\u00f1\u00f3n, <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/30\/latinoamerica\/rusia-seguira-enviando-petroleo-cuba-orix\">adem\u00e1s de Rusia<\/a>, M\u00e9xico es el \u00fanico pa\u00eds que podr\u00eda aprovechar esa ventana para ayudar a Cuba. \u201cPol\u00edticamente, estar\u00eda dispuesto a hacerlo\u201d, afirm\u00f3.<\/p>\n<p>De hecho, la presidenta Claudia Sheinbaum declar\u00f3 este lunes que su gobierno trabaja con autoridades de la isla para reactivar el suministro. El \u00faltimo env\u00edo de di\u00e9sel fue en enero, d\u00edas antes de la advertencia comercial de Trump.<\/p>\n<p>\u201cLo que siempre hemos dicho es que M\u00e9xico tiene todo el derecho de enviar combustible, ya sea por razones humanitarias o comerciales, pero que no queremos afectar a M\u00e9xico\u201d, dijo la mandataria.<\/p>\n<p>En ese sentido, Pi\u00f1\u00f3n dijo que el Gobierno de M\u00e9xico toma recaudos para evitar tensar la relaci\u00f3n con Washington. \u201cEl problema es que en junio comienzan las negociaciones del tratado de libre comercio. M\u00e9xico no quiere entrar en esa mesa con el dolor de cabeza de que Trump est\u00e9 molesto, aunque dijo que lo pod\u00edan hacer. La pol\u00edtica cambia de opini\u00f3n muy r\u00e1pido. La prioridad es concentrarse en negociar\u201d, se\u00f1al\u00f3.<\/p>\n<p>Por su parte, Pech ve poco probable que M\u00e9xico le haga llegar petr\u00f3leo, en un momento de precios altos del crudo y de compromisos ya asumidos. \u201cEn este momento, Pemex no se va a poner a regalar, descompensar\u00edas tus exportaciones\u201d, afirm\u00f3. Pero si vio factible que M\u00e9xico env\u00ede di\u00e9sel, un producto que justamente es m\u00e1s \u00fatil para Cuba, para no tener que pasar por el proceso de refinado.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La dura crisis energ\u00e9tica que atraviesa Cuba, agravada en los \u00faltimos tres meses por las pol\u00edticas del Gobierno de Estados Unidos, tendr\u00e1 un alivio con las 100.000 toneladas (unos 730.000 barriles) de petr\u00f3leo que lleg\u00f3 esta semana a aguas cubanas desde Rusia, pero se trata de un parche breve y cuyo efecto reci\u00e9n impactar\u00eda en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472696","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cu\u00e1ntos d\u00edas le puede durar a Cuba el petr\u00f3leo que llegar\u00e1 en un carguero de Rusia y por qu\u00e9 el alivio no ser\u00e1 inmediato - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/30\/cuba-petroleo-carguero-rusia-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cu\u00e1ntos d\u00edas le puede durar a Cuba el petr\u00f3leo que llegar\u00e1 en un carguero de Rusia y por qu\u00e9 el alivio no ser\u00e1 inmediato - Noticias\" \/>\n<meta property=\"og:description\" content=\"La dura crisis energ\u00e9tica que atraviesa Cuba, agravada en los \u00faltimos tres meses por las pol\u00edticas del Gobierno de Estados Unidos, tendr\u00e1 un alivio con las 100.000 toneladas (unos 730.000 barriles) de petr\u00f3leo que lleg\u00f3 esta semana a aguas cubanas desde Rusia, pero se trata de un parche breve y cuyo efecto reci\u00e9n impactar\u00eda en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/30\/cuba-petroleo-carguero-rusia-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-30T20:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/30\/cuba-petroleo-carguero-rusia-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/30\/cuba-petroleo-carguero-rusia-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Cu\u00e1ntos d\u00edas le puede durar a Cuba el petr\u00f3leo que llegar\u00e1 en un carguero de Rusia y por qu\u00e9 el alivio no ser\u00e1 inmediato\",\"datePublished\":\"2026-03-30T20:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/30\/cuba-petroleo-carguero-rusia-orix\/\"},\"wordCount\":979,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/30\/cuba-petroleo-carguero-rusia-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/30\/cuba-petroleo-carguero-rusia-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/30\/cuba-petroleo-carguero-rusia-orix\/\",\"name\":\"Cu\u00e1ntos d\u00edas le puede durar a Cuba el petr\u00f3leo que llegar\u00e1 en un carguero de Rusia y por qu\u00e9 el alivio no ser\u00e1 inmediato - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-30T20:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/30\/cuba-petroleo-carguero-rusia-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/30\/cuba-petroleo-carguero-rusia-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/30\/cuba-petroleo-carguero-rusia-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cu\u00e1ntos d\u00edas le puede durar a Cuba el petr\u00f3leo que llegar\u00e1 en un carguero de Rusia y por qu\u00e9 el alivio no ser\u00e1 inmediato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cu\u00e1ntos d\u00edas le puede durar a Cuba el petr\u00f3leo que llegar\u00e1 en un carguero de Rusia y por qu\u00e9 el alivio no ser\u00e1 inmediato - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/30\/cuba-petroleo-carguero-rusia-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Cu\u00e1ntos d\u00edas le puede durar a Cuba el petr\u00f3leo que llegar\u00e1 en un carguero de Rusia y por qu\u00e9 el alivio no ser\u00e1 inmediato - Noticias","og_description":"La dura crisis energ\u00e9tica que atraviesa Cuba, agravada en los \u00faltimos tres meses por las pol\u00edticas del Gobierno de Estados Unidos, tendr\u00e1 un alivio con las 100.000 toneladas (unos 730.000 barriles) de petr\u00f3leo que lleg\u00f3 esta semana a aguas cubanas desde Rusia, pero se trata de un parche breve y cuyo efecto reci\u00e9n impactar\u00eda en [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/30\/cuba-petroleo-carguero-rusia-orix\/","og_site_name":"Noticias","article_published_time":"2026-03-30T20:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/30\/cuba-petroleo-carguero-rusia-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/30\/cuba-petroleo-carguero-rusia-orix\/"},"author":{"name":"","@id":""},"headline":"Cu\u00e1ntos d\u00edas le puede durar a Cuba el petr\u00f3leo que llegar\u00e1 en un carguero de Rusia y por qu\u00e9 el alivio no ser\u00e1 inmediato","datePublished":"2026-03-30T20:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/30\/cuba-petroleo-carguero-rusia-orix\/"},"wordCount":979,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/30\/cuba-petroleo-carguero-rusia-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/30\/cuba-petroleo-carguero-rusia-orix\/","url":"https:\/\/noticiasya.com\/2026\/03\/30\/cuba-petroleo-carguero-rusia-orix\/","name":"Cu\u00e1ntos d\u00edas le puede durar a Cuba el petr\u00f3leo que llegar\u00e1 en un carguero de Rusia y por qu\u00e9 el alivio no ser\u00e1 inmediato - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-30T20:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/30\/cuba-petroleo-carguero-rusia-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/30\/cuba-petroleo-carguero-rusia-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/30\/cuba-petroleo-carguero-rusia-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Cu\u00e1ntos d\u00edas le puede durar a Cuba el petr\u00f3leo que llegar\u00e1 en un carguero de Rusia y por qu\u00e9 el alivio no ser\u00e1 inmediato"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2026\/03\/30\/cuba-petroleo-carguero-rusia-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Cu\u00e1ntos d\u00edas le puede durar a Cuba el petr\u00f3leo que llegar\u00e1 en un carguero de Rusia y por qu\u00e9 el alivio no ser\u00e1 inmediato","url":"http:\/\/noticiasya.com\/colorado\/2026\/03\/30\/cuba-petroleo-carguero-rusia-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2026\/03\/30\/cuba-petroleo-carguero-rusia-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-30T20:03:44Z","datePublished":"2026-03-30T20:03:44Z","dateModified":"2026-03-30T20:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Cu\\u00e1ntos d\\u00edas le puede durar a Cuba el petr\\u00f3leo que llegar\\u00e1 en un carguero de Rusia y por qu\\u00e9 el alivio no ser\\u00e1 inmediato\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/03\\\/30\\\/cuba-petroleo-carguero-rusia-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/03\\\/30\\\/cuba-petroleo-carguero-rusia-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-30T20:03:44Z\",\"datePublished\":\"2026-03-30T20:03:44Z\",\"dateModified\":\"2026-03-30T20:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1471021,"url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/09\/rusia-situacion-cuba-critica-estrangulamiento-eeuu-trax\/","url_meta":{"origin":1472696,"position":0},"title":"Rusia dice que la situaci\u00f3n en Cuba es cr\u00edtica debido al &#171;estrangulamiento&#187; de los env\u00edos de petr\u00f3leo por parte de EE.UU.","author":"","date":"febrero 9, 2026","format":false,"excerpt":"El Gobierno de Rusia dijo este lunes que \u201cla situaci\u00f3n en Cuba es realmente cr\u00edtica\u201d, mientras Estados Unidos contin\u00faa interrumpiendo las entregas de petr\u00f3leo al pa\u00eds.\u201cEstamos en contacto intensivo con nuestros amigos cubanos a trav\u00e9s de canales diplom\u00e1ticos y de otro tipo\u201d, dijo el portavoz del Kremlin, Dmitry Peskov. Cuba\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472723,"url":"https:\/\/noticiasya.com\/colorado\/2026\/03\/31\/cuba-buque-ruso-anatoly-kolodkin-petroleo-orix\/","url_meta":{"origin":1472696,"position":1},"title":"El buque ruso Anatoly Kolodkin lleg\u00f3 al puerto de Matanzas en Cuba con 100.000 toneladas de petr\u00f3leo","author":"","date":"marzo 31, 2026","format":false,"excerpt":"El buque de bandera rusa Anatoly Kolodkin lleg\u00f3 este martes por la ma\u00f1ana al puerto de Matanzas en Cuba, seg\u00fan datos de Marine Traffic, con una carga de crudo que marcar\u00e1 un alivio temporal a la crisis energ\u00e9tica que atraviesa la isla, que se agrav\u00f3 en los \u00faltimos meses por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471160,"url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/12\/rusia-contacto-cuba-para-discutir-asistencia-orix\/","url_meta":{"origin":1472696,"position":2},"title":"Rusia confirma que est\u00e1 en contacto con Cuba para &#171;discutir opciones de asistencia&#187;","author":"","date":"febrero 12, 2026","format":false,"excerpt":"El portavoz del Kremlin, Dmitry Peskov, dijo este jueves que Rusia \u201canaliza opciones\u201d para brindar asistencia a Cuba en medio de la presi\u00f3n de Estados Unidos por la interrupci\u00f3n del suministro de petr\u00f3leo a la isla, y que \u201cno desea ninguna escalada\u201d con el Gobierno del presidente Donald Trump.\u201cEstamos en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472684,"url":"https:\/\/noticiasya.com\/colorado\/2026\/03\/30\/rusia-seguira-enviando-petroleo-cuba-orix\/","url_meta":{"origin":1472696,"position":3},"title":"Rusia dice que seguir\u00e1 suministrando ayuda a Cuba tras la llegada de un petrolero a la isla","author":"","date":"marzo 30, 2026","format":false,"excerpt":"Rusia asegur\u00f3 este lunes que seguir\u00e1 suministrando ayuda a Cuba tras la llegada a la isla del petrolero Anatoli Kolodkin con 100.000 toneladas de crudo (m\u00e1s de 700.000 barriles). \u201cPor supuesto, Rusia considera su deber no mantenerse al margen y ofrecer la ayuda necesaria a nuestros amigos cubanos\u201d, dijo Dmitri\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472818,"url":"https:\/\/noticiasya.com\/colorado\/2026\/04\/02\/rusia-prepara-envio-segundo-buque-petroleo-cuba-orix\/","url_meta":{"origin":1472696,"position":4},"title":"Rusia prepara el env\u00edo a Cuba de un segundo buque petrolero en medio de la crisis energ\u00e9tica en la isla","author":"","date":"abril 2, 2026","format":false,"excerpt":"El Gobierno de Rusia est\u00e1 preparando el env\u00edo a Cuba de un segundo buque con petr\u00f3leo que pueda ayudar a la isla a enfrentar la crisis energ\u00e9tica por la que atraviesa desde principios de este a\u00f1o, dijo este jueves el ministro de Energ\u00eda ruso, Sergey Tsivilyov, seg\u00fan declaraciones recogidas por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471198,"url":"https:\/\/noticiasya.com\/colorado\/2026\/02\/13\/cuba-asistencia-rusia-apoyo-paises-orix\/","url_meta":{"origin":1472696,"position":5},"title":"Rusia confirma que proveer\u00e1 &#171;asistencia material&#187; a Cuba: qu\u00e9 otros pa\u00edses ya lo hicieron y con qu\u00e9","author":"","date":"febrero 13, 2026","format":false,"excerpt":"Rusia prometi\u00f3 brindar \u201casistencia\u201d a Cuba en una declaraci\u00f3n realizada por el Ministerio de Exteriores este viernes, sin especificar en qu\u00e9 consistir\u00e1 exactamente.\u201cSin duda, estamos en solidaridad con Cuba y la ayudaremos, incluida la asistencia material. Esto ya se est\u00e1 haciendo\u201d, dijo el viceministro de Exteriores, Sergey Ryabkov, a la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1472696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1472696"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1472696\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1472696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1472696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1472696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}