{"id":1472706,"date":"2026-03-30T18:03:43","date_gmt":"2026-03-31T01:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/30\/saudies-via-petroleo-huties-cierre-trax\/"},"modified":"2026-03-30T18:03:43","modified_gmt":"2026-03-31T01:03:43","slug":"saudies-via-petroleo-huties-cierre-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2026\/03\/30\/saudies-via-petroleo-huties-cierre-trax\/","title":{"rendered":"Los saud\u00edes encontraron una v\u00eda de salida para parte del petr\u00f3leo del mundo. Los hut\u00edes podr\u00edan cerrarla de golpe"},"content":{"rendered":"<p>El mundo, hambriento de petr\u00f3leo, obtuvo un modesto respiro a principios de este mes cuando Arabia Saudita comenz\u00f3 a desviar millones de barriles de crudo \u2014normalmente destinados a buques que transitan por el bloqueado estrecho de Ormuz\u2014 hacia su puerto del mar Rojo de Yanbu.<\/p>\n<p>Pero durante el fin de semana, <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/29\/mundo\/guerra-iran-frente-yemen-huties-trax\">militantes hut\u00edes respaldados por Ir\u00e1n<\/a> entraron en la guerra en una escalada que amenaza con cortar incluso esa v\u00eda.<\/p>\n<p>Cualquier cosa que ponga en peligro los flujos de petr\u00f3leo saud\u00ed que salen por el mar Rojo ejercer\u00e1 m\u00e1s presi\u00f3n al alza sobre los precios mundiales del petr\u00f3leo, dijo Richard Bronze, cofundador y jefe de geopol\u00edtica de la firma de investigaci\u00f3n Energy Aspects.<\/p>\n<p>Hasta 4,6 millones de barriles por d\u00eda se cargaron en buques en Yanbu durante las \u00faltimas dos semanas \u2014m\u00e1s de tres veces el promedio de 2025\u2014, seg\u00fan la firma de datos de transporte mar\u00edtimo Vortexa.<\/p>\n<p>Eso es una peque\u00f1a compensaci\u00f3n por los 15 millones de barriles que el mundo deja de recibir cada d\u00eda que el estrecho de Ormuz permanece cerrado. Pero esos 4,6 millones de barriles bastan para sacudir la oferta y, en un mercado mundial del petr\u00f3leo extremadamente sensible, estrangular otra ruta comercial cr\u00edtica elevar\u00eda a\u00fan m\u00e1s los precios del petr\u00f3leo y desencadenar\u00eda o <a href=\"https:\/\/www.cnn.com\/2026\/03\/25\/asia\/asia-hormuz-energy-austerity-fuel-intl-hnk\">agravar\u00eda la escasez local de combustible<\/a>.<\/p>\n<p>A finales de 2023, <a href=\"https:\/\/www.cnn.com\/2024\/02\/08\/business\/red-sea-crisis-global-trade-explained\">militantes hut\u00edes<\/a> ubicados en Yemen comenzaron a atacar buques comerciales que pasaban por el estrecho de Bab el-Mandeb \u2014en el extremo sur del mar Rojo y que significa \u201cPuerta de las L\u00e1grimas\u201d en \u00e1rabe\u2014 en represalia por la guerra de Israel en Gaza. Los ataques llevaron a las navieras a usar una ruta m\u00e1s larga, a\u00f1adiendo semanas a los viajes y <a href=\"https:\/\/www.cnn.com\/2024\/02\/08\/business\/red-sea-crisis-global-trade-explained\">oblig\u00e1ndolas a gastar m\u00e1s<\/a> en combustible, seguros y salarios de los marineros.<\/p>\n<p>Durante los primeros 28 d\u00edas de marzo, la cantidad de crudo que transit\u00f3 por el estrecho de Bab el-Mandeb aument\u00f3 un 21 % en comparaci\u00f3n con febrero, seg\u00fan Vortexa. Esos env\u00edos son ahora objetivos potenciales de renovados ataques hut\u00edes.<\/p>\n<p>El precio del Brent, el referente mundial del petr\u00f3leo, se ha disparado alrededor de un 50 % desde que comenz\u00f3 la guerra con Ir\u00e1n el 28 de febrero, para cotizar en torno a los US$ 110 por barril el lunes.<\/p>\n<p>Si el estrecho de Bab el-Mandeb tambi\u00e9n se vuelve demasiado peligroso para que los petroleros lo crucen, es \u201cmuy probable\u201d que el Brent se dispare por encima de los US$ 150 por barril en los pr\u00f3ximos meses, lo que ser\u00eda antes de lo que se pronostica actualmente, seg\u00fan Artem Abramov, jefe de investigaci\u00f3n de petr\u00f3leo y gas natural de Rystad Energy, una consultora.<\/p>\n<p>El cierre de la v\u00eda mar\u00edtima \u201csimplemente romper\u00e1 el sistema mucho m\u00e1s r\u00e1pido\u201d, dijo a CNN el lunes. \u201cIncluso la mera amenaza de un cierre del mar Rojo probablemente impondr\u00e1 una presi\u00f3n alcista continua sobre los seguros, el flete y, en \u00faltima instancia, la mayor\u00eda de los referentes de precios del petr\u00f3leo en los pr\u00f3ximos d\u00edas\u201d.<\/p>\n<p>Los hut\u00edes entraron oficialmente en la guerra el s\u00e1bado, cuando dispararon dos misiles hacia Israel. El d\u00eda anterior, Mohammed Mansour, viceministro de informaci\u00f3n del Gobierno hut\u00ed, dijo a CNN que cerrar el estrecho de Bab el-Mandeb \u201ces una opci\u00f3n viable, y las consecuencias ser\u00e1n asumidas por los agresores estadounidenses e israel\u00edes\u201d.<\/p>\n<p>Los hut\u00edes cuentan con una amplia gama de armas, incluidos drones y misiles antibuque, lo que supone un enorme riesgo para los barcos que atraviesan el estrecho.<\/p>\n<p>Para evitar la v\u00eda mar\u00edtima, los petroleros que salgan de Yanbu \u2014con la gran mayor\u00eda con destino a Asia\u2014 tendr\u00edan que tomar una ruta m\u00e1s indirecta y much\u00edsimo m\u00e1s larga, viajando hacia el norte a trav\u00e9s del Canal de Suez en el extremo norte del mar Rojo, hacia el oeste por el mar Mediterr\u00e1neo, descendiendo por la costa occidental de \u00c1frica y cruzando el oc\u00e9ano \u00cdndico.<\/p>\n<p>\u201cSi los hut\u00edes empiezan a amenazar a los buques, entonces, como m\u00ednimo, esto a\u00f1adir\u00e1 varias semanas a los tiempos de viaje hacia Asia\u201d, dijo Bronze, de Energy Aspects, a CNN. \u201cEso profundizar\u00eda el apret\u00f3n de la oferta de crudo en Asia\u201d.<\/p>\n<p>Asia est\u00e1 soportando la peor parte del shock mundial de oferta de petr\u00f3leo. La regi\u00f3n depende de Medio Oriente para aproximadamente el 60 % de su petr\u00f3leo, y los gobiernos han tomado medidas para conservar energ\u00eda durante la crisis.<\/p>\n<p><a href=\"https:\/\/www.cnn.com\/2026\/03\/24\/middleeast\/us-israel-iran-middle-east-war-day-26-what-we-know-intl-hnk\">Filipinas<\/a>, por ejemplo, ha declarado un estado de emergencia energ\u00e9tica y acort\u00f3 la semana laboral para algunos trabajadores del Gobierno a cuatro d\u00edas, mientras que Corea del Sur ha aconsejado a los ciudadanos tomar duchas m\u00e1s cortas. Hasta ahora este mes, todo el petr\u00f3leo que sale de Yanbu y pasa por el estrecho de Bab el-Mandeb ten\u00eda como destino Asia, seg\u00fan Muyu Xu, analista s\u00e9nior de crudo en Kpler, una empresa de datos comerciales y an\u00e1lisis.<\/p>\n<p>Si alg\u00fan ataque hut\u00ed llegara a bloquear efectivamente el estrecho, Xu dijo a CNN, los saud\u00edes o bien empezar\u00edan a priorizar los env\u00edos de crudo hacia la cercana Europa \u2014 privando as\u00ed a Asia \u2014 o bien desviar\u00edan los petroleros hacia Asia a trav\u00e9s del canal de Suez.<\/p>\n<p>Xu dijo que muchas partes de Asia comenzar\u00e1n a ver escasez de crudo en abril a medida que reduzcan sus existencias actuales. \u201cSi no pueden obtener el crudo saud\u00ed a tiempo, eso har\u00e1 que su estrechez de suministro a corto plazo sea a\u00fan peor\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Los altos precios del petr\u00f3leo son \u201cun problema, pero lo m\u00e1s importante es que simplemente no pueden conseguir suficiente petr\u00f3leo\u201d, afirm\u00f3.<\/p>\n<p><em>Con informaci\u00f3n de Tim Lister en Albi, Francia, y Nadeen Ebrahim en Abu Dhabi.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mundo, hambriento de petr\u00f3leo, obtuvo un modesto respiro a principios de este mes cuando Arabia Saudita comenz\u00f3 a desviar millones de barriles de crudo \u2014normalmente destinados a buques que transitan por el bloqueado estrecho de Ormuz\u2014 hacia su puerto del mar Rojo de Yanbu. Pero durante el fin de semana, militantes hut\u00edes respaldados por [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472706","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los saud\u00edes encontraron una v\u00eda de salida para parte del petr\u00f3leo del mundo. Los hut\u00edes podr\u00edan cerrarla de golpe - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/30\/saudies-via-petroleo-huties-cierre-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los saud\u00edes encontraron una v\u00eda de salida para parte del petr\u00f3leo del mundo. Los hut\u00edes podr\u00edan cerrarla de golpe - Noticias\" \/>\n<meta property=\"og:description\" content=\"El mundo, hambriento de petr\u00f3leo, obtuvo un modesto respiro a principios de este mes cuando Arabia Saudita comenz\u00f3 a desviar millones de barriles de crudo \u2014normalmente destinados a buques que transitan por el bloqueado estrecho de Ormuz\u2014 hacia su puerto del mar Rojo de Yanbu. Pero durante el fin de semana, militantes hut\u00edes respaldados por [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/30\/saudies-via-petroleo-huties-cierre-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-31T01:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/30\/saudies-via-petroleo-huties-cierre-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/30\/saudies-via-petroleo-huties-cierre-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Los saud\u00edes encontraron una v\u00eda de salida para parte del petr\u00f3leo del mundo. Los hut\u00edes podr\u00edan cerrarla de golpe\",\"datePublished\":\"2026-03-31T01:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/30\/saudies-via-petroleo-huties-cierre-trax\/\"},\"wordCount\":1042,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/30\/saudies-via-petroleo-huties-cierre-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/30\/saudies-via-petroleo-huties-cierre-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/30\/saudies-via-petroleo-huties-cierre-trax\/\",\"name\":\"Los saud\u00edes encontraron una v\u00eda de salida para parte del petr\u00f3leo del mundo. Los hut\u00edes podr\u00edan cerrarla de golpe - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-31T01:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/30\/saudies-via-petroleo-huties-cierre-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/30\/saudies-via-petroleo-huties-cierre-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/30\/saudies-via-petroleo-huties-cierre-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los saud\u00edes encontraron una v\u00eda de salida para parte del petr\u00f3leo del mundo. Los hut\u00edes podr\u00edan cerrarla de golpe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los saud\u00edes encontraron una v\u00eda de salida para parte del petr\u00f3leo del mundo. Los hut\u00edes podr\u00edan cerrarla de golpe - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/30\/saudies-via-petroleo-huties-cierre-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Los saud\u00edes encontraron una v\u00eda de salida para parte del petr\u00f3leo del mundo. Los hut\u00edes podr\u00edan cerrarla de golpe - Noticias","og_description":"El mundo, hambriento de petr\u00f3leo, obtuvo un modesto respiro a principios de este mes cuando Arabia Saudita comenz\u00f3 a desviar millones de barriles de crudo \u2014normalmente destinados a buques que transitan por el bloqueado estrecho de Ormuz\u2014 hacia su puerto del mar Rojo de Yanbu. Pero durante el fin de semana, militantes hut\u00edes respaldados por [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/30\/saudies-via-petroleo-huties-cierre-trax\/","og_site_name":"Noticias","article_published_time":"2026-03-31T01:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/30\/saudies-via-petroleo-huties-cierre-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/30\/saudies-via-petroleo-huties-cierre-trax\/"},"author":{"name":"","@id":""},"headline":"Los saud\u00edes encontraron una v\u00eda de salida para parte del petr\u00f3leo del mundo. Los hut\u00edes podr\u00edan cerrarla de golpe","datePublished":"2026-03-31T01:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/30\/saudies-via-petroleo-huties-cierre-trax\/"},"wordCount":1042,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/30\/saudies-via-petroleo-huties-cierre-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/30\/saudies-via-petroleo-huties-cierre-trax\/","url":"https:\/\/noticiasya.com\/2026\/03\/30\/saudies-via-petroleo-huties-cierre-trax\/","name":"Los saud\u00edes encontraron una v\u00eda de salida para parte del petr\u00f3leo del mundo. Los hut\u00edes podr\u00edan cerrarla de golpe - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-31T01:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/30\/saudies-via-petroleo-huties-cierre-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/30\/saudies-via-petroleo-huties-cierre-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/30\/saudies-via-petroleo-huties-cierre-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Los saud\u00edes encontraron una v\u00eda de salida para parte del petr\u00f3leo del mundo. Los hut\u00edes podr\u00edan cerrarla de golpe"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2026\/03\/30\/saudies-via-petroleo-huties-cierre-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Los saud\u00edes encontraron una v\u00eda de salida para parte del petr\u00f3leo del mundo. Los hut\u00edes podr\u00edan cerrarla de golpe","url":"http:\/\/noticiasya.com\/colorado\/2026\/03\/30\/saudies-via-petroleo-huties-cierre-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2026\/03\/30\/saudies-via-petroleo-huties-cierre-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-31T01:03:43Z","datePublished":"2026-03-31T01:03:43Z","dateModified":"2026-03-31T01:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Los saud\\u00edes encontraron una v\\u00eda de salida para parte del petr\\u00f3leo del mundo. Los hut\\u00edes podr\\u00edan cerrarla de golpe\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/03\\\/30\\\/saudies-via-petroleo-huties-cierre-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/03\\\/30\\\/saudies-via-petroleo-huties-cierre-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-31T01:03:43Z\",\"datePublished\":\"2026-03-31T01:03:43Z\",\"dateModified\":\"2026-03-31T01:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472650,"url":"https:\/\/noticiasya.com\/colorado\/2026\/03\/28\/salvavidas-mar-rojo-petroleo-riesgo-trax\/","url_meta":{"origin":1472706,"position":0},"title":"&#171;No hay salida&#187;: un salvavidas para el petr\u00f3leo mundial en el mar Rojo ahora tambi\u00e9n est\u00e1 en riesgo","author":"","date":"marzo 28, 2026","format":false,"excerpt":"Los ataques contra buques comerciales en Medio Oriente este mes pr\u00e1cticamente han cerrado el vital estrecho de Ormuz a los petroleros, trastocando el mercado petrolero y obligando a los productores a buscar otras rutas para llevar su combustible a compradores de todo el mundo.Una de las pocas alternativas pasa por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442516,"url":"https:\/\/noticiasya.com\/colorado\/2023\/12\/23\/los-costos-de-envio-aumentan-tras-ataques-en-el-mar-rojo-que-obligaron-a-los-buques-a-tomar-rutas-mas-largas\/","url_meta":{"origin":1472706,"position":1},"title":"Los costos de env\u00edo aumentan tras ataques en el mar Rojo que obligaron a los buques a tomar rutas m\u00e1s largas","author":"","date":"diciembre 23, 2023","format":false,"excerpt":"Londres (CNN) -- Maersk y CMA CGN implementaron nuevos cargos para el transporte de mercanc\u00edas a lo largo de muchas de las rutas mar\u00edtimas m\u00e1s transitadas del mundo despu\u00e9s de tener que desviar sus buques lejos del mar Rojo debido a los ataques.La compa\u00f1\u00eda danesa Maersk dijo este jueves que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472664,"url":"https:\/\/noticiasya.com\/colorado\/2026\/03\/29\/guerra-iran-frente-yemen-huties-trax\/","url_meta":{"origin":1472706,"position":2},"title":"La guerra de Ir\u00e1n tiene un nuevo frente en Yemen. As\u00ed es como podr\u00eda escalar","author":"","date":"marzo 29, 2026","format":false,"excerpt":"Tras un mes de amenazas, los rebeldes hut\u00edes de Yemen, respaldados por Ir\u00e1n, entraron finalmente el s\u00e1bado en el conflicto de Medio Oriente, lanzando dos misiles contra Israel. Adem\u00e1s, en los \u00faltimos d\u00edas han advertido de que podr\u00edan cerrar una v\u00eda navegable clave en la entrada sur del mar Rojo,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472266,"url":"https:\/\/noticiasya.com\/colorado\/2026\/03\/17\/exportaciones-petroleo-irani-estrecho-ormuz-trax\/","url_meta":{"origin":1472706,"position":3},"title":"Ir\u00e1n sigue exportando petr\u00f3leo a trav\u00e9s del estrecho de Ormuz, cuando el resto del tr\u00e1fico est\u00e1 paralizado","author":"","date":"marzo 17, 2026","format":false,"excerpt":"Si Estados Unidos supuso, antes de atacar a Ir\u00e1n, que el principal productor de petr\u00f3leo se mostrar\u00eda reacio a cerrar el estrecho de Ormuz por temor a bloquear sus propias exportaciones de petr\u00f3leo, se equivoc\u00f3 en sus c\u00e1lculos.El tr\u00e1fico mar\u00edtimo a trav\u00e9s del estrecho, por donde normalmente fluye una quinta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445982,"url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/24\/estados-unidos-reino-unido-cuarta-ronda-ataques-huties-yemen-trax\/","url_meta":{"origin":1472706,"position":4},"title":"Estados Unidos y Reino Unido llevan a cabo una cuarta ronda de ataques contra al menos una docena de objetivos hut\u00edes en Yemen","author":"","date":"febrero 24, 2024","format":false,"excerpt":"(CNN) --\u00a0Estados Unidos y el Reino Unido llevaron a cabo nuevos ataques contra al menos una docena de objetivos hut\u00edes en Yemen, seg\u00fan dos funcionarios estadounidenses, lo que marca la cuarta vez que la coalici\u00f3n internacional lanza un ataque combinado contra el grupo rebelde respaldado por Ir\u00e1n.Los ataques incluyeron al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461775,"url":"https:\/\/noticiasya.com\/colorado\/2025\/04\/30\/reino-unido-lanza-ataca-huties-yemen-trax\/","url_meta":{"origin":1472706,"position":5},"title":"Reino Unido lanza ataques contra hut\u00edes en Yemen, en la primera operaci\u00f3n conjunta con EE.UU. bajo el mandato de Trump","author":"","date":"abril 30, 2025","format":false,"excerpt":"Las fuerzas armadas brit\u00e1nicas lanzaron este martes ataques a\u00e9reos contra objetivos hut\u00edes en Yemen junto con fuerzas estadounidenses, seg\u00fan inform\u00f3 el Ministerio de Defensa de Reino Unido. Esta es la primera vez que se reconoce p\u00fablicamente una operaci\u00f3n conjunta desde que la administraci\u00f3n Trump intensific\u00f3 la campa\u00f1a estadounidense contra el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1472706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1472706"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1472706\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1472706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1472706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1472706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}