{"id":1472720,"date":"2026-03-31T06:03:45","date_gmt":"2026-03-31T13:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/31\/prematuros-muerte-recien-nacidos-quimicos-plastico-trax\/"},"modified":"2026-03-31T06:03:45","modified_gmt":"2026-03-31T13:03:45","slug":"prematuros-muerte-recien-nacidos-quimicos-plastico-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2026\/03\/31\/prematuros-muerte-recien-nacidos-quimicos-plastico-trax\/","title":{"rendered":"Millones de nacimientos prematuros y miles de muertes de reci\u00e9n nacidos est\u00e1n vinculadas a un qu\u00edmico del pl\u00e1stico"},"content":{"rendered":"<p>Dos sustancias qu\u00edmicas utilizadas para hacer el pl\u00e1stico m\u00e1s flexible est\u00e1n vinculadas a casi 2 millones de nacimientos prematuros y la muerte de 74.000 reci\u00e9n nacidos en todo el mundo en 2018, seg\u00fan un nuevo estudio.<\/p>\n<p>Se considera que un beb\u00e9 es prematuro cuando nace antes de la semana 37 de gestaci\u00f3n. Aproximadamente 1 de cada 10 beb\u00e9s en Estados Unidos naci\u00f3 prematuro en 2024, seg\u00fan el <a href=\"https:\/\/www.marchofdimes.org\/peristats\/reports\/united-states\/report-card\">Informe de March of Dimes de 2025<\/a>.<\/p>\n<p>\u201cLos beb\u00e9s que sobreviven pueden presentar problemas respiratorios, dificultades para alimentarse, par\u00e1lisis cerebral, retraso en el desarrollo, problemas de visi\u00f3n y de audici\u00f3n\u201d, <a href=\"https:\/\/www.cdc.gov\/maternal-infant-health\/preterm-birth\/index.html\">seg\u00fan los Centros para el Control y la Prevenci\u00f3n de Enfermedades de EE.UU<\/a>.<\/p>\n<p>Los dos qu\u00edmicos del estudio \u2014el ftalato de di-2-etilhexilo (DEHP) y su derivado, el ftalato de diisononilo (DiNP)\u2014 pertenecen a una familia de qu\u00edmicos sint\u00e9ticos llamados ftalatos.<\/p>\n<p>Se sabe que los ftalatos interfieren con el mecanismo de producci\u00f3n hormonal del cuerpo, conocido como sistema endocrino, y est\u00e1n relacionados con problemas de desarrollo, reproductivos, cerebrales, inmunitarios y de otra \u00edndole, <a href=\"https:\/\/www.niehs.nih.gov\/health\/topics\/agents\/endocrine\">seg\u00fan el Instituto Nacional de Ciencias de la Salud Ambiental<\/a>. Incluso peque\u00f1as alteraciones hormonales pueden causar efectos biol\u00f3gicos y de desarrollo significativos, afirma el instituto.<\/p>\n<p>\u201cEsta es una clase peligrosa de sustancias qu\u00edmicas\u201d, dijo el Dr. Leonardo Trasande, autor principal del nuevo estudio y profesor Jim G. Hendrick, M.D., de Pediatr\u00eda en la Facultad de Medicina Grossman de NYU Langone en la ciudad de Nueva York.<\/p>\n<p>\u201cEn el contexto de todos los esfuerzos que estamos realizando para aumentar la natalidad en Estados Unidos, tambi\u00e9n debemos asegurarnos de que los beb\u00e9s nazcan sanos\u201d, a\u00f1adi\u00f3 Trasande, quien tambi\u00e9n es profesor de salud p\u00fablica y director de la Divisi\u00f3n de Pediatr\u00eda Ambiental y del Centro para la Investigaci\u00f3n de Riesgos Ambientales de NYU Langone Health.<\/p>\n<p>\u201cEstos datos respaldan a\u00fan m\u00e1s los esfuerzos para negociar un tratado sobre pl\u00e1sticos que limite las sustancias qu\u00edmicas preocupantes com\u00fanmente utilizadas en estos materiales\u201d, afirm\u00f3.<\/p>\n<p>El Panel de Altos Ftalatos del Consejo Estadounidense de Qu\u00edmica inform\u00f3 a CNN por correo electr\u00f3nico que la Agencia de Protecci\u00f3n Ambiental de EE.UU. realiz\u00f3 una evaluaci\u00f3n integral de riesgos sobre el uso de DiNP bajo la Ley de Control de Sustancias T\u00f3xicas y concluy\u00f3 que no representa un \u201criesgo irrazonable para la salud humana de los consumidores, la poblaci\u00f3n en general o el medio ambiente\u201d.<\/p>\n<p>El consejo, que representa a las industrias qu\u00edmica, de pl\u00e1sticos y de cloro de EE.UU., no hizo comentarios sobre el ftalato de di-2-etilhexilo (DEHP).<\/p>\n<p>Los ftalatos suelen denominarse sustancias qu\u00edmicas \u201cen todas partes\u201d porque se utilizan en una gran cantidad de productos de consumo. Estas sustancias proporcionan flexibilidad en juguetes infantiles, materiales de arte, recipientes para almacenar alimentos, pisos de vinilo, cortinas de ducha, mangueras de jard\u00edn, dispositivos m\u00e9dicos y m\u00e1s.<\/p>\n<p>Los ftalatos tambi\u00e9n ayudan a lubricar sustancias y a transportar fragancias en productos de cuidado personal, como desodorantes, esmaltes de u\u00f1as y perfumes. Geles, aerosoles o champ\u00fas para el cabello; jabones; y lociones corporales.<\/p>\n<p>\u201cEstos son aditivos que tambi\u00e9n se utilizan en el pl\u00e1stico de envoltura tipo film que se usa com\u00fanmente en los envases de alimentos\u201d, dijo Trasande.<\/p>\n<p>Las investigaciones han relacionado los ftalatos con problemas reproductivos como malformaciones genitales y test\u00edculos no descendidos en beb\u00e9s varones, y con un menor recuento de espermatozoides y niveles m\u00e1s bajos de testosterona en hombres adultos. Los estudios tambi\u00e9n han relacionado los ftalatos con la obesidad infantil, el asma, problemas cardiovasculares y el c\u00e1ncer.<\/p>\n<p>Un estudio de 2021, del que Trasande fue coautor, encontr\u00f3 que los ftalatos podr\u00edan contribuir a entre 91.000 y 107.000 muertes prematuras al a\u00f1o entre personas de 55 a 64 a\u00f1os en Estados Unidos. Las personas con los niveles m\u00e1s altos de ftalatos ten\u00edan un mayor riesgo de muerte por cualquier causa, pero especialmente por enfermedades card\u00edacas.<\/p>\n<p>\u00bfC\u00f3mo podr\u00edan estas sustancias qu\u00edmicas contribuir a los partos prematuros y las muertes de reci\u00e9n nacidos? Aunque se necesita mucha m\u00e1s investigaci\u00f3n, los cient\u00edficos tienen algunas ideas.<\/p>\n<p>\u201cUna de las v\u00edas es la alteraci\u00f3n de la funci\u00f3n placentaria, que se ha documentado que se ve afectada por los ftalatos y otros disruptores endocrinos\u201d, afirm\u00f3 Jane Muncke, directora general y jefa cient\u00edfica del Food Packaging Forum, una fundaci\u00f3n sin \u00e1nimo de lucro con sede en Zurich, Suiza, que se centra en la divulgaci\u00f3n cient\u00edfica y la investigaci\u00f3n sobre pl\u00e1sticos y otros productos qu\u00edmicos utilizados en la industria.<\/p>\n<p>\u201cIr\u00f3nicamente, los beb\u00e9s prematuros estar\u00e1n expuestos a a\u00fan m\u00e1s pl\u00e1sticos, ya que las unidades neonatales dependen de tubos de pl\u00e1stico\u201d, a\u00f1adi\u00f3 Muncke, quien no particip\u00f3 en el \u00faltimo estudio. \u201cEsto tambi\u00e9n nos recuerda la urgencia de innovar en materiales m\u00e1s seguros, especialmente para su uso en el sector sanitario, y deber\u00eda ser una prioridad para los responsables pol\u00edticos y los empresarios\u201d.<\/p>\n<p>La placenta, que se adhiere a la pared uterina, proporciona ox\u00edgeno, nutrientes y apoyo inmunol\u00f3gico al feto en desarrollo. La insuficiencia placentaria, en la que este \u00f3rgano no se desarrolla o funciona correctamente, es una de las principales causas de parto prematuro espont\u00e1neo, seg\u00fan los expertos.<\/p>\n<p>\u201cLa inflamaci\u00f3n no favorece la adhesi\u00f3n placentaria y puede facilitar la rotura de membranas\u201d, afirm\u00f3 Trasande. \u201cLa rotura de membranas, la falta de adhesi\u00f3n a la pared uterina y la p\u00e9rdida de nutrientes esenciales para el feto pueden desencadenar contracciones uterinas. No existe una \u00fanica v\u00eda\u201d.<\/p>\n<p>El nuevo estudio, publicado este martes en la revista eClinicalMedicine, examin\u00f3 los efectos del DEHP y el DiNP en 200 pa\u00edses y territorios en 2018. Los datos se obtuvieron de grandes encuestas nacionales en Canad\u00e1, Europa y Estados Unidos, as\u00ed como de estimaciones de investigaciones anteriores en regiones del mundo que no recopilan sus propios datos.<\/p>\n<p>\u00c1frica, Oriente Medio y el sur de Asia fueron las regiones m\u00e1s afectadas por la carga de problemas de salud relacionados con el parto prematuro. Algunas de esas \u00e1reas cuentan con industrias de pl\u00e1sticos en r\u00e1pido crecimiento y altos niveles de residuos pl\u00e1sticos a nivel mundial, seg\u00fan el estudio.<\/p>\n<p>La investigaci\u00f3n no se dise\u00f1\u00f3 para establecer que el DEHP y el DiNP causen directa o exclusivamente partos prematuros, ni tampoco analiz\u00f3 otros tipos de ftalatos, explicaron los autores.<\/p>\n<p>Esto tiene sentido, afirm\u00f3 el Dr. Donghai Liang, profesor asociado de salud ambiental en la Escuela de Salud P\u00fablica Rollins de la Universidad de Emory en Atlanta.<\/p>\n<p>\u201cEn concreto, el DEHP ha sido uno de los ftalatos m\u00e1s estudiados en relaci\u00f3n con los partos prematuros, por lo que existe una base epidemiol\u00f3gica m\u00e1s s\u00f3lida para modelar su contribuci\u00f3n\u201d, explic\u00f3 Liang \u2014quien no particip\u00f3 en la investigaci\u00f3n\u2014 en un correo electr\u00f3nico. \u201cEl DiNP se incluy\u00f3 porque es un sustituto com\u00fan del DEHP y su relevancia aumenta a medida que las industrias abandonan los ftalatos m\u00e1s antiguos.<\/p>\n<p>\u201cDicho esto, no interpretar\u00eda esto como que solo estos dos ftalatos sean relevantes\u201d, a\u00f1adi\u00f3. \u201cLa preocupaci\u00f3n general radica en los ftalatos como clase, y centrarse en uno o dos a la vez podr\u00eda subestimar el riesgo global\u201d.<\/p>\n<p>Los fabricantes suelen buscar sustitutos para sustancias qu\u00edmicas que la ciencia ha relacionado con da\u00f1os a la salud y que est\u00e1n reguladas por los gobiernos federales y estatales. Por ejemplo, en 2008, Estados Unidos prohibi\u00f3 el DEHP en concentraciones superiores al 0,1 % en juguetes y art\u00edculos de puericultura, y dos estados \u2014California y Carolina del Norte\u2014 est\u00e1n trabajando para prohibir el DEHP en las bolsas de soluciones intravenosas.<\/p>\n<p>\u201cEstamos jugando a un peligroso juego del gato y el rat\u00f3n con sustancias qu\u00edmicas peligrosas\u201d, afirm\u00f3 Trasande. \u201cNos encontramos ante una situaci\u00f3n en la que surgen preocupaciones sobre una sustancia qu\u00edmica, y la industria simplemente la sustituye por un an\u00e1logo qu\u00edmico que puede tener los mismos efectos, o incluso peores\u201d.<\/p>\n<p>La buena noticia es que los ftalatos tienen una vida media corta y se eliminan del cuerpo en pocos d\u00edas, seg\u00fan los expertos. Por lo tanto, planificar cuidadosamente para evitar los pl\u00e1sticos puede tener un impacto significativo.<\/p>\n<p>\u201cPara las madres y las familias que esperan un beb\u00e9 y que buscan minimizar la exposici\u00f3n, existen algunas medidas razonables y pr\u00e1cticas que pueden ayudar\u201d, dijo Liang. \u201cEstas incluyen elegir productos de cuidado personal etiquetados como \u2018libres de ftalatos\u2019. Revise las listas de ingredientes en busca de t\u00e9rminos como ftalato de dietilo (DEP), ftalato de dibutilo (DBP) y ftalato de bencilo y butilo (BBzP)\u201d.<\/p>\n<p>Sin embargo, las etiquetas de los productos no siempre enumeran los qu\u00edmicos de forma consistente. Por ejemplo, en los productos de cuidado personal, los ftalatos a menudo se incluyen bajo t\u00e9rminos m\u00e1s generales como \u201cfragancia\u201d o \u201cperfume\u201d, dijo Liang.<\/p>\n<p>\u201cLos ftalatos son aditivos importantes para que las fragancias se mantengan\u201d, dijo Trasande. \u201cOtro consejo clave: dado que el calor favorece que los qu\u00edmicos como los ftalatos se filtren del pl\u00e1stico, evite usar el microondas o lavar los pl\u00e1sticos en el lavavajillas\u201d.<\/p>\n<p>Liang a\u00f1adi\u00f3 que es importante ventilar adecuadamente para mejorar la calidad del aire interior y aspirar con regularidad, ya que los ftalatos pueden acumularse en el polvo dom\u00e9stico.<\/p>\n<p>\u201cDicho esto, es fundamental recalcar que estas exposiciones son generalizadas y a menudo dif\u00edciles de evitar por completo\u201d, afirm\u00f3. \u201cUna protecci\u00f3n eficaz no puede depender \u00fanicamente del comportamiento individual. Las soluciones m\u00e1s efectivas se encuentran en la ra\u00edz del problema e incluyen regulaciones m\u00e1s estrictas, formulaciones de productos m\u00e1s seguras, un mejor etiquetado, una mejor gesti\u00f3n ambiental y supervisi\u00f3n regulatoria\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dos sustancias qu\u00edmicas utilizadas para hacer el pl\u00e1stico m\u00e1s flexible est\u00e1n vinculadas a casi 2 millones de nacimientos prematuros y la muerte de 74.000 reci\u00e9n nacidos en todo el mundo en 2018, seg\u00fan un nuevo estudio. Se considera que un beb\u00e9 es prematuro cuando nace antes de la semana 37 de gestaci\u00f3n. Aproximadamente 1 de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472720","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Millones de nacimientos prematuros y miles de muertes de reci\u00e9n nacidos est\u00e1n vinculadas a un qu\u00edmico del pl\u00e1stico - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/31\/prematuros-muerte-recien-nacidos-quimicos-plastico-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Millones de nacimientos prematuros y miles de muertes de reci\u00e9n nacidos est\u00e1n vinculadas a un qu\u00edmico del pl\u00e1stico - Noticias\" \/>\n<meta property=\"og:description\" content=\"Dos sustancias qu\u00edmicas utilizadas para hacer el pl\u00e1stico m\u00e1s flexible est\u00e1n vinculadas a casi 2 millones de nacimientos prematuros y la muerte de 74.000 reci\u00e9n nacidos en todo el mundo en 2018, seg\u00fan un nuevo estudio. Se considera que un beb\u00e9 es prematuro cuando nace antes de la semana 37 de gestaci\u00f3n. Aproximadamente 1 de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/31\/prematuros-muerte-recien-nacidos-quimicos-plastico-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-31T13:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/31\/prematuros-muerte-recien-nacidos-quimicos-plastico-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/31\/prematuros-muerte-recien-nacidos-quimicos-plastico-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Millones de nacimientos prematuros y miles de muertes de reci\u00e9n nacidos est\u00e1n vinculadas a un qu\u00edmico del pl\u00e1stico\",\"datePublished\":\"2026-03-31T13:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/31\/prematuros-muerte-recien-nacidos-quimicos-plastico-trax\/\"},\"wordCount\":1712,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/31\/prematuros-muerte-recien-nacidos-quimicos-plastico-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/31\/prematuros-muerte-recien-nacidos-quimicos-plastico-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/31\/prematuros-muerte-recien-nacidos-quimicos-plastico-trax\/\",\"name\":\"Millones de nacimientos prematuros y miles de muertes de reci\u00e9n nacidos est\u00e1n vinculadas a un qu\u00edmico del pl\u00e1stico - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-31T13:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/31\/prematuros-muerte-recien-nacidos-quimicos-plastico-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/31\/prematuros-muerte-recien-nacidos-quimicos-plastico-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/31\/prematuros-muerte-recien-nacidos-quimicos-plastico-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Millones de nacimientos prematuros y miles de muertes de reci\u00e9n nacidos est\u00e1n vinculadas a un qu\u00edmico del pl\u00e1stico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Millones de nacimientos prematuros y miles de muertes de reci\u00e9n nacidos est\u00e1n vinculadas a un qu\u00edmico del pl\u00e1stico - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/31\/prematuros-muerte-recien-nacidos-quimicos-plastico-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Millones de nacimientos prematuros y miles de muertes de reci\u00e9n nacidos est\u00e1n vinculadas a un qu\u00edmico del pl\u00e1stico - Noticias","og_description":"Dos sustancias qu\u00edmicas utilizadas para hacer el pl\u00e1stico m\u00e1s flexible est\u00e1n vinculadas a casi 2 millones de nacimientos prematuros y la muerte de 74.000 reci\u00e9n nacidos en todo el mundo en 2018, seg\u00fan un nuevo estudio. Se considera que un beb\u00e9 es prematuro cuando nace antes de la semana 37 de gestaci\u00f3n. Aproximadamente 1 de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/31\/prematuros-muerte-recien-nacidos-quimicos-plastico-trax\/","og_site_name":"Noticias","article_published_time":"2026-03-31T13:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/31\/prematuros-muerte-recien-nacidos-quimicos-plastico-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/31\/prematuros-muerte-recien-nacidos-quimicos-plastico-trax\/"},"author":{"name":"","@id":""},"headline":"Millones de nacimientos prematuros y miles de muertes de reci\u00e9n nacidos est\u00e1n vinculadas a un qu\u00edmico del pl\u00e1stico","datePublished":"2026-03-31T13:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/31\/prematuros-muerte-recien-nacidos-quimicos-plastico-trax\/"},"wordCount":1712,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/31\/prematuros-muerte-recien-nacidos-quimicos-plastico-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/31\/prematuros-muerte-recien-nacidos-quimicos-plastico-trax\/","url":"https:\/\/noticiasya.com\/2026\/03\/31\/prematuros-muerte-recien-nacidos-quimicos-plastico-trax\/","name":"Millones de nacimientos prematuros y miles de muertes de reci\u00e9n nacidos est\u00e1n vinculadas a un qu\u00edmico del pl\u00e1stico - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-31T13:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/31\/prematuros-muerte-recien-nacidos-quimicos-plastico-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/31\/prematuros-muerte-recien-nacidos-quimicos-plastico-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/31\/prematuros-muerte-recien-nacidos-quimicos-plastico-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Millones de nacimientos prematuros y miles de muertes de reci\u00e9n nacidos est\u00e1n vinculadas a un qu\u00edmico del pl\u00e1stico"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2026\/03\/31\/prematuros-muerte-recien-nacidos-quimicos-plastico-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Millones de nacimientos prematuros y miles de muertes de reci\u00e9n nacidos est\u00e1n vinculadas a un qu\u00edmico del pl\u00e1stico","url":"http:\/\/noticiasya.com\/colorado\/2026\/03\/31\/prematuros-muerte-recien-nacidos-quimicos-plastico-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2026\/03\/31\/prematuros-muerte-recien-nacidos-quimicos-plastico-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-31T13:03:45Z","datePublished":"2026-03-31T13:03:45Z","dateModified":"2026-03-31T13:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Millones de nacimientos prematuros y miles de muertes de reci\\u00e9n nacidos est\\u00e1n vinculadas a un qu\\u00edmico del pl\\u00e1stico\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/03\\\/31\\\/prematuros-muerte-recien-nacidos-quimicos-plastico-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/03\\\/31\\\/prematuros-muerte-recien-nacidos-quimicos-plastico-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-31T13:03:45Z\",\"datePublished\":\"2026-03-31T13:03:45Z\",\"dateModified\":\"2026-03-31T13:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472752,"url":"https:\/\/noticiasya.com\/colorado\/2026\/04\/01\/5-cosas-1-abril-orix\/","url_meta":{"origin":1472720,"position":0},"title":"Las 5 cosas que debes saber este 1 de abril","author":"","date":"abril 1, 2026","format":false,"excerpt":"La Corte Suprema de EE.UU. escucha hoy los argumentos en la batalla por la ciudadan\u00eda por nacimiento. El \u00edndice de aprobaci\u00f3n de Trump en materia econ\u00f3mica desciende a un nuevo m\u00ednimo. Misi\u00f3n Artemis II: las claves para entender el pr\u00f3ximo viaje a la Luna y seguirlo paso a paso. Esto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465564,"url":"https:\/\/noticiasya.com\/colorado\/2025\/08\/16\/bebes-prematuros-mueren-italia-contaminacion-detergente-trax\/","url_meta":{"origin":1472720,"position":1},"title":"Dos beb\u00e9s prematuros mueren en Italia por presunta contaminaci\u00f3n con detergente para platos","author":"","date":"agosto 16, 2025","format":false,"excerpt":"Se abri\u00f3 una investigaci\u00f3n penal despu\u00e9s de que dos beb\u00e9s prematuros murieran con pocas horas de diferencia durante la noche del 12 al 13 de agosto en el Hospital San Maurizio, en la ciudad de Bolzano, en el norte de Italia, informaron las autoridades.Ambos beb\u00e9s, que nacieron hace tres semanas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446033,"url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/27\/japon-minimo-historico-natalidad-2023-octavo-consecutivo-bajas-nacimientos-trax\/","url_meta":{"origin":1472720,"position":2},"title":"Jap\u00f3n registra un m\u00ednimo hist\u00f3rico de natalidad en 2023. Es el octavo a\u00f1o consecutivo de descensos en nacimientos","author":"","date":"febrero 27, 2024","format":false,"excerpt":"(CNN) -- El n\u00famero de beb\u00e9s nacidos en Jap\u00f3n descendi\u00f3 por octavo a\u00f1o consecutivo, alcanzando un m\u00ednimo hist\u00f3rico en 2023, seg\u00fan datos preliminares publicados este martes por el gobierno.El n\u00famero de nacimientos en 2023 se redujo a 758.631, lo que representa un descenso del 5,1% respecto al a\u00f1o anterior, mientras\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465340,"url":"https:\/\/noticiasya.com\/colorado\/2025\/08\/09\/ecuador-confirma-muerte-12-bebes-hospital-publico-guayaquil-orix\/","url_meta":{"origin":1472720,"position":3},"title":"Ecuador confirma la muerte de 12 beb\u00e9s en un hospital p\u00fablico de Guayaquil. Se\u00f1ala &#171;causas multifactoriales&#187;","author":"","date":"agosto 9, 2025","format":false,"excerpt":"El Ministerio de Salud de Ecuador confirm\u00f3 este s\u00e1bado que 12 beb\u00e9s reci\u00e9n nacidos han muerto en el Hospital Universitario de Guayaquil, administrado por el Gobierno, debido a lo que llam\u00f3 \u201ccausas multifactoriales\u201d.El Ministerio no aclar\u00f3 el per\u00edodo en el que ocurrieron los fallecimientos. CNN est\u00e1 buscando conseguir detalles del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459254,"url":"https:\/\/noticiasya.com\/colorado\/2025\/02\/26\/siete-bebes-mueren-hipotermia-gaza-trax\/","url_meta":{"origin":1472720,"position":4},"title":"Siete beb\u00e9s mueren de hipotermia en Gaza, seg\u00fan las autoridades sanitarias","author":"","date":"febrero 26, 2025","format":false,"excerpt":"Siete beb\u00e9s han muerto de hipotermia en Gaza desde el domingo, seg\u00fan los responsables sanitarios del enclave, quienes advierten que habr\u00e1 m\u00e1s muertes de este tipo a menos que entre m\u00e1s ayuda a la zona.El Dr. Saeed Salah, director m\u00e9dico del Hospital de la Sociedad Ben\u00e9vola de Amigos del Paciente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462375,"url":"https:\/\/noticiasya.com\/colorado\/2025\/05\/15\/bebes-ciudadania-nacimiento-madres-extranjeras-orix\/","url_meta":{"origin":1472720,"position":5},"title":"El n\u00famero de beb\u00e9s nacidos en EE.UU. que no obtendr\u00eda la ciudadan\u00eda si Trump elimina el derecho","author":"","date":"mayo 15, 2025","format":false,"excerpt":"En la \u00faltima d\u00e9cada, cientos de miles de beb\u00e9s nacidos en Estados Unidos de madres extranjeras han obtenido el derecho a la ciudadan\u00eda por nacimiento, una pr\u00e1ctica garantizada por la 14.\u00aa Enmienda de la Constituci\u00f3n que el presidente Donald Trump busca eliminar.A partir de un decreto, que firm\u00f3 el primer\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1472720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1472720"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1472720\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1472720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1472720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1472720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}