{"id":1472753,"date":"2026-04-01T03:03:58","date_gmt":"2026-04-01T10:03:58","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/01\/encuesta-cnn-aprobacion-trump-economica-nuevo-minimo-trax\/"},"modified":"2026-04-01T03:03:58","modified_gmt":"2026-04-01T10:03:58","slug":"encuesta-cnn-aprobacion-trump-economica-nuevo-minimo-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2026\/04\/01\/encuesta-cnn-aprobacion-trump-economica-nuevo-minimo-trax\/","title":{"rendered":"Encuesta de CNN: el \u00edndice de aprobaci\u00f3n de Trump en materia econ\u00f3mica desciende hasta un nuevo m\u00ednimo"},"content":{"rendered":"<p>Seg\u00fan una nueva encuesta de CNN realizada por SSRS, el \u00edndice de aprobaci\u00f3n del presidente Donald Trump en materia de gesti\u00f3n econ\u00f3mica ha ca\u00eddo a un nuevo m\u00ednimo hist\u00f3rico del 31 %.<\/p>\n<p>El dato refleja el creciente pesimismo entre los estadounidenses sobre el tema que describen sistem\u00e1ticamente como el m\u00e1s importante.<\/p>\n<p>Aproximadamente dos tercios de los encuestados afirman que las pol\u00edticas de Trump han empeorado la situaci\u00f3n econ\u00f3mica en Estados Unidos, un aumento de 10 puntos desde enero. Tan solo el 27 % aprueba la gesti\u00f3n de la inflaci\u00f3n por parte de Trump, frente al 44 % de hace un a\u00f1o.<\/p>\n<p>El \u00edndice de aprobaci\u00f3n general de Trump se ha mantenido relativamente estable en el 35 %, a un punto de su m\u00ednimo hist\u00f3rico, seg\u00fan las encuestas de CNN.<\/p>\n<p>Sin embargo, se ha producido un notable descenso en su popularidad entre sus propios partidarios. El porcentaje de republicanos que aprueban firmemente su gesti\u00f3n ha ca\u00eddo al 43 %, desde el 52 % en enero.<\/p>\n<p>El \u00edndice de aprobaci\u00f3n econ\u00f3mica de Trump ha ca\u00eddo 8 puntos en general desde enero, y experimenta un descenso a\u00fan mayor, de 14 puntos, entre los republicanos.<\/p>\n<p>Entre los conservadores menores de 45 a\u00f1os, la ca\u00edda es a\u00fan m\u00e1s pronunciada, de 23 puntos. Casi 3 de cada 10 republicanos (28 %) afirman que sus pol\u00edticas han empeorado la situaci\u00f3n econ\u00f3mica en Estados Unidos, frente al 13 % que opinaba lo mismo en enero.<\/p>\n<p>Desde que Estados Unidos super\u00f3 la pandemia de covid-19, numerosas encuestas han revelado que la econom\u00eda encabeza la lista de los temas m\u00e1s importantes, y la ciudadan\u00eda se muestra ampliamente insatisfecha con la gesti\u00f3n de Washington.<\/p>\n<p>Sin embargo, una nueva encuesta de CNN muestra que el descontento ha alcanzado un nuevo nivel: el 65 % que afirma que las pol\u00edticas de Trump han empeorado la econom\u00eda es el porcentaje m\u00e1s alto de su presidencia, superior al que opinaba lo mismo sobre las pol\u00edticas del dem\u00f3crata Joe Biden en cualquier momento de su mandato.<\/p>\n<p>Alrededor de tres cuartas partes de los estadounidenses afirman que la econom\u00eda de EE.UU. est\u00e1 en mal estado, un aumento de 8 puntos desde enero, y el porcentaje que la califica de \u201cmuy mal\u201d aument\u00f3 12 puntos.<\/p>\n<p>Aproximadamente 6 de cada 10 dicen que esperan que la econom\u00eda est\u00e9 en mal estado dentro de un a\u00f1o, el porcentaje m\u00e1s alto registrado durante cualquiera de las presidencias de Trump.<\/p>\n<p>La encuesta sugiere que la presi\u00f3n financiera derivada del precio de la gasolina, que ahora promedia m\u00e1s de US$ 4 por gal\u00f3n en todo el pa\u00eds tras el ataque estadounidense a Ir\u00e1n, ha aumentado las frustraciones econ\u00f3micas de los estadounidenses.<\/p>\n<p>Aunque el porcentaje de personas que afirman haber modificado sus h\u00e1bitos de compra o haber reducido sus gastos en extras ha disminuido en comparaci\u00f3n con el a\u00f1o anterior, m\u00e1s de 6 de cada 10 estadounidenses afirmando que siguen recortando sus presupuestos.<\/p>\n<p>Esta es una cifra que se ha mantenido por encima del 60 % en las encuestas de CNN desde 2022.<\/p>\n<p>Adem\u00e1s, una minor\u00eda creciente (45 %, 5 puntos m\u00e1s que el a\u00f1o pasado) afirma haber reducido significativamente la cantidad de kil\u00f3metros que recorre en coche.<\/p>\n<p>En general, el 63 % afirma que el aumento del precio de la gasolina ha provocado dificultades econ\u00f3micas en sus hogares, y el 15 % las considera graves.<\/p>\n<p>La mayor\u00eda (57 %) ve el alza de los precios como una fluctuaci\u00f3n temporal m\u00e1s que como un cambio permanente, aunque <a href=\"https:\/\/www.cnn.com\/2026\/03\/31\/business\/oil-prices-economy-market\">las se\u00f1ales del mercado sugieren que, incluso si la guerra terminara pronto, es probable que haya efectos duraderos en los precios del petr\u00f3leo<\/a>.<\/p>\n<p>Siete de cada diez afirman que el presidente no tiene un plan claro para abordar la situaci\u00f3n del precio de la gasolina, y apenas el 24 % aprueba su gesti\u00f3n.<\/p>\n<p>Al preguntarle cu\u00e1l era el problema m\u00e1s importante que enfrenta el pa\u00eds, un encuestado republicano escribi\u00f3: \u201c\u00a1Los precios! Todo est\u00e1 car\u00edsimo. Es muy dif\u00edcil hacer cualquier cosa que no sea trabajar e ir a casa. \u00a1Ir al supermercado es una locura! \u00a1Entre la gasolina y el precio de los alimentos, somos pobres!\u201d.<\/p>\n<p>En la nueva encuesta, el 40 % menciona un tema econ\u00f3mico como el m\u00e1s importante, m\u00e1s del doble del porcentaje que se\u00f1ala cualquier otro tipo de tema.<\/p>\n<p>Y el 67 % afirma que Trump no ha prestado suficiente atenci\u00f3n a los principales problemas del pa\u00eds, un dato que se ha mantenido bastante estable desde el verano pasado.<\/p>\n<p>Hay pocos indicios de que los dem\u00f3cratas est\u00e9n sacando provecho de lo que los estadounidenses consideran una deficiencia de Trump, ya que un porcentaje a\u00fan mayor, el 74 %, opina que los dem\u00f3cratas en el Congreso tienen prioridades equivocadas.<\/p>\n<p>Los dem\u00f3cratas son m\u00e1s propensos a afirmar que su propio partido tiene un enfoque err\u00f3neo que los republicanos a decir lo mismo de Trump, pero entre los independientes consideran igualmente que los dos partidos est\u00e1n fuera de tema.<\/p>\n<p>Alrededor de tres cuartas partes de los independientes afirman que ambos tienen prioridades equivocadas.<\/p>\n<p>La encuesta tambi\u00e9n muestra indicios de un empeoramiento de la opini\u00f3n p\u00fablica sobre la pol\u00edtica exterior de Trump.<\/p>\n<p>El 63 % afirma que sus decisiones en ese \u00e1mbito han perjudicado la posici\u00f3n de Estados Unidos en el mundo, un aumento 6 puntos desde enero, y solo el 36 % aprueba su gesti\u00f3n de los asuntos internacionales.<\/p>\n<p>Sin embargo, existe cierta estabilidad en la percepci\u00f3n de la situaci\u00f3n en Estados Unidos.<\/p>\n<p>Si bien la opini\u00f3n p\u00fablica es mayoritariamente negativa (el 67 % afirma que las cosas van mal), no es peor que el oto\u00f1o pasado.<\/p>\n<p>Adem\u00e1s, los \u00edndices de aprobaci\u00f3n de Trump en otros temas importantes, como la inmigraci\u00f3n y la pol\u00edtica sanitaria, aunque negativos, se han mantenido pr\u00e1cticamente estables desde principios de a\u00f1o.<\/p>\n<p>Trump y los republicanos en el Congreso cargan con la mayor parte de la culpa que sus oponentes del otro lado del pasillo por el cierre parcial en curso del Departamento de Seguridad Nacional, con un 39 % de los encuestados que dice que el Partido Republicano merece la mayor parte de la responsabilidad, frente a un 25 % que dice lo mismo de los dem\u00f3cratas en el Congreso. Un 28 % cree que ambos grupos comparten la misma culpa.<\/p>\n<p>Uno de cada cinco estadounidenses considera que el cierre parcial del Gobierno es una crisis, una proporci\u00f3n menor que la que opinaba lo mismo durante el impasse gubernametal el oto\u00f1o pasado.<\/p>\n<p>Si bien el impacto m\u00e1s visible del cierre parcial han sido las largas filas en los controles de seguridad de los aeropuertos, ya que los agentes de la TSA no recibieron su salario hasta que un decreto reciente les otorg\u00f3 sus cheques esta semana, la encuesta revela poca diferencia en la evaluaci\u00f3n de la gravedad del cierre seg\u00fan si las personas han tomado un vuelo recientemente.<\/p>\n<p>Y pocos creen que el decreto de Trump de enviar agentes del Servicio de Inmigraci\u00f3n y Control de Aduanas a los aeropuertos haya ayudado a la situaci\u00f3n: el 40 % opin\u00f3 que empeor\u00f3 las cosas, mientras que solo el 21 % cree que las mejor\u00f3.<\/p>\n<p>La mayor\u00eda de los estadounidenses, incluido el 84 % de los republicanos, afirma que la gesti\u00f3n de Trump en la presidencia ha estado a la altura de sus expectativas, pero estas opiniones se concentran entre quienes tienen una visi\u00f3n positiva de su desempe\u00f1o.<\/p>\n<p>Entre todos los adultos que aprueban su gesti\u00f3n, el 91 % afirma que la est\u00e1 llevando a cabo como se esperaba. Sin embargo, quienes la desaprueban est\u00e1n m\u00e1s divididos: el 52 % opina que es lo que esperaban y el 48 % que no.<\/p>\n<p>Muchos afirman que Trump se ha extralimitado en varios aspectos clave de su segundo mandato.<\/p>\n<p>Aproximadamente seis de cada diez opinan que ha ido demasiado lejos al intentar expandir el poder de Estados Unidos sobre otros pa\u00edses, al abusar del poder presidencial y ejecutivo, y al recortar programas del Gobierno federal.<\/p>\n<p>Una mayor\u00eda ligeramente menor (55 %) considera que se ha excedido en la deportaci\u00f3n de inmigrantes indocumentados.<\/p>\n<p><em>La encuesta de CNN fue realizada por SSRS en l\u00ednea y por tel\u00e9fono entre el 26 y el 30 de marzo a una muestra nacional aleatoria de 1.201 adultos. Los resultados para la muestra completa tienen un margen de error de m\u00e1s o menos 3,2 puntos porcentuales.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan una nueva encuesta de CNN realizada por SSRS, el \u00edndice de aprobaci\u00f3n del presidente Donald Trump en materia de gesti\u00f3n econ\u00f3mica ha ca\u00eddo a un nuevo m\u00ednimo hist\u00f3rico del 31 %. El dato refleja el creciente pesimismo entre los estadounidenses sobre el tema que describen sistem\u00e1ticamente como el m\u00e1s importante. Aproximadamente dos tercios de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472753","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Encuesta de CNN: el \u00edndice de aprobaci\u00f3n de Trump en materia econ\u00f3mica desciende hasta un nuevo m\u00ednimo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/01\/encuesta-cnn-aprobacion-trump-economica-nuevo-minimo-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Encuesta de CNN: el \u00edndice de aprobaci\u00f3n de Trump en materia econ\u00f3mica desciende hasta un nuevo m\u00ednimo - Noticias\" \/>\n<meta property=\"og:description\" content=\"Seg\u00fan una nueva encuesta de CNN realizada por SSRS, el \u00edndice de aprobaci\u00f3n del presidente Donald Trump en materia de gesti\u00f3n econ\u00f3mica ha ca\u00eddo a un nuevo m\u00ednimo hist\u00f3rico del 31 %. El dato refleja el creciente pesimismo entre los estadounidenses sobre el tema que describen sistem\u00e1ticamente como el m\u00e1s importante. Aproximadamente dos tercios de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/01\/encuesta-cnn-aprobacion-trump-economica-nuevo-minimo-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-01T10:03:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/01\/encuesta-cnn-aprobacion-trump-economica-nuevo-minimo-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/01\/encuesta-cnn-aprobacion-trump-economica-nuevo-minimo-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Encuesta de CNN: el \u00edndice de aprobaci\u00f3n de Trump en materia econ\u00f3mica desciende hasta un nuevo m\u00ednimo\",\"datePublished\":\"2026-04-01T10:03:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/01\/encuesta-cnn-aprobacion-trump-economica-nuevo-minimo-trax\/\"},\"wordCount\":1452,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/01\/encuesta-cnn-aprobacion-trump-economica-nuevo-minimo-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/01\/encuesta-cnn-aprobacion-trump-economica-nuevo-minimo-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/01\/encuesta-cnn-aprobacion-trump-economica-nuevo-minimo-trax\/\",\"name\":\"Encuesta de CNN: el \u00edndice de aprobaci\u00f3n de Trump en materia econ\u00f3mica desciende hasta un nuevo m\u00ednimo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-01T10:03:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/01\/encuesta-cnn-aprobacion-trump-economica-nuevo-minimo-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/01\/encuesta-cnn-aprobacion-trump-economica-nuevo-minimo-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/01\/encuesta-cnn-aprobacion-trump-economica-nuevo-minimo-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Encuesta de CNN: el \u00edndice de aprobaci\u00f3n de Trump en materia econ\u00f3mica desciende hasta un nuevo m\u00ednimo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Encuesta de CNN: el \u00edndice de aprobaci\u00f3n de Trump en materia econ\u00f3mica desciende hasta un nuevo m\u00ednimo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/01\/encuesta-cnn-aprobacion-trump-economica-nuevo-minimo-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Encuesta de CNN: el \u00edndice de aprobaci\u00f3n de Trump en materia econ\u00f3mica desciende hasta un nuevo m\u00ednimo - Noticias","og_description":"Seg\u00fan una nueva encuesta de CNN realizada por SSRS, el \u00edndice de aprobaci\u00f3n del presidente Donald Trump en materia de gesti\u00f3n econ\u00f3mica ha ca\u00eddo a un nuevo m\u00ednimo hist\u00f3rico del 31 %. El dato refleja el creciente pesimismo entre los estadounidenses sobre el tema que describen sistem\u00e1ticamente como el m\u00e1s importante. Aproximadamente dos tercios de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/01\/encuesta-cnn-aprobacion-trump-economica-nuevo-minimo-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-01T10:03:58+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/01\/encuesta-cnn-aprobacion-trump-economica-nuevo-minimo-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/01\/encuesta-cnn-aprobacion-trump-economica-nuevo-minimo-trax\/"},"author":{"name":"","@id":""},"headline":"Encuesta de CNN: el \u00edndice de aprobaci\u00f3n de Trump en materia econ\u00f3mica desciende hasta un nuevo m\u00ednimo","datePublished":"2026-04-01T10:03:58+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/01\/encuesta-cnn-aprobacion-trump-economica-nuevo-minimo-trax\/"},"wordCount":1452,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/01\/encuesta-cnn-aprobacion-trump-economica-nuevo-minimo-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/01\/encuesta-cnn-aprobacion-trump-economica-nuevo-minimo-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/01\/encuesta-cnn-aprobacion-trump-economica-nuevo-minimo-trax\/","name":"Encuesta de CNN: el \u00edndice de aprobaci\u00f3n de Trump en materia econ\u00f3mica desciende hasta un nuevo m\u00ednimo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-01T10:03:58+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/01\/encuesta-cnn-aprobacion-trump-economica-nuevo-minimo-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/01\/encuesta-cnn-aprobacion-trump-economica-nuevo-minimo-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/01\/encuesta-cnn-aprobacion-trump-economica-nuevo-minimo-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Encuesta de CNN: el \u00edndice de aprobaci\u00f3n de Trump en materia econ\u00f3mica desciende hasta un nuevo m\u00ednimo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2026\/04\/01\/encuesta-cnn-aprobacion-trump-economica-nuevo-minimo-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Encuesta de CNN: el \u00edndice de aprobaci\u00f3n de Trump en materia econ\u00f3mica desciende hasta un nuevo m\u00ednimo","url":"http:\/\/noticiasya.com\/colorado\/2026\/04\/01\/encuesta-cnn-aprobacion-trump-economica-nuevo-minimo-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2026\/04\/01\/encuesta-cnn-aprobacion-trump-economica-nuevo-minimo-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-01T10:03:58Z","datePublished":"2026-04-01T10:03:58Z","dateModified":"2026-04-01T10:03:58Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Encuesta de CNN: el \\u00edndice de aprobaci\\u00f3n de Trump en materia econ\\u00f3mica desciende hasta un nuevo m\\u00ednimo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/04\\\/01\\\/encuesta-cnn-aprobacion-trump-economica-nuevo-minimo-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/04\\\/01\\\/encuesta-cnn-aprobacion-trump-economica-nuevo-minimo-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-01T10:03:58Z\",\"datePublished\":\"2026-04-01T10:03:58Z\",\"dateModified\":\"2026-04-01T10:03:58Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1461140,"url":"https:\/\/noticiasya.com\/colorado\/2025\/04\/13\/aprobacion-economica-trump-cae-segun-encuesta-trax\/","url_meta":{"origin":1472753,"position":0},"title":"Cae la aprobaci\u00f3n de Trump por su manejo de la econom\u00eda, seg\u00fan una nueva encuesta de CBS News","author":"","date":"abril 13, 2025","format":false,"excerpt":"Los \u00edndices de aprobaci\u00f3n del presidente Donald Trump por su manejo de la econom\u00eda y la inflaci\u00f3n cayeron, seg\u00fan una nueva encuesta de CBS News, ya que una amplia mayor\u00eda espera, al menos a corto plazo, aumentos de precios y da\u00f1os econ\u00f3micos por sus pol\u00edticas arancelarias.A continuaci\u00f3n algunas conclusiones clave:La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473371,"url":"https:\/\/noticiasya.com\/colorado\/2026\/04\/21\/trump-aprobacion-nivel-george-bush-trax\/","url_meta":{"origin":1472753,"position":1},"title":"La aprobaci\u00f3n de Trump cae a niveles similares a los de George W. Bush","author":"","date":"abril 21, 2026","format":false,"excerpt":"Fue casi exactamente en esta \u00e9poca, hace 20 a\u00f1os, cuando la aprobaci\u00f3n de George W. Bush comenz\u00f3 a desplomarse. Y cuando sus cifras en la mayor\u00eda de las encuestas cayeron a niveles de los 30 puntos por primera vez a finales del invierno y comienzos de la primavera, la causa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470145,"url":"https:\/\/noticiasya.com\/colorado\/2026\/01\/16\/encuesta-cnn-primer-ano-trump-trax\/","url_meta":{"origin":1472753,"position":2},"title":"Encuesta de CNN revela que la mayor\u00eda de los estadounidenses cree que Trump se centra en las prioridades equivocadas","author":"","date":"enero 16, 2026","format":false,"excerpt":"La opini\u00f3n p\u00fablica sobre casi todos los aspectos del primer a\u00f1o del presidente Donald Trump en la Casa Blanca es negativa, seg\u00fan una nueva encuesta de CNN realizada por SSRS. La mayor\u00eda de los estadounidenses afirma que Trump se centra en las prioridades equivocadas y que hace muy poco para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472752,"url":"https:\/\/noticiasya.com\/colorado\/2026\/04\/01\/5-cosas-1-abril-orix\/","url_meta":{"origin":1472753,"position":3},"title":"Las 5 cosas que debes saber este 1 de abril","author":"","date":"abril 1, 2026","format":false,"excerpt":"La Corte Suprema de EE.UU. escucha hoy los argumentos en la batalla por la ciudadan\u00eda por nacimiento. El \u00edndice de aprobaci\u00f3n de Trump en materia econ\u00f3mica desciende a un nuevo m\u00ednimo. Misi\u00f3n Artemis II: las claves para entender el pr\u00f3ximo viaje a la Luna y seguirlo paso a paso. Esto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472587,"url":"https:\/\/noticiasya.com\/colorado\/2026\/03\/26\/aprobacion-trump-debajo-40-encuestas-trax\/","url_meta":{"origin":1472753,"position":4},"title":"La aprobaci\u00f3n del presidente Trump se mantiene por debajo del 40 %, seg\u00fan nuevas encuestas","author":"","date":"marzo 26, 2026","format":false,"excerpt":"Dos nuevas encuestas sit\u00faan el \u00edndice general de aprobaci\u00f3n del presidente Donald Trump por debajo del 40 %, una cifra baja que apenas ha variado desde febrero.Estos datos provienen de una encuesta realizada por la Universidad Quinnipiac y de otra efectuada ayer por AP-NORC. Mientras tanto, un nuevo sondeo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469336,"url":"https:\/\/noticiasya.com\/colorado\/2025\/12\/17\/analisis-encuestas-aprobacion-trump-trax\/","url_meta":{"origin":1472753,"position":5},"title":"\u00bfQui\u00e9n apoya a Trump? Aparentemente, menos gente que nunca","author":"","date":"diciembre 17, 2025","format":false,"excerpt":"Hace un a\u00f1o, el presidente Donald Trump habl\u00f3 como si el pueblo estadounidense le hubiera otorgado una victoria aplastante para la historia.\u201cEstados Unidos nos ha otorgado un mandato poderoso y sin precedentes\u201d, declar\u00f3 poco despu\u00e9s de las elecciones de noviembre. En su discurso inaugural de enero, afirm\u00f3 que su victoria\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1472753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1472753"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1472753\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1472753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1472753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1472753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}