{"id":1472762,"date":"2026-04-01T08:03:43","date_gmt":"2026-04-01T15:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/01\/bandas-criminales-haiti-ataques-region-artibonite-masacre-reux\/"},"modified":"2026-04-01T08:03:43","modified_gmt":"2026-04-01T15:03:43","slug":"bandas-criminales-haiti-ataques-region-artibonite-masacre-reux","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/colorado\/2026\/04\/01\/bandas-criminales-haiti-ataques-region-artibonite-masacre-reux\/","title":{"rendered":"Bandas criminales de Hait\u00ed mantienen sus ataques en la regi\u00f3n de Artibonite, luego de la masacre que dej\u00f3 decenas de muertos"},"content":{"rendered":"<p>Hombres armados perpetraron nuevos ataques el martes en la regi\u00f3n agr\u00edcola de Artibonite, en Hait\u00ed, pocos d\u00edas despu\u00e9s de que un asalto perpetrado por una banda el fin de semana en la zona de Jean-Denis dejara unas 70 v\u00edctimas mortales, <a href=\"https:\/\/www.cnn.com\/2026\/03\/30\/americas\/haiti-gang-attack-violence-intl-latam\">seg\u00fan<\/a> grupos de derechos humanos y residentes locales.<\/p>\n<p>La Polic\u00eda nacional inform\u00f3 que el martes estaba llevando a cabo operaciones en varias zonas de Artibonite.<\/p>\n<p>Los residentes de Jean-Denis contaron 70 cad\u00e1veres el domingo por la ma\u00f1ana tras un ataque de la banda Gran Grif, seg\u00fan indic\u00f3 la Red Nacional para la Defensa de los Derechos Humanos (RNDDH) en un informe, lo que coincide con las estimaciones del grupo de derechos humanos Defense Plus, pero supera con creces las <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/30\/latinoamerica\/haiti-masacre-banda-criminal-muertos-orix\">estimaciones oficiales<\/a>, que sit\u00faan el n\u00famero de muertos en torno a 16.<\/p>\n<p>La RNDDH se\u00f1al\u00f3 que unas 30 personas m\u00e1s resultaron heridas, y que entre las v\u00edctimas hab\u00eda beb\u00e9s, mujeres embarazadas, adolescentes y un hombre de 80 a\u00f1os.<\/p>\n<p>Hombres armados se retiraron de Jean-Denis el lunes, seg\u00fan la RNDDH, pero el martes se reposicionaron en la cercana Pont Benoit e intentaban lanzar otra ofensiva en la localidad de Marchand Dessalines, a unos 19 km al norte.<\/p>\n<p>Videos compartidos en redes sociales mostraban a hombres armados, presuntamente pertenecientes a la banda Kokorat San Ras, un aliado cercano de la poderosa Gran Grif, repartiendo dinero en efectivo a los residentes de Marchand Dessalines. Gran Grif ha sido designada como organizaci\u00f3n terrorista por Estados Unidos y la vecina Rep\u00fablica Dominicana.<\/p>\n<p>Residentes dijeron a Reuters que las brigadas locales de autodefensa no ten\u00edan la potencia de fuego necesaria para contener a las bandas, que esperaban durante el d\u00eda, cuando la Polic\u00eda estaba presente, pero comenzaban a disparar y a incendiar edificios por la noche.<\/p>\n<p>RNDDH, cuyo informe se bas\u00f3 en entrevistas con autoridades locales, la Polic\u00eda y residentes, se\u00f1al\u00f3 que el ataque de Gran Grif contra Jean-Denis se produjo tras semanas de amenazas y que los residentes no huyeron porque cre\u00edan que la brigada de autodefensa los proteger\u00eda.<\/p>\n<p>Sin embargo, la brigada de autodefensa se retir\u00f3 al carecer de la potencia de fuego necesaria para repeler el ataque, seg\u00fan RNDDH.<\/p>\n<p>La respuesta policial fue limitada, se\u00f1al\u00f3, ya que los veh\u00edculos blindados que lograron llegar al lugar permanecieron all\u00ed solo unas horas antes de retirarse y regresar el lunes.<\/p>\n<p>Las autoridades locales comunicaron al grupo de derechos humanos que la mayor\u00eda de sus veh\u00edculos blindados estaban fuera de servicio, algunos debido a problemas con las bater\u00edas que requer\u00edan la ayuda de mec\u00e1nicos con base en Puerto Pr\u00edncipe, y que las unidades pertenecientes a la fuerza de seguridad respaldada por la Organizaci\u00f3n de las Naciones Unidas (ONU) tuvieron que esperar la autorizaci\u00f3n de la capital antes de desplegarse.<\/p>\n<p>Mientras tanto, el martes, el primer ministro de Hait\u00ed, Alix Didier Fils-Aime, recibi\u00f3 a una delegaci\u00f3n de la ONU con la que discuti\u00f3 la llegada de una misi\u00f3n ampliada de una fuerza de seguridad que hasta ahora solo se ha desplegado parcialmente y que ha adolecido de falta de equipamiento, efectivos y fondos.<\/p>\n<p>En un informe publicado ese mismo d\u00eda, la organizaci\u00f3n sin \u00e1nimo de lucro estadounidense IJDH critic\u00f3 las medidas estatales e internacionales que, seg\u00fan afirm\u00f3, daban prioridad a respuestas militarizadas a corto plazo al tiempo que recortaban la ayuda, deportaban masivamente a migrantes y depend\u00edan de actores no estatales, incluida una empresa militar privada estadounidense y las brigadas de autodefensa, ambas acusadas de ejecuciones extrajudiciales.<\/p>\n<p>\u201cEl panorama social y econ\u00f3mico de Hait\u00ed, ya de por s\u00ed catastr\u00f3fico, se ha deteriorado a\u00fan m\u00e1s\u201d, se\u00f1al\u00f3, a\u00f1adiendo que ni el primer ministro ni el despliegue respaldado por la ONU \u201cparecen estar preparados para transformar las din\u00e1micas subyacentes a los fracasos de sus predecesores\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hombres armados perpetraron nuevos ataques el martes en la regi\u00f3n agr\u00edcola de Artibonite, en Hait\u00ed, pocos d\u00edas despu\u00e9s de que un asalto perpetrado por una banda el fin de semana en la zona de Jean-Denis dejara unas 70 v\u00edctimas mortales, seg\u00fan grupos de derechos humanos y residentes locales. La Polic\u00eda nacional inform\u00f3 que el martes [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472762","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bandas criminales de Hait\u00ed mantienen sus ataques en la regi\u00f3n de Artibonite, luego de la masacre que dej\u00f3 decenas de muertos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/01\/bandas-criminales-haiti-ataques-region-artibonite-masacre-reux\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bandas criminales de Hait\u00ed mantienen sus ataques en la regi\u00f3n de Artibonite, luego de la masacre que dej\u00f3 decenas de muertos - Noticias\" \/>\n<meta property=\"og:description\" content=\"Hombres armados perpetraron nuevos ataques el martes en la regi\u00f3n agr\u00edcola de Artibonite, en Hait\u00ed, pocos d\u00edas despu\u00e9s de que un asalto perpetrado por una banda el fin de semana en la zona de Jean-Denis dejara unas 70 v\u00edctimas mortales, seg\u00fan grupos de derechos humanos y residentes locales. La Polic\u00eda nacional inform\u00f3 que el martes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/01\/bandas-criminales-haiti-ataques-region-artibonite-masacre-reux\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-01T15:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/01\/bandas-criminales-haiti-ataques-region-artibonite-masacre-reux\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/01\/bandas-criminales-haiti-ataques-region-artibonite-masacre-reux\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Bandas criminales de Hait\u00ed mantienen sus ataques en la regi\u00f3n de Artibonite, luego de la masacre que dej\u00f3 decenas de muertos\",\"datePublished\":\"2026-04-01T15:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/01\/bandas-criminales-haiti-ataques-region-artibonite-masacre-reux\/\"},\"wordCount\":697,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/01\/bandas-criminales-haiti-ataques-region-artibonite-masacre-reux\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/01\/bandas-criminales-haiti-ataques-region-artibonite-masacre-reux\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/01\/bandas-criminales-haiti-ataques-region-artibonite-masacre-reux\/\",\"name\":\"Bandas criminales de Hait\u00ed mantienen sus ataques en la regi\u00f3n de Artibonite, luego de la masacre que dej\u00f3 decenas de muertos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-01T15:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/01\/bandas-criminales-haiti-ataques-region-artibonite-masacre-reux\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/01\/bandas-criminales-haiti-ataques-region-artibonite-masacre-reux\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/01\/bandas-criminales-haiti-ataques-region-artibonite-masacre-reux\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bandas criminales de Hait\u00ed mantienen sus ataques en la regi\u00f3n de Artibonite, luego de la masacre que dej\u00f3 decenas de muertos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bandas criminales de Hait\u00ed mantienen sus ataques en la regi\u00f3n de Artibonite, luego de la masacre que dej\u00f3 decenas de muertos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/01\/bandas-criminales-haiti-ataques-region-artibonite-masacre-reux\/","og_locale":"es_ES","og_type":"article","og_title":"Bandas criminales de Hait\u00ed mantienen sus ataques en la regi\u00f3n de Artibonite, luego de la masacre que dej\u00f3 decenas de muertos - Noticias","og_description":"Hombres armados perpetraron nuevos ataques el martes en la regi\u00f3n agr\u00edcola de Artibonite, en Hait\u00ed, pocos d\u00edas despu\u00e9s de que un asalto perpetrado por una banda el fin de semana en la zona de Jean-Denis dejara unas 70 v\u00edctimas mortales, seg\u00fan grupos de derechos humanos y residentes locales. La Polic\u00eda nacional inform\u00f3 que el martes [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/01\/bandas-criminales-haiti-ataques-region-artibonite-masacre-reux\/","og_site_name":"Noticias","article_published_time":"2026-04-01T15:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/01\/bandas-criminales-haiti-ataques-region-artibonite-masacre-reux\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/01\/bandas-criminales-haiti-ataques-region-artibonite-masacre-reux\/"},"author":{"name":"","@id":""},"headline":"Bandas criminales de Hait\u00ed mantienen sus ataques en la regi\u00f3n de Artibonite, luego de la masacre que dej\u00f3 decenas de muertos","datePublished":"2026-04-01T15:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/01\/bandas-criminales-haiti-ataques-region-artibonite-masacre-reux\/"},"wordCount":697,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/01\/bandas-criminales-haiti-ataques-region-artibonite-masacre-reux\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/01\/bandas-criminales-haiti-ataques-region-artibonite-masacre-reux\/","url":"https:\/\/noticiasya.com\/2026\/04\/01\/bandas-criminales-haiti-ataques-region-artibonite-masacre-reux\/","name":"Bandas criminales de Hait\u00ed mantienen sus ataques en la regi\u00f3n de Artibonite, luego de la masacre que dej\u00f3 decenas de muertos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-01T15:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/01\/bandas-criminales-haiti-ataques-region-artibonite-masacre-reux\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/01\/bandas-criminales-haiti-ataques-region-artibonite-masacre-reux\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/01\/bandas-criminales-haiti-ataques-region-artibonite-masacre-reux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Bandas criminales de Hait\u00ed mantienen sus ataques en la regi\u00f3n de Artibonite, luego de la masacre que dej\u00f3 decenas de muertos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/colorado\/2026\/04\/01\/bandas-criminales-haiti-ataques-region-artibonite-masacre-reux\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Bandas criminales de Hait\u00ed mantienen sus ataques en la regi\u00f3n de Artibonite, luego de la masacre que dej\u00f3 decenas de muertos","url":"http:\/\/noticiasya.com\/colorado\/2026\/04\/01\/bandas-criminales-haiti-ataques-region-artibonite-masacre-reux\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/colorado\/2026\/04\/01\/bandas-criminales-haiti-ataques-region-artibonite-masacre-reux\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-01T15:03:43Z","datePublished":"2026-04-01T15:03:43Z","dateModified":"2026-04-01T15:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Bandas criminales de Hait\\u00ed mantienen sus ataques en la regi\\u00f3n de Artibonite, luego de la masacre que dej\\u00f3 decenas de muertos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/04\\\/01\\\/bandas-criminales-haiti-ataques-region-artibonite-masacre-reux\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/colorado\\\/2026\\\/04\\\/01\\\/bandas-criminales-haiti-ataques-region-artibonite-masacre-reux\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-01T15:03:43Z\",\"datePublished\":\"2026-04-01T15:03:43Z\",\"dateModified\":\"2026-04-01T15:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472701,"url":"https:\/\/noticiasya.com\/colorado\/2026\/03\/30\/haiti-masacre-banda-criminal-muertos-orix\/","url_meta":{"origin":1472762,"position":0},"title":"Mueren al menos 16 personas en una masacre perpetrada por una banda criminal en Hait\u00ed, seg\u00fan la polic\u00eda","author":"","date":"marzo 30, 2026","format":false,"excerpt":"Al menos 16 personas murieron en una masacre ocurrida el domingo en Hait\u00ed, perpetrada por el grupo armado Gran Grif en Jean Denis, al norte de la capital Puerto Pr\u00edncipe, seg\u00fan inform\u00f3 este lunes la Polic\u00eda Nacional (PNH).Las autoridades dijeron que la banda criminal bloque\u00f3 caminos para impedir la llegada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460471,"url":"https:\/\/noticiasya.com\/colorado\/2025\/03\/26\/matan-policia-keniano-haiti-emboscada-pandillas-rubio-visita-crisis-seguridad-trax\/","url_meta":{"origin":1472762,"position":1},"title":"Matan a militar keniano en emboscada de pandillas en Hait\u00ed, mientras Rubio visita el Caribe para abordar crisis de seguridad","author":"","date":"marzo 26, 2025","format":false,"excerpt":"Un miembro de la fuerza internacional que lucha contra las pandillas en Hait\u00ed muri\u00f3 en batalla, mientras el secretario de Estado de EE.UU., Marco Rubio, inicia una gira por el Caribe con la crisis de seguridad en el pa\u00eds como uno de los temas principales en la agenda.El militar keniano\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447493,"url":"https:\/\/noticiasya.com\/colorado\/2024\/03\/28\/violencia-pandillas-haiti-ha-matado-mas-1-500-personas-2024-anio-informe-derechos-humanos-onu-trax\/","url_meta":{"origin":1472762,"position":2},"title":"Violencia de pandillas en Hait\u00ed mat\u00f3 a m\u00e1s de 1.500 personas este a\u00f1o, seg\u00fan un informe de derechos humanos de la ONU","author":"","date":"marzo 28, 2024","format":false,"excerpt":"(CNN) -- M\u00e1s de 1.500 personas han muerto a causa de la violencia de las pandillas en Hait\u00ed en lo que va del a\u00f1o, seg\u00fan un informe publicado este jueves por la Oficina de Derechos Humanos de la ONU.A medida que aumenta la violencia de las pandillas, la Oficina del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447520,"url":"https:\/\/noticiasya.com\/colorado\/2024\/03\/28\/violencia-sexual-impune-haiti-informe-onu-trax\/","url_meta":{"origin":1472762,"position":3},"title":"La violencia sexual queda &#171;en gran medida impune&#187; en Hait\u00ed, dice la ONU","author":"","date":"marzo 28, 2024","format":false,"excerpt":"(CNN) -- La Oficina de Derechos Humanos de la ONU describi\u00f3 la violencia sexual en Hait\u00ed como \u201cmuy poco denunciada y en gran medida impune\u201d en un desgarrador informe publicado este jueves que documentaba casos de violaci\u00f3n y relaciones sexuales forzadas con miembros de pandillas, as\u00ed como niveles crecientes de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473621,"url":"https:\/\/noticiasya.com\/colorado\/2026\/04\/28\/corte-suprema-estados-unidos-vida-haiti-trax\/","url_meta":{"origin":1472762,"position":4},"title":"La Corte Suprema de Estados Unidos podr\u00eda cortar pronto una l\u00ednea de vida para Hait\u00ed","author":"","date":"abril 28, 2026","format":false,"excerpt":"Ysmael ya est\u00e1 sintiendo el impacto del aumento de precios en Hait\u00ed. \u201cTodo ha subido\u201d, dice en un video del Programa Mundial de Alimentos, desde el precio de un billete de autob\u00fas hasta el costo de la cena, todo debido al alza de los precios del combustible relacionada con la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446871,"url":"https:\/\/noticiasya.com\/colorado\/2024\/03\/11\/dimite-ariel-henry-primer-ministro-haiti-trax\/","url_meta":{"origin":1472762,"position":5},"title":"Dimite el primer ministro de Hait\u00ed, Ariel Henry, mientras las bandas se desplazan a sus anchas por un pa\u00eds sumido en la crisis","author":"","date":"marzo 11, 2024","format":false,"excerpt":"(CNN) -- El asediado l\u00edder de Hait\u00ed, Ariel Henry, present\u00f3 su dimisi\u00f3n este lunes en la noche, seg\u00fan l\u00edderes regionales, tras semanas de caos creciente en la naci\u00f3n caribe\u00f1a, donde las bandas han estado atacando las estructuras gubernamentales y el orden social est\u00e1 al borde del colapso.El asesor del primer\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/colorado\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1472762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/comments?post=1472762"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/posts\/1472762\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/media?parent=1472762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/categories?post=1472762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/colorado\/wp-json\/wp\/v2\/tags?post=1472762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}