{"id":1436649,"date":"2023-01-26T19:14:01","date_gmt":"2023-01-27T03:14:01","guid":{"rendered":"https:\/\/noticiasya.com\/?p=1436649"},"modified":"2023-01-26T19:14:01","modified_gmt":"2023-01-27T03:14:01","slug":"entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/","title":{"rendered":"Entrevista con Mariangela: Melancol\u00eda para sobrevivir el cambio"},"content":{"rendered":"<p>\u00bfQu\u00e9 pasa cuando das todo sin esperar nada a cambio? Cuando el coraz\u00f3n manda y la creatividad rebasa todo l\u00edmite de tu ADN. Ese es el feeling que representa a Mariangela, la cantautora mexicana que est\u00e1 apoder\u00e1ndose de los charts y que ha trabajado casi artesanalmente una carrera que de a poco est\u00e1 subiendo como la espuma.<\/p>\n<p>Recientemente platicamos de m\u00fasica y entre muchas sorpresas, not\u00e9 que aunque acaba de firmar con una de las disqueras m\u00e1s grandes del mundo, sigue teniendo los pies sobre la tierra y sabe en qu\u00e9 lugar y momento vive.<\/p>\n<p>Conversamos de sus inicios y de c\u00f3mo lleg\u00f3 la m\u00fasica a su vida. Tambi\u00e9n hablamos de sus composiciones que est\u00e1n sonando por todo M\u00e9xico y alcanzando nuevos p\u00fablicos en las ciudades m\u00e1s importantes de Estados Unidos.<\/p>\n<p>Repasamos el trabajo que hubo detr\u00e1s de su primer disco de corta duraci\u00f3n 4 + 1 (2022), una pieza que cre\u00f3 con amor, melancol\u00eda y mucho sentimiento. Un disco que si bien sirve como su primer acercamiento a la escena, tambi\u00e9n tiene un sonido muy trabajado y un mensaje de reflexi\u00f3n para quien lo escucha.<\/p>\n<p>Aunque su estilo conlleva profundidad en su l\u00edrica, tambi\u00e9n lleva consigo un mensaje de aliento que te abraza y te susurra al o\u00eddo que todo va a estar bien. Esa es la melancol\u00eda para sobrevivir el cambio. Esa es Mariangela Guerra.<\/p>\n<p>Checa la charla completa y si eres de aquellos que todo el tiempo est\u00e1 en b\u00fasqueda de nuevos sonidos, Mariangela seguro te va a quitar el aliento&#8230;<\/p>\n<p><iframe loading=\"lazy\" title=\"Mariangela - Espacial (Official Video)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/PkFaYQ78lxc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><strong>Veo que eres una artista que todo el tiempo est\u00e1 creando y lo traduces en canciones desde cualquier lugar en el que est\u00e9s. Plat\u00edcame un poco de qu\u00e9 significa la m\u00fasica en tu vida y c\u00f3mo lleg\u00f3 a ti.<\/strong><\/p>\n<p>La verdad es que desde que estaba peque\u00f1a la m\u00fasica siempre me hab\u00eda gustado. Nunca pens\u00e9 que iba a dedicarme a eso porque no lo ve\u00eda posible. No tengo ning\u00fan contacto, no ten\u00eda nada, yo era de las que bailaba en su cuarto y cantaba y escuchaba m\u00fasica, pero jam\u00e1s pens\u00e9 que iba a ser cantante y compositora, no pasaba por mi cabeza.<\/p>\n<p>Me gustaba mucho escribir poemas y aprend\u00ed tocando la guitarra. Despu\u00e9s cuando empec\u00e9 ya con mi carrera, que fue cuando sub\u00ed un cover de una canci\u00f3n de Carla Morrison que se llama &#8216;Tu Luz&#8217; y que se viraliz\u00f3, mi manager me encontr\u00f3 y me dijo &#8216;Oye, nunca has pensado en escribir canciones?&#8217; Y yo, &#8216;Pues mira, muchacha intens\u00edsima&#8217;, porque soy s\u00faper intensa, &#8216;Que le gusta escribir, tocar la guitarra y me gusta cantar, pues no creo que sea tan dif\u00edcil componer mis propias canciones&#8217;.<\/p>\n<p>Cuando empec\u00e9 a componer, empec\u00e9 a hacerlo por necesidad, porque ya hab\u00eda una manera en la que yo pod\u00eda sacar mis emociones, ya sea l\u00edricamente, mel\u00f3dicamente, con mi guitarra, hasta con una progresi\u00f3n de guitarra y que pod\u00eda sonar a lo que yo sent\u00eda, me cambi\u00f3 completamente la vida ah\u00ed.<\/p>\n<p>Creo que lo que la m\u00fasica significa para m\u00ed, en resumidas palabras, es una necesidad. Es la \u00fanica manera que en la que s\u00e9 expresar lo que siento.<\/p>\n<p><strong>En tu Instagram vi un reel en el que la gente de otros pa\u00edses comparte contigo mensajes y te muestra que tu m\u00fasica llega hasta su ciudad. \u00bfQu\u00e9 se siente saber que alguien est\u00e1 escuchando tu m\u00fasica en Argentina y otra persona en Nueva York?<\/strong><\/p>\n<p>No es algo que pueda describir al 100, es un sentimiento extra\u00f1o como de emociones encontradas. Hay una parte de m\u00ed que al principio sent\u00eda un poquito de miedo porque era incierto, pero ahora siento que es emoci\u00f3n, con nostalgia, con orgullo, con felicidad, con demasiadas cosas.<\/p>\n<p>Literal algo por lo que trabajas, en mi caso tres a\u00f1os de encontrar sonidos que encajen con lo que estoy haciendo y despu\u00e9s sacarlo y que personas en Madrid lo escuchen, no s\u00e9, yo estoy en Texas \u00bfsabes? y tambi\u00e9n lo he visto en Colombia, que tambi\u00e9n es es un lugar donde me escuchan mucho, obviamente mi pa\u00eds, M\u00e9xico, donde yo nac\u00ed y crec\u00ed por casi diez a\u00f1os, es hermoso.<\/p>\n<p>Es un sentimiento muy gratificante el saber que mi coraz\u00f3n y una parte de mi donde yo fui tan vulnerable, pudo tocar a una persona que no me conoce, que no sabe nada de mi al otro lado del mundo.<\/p>\n<p><strong>\u00bfDe d\u00f3nde surge ese cari\u00f1o especial que le tienes a las baladas melanc\u00f3licas?<\/strong><\/p>\n<p>Es que siento que yo soy una persona bien intensa, entonces cuando me siento triste es una tristeza extrema y eso me ha llevado a cosas no muy bonitas como depresiones y ansiedades, tambi\u00e9n como a las cosas buenas, porque cuando yo me emociono o estoy feliz por algo, me emociono intensa, me acuerdo de las palabras de mi mam\u00e1 de &#8216;Mijita, tranquila, tranquila, rel\u00e1jate, respira&#8217;. Creo que esa es la esencia de las canciones, porque cuando eres una persona intensa, cuando est\u00e1s triste, sientes que se te cae el mundo hasta por las cosas que no necesariamente te pasan a ti.<\/p>\n<p>Es tan intenso lo que siento que es a trav\u00e9s de mis canciones y de las baladas melanc\u00f3licas que puedo externarlo. Por ejemplo la canci\u00f3n de &#8216;So\u00f1arte&#8217; es una canci\u00f3n que habla de una muerte, del fallecimiento de alguien que se fue a otro plano, pero es una canci\u00f3n con un ritmo muy up-beat, una canci\u00f3n estilo drum and bass y siento que la intensidad de la l\u00edrica profunda y melanc\u00f3lica y nost\u00e1lgica, viene de eso, de qui\u00e9n soy yo, porque s\u00ed me considero una mujer muy nost\u00e1lgica.<\/p>\n<p><iframe loading=\"lazy\" title=\"Mariangela - Abril (Official Video)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/4WhehH7Alyc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><strong>Cuando escucho tus canciones me doy cuenta de lo bella que puede ser la m\u00fasica cuando es sencilla y se basa en la voz. De hecho Kanye West dijo alguna vez que la voz es el mejor y el m\u00e1s avanzado instrumento musical. \u00bfCompartes algo de este pensamiento?<\/strong><\/p>\n<p>Totalmente. Hay canciones que no han escuchado todav\u00eda donde he tenido ideas de un solo de guitarra o cosas as\u00ed pero realmente con tu voz s\u00ed puedes hacer cosas maravillosas<\/p>\n<p>Tambi\u00e9n siento que depende mucho de la persona que lo escuche. Hay personas que son m\u00e1s m\u00fasica que letra o voz o la melod\u00eda de la voz o escuchan m\u00e1s lo de atr\u00e1s. Entonces no s\u00e9 si es cierto que es una pregunta muy subjetiva.<\/p>\n<p><strong>Los covers que has hecho en Tik Tok seguramente son importantes para ti por algo, pero en tu nuevo EP incluiste un single de Roberto Carlos que es \u2018Cama Y Mesa\u2019, supongo que este tema tiene un especial significado como para incluirlo en esta producci\u00f3n\u2026<\/strong><\/p>\n<p>F\u00edjate que es un tema muy especial para m\u00ed por una raz\u00f3n muy graciosa y s\u00faper inesperada. Roberto Carlos obviamente es un hombre con una trayectoria musical gigante y es una persona conocida alrededor del mundo, pero en especial yo sab\u00eda qui\u00e9n era porque mi pap\u00e1 se llama Carlos y mi hermano se llama Roberto, mi abuelito se llama Roberto y el pap\u00e1 de mi pap\u00e1 se llama Carlos, entonces me acuerdo cuando mi hermano estaba chiquito dec\u00eda &#8216;\u00bfC\u00f3mo te llamas?&#8217; y mi hermano dec\u00eda &#8216;Carlos Roberto&#8217;, y dec\u00eda &#8216;Ah, como Roberto Carlos por el rev\u00e9s&#8217;, entonces yo la pregunta a mi mam\u00e1 &#8216;\u00bfQui\u00e9n es Roberto Carlos?&#8217; de chiquita y entonces me pon\u00edan la canci\u00f3n y con eso ya sab\u00eda qui\u00e9n era.<\/p>\n<p>Cuando sub\u00ed el cover se lo ense\u00f1\u00e9 a mis pap\u00e1s antes de subirlo para pedir su opini\u00f3n porque soy muy cercana con mi familia y mi mam\u00e1 dijo &#8216;Ay qu\u00e9 bonito&#8217; y mi pap\u00e1 &#8216;Est\u00e1 muy bonito pero \u00bfPor qu\u00e9 esa canci\u00f3n? \u00bfNo quieres hacer algo m\u00e1s nuevo? Entonces lo subo y sin esperarlo en Tik Tok primero se hizo medio viral, como con 5 millones de vistas y luego la sub\u00ed a Instagram y pasaron unos 15 y me despierto y abro mi celular y no sabes la cantidad de notificaciones, los seguidores me subieron como 200 mil seguidores, el audio ten\u00eda muchos videos, me hab\u00edan hablado hasta artistas de que jam\u00e1s pensar\u00eda que encontrar\u00edan mi m\u00fasica, bien loco. Me llegaban correos diarios despu\u00e9s de que el cover se viraliz\u00f3 y ahorita en Tik Tok tiene 30 millones de de vistas en Instagram tiene 18 millones en YouTube tiene 1.5 millones de vistas, muy loco. Tambi\u00e9n me llegaban correos de &#8216;Mariangela por favor, s\u00fabelo a Spotify, Apple Music, YouTube Music, etc\u00e9tera, y entonces ya la hice parte del LP.<\/p>\n<p><strong>Llamaste a tu EP 4+1 y por ah\u00ed le\u00eda que el n\u00famero 4 siempre ha estado presente en tu vida. \u00bfMe puedes platicar un poco de qu\u00e9 se trata ese n\u00famero y qu\u00e9 significa para ti?<\/strong><\/p>\n<p>Yo nac\u00ed el 4 de abril, el 4 del 4, entonces desde que estaba chiquita siempre sent\u00ed que el n\u00famero cuatro me iba a acompa\u00f1ar desde el d\u00eda que nac\u00ed, literal estuvo conmigo. Soy muy creyente y muy supersticiosa y en varias ocasiones importantes el n\u00famero cuatro ha sido importante porque me han pasado cosas muy locas con \u00e9l y lo veo en todos lados. Hasta los departamentos de mis amigas son de que 404, 440, 004, es una locura y lo veo en todos lados.<\/p>\n<p>Sab\u00eda que ten\u00eda que hacer alguna canci\u00f3n, alg\u00fan EP o alg\u00fan disco que se llamara 4. Inicialmente nada m\u00e1s iban a salir las cuatro canciones que yo compuse, que son &#8216;Abril&#8217;, &#8216;Espacial&#8217;, &#8216;So\u00f1arte&#8217; e &#8216;Himalaya&#8217;, pero cuando pasa lo de Camilo S\u00e9ptimo se agreg\u00f3 una canci\u00f3n y pues ya no era 4 ahora era 4+1.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1328335 size-large\" src=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/01\/DSC02136-Edit-e1674774813494.jpg?w=1024\" alt=\"\" width=\"1024\" height=\"683\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 pasa cuando das todo sin esperar nada a cambio? Cuando el coraz\u00f3n manda y la creatividad rebasa todo l\u00edmite de tu ADN. Ese es el feeling que representa a Mariangela, la cantautora mexicana que est\u00e1 apoder\u00e1ndose de los charts y que ha trabajado casi artesanalmente una carrera que de a poco est\u00e1 subiendo como [&hellip;]<\/p>\n","protected":false},"author":195803851,"featured_media":1436890,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[51],"tags":[88,89,90],"class_list":["post-1436649","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-entretenimiento","tag-4-1","tag-entrevista","tag-mariangela","post_format-post-format-video","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Entrevista con Mariangela: Melancol\u00eda para sobrevivir el cambio - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entrevista con Mariangela: Melancol\u00eda para sobrevivir el cambio - Noticias\" \/>\n<meta property=\"og:description\" content=\"\u00bfQu\u00e9 pasa cuando das todo sin esperar nada a cambio? Cuando el coraz\u00f3n manda y la creatividad rebasa todo l\u00edmite de tu ADN. Ese es el feeling que representa a Mariangela, la cantautora mexicana que est\u00e1 apoder\u00e1ndose de los charts y que ha trabajado casi artesanalmente una carrera que de a poco est\u00e1 subiendo como [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-27T03:14:01+00:00\" \/>\n<meta name=\"author\" content=\"Eduardo Salinas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Salinas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/\"},\"author\":{\"name\":\"Eduardo Salinas\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\"},\"headline\":\"Entrevista con Mariangela: Melancol\u00eda para sobrevivir el cambio\",\"datePublished\":\"2023-01-27T03:14:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/\"},\"wordCount\":1707,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"4 + 1\",\"Entrevista\",\"Mariangela\"],\"articleSection\":[\"Entretenimiento\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/\",\"name\":\"Entrevista con Mariangela: Melancol\u00eda para sobrevivir el cambio - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2023-01-27T03:14:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entrevista con Mariangela: Melancol\u00eda para sobrevivir el cambio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\",\"name\":\"Eduardo Salinas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"caption\":\"Eduardo Salinas\"},\"sameAs\":[\"http:\/\/eduardo.salinas@entravision.com\"],\"url\":\"https:\/\/noticiasya.com\/corpus-christi\/author\/eduardosalinas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entrevista con Mariangela: Melancol\u00eda para sobrevivir el cambio - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/","og_locale":"es_ES","og_type":"article","og_title":"Entrevista con Mariangela: Melancol\u00eda para sobrevivir el cambio - Noticias","og_description":"\u00bfQu\u00e9 pasa cuando das todo sin esperar nada a cambio? Cuando el coraz\u00f3n manda y la creatividad rebasa todo l\u00edmite de tu ADN. Ese es el feeling que representa a Mariangela, la cantautora mexicana que est\u00e1 apoder\u00e1ndose de los charts y que ha trabajado casi artesanalmente una carrera que de a poco est\u00e1 subiendo como [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/","og_site_name":"Noticias","article_published_time":"2023-01-27T03:14:01+00:00","author":"Eduardo Salinas","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Eduardo Salinas","Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/"},"author":{"name":"Eduardo Salinas","@id":"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0"},"headline":"Entrevista con Mariangela: Melancol\u00eda para sobrevivir el cambio","datePublished":"2023-01-27T03:14:01+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/"},"wordCount":1707,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"image":{"@id":"https:\/\/noticiasya.com\/colorado\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/#primaryimage"},"thumbnailUrl":"","keywords":["4 + 1","Entrevista","Mariangela"],"articleSection":["Entretenimiento"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/","url":"https:\/\/noticiasya.com\/colorado\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/","name":"Entrevista con Mariangela: Melancol\u00eda para sobrevivir el cambio - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/#primaryimage"},"image":{"@id":"https:\/\/noticiasya.com\/colorado\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/#primaryimage"},"thumbnailUrl":"","datePublished":"2023-01-27T03:14:01+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/colorado\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Entrevista con Mariangela: Melancol\u00eda para sobrevivir el cambio"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0","name":"Eduardo Salinas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","caption":"Eduardo Salinas"},"sameAs":["http:\/\/eduardo.salinas@entravision.com"],"url":"https:\/\/noticiasya.com\/corpus-christi\/author\/eduardosalinas"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Entrevista con Mariangela: Melancol\u00eda para sobrevivir el cambio","url":"http:\/\/noticiasya.com\/corpus-christi\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Entretenimiento","author":[{"@type":"Person","name":"Eduardo Salinas"}],"creator":["Eduardo Salinas"],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":["4 + 1","entrevista","mariangela"],"dateCreated":"2023-01-27T03:14:01Z","datePublished":"2023-01-27T03:14:01Z","dateModified":"2023-01-27T03:14:01Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Entrevista con Mariangela: Melancol\\u00eda para sobrevivir el cambio\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2023\\\/01\\\/26\\\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2023\\\/01\\\/26\\\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Entretenimiento\",\"author\":[{\"@type\":\"Person\",\"name\":\"Eduardo Salinas\"}],\"creator\":[\"Eduardo Salinas\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[\"4 + 1\",\"entrevista\",\"mariangela\"],\"dateCreated\":\"2023-01-27T03:14:01Z\",\"datePublished\":\"2023-01-27T03:14:01Z\",\"dateModified\":\"2023-01-27T03:14:01Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1473201,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/04\/15\/zoe-saldana-wagner-moura-100-influyentes-time-orix\/","url_meta":{"origin":1436649,"position":0},"title":"Zoe Salda\u00f1a, Wagner Moura y Claudia Sheinbaum, entre las 100 personas m\u00e1s influyentes del mundo, seg\u00fan la revista TIME","author":"Eduardo Salinas","date":"abril 15, 2026","format":false,"excerpt":"La revista TIME dio a conocer este mi\u00e9rcoles su lista anual de las 100 personas m\u00e1s influyentes del mundo, en la que incluy\u00f3 a una decena de figuras de Iberoam\u00e9rica, entre las que destacan la presidenta de M\u00e9xico, Claudia Sheinbaum, y, retratados en portada el brasile\u00f1o Wagner Moura y la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450099,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/06\/04\/entrevista-con-maldita-vecindad-la-voz-es-nuestra-la-palabra-de-todos\/","url_meta":{"origin":1436649,"position":1},"title":"Entrevista con Maldita Vecindad: La voz es nuestra, la palabra de todos","author":"Eduardo Salinas","date":"junio 4, 2024","format":false,"excerpt":"\u00a1Quien diga que nunca ha escuchado a Maldita Vecindad est\u00e1 mintiendo! Cuando hab\u00eda represi\u00f3n, cuando la polic\u00eda persegu\u00eda a los j\u00f3venes, cuando la m\u00fasica era de delincuentes, cuando el pueblo era silenciado, cuando no hab\u00eda esperanza en las calles, en ese momento, en ese oscuro momento para M\u00e9xico, lleg\u00f3 La\u2026","rel":"","context":"In &quot;Entretenimiento&quot;","block_context":{"text":"Entretenimiento","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/entretenimiento"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2024\/06\/nota.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2024\/06\/nota.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2024\/06\/nota.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2024\/06\/nota.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1450860,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/07\/03\/entrevista-con-alex-fernandez-el-mas-virtuoso-de-los-fernandez\/","url_meta":{"origin":1436649,"position":2},"title":"Entrevista con Alex Fern\u00e1ndez: el m\u00e1s virtuoso de los Fern\u00e1ndez","author":"Eduardo Salinas","date":"julio 3, 2024","format":false,"excerpt":"Si quieres hablar de rancheras y mariachi, su influencia en la m\u00fasica, el cine, la moda y en general la cultura mexicana, s\u00ed o s\u00ed tienes que mencionar a la Dinast\u00eda Fern\u00e1ndez. Desde el abuelo, Don Vicente, aclamado por las ovaciones y nombrado por muchos como el mejor cantante de\u2026","rel":"","context":"In &quot;Entretenimiento&quot;","block_context":{"text":"Entretenimiento","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/entretenimiento"},"img":{"alt_text":"Entrevista con Alex Fern\u00e1ndez: el m\u00e1s virtuoso de los Fern\u00e1ndez","src":"https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2024\/07\/Sin-titulo-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2024\/07\/Sin-titulo-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2024\/07\/Sin-titulo-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2024\/07\/Sin-titulo-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1451420,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/07\/25\/entrevista-con-duplat-entre-teclas-y-nostalgia\/","url_meta":{"origin":1436649,"position":3},"title":"Entrevista con Duplat: Entre teclas y nostalgia","author":"Eduardo Salinas","date":"julio 25, 2024","format":false,"excerpt":"Me queda claro que Colombia no es solo reggaet\u00f3n, adem\u00e1s Bogot\u00e1 y Medell\u00edn no son lo mismo.\u00a0 Una ciudad oscura, lluviosa y por momentos gris, produce artistas magn\u00edficos, sobrados de talento. Y es que Duplat se volvi\u00f3 en una especie de obsesi\u00f3n desde que lo escuch\u00e9 por primera vez. Todo\u2026","rel":"","context":"In &quot;Entretenimiento&quot;","block_context":{"text":"Entretenimiento","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/entretenimiento"},"img":{"alt_text":"Entrevista con Duplat: Entre teclas y nostalgia","src":"https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2024\/07\/Sin-titulo-1-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2024\/07\/Sin-titulo-1-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2024\/07\/Sin-titulo-1-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2024\/07\/Sin-titulo-1-2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1439762,"url":"https:\/\/noticiasya.com\/corpus-christi\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/","url_meta":{"origin":1436649,"position":4},"title":"Entrevista con Raymix: La gente quiere bailar","author":"Eduardo Salinas","date":"julio 3, 2023","format":"video","excerpt":"Hacer una canci\u00f3n que suene en cada rinc\u00f3n del continente no es cosa f\u00e1cil, mucho menos hacer que esa canci\u00f3n de inicio a un nuevo g\u00e9nero musical y que ponga a bailar a todo aquel que la escuche en fiestas, bares, conciertos, tocadas y hasta en el transporte p\u00fablico. Eso\u2026","rel":"","context":"In &quot;Entretenimiento&quot;","block_context":{"text":"Entretenimiento","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/entretenimiento"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/07\/img15.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/07\/img15.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/07\/img15.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/07\/img15.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1465852,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/08\/25\/exprofesora-eeuu-compro-casa-italia-vida-mas-sencilla-trax\/","url_meta":{"origin":1436649,"position":5},"title":"Esta exprofesora de EE.UU. compr\u00f3 una casa, a precio de ganga, en un pueblo rural de Italia para vivir una vida m\u00e1s sencilla","author":"","date":"agosto 25, 2025","format":false,"excerpt":"Amelia Butler, originaria de EE.UU., anhelaba paz y tranquilidad despu\u00e9s de trabajar como maestra durante 20 a\u00f1os. Ella dice que comprar una casa a un precio de ganga en Italia le ha dado precisamente eso.Esta mujer de 57 a\u00f1os ahora pasa la mitad del a\u00f1o en el pueblo rural de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1436649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/users\/195803851"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1436649"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1436649\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1436649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1436649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1436649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}