{"id":1447081,"date":"2024-03-18T14:03:41","date_gmt":"2024-03-18T21:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/18\/que-es-sindrome-persona-rigida-diagnostico-sintomas-tratamiento-trax\/"},"modified":"2024-03-18T14:03:41","modified_gmt":"2024-03-18T21:03:41","slug":"que-es-sindrome-persona-rigida-diagnostico-sintomas-tratamiento-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/18\/que-es-sindrome-persona-rigida-diagnostico-sintomas-tratamiento-trax\/","title":{"rendered":"\u00bfQu\u00e9 es el s\u00edndrome de la persona r\u00edgida, cu\u00e1les son sus s\u00edntomas y c\u00f3mo se trata?"},"content":{"rendered":"<p>(CNN) &#8212; Celine Dion comparti\u00f3 en 2022 que le hab\u00edan diagnosticado el s\u00edndrome de la persona r\u00edgida (SPS, por sus siglas en ingl\u00e9s), una afecci\u00f3n neurol\u00f3gica rara que puede llevar a\u00f1os diagnosticar.<\/p>\n<p>El s\u00edndrome de la persona r\u00edgida se caracteriza por rigidez y espasmos musculares, mayor sensibilidad a est\u00edmulos como el sonido y las luces, y angustia emocional que puede causar espasmos musculares, seg\u00fan el Instituto Nacional de Trastornos Neurol\u00f3gicos y Accidentes Cerebrovasculares.<\/p>\n<p>\u201cCon frecuencia se asocia con espasmos musculares, que pueden ser bastante severos. Estos pueden causar ca\u00eddas, dolor severo y una discapacidad significativa\u201d, dijo el Dr. Emile Sami Moukheiber del Centro de S\u00edndrome de la Persona R\u00edgida en Johns Hopkins Medicine. \u201cLas ca\u00eddas por espasmos severos son muy comunes. Estos espasmos pueden ser precipitados por sobresaltos, emociones severas, clima fr\u00edo\u201d.<\/p>\n<p>Estos espasmos pueden ser lo suficientemente fuertes como para fracturar un hueso y cualquier ca\u00edda puede provocar lesiones graves.<\/p>\n<p>Dion dijo en un video que los espasmos afectan &#171;todos los aspectos&#187; de su vida diaria, &#171;a veces causando dificultades cuando camino y no permiti\u00e9ndome usar mis cuerdas vocales para cantar de la forma en que estoy acostumbrada&#187;.<\/p>\n<p>Los s\u00edntomas del s\u00edndrome tambi\u00e9n pueden causar ansiedad.<\/p>\n<p>\u201cMuchos pacientes, si no es que todos, tienen una ansiedad que es intr\u00ednseca a la enfermedad y esa ansiedad en realidad se alimenta de las dolencias f\u00edsicas de la enfermedad que las personas pueden tener\u201d, dijo en un comunicado el Dr. Scott Newsome, director del Centro de S\u00edndrome de la Persona R\u00edgida en un video del sitio web de la organizaci\u00f3n.<\/p>\n<p>\u00bfQui\u00e9n se ve afectado por el s\u00edndrome de la persona r\u00edgida?<\/p>\n<p>Justin Bieber explica la condici\u00f3n m\u00e9dica que padece 1:18<\/p>\n<p>La afecci\u00f3n afecta a alrededor de un mill\u00f3n de personas y la mayor\u00eda de los neur\u00f3logos generales ver\u00e1n solo uno o dos casos en su vida, dijo Moukheiber.<\/p>\n<p>El primer caso de s\u00edndrome de la persona r\u00edgida se inform\u00f3 en la d\u00e9cada de 1950, seg\u00fan Newsome, y la enfermedad hist\u00f3ricamente se denomin\u00f3 &#171;s\u00edndrome del hombre r\u00edgido&#187;.<\/p>\n<p>Desde entonces, se ha descubierto que afecta al doble de mujeres que de hombres y se cambi\u00f3 el nombre a s\u00edndrome de la persona r\u00edgida para evitar confusiones.<\/p>\n<p>\u00bfQu\u00e9 causa el s\u00edndrome de la persona r\u00edgida?<\/p>\n<p>Se cree que el s\u00edndrome de la persona r\u00edgida tiene caracter\u00edsticas de una enfermedad autoinmune, seg\u00fan el Instituto Nacional de Trastornos Neurol\u00f3gicos y Accidentes Cerebrovasculares.<\/p>\n<p>Aunque la causa exacta no est\u00e1 clara, seg\u00fan el instituto, \u201clas personas con SPS tienen niveles elevados de GAD, un anticuerpo que act\u00faa contra una enzima involucrada en la s\u00edntesis de un importante neurotransmisor en el cerebro\u201d.<\/p>\n<p>Debido a la rareza de la enfermedad y la ambig\u00fcedad de sus s\u00edntomas, las personas a menudo buscan atenci\u00f3n para el dolor cr\u00f3nico antes de recibir atenci\u00f3n neurol\u00f3gica. En promedio, toma alrededor de siete a\u00f1os para que alguien reciba un diagn\u00f3stico del s\u00edndrome de la persona r\u00edgida, dice Newsome.<\/p>\n<p>&#171;A veces, [los pacientes] son \u200b\u200betiquetados como locos&#187;, dijo, &#171;porque en el examen inicial, no hay las caracter\u00edsticas distintivas del s\u00edndrome de la persona r\u00edgida&#187;.<\/p>\n<p>\u00bfC\u00f3mo se trata el s\u00edndrome de la persona r\u00edgida?<\/p>\n<p>No existe una cura conocida para el s\u00edndrome de la persona r\u00edgida, pero los medicamentos pueden aliviar los s\u00edntomas. Los medicamentos de inmunoglobulina pueden ayudar a reducir la sensibilidad a los desencadenantes de luz o sonido, lo que podr\u00eda ayudar a evitar ca\u00eddas o espasmos.<\/p>\n<p>Los analg\u00e9sicos, los ansiol\u00edticos y los relajantes musculares pueden formar parte del tratamiento de esta enfermedad. El Centro del S\u00edndrome de la Persona R\u00edgida tambi\u00e9n utiliza inyecciones de toxina botul\u00ednica.<\/p>\n<p>\u201cSi no se trata, la enfermedad puede causar un deterioro grave de la vida diaria\u201d, dijo Moukheiber.<\/p>\n<p>Pero con tratamiento, los s\u00edntomas se pueden controlar.<\/p>\n<p>Dion, quien dijo que ha tenido problemas con su salud por un tiempo, dijo que tiene un gran equipo de profesionales m\u00e9dicos y el apoyo de sus hijos.<\/p>\n<p>\u201cEstoy trabajando arduamente con mi terapeuta de medicina deportiva todos los d\u00edas para recuperar mi fuerza y \u200b\u200b\u200b\u200bmi capacidad para rendir nuevamente\u201d, dijo. \u201cPero tengo que admitir que ha sido una lucha\u201d.<\/p>\n<p>Para una artista como Dion, los ruidos fuertes y las luces brillantes pueden desencadenar espasmos musculares.<\/p>\n<p>\u201cEsta es una enfermedad muy desafiante que podr\u00eda afectarla si no se trata de manera agresiva, oportuna y apropiada\u201d, dijo Moukheiber.<\/p>\n<p>Nota del editor: Este art\u00edculo fue publicado por primera vez en diciembre de 2022 y actualizado en marzo de 2024<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Celine Dion comparti\u00f3 en 2022 que le hab\u00edan diagnosticado el s\u00edndrome de la persona r\u00edgida (SPS, por sus siglas en ingl\u00e9s), una afecci\u00f3n neurol\u00f3gica rara que puede llevar a\u00f1os diagnosticar. El s\u00edndrome de la persona r\u00edgida se caracteriza por rigidez y espasmos musculares, mayor sensibilidad a est\u00edmulos como el sonido y las luces, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1447081","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQu\u00e9 es el s\u00edndrome de la persona r\u00edgida, cu\u00e1les son sus s\u00edntomas y c\u00f3mo se trata? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/03\/18\/que-es-sindrome-persona-rigida-diagnostico-sintomas-tratamiento-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 es el s\u00edndrome de la persona r\u00edgida, cu\u00e1les son sus s\u00edntomas y c\u00f3mo se trata? - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Celine Dion comparti\u00f3 en 2022 que le hab\u00edan diagnosticado el s\u00edndrome de la persona r\u00edgida (SPS, por sus siglas en ingl\u00e9s), una afecci\u00f3n neurol\u00f3gica rara que puede llevar a\u00f1os diagnosticar. El s\u00edndrome de la persona r\u00edgida se caracteriza por rigidez y espasmos musculares, mayor sensibilidad a est\u00edmulos como el sonido y las luces, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/03\/18\/que-es-sindrome-persona-rigida-diagnostico-sintomas-tratamiento-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-18T21:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/18\/que-es-sindrome-persona-rigida-diagnostico-sintomas-tratamiento-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/18\/que-es-sindrome-persona-rigida-diagnostico-sintomas-tratamiento-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfQu\u00e9 es el s\u00edndrome de la persona r\u00edgida, cu\u00e1les son sus s\u00edntomas y c\u00f3mo se trata?\",\"datePublished\":\"2024-03-18T21:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/18\/que-es-sindrome-persona-rigida-diagnostico-sintomas-tratamiento-trax\/\"},\"wordCount\":852,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/18\/que-es-sindrome-persona-rigida-diagnostico-sintomas-tratamiento-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/18\/que-es-sindrome-persona-rigida-diagnostico-sintomas-tratamiento-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/03\/18\/que-es-sindrome-persona-rigida-diagnostico-sintomas-tratamiento-trax\/\",\"name\":\"\u00bfQu\u00e9 es el s\u00edndrome de la persona r\u00edgida, cu\u00e1les son sus s\u00edntomas y c\u00f3mo se trata? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-18T21:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/18\/que-es-sindrome-persona-rigida-diagnostico-sintomas-tratamiento-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/18\/que-es-sindrome-persona-rigida-diagnostico-sintomas-tratamiento-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/18\/que-es-sindrome-persona-rigida-diagnostico-sintomas-tratamiento-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 es el s\u00edndrome de la persona r\u00edgida, cu\u00e1les son sus s\u00edntomas y c\u00f3mo se trata?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 es el s\u00edndrome de la persona r\u00edgida, cu\u00e1les son sus s\u00edntomas y c\u00f3mo se trata? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/03\/18\/que-es-sindrome-persona-rigida-diagnostico-sintomas-tratamiento-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 es el s\u00edndrome de la persona r\u00edgida, cu\u00e1les son sus s\u00edntomas y c\u00f3mo se trata? - Noticias","og_description":"(CNN) &#8212; Celine Dion comparti\u00f3 en 2022 que le hab\u00edan diagnosticado el s\u00edndrome de la persona r\u00edgida (SPS, por sus siglas en ingl\u00e9s), una afecci\u00f3n neurol\u00f3gica rara que puede llevar a\u00f1os diagnosticar. El s\u00edndrome de la persona r\u00edgida se caracteriza por rigidez y espasmos musculares, mayor sensibilidad a est\u00edmulos como el sonido y las luces, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/03\/18\/que-es-sindrome-persona-rigida-diagnostico-sintomas-tratamiento-trax\/","og_site_name":"Noticias","article_published_time":"2024-03-18T21:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/03\/18\/que-es-sindrome-persona-rigida-diagnostico-sintomas-tratamiento-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/03\/18\/que-es-sindrome-persona-rigida-diagnostico-sintomas-tratamiento-trax\/"},"author":{"name":"","@id":""},"headline":"\u00bfQu\u00e9 es el s\u00edndrome de la persona r\u00edgida, cu\u00e1les son sus s\u00edntomas y c\u00f3mo se trata?","datePublished":"2024-03-18T21:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/03\/18\/que-es-sindrome-persona-rigida-diagnostico-sintomas-tratamiento-trax\/"},"wordCount":852,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/03\/18\/que-es-sindrome-persona-rigida-diagnostico-sintomas-tratamiento-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/03\/18\/que-es-sindrome-persona-rigida-diagnostico-sintomas-tratamiento-trax\/","url":"https:\/\/noticiasya.com\/2024\/03\/18\/que-es-sindrome-persona-rigida-diagnostico-sintomas-tratamiento-trax\/","name":"\u00bfQu\u00e9 es el s\u00edndrome de la persona r\u00edgida, cu\u00e1les son sus s\u00edntomas y c\u00f3mo se trata? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-18T21:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/03\/18\/que-es-sindrome-persona-rigida-diagnostico-sintomas-tratamiento-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/03\/18\/que-es-sindrome-persona-rigida-diagnostico-sintomas-tratamiento-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/03\/18\/que-es-sindrome-persona-rigida-diagnostico-sintomas-tratamiento-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 es el s\u00edndrome de la persona r\u00edgida, cu\u00e1les son sus s\u00edntomas y c\u00f3mo se trata?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/18\/que-es-sindrome-persona-rigida-diagnostico-sintomas-tratamiento-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfQu\u00e9 es el s\u00edndrome de la persona r\u00edgida, cu\u00e1les son sus s\u00edntomas y c\u00f3mo se trata?","url":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/18\/que-es-sindrome-persona-rigida-diagnostico-sintomas-tratamiento-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/18\/que-es-sindrome-persona-rigida-diagnostico-sintomas-tratamiento-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-18T21:03:41Z","datePublished":"2024-03-18T21:03:41Z","dateModified":"2024-03-18T21:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfQu\\u00e9 es el s\\u00edndrome de la persona r\\u00edgida, cu\\u00e1les son sus s\\u00edntomas y c\\u00f3mo se trata?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/18\\\/que-es-sindrome-persona-rigida-diagnostico-sintomas-tratamiento-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/18\\\/que-es-sindrome-persona-rigida-diagnostico-sintomas-tratamiento-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-18T21:03:41Z\",\"datePublished\":\"2024-03-18T21:03:41Z\",\"dateModified\":\"2024-03-18T21:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1444952,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/02\/05\/celine-dion-padece-el-sindrome-de-la-persona-rigida-que-es-cuales-son-sus-sintomas-y-como-se-trata\/","url_meta":{"origin":1447081,"position":0},"title":"Celine Dion padece el s\u00edndrome de la persona r\u00edgida: \u00bfqu\u00e9 es, cu\u00e1les son sus s\u00edntomas y c\u00f3mo se trata?","author":"","date":"febrero 5, 2024","format":false,"excerpt":"(CNN) --\u00a0Celine Dion sorprendi\u00f3 el domingo con su aparici\u00f3n en los premios Grammy, donde present\u00f3 el premio al Album del a\u00f1o.Dion comparti\u00f3 en 2022 que le hab\u00edan diagnosticado el s\u00edndrome de la persona r\u00edgida (SPS, por sus siglas en ingl\u00e9s), una afecci\u00f3n neurol\u00f3gica rara que puede llevar a\u00f1os diagnosticar.El s\u00edndrome\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448431,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/04\/23\/celine-dion-vida-sindrome-persona-rigida-trax\/","url_meta":{"origin":1447081,"position":1},"title":"Celine Dion cuenta c\u00f3mo es su vida con el s\u00edndrome de la persona r\u00edgida: \u201cNada me va a detener\u201d","author":"","date":"abril 23, 2024","format":false,"excerpt":"(CNN) -- Celine Dion se sincer\u00f3 sobre c\u00f3mo es vivir con la rara enfermedad neurol\u00f3gica del S\u00edndrome de la Persona R\u00edgida y dijo: \"Nada me detendr\u00e1\".En una entrevista con Vogue France publicada este lunes, la cantante nacida en Canad\u00e1 dijo que estaba \"bien, pero es mucho trabajo\", y agreg\u00f3: \"Estoy\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450139,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/06\/07\/celine-dion-fracturado-costillas-cantar-sindrome-persona-rigida-trax\/","url_meta":{"origin":1447081,"position":2},"title":"Celine Dion dice que se ha fracturado costillas y le cuesta cantar a causa del raro s\u00edndrome de la persona r\u00edgida","author":"","date":"junio 7, 2024","format":false,"excerpt":"(CNN) -- Celine Dion comparti\u00f3 detalles sobre lo dif\u00edcil que se ha vuelto su vida debido a que padece el s\u00edndrome de la persona r\u00edgida.En un fragmento de una entrevista con Hoda Kotb de la NBC, la aclamada cantante revel\u00f3 que cuando intenta cantar es \"como si alguien te estuviera\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451456,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/07\/26\/celine-dion-dramatica-presentacion-inauguracion-juegos-olimpicos-paris-trax\/","url_meta":{"origin":1447081,"position":3},"title":"Celine Dion regresa al escenario para una dram\u00e1tica presentaci\u00f3n en la ceremonia de inauguraci\u00f3n de los Juegos Ol\u00edmpicos de Par\u00eds","author":"","date":"julio 26, 2024","format":false,"excerpt":"(CNN) -- Celine Dion regres\u00f3 a los escenarios en los Juegos Ol\u00edmpicos de Verano en Par\u00eds de manera verdaderamente grandiosa.La cantante cerr\u00f3 la ceremonia el viernes inmediatamente despu\u00e9s del encendido del pebetero ol\u00edmpico, con una actuaci\u00f3n desde el primer escenario de la Torre Eiffel, cantando un cl\u00e1sico: \u201cL\u2019Hymne \u00e0 l\u2019amour\u201d\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444978,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/02\/06\/ignoro-taylor-swift-a-celine-dion-en-los-grammy-las-fotos-tras-bambalinas-dicen-lo-contrario\/","url_meta":{"origin":1447081,"position":4},"title":"\u00bfIgnor\u00f3 Taylor Swift a Celine Dion en los Grammy? Las fotos tras bambalinas dicen lo contrario","author":"","date":"febrero 6, 2024","format":false,"excerpt":"(CNN) -- Terminar los Grammy 2024 con un tierno momento entre dos divas queridas \u2014Taylor Swift y Celine Dion\u2014 debi\u00f3 haber sido algo f\u00e1cil. Pero los espectadores resultaron divididos al final de la ceremonia.Cuando Dion, presentadora sorpresa, anunci\u00f3 que Swift era la ganadora en la categor\u00eda \u00c1lbum del A\u00f1o, la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473775,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/05\/04\/hantavirus-causas-sintomas-tratamiento-roedores-trax\/","url_meta":{"origin":1447081,"position":5},"title":"\u00bfQu\u00e9 es el hantavirus? Causas, s\u00edntomas y tratamiento de este virus transmitido por roedores","author":"","date":"mayo 4, 2026","format":false,"excerpt":"Se sospecha que el hantavirus, una enfermedad rara causada generalmente por la exposici\u00f3n a la orina o las heces de roedores infectados, es la causa de la muerte de tres personas a bordo de un crucero en el oc\u00e9ano Atl\u00e1ntico.Seg\u00fan la Organizaci\u00f3n Mundial de la Salud (OMS), se ha confirmado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1447081"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447081\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1447081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1447081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1447081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}