{"id":1447103,"date":"2024-03-18T17:03:47","date_gmt":"2024-03-19T00:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/18\/decenas-ciudadanos-estadounidenses-evacuan-haiti-trax\/"},"modified":"2024-03-18T17:03:47","modified_gmt":"2024-03-19T00:03:47","slug":"decenas-ciudadanos-estadounidenses-evacuan-haiti-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/18\/decenas-ciudadanos-estadounidenses-evacuan-haiti-trax\/","title":{"rendered":"Decenas de ciudadanos estadounidenses evacuan Hait\u00ed en el primer vuelo ch\u00e1rter del Departamento de Estado"},"content":{"rendered":"<p>(CNN) &#8212; Decenas de ciudadanos estadounidenses fueron evacuados de Hait\u00ed en un vuelo ch\u00e1rter del Departamento de Estado, y se espera que salgan potencialmente m\u00e1s, a medida que la naci\u00f3n caribe\u00f1a sigue paralizada por la escalada de violencia de pandillas y la inestabilidad pol\u00edtica que ha dejado las bulliciosas calles vac\u00edas y las necesidades como alimentos y gas escasean.<\/p>\n<p>El vuelo parti\u00f3 el domingo de Cabo Haitiano, en la costa norte de Hait\u00ed, y aterriz\u00f3 en el Aeropuerto Internacional de Miami, seg\u00fan inform\u00f3 el Departamento de Estado. M\u00e1s de 30 ciudadanos estadounidenses viajaban a bordo, y funcionarios del gobierno est\u00e1n ahora &#171;ayudando con los pr\u00f3ximos pasos&#187;, dijo un portavoz del Departamento de Estado.<\/p>\n<p>M\u00e1s de 16.000 personas abandonaron la capital de Hait\u00ed en una semana<\/p>\n<p>Por su parte, una organizaci\u00f3n sin fines de lucro con sede en Florida ha estado trabajando para rescatar de Hait\u00ed a docenas de estadounidenses y aliados, pero a\u00fan tiene en lista de espera a m\u00e1s de 100 personas que han pedido ayuda para salir del pa\u00eds. La misionera estadounidense Jill Dolan y su familia en Puerto Pr\u00edncipe se sienten &#171;como si nos estuvi\u00e9ramos hundiendo en arena r\u00e1pida&#187;, escribi\u00f3 su organizaci\u00f3n en una publicaci\u00f3n en Facebook el fin de semana. &#171;Sin embargo, estamos agradecidos de estar vivos&#187;.<\/p>\n<p>El Departamento de Estado seguir\u00e1 ayudando a los ciudadanos estadounidenses que buscan salir de Hait\u00ed, con un portavoz adjunto describiendo la &#171;situaci\u00f3n fluida y en r\u00e1pida evoluci\u00f3n sobre el terreno&#187;.<\/p>\n<p>&#171;Estaremos en contacto con ellos si se materializan medidas adicionales&#187;, dijo Vedant Patel el lunes en una rueda de prensa, a\u00f1adiendo que Hait\u00ed es ahora &#171;una de las situaciones humanitarias m\u00e1s graves del mundo&#187;.<\/p>\n<p>Project DYNAMO, un grupo internacional de b\u00fasqueda, rescate y ayuda sin fines de lucro, dirigido por veteranos y financiado por donantes, con sede en Tampa, ha recibido m\u00e1s de 100 solicitudes de evacuaci\u00f3n de estadounidenses en Hait\u00ed.<\/p>\n<p>&#171;Hemos sacado a un mont\u00f3n&#187; de un punto de Hait\u00ed m\u00e1s cercano a Cuba que a Puerto Pr\u00edncipe, dijo el fundador Bryan Stern a CNN el lunes por la tarde. &#171;Quer\u00edamos sacar m\u00e1s, pero tuvimos un problema de combustible&#8230; as\u00ed que realmente no quiero dar cifras porque es muy peligroso, es muy complicado&#187;.<\/p>\n<p>Milicias armadas con machetes luchan contra las pandillas en Puerto Pr\u00edncipe mientras las \u00e9lites de Hait\u00ed compiten por el poder<\/p>\n<p>La crisis en Hait\u00ed se intensific\u00f3 a principios de este mes cuando bandas rivales empezaron a causar estragos coordinados, seg\u00fan fuentes de seguridad. En Puerto Pr\u00edncipe, a m\u00e1s de 160 kil\u00f3metros de Cabo Haitiano, el aeropuerto cerr\u00f3 bajo el asedio de las bandas en medio de enfrentamientos con la polic\u00eda en los alrededores. Las bandas controlan ahora el 80% de Puerto Pr\u00edncipe, seg\u00fan estimaciones de la ONU, y est\u00e1n limitando gravemente el suministro de alimentos, combustible y agua en toda la ciudad.<\/p>\n<p>Las bandas han presionado para que dimita el primer ministro, Ariel Henry, quien la semana pasada dijo que dimitir\u00eda tras el establecimiento de un consejo de transici\u00f3n, cuya composici\u00f3n se espera que est\u00e9 finalizada &#171;tan pronto como hoy&#187;, dijo el lunes Patel, del Departamento de Estado.<\/p>\n<p>&#171;El anuncio de este consejo, creemos, ayudar\u00e1 a allanar el camino para unas elecciones libres y justas y el despliegue de la misi\u00f3n multinacional de apoyo a la seguridad&#187;, dijo.<\/p>\n<p>&#171;La situaci\u00f3n de seguridad en Hait\u00ed es impredecible y peligrosa&#187;, dijo el Departamento de Estado en un comunicado el s\u00e1bado anunciando el vuelo y advirtiendo del peligro en la ruta terrestre de Puerto Pr\u00edncipe a Cabo Haitiano.<\/p>\n<p>&#171;Le recomendamos que considere el vuelo a Cabo Haitiano solo si cree que puede llegar al aeropuerto de forma segura&#187;, dec\u00eda el comunicado. &#171;No podemos proporcionar viajes por tierra desde otras partes de Hait\u00ed a Cabo Haitiano&#187;.<\/p>\n<p>Saquean contenedor de la ONU con suministros m\u00e9dicos para reci\u00e9n nacidos y madres en Puerto Pr\u00edncipe mientras se profundiza la crisis en Hait\u00ed<\/p>\n<p>&#171;Necesitamos mucho la ayuda de la gente&#187;<\/p>\n<p>Con el peligro en pr\u00e1cticamente todas las calles de Puerto Pr\u00edncipe, Dolan y sus familiares se esconden en una casa de hu\u00e9spedes cerca del aeropuerto cerrado, inform\u00f3 WPTV, afiliada de CNN. La familia tambi\u00e9n ha documentado su experiencia en l\u00ednea a trav\u00e9s de su organizaci\u00f3n sin fines de lucro, Love A Neighbor, que supervisa un orfanato, un hogar de ancianos y un proyecto de preservaci\u00f3n de la familia en las zonas rurales de Hait\u00ed.<\/p>\n<p>&#171;O\u00edmos muchos disparos, generalmente por la noche&#187;, dijo a WPTV. &#171;O\u00edmos muchas cosas. Sin embargo, ayer hubo muchos durante el d\u00eda. As\u00ed que nunca se sabe&#187;.<\/p>\n<p>Una de las hijas de Dolan planea casarse a finales de este mes en Florida, por lo que el resto de la familia reserv\u00f3 pasajes para ir a EE.UU. semanas antes de que la violencia se intensificara en Hait\u00ed, dijo a la estaci\u00f3n. Como la mayor\u00eda de las compa\u00f1\u00edas a\u00e9reas han suspendido los vuelos desde y hacia el pa\u00eds, esos pasajes no se utilizaron, explic\u00f3.<\/p>\n<p>Con su lista de espera de hasta tres d\u00edgitos de personas que necesitan ser rescatadas de Hait\u00ed, Project DYNAMO necesita m\u00e1s dinero para recursos, dijo Stern, a\u00f1adiendo que sin fondos, sus manos est\u00e1n atadas.<\/p>\n<p>&#171;Necesitamos la ayuda de la gente, y la necesitamos mucho&#187;, dijo. &#171;Algunas de estas personas est\u00e1n en circunstancias extremadamente terribles, y podemos hacerlo. Solo necesito ayuda con recursos&#187;.<\/p>\n<p>&#8212; Esta es una noticia en desarrollo y ser\u00e1 actualizada. Michael Conte de CNN contribuy\u00f3 con este reportaje.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Decenas de ciudadanos estadounidenses fueron evacuados de Hait\u00ed en un vuelo ch\u00e1rter del Departamento de Estado, y se espera que salgan potencialmente m\u00e1s, a medida que la naci\u00f3n caribe\u00f1a sigue paralizada por la escalada de violencia de pandillas y la inestabilidad pol\u00edtica que ha dejado las bulliciosas calles vac\u00edas y las necesidades como [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1447103","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Decenas de ciudadanos estadounidenses evacuan Hait\u00ed en el primer vuelo ch\u00e1rter del Departamento de Estado - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/03\/18\/decenas-ciudadanos-estadounidenses-evacuan-haiti-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Decenas de ciudadanos estadounidenses evacuan Hait\u00ed en el primer vuelo ch\u00e1rter del Departamento de Estado - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Decenas de ciudadanos estadounidenses fueron evacuados de Hait\u00ed en un vuelo ch\u00e1rter del Departamento de Estado, y se espera que salgan potencialmente m\u00e1s, a medida que la naci\u00f3n caribe\u00f1a sigue paralizada por la escalada de violencia de pandillas y la inestabilidad pol\u00edtica que ha dejado las bulliciosas calles vac\u00edas y las necesidades como [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/03\/18\/decenas-ciudadanos-estadounidenses-evacuan-haiti-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-19T00:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/18\/decenas-ciudadanos-estadounidenses-evacuan-haiti-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/18\/decenas-ciudadanos-estadounidenses-evacuan-haiti-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Decenas de ciudadanos estadounidenses evacuan Hait\u00ed en el primer vuelo ch\u00e1rter del Departamento de Estado\",\"datePublished\":\"2024-03-19T00:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/18\/decenas-ciudadanos-estadounidenses-evacuan-haiti-trax\/\"},\"wordCount\":993,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/18\/decenas-ciudadanos-estadounidenses-evacuan-haiti-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/18\/decenas-ciudadanos-estadounidenses-evacuan-haiti-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/03\/18\/decenas-ciudadanos-estadounidenses-evacuan-haiti-trax\/\",\"name\":\"Decenas de ciudadanos estadounidenses evacuan Hait\u00ed en el primer vuelo ch\u00e1rter del Departamento de Estado - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-19T00:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/18\/decenas-ciudadanos-estadounidenses-evacuan-haiti-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/18\/decenas-ciudadanos-estadounidenses-evacuan-haiti-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/18\/decenas-ciudadanos-estadounidenses-evacuan-haiti-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Decenas de ciudadanos estadounidenses evacuan Hait\u00ed en el primer vuelo ch\u00e1rter del Departamento de Estado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Decenas de ciudadanos estadounidenses evacuan Hait\u00ed en el primer vuelo ch\u00e1rter del Departamento de Estado - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/03\/18\/decenas-ciudadanos-estadounidenses-evacuan-haiti-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Decenas de ciudadanos estadounidenses evacuan Hait\u00ed en el primer vuelo ch\u00e1rter del Departamento de Estado - Noticias","og_description":"(CNN) &#8212; Decenas de ciudadanos estadounidenses fueron evacuados de Hait\u00ed en un vuelo ch\u00e1rter del Departamento de Estado, y se espera que salgan potencialmente m\u00e1s, a medida que la naci\u00f3n caribe\u00f1a sigue paralizada por la escalada de violencia de pandillas y la inestabilidad pol\u00edtica que ha dejado las bulliciosas calles vac\u00edas y las necesidades como [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/03\/18\/decenas-ciudadanos-estadounidenses-evacuan-haiti-trax\/","og_site_name":"Noticias","article_published_time":"2024-03-19T00:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/03\/18\/decenas-ciudadanos-estadounidenses-evacuan-haiti-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/03\/18\/decenas-ciudadanos-estadounidenses-evacuan-haiti-trax\/"},"author":{"name":"","@id":""},"headline":"Decenas de ciudadanos estadounidenses evacuan Hait\u00ed en el primer vuelo ch\u00e1rter del Departamento de Estado","datePublished":"2024-03-19T00:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/03\/18\/decenas-ciudadanos-estadounidenses-evacuan-haiti-trax\/"},"wordCount":993,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/03\/18\/decenas-ciudadanos-estadounidenses-evacuan-haiti-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/03\/18\/decenas-ciudadanos-estadounidenses-evacuan-haiti-trax\/","url":"https:\/\/noticiasya.com\/2024\/03\/18\/decenas-ciudadanos-estadounidenses-evacuan-haiti-trax\/","name":"Decenas de ciudadanos estadounidenses evacuan Hait\u00ed en el primer vuelo ch\u00e1rter del Departamento de Estado - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-19T00:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/03\/18\/decenas-ciudadanos-estadounidenses-evacuan-haiti-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/03\/18\/decenas-ciudadanos-estadounidenses-evacuan-haiti-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/03\/18\/decenas-ciudadanos-estadounidenses-evacuan-haiti-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Decenas de ciudadanos estadounidenses evacuan Hait\u00ed en el primer vuelo ch\u00e1rter del Departamento de Estado"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/18\/decenas-ciudadanos-estadounidenses-evacuan-haiti-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Decenas de ciudadanos estadounidenses evacuan Hait\u00ed en el primer vuelo ch\u00e1rter del Departamento de Estado","url":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/18\/decenas-ciudadanos-estadounidenses-evacuan-haiti-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/18\/decenas-ciudadanos-estadounidenses-evacuan-haiti-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-19T00:03:47Z","datePublished":"2024-03-19T00:03:47Z","dateModified":"2024-03-19T00:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Decenas de ciudadanos estadounidenses evacuan Hait\\u00ed en el primer vuelo ch\\u00e1rter del Departamento de Estado\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/18\\\/decenas-ciudadanos-estadounidenses-evacuan-haiti-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/18\\\/decenas-ciudadanos-estadounidenses-evacuan-haiti-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-19T00:03:47Z\",\"datePublished\":\"2024-03-19T00:03:47Z\",\"dateModified\":\"2024-03-19T00:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1447162,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/20\/estadounidenses-evacuan-haiti-helicoptero-trax\/","url_meta":{"origin":1447103,"position":0},"title":"M\u00e1s estadounidenses evacuan Hait\u00ed en un vuelo en helic\u00f3ptero de EE.UU. Se esperan &#171;m\u00faltiples&#187; viajes, seg\u00fan el Departamento de Estado","author":"","date":"marzo 20, 2024","format":false,"excerpt":"(CNN) -- Otro grupo de estadounidenses fue evacuado el mi\u00e9rcoles de Hait\u00ed en un vuelo organizado por Estados Unidos en helic\u00f3ptero, el m\u00e1s reciente de lo que el Departamento de Estado espera que sean \"m\u00faltiples viajes\" para sacar sanos y salvos a ciudadanos estadounidenses mientras la naci\u00f3n caribe\u00f1a se hunde\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447378,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/26\/avion-estadounidenses-evacuados-haiti-florida-trax\/","url_meta":{"origin":1447103,"position":1},"title":"Aterriz\u00f3 en Florida otro avi\u00f3n con ciudadanos estadounidenses que fueron evacuados de Hait\u00ed","author":"","date":"marzo 26, 2024","format":false,"excerpt":"(CNN) -- Un avi\u00f3n que transport\u00f3 a 21 estadounidenses que salieron de Hait\u00ed lleg\u00f3 a Orlando, Florida, el s\u00e1bado por la noche, el m\u00e1s reciente de una serie de vuelos fletados por Estados Unidos desde la asediada naci\u00f3n caribe\u00f1a, que se encuentra en caos en medio de una rampante violencia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447135,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/19\/crisis-violencia-haiti-pareja-indiana-evacuar-adolescentes-adoptaron-trax\/","url_meta":{"origin":1447103,"position":2},"title":"Cientos de estadounidenses viven en Hait\u00ed en medio de la violencia. Una pareja de Indiana est\u00e1 tratando desesperadamente de evacuar a dos adolescentes que adoptaron","author":"","date":"marzo 19, 2024","format":false,"excerpt":"(CNN) -- Ha pasado m\u00e1s de una semana desde que Missy y John Tennant hablaron con los dos chicos adolescentes en Hait\u00ed que adoptaron recientemente.Los chicos, de 13 y 15 a\u00f1os, est\u00e1n atrapados en el pa\u00eds caribe\u00f1o, escondidos con otros ni\u00f1os dentro de un orfanato rodeado de violencia de pandillas,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447377,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/26\/eeuu-haiti-santo-domingo-evacuados-orix\/","url_meta":{"origin":1447103,"position":3},"title":"EE.UU. ha evacuado de Hait\u00ed a Santo Domingo a 160 estadounidenses desde el 17 de marzo","author":"","date":"marzo 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El Departamento de Estado de Estados Unidos dijo este jueves a CNN que desde el 17 de marzo han evacuado de Hait\u00ed a Santo Domingo, Rep\u00fablica Dominicana, a m\u00e1s de 160 ciudadanos estadounidenses.Los vuelos organizados por el gobierno de Estados Unidos para sacar a sus ciudadanos, en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449864,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/05\/30\/ee-uu-negocia-pandilla-asegurar-cuerpos-misioneros-asesinados-haiti-trax\/","url_meta":{"origin":1447103,"position":4},"title":"Exclusiva: EE.UU. negocia con una pandilla para asegurar los cuerpos de los misioneros estadounidenses asesinados en Hait\u00ed","author":"","date":"mayo 30, 2024","format":false,"excerpt":"(CNN) -- El primer vuelo comercial de Estados Unidos a Hait\u00ed en meses realiz\u00f3 un sombr\u00edo viaje de ida y vuelta este jueves, regresando con los cuerpos de una joven pareja estadounidense asesinada por una pandilla en Puerto Pr\u00edncipe la semana pasada.Los restos de Davy y Natalie Lloyd fueron acompa\u00f1ados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447115,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/19\/exmarine-boyce-young-varado-haiti-trax\/","url_meta":{"origin":1447103,"position":5},"title":"Una familia trabaja para traer a casa a un exmarine estadounidense varado en Hait\u00ed durante m\u00e1s de dos semanas","author":"","date":"marzo 19, 2024","format":false,"excerpt":"(CNN) -- El estadounidense Boyce Young se encuentra varado en Hait\u00ed durante m\u00e1s de dos semanas y su hija le dijo a CNN que su familia hace todo lo posible para traerlo a casa.El exmarine de 75 a\u00f1os lleg\u00f3 a Hait\u00ed el 15 de febrero para realizar algunas tareas de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1447103"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447103\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1447103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1447103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1447103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}