{"id":1447161,"date":"2024-03-20T18:03:43","date_gmt":"2024-03-21T01:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/20\/defensa-genaro-garcia-luna-vuelve-pedir-la-anulacion-veredicto-orix\/"},"modified":"2024-03-20T18:03:43","modified_gmt":"2024-03-21T01:03:43","slug":"defensa-genaro-garcia-luna-vuelve-pedir-la-anulacion-veredicto-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/20\/defensa-genaro-garcia-luna-vuelve-pedir-la-anulacion-veredicto-orix\/","title":{"rendered":"La defensa de Genaro Garc\u00eda Luna vuelve a pedir la anulaci\u00f3n del veredicto que lo conden\u00f3"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0La defensa de Genaro Garc\u00eda Luna present\u00f3 este martes una nueva moci\u00f3n para insistir que se anule el juicio que conden\u00f3 al exsecretario de Seguridad Ciudadana de M\u00e9xico en Estados Unidos, seg\u00fan los documentos judiciales a los que tuvo acceso CNN.<\/p>\n<p>En su solicitud al juez federal Brian Cogan, los abogados de Garc\u00eda Luna piden que se declare nulo el veredicto de culpabilidad y ordene un nuevo juicio, luego de que a principios de mes la Fiscal\u00eda presentara una respuesta oponi\u00e9ndose a esa solicitud.<\/p>\n<p>En febrero de 2023, un juicio llevado a cabo en Estados Unidos declar\u00f3 culpable al exfuncionario de varios delitos relacionados con narcotr\u00e1fico. Su sentencia a\u00fan no ha sido anunciada, pero Garc\u00eda Luna podr\u00eda recibir una pena de entre 20 a\u00f1os a cadena perpetua.<\/p>\n<p>En diciembre del a\u00f1o pasado, los abogados de Garc\u00eda Luna presentaron una moci\u00f3n en la que aseguraron que desde que se dio a conocer el veredicto del jurado han salido a relucir nuevas pruebas que ser\u00edan favorables para su cliente que, en su criterio, podr\u00edan desmoronar el caso presentado por la Fiscal\u00eda.<\/p>\n<p>La defensa de Genaro Garc\u00eda Luna solicita la anulaci\u00f3n del veredicto que lo conden\u00f3 y pide un nuevo juicio<\/p>\n<p>En el documento de 56 p\u00e1ginas presentado en la Corte del Distrito Este de Nueva York, los abogados de Garc\u00eda Luna afirmaban que pod\u00edan demostrar que varios testigos clave de la Fiscal\u00eda hicieron declaraciones falsas en su testimonio, y que durante el proceso la Fiscal\u00eda habr\u00eda violado la jurisprudencia contenida en el caso Brady vs. Maryland, seg\u00fan la cual la supresi\u00f3n de la evidencia que podr\u00eda favorecer a un acusado constituye una violaci\u00f3n al debido proceso.<\/p>\n<p>En su respuesta este 1 de marzo, los fiscales acusaron a Garc\u00eda Luna de intentar sobornar con US$ 2 millones a sus compa\u00f1eros de prisi\u00f3n a cambio de dar declaraciones falsas y de testificar a su favor. Tambi\u00e9n argumentan que las supuestas nuevas pruebas de la defensa eran conocidas o deber\u00edan de haber sido conocidas por el acusado antes del juicio.<\/p>\n<p>\u201cEl Tribunal deber\u00eda rechazar el argumento de la defensa sobre la colusi\u00f3n de testigos, que es producto de un plan corrupto para sobornar el perjurio y obstruir la justicia. En concreto, la investigaci\u00f3n del Gobierno ha revelado pruebas convincentes de un complot del acusado para obtener declaraciones juradas falsas y falso testimonio para su nueva moci\u00f3n de juicio al ofrecer dinero y otros incentivos a los reclusos en el Centro de Detenci\u00f3n Metropolitano de Brooklyn\u201d, se lee en la moci\u00f3n de la Fiscal\u00eda.<\/p>\n<p>El juez le dio a la defensa otra oportunidad para responder antes de tomar una decisi\u00f3n. El magistrado podr\u00eda programar una fecha para escuchar argumentos o emitir su decisi\u00f3n por escrito. No est\u00e1 claro cu\u00e1ndo llegar\u00eda la decisi\u00f3n del juez Cogan, quien a\u00fan tiene programado anunciar la sentencia el 24 de junio.<\/p>\n<p>\u00bfQui\u00e9n es Genaro Garc\u00eda Luna?<\/p>\n<p>Garc\u00eda Luna, que durante una d\u00e9cada se desempe\u00f1\u00f3 como jefe de la ahora disuelta Agencia Federal de Investigaci\u00f3n de M\u00e9xico, equivalente al FBI, fue arrestado el 9 de diciembre de 2019 en Dallas y acusado de narcotr\u00e1fico y de aceptar sobornos millonarios del C\u00e1rtel de Sinaloa, liderado en ese entonces por Joaqu\u00edn \u201cEl Chapo\u201d Guzm\u00e1n.<\/p>\n<p>La fiscal\u00eda argument\u00f3 que, a cambio de dinero, Garc\u00eda Luna permiti\u00f3 que el C\u00e1rtel de Sinaloa operara con impunidad en M\u00e9xico y ayud\u00f3 a los traficantes a transportar drogas de manera segura y sin la intervenci\u00f3n de las fuerzas de la ley hacia Estados Unidos, y que incluso llev\u00f3 a cabo ataques contra carteles rivales.<\/p>\n<p>El exfuncionario enfrentaba varios cargos de participaci\u00f3n en una empresa criminal continua y otros de conspiraci\u00f3n para obtener, importar y distribuir miles de kilogramos de coca\u00edna en EE.UU., adem\u00e1s de presuntamente haber hecho declaraciones falsas a funcionarios estadounidenses de inmigraci\u00f3n.<\/p>\n<p>Garc\u00eda Luna se ha declarado inocente de todos los cargos.<\/p>\n<p>Con informaci\u00f3n de Mar\u00eda Santana<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0La defensa de Genaro Garc\u00eda Luna present\u00f3 este martes una nueva moci\u00f3n para insistir que se anule el juicio que conden\u00f3 al exsecretario de Seguridad Ciudadana de M\u00e9xico en Estados Unidos, seg\u00fan los documentos judiciales a los que tuvo acceso CNN. En su solicitud al juez federal Brian Cogan, los abogados de Garc\u00eda [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1447161","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La defensa de Genaro Garc\u00eda Luna vuelve a pedir la anulaci\u00f3n del veredicto que lo conden\u00f3 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/03\/20\/defensa-genaro-garcia-luna-vuelve-pedir-la-anulacion-veredicto-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La defensa de Genaro Garc\u00eda Luna vuelve a pedir la anulaci\u00f3n del veredicto que lo conden\u00f3 - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212;\u00a0La defensa de Genaro Garc\u00eda Luna present\u00f3 este martes una nueva moci\u00f3n para insistir que se anule el juicio que conden\u00f3 al exsecretario de Seguridad Ciudadana de M\u00e9xico en Estados Unidos, seg\u00fan los documentos judiciales a los que tuvo acceso CNN. En su solicitud al juez federal Brian Cogan, los abogados de Garc\u00eda [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/03\/20\/defensa-genaro-garcia-luna-vuelve-pedir-la-anulacion-veredicto-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-21T01:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/20\/defensa-genaro-garcia-luna-vuelve-pedir-la-anulacion-veredicto-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/20\/defensa-genaro-garcia-luna-vuelve-pedir-la-anulacion-veredicto-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La defensa de Genaro Garc\u00eda Luna vuelve a pedir la anulaci\u00f3n del veredicto que lo conden\u00f3\",\"datePublished\":\"2024-03-21T01:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/20\/defensa-genaro-garcia-luna-vuelve-pedir-la-anulacion-veredicto-orix\/\"},\"wordCount\":743,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/20\/defensa-genaro-garcia-luna-vuelve-pedir-la-anulacion-veredicto-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/20\/defensa-genaro-garcia-luna-vuelve-pedir-la-anulacion-veredicto-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/03\/20\/defensa-genaro-garcia-luna-vuelve-pedir-la-anulacion-veredicto-orix\/\",\"name\":\"La defensa de Genaro Garc\u00eda Luna vuelve a pedir la anulaci\u00f3n del veredicto que lo conden\u00f3 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-21T01:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/20\/defensa-genaro-garcia-luna-vuelve-pedir-la-anulacion-veredicto-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/20\/defensa-genaro-garcia-luna-vuelve-pedir-la-anulacion-veredicto-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/20\/defensa-genaro-garcia-luna-vuelve-pedir-la-anulacion-veredicto-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La defensa de Genaro Garc\u00eda Luna vuelve a pedir la anulaci\u00f3n del veredicto que lo conden\u00f3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La defensa de Genaro Garc\u00eda Luna vuelve a pedir la anulaci\u00f3n del veredicto que lo conden\u00f3 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/03\/20\/defensa-genaro-garcia-luna-vuelve-pedir-la-anulacion-veredicto-orix\/","og_locale":"es_ES","og_type":"article","og_title":"La defensa de Genaro Garc\u00eda Luna vuelve a pedir la anulaci\u00f3n del veredicto que lo conden\u00f3 - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212;\u00a0La defensa de Genaro Garc\u00eda Luna present\u00f3 este martes una nueva moci\u00f3n para insistir que se anule el juicio que conden\u00f3 al exsecretario de Seguridad Ciudadana de M\u00e9xico en Estados Unidos, seg\u00fan los documentos judiciales a los que tuvo acceso CNN. En su solicitud al juez federal Brian Cogan, los abogados de Garc\u00eda [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/03\/20\/defensa-genaro-garcia-luna-vuelve-pedir-la-anulacion-veredicto-orix\/","og_site_name":"Noticias","article_published_time":"2024-03-21T01:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/03\/20\/defensa-genaro-garcia-luna-vuelve-pedir-la-anulacion-veredicto-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/03\/20\/defensa-genaro-garcia-luna-vuelve-pedir-la-anulacion-veredicto-orix\/"},"author":{"name":"","@id":""},"headline":"La defensa de Genaro Garc\u00eda Luna vuelve a pedir la anulaci\u00f3n del veredicto que lo conden\u00f3","datePublished":"2024-03-21T01:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/03\/20\/defensa-genaro-garcia-luna-vuelve-pedir-la-anulacion-veredicto-orix\/"},"wordCount":743,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/03\/20\/defensa-genaro-garcia-luna-vuelve-pedir-la-anulacion-veredicto-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/03\/20\/defensa-genaro-garcia-luna-vuelve-pedir-la-anulacion-veredicto-orix\/","url":"https:\/\/noticiasya.com\/2024\/03\/20\/defensa-genaro-garcia-luna-vuelve-pedir-la-anulacion-veredicto-orix\/","name":"La defensa de Genaro Garc\u00eda Luna vuelve a pedir la anulaci\u00f3n del veredicto que lo conden\u00f3 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-21T01:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/03\/20\/defensa-genaro-garcia-luna-vuelve-pedir-la-anulacion-veredicto-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/03\/20\/defensa-genaro-garcia-luna-vuelve-pedir-la-anulacion-veredicto-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/03\/20\/defensa-genaro-garcia-luna-vuelve-pedir-la-anulacion-veredicto-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La defensa de Genaro Garc\u00eda Luna vuelve a pedir la anulaci\u00f3n del veredicto que lo conden\u00f3"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/20\/defensa-genaro-garcia-luna-vuelve-pedir-la-anulacion-veredicto-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La defensa de Genaro Garc\u00eda Luna vuelve a pedir la anulaci\u00f3n del veredicto que lo conden\u00f3","url":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/20\/defensa-genaro-garcia-luna-vuelve-pedir-la-anulacion-veredicto-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/20\/defensa-genaro-garcia-luna-vuelve-pedir-la-anulacion-veredicto-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-21T01:03:43Z","datePublished":"2024-03-21T01:03:43Z","dateModified":"2024-03-21T01:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La defensa de Genaro Garc\\u00eda Luna vuelve a pedir la anulaci\\u00f3n del veredicto que lo conden\\u00f3\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/20\\\/defensa-genaro-garcia-luna-vuelve-pedir-la-anulacion-veredicto-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/20\\\/defensa-genaro-garcia-luna-vuelve-pedir-la-anulacion-veredicto-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-21T01:03:43Z\",\"datePublished\":\"2024-03-21T01:03:43Z\",\"dateModified\":\"2024-03-21T01:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1452863,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/09\/19\/solicitan-ee-uu-cadena-perpetua-multa-millonaria-garcia-luna-orix\/","url_meta":{"origin":1447161,"position":0},"title":"Solicitan en EE.UU. cadena perpetua y multa millonaria contra Genaro Garc\u00eda Luna","author":"","date":"septiembre 19, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El Departamento de Justicia de Estados Unidos solicit\u00f3 este jueves cadena perpetua y una multa de US$ 5 millones para el exsecretario de Seguridad P\u00fablica de M\u00e9xico Genaro Garc\u00eda Luna, declarado culpable por delitos relacionados con narcotr\u00e1fico.El documento enviado a la corte del Distrito Este de Nueva\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452779,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/09\/17\/garcia-luna-carta-acuerdo-fiscalia-nueva-york-culpabilidad-politicos-mexicanos-orix\/","url_meta":{"origin":1447161,"position":1},"title":"Garc\u00eda Luna dice que la Fiscal\u00eda de Nueva York le ofreci\u00f3 un acuerdo de culpabilidad a cambio de se\u00f1alar a pol\u00edticos mexicanos, pero no acept\u00f3","author":"","date":"septiembre 17, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Genaro Garc\u00eda Luna, exsecretario de Seguridad P\u00fablica de M\u00e9xico entre 2006 y 2012, revel\u00f3 que la Fiscal\u00eda de Nueva York le propuso aceptar un acuerdo de culpabilidad que supondr\u00eda pasar en prisi\u00f3n seis meses, obtener beneficios econ\u00f3micos y convertirse en testigo para se\u00f1alar a personas e instituciones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455121,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/10\/15\/genaro-garcia-luna-clemencia-al-juez-antes-sentencia-orix\/","url_meta":{"origin":1447161,"position":2},"title":"Genaro Garc\u00eda Luna pide clemencia al juez un d\u00eda antes de su sentencia","author":"","date":"octubre 15, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Genaro Garc\u00eda Luna, secretario de Seguridad P\u00fablica de M\u00e9xico durante la presidencia de Felipe Calder\u00f3n y juzgado en Estados Unidos por cargos de narcotr\u00e1fico y v\u00ednculos con la delincuencia organizada, pidi\u00f3 este martes clemencia al juez Brian Cogan, que dar\u00e1 sentencia de su caso.A un d\u00eda de su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455189,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/10\/17\/condena-genaro-garcia-luna-anios-prision-orix\/","url_meta":{"origin":1447161,"position":3},"title":"Una \u201cdoble vida\u201d y la comparaci\u00f3n con el Chapo Guzm\u00e1n: detr\u00e1s de la condena de Garc\u00eda Luna a m\u00e1s de 38 a\u00f1os de prisi\u00f3n","author":"","date":"octubre 17, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Cuando el juez Brian Cogan conden\u00f3 al exsecretario de Seguridad P\u00fablica de M\u00e9xico, Genaro Garc\u00eda Luna, a 460 meses de c\u00e1rcel (m\u00e1s de 38 a\u00f1os de prisi\u00f3n), una multa de US$ 2 millones y cinco a\u00f1os de libertad condicional, habl\u00f3 de una \"doble vida\" del exfuncionario mexicano\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464206,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/07\/03\/defensa-garcia-luna-rechaza-traslado-prision-colorado-orix\/","url_meta":{"origin":1447161,"position":4},"title":"La defensa de Garc\u00eda Luna rechaza su traslado a prisi\u00f3n de m\u00e1xima seguridad en Colorado","author":"","date":"julio 3, 2025","format":false,"excerpt":"La defensa legal de Genaro Garc\u00eda Luna denunci\u00f3 que su cliente fue trasladado sin raz\u00f3n alguna de una c\u00e1rcel en Nueva York a la prisi\u00f3n de m\u00e1xima seguridad Florence, en Colorado, donde est\u00e1n recluidos criminales de alto perfil como Joaqu\u00edn \u201cEl Chapo\u201d Guzm\u00e1n.C\u00e9sar de Castro, abogado de Garc\u00eda Luna en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462693,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/05\/22\/jueza-ee-uu-genaro-garcia-luna-pagar-2-500-millones-mexico-orix\/","url_meta":{"origin":1447161,"position":5},"title":"Jueza de EE.UU. ordena a Genaro Garc\u00eda Luna y a su esposa pagar casi US$ 2.500 millones al Gobierno de M\u00e9xico","author":"","date":"mayo 22, 2025","format":false,"excerpt":"Una jueza de Estados Unidos orden\u00f3 al exsecretario de Seguridad de M\u00e9xico Genaro Garc\u00eda Luna y a su esposa, Linda Cristina Pereyra, pagar al Gobierno mexicano casi US$ 2.500 millones por las afectaciones al erario derivadas de un esquema de contratos fraudulentos presuntamente encabezado por ambos, dijo este jueves la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1447161"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447161\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1447161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1447161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1447161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}