{"id":1447163,"date":"2024-03-20T19:03:40","date_gmt":"2024-03-21T02:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/20\/obispos-costa-rica-panama-colombia-zona-darien-orix\/"},"modified":"2024-03-20T19:03:40","modified_gmt":"2024-03-21T02:03:40","slug":"obispos-costa-rica-panama-colombia-zona-darien-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/20\/obispos-costa-rica-panama-colombia-zona-darien-orix\/","title":{"rendered":"Obispos de Costa Rica, Panam\u00e1 y Colombia visitan zona del Dari\u00e9n por tema migratorio"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Obispos de Panam\u00e1, Costa Rica y Colombia visitaron este martes la zona del tap\u00f3n del Dari\u00e9n, en el lado paname\u00f1o, como parte de las actividades del encuentro Pascua con nuestros hermanos migrantes, reuni\u00f3n promovida por el papa Francisco, inform\u00f3 la Conferencia Episcopal de Costa Rica.<\/p>\n<p>A trav\u00e9s de un comunicado, la Conferencia Episcopal explic\u00f3 que los sacerdotes acudieron a un albergue en la comunidad de Lajas Blancas para dialogar con migrantes y para ofrecer una celebraci\u00f3n de eucarist\u00eda presidida por el cardenal colombiano Luis Jos\u00e9 Rueda Aparicio, presidente de la Conferencia Episcopal de este pa\u00eds.<\/p>\n<p>El cruce por el Dari\u00e9n, un infierno con ruta al futuro<\/p>\n<p>\u201cLos migrantes est\u00e1n en el coraz\u00f3n del papa, y nos ha exhortado a los obispos a comprender, pero sobre todo atender integralmente su situaci\u00f3n\u201d, dijo el arzobispo de Panam\u00e1 y vicepresidente del Consejo Episcopal Latinoamericano, monse\u00f1or Jos\u00e9 Domingo Ulloa Mendieta a trav\u00e9s del comunicado.<\/p>\n<p>El papa Francisco envi\u00f3 este martes un mensaje a los obispos y representantes de la iglesia para atender el fen\u00f3meno migratorio y arropar a los migrantes que son presa del negocio del tr\u00e1fico de personas.<\/p>\n<p>\u201cEsta caravana humana pasa por el tap\u00f3n del Dari\u00e9n, una selva que es triunfo de la naturaleza pero que hoy se convierte en un verdadero viacrucis que no s\u00f3lo pone en evidencia los l\u00edmites de la gobernanza migratoria en el hemisferio occidental, sino alimenta un pr\u00f3spero negocio que permite acumular ganancias il\u00edcitas del tr\u00e1fico humano\u201d, explic\u00f3 el papa en un mensaje enviado desde la Ciudad del Vaticano a los prelados centroamericanos.<\/p>\n<p>Papa Francisco: El miedo irracional a los inmigrantes &#171;nos vuelve locos&#187;<\/p>\n<p>Cerca de 40.000 migrantes atravesaron la selva del Dari\u00e9n en Panam\u00e1 entre enero y febrero de este a\u00f1o, y un 90% corresponde a personas del continente americano y un 10% de otros continentes, seg\u00fan inform\u00f3 el Servicio Nacional de Migraci\u00f3n de Panam\u00e1 en su \u00faltimo reporte.<\/p>\n<p>De ese total, el 99% son v\u00edctimas del crimen organizado, asegur\u00f3 la directora de Migraci\u00f3n del pa\u00eds, Samira Gozaine, lo cual, dice, hace que desaf\u00eden caminos irregulares en la frontera con Colombia y que a final del a\u00f1o se haya superado la cifra total de migrantes de 2023.<\/p>\n<p>Estad\u00edsticas de Migraci\u00f3n Panam\u00e1 indican que, en enero del a\u00f1o pasado, cruzaron por la selva del Dari\u00e9n 24.634 migrantes, y en febrero de ese mismo a\u00f1o, lo hicieron 24.657. Al terminar el a\u00f1o, se registr\u00f3 una cifra r\u00e9cord, total, de 520.085, seg\u00fan los datos de la instituci\u00f3n.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Obispos de Panam\u00e1, Costa Rica y Colombia visitaron este martes la zona del tap\u00f3n del Dari\u00e9n, en el lado paname\u00f1o, como parte de las actividades del encuentro Pascua con nuestros hermanos migrantes, reuni\u00f3n promovida por el papa Francisco, inform\u00f3 la Conferencia Episcopal de Costa Rica. A trav\u00e9s de un comunicado, la Conferencia [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1447163","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Obispos de Costa Rica, Panam\u00e1 y Colombia visitan zona del Dari\u00e9n por tema migratorio - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/03\/20\/obispos-costa-rica-panama-colombia-zona-darien-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Obispos de Costa Rica, Panam\u00e1 y Colombia visitan zona del Dari\u00e9n por tema migratorio - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; Obispos de Panam\u00e1, Costa Rica y Colombia visitaron este martes la zona del tap\u00f3n del Dari\u00e9n, en el lado paname\u00f1o, como parte de las actividades del encuentro Pascua con nuestros hermanos migrantes, reuni\u00f3n promovida por el papa Francisco, inform\u00f3 la Conferencia Episcopal de Costa Rica. A trav\u00e9s de un comunicado, la Conferencia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/03\/20\/obispos-costa-rica-panama-colombia-zona-darien-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-21T02:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/20\/obispos-costa-rica-panama-colombia-zona-darien-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/20\/obispos-costa-rica-panama-colombia-zona-darien-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Obispos de Costa Rica, Panam\u00e1 y Colombia visitan zona del Dari\u00e9n por tema migratorio\",\"datePublished\":\"2024-03-21T02:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/20\/obispos-costa-rica-panama-colombia-zona-darien-orix\/\"},\"wordCount\":476,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/20\/obispos-costa-rica-panama-colombia-zona-darien-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/20\/obispos-costa-rica-panama-colombia-zona-darien-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/03\/20\/obispos-costa-rica-panama-colombia-zona-darien-orix\/\",\"name\":\"Obispos de Costa Rica, Panam\u00e1 y Colombia visitan zona del Dari\u00e9n por tema migratorio - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-21T02:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/20\/obispos-costa-rica-panama-colombia-zona-darien-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/20\/obispos-costa-rica-panama-colombia-zona-darien-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/20\/obispos-costa-rica-panama-colombia-zona-darien-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Obispos de Costa Rica, Panam\u00e1 y Colombia visitan zona del Dari\u00e9n por tema migratorio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Obispos de Costa Rica, Panam\u00e1 y Colombia visitan zona del Dari\u00e9n por tema migratorio - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/03\/20\/obispos-costa-rica-panama-colombia-zona-darien-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Obispos de Costa Rica, Panam\u00e1 y Colombia visitan zona del Dari\u00e9n por tema migratorio - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; Obispos de Panam\u00e1, Costa Rica y Colombia visitaron este martes la zona del tap\u00f3n del Dari\u00e9n, en el lado paname\u00f1o, como parte de las actividades del encuentro Pascua con nuestros hermanos migrantes, reuni\u00f3n promovida por el papa Francisco, inform\u00f3 la Conferencia Episcopal de Costa Rica. A trav\u00e9s de un comunicado, la Conferencia [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/03\/20\/obispos-costa-rica-panama-colombia-zona-darien-orix\/","og_site_name":"Noticias","article_published_time":"2024-03-21T02:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/03\/20\/obispos-costa-rica-panama-colombia-zona-darien-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/03\/20\/obispos-costa-rica-panama-colombia-zona-darien-orix\/"},"author":{"name":"","@id":""},"headline":"Obispos de Costa Rica, Panam\u00e1 y Colombia visitan zona del Dari\u00e9n por tema migratorio","datePublished":"2024-03-21T02:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/03\/20\/obispos-costa-rica-panama-colombia-zona-darien-orix\/"},"wordCount":476,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/03\/20\/obispos-costa-rica-panama-colombia-zona-darien-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/03\/20\/obispos-costa-rica-panama-colombia-zona-darien-orix\/","url":"https:\/\/noticiasya.com\/2024\/03\/20\/obispos-costa-rica-panama-colombia-zona-darien-orix\/","name":"Obispos de Costa Rica, Panam\u00e1 y Colombia visitan zona del Dari\u00e9n por tema migratorio - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-21T02:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/03\/20\/obispos-costa-rica-panama-colombia-zona-darien-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/03\/20\/obispos-costa-rica-panama-colombia-zona-darien-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/03\/20\/obispos-costa-rica-panama-colombia-zona-darien-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Obispos de Costa Rica, Panam\u00e1 y Colombia visitan zona del Dari\u00e9n por tema migratorio"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/20\/obispos-costa-rica-panama-colombia-zona-darien-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Obispos de Costa Rica, Panam\u00e1 y Colombia visitan zona del Dari\u00e9n por tema migratorio","url":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/20\/obispos-costa-rica-panama-colombia-zona-darien-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/20\/obispos-costa-rica-panama-colombia-zona-darien-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-21T02:03:40Z","datePublished":"2024-03-21T02:03:40Z","dateModified":"2024-03-21T02:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Obispos de Costa Rica, Panam\\u00e1 y Colombia visitan zona del Dari\\u00e9n por tema migratorio\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/20\\\/obispos-costa-rica-panama-colombia-zona-darien-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/20\\\/obispos-costa-rica-panama-colombia-zona-darien-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-21T02:03:40Z\",\"datePublished\":\"2024-03-21T02:03:40Z\",\"dateModified\":\"2024-03-21T02:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1456805,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/12\/20\/panama-reporta-55-migrantes-muertos-y-180-ninos-solos-en-la-selva-del-darien-en-2024\/","url_meta":{"origin":1447163,"position":0},"title":"Panam\u00e1 reporta 55 migrantes muertos y 180 ni\u00f1os solos en la selva del Dari\u00e9n en 2024","author":"","date":"diciembre 20, 2024","format":false,"excerpt":"Al menos 55 migrantes murieron en la selva del Dari\u00e9n este a\u00f1o y 180 menores de edad est\u00e1n en albergues de la Secretar\u00eda Nacional de Ni\u00f1ez, Adolescencia y Familia de Panam\u00e1 (Senniaf) al quedar solos durante su traves\u00eda, inform\u00f3 este jueves el presidente de Panam\u00e1, Jos\u00e9 Ra\u00fal Mulino, en su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459459,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/03\/03\/panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix\/","url_meta":{"origin":1447163,"position":1},"title":"Panam\u00e1 y Costa Rica acuerdan protocolo para atender retorno de migrantes desde EE.UU.","author":"","date":"marzo 3, 2025","format":false,"excerpt":"Los ministros de Seguridad de Costa Rica y Panam\u00e1 anunciaron este lunes la implementaci\u00f3n de rutas de autobuses como estrategia \u201chumanitaria y regulada\u201d para atender en sus pa\u00edses el regreso de migrantes, ante las pol\u00edticas implementadas por el Gobierno de Estados Unidos.Al inaugurar una aduana en Pe\u00f1as Blancas, Costa Rica,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451043,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/07\/11\/panama-pasos-darien-protesta-colombia-orix\/","url_meta":{"origin":1447163,"position":2},"title":"Panam\u00e1 despliega patrullaje en el mar Caribe y cierra m\u00e1s pasos en el Dari\u00e9n a pesar de protesta de Colombia","author":"","date":"julio 11, 2024","format":false,"excerpt":"(CNN en Espa\u00f1ol) -- El ministro de Seguridad Publica de Panam\u00e1, Frank \u00c1brego, inform\u00f3 a trav\u00e9s de un comunicado que se cerraron entre cuatro y cinco pasos de la frontera con Colombia en la zona del Dari\u00e9n.\u00c1brego dijo que los sitios que se han cerrado son por donde ingresaban migrantes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446000,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/02\/25\/casi-70-000-migrantes-han-cruzado-darien-rumbo-ee-uu-2024-informa-ministro-seguridad-panama-orix\/","url_meta":{"origin":1447163,"position":3},"title":"Casi 70.000 migrantes han cruzado el Dari\u00e9n rumbo a EE.UU. en 2024, informa el ministro de Seguridad de Panam\u00e1","author":"","date":"febrero 25, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Casi 70.000 migrantes han cruzado la selva del Dari\u00e9n, que divide a Colombia de Panam\u00e1, en ruta hacia el norte del continente en lo que va de 2024, inform\u00f3 este domingo el ministro de Seguridad de Panam\u00e1, Juan Manuel Pino.El funcionario explic\u00f3 en un mensaje publicado en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459307,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/02\/27\/migrantes-indocumentados-panama-colombia-eeuu-orix\/","url_meta":{"origin":1447163,"position":4},"title":"300 migrantes indocumentados viajar\u00e1n desde Panam\u00e1 hacia Colombia tras desistir de llegar a EE.UU., informa una fuente","author":"","date":"febrero 27, 2025","format":false,"excerpt":"Unos 300 migrantes indocumentados que se encuentran en las costas de Miramar, Col\u00f3n, en el norte de Panam\u00e1, se preparan para regresar a Necocl\u00ed, en el oeste de Colombia, en una traves\u00eda a la inversa de que pretend\u00edan seguir hacia el norte del continente, confirm\u00f3 a CNN una fuente oficial\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456707,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/12\/18\/migrantes-darien-disminuyo-41-2024-orix\/","url_meta":{"origin":1447163,"position":5},"title":"El n\u00famero de migrantes que cruzaron el Dari\u00e9n disminuy\u00f3 un 41% en 2024, informan autoridades paname\u00f1as","author":"","date":"diciembre 18, 2024","format":false,"excerpt":"La cifra de migrantes que atravesaron la selva del Dari\u00e9n en 2024 disminuy\u00f3 un 41% comparada con el mismo periodo en 2023, inform\u00f3 este martes el director del Servicio Nacional de Migraci\u00f3n (SNM) de Panam\u00e1, Roger Mojica Rivera.Las autoridades paname\u00f1as han registrado el ingreso de 300.549 migrantes irregulares por la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1447163"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447163\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1447163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1447163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1447163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}