{"id":1447231,"date":"2024-03-22T06:03:51","date_gmt":"2024-03-22T13:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/22\/netflix-3-body-problem-china-trax\/"},"modified":"2024-03-22T06:03:51","modified_gmt":"2024-03-22T13:03:51","slug":"netflix-3-body-problem-china-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/22\/netflix-3-body-problem-china-trax\/","title":{"rendered":"El \u00e9xito de taquilla de Netflix &#8216;3 body problem&#8217; divide la opini\u00f3n y provoca ira nacionalista en China"},"content":{"rendered":"<p>(CNN) &#8212; Una adaptaci\u00f3n de Netflix de la popular novela de ciencia ficci\u00f3n china \u201c3 body problem\u201d divide opiniones en China y provoca ira nacionalista en l\u00ednea por escenas que representan un per\u00edodo violento y tumultuoso en la historia moderna del pa\u00eds.<\/p>\n<p>Las reacciones han sido mixtas en las redes sociales chinas desde el estreno el jueves de la serie en ingl\u00e9s de ocho cap\u00edtulos \u201c3 Body Problem\u201d, basada en la novela ganadora del Premio Hugo de Liu Cixin, el autor de ciencia ficci\u00f3n m\u00e1s c\u00e9lebre del pa\u00eds.<\/p>\n<p>Jake Paul se enfrentar\u00e1 a la leyenda del boxeo Mike Tyson en una pelea de exhibici\u00f3n que se transmitir\u00e1 por Netflix<\/p>\n<p>Netflix no est\u00e1 disponible en China, pero los espectadores pueden ver su contenido utilizando redes privadas virtuales (VPN) para evitar estrictas restricciones geogr\u00e1ficas, o consumiendo versiones pirateadas.<\/p>\n<p>Una escena inicial de &#171;El problema de los 3 cuerpos&#187; de Netflix muestra una sesi\u00f3n de lucha mao\u00edsta durante la Revoluci\u00f3n Cultural de China. netflix<\/p>\n<p>La novela de Liu, parte de una trilog\u00eda, es una de las exportaciones culturales de mayor \u00e9xito de China en los \u00faltimos a\u00f1os y cuenta con legiones de admiradores en todo el mundo, incluido el expresidente de EE.UU. Barack Obama.<\/p>\n<p>Entre los usuarios de Internet m\u00e1s patri\u00f3ticos del pa\u00eds, las discusiones sobre la adaptaci\u00f3n se tornaron pol\u00edticas, y algunos acusaron a la producci\u00f3n estadounidense de gran presupuesto de hacer quedar mal a China.<\/p>\n<p>El espect\u00e1culo comienza con una escena desgarradora que representa la Revoluci\u00f3n Cultural de Mao Zedong, que consumi\u00f3 a China en un derramamiento de sangre y caos durante una d\u00e9cada a partir de 1966. En el campus de la prestigiosa Universidad Tsinghua de Beijing, un profesor de f\u00edsica es brutalmente asesinado a golpes en el escenario por sus propios estudiantes y denunciado por su colega y esposa, mientras su hija Ye Wenjie (interpretada por Zine Tseng) observa horrorizada.<\/p>\n<p>Este tipo de \u201csesiones de lucha\u201d fueron frecuentes durante el per\u00edodo de agitaci\u00f3n que dur\u00f3 una d\u00e9cada, en el que los \u201cenemigos de clase\u201d fueron humillados, golpeados y torturados p\u00fablicamente por los fren\u00e9ticos Guardias Rojos de Mao.<\/p>\n<p>Pero algunos comentaristas en l\u00ednea acusaron a los productores del programa de \u201chacer una bandeja entera de dumplings solo por un poco de salsa de vinagre\u201d, un dicho popular usado para describir un motivo oculto; en este caso, argumentaron, hacer una serie de televisi\u00f3n entera solo para pintar una mala imagen de China.<\/p>\n<p>&#171;\u00a1Netflix no entiendes &#8216;El problema de los tres cuerpos&#8217; ni a Ye Wenjie en absoluto!&#187;, se lee en un comentario en la plataforma de redes sociales Weibo. \u201c\u00a1T\u00fa solo entiendes lo pol\u00edticamente correcto!\u201d<\/p>\n<p>Otros salieron en defensa del programa, diciendo que la escena sigue de cerca las representaciones del libro y es una recreaci\u00f3n veraz de la historia.<\/p>\n<p>&#171;La historia es mucho m\u00e1s absurda que una serie de televisi\u00f3n, pero ustedes fingen no verla&#187;, se lee en un comentario en Douban, un sitio popular para rese\u00f1as de pel\u00edculas, libros y m\u00fasica.<\/p>\n<p>El autor Liu dijo en una entrevista con el New York Times en 2019 que originalmente quer\u00eda abrir el libro con escenas de la Revoluci\u00f3n Cultural de Mao, pero a su editor chino le preocupaba que nunca lograran superar la censura del gobierno y las enterr\u00f3 en medio de la narrativo.<\/p>\n<p>La versi\u00f3n en ingl\u00e9s del libro, traducida por Ken Liu, situ\u00f3 las escenas al principio de la novela, con la bendici\u00f3n del autor.<\/p>\n<p>La desilusi\u00f3n de Ye Wenjie con la Revoluci\u00f3n Cultural resulta m\u00e1s tarde fundamental en la trama del thriller de ciencia ficci\u00f3n, que salta entre el pasado y el presente.<\/p>\n<p>\u201c3 body problem\u201d fue adaptada para Netflix por los cocreadores de \u201cGame of Thrones\u201d, David Benioff y D.B. Weiss y el productor estadounidense Alexander Woo.<\/p>\n<p>Varios otros aspectos del programa, desde el reparto y los efectos visuales hasta los cambios radicales en el escenario y los personajes originales de la historia, tambi\u00e9n atrajeron la ira de los usuarios chinos de las redes sociales. Muchos lo compararon con una adaptaci\u00f3n televisiva china lanzada el a\u00f1o pasado: una versi\u00f3n mucho m\u00e1s larga y cercana al libro que tuvo 30 episodios y fue altamente calificada en las plataformas de rese\u00f1as chinas.<\/p>\n<p>La adaptaci\u00f3n de Netflix cont\u00f3 con un elenco internacional y situ\u00f3 gran parte de la acci\u00f3n en el Londres actual, lo que hizo que la historia fuera mucho menos china.<\/p>\n<p>Algunos espectadores chinos criticaron la alteraci\u00f3n, diciendo que interpretaba una trama que glorifica a Occidente por salvar a la humanidad de un desastre provocado por China hace d\u00e9cadas.<\/p>\n<p>Pero no todos han elegido bando.<\/p>\n<p>\u201c\u00bfPor qu\u00e9 algunas personas siempre necesitan convertir un producto cultural en enemigo?\u201d, dijo un usuario en Weibo. \u201cNuestra versi\u00f3n puede ser buena, la de ellos tambi\u00e9n puede ser excelente. \u00bfPor qu\u00e9 siempre tenemos que pelear por eso?&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Una adaptaci\u00f3n de Netflix de la popular novela de ciencia ficci\u00f3n china \u201c3 body problem\u201d divide opiniones en China y provoca ira nacionalista en l\u00ednea por escenas que representan un per\u00edodo violento y tumultuoso en la historia moderna del pa\u00eds. Las reacciones han sido mixtas en las redes sociales chinas desde el estreno [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1447231","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El \u00e9xito de taquilla de Netflix &#039;3 body problem&#039; divide la opini\u00f3n y provoca ira nacionalista en China - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/03\/22\/netflix-3-body-problem-china-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El \u00e9xito de taquilla de Netflix &#039;3 body problem&#039; divide la opini\u00f3n y provoca ira nacionalista en China - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Una adaptaci\u00f3n de Netflix de la popular novela de ciencia ficci\u00f3n china \u201c3 body problem\u201d divide opiniones en China y provoca ira nacionalista en l\u00ednea por escenas que representan un per\u00edodo violento y tumultuoso en la historia moderna del pa\u00eds. Las reacciones han sido mixtas en las redes sociales chinas desde el estreno [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/03\/22\/netflix-3-body-problem-china-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-22T13:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/22\/netflix-3-body-problem-china-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/22\/netflix-3-body-problem-china-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El \u00e9xito de taquilla de Netflix &#8216;3 body problem&#8217; divide la opini\u00f3n y provoca ira nacionalista en China\",\"datePublished\":\"2024-03-22T13:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/22\/netflix-3-body-problem-china-trax\/\"},\"wordCount\":886,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/22\/netflix-3-body-problem-china-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/22\/netflix-3-body-problem-china-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/03\/22\/netflix-3-body-problem-china-trax\/\",\"name\":\"El \u00e9xito de taquilla de Netflix '3 body problem' divide la opini\u00f3n y provoca ira nacionalista en China - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-22T13:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/22\/netflix-3-body-problem-china-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/22\/netflix-3-body-problem-china-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/22\/netflix-3-body-problem-china-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El \u00e9xito de taquilla de Netflix &#8216;3 body problem&#8217; divide la opini\u00f3n y provoca ira nacionalista en China\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El \u00e9xito de taquilla de Netflix '3 body problem' divide la opini\u00f3n y provoca ira nacionalista en China - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/03\/22\/netflix-3-body-problem-china-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El \u00e9xito de taquilla de Netflix '3 body problem' divide la opini\u00f3n y provoca ira nacionalista en China - Noticias","og_description":"(CNN) &#8212; Una adaptaci\u00f3n de Netflix de la popular novela de ciencia ficci\u00f3n china \u201c3 body problem\u201d divide opiniones en China y provoca ira nacionalista en l\u00ednea por escenas que representan un per\u00edodo violento y tumultuoso en la historia moderna del pa\u00eds. Las reacciones han sido mixtas en las redes sociales chinas desde el estreno [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/03\/22\/netflix-3-body-problem-china-trax\/","og_site_name":"Noticias","article_published_time":"2024-03-22T13:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/03\/22\/netflix-3-body-problem-china-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/03\/22\/netflix-3-body-problem-china-trax\/"},"author":{"name":"","@id":""},"headline":"El \u00e9xito de taquilla de Netflix &#8216;3 body problem&#8217; divide la opini\u00f3n y provoca ira nacionalista en China","datePublished":"2024-03-22T13:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/03\/22\/netflix-3-body-problem-china-trax\/"},"wordCount":886,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/03\/22\/netflix-3-body-problem-china-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/03\/22\/netflix-3-body-problem-china-trax\/","url":"https:\/\/noticiasya.com\/2024\/03\/22\/netflix-3-body-problem-china-trax\/","name":"El \u00e9xito de taquilla de Netflix '3 body problem' divide la opini\u00f3n y provoca ira nacionalista en China - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-22T13:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/03\/22\/netflix-3-body-problem-china-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/03\/22\/netflix-3-body-problem-china-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/03\/22\/netflix-3-body-problem-china-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El \u00e9xito de taquilla de Netflix &#8216;3 body problem&#8217; divide la opini\u00f3n y provoca ira nacionalista en China"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/22\/netflix-3-body-problem-china-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El \u00e9xito de taquilla de Netflix &#8216;3 body problem&#8217; divide la opini\u00f3n y provoca ira nacionalista en China","url":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/22\/netflix-3-body-problem-china-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/22\/netflix-3-body-problem-china-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-22T13:03:51Z","datePublished":"2024-03-22T13:03:51Z","dateModified":"2024-03-22T13:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El \\u00e9xito de taquilla de Netflix &#8216;3 body problem&#8217; divide la opini\\u00f3n y provoca ira nacionalista en China\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/22\\\/netflix-3-body-problem-china-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/22\\\/netflix-3-body-problem-china-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-22T13:03:51Z\",\"datePublished\":\"2024-03-22T13:03:51Z\",\"dateModified\":\"2024-03-22T13:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1458701,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/02\/13\/diego-guelar-lo-que-se-llama-la-nueva-derecha-es-un-fenomeno-hegemonico-en-el-mundo\/","url_meta":{"origin":1447231,"position":0},"title":"Diego Guelar: &#171;Lo que se llama la nueva derecha es un fen\u00f3meno hegem\u00f3nico en el mundo&#187;","author":"","date":"febrero 13, 2025","format":false,"excerpt":"Diego Guelar, exembajador argentino ante Estados Unidos y China, visit\u00f3 este jueves los estudios de CNN Radio para conversar sobre el nuevo mapa geopol\u00edtico con Dondadl Trump en el poder y se refiri\u00f3 a las medidas del presidente Javier Milei: \u201cLa realidad es mucho m\u00e1s rica que la ficci\u00f3n\u201d.Al inicio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468582,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/11\/21\/furia-china-takaichi-japon-trax\/","url_meta":{"origin":1447231,"position":1},"title":"La verdadera raz\u00f3n detr\u00e1s de la furia de China hacia Takaichi, primera ministra de Jap\u00f3n","author":"","date":"noviembre 21, 2025","format":false,"excerpt":"A pocas semanas de asumir el cargo, la nueva l\u00edder de Jap\u00f3n se ha enfrentado a las consecuencias de cruzar la l\u00ednea roja de China respecto a Taiw\u00e1n.Desde que Sanae Takaichi sugiri\u00f3 que su pa\u00eds podr\u00eda responder militarmente si China toma el control de Taiw\u00e1n por la fuerza, Beijing ha\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458773,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/02\/15\/superproduccion-animacion-china-records-taquilla-trax\/","url_meta":{"origin":1447231,"position":2},"title":"La superproducci\u00f3n de animaci\u00f3n china bati\u00f3 r\u00e9cords de taquilla en su pa\u00eds. Ahora llega a los cines de Occidente","author":"","date":"febrero 15, 2025","format":false,"excerpt":"Un revoltoso ni\u00f1o chino que lucha contra dragones y desaf\u00eda al destino ha llegado a las pantallas occidentales tras batir r\u00e9cords de taquilla en China.\u201cNe Zha 2\u201d, una superproducci\u00f3n de animaci\u00f3n basada vagamente en la mitolog\u00eda china, es ahora la pel\u00edcula m\u00e1s taquillera de todos los tiempos en un solo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445875,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/02\/21\/messi-china-hong-kong-partido-trax\/","url_meta":{"origin":1447231,"position":3},"title":"Messi niega que su ausencia en el partido de Hong Kong fuera por motivos pol\u00edticos: &#171;He tenido una relaci\u00f3n muy estrecha y especial con China&#187;","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN) -- Lionel Messi\u00a0todav\u00eda est\u00e1 tratando de explicar su ausencia de un\u00a0partido de f\u00fatbol en Hong Kong. La estrella del Inter Miami public\u00f3 este lunes un video en la plataforma de redes sociales china Weibo, luego de una declaraci\u00f3n que hizo en texto hace unas dos semanas.El 4 de febrero,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445716,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/02\/20\/messi-niega-que-su-ausencia-en-el-partido-de-hong-kong-fuera-por-motivos-politicos-he-tenido-una-relacion-muy-estrecha-y-especial-con-china-2\/","url_meta":{"origin":1447231,"position":4},"title":"Messi niega que su ausencia en el partido de Hong Kong fuera por motivos pol\u00edticos: &#171;He tenido una relaci\u00f3n muy estrecha y especial con China&#187;","author":"","date":"febrero 20, 2024","format":false,"excerpt":"(CNN) -- Lionel Messi\u00a0todav\u00eda est\u00e1 tratando de explicar su ausencia de un\u00a0partido de f\u00fatbol en Hong Kong. La estrella del Inter Miami public\u00f3 este lunes un video en la plataforma de redes sociales china Weibo, luego de una declaraci\u00f3n que hizo en texto hace unas dos semanas.El 4 de febrero,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445679,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/02\/19\/messi-niega-que-su-ausencia-en-el-partido-de-hong-kong-fuera-por-motivos-politicos-he-tenido-una-relacion-muy-estrecha-y-especial-con-china\/","url_meta":{"origin":1447231,"position":5},"title":"Messi niega que su ausencia en el partido de Hong Kong fuera por motivos pol\u00edticos: &#171;He tenido una relaci\u00f3n muy estrecha y especial con China&#187;","author":"","date":"febrero 19, 2024","format":false,"excerpt":"(CNN) -- Lionel Messi\u00a0todav\u00eda est\u00e1 tratando de explicar su ausencia de un\u00a0partido de f\u00fatbol en Hong Kong. La estrella del Inter Miami public\u00f3 este lunes un video en la plataforma de redes sociales china Weibo, luego de una declaraci\u00f3n que hizo en texto hace unas dos semanas.El 4 de febrero,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1447231"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447231\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1447231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1447231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1447231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}