{"id":1447253,"date":"2024-03-22T12:03:42","date_gmt":"2024-03-22T19:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/22\/kate-princesa-de-gales-cancer-trax\/"},"modified":"2024-03-22T12:03:42","modified_gmt":"2024-03-22T19:03:42","slug":"kate-princesa-de-gales-cancer-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/22\/kate-princesa-de-gales-cancer-trax\/","title":{"rendered":"Kate, princesa de Gales, anuncia que tiene c\u00e1ncer"},"content":{"rendered":"<p>(CNN) \u2013\u2013 Kate, princesa de Gales, revel\u00f3 este viernes que le diagnosticaron c\u00e1ncer y que se encuentra en las &#171;primeras etapas&#187; de tratamiento.<\/p>\n<p>\u00daltima hora de Kate, princesa de Gales, tras el anuncio de que tiene c\u00e1ncer, en vivo<\/p>\n<p>El anuncio, que la princesa describi\u00f3 como un &#171;gran impacto&#187;, se hizo a trav\u00e9s de un mensaje de video. La noticia se conoce dos meses despu\u00e9s de que Catherine se alejara temporalmente de la vida p\u00fablica luego de lo que el Palacio de Kensington inform\u00f3 en ese momento era una cirug\u00eda por una afecci\u00f3n abdominal no cancerosa.<\/p>\n<p>\u00bfQu\u00e9 ha pasado con Kate, princesa de Gales, en los \u00faltimos meses? Esto sabemos<\/p>\n<p>&#171;En enero me somet\u00ed a una cirug\u00eda abdominal importante en Londres y en ese momento se pens\u00f3 que mi condici\u00f3n no era cancerosa&#187;, dijo la princesa, de 42 a\u00f1os, quien est\u00e1 casada con el heredero al trono brit\u00e1nico, el pr\u00edncipe William.<\/p>\n<p>\u00bfQui\u00e9n es Kate, la princesa de Gales? Conoce su vida, antes y despu\u00e9s de llegar a la familia real<\/p>\n<p>&#171;La cirug\u00eda fue exitosa. Sin embargo, las pruebas posteriores a la operaci\u00f3n encontraron que hab\u00eda c\u00e1ncer. Por lo tanto, mi equipo m\u00e9dico me recomend\u00f3 que me sometiera a un tratamiento de quimioterapia preventiva y ahora me encuentro en las primeras etapas de ese tratamiento\u201d.<\/p>\n<p>Kate, princesa de Gales<\/p>\n<p>Kate continu\u00f3 diciendo: \u201cWilliam y yo hemos estado haciendo todo lo posible para procesar y gestionar esto de forma privada por el bien de nuestra joven familia\u201d.<\/p>\n<p>Y agreg\u00f3: \u201cComo pueden imaginar, esto ha llevado tiempo. Me ha tomado tiempo recuperarme de una cirug\u00eda mayor para poder iniciar mi tratamiento. Pero, lo m\u00e1s importante, nos ha tomado tiempo explicarles todo a George, Charlotte y Louis de una manera apropiada para ellos, y asegurarles que voy a estar bien\u201d.<\/p>\n<p>AN\u00c1LISIS | C\u00f3mo la saga fotogr\u00e1fica de Kate se convirti\u00f3 en una crisis para la monarqu\u00eda brit\u00e1nica<\/p>\n<p>Catherine dijo que les hab\u00eda dicho que estaba \u201cbien y cada d\u00eda se volv\u00eda m\u00e1s fuerte al concentrarse en las cosas que me ayudar\u00e1n a sanar; en mi mente, cuerpo y esp\u00edritu\u201d.<br \/>\nElogi\u00f3 al pr\u00edncipe William por estar a su lado como \u201cuna gran fuente de consuelo y tranquilidad\u201d, as\u00ed como por el apoyo que ha recibido del p\u00fablico.<\/p>\n<p>&#171;Esperamos que comprendan que, como familia, ahora necesitamos algo de tiempo, espacio y privacidad mientras completo mi tratamiento. Mis funciones siempre me han aportado un profundo sentimiento de alegr\u00eda y estoy deseando volver cuando pueda, pero por ahora debo centrarme en recuperarme por completo&#187;, declar\u00f3 la princesa.<\/p>\n<p>OPINI\u00d3N | Lo que realmente hay detr\u00e1s de la controversia por la foto de Kate<\/p>\n<p>Termin\u00f3 su efusivo mensaje diciendo que tambi\u00e9n ten\u00eda presentes a &#171;todos aquellos cuyas vidas se han visto afectadas por el c\u00e1ncer&#187;.<\/p>\n<p>&#171;Para todos los que se enfrentan a esta enfermedad, en cualquiera de sus formas, por favor, no pierdan la fe ni la esperanza. No est\u00e1n solos&#187;, concluy\u00f3 Kate.<\/p>\n<p>Catherine, princesa de Gales, fotografiada en noviembre. Max Mumby\/Indigo\/Getty Images\/Archivo<\/p>\n<p>El anuncio representa un golpe devastador para la monarqu\u00eda brit\u00e1nica, ya que el rey Carlos III est\u00e1 actualmente en tratamiento por un c\u00e1ncer no especificado, que fue anunciado por el Palacio de Buckingham a principios de febrero.<\/p>\n<p>As\u00ed es el \u00e1rbol geneal\u00f3gico de la realeza de Reino Unido: qui\u00e9n es qui\u00e9n en la Casa de Windsor<\/p>\n<p>La actualizaci\u00f3n sobre el c\u00e1ncer de la princesa ocurre luego de que Kate se sometiera con \u00e9xito a una operaci\u00f3n abdominal el 16 de enero. Tras la intervenci\u00f3n, permaneci\u00f3 en un hospital londinense durante 13 d\u00edas y, por recomendaci\u00f3n m\u00e9dica, ha estado alejada de los actos p\u00fablicos durante su recuperaci\u00f3n.<\/p>\n<p>Kate fue vista en p\u00fablico por primera vez desde su operaci\u00f3n, visitando una granja con su esposo, el pr\u00edncipe William, el pasado fin de semana.<\/p>\n<p>El primer ministro Rishi Sunak declar\u00f3 que la princesa de Gales cuenta con &#171;el amor y el apoyo de todo el pa\u00eds&#187;. En redes sociales djio este viernes que Kate hab\u00eda mostrado &#171;una tremenda valent\u00eda con su declaraci\u00f3n&#187; y que sus oraciones estaban con ella, y &#171;en particular con sus tres hijos&#187;.<\/p>\n<p>Tambi\u00e9n se\u00f1al\u00f3 que la princesa fue &#171;tratada injustamente&#187; por algunos sectores de los medios de comunicaci\u00f3n y en las redes sociales. Kate fue objeto de intensas especulaciones en internet, extra\u00f1as teor\u00edas conspirativas y rumores tras su ausencia p\u00fablica despu\u00e9s de que la operaran en enero.&#187;Cuando se trata de cuestiones de salud, como todo el mundo, se le debe conceder la privacidad necesaria para centrarse en su tratamiento y estar con su querida familia&#187;, escribi\u00f3 Sunak en X.<\/p>\n<p>Noticia en desarrollo&#8230;<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) \u2013\u2013 Kate, princesa de Gales, revel\u00f3 este viernes que le diagnosticaron c\u00e1ncer y que se encuentra en las &#171;primeras etapas&#187; de tratamiento. \u00daltima hora de Kate, princesa de Gales, tras el anuncio de que tiene c\u00e1ncer, en vivo El anuncio, que la princesa describi\u00f3 como un &#171;gran impacto&#187;, se hizo a trav\u00e9s de un [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1447253","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Kate, princesa de Gales, anuncia que tiene c\u00e1ncer - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/03\/22\/kate-princesa-de-gales-cancer-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kate, princesa de Gales, anuncia que tiene c\u00e1ncer - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) \u2013\u2013 Kate, princesa de Gales, revel\u00f3 este viernes que le diagnosticaron c\u00e1ncer y que se encuentra en las &#171;primeras etapas&#187; de tratamiento. \u00daltima hora de Kate, princesa de Gales, tras el anuncio de que tiene c\u00e1ncer, en vivo El anuncio, que la princesa describi\u00f3 como un &#171;gran impacto&#187;, se hizo a trav\u00e9s de un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/03\/22\/kate-princesa-de-gales-cancer-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-22T19:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/22\/kate-princesa-de-gales-cancer-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/22\/kate-princesa-de-gales-cancer-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Kate, princesa de Gales, anuncia que tiene c\u00e1ncer\",\"datePublished\":\"2024-03-22T19:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/22\/kate-princesa-de-gales-cancer-trax\/\"},\"wordCount\":849,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/22\/kate-princesa-de-gales-cancer-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/22\/kate-princesa-de-gales-cancer-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/03\/22\/kate-princesa-de-gales-cancer-trax\/\",\"name\":\"Kate, princesa de Gales, anuncia que tiene c\u00e1ncer - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-22T19:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/22\/kate-princesa-de-gales-cancer-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/22\/kate-princesa-de-gales-cancer-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/22\/kate-princesa-de-gales-cancer-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kate, princesa de Gales, anuncia que tiene c\u00e1ncer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kate, princesa de Gales, anuncia que tiene c\u00e1ncer - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/03\/22\/kate-princesa-de-gales-cancer-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Kate, princesa de Gales, anuncia que tiene c\u00e1ncer - Noticias","og_description":"(CNN) \u2013\u2013 Kate, princesa de Gales, revel\u00f3 este viernes que le diagnosticaron c\u00e1ncer y que se encuentra en las &#171;primeras etapas&#187; de tratamiento. \u00daltima hora de Kate, princesa de Gales, tras el anuncio de que tiene c\u00e1ncer, en vivo El anuncio, que la princesa describi\u00f3 como un &#171;gran impacto&#187;, se hizo a trav\u00e9s de un [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/03\/22\/kate-princesa-de-gales-cancer-trax\/","og_site_name":"Noticias","article_published_time":"2024-03-22T19:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/03\/22\/kate-princesa-de-gales-cancer-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/03\/22\/kate-princesa-de-gales-cancer-trax\/"},"author":{"name":"","@id":""},"headline":"Kate, princesa de Gales, anuncia que tiene c\u00e1ncer","datePublished":"2024-03-22T19:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/03\/22\/kate-princesa-de-gales-cancer-trax\/"},"wordCount":849,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/03\/22\/kate-princesa-de-gales-cancer-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/03\/22\/kate-princesa-de-gales-cancer-trax\/","url":"https:\/\/noticiasya.com\/2024\/03\/22\/kate-princesa-de-gales-cancer-trax\/","name":"Kate, princesa de Gales, anuncia que tiene c\u00e1ncer - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-22T19:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/03\/22\/kate-princesa-de-gales-cancer-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/03\/22\/kate-princesa-de-gales-cancer-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/03\/22\/kate-princesa-de-gales-cancer-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Kate, princesa de Gales, anuncia que tiene c\u00e1ncer"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/22\/kate-princesa-de-gales-cancer-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Kate, princesa de Gales, anuncia que tiene c\u00e1ncer","url":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/22\/kate-princesa-de-gales-cancer-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/22\/kate-princesa-de-gales-cancer-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-22T19:03:42Z","datePublished":"2024-03-22T19:03:42Z","dateModified":"2024-03-22T19:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Kate, princesa de Gales, anuncia que tiene c\\u00e1ncer\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/22\\\/kate-princesa-de-gales-cancer-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/22\\\/kate-princesa-de-gales-cancer-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-22T19:03:42Z\",\"datePublished\":\"2024-03-22T19:03:42Z\",\"dateModified\":\"2024-03-22T19:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1450579,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/06\/21\/cumple-principe-william-foto-kate-trax\/","url_meta":{"origin":1447253,"position":0},"title":"Kate y los hijos desean feliz cumplea\u00f1os al pr\u00edncipe William con divertida foto familiar","author":"","date":"junio 21, 2024","format":false,"excerpt":"(CNN) -- La familia del pr\u00edncipe William celebr\u00f3 el viernes su cumplea\u00f1os n\u00famero 42 publicando una divertida foto de \u00e9l saltando desde una duna de arena, tomado de la mano de sus tres hijos: el pr\u00edncipe Jorge, la princesa Carlota y el pr\u00edncipe Luis.\"\u00a1Feliz cumplea\u00f1os, pap\u00e1, todos te queremos mucho!\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450358,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/06\/14\/kate-princesa-progreso-cancer-aparicion-publica-meses-trax\/","url_meta":{"origin":1447253,"position":1},"title":"Kate, princesa de Gales, tuvo &#171;buenos progresos&#187; contra el c\u00e1ncer y se alista para su primera aparici\u00f3n p\u00fablica en meses","author":"","date":"junio 14, 2024","format":false,"excerpt":"(CNN) -- La princesa de Gales, Kate Middleton, inform\u00f3 que est\u00e1 haciendo un \"buen progreso\" en su recuperaci\u00f3n del c\u00e1ncer, y que har\u00e1 su primera aparici\u00f3n p\u00fablica en meses en la celebraci\u00f3n oficial del cumplea\u00f1os del rey Carlos, este s\u00e1bado.Kate, quien revel\u00f3 en marzo que fue diagnosticada con c\u00e1ncer, dijo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446878,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/12\/agencias-retiran-foto-kate-manipulacion-imagen-trax\/","url_meta":{"origin":1447253,"position":2},"title":"Agencias de noticias retiran una foto de Kate, princesa de Gales, citando preocupaciones de manipulaci\u00f3n de la imagen","author":"","date":"marzo 12, 2024","format":false,"excerpt":"(CNN) -- Varias agencias de noticias importantes han retirado una imagen distribuida por el Palacio de Kensington que muestra a Kate, princesa de Gales, y sus hijos, diciendo que creen que la foto ha sido manipulada.La fotograf\u00eda es la primera imagen oficialmente publicada de la princesa desde que se someti\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447273,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/23\/kate-gales-princesa-importante-familia-real-trax\/","url_meta":{"origin":1447253,"position":3},"title":"Kate, princesa de Gales, se ha convertido en un miembro cada vez m\u00e1s importante de la familia real","author":"","date":"marzo 23, 2024","format":false,"excerpt":"(CNN) -- Catherine, princesa de Gales, ha revelado que tiene c\u00e1ncer y est\u00e1 recibiendo quimioterapia preventiva despu\u00e9s de semanas de especulaciones sobre su salud y su ausencia del ojo p\u00fablico.En un comunicado calific\u00f3 la noticia de \u201cshock\u201d y pidi\u00f3 privacidad para ella y su joven familia. No ha asumido funciones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447252,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/22\/kate-princesa-gales-cancer-ultima-hora-reacciones-orix\/","url_meta":{"origin":1447253,"position":4},"title":"\u00daltima hora de Kate, princesa de Gales, tras el anuncio de que tiene c\u00e1ncer, en vivo: reacciones, noticias y \u00faltima hora","author":"","date":"marzo 22, 2024","format":false,"excerpt":"Para ver las entradas m\u00e1s recientes haz clic aqu\u00ed.The-CNN-Wire\u2122 & \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447271,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/23\/analisis-revelacion-cancer-kate-familia-real-nueva-agitacion-trax\/","url_meta":{"origin":1447253,"position":5},"title":"AN\u00c1LISIS | La revelaci\u00f3n del c\u00e1ncer de Kate arroja a la familia real a una nueva agitaci\u00f3n","author":"","date":"marzo 23, 2024","format":false,"excerpt":"(CNN) -- El anuncio de Catherine, princesa de Gales, de que hab\u00eda comenzado la quimioterapia para el c\u00e1ncer y que se encontraba en las \u201cprimeras etapas de ese tratamiento\u201d fue un rayo ca\u00eddo del cielo.Cuando Gran Breta\u00f1a se despert\u00f3 este s\u00e1bado por la ma\u00f1ana, el tono de todos los peri\u00f3dicos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1447253"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447253\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1447253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1447253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1447253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}