{"id":1447303,"date":"2024-03-24T16:03:56","date_gmt":"2024-03-24T23:03:56","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/24\/extinguen-incendio-crucero-carnival-freedom-impacto-rayo-trax\/"},"modified":"2024-03-24T16:03:56","modified_gmt":"2024-03-24T23:03:56","slug":"extinguen-incendio-crucero-carnival-freedom-impacto-rayo-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/24\/extinguen-incendio-crucero-carnival-freedom-impacto-rayo-trax\/","title":{"rendered":"Extinguen incendio en el crucero Carnival Freedom despu\u00e9s de que testigos informaran sobre el posible impacto de un rayo"},"content":{"rendered":"<p>(CNN) &#8212; Heath Barnes abri\u00f3 su libro en las cubiertas superiores del crucero Carnival Freedom con destino a las Bahamas. Llov\u00eda. Pero su relajaci\u00f3n el s\u00e1bado por la tarde se vio interrumpida por \u201clos truenos y rel\u00e1mpagos m\u00e1s fuertes que jam\u00e1s haya escuchado\u201d, le dijo a CNN.<\/p>\n<p>Barnes, de Woodsboro, Maryland, volvi\u00f3 a entrar y minutos despu\u00e9s se enter\u00f3 por su sobrino y los dos amigos de su sobrino, todos de 16 a\u00f1os, que el barco estaba en llamas.<\/p>\n<p>\u201cPens\u00e9 que me estaban haciendo pasar un mal rato, pero me levant\u00e9 y sal\u00ed al balc\u00f3n y, efectivamente, las llamas y el humo sal\u00edan de la cola\u201d, dijo Barnes, quien comparti\u00f3 im\u00e1genes del incidente con CNN.<\/p>\n<p>Heath Barnes tom\u00f3 esta fotograf\u00eda del fuego y el humo saliendo de un embudo de escape del crucero Carnival Freedom cerca de las Bahamas, el 23 de marzo. Heath Barnes<\/p>\n<p>Los funcionarios del crucero informaron que el incendio se produjo en el lado de babor del embudo de escape del barco alrededor de las 3:15 p.m. hora local, seg\u00fan un comunicado de prensa de Carnival Cruise Line.<\/p>\n<p>Los testigos informaron que el barco pudo haber sido alcanzado por un rayo, pero eso no ha sido confirmado y la causa a\u00fan est\u00e1 en investigaci\u00f3n, seg\u00fan la empresa de cruceros.<\/p>\n<p>Mientras el equipo de respuesta a incendios del barco trabajaba para extinguir el incendio, el capit\u00e1n del crucero gir\u00f3 el barco hacia un \u00e1rea de fuertes lluvias para ayudar a apagar las llamas, seg\u00fan el comunicado.<\/p>\n<p>El fuego pareci\u00f3 extinguirse aproximadamente dos horas despu\u00e9s de su inicio. No se reportaron heridos entre los hu\u00e9spedes, pero dos miembros del equipo de bomberos fueron tratados por inhalaci\u00f3n leve de humo, seg\u00fan la compa\u00f1\u00eda de cruceros.<\/p>\n<p>La parte de babor del embudo de escape cay\u00f3 sobre la cubierta 10 del barco como resultado del incendio, seg\u00fan Carnival.<\/p>\n<p>El barco estaba a unos 32 kil\u00f3metros de la isla Eleuthera, Bahamas, cuando se produjo el incendio. El incidente comenz\u00f3 cuando el barco se dirig\u00eda a Freeport, seg\u00fan el comunicado.<\/p>\n<p>\u00bfImaginas zarpar en el Titanic II? Un multimillonario quiere hacerlo realidad<\/p>\n<p>La l\u00ednea de cruceros indic\u00f3 que los pasajeros pudieron asistir a la cena como estaba previsto el s\u00e1bado por la noche y que todas las \u00e1reas del barco estaban en pleno funcionamiento a partir del domingo, excepto las cubiertas abiertas.<\/p>\n<p>El barco visit\u00f3 Freeport el domingo, dijo Carnival, y a\u00f1adi\u00f3 que no hubo problemas operativos con los sistemas del barco. &#171;Carnival no espera ning\u00fan impacto en el pr\u00f3ximo viaje del Carnival Freedom programado para partir de Puerto Ca\u00f1averal el lunes 25 de marzo&#187;, afirma el comunicado.<\/p>\n<p>La Guardia Costera de Estados Unidos fue notificada sobre el incidente.<\/p>\n<p>Barnes dijo que despu\u00e9s de que ocurri\u00f3 el incendio, se pidi\u00f3 a los pasajeros que permanecieran en sus cabinas hasta aproximadamente las 5:40 p.m.<\/p>\n<p>Este fue su viaje n\u00famero 18 en Carnival Cruise.<\/p>\n<p>&#171;Este fue el m\u00e1s interesante&#187;, coment\u00f3. &#171;No es su culpa, es la madre naturaleza&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Heath Barnes abri\u00f3 su libro en las cubiertas superiores del crucero Carnival Freedom con destino a las Bahamas. Llov\u00eda. Pero su relajaci\u00f3n el s\u00e1bado por la tarde se vio interrumpida por \u201clos truenos y rel\u00e1mpagos m\u00e1s fuertes que jam\u00e1s haya escuchado\u201d, le dijo a CNN. Barnes, de Woodsboro, Maryland, volvi\u00f3 a entrar y [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1447303","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Extinguen incendio en el crucero Carnival Freedom despu\u00e9s de que testigos informaran sobre el posible impacto de un rayo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/03\/24\/extinguen-incendio-crucero-carnival-freedom-impacto-rayo-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Extinguen incendio en el crucero Carnival Freedom despu\u00e9s de que testigos informaran sobre el posible impacto de un rayo - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Heath Barnes abri\u00f3 su libro en las cubiertas superiores del crucero Carnival Freedom con destino a las Bahamas. Llov\u00eda. Pero su relajaci\u00f3n el s\u00e1bado por la tarde se vio interrumpida por \u201clos truenos y rel\u00e1mpagos m\u00e1s fuertes que jam\u00e1s haya escuchado\u201d, le dijo a CNN. Barnes, de Woodsboro, Maryland, volvi\u00f3 a entrar y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/03\/24\/extinguen-incendio-crucero-carnival-freedom-impacto-rayo-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-24T23:03:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/24\/extinguen-incendio-crucero-carnival-freedom-impacto-rayo-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/24\/extinguen-incendio-crucero-carnival-freedom-impacto-rayo-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Extinguen incendio en el crucero Carnival Freedom despu\u00e9s de que testigos informaran sobre el posible impacto de un rayo\",\"datePublished\":\"2024-03-24T23:03:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/24\/extinguen-incendio-crucero-carnival-freedom-impacto-rayo-trax\/\"},\"wordCount\":558,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/24\/extinguen-incendio-crucero-carnival-freedom-impacto-rayo-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/24\/extinguen-incendio-crucero-carnival-freedom-impacto-rayo-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/03\/24\/extinguen-incendio-crucero-carnival-freedom-impacto-rayo-trax\/\",\"name\":\"Extinguen incendio en el crucero Carnival Freedom despu\u00e9s de que testigos informaran sobre el posible impacto de un rayo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-24T23:03:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/24\/extinguen-incendio-crucero-carnival-freedom-impacto-rayo-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/24\/extinguen-incendio-crucero-carnival-freedom-impacto-rayo-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/24\/extinguen-incendio-crucero-carnival-freedom-impacto-rayo-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Extinguen incendio en el crucero Carnival Freedom despu\u00e9s de que testigos informaran sobre el posible impacto de un rayo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Extinguen incendio en el crucero Carnival Freedom despu\u00e9s de que testigos informaran sobre el posible impacto de un rayo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/03\/24\/extinguen-incendio-crucero-carnival-freedom-impacto-rayo-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Extinguen incendio en el crucero Carnival Freedom despu\u00e9s de que testigos informaran sobre el posible impacto de un rayo - Noticias","og_description":"(CNN) &#8212; Heath Barnes abri\u00f3 su libro en las cubiertas superiores del crucero Carnival Freedom con destino a las Bahamas. Llov\u00eda. Pero su relajaci\u00f3n el s\u00e1bado por la tarde se vio interrumpida por \u201clos truenos y rel\u00e1mpagos m\u00e1s fuertes que jam\u00e1s haya escuchado\u201d, le dijo a CNN. Barnes, de Woodsboro, Maryland, volvi\u00f3 a entrar y [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/03\/24\/extinguen-incendio-crucero-carnival-freedom-impacto-rayo-trax\/","og_site_name":"Noticias","article_published_time":"2024-03-24T23:03:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/03\/24\/extinguen-incendio-crucero-carnival-freedom-impacto-rayo-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/03\/24\/extinguen-incendio-crucero-carnival-freedom-impacto-rayo-trax\/"},"author":{"name":"","@id":""},"headline":"Extinguen incendio en el crucero Carnival Freedom despu\u00e9s de que testigos informaran sobre el posible impacto de un rayo","datePublished":"2024-03-24T23:03:56+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/03\/24\/extinguen-incendio-crucero-carnival-freedom-impacto-rayo-trax\/"},"wordCount":558,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/03\/24\/extinguen-incendio-crucero-carnival-freedom-impacto-rayo-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/03\/24\/extinguen-incendio-crucero-carnival-freedom-impacto-rayo-trax\/","url":"https:\/\/noticiasya.com\/2024\/03\/24\/extinguen-incendio-crucero-carnival-freedom-impacto-rayo-trax\/","name":"Extinguen incendio en el crucero Carnival Freedom despu\u00e9s de que testigos informaran sobre el posible impacto de un rayo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-24T23:03:56+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/03\/24\/extinguen-incendio-crucero-carnival-freedom-impacto-rayo-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/03\/24\/extinguen-incendio-crucero-carnival-freedom-impacto-rayo-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/03\/24\/extinguen-incendio-crucero-carnival-freedom-impacto-rayo-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Extinguen incendio en el crucero Carnival Freedom despu\u00e9s de que testigos informaran sobre el posible impacto de un rayo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/24\/extinguen-incendio-crucero-carnival-freedom-impacto-rayo-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Extinguen incendio en el crucero Carnival Freedom despu\u00e9s de que testigos informaran sobre el posible impacto de un rayo","url":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/24\/extinguen-incendio-crucero-carnival-freedom-impacto-rayo-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/24\/extinguen-incendio-crucero-carnival-freedom-impacto-rayo-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-24T23:03:56Z","datePublished":"2024-03-24T23:03:56Z","dateModified":"2024-03-24T23:03:56Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Extinguen incendio en el crucero Carnival Freedom despu\\u00e9s de que testigos informaran sobre el posible impacto de un rayo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/24\\\/extinguen-incendio-crucero-carnival-freedom-impacto-rayo-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/24\\\/extinguen-incendio-crucero-carnival-freedom-impacto-rayo-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-24T23:03:56Z\",\"datePublished\":\"2024-03-24T23:03:56Z\",\"dateModified\":\"2024-03-24T23:03:56Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1450726,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/06\/26\/incendio-crucero-mas-grande-mundo-trax\/","url_meta":{"origin":1447303,"position":0},"title":"Se produce un incendio en el crucero m\u00e1s grande del mundo","author":"","date":"junio 26, 2024","format":false,"excerpt":"(CNN) -- La tripulaci\u00f3n a bordo del crucero m\u00e1s grande del mundo, el Icon of the Seas, fue llamada a combatir un incendio esta semana mientras el gigantesco barco estaba atracado en un puerto de M\u00e9xico.El \"peque\u00f1o incendio\" se \"extingui\u00f3 r\u00e1pidamente\" despu\u00e9s de que se desatara este martes, confirm\u00f3 a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444197,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/01\/21\/asi-fue-como-el-crucero-de-tres-anos-se-vino-abajo\/","url_meta":{"origin":1447303,"position":1},"title":"As\u00ed fue como el crucero de tres a\u00f1os se vino abajo","author":"","date":"enero 21, 2024","format":false,"excerpt":"(CNN) --\u00a0En abril de 2023, George Fox se estaba preparando para la aventura de su vida: un crucero de tres a\u00f1os que lo llevar\u00eda alrededor del mundo. La salida estaba programada para el crucero inaugural de Life at Sea, programado para salir de Estambul el 1 de noviembre.Solo hab\u00eda un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473762,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/05\/03\/hantavirus-crucero-muertos-trax\/","url_meta":{"origin":1447303,"position":2},"title":"Brote de hantavirus en un crucero deja tres muertos y otros gravemente enfermos; zarp\u00f3 desde Argentina","author":"","date":"mayo 3, 2026","format":false,"excerpt":"Un presunto brote de hantavirus en un crucero en el oc\u00e9ano Atl\u00e1ntico mat\u00f3 a tres personas y enferm\u00f3 al menos a otras tres, inform\u00f3 el domingo la Organizaci\u00f3n Mundial de la Salud.En un comunicado a The Associated Press, la OMS dijo que estaba en marcha una investigaci\u00f3n, pero que al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470516,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/01\/27\/tribunal-admite-buque-rusia-hundido-ucrania-trax\/","url_meta":{"origin":1447303,"position":3},"title":"Tras a\u00f1os de negaciones, un tribunal ruso admite accidentalmente que el buque insignia del mar Negro fue hundido por Ucrania","author":"","date":"enero 27, 2026","format":false,"excerpt":"Rusia admiti\u00f3 por primera vez que un misil ucraniano hundi\u00f3 su preciado buque insignia del mar Negro. Sin embargo, luego borr\u00f3 la declaraci\u00f3n y volvi\u00f3 a la versi\u00f3n oficial de que el crucero de misiles guiados Moskva se hundi\u00f3 debido a un extra\u00f1o accidente.El Moskva era uno de los buques\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466415,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/09\/13\/crucero-mas-grande-mundo-tres-naves-hermanas-gigante-trax\/","url_meta":{"origin":1447303,"position":4},"title":"\u00a1Son cuatrillizos! El crucero m\u00e1s grande del mundo tendr\u00e1 tres naves hermanas de tama\u00f1o gigante","author":"","date":"septiembre 13, 2025","format":false,"excerpt":"En nuestro resumen de viajes de esta semana: la capital europea con un laberinto submarino debajo de sus calles, por qu\u00e9 una empresa de surf de Abu Dhabi cree haber encontrado \u201cla ola perfecta\u201d y el auge de los cruceros XXL.El crucero m\u00e1s grande del mundo, Icon of the Seas,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444020,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/01\/17\/cualquier-cosa-puede-suceder-el-reality-show-de-la-vida-real-de-un-crucero-de-nueve-meses\/","url_meta":{"origin":1447303,"position":5},"title":"&#171;Cualquier cosa puede suceder&#187;: el &#171;reality show de la vida real&#187; de un crucero de nueve meses","author":"","date":"enero 17, 2024","format":false,"excerpt":"(CNN) -- Nueve meses. Siete continentes. Cientos de pasajeros en el mar. Millones m\u00e1s sigui\u00e9ndolo en l\u00ednea.Bienvenidos a bordo del Ultimate World Cruise de Royal Caribbean, que zarp\u00f3 hace un mes y ha cautivado inesperadamente la imaginaci\u00f3n de Internet.No, el crucero no es el primero de su clase: los viajes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1447303"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447303\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1447303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1447303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1447303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}