{"id":1447377,"date":"2024-03-26T08:03:50","date_gmt":"2024-03-26T15:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/26\/eeuu-haiti-santo-domingo-evacuados-orix\/"},"modified":"2024-03-26T08:03:50","modified_gmt":"2024-03-26T15:03:50","slug":"eeuu-haiti-santo-domingo-evacuados-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/26\/eeuu-haiti-santo-domingo-evacuados-orix\/","title":{"rendered":"EE.UU. ha evacuado de Hait\u00ed a Santo Domingo a 160 estadounidenses desde el 17 de marzo"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El Departamento de Estado de Estados Unidos dijo este jueves a CNN que desde el 17 de marzo han evacuado de Hait\u00ed a Santo Domingo, Rep\u00fablica Dominicana, a m\u00e1s de 160 ciudadanos estadounidenses.<\/p>\n<p>Los vuelos organizados por el gobierno de Estados Unidos para sacar a sus ciudadanos, en medio de la ola de violencia en Hait\u00ed, continuar\u00e1n este viernes, indic\u00f3 a CNN el portavoz de Aeropuertos Dominicanos Siglo XXI (Aerodom), Luis L\u00f3pez. Agreg\u00f3 que se prev\u00e9 que cuatro helic\u00f3pteros con capacidad para 18 personas cada uno aterricen en el Aeropuerto Internacional de Las Am\u00e9ricas.<\/p>\n<p>Los vuelos son operados por un helic\u00f3ptero comercial, agreg\u00f3 L\u00f3pez.<\/p>\n<p>En tanto, el Gobierno de Rep\u00fablica Dominicana report\u00f3 haber trasladado a 296 personas desde Hait\u00ed en evacuaciones preventivas o de emergencia, inform\u00f3 la Presidencia de ese pa\u00eds en un comunicado oficial.<\/p>\n<p>En los traslados se encontraba personal de la Uni\u00f3n Europea, el Banco Mundial, la Embajada de Canad\u00e1, el Fondo Monetario Internacional, las Naciones Unidas y la Embajada de Cuba.<\/p>\n<p>Entre los 296 evacuados hay 174 hombres, 105 mujeres, 9 ni\u00f1as y 8 ni\u00f1os, de acuerdo con lo informado por el Ministerio de Defensa dominicano (MIDE) en la nota de prensa del Gobierno.<\/p>\n<p>Colabor\u00f3 con este reporte Ivonne Vald\u00e9s<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El Departamento de Estado de Estados Unidos dijo este jueves a CNN que desde el 17 de marzo han evacuado de Hait\u00ed a Santo Domingo, Rep\u00fablica Dominicana, a m\u00e1s de 160 ciudadanos estadounidenses. Los vuelos organizados por el gobierno de Estados Unidos para sacar a sus ciudadanos, en medio de la ola [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1447377","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EE.UU. ha evacuado de Hait\u00ed a Santo Domingo a 160 estadounidenses desde el 17 de marzo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/03\/26\/eeuu-haiti-santo-domingo-evacuados-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EE.UU. ha evacuado de Hait\u00ed a Santo Domingo a 160 estadounidenses desde el 17 de marzo - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; El Departamento de Estado de Estados Unidos dijo este jueves a CNN que desde el 17 de marzo han evacuado de Hait\u00ed a Santo Domingo, Rep\u00fablica Dominicana, a m\u00e1s de 160 ciudadanos estadounidenses. Los vuelos organizados por el gobierno de Estados Unidos para sacar a sus ciudadanos, en medio de la ola [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/03\/26\/eeuu-haiti-santo-domingo-evacuados-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-26T15:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/26\/eeuu-haiti-santo-domingo-evacuados-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/26\/eeuu-haiti-santo-domingo-evacuados-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"EE.UU. ha evacuado de Hait\u00ed a Santo Domingo a 160 estadounidenses desde el 17 de marzo\",\"datePublished\":\"2024-03-26T15:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/26\/eeuu-haiti-santo-domingo-evacuados-orix\/\"},\"wordCount\":243,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/26\/eeuu-haiti-santo-domingo-evacuados-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/26\/eeuu-haiti-santo-domingo-evacuados-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/03\/26\/eeuu-haiti-santo-domingo-evacuados-orix\/\",\"name\":\"EE.UU. ha evacuado de Hait\u00ed a Santo Domingo a 160 estadounidenses desde el 17 de marzo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-26T15:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/26\/eeuu-haiti-santo-domingo-evacuados-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/26\/eeuu-haiti-santo-domingo-evacuados-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/26\/eeuu-haiti-santo-domingo-evacuados-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EE.UU. ha evacuado de Hait\u00ed a Santo Domingo a 160 estadounidenses desde el 17 de marzo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EE.UU. ha evacuado de Hait\u00ed a Santo Domingo a 160 estadounidenses desde el 17 de marzo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/03\/26\/eeuu-haiti-santo-domingo-evacuados-orix\/","og_locale":"es_ES","og_type":"article","og_title":"EE.UU. ha evacuado de Hait\u00ed a Santo Domingo a 160 estadounidenses desde el 17 de marzo - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; El Departamento de Estado de Estados Unidos dijo este jueves a CNN que desde el 17 de marzo han evacuado de Hait\u00ed a Santo Domingo, Rep\u00fablica Dominicana, a m\u00e1s de 160 ciudadanos estadounidenses. Los vuelos organizados por el gobierno de Estados Unidos para sacar a sus ciudadanos, en medio de la ola [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/03\/26\/eeuu-haiti-santo-domingo-evacuados-orix\/","og_site_name":"Noticias","article_published_time":"2024-03-26T15:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/03\/26\/eeuu-haiti-santo-domingo-evacuados-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/03\/26\/eeuu-haiti-santo-domingo-evacuados-orix\/"},"author":{"name":"","@id":""},"headline":"EE.UU. ha evacuado de Hait\u00ed a Santo Domingo a 160 estadounidenses desde el 17 de marzo","datePublished":"2024-03-26T15:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/03\/26\/eeuu-haiti-santo-domingo-evacuados-orix\/"},"wordCount":243,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/03\/26\/eeuu-haiti-santo-domingo-evacuados-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/03\/26\/eeuu-haiti-santo-domingo-evacuados-orix\/","url":"https:\/\/noticiasya.com\/2024\/03\/26\/eeuu-haiti-santo-domingo-evacuados-orix\/","name":"EE.UU. ha evacuado de Hait\u00ed a Santo Domingo a 160 estadounidenses desde el 17 de marzo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-26T15:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/03\/26\/eeuu-haiti-santo-domingo-evacuados-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/03\/26\/eeuu-haiti-santo-domingo-evacuados-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/03\/26\/eeuu-haiti-santo-domingo-evacuados-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"EE.UU. ha evacuado de Hait\u00ed a Santo Domingo a 160 estadounidenses desde el 17 de marzo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/26\/eeuu-haiti-santo-domingo-evacuados-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"EE.UU. ha evacuado de Hait\u00ed a Santo Domingo a 160 estadounidenses desde el 17 de marzo","url":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/26\/eeuu-haiti-santo-domingo-evacuados-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/26\/eeuu-haiti-santo-domingo-evacuados-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-26T15:03:50Z","datePublished":"2024-03-26T15:03:50Z","dateModified":"2024-03-26T15:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"EE.UU. ha evacuado de Hait\\u00ed a Santo Domingo a 160 estadounidenses desde el 17 de marzo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/26\\\/eeuu-haiti-santo-domingo-evacuados-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/26\\\/eeuu-haiti-santo-domingo-evacuados-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-26T15:03:50Z\",\"datePublished\":\"2024-03-26T15:03:50Z\",\"dateModified\":\"2024-03-26T15:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1447162,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/20\/estadounidenses-evacuan-haiti-helicoptero-trax\/","url_meta":{"origin":1447377,"position":0},"title":"M\u00e1s estadounidenses evacuan Hait\u00ed en un vuelo en helic\u00f3ptero de EE.UU. Se esperan &#171;m\u00faltiples&#187; viajes, seg\u00fan el Departamento de Estado","author":"","date":"marzo 20, 2024","format":false,"excerpt":"(CNN) -- Otro grupo de estadounidenses fue evacuado el mi\u00e9rcoles de Hait\u00ed en un vuelo organizado por Estados Unidos en helic\u00f3ptero, el m\u00e1s reciente de lo que el Departamento de Estado espera que sean \"m\u00faltiples viajes\" para sacar sanos y salvos a ciudadanos estadounidenses mientras la naci\u00f3n caribe\u00f1a se hunde\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447066,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/17\/republica-dominicana-evacua-27-ciudadanos-haiti-trax\/","url_meta":{"origin":1447377,"position":1},"title":"Rep\u00fablica Dominicana evacua a 27 de sus ciudadanos desde Hait\u00ed","author":"","date":"marzo 17, 2024","format":false,"excerpt":"(CNN) -- Rep\u00fablica Dominicana evacu\u00f3 a 27 de sus ciudadanos del vecino Hait\u00ed luego de que solicitaron salir debido a la actual inseguridad en ese pa\u00eds, dijo este domingo la Canciller\u00eda dominicana.Dieciocho hombres, siete mujeres y dos menores fueron sacados de Hait\u00ed en tres helic\u00f3pteros de la Fuerza A\u00e9rea Dominicana.Aterrizaron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447378,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/26\/avion-estadounidenses-evacuados-haiti-florida-trax\/","url_meta":{"origin":1447377,"position":2},"title":"Aterriz\u00f3 en Florida otro avi\u00f3n con ciudadanos estadounidenses que fueron evacuados de Hait\u00ed","author":"","date":"marzo 26, 2024","format":false,"excerpt":"(CNN) -- Un avi\u00f3n que transport\u00f3 a 21 estadounidenses que salieron de Hait\u00ed lleg\u00f3 a Orlando, Florida, el s\u00e1bado por la noche, el m\u00e1s reciente de una serie de vuelos fletados por Estados Unidos desde la asediada naci\u00f3n caribe\u00f1a, que se encuentra en caos en medio de una rampante violencia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458375,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/02\/06\/presidente-republica-dominicana-haiti-violencia-trax\/","url_meta":{"origin":1447377,"position":3},"title":"Presidente de Rep\u00fablica Dominicana dice no hay tiempo que perder para ayudar a Hait\u00ed a enfrentar la violencia de pandillas","author":"","date":"febrero 6, 2025","format":false,"excerpt":"El presidente de Rep\u00fablica Dominicana, Luis Abinader, dijo que la comunidad internacional \u201cno tiene tiempo que perder\u201d en apoyar al pa\u00eds vecino Hait\u00ed, que lucha por contener la violencia generalizada de las pandillas.Al hablar en una conferencia de prensa con el secretario de Estado de EE.UU., Marco Rubio, este jueves,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461621,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/04\/25\/republica-dominicana-haiti-violaciones-dd-hh-migrantes-orix\/","url_meta":{"origin":1447377,"position":4},"title":"Rep\u00fablica Dominicana rechaza se\u00f1alamientos de Hait\u00ed sobre violaciones de DD.HH. de migrantes","author":"","date":"abril 25, 2025","format":false,"excerpt":"El Gobierno de Rep\u00fablica Dominicana asegur\u00f3 este jueves que las repatriaciones de ciudadanos haitianos se realizan en cumplimiento de la ley, en rechazo a la denuncia emitida por el Consejo Presidencial de Transici\u00f3n (CPT) de Hait\u00ed, que calific\u00f3 las expulsiones como \u201cespecialmente preocupantes\u201d.La postura oficial se da en medio de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446881,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/12\/advertencia-republica-dominicana-haiti-luis-abinader-orix\/","url_meta":{"origin":1447377,"position":5},"title":"\u201cDespu\u00e9s no se quejen de las acciones que vamos a tener que hacer\u201d: la advertencia del presidente Luis Abinader por crisis en Hait\u00ed","author":"","date":"marzo 12, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de Rep\u00fablica Dominicana, Luis Abinader, dijo el lunes en rueda de prensa que tomar\u00e1n m\u00e1s medidas para proteger al pa\u00eds ante la crisis en Hait\u00ed. Advirti\u00f3 a la comunidad internacional que si no act\u00faa, \u201cdespu\u00e9s no se quejen\u201d de las acciones que su Gobierno pueda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1447377"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447377\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1447377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1447377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1447377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}