{"id":1447388,"date":"2024-03-26T14:03:47","date_gmt":"2024-03-26T21:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/26\/manuel-rosales-quien-es-venezuela-orix\/"},"modified":"2024-03-26T14:03:47","modified_gmt":"2024-03-26T21:03:47","slug":"manuel-rosales-quien-es-venezuela-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/26\/manuel-rosales-quien-es-venezuela-orix\/","title":{"rendered":"\u00bfQui\u00e9n es Manuel Rosales, el candidato presidencial opositor que s\u00ed se pudo inscribir en Venezuela?"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Manuel Rosales parece ser la carta que le queda a la oposici\u00f3n en Venezuela. Despu\u00e9s de que Corina Yoris no pudiera inscribir su candidatura en reemplazo de la inhabilitada Mar\u00eda Corina Machado \u2014ganadora de las primarias\u2014, Un Nuevo Tiempo (UNT), uno de los partidos pol\u00edticos que hab\u00eda apoyado a Machado, decidi\u00f3 a \u00faltima hora inscribir a su l\u00edder, el gobernador del estado Zulia, Manuel Rosales, quien no particip\u00f3 en las primarias.<\/p>\n<p>A pesar de la sorpresa de la postulaci\u00f3n, Machado no descart\u00f3 un acuerdo posterior con Rosales. &#171;Vamos d\u00eda a d\u00eda&#187;, dijo, al tiempo que ratific\u00f3 que su candidata ser\u00eda Corina Yoris, quien\u00a0en\u00a0entrevista con CNN\u00a0dijo que si\u00a0hubiese otra candidatura se romper\u00eda la unidad opositora.<\/p>\n<p>Este martes,\u00a0Rosales dijo en conferencia de prensa que se inscribi\u00f3 para no &#171;dejarle la cancha libre&#187; a Nicol\u00e1s Maduro, el presidente y candidato a la reelecci\u00f3n. Rosales, quien reconoci\u00f3 la labor de Machado, dijo que va a &#171;reconstruir Venezuela, sin odios&#187;, y que en las elecciones del 28 de julio el pa\u00eds est\u00e1 entre\u00a0votar &#171;o no votar para que Venezuela se caiga a pedazos&#187;.<\/p>\n<p>Manuel Rosales, l\u00edder en Zulia y rival de Ch\u00e1vez en 2006<\/p>\n<p>Rosales, de 71 a\u00f1os, es un dirigente opositor venezolano que ya fue candidato a presidente, se enfrent\u00f3 a Hugo Ch\u00e1vez y estuvo encarcelado. Ha sido diputado nacional por el Zulia, alcalde de Maracaibo y gobernador del Zulia en dos ocasiones.<\/p>\n<p>En 2002 fue uno de los firmantes del llamado &#171;Decreto Carmona&#187;, que buscaba establecer un Gobierno de transici\u00f3n tras el golpe de Estado del 11 de abril, en el que el presidente Hugo Ch\u00e1vez fue expulsado del poder durante\u00a047 horas y Pedro Carmona nombrado presidente. Ch\u00e1vez fue restablecido en el poder solo dos d\u00edas despu\u00e9s.\u00a0En 2006, Rosales dijo que fue un &#171;error&#187; de &#171;buena fe&#187;\u00a0haber firmado el decreto.<\/p>\n<p>M\u00e1s tarde\u00a0ese mismo a\u00f1o represent\u00f3 a la oposici\u00f3n\u00a0en las elecciones contra Ch\u00e1vez, donde result\u00f3 derrotado con el 36,9% de los votos\u00a0frente al 62,82% del presidente.<\/p>\n<p>En 2008, Manuel Rosales fue imputado de enriquecimiento il\u00edcito tras un informe presentado por la Contralor\u00eda General de la Rep\u00fablica y acusado formalmente por el Ministerio P\u00fablico en 2009. Rosales asegur\u00f3 ser inocente y v\u00edctima de persecuci\u00f3n pol\u00edtica.<\/p>\n<p>En abril de 2009 se solicit\u00f3 su captura, que no pudo ser concretada debido a su salida del pa\u00eds hacia Per\u00fa.<\/p>\n<p>En octubre de 2015, Rosales anunci\u00f3 su regreso a Venezuela pese a que todav\u00eda exist\u00eda una orden de captura en su contra. A su llegada\u00a0al pa\u00eds fue capturado, puesto bajo custodia y encarcelado, para ser liberado\u00a0en diciembre de 2016\u00a0tras haber estado en arresto domiciliario desde octubre. Su caso nunca lleg\u00f3 a juicio. En 2017 el Tribunal Supremo de Justicia suspendi\u00f3,\u00a0con un amparo cautelar,\u00a0la inhabilitaci\u00f3n en su contra impuesta en 2014, sentenciando que hubo violaci\u00f3n\u00a0a los derechos al debido proceso y la defensa.<\/p>\n<p>Ese a\u00f1o\u00a0neg\u00f3 en entrevista con CNN haber negociado su liberaci\u00f3n con el Gobierno de Maduro. Incluso reiter\u00f3 que segu\u00eda siendo cr\u00edtico al chavismo.<\/p>\n<p>Desde 2021, Rosales es gobernador del Zulia, estado petrolero ubicado en el occidente de Venezuela y fronterizo con Colombia. Ya hab\u00eda ocupado ese cargo entre 2000 y 2008, como representante del partido Acci\u00f3n Democr\u00e1tica, de tendencia socialdem\u00f3crata.<\/p>\n<p>Con informaci\u00f3n de Osmary Hern\u00e1ndez y Alfredo Meza<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Manuel Rosales parece ser la carta que le queda a la oposici\u00f3n en Venezuela. Despu\u00e9s de que Corina Yoris no pudiera inscribir su candidatura en reemplazo de la inhabilitada Mar\u00eda Corina Machado \u2014ganadora de las primarias\u2014, Un Nuevo Tiempo (UNT), uno de los partidos pol\u00edticos que hab\u00eda apoyado a Machado, decidi\u00f3 a [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1447388","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQui\u00e9n es Manuel Rosales, el candidato presidencial opositor que s\u00ed se pudo inscribir en Venezuela? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/03\/26\/manuel-rosales-quien-es-venezuela-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQui\u00e9n es Manuel Rosales, el candidato presidencial opositor que s\u00ed se pudo inscribir en Venezuela? - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; Manuel Rosales parece ser la carta que le queda a la oposici\u00f3n en Venezuela. Despu\u00e9s de que Corina Yoris no pudiera inscribir su candidatura en reemplazo de la inhabilitada Mar\u00eda Corina Machado \u2014ganadora de las primarias\u2014, Un Nuevo Tiempo (UNT), uno de los partidos pol\u00edticos que hab\u00eda apoyado a Machado, decidi\u00f3 a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/03\/26\/manuel-rosales-quien-es-venezuela-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-26T21:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/26\/manuel-rosales-quien-es-venezuela-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/26\/manuel-rosales-quien-es-venezuela-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfQui\u00e9n es Manuel Rosales, el candidato presidencial opositor que s\u00ed se pudo inscribir en Venezuela?\",\"datePublished\":\"2024-03-26T21:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/26\/manuel-rosales-quien-es-venezuela-orix\/\"},\"wordCount\":617,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/26\/manuel-rosales-quien-es-venezuela-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/26\/manuel-rosales-quien-es-venezuela-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/03\/26\/manuel-rosales-quien-es-venezuela-orix\/\",\"name\":\"\u00bfQui\u00e9n es Manuel Rosales, el candidato presidencial opositor que s\u00ed se pudo inscribir en Venezuela? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-26T21:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/26\/manuel-rosales-quien-es-venezuela-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/26\/manuel-rosales-quien-es-venezuela-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/26\/manuel-rosales-quien-es-venezuela-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQui\u00e9n es Manuel Rosales, el candidato presidencial opositor que s\u00ed se pudo inscribir en Venezuela?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQui\u00e9n es Manuel Rosales, el candidato presidencial opositor que s\u00ed se pudo inscribir en Venezuela? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/03\/26\/manuel-rosales-quien-es-venezuela-orix\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQui\u00e9n es Manuel Rosales, el candidato presidencial opositor que s\u00ed se pudo inscribir en Venezuela? - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; Manuel Rosales parece ser la carta que le queda a la oposici\u00f3n en Venezuela. Despu\u00e9s de que Corina Yoris no pudiera inscribir su candidatura en reemplazo de la inhabilitada Mar\u00eda Corina Machado \u2014ganadora de las primarias\u2014, Un Nuevo Tiempo (UNT), uno de los partidos pol\u00edticos que hab\u00eda apoyado a Machado, decidi\u00f3 a [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/03\/26\/manuel-rosales-quien-es-venezuela-orix\/","og_site_name":"Noticias","article_published_time":"2024-03-26T21:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/03\/26\/manuel-rosales-quien-es-venezuela-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/03\/26\/manuel-rosales-quien-es-venezuela-orix\/"},"author":{"name":"","@id":""},"headline":"\u00bfQui\u00e9n es Manuel Rosales, el candidato presidencial opositor que s\u00ed se pudo inscribir en Venezuela?","datePublished":"2024-03-26T21:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/03\/26\/manuel-rosales-quien-es-venezuela-orix\/"},"wordCount":617,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/03\/26\/manuel-rosales-quien-es-venezuela-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/03\/26\/manuel-rosales-quien-es-venezuela-orix\/","url":"https:\/\/noticiasya.com\/2024\/03\/26\/manuel-rosales-quien-es-venezuela-orix\/","name":"\u00bfQui\u00e9n es Manuel Rosales, el candidato presidencial opositor que s\u00ed se pudo inscribir en Venezuela? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-26T21:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/03\/26\/manuel-rosales-quien-es-venezuela-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/03\/26\/manuel-rosales-quien-es-venezuela-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/03\/26\/manuel-rosales-quien-es-venezuela-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQui\u00e9n es Manuel Rosales, el candidato presidencial opositor que s\u00ed se pudo inscribir en Venezuela?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/26\/manuel-rosales-quien-es-venezuela-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfQui\u00e9n es Manuel Rosales, el candidato presidencial opositor que s\u00ed se pudo inscribir en Venezuela?","url":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/26\/manuel-rosales-quien-es-venezuela-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/26\/manuel-rosales-quien-es-venezuela-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-26T21:03:47Z","datePublished":"2024-03-26T21:03:47Z","dateModified":"2024-03-26T21:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfQui\\u00e9n es Manuel Rosales, el candidato presidencial opositor que s\\u00ed se pudo inscribir en Venezuela?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/26\\\/manuel-rosales-quien-es-venezuela-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/26\\\/manuel-rosales-quien-es-venezuela-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-26T21:03:47Z\",\"datePublished\":\"2024-03-26T21:03:47Z\",\"dateModified\":\"2024-03-26T21:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1447382,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/26\/oposicion-venezuela-corina-machado-corina-yoris-inscripcion-elecciones-venezuela-orix\/","url_meta":{"origin":1447388,"position":0},"title":"La oposici\u00f3n mayoritaria no pudo inscribir a la sustituta de Machado. \u00bfQu\u00e9 viene ahora?","author":"","date":"marzo 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La Plataforma Unitaria Democr\u00e1tica (PUD) no pudo inscribir a Corina Yoris, la candidata propuesta por la ganadora de las primarias, Mar\u00eda Corina Machado, para sustituirla en la elecci\u00f3n presidencial, porque no le permitieron el acceso al sistema de postulaciones del Consejo Nacional Electoral, seg\u00fan denunci\u00f3 la l\u00edder\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447354,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/25\/corina-yoris-conclusiones-entrevista-orix\/","url_meta":{"origin":1447388,"position":1},"title":"Corina Yoris no ha podido inscribir su candidatura: &#171;Est\u00e1n cercenando el derecho a millones de venezolanos; son horas muy oscuras&#187;","author":"","date":"marzo 25, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La opositora venezolana Corina Yoris, quien denunci\u00f3 que no pudo inscribirse como candidata presidencial, dijo a CNN en Espa\u00f1ol que \u201cson horas oscuras, por no decir negras, en la realidad pol\u00edtica venezolana\u201d. Yoris fue la aspirante elegida para sustituir en la elecci\u00f3n presidencial a Mar\u00eda Corina Machado,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447277,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/23\/oposicion-venezolana-denuncia-problemas-inscribir-corina-yoris-orix\/","url_meta":{"origin":1447388,"position":2},"title":"Oposici\u00f3n venezolana denuncia problemas para inscribir a candidata presidencial Corina Yoris","author":"","date":"marzo 23, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0La oposici\u00f3n venezolana denunci\u00f3 este s\u00e1bado que a\u00fan no ha podido inscribir oficialmente a Corina Yoris como candidata presidencial para los comicios de julio, un plazo que oficialmente termina este lunes.\"Tras cerca de 72 horas del inicio del proceso postulaci\u00f3n de candidaturas presidenciales, denunciamos que el sistema del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447938,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/04\/10\/petro-oposicion-venezolana-orix\/","url_meta":{"origin":1447388,"position":3},"title":"Petro dice que se reuni\u00f3 con la oposici\u00f3n venezolana, pero all\u00ed se preguntan con qui\u00e9n","author":"","date":"abril 10, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Cerca del mediod\u00eda de este mi\u00e9rcoles, el presidente de Colombia, Gustavo Petro, inform\u00f3 en sus redes sociales que as\u00ed como el martes se reuni\u00f3 con su hom\u00f3logo de Venezuela, Nicol\u00e1s Maduro, este mi\u00e9rcoles lo hizo con sectores de la oposici\u00f3n venezolana, seg\u00fan dijo, \u201cen la perspectiva de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447349,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/25\/maduro-candidato-oposicion-elecciones-orix\/","url_meta":{"origin":1447388,"position":4},"title":"Maduro se registra como candidato y le dice a la oposici\u00f3n: \u201cHabr\u00e1 elecciones con ustedes o sin ustedes\u201d","author":"","date":"marzo 25, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de Venezuela, Nicol\u00e1s Maduro, no tuvo contratiempos este lunes para registrarse como candidato presidencial del Partido Socialista Unido de Venezuela (PSUV), en un acto p\u00fablico en el que dijo que el 28 de julio habr\u00e1 elecciones con o sin la oposici\u00f3n.El oficialismo en Venezuela nombra\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447258,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/22\/machado-corina-yoris-sustituta-candidatura-oposicion-venezuela-orix\/","url_meta":{"origin":1447388,"position":5},"title":"Machado designa a Corina Yoris como su sustituta en la candidatura de la Plataforma Unitaria de la oposici\u00f3n venezolana","author":"","date":"marzo 22, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 La l\u00edder opositora venezolana Mar\u00eda Corina Machado anunci\u00f3 este viernes a la acad\u00e9mica Corina Yoris como su sustituta en la candidatura de la Plataforma Unitaria Democr\u00e1tica (PUD), que re\u00fane a los partidos mayoritarios de la oposici\u00f3n al Gobierno de Venezuela, para las elecciones presidenciales del pr\u00f3ximo 28\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1447388"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447388\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1447388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1447388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1447388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}