{"id":1447414,"date":"2024-03-27T01:03:51","date_gmt":"2024-03-27T08:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/27\/fda-aprueba-medicamento-sotatercept-winrevair-hap-trax\/"},"modified":"2024-03-27T01:03:51","modified_gmt":"2024-03-27T08:03:51","slug":"fda-aprueba-medicamento-sotatercept-winrevair-hap-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/27\/fda-aprueba-medicamento-sotatercept-winrevair-hap-trax\/","title":{"rendered":"La FDA aprueba nuevo medicamento que puede ayudar a detener e incluso revertir una afecci\u00f3n rara y fatal que los m\u00e9dicos llaman una &#8216;bomba de tiempo&#8217;"},"content":{"rendered":"<p>(CNN) &#8212; Cuando los m\u00e9dicos le dijeron a Katrina Barry que ten\u00eda una afecci\u00f3n rara y grave llamada hipertensi\u00f3n arterial pulmonar o HAP, le advirtieron que no buscara informaci\u00f3n en Internet.<\/p>\n<p>Vamos, pens\u00f3; \u00bfquer\u00edan que una joven que se dirig\u00eda a la escuela de posgrado, que hab\u00eda sobrevivido a un vuelo transatl\u00e1ntico mientras ten\u00eda un ataque al coraz\u00f3n y ahora una cirug\u00eda a coraz\u00f3n abierto, no buscara la condici\u00f3n que segu\u00eda intentando matarla?<\/p>\n<p>Esper\u00e1ndola en internet hab\u00eda informaci\u00f3n inquietante. La HAP afecta a aproximadamente de 500 a 1.000 estadounidenses cada a\u00f1o, a menudo mujeres entre las edades de 30 y 60 a\u00f1os, seg\u00fan la Asociaci\u00f3n Estadounidense del Pulm\u00f3n.<\/p>\n<p>Barry, que ten\u00eda 25 a\u00f1os en ese momento, descubri\u00f3 en su lectura que ten\u00eda de dos a cinco a\u00f1os de vida, seg\u00fan la gravedad de su condici\u00f3n en ese momento.<\/p>\n<p>Luego, su equipo m\u00e9dico le ofreci\u00f3 una posible tabla de salvaci\u00f3n: un medicamento experimental \u00fanico en su tipo llamado sotatercept que atrapa un factor de crecimiento que se produce en exceso en personas con HAP, cambiando potencialmente la biolog\u00eda subyacente de la enfermedad.<\/p>\n<p>D\u00eda Mundial de las Enfermedades Raras: \u00bfqu\u00e9 son y c\u00f3mo identificarlas?<\/p>\n<p>Se inscribi\u00f3 en un estudio para probar el medicamento, que se administra cada tres semanas por inyecci\u00f3n bajo la piel.<\/p>\n<p>Comenz\u00f3 el tratamiento al amanecer de la pandemia de covid-19, en marzo de 2020. Barry dijo que usaba diligentemente una mascarilla N95 y dos capas de ropa y se lavaba despu\u00e9s de cada viaje al hospital para sus inyecciones para evitar contraer covid en el camino.<\/p>\n<p>&#171;Tuve que ir al hospital porque me estaba muriendo si no recib\u00eda este medicamento&#187;, dijo. &#171;Esta era la \u00fanica oportunidad que ten\u00eda de sobrevivir&#187;.<\/p>\n<p>Este martes, la Administraci\u00f3n de Alimentos y Medicamentos de Estados Unidos (FDA) aprob\u00f3 el medicamento que Barry ha tomado durante cuatro a\u00f1os, un medicamento al que atribuye haberla mantenido viva y haberle permitido reanudar muchas de las actividades que disfrutaba antes de su diagn\u00f3stico.<\/p>\n<p>Merck, la empresa que fabrica el medicamento, dijo que se vender\u00e1 bajo el nombre de marca Winrevair.<\/p>\n<p>Barry, ahora de 29 a\u00f1os, es consultora de pacientes para Merck, pero dijo que no ha recibido compensaci\u00f3n por contar su historia.<\/p>\n<p>Winrevair fue aprobado por la FDA el martes para ayudar a tratar la hipertensi\u00f3n arterial pulmonar. (Cr\u00e9dito: Cortes\u00eda de Merck)<\/p>\n<p>Winrevair es un medicamento biol\u00f3gico dise\u00f1ado para atrapar y retener prote\u00ednas llamadas activinas que se producen en exceso en las personas que tienen HAP. Estas prote\u00ednas hacen que las paredes de los vasos sangu\u00edneos de una persona sigan creciendo y engros\u00e1ndose con el tiempo.<\/p>\n<p>A medida que los vasos sangu\u00edneos se estrechan, el coraz\u00f3n se ve obligado a trabajar m\u00e1s para bombear sangre a los pulmones. Este estr\u00e9s eventualmente da\u00f1a el coraz\u00f3n, causando que falle.<\/p>\n<p>Sin tratamiento, las personas con HAP suelen vivir unos dos o tres a\u00f1os despu\u00e9s de su diagn\u00f3stico. El tratamiento con una combinaci\u00f3n de medicamentos que dilatan o relajan los vasos sangu\u00edneos puede mejorar esta perspectiva, pero no son una cura.<\/p>\n<p>&#171;Este medicamento tiene un mecanismo de acci\u00f3n muy diferente, y puede reequilibrar realmente parte del crecimiento que ocurre en los arteriolos pulmonares muy peque\u00f1os donde comienza la enfermedad&#187;, dijo la Dra. Vallerie McLaughlin, cardi\u00f3loga de la Universidad de Michigan que ayud\u00f3 a estudiar sotatercept.<\/p>\n<p>&#171;Eso puede atacar la enfermedad desde un \u00e1ngulo diferente y permitir lo que llamamos remodelaci\u00f3n inversa&#187;, dijo, lo que significa que los pacientes podr\u00edan mejorar con el tiempo mientras toman el medicamento.<\/p>\n<p>Winrevair es el primer tipo nuevo de medicamento que surge para pacientes con HAP en mucho tiempo, dijo el Dr. Panagis Galiatsatos, especialista en medicina pulmonar y de cuidados cr\u00edticos en el Centro M\u00e9dico Bayview de Johns Hopkins y portavoz de la Asociaci\u00f3n Estadounidense del Pulm\u00f3n.<\/p>\n<p>La FDA advierte contra el uso de dispositivos inteligentes como relojes y anillos para medir el az\u00facar en sangre<\/p>\n<p>En estudios con animales realizados antes de los ensayos en humanos, el medicamento parec\u00eda poder hacer m\u00e1s que solo tratar los s\u00edntomas: parec\u00eda que podr\u00eda detener el engrosamiento de los vasos sangu\u00edneos y tal vez prolongar la vida de los pacientes, pero esos beneficios no se han demostrado en humanos.<\/p>\n<p>En cambio, dijo Galiatsatos, la FDA aprob\u00f3 el medicamento bas\u00e1ndose en otras se\u00f1ales de efectividad, incluido si los pacientes pod\u00edan caminar m\u00e1s lejos en seis minutos de lo que pod\u00edan antes de comenzar a tomar el medicamento, una medida cl\u00ednica llamada prueba de caminata de seis minutos.<\/p>\n<p>En un estudio que incluy\u00f3 a 323 personas que tomaron sotatercept o un placebo durante seis meses, aquellos que recibieron el medicamento pudieron caminar 34 metros, aproximadamente media cuadra de la ciudad, m\u00e1s lejos en seis minutos de lo que pod\u00edan antes de comenzar el tratamiento, mientras que las personas en el grupo placebo pudieron caminar solo alrededor de 1 metro m\u00e1s de lo que pod\u00edan cuando comenzaron el estudio. Ambos grupos tambi\u00e9n estaban tomando los medicamentos est\u00e1ndar para la condici\u00f3n, que ayudan a relajar los vasos sangu\u00edneos para mejorar el flujo sangu\u00edneo.<\/p>\n<p>Al final del estudio, nueve participantes, o aproximadamente el 5%, en el grupo de sotatercept hab\u00edan muerto o su enfermedad hab\u00eda empeorado, mientras que 42 pacientes, o aproximadamente el 26%, en el grupo que tomaba un placebo hab\u00edan muerto o empeorado.<\/p>\n<p>La FDA estuvo dispuesta a actuar r\u00e1pidamente para aprobar el medicamento porque la enfermedad, dijo Galiatsatos, es una &#171;bomba de tiempo&#187; para quienes no pueden esperar estudios m\u00e1s largos.<\/p>\n<p>El estudio que llev\u00f3 a la aprobaci\u00f3n del medicamento se public\u00f3 en el New England Journal of Medicine el a\u00f1o pasado.<\/p>\n<p>&#171;Muchos de nosotros estamos emocionados con un medicamento como este, para poder ofrecer a nuestros pacientes algo que creemos que es mejor que su terapia est\u00e1ndar actual&#187;, dijo Galiatsatos, quien se\u00f1al\u00f3 que ni \u00e9l ni la Asociaci\u00f3n Estadounidense del Pulm\u00f3n tienen ning\u00fan inter\u00e9s financiero en el medicamento.<\/p>\n<p>Pero Galiatsatos dijo que por prometedor que parezca el medicamento, todav\u00eda hay muchas inc\u00f3gnitas, como si el medicamento beneficiar\u00e1 a todos los pacientes con HAP por igual. Aunque un n\u00famero significativo de personas diagnosticadas con la enfermedad son afroamericanas, se\u00f1al\u00f3, solo siete personas en el ensayo cl\u00ednico, que representan el 2% de los participantes, eran negras.<\/p>\n<p>&#171;Tiendo a contener la respiraci\u00f3n&#187; con cualquier nuevo medicamento, dijo Galiatsatos, agregando que &#171;est\u00e1 esperando que lleguen los datos del mundo real para ver qu\u00e9 tan bien funcion\u00f3 esto en pacientes m\u00e1s diversos&#187;.<\/p>\n<p>Un gen que proteg\u00eda a los humanos hace 5.000 a\u00f1os podr\u00eda estar relacionado con una enfermedad moderna degenerativa<\/p>\n<p>Como &#171;un milagro&#187;<\/p>\n<p>En julio de 2019, Barry hab\u00eda alquilado un apartamento para el verano en Grecia, donde estaba ansiosa por hacer trabajo voluntario en un hospital infantil. Pero mientras estaba en el extranjero, la falta de aliento por la que hab\u00eda estado preguntando a los m\u00e9dicos durante m\u00e1s de dos a\u00f1os empeor\u00f3 repentinamente.<\/p>\n<p>Se despert\u00f3 una ma\u00f1ana jadeando por aire y se dio cuenta de que la situaci\u00f3n era grave. Sab\u00eda que ten\u00eda que volver a casa a Boston en busca de ayuda. Llam\u00f3 a su madre, y reservaron un vuelo para que ella regresara a Estados Unidos.<\/p>\n<p>Aterriz\u00f3 en el aeropuerto y fue directamente al hospital. All\u00ed, los m\u00e9dicos le hicieron una tomograf\u00eda computarizada y encontraron lo que parec\u00edan docenas de co\u00e1gulos sangu\u00edneos en los diminutos vasos que recorren los pulmones. Su coraz\u00f3n hab\u00eda sido gravemente da\u00f1ado por un ataque al coraz\u00f3n.<\/p>\n<p>&#171;El cardi\u00f3logo dijo que mi nivel de da\u00f1o card\u00edaco no se encuentra hasta la autopsia&#187;, dijo Barry. &#171;Y todos los m\u00e9dicos dijeron que no deber\u00eda haber sobrevivido a ese vuelo a casa&#187;.<\/p>\n<p>Sigui\u00f3 una delicada operaci\u00f3n para eliminar los co\u00e1gulos, pero los cirujanos que le abrieron el pecho descubrieron que sus vasos sangu\u00edneos en realidad se hab\u00edan colapsado en muchas \u00e1reas, imitando a los co\u00e1gulos sangu\u00edneos. La presi\u00f3n arterial dentro de su coraz\u00f3n estaba por las nubes, y fue entonces cuando finalmente supieron con qu\u00e9 estaban lidiando: HAP, dijo.<\/p>\n<p>Debido a que la enfermedad es rara y a menudo afecta a mujeres j\u00f3venes, los retrasos en el diagn\u00f3stico son lamentablemente comunes, dijo Barry.<\/p>\n<p>FDA investiga informes sobre p\u00e9rdida de cabello y pensamientos suicidas en personas que usan medicamentos populares para la diabetes y para perder peso<\/p>\n<p>Mientras los m\u00e9dicos estaban calentando el cuerpo de Barry para sacarla de la cirug\u00eda, su coraz\u00f3n no volv\u00eda a arrancar. Pas\u00f3 una semana en un coma inducido en una m\u00e1quina de bypass card\u00edaco-pulmonar. El equipo m\u00e9dico le dijo a sus padres que probablemente necesitar\u00eda un trasplante de coraz\u00f3n-pulm\u00f3n inmediato.<\/p>\n<p>Despu\u00e9s de unos d\u00edas en la m\u00e1quina de bypass, sin embargo, su cuerpo comenz\u00f3 a recuperarse, y los m\u00e9dicos pudieron sacarla del coma.<\/p>\n<p>Cuando se despert\u00f3, se enter\u00f3 de su diagn\u00f3stico de hipertensi\u00f3n pulmonar.<\/p>\n<p>A los 25 a\u00f1os, enfrentando una vida mucho m\u00e1s corta de lo esperado, Barry ve\u00eda todo de manera diferente.<\/p>\n<p>&#171;\u00bfPor qu\u00e9 estoy ahorrando si no voy a tener una jubilaci\u00f3n?&#187;, se preguntaba. &#171;D\u00e9jame disfrutar de la vida que tengo ahora&#187;.<\/p>\n<p>Pero ni siquiera quedaba mucha vida para disfrutar, dijo.<\/p>\n<p>Katrina Barry caminando en Grecia en 2022. (Cr\u00e9dito: Cortes\u00eda de Katrina Barry)<\/p>\n<p>Estaba atada a tanques de ox\u00edgeno y siempre se preguntaba cu\u00e1ntos necesitar\u00eda por el tiempo que quisiera estar fuera de casa. Tambi\u00e9n hab\u00eda una gran bomba de medicaci\u00f3n nueva que viv\u00eda en una ri\u00f1onera que nunca pod\u00eda quitarse, ni siquiera para ducharse.<\/p>\n<p>La bomba suministraba un flujo continuo de medicamentos a trav\u00e9s de un cat\u00e9ter insertado directamente en una vena grande de su cuerpo para ayudar a mantener abiertos sus vasos sangu\u00edneos. Si algo le sucediera a la bomba, le dijeron que ten\u00eda tres horas para llegar al hospital m\u00e1s cercano para recibir ayuda.<\/p>\n<p>Estar viva era agradable y todo, pens\u00f3 Barry, pero \u00bfqu\u00e9 pasa con usar un vestido? \u00bfQu\u00e9 pasa con ir a nadar?<\/p>\n<p>&#171;La lista de todas las cosas que no pod\u00eda hacer continuaba&#187;, dijo.<\/p>\n<p>Barry fue diagnosticada poco despu\u00e9s de su cirug\u00eda en octubre de 2019, y aprovech\u00f3 la oportunidad de probar sotatercept en la primavera de 2020. Las mejoras no fueron instant\u00e1neas, pero despu\u00e9s de unos meses, pas\u00f3 de no poder siquiera doblar su ropa a poder hacer un poco m\u00e1s. Pudo hacer caminatas cortas y remar un poco.<\/p>\n<p>Despu\u00e9s de un a\u00f1o, dijo Barry, pudo dejar de usar ox\u00edgeno continuo y usarlo solo por la noche. Eventualmente pudo dejar de usarlo por la noche tambi\u00e9n.<\/p>\n<p>La FDA aprueba la primera p\u00edldora para la depresi\u00f3n posparto en EE.UU. (2023)<\/p>\n<p>Despu\u00e9s de aproximadamente 18 meses, los m\u00e9dicos pudieron quitarle su l\u00ednea central y la voluminosa bomba de med, lo que le permiti\u00f3 cambiar de las versiones intravenosas de sus medicamentos vasodilatadores a las formas en pastillas.<\/p>\n<p>&#171;Para m\u00ed, eso fue tan cambiante en la vida&#187;, dijo Barry.<\/p>\n<p>Mejor\u00f3 tanto que pudo regresar a Grecia en 2022 y hacer senderismo en un volc\u00e1n. El mes pasado, fue a esquiar.<\/p>\n<p>Barry todav\u00eda tiene HAP. Sus pulmones arden y se queda sin aliento si se esfuerza mucho.<\/p>\n<p>&#171;Pero ha mejorado con el tiempo&#187;, dijo Barry.<\/p>\n<p>Est\u00e1 inscrita en un programa de maestr\u00eda en salud p\u00fablica, y pudo usar un vestido en la boda de su hermano. No ha necesitado el trasplante de coraz\u00f3n y pulm\u00f3n que los m\u00e9dicos pensaron que podr\u00eda necesitar.<\/p>\n<p>&#171;Es un medicamento milagroso, honestamente&#187;, dijo sobre el sotatercept. &#171;Suena extra\u00f1o decirlo, pero dio tantas cosas positivas y no tantas negativas&#187;.<\/p>\n<p>Sabe que al menos una persona en la comunidad de HAP, muy unida, experiment\u00f3 sangrado mientras tomaba el medicamento y tuvo que dejar de tomarlo.<\/p>\n<p>Sangrado y mareos entre los riesgos<\/p>\n<p>En los ensayos cl\u00ednicos, las personas que tomaban sotatercept ten\u00edan m\u00e1s sangrados nasales debido a la ruptura de los vasos sangu\u00edneos en sus narices, y desarrollaron m\u00e1s venas de ara\u00f1a debajo de su piel. Los expertos dicen que el medicamento puede estimular el crecimiento de nuevos vasos sangu\u00edneos.<\/p>\n<p>Otros efectos secundarios incluyeron mareos y aumento de hemoglobina, la mol\u00e9cula que transporta ox\u00edgeno en la sangre. Algunas personas con HAP ya tienen niveles elevados de hemoglobina, ya que sus cuerpos intentan compensar la condici\u00f3n, por lo que agregar el medicamento encima de eso podr\u00eda ser demasiado para ellos, dijeron los expertos.<\/p>\n<p>Sotatercept tambi\u00e9n puede disminuir las plaquetas, las c\u00e9lulas que ayudan a formar co\u00e1gulos, lo que aumenta el riesgo de sangrado.<\/p>\n<p>&#171;Ha habido algunos informes de sangrado gastrointestinal e incluso sangrado dentro del cerebro&#187;, dijo la Dra. Kristin Highland, especialista en pulmones en la Cl\u00ednica Cleveland que trata a personas con HAP. &#171;Entonces, el sangrado es probablemente un efecto secundario real&#187;.<\/p>\n<p>Los m\u00e9dicos que han probado sotatercept creen que podr\u00eda ser un gran avance. Pero tambi\u00e9n reconocen que todav\u00eda hay muchas inc\u00f3gnitas, como si las personas que toman sotatercept necesitar\u00e1n seguir tomando la combinaci\u00f3n de medicamentos que ayudan a relajar sus vasos sangu\u00edneos y reducir su presi\u00f3n arterial, dijo Highland.<\/p>\n<p>Un procedimiento innovador permite que las reparaciones card\u00edacas crezcan con los ni\u00f1os, seg\u00fan muestra un nuevo estudio<\/p>\n<p>&#171;Esa es la pregunta del mill\u00f3n de d\u00f3lares&#187;, dijo. &#171;Ciertamente, hay mucha esperanza de que tal vez esto permitir\u00eda dosis m\u00e1s bajas o posiblemente la eliminaci\u00f3n de una de esas terapias. Pero no creo que tengamos la respuesta a eso&#187;.<\/p>\n<p>Merck dice que planea cobrar un costo mayorista de US$ 14.000 por vial y la dosificaci\u00f3n se basa en el peso del paciente. El medicamento vendr\u00e1 en kits de vial \u00fanico o doble que se pueden usar en casa.<\/p>\n<p>Bas\u00e1ndose en datos de ensayos cl\u00ednicos, Merck dice que espera que la mayor\u00eda de los pacientes necesiten un vial \u00fanico cada tres semanas, por un costo anual de alrededor de US$ 243.000.<\/p>\n<p>El costo mayorista no es t\u00edpicamente lo que pagan los pacientes. El costo final para los individuos se determina despu\u00e9s de que los proveedores de seguros negocian el precio.<\/p>\n<p>A\u00fan as\u00ed, eso es significativamente m\u00e1s de lo que algunos analistas esperaban ver. El Instituto para la Revisi\u00f3n Cl\u00ednica y Econ\u00f3mica, una organizaci\u00f3n sin fines de lucro, dijo que los beneficios del medicamento valdr\u00edan el costo alrededor de US$ 35.000 por a\u00f1o.<\/p>\n<p>Merck dijo en un comunicado de prensa que esperaba que el medicamento estuviera en farmacias especializadas para fines de abril.<\/p>\n<p>Al menos inicialmente, los pacientes tienen que recibir sus inyecciones de sotatercept en una cl\u00ednica, donde pueden ser monitoreados. Con el tiempo, dijo Barry, pudo comenzar a darse las inyecciones en casa, lo que ha sido m\u00e1s conveniente.<\/p>\n<p>El Dr. Aaron Waxman, m\u00e9dico de Barry y director del programa de enfermedad vascular pulmonar en el Hospital Brigham and Women&#8217;s de Boston, dijo que ha visto a otros pacientes que han tenido tanto \u00e9xito como ella en los seis a\u00f1os que han estado estudiando el medicamento. Esas personas tambi\u00e9n han podido dejar sus bombas de med y cambiar a p\u00edldoras para sus otras terapias.<\/p>\n<p>Una de esas p\u00edldoras, Opsynvi, una nueva combinaci\u00f3n de dos medicamentos com\u00fanmente tomados fabricados por Johnson &#038; Johnson, recibi\u00f3 la aprobaci\u00f3n de la FDA el lunes para tratar la HAP.<\/p>\n<p>&#171;Estamos viendo una mejora marcada que sugerir\u00eda una reversi\u00f3n&#187; de la enfermedad con sotatercept, dijo Waxman.<\/p>\n<p>&#171;Nunca he visto este tipo de mejora en la enfermedad antes&#187;, dijo. &#171;Creo que esto cambiar\u00e1 el juego&#187;.<\/p>\n<p>Barry dice que el medicamento ya ha sido un faro para personas que pueden no tener mucho por qu\u00e9 luchar.<\/p>\n<p>&#171;Ha tra\u00eddo tanta esperanza a personas que han perdido toda esperanza debido a esta enfermedad fatal&#187;, dijo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Cuando los m\u00e9dicos le dijeron a Katrina Barry que ten\u00eda una afecci\u00f3n rara y grave llamada hipertensi\u00f3n arterial pulmonar o HAP, le advirtieron que no buscara informaci\u00f3n en Internet. Vamos, pens\u00f3; \u00bfquer\u00edan que una joven que se dirig\u00eda a la escuela de posgrado, que hab\u00eda sobrevivido a un vuelo transatl\u00e1ntico mientras ten\u00eda un [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1447414","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La FDA aprueba nuevo medicamento que puede ayudar a detener e incluso revertir una afecci\u00f3n rara y fatal que los m\u00e9dicos llaman una &#039;bomba de tiempo&#039; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/03\/27\/fda-aprueba-medicamento-sotatercept-winrevair-hap-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La FDA aprueba nuevo medicamento que puede ayudar a detener e incluso revertir una afecci\u00f3n rara y fatal que los m\u00e9dicos llaman una &#039;bomba de tiempo&#039; - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Cuando los m\u00e9dicos le dijeron a Katrina Barry que ten\u00eda una afecci\u00f3n rara y grave llamada hipertensi\u00f3n arterial pulmonar o HAP, le advirtieron que no buscara informaci\u00f3n en Internet. Vamos, pens\u00f3; \u00bfquer\u00edan que una joven que se dirig\u00eda a la escuela de posgrado, que hab\u00eda sobrevivido a un vuelo transatl\u00e1ntico mientras ten\u00eda un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/03\/27\/fda-aprueba-medicamento-sotatercept-winrevair-hap-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-27T08:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/27\/fda-aprueba-medicamento-sotatercept-winrevair-hap-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/27\/fda-aprueba-medicamento-sotatercept-winrevair-hap-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La FDA aprueba nuevo medicamento que puede ayudar a detener e incluso revertir una afecci\u00f3n rara y fatal que los m\u00e9dicos llaman una &#8216;bomba de tiempo&#8217;\",\"datePublished\":\"2024-03-27T08:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/27\/fda-aprueba-medicamento-sotatercept-winrevair-hap-trax\/\"},\"wordCount\":2826,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/27\/fda-aprueba-medicamento-sotatercept-winrevair-hap-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/27\/fda-aprueba-medicamento-sotatercept-winrevair-hap-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/03\/27\/fda-aprueba-medicamento-sotatercept-winrevair-hap-trax\/\",\"name\":\"La FDA aprueba nuevo medicamento que puede ayudar a detener e incluso revertir una afecci\u00f3n rara y fatal que los m\u00e9dicos llaman una 'bomba de tiempo' - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-27T08:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/27\/fda-aprueba-medicamento-sotatercept-winrevair-hap-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/27\/fda-aprueba-medicamento-sotatercept-winrevair-hap-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/27\/fda-aprueba-medicamento-sotatercept-winrevair-hap-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La FDA aprueba nuevo medicamento que puede ayudar a detener e incluso revertir una afecci\u00f3n rara y fatal que los m\u00e9dicos llaman una &#8216;bomba de tiempo&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La FDA aprueba nuevo medicamento que puede ayudar a detener e incluso revertir una afecci\u00f3n rara y fatal que los m\u00e9dicos llaman una 'bomba de tiempo' - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/03\/27\/fda-aprueba-medicamento-sotatercept-winrevair-hap-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La FDA aprueba nuevo medicamento que puede ayudar a detener e incluso revertir una afecci\u00f3n rara y fatal que los m\u00e9dicos llaman una 'bomba de tiempo' - Noticias","og_description":"(CNN) &#8212; Cuando los m\u00e9dicos le dijeron a Katrina Barry que ten\u00eda una afecci\u00f3n rara y grave llamada hipertensi\u00f3n arterial pulmonar o HAP, le advirtieron que no buscara informaci\u00f3n en Internet. Vamos, pens\u00f3; \u00bfquer\u00edan que una joven que se dirig\u00eda a la escuela de posgrado, que hab\u00eda sobrevivido a un vuelo transatl\u00e1ntico mientras ten\u00eda un [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/03\/27\/fda-aprueba-medicamento-sotatercept-winrevair-hap-trax\/","og_site_name":"Noticias","article_published_time":"2024-03-27T08:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"14 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/03\/27\/fda-aprueba-medicamento-sotatercept-winrevair-hap-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/03\/27\/fda-aprueba-medicamento-sotatercept-winrevair-hap-trax\/"},"author":{"name":"","@id":""},"headline":"La FDA aprueba nuevo medicamento que puede ayudar a detener e incluso revertir una afecci\u00f3n rara y fatal que los m\u00e9dicos llaman una &#8216;bomba de tiempo&#8217;","datePublished":"2024-03-27T08:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/03\/27\/fda-aprueba-medicamento-sotatercept-winrevair-hap-trax\/"},"wordCount":2826,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/03\/27\/fda-aprueba-medicamento-sotatercept-winrevair-hap-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/03\/27\/fda-aprueba-medicamento-sotatercept-winrevair-hap-trax\/","url":"https:\/\/noticiasya.com\/2024\/03\/27\/fda-aprueba-medicamento-sotatercept-winrevair-hap-trax\/","name":"La FDA aprueba nuevo medicamento que puede ayudar a detener e incluso revertir una afecci\u00f3n rara y fatal que los m\u00e9dicos llaman una 'bomba de tiempo' - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-27T08:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/03\/27\/fda-aprueba-medicamento-sotatercept-winrevair-hap-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/03\/27\/fda-aprueba-medicamento-sotatercept-winrevair-hap-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/03\/27\/fda-aprueba-medicamento-sotatercept-winrevair-hap-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La FDA aprueba nuevo medicamento que puede ayudar a detener e incluso revertir una afecci\u00f3n rara y fatal que los m\u00e9dicos llaman una &#8216;bomba de tiempo&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/27\/fda-aprueba-medicamento-sotatercept-winrevair-hap-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La FDA aprueba nuevo medicamento que puede ayudar a detener e incluso revertir una afecci\u00f3n rara y fatal que los m\u00e9dicos llaman una &#8216;bomba de tiempo&#8217;","url":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/27\/fda-aprueba-medicamento-sotatercept-winrevair-hap-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/27\/fda-aprueba-medicamento-sotatercept-winrevair-hap-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-27T08:03:51Z","datePublished":"2024-03-27T08:03:51Z","dateModified":"2024-03-27T08:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La FDA aprueba nuevo medicamento que puede ayudar a detener e incluso revertir una afecci\\u00f3n rara y fatal que los m\\u00e9dicos llaman una &#8216;bomba de tiempo&#8217;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/27\\\/fda-aprueba-medicamento-sotatercept-winrevair-hap-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/27\\\/fda-aprueba-medicamento-sotatercept-winrevair-hap-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-27T08:03:51Z\",\"datePublished\":\"2024-03-27T08:03:51Z\",\"dateModified\":\"2024-03-27T08:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1448254,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/04\/18\/amlo-mexico-buscara-proteger-exvicepresidente-ecuador-jorge-glas-orix\/","url_meta":{"origin":1447414,"position":0},"title":"L\u00f3pez Obrador dice que M\u00e9xico buscar\u00e1 proteger al exvicepresidente ecuatoriano Jorge Glas y garantizar su derecho al asilo","author":"","date":"abril 18, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, dijo este jueves que su Gobierno buscar\u00e1 garantizar el bienestar del exvicepresidente de Ecuador, Jorge Glas, a quien la polic\u00eda de ese pa\u00eds arrest\u00f3 en la Embajada mexicana en Quito a inicios de mes, para abrir una crisis diplom\u00e1tica entre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463327,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/06\/07\/hombres-probabilidades-mujeres-morir-corazon-roto-trax\/","url_meta":{"origin":1447414,"position":1},"title":"Los hombres tienen m\u00e1s probabilidades que las mujeres de morir por el s\u00edndrome del coraz\u00f3n roto, seg\u00fan un estudio","author":"","date":"junio 7, 2025","format":false,"excerpt":"Un hombre de 59 a\u00f1os lleg\u00f3 al Primer Hospital de la Universidad de Beijing para un procedimiento cuando comenz\u00f3 a experimentar un dolor de pecho severo y dificultad para respirar.Cuatro meses antes, le hab\u00edan extirpado tumores cancerosos de la vejiga. Frente a su familia, hac\u00eda todo lo posible por mostrarse\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469173,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/12\/11\/donante-esperma-cancer-ninos-trax\/","url_meta":{"origin":1447414,"position":2},"title":"Al menos 197 ni\u00f1os fueron concebidos con el esperma de un donante que ten\u00eda un gen asociado al c\u00e1ncer. Algunos ya murieron","author":"","date":"diciembre 11, 2025","format":false,"excerpt":"Un donante de esperma con una mutaci\u00f3n gen\u00e9tica rara vinculada a un mayor riesgo de desarrollar c\u00e1ncer concibi\u00f3 al menos 197 ni\u00f1os en Europa; algunos ya murieron a causa de la enfermedad, seg\u00fan una nueva investigaci\u00f3n.El donante, que es sano, ten\u00eda una mutaci\u00f3n poco com\u00fan en un gen llamado TP53,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460999,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/04\/09\/robbie-williams-diagnosticaron-escorbuto-este-ano-trax\/","url_meta":{"origin":1447414,"position":3},"title":"Robbie Williams dice que le diagnosticaron escorbuto a principios de este a\u00f1o","author":"","date":"abril 9, 2025","format":false,"excerpt":"El cantante Robbie Williams revel\u00f3 que le diagnosticaron escorbuto, una deficiencia de vitaminas, a principios de este a\u00f1o.Williams, de 51 a\u00f1os, comparti\u00f3 una actualizaci\u00f3n sobre su salud en una entrevista con el Mirror publicada el lunes, diciendo que se enter\u00f3 de su diagn\u00f3stico despu\u00e9s de haber estado luchando con su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451297,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/07\/21\/joe-biden-no-buscara-la-reeleccion-presidencial-trax\/","url_meta":{"origin":1447414,"position":4},"title":"Joe Biden no buscar\u00e1 la reelecci\u00f3n presidencial","author":"","date":"julio 21, 2024","format":false,"excerpt":"(CNN) -- El presidente de EE.UU. Joe Biden anunci\u00f3 que no busca la reelecci\u00f3n en una carta publicada en su cuenta oficial de X. Biden dijo que hablar\u00e1 con la naci\u00f3n a finales de esta semana y proporcionar\u00e1 m\u00e1s detalles.\"Ha sido el mayor honor de mi vida ser su presidente\",\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443597,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/01\/12\/sobrevivio-a-6-infartos-ahora-promueve-la-salud-cardiovascular-en-miss-america\/","url_meta":{"origin":1447414,"position":5},"title":"Sobrevivi\u00f3 a 6 infartos. Ahora promueve la salud cardiovascular en Miss Am\u00e9rica","author":"","date":"enero 12, 2024","format":false,"excerpt":"(CNN) -- A los 16 a\u00f1os, Jude Mabon\u00e9 se acostaba a menudo pregunt\u00e1ndose si se despertar\u00eda a la ma\u00f1ana siguiente. Acababa de sufrir su primer infarto, y antes de cumplir los 18 sufrir\u00eda cinco m\u00e1s, lo que la llev\u00f3 a elaborar una lista de cosas que hacer antes de morir\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1447414"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447414\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1447414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1447414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1447414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}