{"id":1447496,"date":"2024-03-28T10:03:49","date_gmt":"2024-03-28T17:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/28\/analisis-verdadera-cara-inmigracion-trax\/"},"modified":"2024-03-28T10:03:49","modified_gmt":"2024-03-28T17:03:49","slug":"analisis-verdadera-cara-inmigracion-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/28\/analisis-verdadera-cara-inmigracion-trax\/","title":{"rendered":"AN\u00c1LISIS | El colapso del puente de Baltimore refleja la verdadera cara de la inmigraci\u00f3n en EE.UU."},"content":{"rendered":"<p>(CNN) &#8212; Baltimore estaba durmiendo cuando un barco completamente cargado, a la deriva y sin energ\u00eda, se estrell\u00f3 contra el puente Francis Scott Key, derrib\u00e1ndolo en segundos.<\/p>\n<p>Si el desastre hubiera ocurrido durante el d\u00eda, cientos de autom\u00f3viles y camiones podr\u00edan haber estado en el puente sobre un canal que conduce a uno de los puertos m\u00e1s transitados de la costa este. As\u00ed que fue una suerte que sucediera en las primeras horas y que la polic\u00eda recibiera suficiente aviso para impedir que los veh\u00edculos entraran en el puente.<\/p>\n<p>Pero las seis personas presuntamente muertas en la tragedia no pudieron escapar. Eran trabajadores de mantenimiento, el tipo de personas que pocos notan pero que hacen trabajos duros durante la noche para mantener el pa\u00eds en funcionamiento.<\/p>\n<p>Todos los desaparecidos eran inmigrantes, forasteros que hab\u00edan llegado a Estados Unidos desde Am\u00e9rica Central y del Sur en busca de una vida mejor.<\/p>\n<p>Sus historias y aspiraciones reflejaron las vidas de millones de nuevos inmigrantes a Estados Unidos. Son mucho m\u00e1s representativos de la poblaci\u00f3n migrante que la imagen extrema y enga\u00f1osa que Donald Trump suele lanzar sobre los migrantes. El presunto candidato republicano a menudo afirma falsamente que pa\u00edses extranjeros est\u00e1n entrando en sus asilos y c\u00e1rceles para enviar a sus \u201cpeores personas\u201d como una fuerza de invasi\u00f3n de facto a Estados Unidos.<\/p>\n<p>\u00bfQui\u00e9nes son las 6 v\u00edctimas del colapso del puente en Baltimore que se asume est\u00e1n muertas?<\/p>\n<p>La demonizaci\u00f3n que hace Trump de los inmigrantes que intentan cruzar ilegalmente al pa\u00eds y que, seg\u00fan \u00e9l, est\u00e1n \u201cenvenenando la sangre\u201d del pa\u00eds, a menudo se siente como una condena taquigr\u00e1fica de los inmigrantes en su conjunto.<\/p>\n<p>Se han recuperado los cuerpos de dos de los seis trabajadores de la construcci\u00f3n que murieron despu\u00e9s de que un carguero chocara contra un pilar del puente. Se han detenido las labores de b\u00fasqueda de los otros cuatro trabajadores, que se presumen muertos.<\/p>\n<p>El carguero Dali es visto despu\u00e9s de chocar y colapsar el puente Francis Scott Key el 26 de marzo en Baltimore, Maryland. (Tasos Katopodis\/Getty Images)<\/p>\n<p>Uno de los trabajadores es Miguel Luna, padre de tres hijos, de El Salvador, que vivi\u00f3 en Maryland durante 19 a\u00f1os. Maynor Yassir Suazo Sandoval, un hondure\u00f1o padre de dos hijos, tambi\u00e9n estaba en el puente. Vive en Estados Unidos desde hace 18 a\u00f1os y tiene un hijo de 18 a\u00f1os y una hija de 5 a\u00f1os. Tambi\u00e9n est\u00e1n desaparecidos dos guatemaltecos. Y tres mexicanos estaban entre la tripulaci\u00f3n que trabajaba en el puente. Uno fue rescatado de las g\u00e9lidas aguas de abajo.<\/p>\n<p>A menudo, los inmigrantes realizan trabajos que otras personas no quieren hacer: los que tienen los salarios m\u00e1s bajos y las peores condiciones. Algunos lo hacen para apoyar a las familias en EE.UU. y sentar las bases de una vida mejor para sus hijos y nietos. Muchos env\u00edan dinero a casa para apoyar a familiares que viven en econom\u00edas mucho menos pr\u00f3speras. Los trabajadores inmigrantes mexicanos, por ejemplo, transfirieron m\u00e1s de US$ 60.000 millones en remesas a su pa\u00eds en 2023, seg\u00fan el Banco Central de M\u00e9xico.<\/p>\n<p>Quiz\u00e1s valga la pena recordar los sacrificios de los desaparecidos, presuntamente muertos en Baltimore el lunes por la noche, cuando la ret\u00f3rica antiinmigrante vuelva a aumentar en el per\u00edodo previo a las elecciones presidenciales de noviembre.<\/p>\n<p>Y cuando el puente Francis Scott Key vuelva a levantarse, es muy probable que sean inmigrantes quienes lo construyan.<\/p>\n<p>El presidente Joe Biden ha prometido que el gobierno federal reconstruir\u00e1 el puente en Baltimore, una ciudad que durante mucho tiempo ha estado plagada de recursos limitados, una alta tasa de homicidios, una guerra encarnizada entre bandas de narcotraficantes y corrupci\u00f3n pol\u00edtica.<\/p>\n<p>Pero llevar\u00e1 un tiempo, ya que el portacontenedores, el Dali, todav\u00eda est\u00e1 atrapado en el agua debajo de los escombros del puente. Cualquier cierre prolongado del puerto de Baltimore podr\u00eda ser desastroso para los trabajadores portuarios que dependen de un flujo constante de barcos que entran y salen para mantenerse empleados. Y el impacto en cadena del cierre de un nodo clave de la cadena de suministro podr\u00eda extenderse a cientos de kil\u00f3metros de la ciudad de la costa este. Actualmente once barcos est\u00e1n atrapados dentro del puerto y no pueden ir a ninguna parte, una situaci\u00f3n que probablemente costar\u00e1 a sus propietarios millones de d\u00f3lares.<\/p>\n<p>&#171;Estamos comprometidos a entregar todos los recursos federales necesarios, todos los recursos federales necesarios para ayudar a Maryland a volver a la normalidad, y vamos a trabajar con ellos en cada paso del camino para reconstruir este puente&#187;, dijo el secretario de Transporte, Pete Buttigieg, a los periodistas en la Casa Blanca eeste mi\u00e9rcoles.<\/p>\n<p>&#171;No va a ser sencillo&#187;, afirm\u00f3. &#171;La reconstrucci\u00f3n no ser\u00e1 r\u00e1pida, f\u00e1cil ni barata, pero lo lograremos&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Baltimore estaba durmiendo cuando un barco completamente cargado, a la deriva y sin energ\u00eda, se estrell\u00f3 contra el puente Francis Scott Key, derrib\u00e1ndolo en segundos. Si el desastre hubiera ocurrido durante el d\u00eda, cientos de autom\u00f3viles y camiones podr\u00edan haber estado en el puente sobre un canal que conduce a uno de los [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1447496","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AN\u00c1LISIS | El colapso del puente de Baltimore refleja la verdadera cara de la inmigraci\u00f3n en EE.UU. - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/03\/28\/analisis-verdadera-cara-inmigracion-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AN\u00c1LISIS | El colapso del puente de Baltimore refleja la verdadera cara de la inmigraci\u00f3n en EE.UU. - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Baltimore estaba durmiendo cuando un barco completamente cargado, a la deriva y sin energ\u00eda, se estrell\u00f3 contra el puente Francis Scott Key, derrib\u00e1ndolo en segundos. Si el desastre hubiera ocurrido durante el d\u00eda, cientos de autom\u00f3viles y camiones podr\u00edan haber estado en el puente sobre un canal que conduce a uno de los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/03\/28\/analisis-verdadera-cara-inmigracion-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-28T17:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/28\/analisis-verdadera-cara-inmigracion-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/28\/analisis-verdadera-cara-inmigracion-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"AN\u00c1LISIS | El colapso del puente de Baltimore refleja la verdadera cara de la inmigraci\u00f3n en EE.UU.\",\"datePublished\":\"2024-03-28T17:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/28\/analisis-verdadera-cara-inmigracion-trax\/\"},\"wordCount\":881,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/28\/analisis-verdadera-cara-inmigracion-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/28\/analisis-verdadera-cara-inmigracion-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/03\/28\/analisis-verdadera-cara-inmigracion-trax\/\",\"name\":\"AN\u00c1LISIS | El colapso del puente de Baltimore refleja la verdadera cara de la inmigraci\u00f3n en EE.UU. - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-28T17:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/28\/analisis-verdadera-cara-inmigracion-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/28\/analisis-verdadera-cara-inmigracion-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/28\/analisis-verdadera-cara-inmigracion-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AN\u00c1LISIS | El colapso del puente de Baltimore refleja la verdadera cara de la inmigraci\u00f3n en EE.UU.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AN\u00c1LISIS | El colapso del puente de Baltimore refleja la verdadera cara de la inmigraci\u00f3n en EE.UU. - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/03\/28\/analisis-verdadera-cara-inmigracion-trax\/","og_locale":"es_ES","og_type":"article","og_title":"AN\u00c1LISIS | El colapso del puente de Baltimore refleja la verdadera cara de la inmigraci\u00f3n en EE.UU. - Noticias","og_description":"(CNN) &#8212; Baltimore estaba durmiendo cuando un barco completamente cargado, a la deriva y sin energ\u00eda, se estrell\u00f3 contra el puente Francis Scott Key, derrib\u00e1ndolo en segundos. Si el desastre hubiera ocurrido durante el d\u00eda, cientos de autom\u00f3viles y camiones podr\u00edan haber estado en el puente sobre un canal que conduce a uno de los [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/03\/28\/analisis-verdadera-cara-inmigracion-trax\/","og_site_name":"Noticias","article_published_time":"2024-03-28T17:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/03\/28\/analisis-verdadera-cara-inmigracion-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/03\/28\/analisis-verdadera-cara-inmigracion-trax\/"},"author":{"name":"","@id":""},"headline":"AN\u00c1LISIS | El colapso del puente de Baltimore refleja la verdadera cara de la inmigraci\u00f3n en EE.UU.","datePublished":"2024-03-28T17:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/03\/28\/analisis-verdadera-cara-inmigracion-trax\/"},"wordCount":881,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/03\/28\/analisis-verdadera-cara-inmigracion-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/03\/28\/analisis-verdadera-cara-inmigracion-trax\/","url":"https:\/\/noticiasya.com\/2024\/03\/28\/analisis-verdadera-cara-inmigracion-trax\/","name":"AN\u00c1LISIS | El colapso del puente de Baltimore refleja la verdadera cara de la inmigraci\u00f3n en EE.UU. - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-28T17:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/03\/28\/analisis-verdadera-cara-inmigracion-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/03\/28\/analisis-verdadera-cara-inmigracion-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/03\/28\/analisis-verdadera-cara-inmigracion-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"AN\u00c1LISIS | El colapso del puente de Baltimore refleja la verdadera cara de la inmigraci\u00f3n en EE.UU."}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/28\/analisis-verdadera-cara-inmigracion-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"AN\u00c1LISIS | El colapso del puente de Baltimore refleja la verdadera cara de la inmigraci\u00f3n en EE.UU.","url":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/28\/analisis-verdadera-cara-inmigracion-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/28\/analisis-verdadera-cara-inmigracion-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-28T17:03:49Z","datePublished":"2024-03-28T17:03:49Z","dateModified":"2024-03-28T17:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"AN\\u00c1LISIS | El colapso del puente de Baltimore refleja la verdadera cara de la inmigraci\\u00f3n en EE.UU.\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/28\\\/analisis-verdadera-cara-inmigracion-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/28\\\/analisis-verdadera-cara-inmigracion-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-28T17:03:49Z\",\"datePublished\":\"2024-03-28T17:03:49Z\",\"dateModified\":\"2024-03-28T17:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1447413,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/26\/victimas-colapso-puente-baltimore-mexicanos-guatemaltecos-trax\/","url_meta":{"origin":1447496,"position":0},"title":"Las v\u00edctimas del colapso del puente de Baltimore incluyen ciudadanos mexicanos y guatemaltecos, dicen las autoridades","author":"","date":"marzo 26, 2024","format":false,"excerpt":"(CNN) -- Las seis personas que a\u00fan est\u00e1n desaparecidas tras el colapso del puente Francis Scott Key en Baltimore incluyen ciudadanos mexicanos, seg\u00fan Rafael Laveaga, jefe de la Secci\u00f3n Consular de la Embajada de M\u00e9xico en Washington, quien habl\u00f3 con los periodistas cerca del lugar el martes.La Guardia Costera de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447418,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/27\/colapso-puente-key-baltimore-barco-danos-orix\/","url_meta":{"origin":1447496,"position":1},"title":"Resumen de noticias del colapso del puente Key en Baltimore tras el choque de un barco, del 26 de marzo","author":"","date":"marzo 27, 2024","format":false,"excerpt":"Este seguimiento termin\u00f3. Puedes ver las \u00faltimas noticias del colapso del puente Key en Baltimore tras el choque de un barco, haciendo click aqu\u00ed.El buque Dali se estrell\u00f3 contra el puente Francis Scott Key y provoc\u00f3 su colapso en Baltimore. Cr\u00e9dito: Julia Nikhinson\/Reuters.El carguero Dali despu\u00e9s de chocar y colapsar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447386,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/26\/que-paso-por-que-colapso-puente-baltimore-victimas-fotos-trax\/","url_meta":{"origin":1447496,"position":2},"title":"\u00bfPor qu\u00e9 colaps\u00f3 el puente de Baltimore, cu\u00e1ntas v\u00edctimas hay y qu\u00e9 sabemos del accidente?","author":"","date":"marzo 26, 2024","format":false,"excerpt":"(CNN) -- Un enorme buque de carga se estrell\u00f3 contra el puente Francis Scott Key de Baltimore la madrugada del martes, causando que el puente de 2,5 kil\u00f3metros se desmoronara con autom\u00f3viles y personas al agua helada.Esto es lo que sabemos sobre la cat\u00e1strofe:\u00bfPor qu\u00e9 se derrumb\u00f3 el puente?Poco antes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447593,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/04\/01\/puente-baltimore-sobreviviente-colapso-larry-desantis-trax\/","url_meta":{"origin":1447496,"position":3},"title":"&#171;Me considero muy afortunado&#187;: habla una de las \u00faltimas personas en salir del puente de Baltimore antes de su derrumbe","author":"","date":"abril 1, 2024","format":false,"excerpt":"(CNN) -- Eran poco m\u00e1s de la 1:00 a.m. del 26 de marzo y Larry DeSantis se dirig\u00eda a su segundo trabajo en Herman's Bakery, en la zona de Baltimore: la mitad de otra larga, pero normal, jornada laboral.Cuando un barco colision\u00f3 con el puente Francis Scott Key, provocando su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450207,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/06\/11\/reabren-canal-navegacion-puerto-baltimore-accidente-trax\/","url_meta":{"origin":1447496,"position":4},"title":"Reabren el canal de navegaci\u00f3n del puerto de Baltimore totalmente m\u00e1s de dos meses despu\u00e9s del derrumbe del puente","author":"","date":"junio 11, 2024","format":false,"excerpt":"(CNN) -- El canal de navegaci\u00f3n del puerto de Baltimore vuelve a estar plenamente operativo, seg\u00fan anunciaron este lunes las autoridades a cargo. Pasaron m\u00e1s de dos meses desde que un enorme buque de carga choc\u00f3 contra el puente Francis Scott Key y cort\u00f3 el acceso a la crucial arteria\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447417,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/27\/ultima-hora-colapso-puente-key-baltimore-barco-orix\/","url_meta":{"origin":1447496,"position":5},"title":"\u00daltima hora del colapso del puente Key en Baltimore tras el choque de un barco, en vivo","author":"","date":"marzo 27, 2024","format":false,"excerpt":"\ud83d\udd04 Haz clic aqu\u00ed para ver las entradas m\u00e1s recientesEl carguero Dali despu\u00e9s de chocar y colapsar el puente Francis Scott Key el 26 de marzo de 2024 en Baltimore, Maryland. Los rescatistas est\u00e1n buscando al menos a siete personas, dicen las autoridades, mientras que otras dos han sido sacadas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1447496"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447496\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1447496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1447496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1447496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}