{"id":1447503,"date":"2024-03-28T11:03:47","date_gmt":"2024-03-28T18:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/28\/puerto-rico-emergencia-salud-dengue-trax\/"},"modified":"2024-03-28T11:03:47","modified_gmt":"2024-03-28T18:03:47","slug":"puerto-rico-emergencia-salud-dengue-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/28\/puerto-rico-emergencia-salud-dengue-trax\/","title":{"rendered":"Puerto Rico declara emergencia de salud p\u00fablica luego de m\u00e1s de 500 casos de dengue en 2024"},"content":{"rendered":"<p>(CNN) &#8212; Puerto Rico declar\u00f3 la emergencia de salud p\u00fablica debido al creciente n\u00famero de casos de dengue.<\/p>\n<p>El secretario de Salud de Puerto Rico, Carlos Mellado, dijo que el departamento de salud ha registrado 549 casos de dengue en lo que va del a\u00f1o, superando con creces las cifras hist\u00f3ricas.<\/p>\n<p>\u201cNuestros equipos han estado trabajando en un plan integrado de prevenci\u00f3n y control en respuesta a las arbovirosis y vamos a ampliar la respuesta implementada\u201d, dijo Mellado en un comunicado, se\u00f1alando que la declaraci\u00f3n permitir\u00e1 recursos adicionales que puedan fortalecer la vigilancia y el manejo de programas.<\/p>\n<p>El dengue es el virus transmitido por mosquitos m\u00e1s com\u00fan en todo el mundo. M\u00e1s de 400 millones de personas se infectan cada a\u00f1o. Se propaga principalmente a trav\u00e9s del mosquito Aedes aegypti, que tambi\u00e9n es portador de otros virus como el de la fiebre amarilla, el chikungunya y el Zika.<\/p>\n<p>El virus es end\u00e9mico en m\u00e1s de 100 pa\u00edses de climas tropicales y subtropicales, principalmente en \u00e1reas urbanas y semiurbanas, seg\u00fan la Organizaci\u00f3n Mundial de la Salud, y en los territorios estadounidenses de Puerto Rico, las Islas V\u00edrgenes estadounidenses y Samoa Americana.<\/p>\n<p>Aproximadamente 1 de cada 4 personas infectadas con dengue presentar\u00e1 s\u00edntomas, como fiebre, n\u00e1useas, v\u00f3mitos, sarpullido y dolores corporales, generalmente dolores musculares, articulares, \u00f3seos o detr\u00e1s de los ojos.<\/p>\n<p>El dengue grave es menos com\u00fan, pero los s\u00edntomas pueden incluir shock y hemorragia interna. Alrededor de 40.000 personas mueren cada a\u00f1o a causa del dengue grave en todo el mundo, seg\u00fan los Centros para el Control y la Prevenci\u00f3n de Enfermedades de Estados Unidos.<\/p>\n<p>Los funcionarios de salud en Puerto Rico est\u00e1n instando a la gente a usar repelente de insectos y eliminar posibles criaderos de mosquitos evitando que se acumule agua.<\/p>\n<p>\u201cTambi\u00e9n es fundamental usar ropa que cubra la piel expuesta y considerar instalar mosquiteros en las camas y mallas de alambre en puertas y ventanas\u201d, dijo Mellado.<\/p>\n<p>En Estados Unidos existe una vacuna contra el dengue para ni\u00f1os de 9 a 16 a\u00f1os que tienen evidencia confirmada por laboratorio de una infecci\u00f3n previa por dengue y que viven en \u00e1reas donde el dengue es end\u00e9mico, incluido Puerto Rico. No existe ninguna vacuna contra el dengue disponible para adultos en Estados Unidos.<\/p>\n<p>Ocasionalmente se producen brotes de dengue en los Estados Unidos continentales; El a\u00f1o pasado, se reportaron varios casos en Florida. Pero la mayor\u00eda de los casos se reportan en Puerto Rico, dijo a CNN el a\u00f1o pasado la Dra. Gabriela Paz-Bailey, jefa de la Divisi\u00f3n de Dengue de la Divisi\u00f3n de Enfermedades Transmitidas por Vectores del DCC.<\/p>\n<p>\u201cTiene el clima perfecto para ello. Es una isla tropical\u201d, dijo Paz-Bailey. \u201cDe hecho, hay esfuerzos del departamento de salud y de otras organizaciones como la unidad de control de vectores de Puerto Rico para controlar el dengue en el \u00e1rea\u201d.<\/p>\n<p>El cambio clim\u00e1tico tambi\u00e9n fomentar\u00e1 la propagaci\u00f3n del dengue en todo el mundo, afirm\u00f3 Paz-Bailey.<\/p>\n<p>&#171;Las temperaturas m\u00e1s altas probablemente ampliar\u00e1n la variedad de lugares donde un mosquito puede sobrevivir&#187;, dijo. &#171;Y luego tambi\u00e9n puede facilitar la transmisi\u00f3n por otras v\u00edas, como una replicaci\u00f3n viral m\u00e1s r\u00e1pida en el mosquito y una mayor supervivencia de los mosquitos&#187;.<\/p>\n<p>Jamie Gumbrecht de CNN contribuy\u00f3 a este informe.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Puerto Rico declar\u00f3 la emergencia de salud p\u00fablica debido al creciente n\u00famero de casos de dengue. El secretario de Salud de Puerto Rico, Carlos Mellado, dijo que el departamento de salud ha registrado 549 casos de dengue en lo que va del a\u00f1o, superando con creces las cifras hist\u00f3ricas. \u201cNuestros equipos han estado [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1447503","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Puerto Rico declara emergencia de salud p\u00fablica luego de m\u00e1s de 500 casos de dengue en 2024 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/03\/28\/puerto-rico-emergencia-salud-dengue-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Puerto Rico declara emergencia de salud p\u00fablica luego de m\u00e1s de 500 casos de dengue en 2024 - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Puerto Rico declar\u00f3 la emergencia de salud p\u00fablica debido al creciente n\u00famero de casos de dengue. El secretario de Salud de Puerto Rico, Carlos Mellado, dijo que el departamento de salud ha registrado 549 casos de dengue en lo que va del a\u00f1o, superando con creces las cifras hist\u00f3ricas. \u201cNuestros equipos han estado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/03\/28\/puerto-rico-emergencia-salud-dengue-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-28T18:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/28\/puerto-rico-emergencia-salud-dengue-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/28\/puerto-rico-emergencia-salud-dengue-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Puerto Rico declara emergencia de salud p\u00fablica luego de m\u00e1s de 500 casos de dengue en 2024\",\"datePublished\":\"2024-03-28T18:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/28\/puerto-rico-emergencia-salud-dengue-trax\/\"},\"wordCount\":612,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/28\/puerto-rico-emergencia-salud-dengue-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/28\/puerto-rico-emergencia-salud-dengue-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/03\/28\/puerto-rico-emergencia-salud-dengue-trax\/\",\"name\":\"Puerto Rico declara emergencia de salud p\u00fablica luego de m\u00e1s de 500 casos de dengue en 2024 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-28T18:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/28\/puerto-rico-emergencia-salud-dengue-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/28\/puerto-rico-emergencia-salud-dengue-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/28\/puerto-rico-emergencia-salud-dengue-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Puerto Rico declara emergencia de salud p\u00fablica luego de m\u00e1s de 500 casos de dengue en 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Puerto Rico declara emergencia de salud p\u00fablica luego de m\u00e1s de 500 casos de dengue en 2024 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/03\/28\/puerto-rico-emergencia-salud-dengue-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Puerto Rico declara emergencia de salud p\u00fablica luego de m\u00e1s de 500 casos de dengue en 2024 - Noticias","og_description":"(CNN) &#8212; Puerto Rico declar\u00f3 la emergencia de salud p\u00fablica debido al creciente n\u00famero de casos de dengue. El secretario de Salud de Puerto Rico, Carlos Mellado, dijo que el departamento de salud ha registrado 549 casos de dengue en lo que va del a\u00f1o, superando con creces las cifras hist\u00f3ricas. \u201cNuestros equipos han estado [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/03\/28\/puerto-rico-emergencia-salud-dengue-trax\/","og_site_name":"Noticias","article_published_time":"2024-03-28T18:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/03\/28\/puerto-rico-emergencia-salud-dengue-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/03\/28\/puerto-rico-emergencia-salud-dengue-trax\/"},"author":{"name":"","@id":""},"headline":"Puerto Rico declara emergencia de salud p\u00fablica luego de m\u00e1s de 500 casos de dengue en 2024","datePublished":"2024-03-28T18:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/03\/28\/puerto-rico-emergencia-salud-dengue-trax\/"},"wordCount":612,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/03\/28\/puerto-rico-emergencia-salud-dengue-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/03\/28\/puerto-rico-emergencia-salud-dengue-trax\/","url":"https:\/\/noticiasya.com\/2024\/03\/28\/puerto-rico-emergencia-salud-dengue-trax\/","name":"Puerto Rico declara emergencia de salud p\u00fablica luego de m\u00e1s de 500 casos de dengue en 2024 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-28T18:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/03\/28\/puerto-rico-emergencia-salud-dengue-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/03\/28\/puerto-rico-emergencia-salud-dengue-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/03\/28\/puerto-rico-emergencia-salud-dengue-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Puerto Rico declara emergencia de salud p\u00fablica luego de m\u00e1s de 500 casos de dengue en 2024"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/28\/puerto-rico-emergencia-salud-dengue-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Puerto Rico declara emergencia de salud p\u00fablica luego de m\u00e1s de 500 casos de dengue en 2024","url":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/28\/puerto-rico-emergencia-salud-dengue-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/28\/puerto-rico-emergencia-salud-dengue-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-28T18:03:47Z","datePublished":"2024-03-28T18:03:47Z","dateModified":"2024-03-28T18:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Puerto Rico declara emergencia de salud p\\u00fablica luego de m\\u00e1s de 500 casos de dengue en 2024\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/28\\\/puerto-rico-emergencia-salud-dengue-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/28\\\/puerto-rico-emergencia-salud-dengue-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-28T18:03:47Z\",\"datePublished\":\"2024-03-28T18:03:47Z\",\"dateModified\":\"2024-03-28T18:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1448289,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/04\/19\/casos-dengue-superan-52-millones-en-america-trax\/","url_meta":{"origin":1447503,"position":0},"title":"Los casos de dengue superan los 5,2 millones en Am\u00e9rica; el brote supera el r\u00e9cord anual, advierte la OPS","author":"","date":"abril 19, 2024","format":false,"excerpt":"(CNN) -- Los casos de dengue est\u00e1n aumentando en Am\u00e9rica. El n\u00famero de casos reportados esta semana superaron los 5,2 millones, por encima del r\u00e9cord anual establecido en 2023, de acuerdo con la Organizaci\u00f3n Panamericana de la Salud (OPS).Ashley Baldwin, portavoz de la OPS, le dijo a CNN el jueves\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447500,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/28\/que-es-dengue-como-tratarlo-orix\/","url_meta":{"origin":1447503,"position":1},"title":"\u00bfQu\u00e9 es el dengue y c\u00f3mo tratarlo?","author":"","date":"marzo 28, 2024","format":false,"excerpt":"(CNN) -- \u00a0Los casos de dengue en Am\u00e9rica han registrado un \u201caumento exponencial\u201d en 2024 dijeron la Organizaci\u00f3n Mundial de la Salud (OMS) y la Organizaci\u00f3n Panamericana de la Salud (OPS) en febrero. \u00bfQu\u00e9 es el dengue y por qu\u00e9 los casos de esa enfermedad infecciosa han superado este a\u00f1o\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458954,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/02\/19\/sao-paulo-brasil-emergencia-salud-dengue-orix\/","url_meta":{"origin":1447503,"position":2},"title":"Sao Paulo, Brasil, declara emergencia de salud p\u00fablica por dengue","author":"","date":"febrero 19, 2025","format":false,"excerpt":"El Gobierno de Sao Paulo, Brasil, declar\u00f3 este mi\u00e9rcoles emergencia de salud p\u00fablica debido a la cifra de casos de dengue registrados en el estado en lo que va del a\u00f1o.El Ejecutivo local inform\u00f3 en su cuenta de X y a trav\u00e9s de su agencia oficial de noticias que la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447512,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/28\/ops-advierte-dengue-america-trax\/","url_meta":{"origin":1447503,"position":3},"title":"La OPS advierte sobre la &#171;peor temporada de dengue&#187; que puede enfrentar Am\u00e9rica en 2024","author":"","date":"marzo 28, 2024","format":false,"excerpt":"(CNN) --\u00a0El n\u00famero de casos de dengue en el continente americano es tres veces mayor al registrado en el mismo periodo del a\u00f1o pasado, de acuerdo con funcionarios de la Organizaci\u00f3n Panamericana de la Salud (OPS).En lo que vamos de 2024, se registran al menos 3,5 millones de casos, y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445077,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/02\/08\/rio-de-janeiro-declara-emergencia-de-salud-por-dengue-mientras-brasil-se-prepara-para-el-carnaval\/","url_meta":{"origin":1447503,"position":4},"title":"R\u00edo de Janeiro declara emergencia de salud por dengue, mientras Brasil se prepara para el carnaval","author":"","date":"febrero 8, 2024","format":false,"excerpt":"(CNN) -- El alcalde de\u00a0 R\u00edo de Janeiro, en Brasil, Eduardo Paes, declar\u00f3 el estado de emergencia de salud p\u00fablica debido a una epidemia de dengue, report\u00f3 CNN Brasil, afiliada de CNN.El aumento en los casos de dengue ocurre mientras R\u00edo de Janeiro y todo el pa\u00eds se preparan para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456350,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/12\/07\/america-dengue-alza-2024-175-73-orix\/","url_meta":{"origin":1447503,"position":5},"title":"Am\u00e9rica suma 12,6 millones de casos de dengue en 2024, un alza de 175,73% en comparaci\u00f3n con el a\u00f1o anterior","author":"","date":"diciembre 7, 2024","format":false,"excerpt":"A menos de un mes de que termine 2024, los casos de dengue en Am\u00e9rica suman 12.669.716, un incremento de 175,73% en comparaci\u00f3n a los que se registraron en todo 2023, de acuerdo con la plataforma de la Organizaci\u00f3n Mundial de la Salud (OMS) y la Organizaci\u00f3n Panamericana de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1447503"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447503\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1447503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1447503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1447503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}