{"id":1447522,"date":"2024-03-29T02:03:39","date_gmt":"2024-03-29T09:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/29\/desvian-vuelo-united-airlines-problema-motor-trax\/"},"modified":"2024-03-29T02:03:39","modified_gmt":"2024-03-29T09:03:39","slug":"desvian-vuelo-united-airlines-problema-motor-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/29\/desvian-vuelo-united-airlines-problema-motor-trax\/","title":{"rendered":"Desv\u00edan un vuelo de United Airlines con destino a Par\u00eds por un problema en el motor"},"content":{"rendered":"<p>(CNN) &#8212; Un vuelo de United Airlines con destino a Par\u00eds fue desviado a Denver despu\u00e9s de que se registrara un problema de motor en la noche del jueves, seg\u00fan la aerol\u00ednea.<\/p>\n<p>El vuelo 990 de United sali\u00f3 de San Francisco sobre las 05:57 p.m. hora local, seg\u00fan flightaware.com.<\/p>\n<p>El vuelo fue desviado al aeropuerto internacional de Denver cuando &#171;la tripulaci\u00f3n inform\u00f3 de un problema con un motor&#187;, inform\u00f3 United a CNN en un comunicado.<\/p>\n<p>El avi\u00f3n aterriz\u00f3 sin problemas y todos los pasajeros desembarcaron. El avi\u00f3n era un Boeing 777 con 273 pasajeros y 12 miembros de la tripulaci\u00f3n a bordo, dijo la aerol\u00ednea.<\/p>\n<p>El vuelo fue cancelado al llegar a Denver y la aerol\u00ednea dijo que est\u00e1n trabajando con los clientes para ponerlos en nuevos vuelos.<\/p>\n<p>CNN se puso en contacto con la Administraci\u00f3n Federal de Aviaci\u00f3n para obtener m\u00e1s informaci\u00f3n.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Un vuelo de United Airlines con destino a Par\u00eds fue desviado a Denver despu\u00e9s de que se registrara un problema de motor en la noche del jueves, seg\u00fan la aerol\u00ednea. El vuelo 990 de United sali\u00f3 de San Francisco sobre las 05:57 p.m. hora local, seg\u00fan flightaware.com. El vuelo fue desviado al aeropuerto [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1447522","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Desv\u00edan un vuelo de United Airlines con destino a Par\u00eds por un problema en el motor - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/03\/29\/desvian-vuelo-united-airlines-problema-motor-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desv\u00edan un vuelo de United Airlines con destino a Par\u00eds por un problema en el motor - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Un vuelo de United Airlines con destino a Par\u00eds fue desviado a Denver despu\u00e9s de que se registrara un problema de motor en la noche del jueves, seg\u00fan la aerol\u00ednea. El vuelo 990 de United sali\u00f3 de San Francisco sobre las 05:57 p.m. hora local, seg\u00fan flightaware.com. El vuelo fue desviado al aeropuerto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/03\/29\/desvian-vuelo-united-airlines-problema-motor-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-29T09:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/29\/desvian-vuelo-united-airlines-problema-motor-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/29\/desvian-vuelo-united-airlines-problema-motor-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Desv\u00edan un vuelo de United Airlines con destino a Par\u00eds por un problema en el motor\",\"datePublished\":\"2024-03-29T09:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/29\/desvian-vuelo-united-airlines-problema-motor-trax\/\"},\"wordCount\":190,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/29\/desvian-vuelo-united-airlines-problema-motor-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/29\/desvian-vuelo-united-airlines-problema-motor-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/03\/29\/desvian-vuelo-united-airlines-problema-motor-trax\/\",\"name\":\"Desv\u00edan un vuelo de United Airlines con destino a Par\u00eds por un problema en el motor - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-29T09:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/29\/desvian-vuelo-united-airlines-problema-motor-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/29\/desvian-vuelo-united-airlines-problema-motor-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/29\/desvian-vuelo-united-airlines-problema-motor-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Desv\u00edan un vuelo de United Airlines con destino a Par\u00eds por un problema en el motor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desv\u00edan un vuelo de United Airlines con destino a Par\u00eds por un problema en el motor - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/03\/29\/desvian-vuelo-united-airlines-problema-motor-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Desv\u00edan un vuelo de United Airlines con destino a Par\u00eds por un problema en el motor - Noticias","og_description":"(CNN) &#8212; Un vuelo de United Airlines con destino a Par\u00eds fue desviado a Denver despu\u00e9s de que se registrara un problema de motor en la noche del jueves, seg\u00fan la aerol\u00ednea. El vuelo 990 de United sali\u00f3 de San Francisco sobre las 05:57 p.m. hora local, seg\u00fan flightaware.com. El vuelo fue desviado al aeropuerto [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/03\/29\/desvian-vuelo-united-airlines-problema-motor-trax\/","og_site_name":"Noticias","article_published_time":"2024-03-29T09:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/03\/29\/desvian-vuelo-united-airlines-problema-motor-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/03\/29\/desvian-vuelo-united-airlines-problema-motor-trax\/"},"author":{"name":"","@id":""},"headline":"Desv\u00edan un vuelo de United Airlines con destino a Par\u00eds por un problema en el motor","datePublished":"2024-03-29T09:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/03\/29\/desvian-vuelo-united-airlines-problema-motor-trax\/"},"wordCount":190,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/03\/29\/desvian-vuelo-united-airlines-problema-motor-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/03\/29\/desvian-vuelo-united-airlines-problema-motor-trax\/","url":"https:\/\/noticiasya.com\/2024\/03\/29\/desvian-vuelo-united-airlines-problema-motor-trax\/","name":"Desv\u00edan un vuelo de United Airlines con destino a Par\u00eds por un problema en el motor - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-29T09:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/03\/29\/desvian-vuelo-united-airlines-problema-motor-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/03\/29\/desvian-vuelo-united-airlines-problema-motor-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/03\/29\/desvian-vuelo-united-airlines-problema-motor-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Desv\u00edan un vuelo de United Airlines con destino a Par\u00eds por un problema en el motor"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/29\/desvian-vuelo-united-airlines-problema-motor-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Desv\u00edan un vuelo de United Airlines con destino a Par\u00eds por un problema en el motor","url":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/29\/desvian-vuelo-united-airlines-problema-motor-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/29\/desvian-vuelo-united-airlines-problema-motor-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-29T09:03:39Z","datePublished":"2024-03-29T09:03:39Z","dateModified":"2024-03-29T09:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Desv\\u00edan un vuelo de United Airlines con destino a Par\\u00eds por un problema en el motor\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/29\\\/desvian-vuelo-united-airlines-problema-motor-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/29\\\/desvian-vuelo-united-airlines-problema-motor-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-29T09:03:39Z\",\"datePublished\":\"2024-03-29T09:03:39Z\",\"dateModified\":\"2024-03-29T09:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1462785,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/05\/25\/vuelo-tokio-desvio-seattle-pasajero-intentara-abrir-puerta-salida-trax\/","url_meta":{"origin":1447522,"position":0},"title":"Desv\u00edan a Seattle un avi\u00f3n que ven\u00eda de Tokio luego de que un pasajero intentara abrir una puerta durante el vuelo","author":"","date":"mayo 25, 2025","format":false,"excerpt":"Un vuelo de Tokio a Houston fue desviado a Seattle el s\u00e1bado despu\u00e9s de que un pasajero intent\u00f3 abrir una salida del avi\u00f3n en pleno vuelo, seg\u00fan el FBI y un portavoz del Puerto de Seattle.La tripulaci\u00f3n y los pasajeros sujetaron a la persona, que fue trasladada a un hospital\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461299,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/04\/17\/avion-united-airlines-animal-despegue-trax\/","url_meta":{"origin":1447522,"position":1},"title":"El motor de un avi\u00f3n de United Airlines se incendi\u00f3 tras impactar a un animal durante el despegue","author":"","date":"abril 17, 2025","format":false,"excerpt":"Un video dram\u00e1tico muestra los ardientes momentos despu\u00e9s de que un Boeing 737-800 de United Airlines choc\u00f3 contra un animal al despegar del Aeropuerto Internacional de Denver el domingo.\u201cDe vez en cuando, una peque\u00f1a r\u00e1faga de aire sale del motor derecho del avi\u00f3n\u201d, advirti\u00f3 el control de tr\u00e1fico a\u00e9reo a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458130,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/02\/02\/evacuan-vuelo-united-airlines-houston-nueva-york-motor-trax\/","url_meta":{"origin":1447522,"position":2},"title":"Evacuan vuelo de United Airlines de Houston a Nueva York tras reportarse un problema en el motor","author":"","date":"febrero 2, 2025","format":false,"excerpt":"Un vuelo de United Airlines de Houston a Nueva York fue evacuado despu\u00e9s de que se reportara un problema en el motor antes del despegue, seg\u00fan la Administraci\u00f3n Federal de Aviaci\u00f3n (FAA, por sus siglas en ingl\u00e9s).El Departamento de Bomberos de Houston dijo en un comunicado en X que est\u00e1n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465097,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/08\/04\/vuelo-united-airlines-aterrizaje-emergencia-trax\/","url_meta":{"origin":1447522,"position":3},"title":"Un vuelo de United Airlines aterriza de emergencia en Dulles tras una llamada de &#171;mayday&#187; del piloto","author":"","date":"agosto 4, 2025","format":false,"excerpt":"Un vuelo de United Airlines que viajaba desde el Aeropuerto Internacional Washington Dulles realiz\u00f3 un aterrizaje de emergencia el mes pasado luego de que el piloto declarara una llamada de emergencia poco despu\u00e9s del despegue debido a una presunta falla del motor.El vuelo 108 de United, con destino a M\u00fanich,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446883,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/12\/problemas-boeing-no-paran-7-incidentes-con-aviones-meses-orix\/","url_meta":{"origin":1447522,"position":4},"title":"Los problemas de Boeing no paran: al menos 7 incidentes con aviones en menos de tres meses de 2024","author":"","date":"marzo 12, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- De nueva cuenta, Boeing se encuentra bajo los reflectores medi\u00e1ticos por otro problema en uno de sus aviones, lo cual resalta a\u00fan m\u00e1s el desastroso 2024 que ha tenido el gigante de la aviaci\u00f3n.En apenas poco menos de tres meses este a\u00f1o, la compa\u00f1\u00eda se ha visto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449790,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/05\/27\/vuelo-united-aborta-despegue-aeropuerto-ohare-de-chicago-despues-de-que-se-informara-incendio-en-motor-lo-que-llevo-a-funcionarios-a-retrasar-las-llegadas-trax\/","url_meta":{"origin":1447522,"position":5},"title":"Un vuelo de United aborta el despegue en el aeropuerto O&#8217;Hare de Chicago despu\u00e9s de que se informara de un incendio en el motor, lo que llev\u00f3 a los funcionarios a retrasar las llegadas","author":"","date":"mayo 27, 2024","format":false,"excerpt":"(CNN) -- Nadie result\u00f3 herido este lunes cuando un vuelo de United Airlines abort\u00f3 el despegue en el Aeropuerto Internacional O'Hare de Chicago debido a lo que la Administraci\u00f3n Federal de Aviaci\u00f3n dijo que era un incendio en el motor.El vuelo 2091 de United estaba programado para volar a Seattle\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1447522"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447522\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1447522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1447522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1447522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}