{"id":1447525,"date":"2024-03-29T08:03:44","date_gmt":"2024-03-29T15:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/29\/quienes-eran-6-personas-murieron-derrumbe-puente-baltimore-trax\/"},"modified":"2024-03-29T08:03:44","modified_gmt":"2024-03-29T15:03:44","slug":"quienes-eran-6-personas-murieron-derrumbe-puente-baltimore-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/29\/quienes-eran-6-personas-murieron-derrumbe-puente-baltimore-trax\/","title":{"rendered":"\u00bfQui\u00e9nes son las 6 v\u00edctimas del colapso del puente en Baltimore que se asume est\u00e1n muertas?"},"content":{"rendered":"<p>(CNN) &#8212; Trabajaban durante el turno de la noche arreglando baches en el famoso puente Francis Scott Key de Baltimore, en el que 30.000 habitantes de Maryland confiaban cada d\u00eda. Pero su labor result\u00f3 en tragedia la madrugada del martes, cuando un barco de carga de m\u00e1s de 96.600 toneladas choc\u00f3 contra el puente, arrojando a los trabajadores de la construcci\u00f3n al agua peligrosamente fr\u00eda.<\/p>\n<p>Tras un d\u00eda de b\u00fasqueda, las autoridades suspendieron la misi\u00f3n de rescate y dieron por muertos a los trabajadores. Era pr\u00e1cticamente imposible sobrevivir en el agua helada de 15 metros de profundidad despu\u00e9s de varias horas, y era demasiado peligroso para los buzos navegar por el agua oscura entre escombros afilados.<\/p>\n<p>Desde entonces, se han recuperado dos cuerpos, los de Alejandro Hern\u00e1ndez Fuentes de M\u00e9xico y Dorlian Ronial Castillo Cabrera de Guatemala, hallados de una camioneta en el agua, dijo el mi\u00e9rcoles la Polic\u00eda Estatal de Maryland.<\/p>\n<p>\u00daltima hora del colapso del puente Key en Baltimore tras el choque de un barco, en vivo<\/p>\n<p>Ahora, el duelo trasciende fronteras.<\/p>\n<p>&#171;Sabemos que nuestra gente est\u00e1 involucrada&#187;, dijo Rafael Laveaga, jefe de la embajada de M\u00e9xico en la secci\u00f3n consular de Washington. \u201cEra un equipo el que estaba reparando partes de los baches en el puente, y ellos son los que van a construir el puente nuevamente: los latinos\u201d.<\/p>\n<p>Los seis trabajadores de la construcci\u00f3n eran inmigrantes de cuatro pa\u00edses diferentes: Honduras, El Salvador, M\u00e9xico y Guatemala. Estas son algunas de sus historias:<\/p>\n<p>Un padre de dos ni\u00f1os que ten\u00eda m\u00faltiples trabajos<\/p>\n<p>A Maynor Yassir Suazo Sandoval le sobreviven su esposa y sus dos hijos, seg\u00fan su hermano. (Cr\u00e9dito: Mart\u00edn Suazo)<\/p>\n<p>Maynor Yassir Suazo Sandoval, de 38 a\u00f1os, fue uno de los trabajadores de la construcci\u00f3n que desaparecieron tras el colapso del puente, dijo su hermano Mart\u00edn Suazo a CNN.<\/p>\n<p>Miembros de la familia en Baltimore llamaron a Mart\u00edn Suazo la madrugada del martes para decirle que su hermano hab\u00eda desaparecido, relat\u00f3 Suazo.<\/p>\n<p>Maynor Suazo era originario de Santa B\u00e1rbara, Honduras, pero se traslad\u00f3 a Estados Unidos en busca de una vida mejor, seg\u00fan su hermano. Maynor llevaba 18 a\u00f1os viviendo en EE.UU. Estaba casado y ten\u00eda dos hijos: un joven de 18 a\u00f1os y una hija de 5, seg\u00fan Mart\u00edn Suazo.<\/p>\n<p>Adem\u00e1s de trabajar como obrero de la construcci\u00f3n, Sandoval era tambi\u00e9n un emprendedor que cre\u00f3 una empresa de mantenimiento, dijo su hermano.<\/p>\n<p>Suazo, que vive en Honduras, a\u00f1adi\u00f3 que su familia est\u00e1 agradecida por el apoyo que han recibido del FBI, la embajada de Honduras en Washington y el gobernador de Maryland, quien prometi\u00f3 hacer todo lo posible para encontrar y recuperar los cuerpos.<\/p>\n<p>Suazo dijo que su familia se aferraba a la esperanza de encontrar a su hermano con vida.<\/p>\n<p>Maynor Suazo, que deja siete hermanos, fue descrito por su hermano Carlos Suazo Sandoval, quien vive en Baltimore, como una persona amable y alegre que ten\u00eda \u201cvisi\u00f3n\u201d.<\/p>\n<p>\u201cA\u00fan tenemos fe hasta este momento, Dios conceda el milagro, ser\u00eda hermoso\u201d, le dijo Carlos a Mar\u00eda Santana de CNN en Espa\u00f1ol este mi\u00e9rcoles. \u201cTodav\u00eda tenemos esperanza, s\u00e9 que el tiempo es nuestro peor enemigo\u201d, afirm\u00f3.<\/p>\n<p>La prioridad de la familia Suazo es encontrar el cuerpo de Maynor, luego podr\u00e1n preocuparse por otra cosas, incluida la carga financiera que la familia de Maynor podr\u00eda enfrentar y contarle la dolorosa noticia a su madre de 72 a\u00f1os en Honduras.<\/p>\n<p>La familia planea repatriar el cuerpo a ese pa\u00eds si lo encuentran, dijo Carlos Suazo.<\/p>\n<p>\u201cHan encontrado autos, pero todav\u00eda no han movido ninguno carro porque hay mucha estructura de acero, y deben tener cuidado porque son seres humanos\u201d, dijo Carlos Suazo.<\/p>\n<p>\u201cAunque est\u00e9n sin vida, nosotros los familiares necesitamos que rescaten los cuerpos al menos para verlos y que se los entreguen a mi familia, a toda su familia, a las personas que son de M\u00e9xico, Guatemala, El Salvador y en el caso de nosotros, que somos hondure\u00f1os\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Un padre de tres hijos que vivi\u00f3 en Maryland durante 19 a\u00f1os<\/p>\n<p>Miguel Luna es esposo y padre de tres hijos. (Obtenida por CNN)<\/p>\n<p>Miguel Luna tambi\u00e9n se encontraba en el puente Francis Scott Key cuando se derrumb\u00f3 el martes, seg\u00fan un comunicado de CASA, una organizaci\u00f3n sin \u00e1nimo de lucro que presta servicios esenciales a familias inmigrantes y de clase trabajadora.<\/p>\n<p>&#171;Lamentablemente, descubrimos que uno de los trabajadores de la construcci\u00f3n implicados era miembro de nuestra familia CASA desde hac\u00eda mucho tiempo, lo que a\u00f1ade una capa a\u00fan m\u00e1s profunda de tristeza a esta situaci\u00f3n ya de por s\u00ed dolorosa&#187;, dijo el director ejecutivo de CASA, Gustavo Torres, en el comunicado.<\/p>\n<p>&#171;Miguel Luna, de El Salvador, sali\u00f3 a las 6:30 p.m. del lunes para ir a trabajar y (&#8230;) no ha regresado a casa. Es esposo, padre de tres hijos y ha llamado a Maryland su hogar durante m\u00e1s de 19 a\u00f1os&#187;, indic\u00f3 el comunicado.<\/p>\n<p>&#171;Toda la regi\u00f3n de Baltimore y la familia CASA lamentan esta tragedia&#187;, dijo Torres. &#171;Nuestros corazones est\u00e1n entristecidos por las familias de las v\u00edctimas y todos los afectados por este horrible accidente&#187;.<\/p>\n<p>CNN ha tratado de comunicarse con los miembros de la familia de Luna para obtener m\u00e1s informaci\u00f3n.<\/p>\n<p>CASA dijo que est\u00e1 trabajando para proporcionar apoyo humanitario mientras las familias se enfrentan a la tragedia y buscan respuestas sobre sus seres queridos desaparecidos.<\/p>\n<p>AMLO confirma tres mexicanos afectados tras colapso del puente de Baltimore 2:35<\/p>\n<p>Ratneswar Roychowdhury, un cliente frecuente del cami\u00f3n de comida que tiene la esposa de Luna, dijo que lo vio por \u00faltima vez echando gasolina el s\u00e1bado. Como Luna no hablaba ingl\u00e9s con fluidez, se comunicaban a trav\u00e9s de una aplicaci\u00f3n de traducci\u00f3n.<\/p>\n<p>&#171;Es muy triste. Habi\u00e9ndolo conocido desde hace casi un a\u00f1o y medio\u2026 es bastante desalentador para todos\u201d, dijo Roychowdhury a CNN mientras estaba parado afuera del cami\u00f3n de comida en Glen Burnie, Maryland.<\/p>\n<p>\u201cRealmente lo siento por su familia. \u00c9l tiene\u2026 familia aqu\u00ed y los cuida a todos. Es muy triste para su familia saber que est\u00e1 desaparecido\u201d.<\/p>\n<p>Un hombre con el sue\u00f1o de ayudar a su familia<\/p>\n<p>Dorlian Castillo Cabrera fue identificado como uno de los trabajadores guatemaltecos desaparecidos tras el colapso del puente en Baltimore. (Cr\u00e9dito: Dorli\u00e1n Castillo)<\/p>\n<p>Dorlian Castillo Cabrera, de Guatemala, era otro de los trabajadores que estaban en el puente en el momento del colapso.<\/p>\n<p>Pima Castillo, cu\u00f1ada de Cabrera, dijo que \u00e9l hab\u00eda trabajado en Brawner Builders durante al menos tres a\u00f1os y que amaba su trabajo. \u00c9l no estaba casado y no ten\u00eda hijos, dijo.<\/p>\n<p>Marlon Castillo, su primo, dijo a CNN que Cabrera vino a Estados Unidos para seguir su sue\u00f1o y ayudar a su madre.<\/p>\n<p>\u201cLamentablemente estaba en un lugar donde nadie se imaginaba lo que iba a pasar\u201d, dijo Marlon Castillo.<\/p>\n<p>Su cuerpo fue recuperado.<\/p>\n<p>Un hombre de familia que deja un enorme &#8216;vac\u00edo&#8217;<\/p>\n<p>En Dundalk, Maryland, el Owls Corner Caf\u00e9 est\u00e1 apoyando a uno de sus empleados, cuyo esposo, Jos\u00e9 Mynor L\u00f3pez, est\u00e1 desaparecido desde que se derrumb\u00f3 el puente.<\/p>\n<p>La esposa de L\u00f3pez, Isabel Franco, trabaja en el caf\u00e9, seg\u00fan la propietaria Lilly Ord\u00f3\u00f1ez.<\/p>\n<p>La empresa inici\u00f3 una p\u00e1gina GoFundMe para Franco y su familia, escribiendo que la familia de L\u00f3pez ahora enfrenta un \u201cfuturo incierto\u201d sin su \u201cprincipal proveedor y pilar de fortaleza\u201d.<\/p>\n<p>\u201c(L\u00f3pez) trabaj\u00f3 incansablemente para garantizar que su familia tuviera todo lo que necesitaba\u201d, seg\u00fan la p\u00e1gina de GoFundMe. &#171;Su repentina ausencia ha dejado un vac\u00edo que no se puede llenar, ni emocional ni econ\u00f3micamente&#187;.<\/p>\n<p>CNN ha buscado confirmaci\u00f3n de las autoridades locales de que L\u00f3pez se encuentra entre los desaparecidos.<\/p>\n<p>Hay mexicanos entre las v\u00edctimas<\/p>\n<p>Hay dos mexicanos entre las v\u00edctimas por el colapso del puente Francis Scott Key en Baltimore, Maryland, seg\u00fan confirm\u00f3 el presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, este mi\u00e9rcoles. El mandatario dijo que una persona herida fue rescatada y est\u00e1 &#171;a salvo&#187;.<\/p>\n<p>El presidente lament\u00f3 lo sucedido y asegur\u00f3 que, aunque sabe qui\u00e9nes y de d\u00f3nde son, no compartir\u00e1 informaci\u00f3n a petici\u00f3n de las familias que est\u00e1n siendo &#171;muy buscadas&#187; por los medios. Agreg\u00f3 que, desde el Gobierno de M\u00e9xico, &#171;se les est\u00e1 apoyando&#187;.<\/p>\n<p>L\u00f3pez Obrador destac\u00f3 que hay otros desaparecidos que son &#171;hermanos de pa\u00edses centroamericanos&#187; y que &#171;la mayor\u00eda de los que est\u00e1n desaparecidos son migrantes&#187;, por lo que el incidente demuestra que &#171;los migrantes van a hacer trabajos a medianoche, trabajos muy riesgosos&#187;. El presidente de M\u00e9xico se\u00f1al\u00f3 que &#171;por eso no merecen ser tratados como suele pasar por algunos pol\u00edticos irresponsables y con poca sensibilidad&#187;.<\/p>\n<p>&#8212; Esta es una historia en desarrollo y ser\u00e1 actualizada.<\/p>\n<p>&#8212; Tina Burnside, Ivonne Vald\u00e9s y Abel Alvarado, todos de CNN, contribuyeron a este informe.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Trabajaban durante el turno de la noche arreglando baches en el famoso puente Francis Scott Key de Baltimore, en el que 30.000 habitantes de Maryland confiaban cada d\u00eda. Pero su labor result\u00f3 en tragedia la madrugada del martes, cuando un barco de carga de m\u00e1s de 96.600 toneladas choc\u00f3 contra el puente, arrojando [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1447525","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQui\u00e9nes son las 6 v\u00edctimas del colapso del puente en Baltimore que se asume est\u00e1n muertas? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/03\/29\/quienes-eran-6-personas-murieron-derrumbe-puente-baltimore-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQui\u00e9nes son las 6 v\u00edctimas del colapso del puente en Baltimore que se asume est\u00e1n muertas? - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Trabajaban durante el turno de la noche arreglando baches en el famoso puente Francis Scott Key de Baltimore, en el que 30.000 habitantes de Maryland confiaban cada d\u00eda. Pero su labor result\u00f3 en tragedia la madrugada del martes, cuando un barco de carga de m\u00e1s de 96.600 toneladas choc\u00f3 contra el puente, arrojando [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/03\/29\/quienes-eran-6-personas-murieron-derrumbe-puente-baltimore-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-29T15:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/29\/quienes-eran-6-personas-murieron-derrumbe-puente-baltimore-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/29\/quienes-eran-6-personas-murieron-derrumbe-puente-baltimore-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfQui\u00e9nes son las 6 v\u00edctimas del colapso del puente en Baltimore que se asume est\u00e1n muertas?\",\"datePublished\":\"2024-03-29T15:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/29\/quienes-eran-6-personas-murieron-derrumbe-puente-baltimore-trax\/\"},\"wordCount\":1579,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/29\/quienes-eran-6-personas-murieron-derrumbe-puente-baltimore-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/29\/quienes-eran-6-personas-murieron-derrumbe-puente-baltimore-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/03\/29\/quienes-eran-6-personas-murieron-derrumbe-puente-baltimore-trax\/\",\"name\":\"\u00bfQui\u00e9nes son las 6 v\u00edctimas del colapso del puente en Baltimore que se asume est\u00e1n muertas? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-29T15:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/29\/quienes-eran-6-personas-murieron-derrumbe-puente-baltimore-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/29\/quienes-eran-6-personas-murieron-derrumbe-puente-baltimore-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/29\/quienes-eran-6-personas-murieron-derrumbe-puente-baltimore-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQui\u00e9nes son las 6 v\u00edctimas del colapso del puente en Baltimore que se asume est\u00e1n muertas?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQui\u00e9nes son las 6 v\u00edctimas del colapso del puente en Baltimore que se asume est\u00e1n muertas? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/03\/29\/quienes-eran-6-personas-murieron-derrumbe-puente-baltimore-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQui\u00e9nes son las 6 v\u00edctimas del colapso del puente en Baltimore que se asume est\u00e1n muertas? - Noticias","og_description":"(CNN) &#8212; Trabajaban durante el turno de la noche arreglando baches en el famoso puente Francis Scott Key de Baltimore, en el que 30.000 habitantes de Maryland confiaban cada d\u00eda. Pero su labor result\u00f3 en tragedia la madrugada del martes, cuando un barco de carga de m\u00e1s de 96.600 toneladas choc\u00f3 contra el puente, arrojando [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/03\/29\/quienes-eran-6-personas-murieron-derrumbe-puente-baltimore-trax\/","og_site_name":"Noticias","article_published_time":"2024-03-29T15:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/03\/29\/quienes-eran-6-personas-murieron-derrumbe-puente-baltimore-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/03\/29\/quienes-eran-6-personas-murieron-derrumbe-puente-baltimore-trax\/"},"author":{"name":"","@id":""},"headline":"\u00bfQui\u00e9nes son las 6 v\u00edctimas del colapso del puente en Baltimore que se asume est\u00e1n muertas?","datePublished":"2024-03-29T15:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/03\/29\/quienes-eran-6-personas-murieron-derrumbe-puente-baltimore-trax\/"},"wordCount":1579,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/03\/29\/quienes-eran-6-personas-murieron-derrumbe-puente-baltimore-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/03\/29\/quienes-eran-6-personas-murieron-derrumbe-puente-baltimore-trax\/","url":"https:\/\/noticiasya.com\/2024\/03\/29\/quienes-eran-6-personas-murieron-derrumbe-puente-baltimore-trax\/","name":"\u00bfQui\u00e9nes son las 6 v\u00edctimas del colapso del puente en Baltimore que se asume est\u00e1n muertas? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-29T15:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/03\/29\/quienes-eran-6-personas-murieron-derrumbe-puente-baltimore-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/03\/29\/quienes-eran-6-personas-murieron-derrumbe-puente-baltimore-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/03\/29\/quienes-eran-6-personas-murieron-derrumbe-puente-baltimore-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQui\u00e9nes son las 6 v\u00edctimas del colapso del puente en Baltimore que se asume est\u00e1n muertas?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/29\/quienes-eran-6-personas-murieron-derrumbe-puente-baltimore-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfQui\u00e9nes son las 6 v\u00edctimas del colapso del puente en Baltimore que se asume est\u00e1n muertas?","url":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/29\/quienes-eran-6-personas-murieron-derrumbe-puente-baltimore-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/29\/quienes-eran-6-personas-murieron-derrumbe-puente-baltimore-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-29T15:03:44Z","datePublished":"2024-03-29T15:03:44Z","dateModified":"2024-03-29T15:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfQui\\u00e9nes son las 6 v\\u00edctimas del colapso del puente en Baltimore que se asume est\\u00e1n muertas?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/29\\\/quienes-eran-6-personas-murieron-derrumbe-puente-baltimore-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/29\\\/quienes-eran-6-personas-murieron-derrumbe-puente-baltimore-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-29T15:03:44Z\",\"datePublished\":\"2024-03-29T15:03:44Z\",\"dateModified\":\"2024-03-29T15:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1447789,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/04\/05\/cuerpo-baltimore-victima-maynor-suazo-sandoval-trax\/","url_meta":{"origin":1447525,"position":0},"title":"Recuperan el cuerpo de Maynor Suazo Sandoval, v\u00edctima del colapso del puente en Baltimore","author":"","date":"abril 5, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 El cuerpo de Maynor Yasir Suazo-Sandoval, una de las v\u00edctimas del colapso del puente Francis Scott Key en Baltimore, fue recuperado este mi\u00e9rcoles, inform\u00f3 un comunicado del Centro de Informaci\u00f3n Conjunta del Puente Key.\u00bfQui\u00e9nes son las 6 v\u00edctimas del colapso del puente en Baltimore?La agencia explic\u00f3 que sus\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447571,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/31\/retiro-escombro-puente-baltimore-canal-trax\/","url_meta":{"origin":1447525,"position":1},"title":"Equipos trabajan para retirar los primeros escombros del puente de Baltimore, con la mira puesta en la apertura de un canal temporal","author":"","date":"marzo 31, 2024","format":false,"excerpt":"(CNN) -- Las cuadrillas est\u00e1n trabajando para retirar la primera parte de los restos del puente de Baltimore, el punto de partida en un proceso de limpieza complicado y extenso que podr\u00eda ayudar a abrir un canal temporal para llevar m\u00e1s embarcaciones al agua alrededor del lugar del colapso, dijeron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447386,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/26\/que-paso-por-que-colapso-puente-baltimore-victimas-fotos-trax\/","url_meta":{"origin":1447525,"position":2},"title":"\u00bfPor qu\u00e9 colaps\u00f3 el puente de Baltimore, cu\u00e1ntas v\u00edctimas hay y qu\u00e9 sabemos del accidente?","author":"","date":"marzo 26, 2024","format":false,"excerpt":"(CNN) -- Un enorme buque de carga se estrell\u00f3 contra el puente Francis Scott Key de Baltimore la madrugada del martes, causando que el puente de 2,5 kil\u00f3metros se desmoronara con autom\u00f3viles y personas al agua helada.Esto es lo que sabemos sobre la cat\u00e1strofe:\u00bfPor qu\u00e9 se derrumb\u00f3 el puente?Poco antes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447539,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/29\/retiro-escombros-puente-baltimore-trax\/","url_meta":{"origin":1447525,"position":3},"title":"&#171;Un trabajo incre\u00edblemente complejo&#187;: as\u00ed limpiar\u00e1n el \u00e1rea del colapsado puente de Baltimore","author":"","date":"marzo 29, 2024","format":false,"excerpt":"(CNN) -- Los equipos que trabajan para despejar la estructura de acero del puente Francis Scott Key y el carguero que lo derrib\u00f3 se enfrentan a \"un trabajo incre\u00edblemente complejo\", esencial para reabrir el puerto de Baltimore y recuperar los restos que puedan yacer bajo los escombros, dijo el jueves\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447496,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/28\/analisis-verdadera-cara-inmigracion-trax\/","url_meta":{"origin":1447525,"position":4},"title":"AN\u00c1LISIS | El colapso del puente de Baltimore refleja la verdadera cara de la inmigraci\u00f3n en EE.UU.","author":"","date":"marzo 28, 2024","format":false,"excerpt":"(CNN) -- Baltimore estaba durmiendo cuando un barco completamente cargado, a la deriva y sin energ\u00eda, se estrell\u00f3 contra el puente Francis Scott Key, derrib\u00e1ndolo en segundos.Si el desastre hubiera ocurrido durante el d\u00eda, cientos de autom\u00f3viles y camiones podr\u00edan haber estado en el puente sobre un canal que conduce\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450207,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/06\/11\/reabren-canal-navegacion-puerto-baltimore-accidente-trax\/","url_meta":{"origin":1447525,"position":5},"title":"Reabren el canal de navegaci\u00f3n del puerto de Baltimore totalmente m\u00e1s de dos meses despu\u00e9s del derrumbe del puente","author":"","date":"junio 11, 2024","format":false,"excerpt":"(CNN) -- El canal de navegaci\u00f3n del puerto de Baltimore vuelve a estar plenamente operativo, seg\u00fan anunciaron este lunes las autoridades a cargo. Pasaron m\u00e1s de dos meses desde que un enorme buque de carga choc\u00f3 contra el puente Francis Scott Key y cort\u00f3 el acceso a la crucial arteria\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1447525"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447525\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1447525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1447525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1447525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}