{"id":1447533,"date":"2024-03-29T11:03:50","date_gmt":"2024-03-29T18:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/29\/eeuu-desestima-cargos-alex-saab-orix\/"},"modified":"2024-03-29T11:03:50","modified_gmt":"2024-03-29T18:03:50","slug":"eeuu-desestima-cargos-alex-saab-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/29\/eeuu-desestima-cargos-alex-saab-orix\/","title":{"rendered":"Justicia de EE.UU. desestima los cargos contra Alex Saab, aliado del gobierno de Maduro"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; La justicia de Estados Unidos desestim\u00f3 este jueves los cargos contra el empresario Alex Saab, aliado cercano del presidente de Venezuela Nicol\u00e1s Maduro. Saab fue liberado por Estados Unidos en diciembre de 2023 a cambio de la liberaci\u00f3n de 10 estadounidenses detenidos por diversos motivos en Venezuela.<\/p>\n<p>El empresario hab\u00eda permanecido detenido dos a\u00f1os por un cargo de conspiraci\u00f3n para cometer lavado de dinero.<\/p>\n<p>El fallo lleva la firma del juez Robert Scola, de la Corte Federal del Distrito Sur de Florida, as\u00ed como de dos fiscales federales, en representaci\u00f3n del Departamento de Justicia de EE.UU.<\/p>\n<p>Las cuentas pendientes de Alex Saab con la justicia colombiana<\/p>\n<p>Saab, un empresario de origen colombiano, recibi\u00f3 en diciembre el perd\u00f3n presidencial de Joe Biden. Hab\u00eda sido detenido en Cabo Verde en junio de 2020 por una notificaci\u00f3n de alerta roja de Interpol y luego extraditado a Estados Unidos en octubre de 2021. Tras su detenci\u00f3n, el gobierno de Maduro afirm\u00f3 que ten\u00eda estatus diplom\u00e1tico y cumpl\u00edauna misi\u00f3n especial para obtener alimentos para importar al pa\u00eds.<\/p>\n<p>EE.UU. acusaba a Saab de estar supuestamente detr\u00e1s de una vasta red de corrupci\u00f3n que involucraba sobreprecios en cajas de alimentos subsidiadas por el Estado venezolano.<\/p>\n<p>CNN est\u00e1 tratando de contactarse con la representaci\u00f3n legal de Saab para conocer su reacci\u00f3n, as\u00ed como la del Gobierno de Venezuela.<\/p>\n<p>La decisi\u00f3n de la Corte de Florida ocurre poco despu\u00e9s de que el Departamento de Estado manifestara su preocupaci\u00f3n por las dificultades de candidatos opositores venezolanos para registrarse en las elecciones presidenciales del 28 de julio, cuya hoja de ruta fue se\u00f1alada en los Acuerdos de Barbados, firmados en octubre.<\/p>\n<p>\u201cVamos a continuar dejando claro a Maduro y a sus representantes, que necesitan garantizar el acceso de observadores internacionales. Necesitan terminar con el encarcelamiento y el acoso a miembros de la sociedad civil y necesitan permitir una elecci\u00f3n libre y justa. Entonces, como hemos dejado claro, las acciones que sean contrarias a la letra y al esp\u00edritu del Acuerdo de Barbados tendr\u00e1n consecuencias\u201d, dijo este jueves el portavoz del Departamento de Estado, Matthew Miller, refiri\u00e9ndose a la situaci\u00f3n en Venezuela.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; La justicia de Estados Unidos desestim\u00f3 este jueves los cargos contra el empresario Alex Saab, aliado cercano del presidente de Venezuela Nicol\u00e1s Maduro. Saab fue liberado por Estados Unidos en diciembre de 2023 a cambio de la liberaci\u00f3n de 10 estadounidenses detenidos por diversos motivos en Venezuela. El empresario hab\u00eda permanecido detenido [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1447533","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Justicia de EE.UU. desestima los cargos contra Alex Saab, aliado del gobierno de Maduro - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/03\/29\/eeuu-desestima-cargos-alex-saab-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Justicia de EE.UU. desestima los cargos contra Alex Saab, aliado del gobierno de Maduro - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; La justicia de Estados Unidos desestim\u00f3 este jueves los cargos contra el empresario Alex Saab, aliado cercano del presidente de Venezuela Nicol\u00e1s Maduro. Saab fue liberado por Estados Unidos en diciembre de 2023 a cambio de la liberaci\u00f3n de 10 estadounidenses detenidos por diversos motivos en Venezuela. El empresario hab\u00eda permanecido detenido [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/03\/29\/eeuu-desestima-cargos-alex-saab-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-29T18:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/29\/eeuu-desestima-cargos-alex-saab-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/29\/eeuu-desestima-cargos-alex-saab-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Justicia de EE.UU. desestima los cargos contra Alex Saab, aliado del gobierno de Maduro\",\"datePublished\":\"2024-03-29T18:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/29\/eeuu-desestima-cargos-alex-saab-orix\/\"},\"wordCount\":410,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/29\/eeuu-desestima-cargos-alex-saab-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/29\/eeuu-desestima-cargos-alex-saab-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/03\/29\/eeuu-desestima-cargos-alex-saab-orix\/\",\"name\":\"Justicia de EE.UU. desestima los cargos contra Alex Saab, aliado del gobierno de Maduro - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-29T18:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/29\/eeuu-desestima-cargos-alex-saab-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/29\/eeuu-desestima-cargos-alex-saab-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/29\/eeuu-desestima-cargos-alex-saab-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Justicia de EE.UU. desestima los cargos contra Alex Saab, aliado del gobierno de Maduro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Justicia de EE.UU. desestima los cargos contra Alex Saab, aliado del gobierno de Maduro - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/03\/29\/eeuu-desestima-cargos-alex-saab-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Justicia de EE.UU. desestima los cargos contra Alex Saab, aliado del gobierno de Maduro - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; La justicia de Estados Unidos desestim\u00f3 este jueves los cargos contra el empresario Alex Saab, aliado cercano del presidente de Venezuela Nicol\u00e1s Maduro. Saab fue liberado por Estados Unidos en diciembre de 2023 a cambio de la liberaci\u00f3n de 10 estadounidenses detenidos por diversos motivos en Venezuela. El empresario hab\u00eda permanecido detenido [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/03\/29\/eeuu-desestima-cargos-alex-saab-orix\/","og_site_name":"Noticias","article_published_time":"2024-03-29T18:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/03\/29\/eeuu-desestima-cargos-alex-saab-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/03\/29\/eeuu-desestima-cargos-alex-saab-orix\/"},"author":{"name":"","@id":""},"headline":"Justicia de EE.UU. desestima los cargos contra Alex Saab, aliado del gobierno de Maduro","datePublished":"2024-03-29T18:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/03\/29\/eeuu-desestima-cargos-alex-saab-orix\/"},"wordCount":410,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/03\/29\/eeuu-desestima-cargos-alex-saab-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/03\/29\/eeuu-desestima-cargos-alex-saab-orix\/","url":"https:\/\/noticiasya.com\/2024\/03\/29\/eeuu-desestima-cargos-alex-saab-orix\/","name":"Justicia de EE.UU. desestima los cargos contra Alex Saab, aliado del gobierno de Maduro - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-29T18:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/03\/29\/eeuu-desestima-cargos-alex-saab-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/03\/29\/eeuu-desestima-cargos-alex-saab-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/03\/29\/eeuu-desestima-cargos-alex-saab-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Justicia de EE.UU. desestima los cargos contra Alex Saab, aliado del gobierno de Maduro"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/29\/eeuu-desestima-cargos-alex-saab-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Justicia de EE.UU. desestima los cargos contra Alex Saab, aliado del gobierno de Maduro","url":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/29\/eeuu-desestima-cargos-alex-saab-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/29\/eeuu-desestima-cargos-alex-saab-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-29T18:03:50Z","datePublished":"2024-03-29T18:03:50Z","dateModified":"2024-03-29T18:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Justicia de EE.UU. desestima los cargos contra Alex Saab, aliado del gobierno de Maduro\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/29\\\/eeuu-desestima-cargos-alex-saab-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/29\\\/eeuu-desestima-cargos-alex-saab-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-29T18:03:50Z\",\"datePublished\":\"2024-03-29T18:03:50Z\",\"dateModified\":\"2024-03-29T18:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1449443,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/05\/13\/estrenan-documental-investigacion-periodistica-alex-saab-aliado-nicolas-maduro-orix\/","url_meta":{"origin":1447533,"position":0},"title":"Estrenan documental con la historia de la investigaci\u00f3n period\u00edstica sobre Alex Saab, aliado de Nicol\u00e1s Maduro","author":"","date":"mayo 13, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0\u201cHubiese sido m\u00e1s f\u00e1cil mirar a otro lado\u201d. Es una idea que siempre tiene presente el periodista Roberto Deniz, quien desde hace m\u00e1s de cinco a\u00f1os no pone un pie en Venezuela tras exiliarse desde 2017 debido a sus investigaciones sobre Alex Saab, aliado del presidente Nicol\u00e1s Maduro\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470233,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/01\/19\/quien-es-alex-saab-maduro-orix\/","url_meta":{"origin":1447533,"position":1},"title":"\u00bfQui\u00e9n es Alex Saab, el empresario colombiano aliado de Maduro al que Delcy Rodr\u00edguez quit\u00f3 del Gabinete de Venezuela?","author":"","date":"enero 19, 2026","format":false,"excerpt":"El empresario colombiano Alex Saab, colaborador cercano del derrocado presidente de Venezuela Nicol\u00e1s Maduro, fue desplazado del Gobierno por la mandataria encargada, Delcy Rodr\u00edguez, en otro cap\u00edtulo de la nueva relaci\u00f3n entre Caracas y Washington, por la que se detuvo, extradit\u00f3 y luego liber\u00f3 al hombre acusado de ser \u201cfinancista\u201d\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442502,"url":"https:\/\/noticiasya.com\/corpus-christi\/2023\/12\/22\/las-cuentas-pendientes-de-alex-saab-con-la-justicia-colombiana\/","url_meta":{"origin":1447533,"position":2},"title":"Las cuentas pendientes de Alex Saab con la justicia colombiana","author":"","date":"diciembre 22, 2023","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La primera vez que se hizo visible el nombre de Alex Saab en el mundo de la pol\u00edtica y los negocios venezolanos fue en 2011 en un acto de firma de convenios entre los Gobiernos de los entonces presidentes de Venezuela, Hugo Ch\u00e1vez, y de Colombia, Juan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":9,"url":"https:\/\/noticiasya.com\/corpus-christi\/2023\/12\/20\/estados-unidos-libera-a-alex-saab-aliado-del-gobierno-de-maduro-a-cambio-de-que-venezuela-deje-en-libertad-a-10-estadounidenses-detenidos-en-el-pais\/","url_meta":{"origin":1447533,"position":3},"title":"Estados Unidos libera a Alex Saab, aliado del Gobierno de Maduro, a cambio de que Venezuela deje en libertad a 10 estadounidenses detenidos en el pa\u00eds","author":"agomez","date":"diciembre 20, 2023","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 Estados Unidos dej\u00f3 en libertad a Alex Saab \u2013\u2013aliado cercano del presidente Nicol\u00e1s Maduro y quien permanec\u00eda detenido en Miami desde octubre de 2021 por un cargo de conspiraci\u00f3n para cometer lavado de dinero\u2013\u2013 a cambio de la liberaci\u00f3n de 10 estadounidenses detenidos por diversos motivos en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/default.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/default.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/default.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/default.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1471649,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/02\/25\/tarek-william-saab-alfredo-ruiz-angulo-renuncias-orix\/","url_meta":{"origin":1447533,"position":4},"title":"Tarek William Saab renuncia como fiscal de Venezuela y asume como defensor del Pueblo encargado","author":"","date":"febrero 25, 2026","format":false,"excerpt":"Tarek William Saab y Alfredo Jos\u00e9 Ruiz Angulo renunciaron este mi\u00e9rcoles a sus cargos como fiscal general y defensor del Pueblo en Venezuela, respectivamente, inform\u00f3 el presidente de la Asamblea Nacional, Jorge Rodr\u00edguez.Durante la sesi\u00f3n del \u00f3rgano legislativo, Rodr\u00edguez ley\u00f3 ambas cartas de renuncia.En la suya, Ruiz Angulo dijo que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471790,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/03\/02\/quien-es-tarek-william-saab-por-que-dejo-fiscal-delcy-orix\/","url_meta":{"origin":1447533,"position":5},"title":"\u00bfQu\u00e9 hay detr\u00e1s de la salida de Tarek William Saab y de los cambios en el Gabinete de Delcy Rodr\u00edguez?","author":"","date":"marzo 2, 2026","format":false,"excerpt":"Al presentar su renuncia como fiscal general de Venezuela, un cargo que ocup\u00f3 por casi 10 a\u00f1os, Tarek William Saab fue nombrado de inmediato como defensor del pueblo encargado. Ese cargo, seg\u00fan analistas consultados por CNN, representa un cambio significativo: aunque tiene menor visibilidad p\u00fablica que en su posici\u00f3n anterior,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1447533"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447533\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1447533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1447533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1447533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}