{"id":1447540,"date":"2024-03-29T15:03:48","date_gmt":"2024-03-29T22:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/29\/testimonios-ecuador-caso-metastasis-orix\/"},"modified":"2024-03-29T15:03:48","modified_gmt":"2024-03-29T22:03:48","slug":"testimonios-ecuador-caso-metastasis-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/29\/testimonios-ecuador-caso-metastasis-orix\/","title":{"rendered":"Testimonios explosivos en Ecuador salpican a decenas de personas dentro del caso Met\u00e1stasis por delincuencia organizada"},"content":{"rendered":"<p>(CNN) &#8212; El caso Met\u00e1stasis en Ecuador va tomando nuevos giros a medida que avanzan las investigaciones de la Fiscal\u00eda sobre la existencia de una presunta estructura criminal que operaba en distintas instituciones del Estado, especialmente dentro del \u00e1mbito judicial.<\/p>\n<p>Un juez de Ecuador dicta prisi\u00f3n preventiva contra 16 procesados por delincuencia organizada en el caso Met\u00e1stasis<\/p>\n<p>El caso Met\u00e1stasis estall\u00f3 en diciembre de 2023 tras un megaoperativo a escala nacional que logr\u00f3 la detenci\u00f3n de exautoridades judiciales, carcelarias, empresarios, abogados, miembros de la fuerza p\u00fablica y l\u00edderes de bandas delincuenciales, entre otros, por su presunta vinculaci\u00f3n con una trama de corrupci\u00f3n y narcotr\u00e1fico. Mientras que a inicios de marzo se hizo p\u00fablico otro caso, bautizado Purga, que es, seg\u00fan la Fiscal\u00eda, una consecuencia del caso Met\u00e1stasis y que busca continuar con la depuraci\u00f3n y limpieza de instituciones corruptas en el pa\u00eds.<\/p>\n<p>Tras la muerte de Leandro Norero, l\u00edder de un grupo vinculado al narcotr\u00e1fico, durante una revuelta carcelaria en 2022, surgieron indicios de una estructura criminal que operaba para favorecerlo y que ha afectado a las instituciones del Estado, seg\u00fan la Fiscal\u00eda.<\/p>\n<p>Dentro del caso Met\u00e1stasis hay 52 procesados y en el caso Purga hay 12 hasta el momento. Varios de los vinculados a las investigaciones han sido se\u00f1alados por recibir dinero, bienes, autos, joyas y otros art\u00edculos a cambio de favorecer a trav\u00e9s de un financiamiento ilegal en procesos judiciales y otorgar beneficios penitenciarios a determinadas personas.<\/p>\n<p>Testimonios anticipados: Rafael Correa se defiende<\/p>\n<p>Este jueves se instal\u00f3 una audiencia en la Corte Nacional de Justicia para recibir cuatro testimonios anticipados de testigos considerados clave por la Fiscal\u00eda dentro del caso.<\/p>\n<p>Marcelo Laso, uno de los testigos de la Fiscal\u00eda, compa\u00f1ero de celda y amigo de Norero, indic\u00f3 que este supuestamente hablaba desde la c\u00e1rcel por videollamada con varios de los ahora procesados en el caso Met\u00e1stasis, y adicionalmente con el expresidente Rafael Correa sobre la situaci\u00f3n jur\u00eddica del exvicepresidente Jorge Glas, quien se encontraba detenido en un penal cumpliendo su sentencia por delitos de corrupci\u00f3n.<\/p>\n<p>&#171;El usuario de Rafael Correa, me parece, era RC5, pues la verdad, hablaron un par de veces. Hablaban de la libertad del se\u00f1or Jorge Glas por fines pol\u00edticos. Sab\u00eda que eventualmente pod\u00eda coger fuerza, pod\u00eda lograr un cargo pol\u00edtico y sab\u00edan que les iban a servir&#187;, precis\u00f3 Laso.<\/p>\n<p>Inmediatamente, el expresidente Correa respondi\u00f3 a estas afirmaciones en sus redes sociales.<\/p>\n<p>&#171;Realmente demencial, pero relativamente sencillo de derrumbar. Tienen el tel\u00e9fono de Norero, confirmen si ah\u00ed existe alguna llamada que haya hecho al usuario RC o RC5 de Threema. M\u00e1s falso que el cuaderno de Hello Kitty&#187;, reaccion\u00f3 Correa.<\/p>\n<p>Laso no est\u00e1 procesado por el caso Met\u00e1stasis, pero la amistad que tuvo con Norero lo hace una pieza clave en la investigaci\u00f3n, seg\u00fan la Fiscal\u00eda.<\/p>\n<p>Mayra Salazar: el testimonio m\u00e1s esperado sobre la manipulaci\u00f3n de la justicia<\/p>\n<p>La exfuncionaria p\u00fablica Mayra Salazar, detenida en diciembre por el caso Met\u00e1stasis y otra de las procesadas por presunta participaci\u00f3n en el delito de delincuencia organizada, es una testigo protegida por la Fiscal\u00eda del Estado en este proceso judicial. Desde hace varias semanas, la Fiscal\u00eda ha ido liberando una serie de chats con conversaciones que involucran a Salazar y otros procesados en esta trama de corrupci\u00f3n. Los chats han sido colgados paulatinamente por la Fiscal\u00eda en sus cuentas oficiales.<\/p>\n<p>Salazar, seg\u00fan la Fiscal\u00eda, era amiga y compa\u00f1era sentimental de Norero y acumulaba una serie de conexiones con pol\u00edticos, narcotraficantes, funcionarios, jueces y personas clave para la manipulaci\u00f3n del sistema de justicia. Salazar no ha confirmado si manten\u00eda una relaci\u00f3n sentimental, pero neg\u00f3 haber visitado alguna de las c\u00e1rceles donde Norero fue recluido.<\/p>\n<p>Durante su testimonio de este jueves, Mayra Salazar \u2014qui\u00e9n lleg\u00f3 a la audiencia fuertemente custodiada por la Polic\u00eda\u2014 pidi\u00f3 disculpas y sostuvo que sus actuaciones &#171;no fueron correctas&#187; y admiti\u00f3 haber ayudado a Norero a tener acercamientos con jueces para lograr fallos favorables en los procesos en su contra. Tambi\u00e9n acept\u00f3 que ayud\u00f3 a otras personas que le ped\u00edan acercamientos con figuras clave del sistema judicial para conseguir favores.<\/p>\n<p>Salazar se desempe\u00f1aba en el \u00e1rea de Comunicaci\u00f3n en la Corte Provincial de Justicia de Guayas, en donde trabaj\u00f3 directamente con la entonces presidenta de la Corte, Fabiola Gallardo, ahora procesada en el caso Purga (secuela del caso Met\u00e1stasis). Gallardo est\u00e1 detenida y CNN est\u00e1 intentando contactar con su defensa.<\/p>\n<p>Al inicio de su intervenci\u00f3n, Salazar anticip\u00f3 que revelar\u00eda qui\u00e9n encabeza, seg\u00fan su versi\u00f3n, el manejo de la justicia en la provincia de Guayas.<\/p>\n<p>&#171;Esto era un dar-dar&#187;<\/p>\n<p>Durante su testimonio, Salazar dijo que el exasamble\u00edsta Pablo Muentes, quien fue detenido dentro del caso Purga, manejaba a la mayor\u00eda de vocales del Consejo de la Judicatura.<\/p>\n<p>&#171;Esto era un dar-dar. Le daban cuotas en el Consejo de la Judicatura, para eso fue mi contrataci\u00f3n&#187;, afirm\u00f3 Salazar. CNN solicit\u00f3 comentarios al abogado de Muentes sobre estas declaraciones y est\u00e1 a la espera de una respuesta.<\/p>\n<p>La semana pasada, Diego Chimbo, abogado de Muentes, expres\u00f3 que el proceso tiene ilegalidades y que la defensa encuentra contradicciones que desvanecen los indicios.<\/p>\n<p>Sobre el asesinato de Fernando Villavicencio<\/p>\n<p>Salazar arremeti\u00f3 contra Muentes y agreg\u00f3 que desconoce si el excandidato presidencial asesinado en agosto de 2023, Fernando Villavicencio, ten\u00eda el mismo nivel de informaci\u00f3n sobre Muentes que ella ten\u00eda, pues Villavicencio manten\u00eda una abierta y dura confrontaci\u00f3n con esta persona antes de ser asesinado.<\/p>\n<p>&#171;No s\u00e9 si Fernando Villavicencio obtuvo la misma informaci\u00f3n que yo obtuve durante los dos a\u00f1os que trabaj\u00e9 con el se\u00f1or Pablo Muentes&#187;, precis\u00f3.<\/p>\n<p>Agreg\u00f3 que si la Fiscal\u00eda investiga m\u00e1s a fondo podr\u00eda encontrar posibles motivaciones detr\u00e1s del crimen del excandidato.<\/p>\n<p>CNN est\u00e1 solicitando a la defensa de Muentes una reacci\u00f3n a este testimonio.<\/p>\n<p>&#171;Mi fin habr\u00eda sido la muerte. Ojal\u00e1 pueda enmendar mis errores&#187;<\/p>\n<p>Al final de su intervenci\u00f3n, Salazar, en medio de l\u00e1grimas, volvi\u00f3 a reconocer que cometi\u00f3 errores y que su vida cambi\u00f3 desde su detenci\u00f3n el 13 de diciembre de 2023 tras el megaoperativo dentro del caso Met\u00e1stasis.<\/p>\n<p>&#171;Mis actuaciones no fueron las correctas. Mi vida tom\u00f3 otro rumbo. Esa Mayra muri\u00f3 el d\u00eda que entr\u00f3 al centro de privaci\u00f3n de libertad. Yo le agradezco se\u00f1ora fiscal por hacer esta investigaci\u00f3n porque m\u00e1s que seguro yo habr\u00eda seguido teniendo contacto con estas personas que no aportaron en nada a mi vida. Mi fin habr\u00eda sido la muerte. Ojal\u00e1 con el apoyo de la justicia en algo pueda enmendar los errores que he cometido&#187;, dijo Salazar.<\/p>\n<p>Los otros dos testigos que presentaron sus testimonios este jueves de forma anticipada hablaron sobre las conexiones entre distintas personas con procesados vinculados en delitos de delincuencia organizada, asociaci\u00f3n il\u00edcita y narcotr\u00e1fico.<\/p>\n<p>Conexiones y narcopol\u00edtica<\/p>\n<p>El caso Met\u00e1stasis es considerado por la fiscal general, Diana Salazar, como uno de los m\u00e1s grandes en la historia contra la corrupci\u00f3n y el narcotr\u00e1fico. En diciembre pasado, la funcionaria dijo que la narcopol\u00edtica ha permeado las fibras m\u00e1s sensibles del Estado ecuatoriano.<\/p>\n<p>\u201cHoy el t\u00e9rmino \u2018narcopol\u00edtica\u2019 en Ecuador ha sido evidente, ya no est\u00e1 lejano (&#8230;) Podemos ver c\u00f3mo las estructuras criminales han permeado las instituciones para lograr sus objetivos\u201d, agreg\u00f3 Salazar.<\/p>\n<p>A mediados de abril terminar\u00e1n los 120 d\u00edas de la etapa de instrucci\u00f3n fiscal en el caso Met\u00e1stasis. Luego de ello, la Fiscal\u00eda pedir\u00e1 que se convoque a la audiencia preparatoria de juicio.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El caso Met\u00e1stasis en Ecuador va tomando nuevos giros a medida que avanzan las investigaciones de la Fiscal\u00eda sobre la existencia de una presunta estructura criminal que operaba en distintas instituciones del Estado, especialmente dentro del \u00e1mbito judicial. Un juez de Ecuador dicta prisi\u00f3n preventiva contra 16 procesados por delincuencia organizada en el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1447540","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Testimonios explosivos en Ecuador salpican a decenas de personas dentro del caso Met\u00e1stasis por delincuencia organizada - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/03\/29\/testimonios-ecuador-caso-metastasis-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Testimonios explosivos en Ecuador salpican a decenas de personas dentro del caso Met\u00e1stasis por delincuencia organizada - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El caso Met\u00e1stasis en Ecuador va tomando nuevos giros a medida que avanzan las investigaciones de la Fiscal\u00eda sobre la existencia de una presunta estructura criminal que operaba en distintas instituciones del Estado, especialmente dentro del \u00e1mbito judicial. Un juez de Ecuador dicta prisi\u00f3n preventiva contra 16 procesados por delincuencia organizada en el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/03\/29\/testimonios-ecuador-caso-metastasis-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-29T22:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/29\/testimonios-ecuador-caso-metastasis-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/29\/testimonios-ecuador-caso-metastasis-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Testimonios explosivos en Ecuador salpican a decenas de personas dentro del caso Met\u00e1stasis por delincuencia organizada\",\"datePublished\":\"2024-03-29T22:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/29\/testimonios-ecuador-caso-metastasis-orix\/\"},\"wordCount\":1359,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/29\/testimonios-ecuador-caso-metastasis-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/29\/testimonios-ecuador-caso-metastasis-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/03\/29\/testimonios-ecuador-caso-metastasis-orix\/\",\"name\":\"Testimonios explosivos en Ecuador salpican a decenas de personas dentro del caso Met\u00e1stasis por delincuencia organizada - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-29T22:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/29\/testimonios-ecuador-caso-metastasis-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/29\/testimonios-ecuador-caso-metastasis-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/29\/testimonios-ecuador-caso-metastasis-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Testimonios explosivos en Ecuador salpican a decenas de personas dentro del caso Met\u00e1stasis por delincuencia organizada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Testimonios explosivos en Ecuador salpican a decenas de personas dentro del caso Met\u00e1stasis por delincuencia organizada - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/03\/29\/testimonios-ecuador-caso-metastasis-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Testimonios explosivos en Ecuador salpican a decenas de personas dentro del caso Met\u00e1stasis por delincuencia organizada - Noticias","og_description":"(CNN) &#8212; El caso Met\u00e1stasis en Ecuador va tomando nuevos giros a medida que avanzan las investigaciones de la Fiscal\u00eda sobre la existencia de una presunta estructura criminal que operaba en distintas instituciones del Estado, especialmente dentro del \u00e1mbito judicial. Un juez de Ecuador dicta prisi\u00f3n preventiva contra 16 procesados por delincuencia organizada en el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/03\/29\/testimonios-ecuador-caso-metastasis-orix\/","og_site_name":"Noticias","article_published_time":"2024-03-29T22:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/03\/29\/testimonios-ecuador-caso-metastasis-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/03\/29\/testimonios-ecuador-caso-metastasis-orix\/"},"author":{"name":"","@id":""},"headline":"Testimonios explosivos en Ecuador salpican a decenas de personas dentro del caso Met\u00e1stasis por delincuencia organizada","datePublished":"2024-03-29T22:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/03\/29\/testimonios-ecuador-caso-metastasis-orix\/"},"wordCount":1359,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/03\/29\/testimonios-ecuador-caso-metastasis-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/03\/29\/testimonios-ecuador-caso-metastasis-orix\/","url":"https:\/\/noticiasya.com\/2024\/03\/29\/testimonios-ecuador-caso-metastasis-orix\/","name":"Testimonios explosivos en Ecuador salpican a decenas de personas dentro del caso Met\u00e1stasis por delincuencia organizada - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-29T22:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/03\/29\/testimonios-ecuador-caso-metastasis-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/03\/29\/testimonios-ecuador-caso-metastasis-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/03\/29\/testimonios-ecuador-caso-metastasis-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Testimonios explosivos en Ecuador salpican a decenas de personas dentro del caso Met\u00e1stasis por delincuencia organizada"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/29\/testimonios-ecuador-caso-metastasis-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Testimonios explosivos en Ecuador salpican a decenas de personas dentro del caso Met\u00e1stasis por delincuencia organizada","url":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/29\/testimonios-ecuador-caso-metastasis-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/29\/testimonios-ecuador-caso-metastasis-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-29T22:03:48Z","datePublished":"2024-03-29T22:03:48Z","dateModified":"2024-03-29T22:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Testimonios explosivos en Ecuador salpican a decenas de personas dentro del caso Met\\u00e1stasis por delincuencia organizada\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/29\\\/testimonios-ecuador-caso-metastasis-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/29\\\/testimonios-ecuador-caso-metastasis-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-29T22:03:48Z\",\"datePublished\":\"2024-03-29T22:03:48Z\",\"dateModified\":\"2024-03-29T22:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1447692,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/04\/03\/allanamientos-detenciones-caso-plaga-ecuador-orix\/","url_meta":{"origin":1447540,"position":0},"title":"Allanamientos y detenciones en el caso Plaga por presunta delincuencia organizada en Ecuador","author":"","date":"abril 3, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La Fiscal\u00eda General del Estado en Ecuador sac\u00f3 a la luz este mi\u00e9rcoles un nuevo caso de delincuencia organizada al que denomin\u00f3 caso Plaga. Investigan la presunta existencia de una nueva estructura criminal dentro del sistema de justicia de ese pa\u00eds.La Fiscal\u00eda inform\u00f3 que, en este caso,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449473,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/05\/14\/fiscalia-ecuador-pide-informacion-paradero-ronny-aleaga-metastasis-orix\/","url_meta":{"origin":1447540,"position":1},"title":"La Fiscal\u00eda de Ecuador pide a asamble\u00edstas informaci\u00f3n sobre el paradero del exlegislador Ronny Aleaga, investigado por el caso Met\u00e1stasis","author":"","date":"mayo 14, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La Fiscal\u00eda de Ecuador pidi\u00f3 a dos asamble\u00edstas, Pamela Aguirre y Lenin Barreto, informaci\u00f3n sobre el paradero del exlegislador Ronny Aleaga, quien es investigado en el caso Met\u00e1stasis y est\u00e1 pr\u00f3fugo de la Justicia por contar con una orden de prisi\u00f3n preventiva.La instituci\u00f3n dio a conocer su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456086,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/11\/25\/sentencian-prision-exfuncionarios-ecuador-caso-metastasis-orix\/","url_meta":{"origin":1447540,"position":2},"title":"Sentencian a prisi\u00f3n a 2 ex altos funcionarios de Ecuador y a otras 18 personas por el caso Met\u00e1stasis","author":"","date":"noviembre 25, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Un tribunal de la Corte Nacional de Justicia de Ecuador conden\u00f3 este lunes por cargos de delincuencia organizada a nueve a\u00f1os y cuatro meses de prisi\u00f3n a dos ex altos funcionarios, en calidad de colaboradores dentro del caso Met\u00e1stasis.Los sentenciados son el expresidente del Consejo de la Judicatura\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446500,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/04\/ecuador-golpe-criminal-justicia-orix\/","url_meta":{"origin":1447540,"position":3},"title":"Nuevo golpe contra posible estructura criminal en la Justicia ecuatoriana deja varios detenidos","author":"","date":"marzo 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La Fiscal\u00eda de Ecuador, junto con la Polic\u00eda Nacional, ejecut\u00f3 en las \u00faltimas horas un operativo en el que fueron detenidas 12 personas en un caso por posible delincuencia organizada, inform\u00f3 el cuerpo judicial en X este lunes en la madrugada.Durante el procedimiento se realizaron allanamientos en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465614,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/08\/18\/ecuador-cargos-autores-asesinato-fernando-villavicencio-orix\/","url_meta":{"origin":1447540,"position":4},"title":"Fiscal\u00eda de Ecuador formular\u00e1 cargos contra presuntos autores intelectuales del asesinato de Fernando Villavicencio","author":"","date":"agosto 18, 2025","format":false,"excerpt":"La Fiscal\u00eda General de Ecuador inform\u00f3 este lunes que ha solicitado a un juez que convoque al exministro del Interior, Jos\u00e9 Serrano; al condenado por delitos de corrupci\u00f3n Daniel Salcedo, quien est\u00e1 en prisi\u00f3n; al exasamble\u00edsta del corre\u00edsmo Ronny Aleaga y al empresario Xavier Jord\u00e1n a una audiencia de formulaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462184,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/05\/09\/ecuador-emboscada-militares-muertos-operacion-mineria-ilegal-orix\/","url_meta":{"origin":1447540,"position":5},"title":"Una emboscada deja 11 militares muertos durante una operaci\u00f3n contra la miner\u00eda ilegal en Ecuador","author":"","date":"mayo 9, 2025","format":false,"excerpt":"El Ej\u00e9rcito de Ecuador inform\u00f3 este viernes que 11 militares murieron y uno result\u00f3 herido luego de que una patrulla fue emboscada durante una operaci\u00f3n contra la miner\u00eda ilegal en el sector de Alto Punino, ubicado en la provincia de Orellana \u2015nororiente del pa\u00eds.Cuatro equipos de combate, en los que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1447540"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447540\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1447540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1447540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1447540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}