{"id":1447562,"date":"2024-03-30T13:03:41","date_gmt":"2024-03-30T20:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/30\/att-filtracion-datos-personales-estados-unidos-dark-web-trax\/"},"modified":"2024-03-30T13:03:41","modified_gmt":"2024-03-30T20:03:41","slug":"att-filtracion-datos-personales-estados-unidos-dark-web-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/30\/att-filtracion-datos-personales-estados-unidos-dark-web-trax\/","title":{"rendered":"AT&#038;T dice que los datos personales de 73 millones de titulares de cuentas en EE.UU. se filtraron a la &#8216;dark web&#8217;"},"content":{"rendered":"<p>Nueva York (CNN) &#8212; AT&#038;T ha iniciado una investigaci\u00f3n sobre el origen de una filtraci\u00f3n de datos que incluye informaci\u00f3n personal de 73 millones de clientes actuales y anteriores en Estados Unidos.<\/p>\n<p>En un comunicado de prensa del s\u00e1bado por la ma\u00f1ana, el gigante de las telecomunicaciones dijo que los datos fueron \u201cpublicados en la dark web hace aproximadamente dos semanas\u201d y contienen informaci\u00f3n como los n\u00fameros de Seguro Social de los titulares de cuentas.<\/p>\n<p>&#171;A\u00fan no se sabe si los datos&#8230; se originaron en AT&#038;T o en uno de sus proveedores&#187;, a\u00f1adi\u00f3 la compa\u00f1\u00eda. &#171;Actualmente, AT&#038;T no tiene evidencia de acceso no autorizado a sus sistemas que haya resultado en la exfiltraci\u00f3n del conjunto de datos&#187;.<\/p>\n<p>El FBI arresta a un sospechoso relacionado con la filtraci\u00f3n de documentos del Pent\u00e1gono<\/p>\n<p>Los datos parecen haber sido de 2019 o antes. Seg\u00fan AT&#038;T, la filtraci\u00f3n no parece contener informaci\u00f3n financiera ni detalles espec\u00edficos sobre el historial de llamadas. La compa\u00f1\u00eda dijo que la filtraci\u00f3n muestra que aproximadamente 7,6 millones de titulares de cuentas actuales y 65,4 millones de antiguos titulares de cuentas se vieron afectados.<\/p>\n<p>AT&#038;T dijo que se est\u00e1 comunicando con los clientes y pidi\u00e9ndoles que restablezcan las contrase\u00f1as de sus cuentas. Tambi\u00e9n insta a los clientes a permanecer alerta sobre cambios en sus cuentas o informes crediticios, y agrega que AT&#038;T &#171;ofrecer\u00e1 monitoreo de cr\u00e9dito a nuestra costa cuando corresponda&#187;.<\/p>\n<p>La empresa fue alertada de una posible filtraci\u00f3n hace unas dos semanas. La noticia de la filtraci\u00f3n fue publicada por primera vez por la cuenta X vx-underground el 17 de marzo.<\/p>\n<p>En ese momento, AT&#038;T le dijo a CNN: \u201cNo tenemos indicios de que nuestros sistemas est\u00e9n comprometidos. En 2021 determinamos que la informaci\u00f3n ofrecida en este foro en l\u00ednea no parec\u00eda provenir de nuestros sistemas. Creemos y estamos trabajando para confirmar que el conjunto de datos discutido hoy es el mismo conjunto de datos que se ha reciclado varias veces en este foro\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nueva York (CNN) &#8212; AT&#038;T ha iniciado una investigaci\u00f3n sobre el origen de una filtraci\u00f3n de datos que incluye informaci\u00f3n personal de 73 millones de clientes actuales y anteriores en Estados Unidos. En un comunicado de prensa del s\u00e1bado por la ma\u00f1ana, el gigante de las telecomunicaciones dijo que los datos fueron \u201cpublicados en la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1447562","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AT&amp;T dice que los datos personales de 73 millones de titulares de cuentas en EE.UU. se filtraron a la &#039;dark web&#039; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/03\/30\/att-filtracion-datos-personales-estados-unidos-dark-web-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AT&amp;T dice que los datos personales de 73 millones de titulares de cuentas en EE.UU. se filtraron a la &#039;dark web&#039; - Noticias\" \/>\n<meta property=\"og:description\" content=\"Nueva York (CNN) &#8212; AT&#038;T ha iniciado una investigaci\u00f3n sobre el origen de una filtraci\u00f3n de datos que incluye informaci\u00f3n personal de 73 millones de clientes actuales y anteriores en Estados Unidos. En un comunicado de prensa del s\u00e1bado por la ma\u00f1ana, el gigante de las telecomunicaciones dijo que los datos fueron \u201cpublicados en la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/03\/30\/att-filtracion-datos-personales-estados-unidos-dark-web-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-30T20:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/30\/att-filtracion-datos-personales-estados-unidos-dark-web-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/30\/att-filtracion-datos-personales-estados-unidos-dark-web-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"AT&#038;T dice que los datos personales de 73 millones de titulares de cuentas en EE.UU. se filtraron a la &#8216;dark web&#8217;\",\"datePublished\":\"2024-03-30T20:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/30\/att-filtracion-datos-personales-estados-unidos-dark-web-trax\/\"},\"wordCount\":393,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/30\/att-filtracion-datos-personales-estados-unidos-dark-web-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/30\/att-filtracion-datos-personales-estados-unidos-dark-web-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/03\/30\/att-filtracion-datos-personales-estados-unidos-dark-web-trax\/\",\"name\":\"AT&T dice que los datos personales de 73 millones de titulares de cuentas en EE.UU. se filtraron a la 'dark web' - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-30T20:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/30\/att-filtracion-datos-personales-estados-unidos-dark-web-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/30\/att-filtracion-datos-personales-estados-unidos-dark-web-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/30\/att-filtracion-datos-personales-estados-unidos-dark-web-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AT&#038;T dice que los datos personales de 73 millones de titulares de cuentas en EE.UU. se filtraron a la &#8216;dark web&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AT&T dice que los datos personales de 73 millones de titulares de cuentas en EE.UU. se filtraron a la 'dark web' - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/03\/30\/att-filtracion-datos-personales-estados-unidos-dark-web-trax\/","og_locale":"es_ES","og_type":"article","og_title":"AT&T dice que los datos personales de 73 millones de titulares de cuentas en EE.UU. se filtraron a la 'dark web' - Noticias","og_description":"Nueva York (CNN) &#8212; AT&#038;T ha iniciado una investigaci\u00f3n sobre el origen de una filtraci\u00f3n de datos que incluye informaci\u00f3n personal de 73 millones de clientes actuales y anteriores en Estados Unidos. En un comunicado de prensa del s\u00e1bado por la ma\u00f1ana, el gigante de las telecomunicaciones dijo que los datos fueron \u201cpublicados en la [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/03\/30\/att-filtracion-datos-personales-estados-unidos-dark-web-trax\/","og_site_name":"Noticias","article_published_time":"2024-03-30T20:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/03\/30\/att-filtracion-datos-personales-estados-unidos-dark-web-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/03\/30\/att-filtracion-datos-personales-estados-unidos-dark-web-trax\/"},"author":{"name":"","@id":""},"headline":"AT&#038;T dice que los datos personales de 73 millones de titulares de cuentas en EE.UU. se filtraron a la &#8216;dark web&#8217;","datePublished":"2024-03-30T20:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/03\/30\/att-filtracion-datos-personales-estados-unidos-dark-web-trax\/"},"wordCount":393,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/03\/30\/att-filtracion-datos-personales-estados-unidos-dark-web-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/03\/30\/att-filtracion-datos-personales-estados-unidos-dark-web-trax\/","url":"https:\/\/noticiasya.com\/2024\/03\/30\/att-filtracion-datos-personales-estados-unidos-dark-web-trax\/","name":"AT&T dice que los datos personales de 73 millones de titulares de cuentas en EE.UU. se filtraron a la 'dark web' - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-30T20:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/03\/30\/att-filtracion-datos-personales-estados-unidos-dark-web-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/03\/30\/att-filtracion-datos-personales-estados-unidos-dark-web-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/03\/30\/att-filtracion-datos-personales-estados-unidos-dark-web-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"AT&#038;T dice que los datos personales de 73 millones de titulares de cuentas en EE.UU. se filtraron a la &#8216;dark web&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/30\/att-filtracion-datos-personales-estados-unidos-dark-web-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"AT&#038;T dice que los datos personales de 73 millones de titulares de cuentas en EE.UU. se filtraron a la &#8216;dark web&#8217;","url":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/30\/att-filtracion-datos-personales-estados-unidos-dark-web-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2024\/03\/30\/att-filtracion-datos-personales-estados-unidos-dark-web-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-30T20:03:41Z","datePublished":"2024-03-30T20:03:41Z","dateModified":"2024-03-30T20:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"AT&#038;T dice que los datos personales de 73 millones de titulares de cuentas en EE.UU. se filtraron a la &#8216;dark web&#8217;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/30\\\/att-filtracion-datos-personales-estados-unidos-dark-web-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2024\\\/03\\\/30\\\/att-filtracion-datos-personales-estados-unidos-dark-web-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-30T20:03:41Z\",\"datePublished\":\"2024-03-30T20:03:41Z\",\"dateModified\":\"2024-03-30T20:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1465558,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/08\/16\/att-reclamo-pago-clientes-trax\/","url_meta":{"origin":1447562,"position":0},"title":"AT&#038;T podr\u00eda pagar a clientes hasta US$ 7.500 en un acuerdo de US$ 177 millones por filtraci\u00f3n de datos","author":"","date":"agosto 16, 2025","format":false,"excerpt":"Millones de clientes de AT&T pueden presentar reclamos por hasta US$ 7.500 en pagos en efectivo como parte de un acuerdo de US$ 177 millones relacionado con una filtraci\u00f3n de datos en 2024.La empresa de telecomunicaciones enfrent\u00f3 un par de filtraciones de datos, anunciadas en marzo y julio de 2024,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452241,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/08\/28\/att-interrupcion-servicio-por-que-pasa-trax\/","url_meta":{"origin":1447562,"position":1},"title":"AT&#038;T sufri\u00f3 otra interrupci\u00f3n del servicio: \u00bfpor qu\u00e9 sigue pasando esto?","author":"","date":"agosto 28, 2024","format":false,"excerpt":"(CNN) -- El servicio inal\u00e1mbrico de AT&T dej\u00f3 de funcionar para algunos clientes el martes, lo que afect\u00f3 su capacidad de comunicarse con el 911 en caso de una emergencia.Se solucion\u00f3 en pocas horas, y la compa\u00f1\u00eda atribuy\u00f3 el problema a un problema de software, pero es solo uno de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445980,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/02\/24\/hijo-presidente-mexico-filtracion-numero-telefonico-amlo-the-new-york-times-orix\/","url_meta":{"origin":1447562,"position":2},"title":"Hijo del presidente de M\u00e9xico denuncia filtraci\u00f3n de n\u00famero telef\u00f3nico tras controversia entre AMLO y periodista de The New York Times","author":"","date":"febrero 24, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 El hijo mayor del presidente de M\u00e9xico Andr\u00e9s Manuel L\u00f3pez Obrador denunci\u00f3 este s\u00e1bado que su n\u00famero de tel\u00e9fono fue filtrado y sugiri\u00f3 que ser\u00eda una represalia a la controversia que desat\u00f3 esta semana el mandatario al revelar los datos personales de una corresponsal de The New\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463310,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/06\/07\/doge-datos-seguro-social-trax\/","url_meta":{"origin":1447562,"position":3},"title":"El DOGE acaba de recibir luz verde para acceder a tus datos del Seguro Social. \u00bfQu\u00e9 significa?","author":"","date":"junio 7, 2025","format":false,"excerpt":"Cuando la gente piensa en el Seguro Social, normalmente piensa en los beneficios mensuales para los aproximadamente 69 millones de jubilados, trabajadores con discapacidad, dependientes y sobrevivientes que los reciben hoy en d\u00eda.Pero los esfuerzos realizados este a\u00f1o por el Departamento de Eficiencia Gubernamental (DOGE, por sus siglas en ingl\u00e9s)\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460395,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/03\/25\/23andme-quiebra-como-eliminar-datos-geneticos-trax\/","url_meta":{"origin":1447562,"position":4},"title":"23andMe est\u00e1 en quiebra y busca vender los datos gen\u00e9ticos de sus clientes; te explicamos c\u00f3mo eliminarlos","author":"","date":"marzo 25, 2025","format":false,"excerpt":"Muchos clientes de 23andMe se registraron en el servicio de pruebas gen\u00e9ticas con la esperanza de obtener informaci\u00f3n interesante sobre su pasado. Sin embargo, los defensores del consumidor ahora instan a estos usuarios a solicitar la eliminaci\u00f3n de sus cuentas y datos del sitio para evitar que su informaci\u00f3n gen\u00e9tica\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458945,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/02\/19\/que-podria-ganar-doge-acceder-datos-seguridad-social-trax\/","url_meta":{"origin":1447562,"position":5},"title":"Qu\u00e9 podr\u00eda ganar DOGE al acceder a sus datos de seguridad social","author":"","date":"febrero 19, 2025","format":false,"excerpt":"Cuando la gente piensa en la seguridad social, generalmente piensa en los beneficios mensuales para los aproximadamente 69 millones de jubilados, trabajadores discapacitados, dependientes y sobrevivientes que los reciben hoy.Pero la noticia de que miembros del Departamento de Eficiencia Gubernamental (DOGE) est\u00e1n buscando acceso a los sistemas de datos de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1447562"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1447562\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1447562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1447562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1447562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}