{"id":1459381,"date":"2025-03-01T19:03:49","date_gmt":"2025-03-02T03:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/01\/detienen-exfuncionarios-michoacan-desvio-recursos-publicos-orix\/"},"modified":"2025-03-01T19:03:49","modified_gmt":"2025-03-02T03:03:49","slug":"detienen-exfuncionarios-michoacan-desvio-recursos-publicos-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2025\/03\/01\/detienen-exfuncionarios-michoacan-desvio-recursos-publicos-orix\/","title":{"rendered":"Detienen al menos tres exfuncionarios del estado mexicano de Michoac\u00e1n, acusados de presunto desv\u00edo de recursos p\u00fablicos"},"content":{"rendered":"<p>Al menos tres exfuncionarios del exgobernador del estado mexicano de Michoac\u00e1n, Silvano Aureoles Conejo (2015-2021), fueron detenidos este s\u00e1bado acusados de presunto desv\u00edo de recursos p\u00fablicos durante esa administraci\u00f3n estatal, de acuerdo con datos del Registro Nacional de Detenciones.<\/p>\n<p>Seg\u00fan datos de dicho registro federal, que forma parte del Sistema Nacional de Informaci\u00f3n en Seguridad P\u00fablica, el listado de exfuncionarios es encabezada por Carlos Maldonado, exsecretario de Finanzas durante el gobierno de Aureoles Conejo, y quien fue detenido en un aeropuerto fuera de M\u00e9xico y enviado de regreso al pa\u00eds a solicitud de las autoridades mexicanas.<\/p>\n<p>En tanto, Mario Delgado Murillo, exdelegado de Finanzas de la Secretar\u00eda de Seguridad P\u00fablica del Estado de Michoac\u00e1n, y Elizabeth Villegas Pineda, exfuncionaria de la Secretar\u00eda de Seguridad P\u00fablica (SSP), fueron arrestados en Morelia, capital de ese estado, seg\u00fan informaci\u00f3n oficial.<\/p>\n<p>CNN ha solicitado m\u00e1s informaci\u00f3n a la Fiscal\u00eda General de M\u00e9xico y al Gobierno de Michoac\u00e1n, pero sin obtener respuesta hasta el momento.<\/p>\n<p>CNN busca informaci\u00f3n sobre si los detenidos cuentan con representaci\u00f3n legal.<\/p>\n<p>El actual gobernador de la entidad, el oficialista Alfredo Ram\u00edrez Bedolla, acusa a su antecesor Aureoles Conejo de presunto desv\u00edo de recursos p\u00fablicos durante su administraci\u00f3n, por lo cual su gobierno ya ha levantado denuncias ante la Fiscal\u00eda General de M\u00e9xico en contra de exfuncionarios.<\/p>\n<p>Ram\u00edrez Bedolla acusa que durante la administraci\u00f3n de Aureoles Conejo se erogaron recursos excesivos para temas de seguridad.<\/p>\n<p>En julio de 2022, Ram\u00edrez Bedolla se reuni\u00f3 con el fiscal general de M\u00e9xico, Alejandro Gertz Manero, para dar seguimiento a dichas denuncias, seg\u00fan informaci\u00f3n del Gobierno de Michoac\u00e1n.<\/p>\n<p>Aureoles Conejo lleg\u00f3 a la gobernaci\u00f3n del estado de Michoac\u00e1n en 2015, abanderado por el Partido de la Revoluci\u00f3n Democr\u00e1tica (PRD), y fue durante su gobierno que la violencia que azota ese estado del occidente de M\u00e9xico se dispar\u00f3. Algunos medios mexicanos se\u00f1alaron al exgobernador de habitar en un b\u00fanker que habr\u00eda sido instalado en su residencia oficial para protegerse de los grupos delincuenciales, algo que el pol\u00edtico neg\u00f3 en mensajes publicados en su cuenta de X (antes Twitter).<\/p>\n<p>\u201cHoy varios medios de comunicaci\u00f3n retomaron la informaci\u00f3n sobre las condiciones en las que viv\u00ed como gobernador de Michoac\u00e1n y al respecto quiero ser muy claro\u201d, dijo Aureoles Conejo en un mensaje publicado en esa red social el 11 de noviembre de 2021.<\/p>\n<p>\u201cNo es un b\u00fanker, es la casa de Gobierno en la que han vivido otros gobernadores de Michoac\u00e1n. No le hice ni un solo arreglo en los tres a\u00f1os que estuve viviendo ah\u00ed. Nada de lo que hay en esa casa se construy\u00f3 en mi administraci\u00f3n\u201d, a\u00f1adi\u00f3 en su mensaje.<\/p>\n<p>Fue en Michoac\u00e1n donde el expresidente Felipe Calder\u00f3n les declar\u00f3 la guerra a los c\u00e1rteles del narcotr\u00e1fico en diciembre de 2006.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al menos tres exfuncionarios del exgobernador del estado mexicano de Michoac\u00e1n, Silvano Aureoles Conejo (2015-2021), fueron detenidos este s\u00e1bado acusados de presunto desv\u00edo de recursos p\u00fablicos durante esa administraci\u00f3n estatal, de acuerdo con datos del Registro Nacional de Detenciones. Seg\u00fan datos de dicho registro federal, que forma parte del Sistema Nacional de Informaci\u00f3n en Seguridad [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459381","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Detienen al menos tres exfuncionarios del estado mexicano de Michoac\u00e1n, acusados de presunto desv\u00edo de recursos p\u00fablicos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/01\/detienen-exfuncionarios-michoacan-desvio-recursos-publicos-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Detienen al menos tres exfuncionarios del estado mexicano de Michoac\u00e1n, acusados de presunto desv\u00edo de recursos p\u00fablicos - Noticias\" \/>\n<meta property=\"og:description\" content=\"Al menos tres exfuncionarios del exgobernador del estado mexicano de Michoac\u00e1n, Silvano Aureoles Conejo (2015-2021), fueron detenidos este s\u00e1bado acusados de presunto desv\u00edo de recursos p\u00fablicos durante esa administraci\u00f3n estatal, de acuerdo con datos del Registro Nacional de Detenciones. Seg\u00fan datos de dicho registro federal, que forma parte del Sistema Nacional de Informaci\u00f3n en Seguridad [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/01\/detienen-exfuncionarios-michoacan-desvio-recursos-publicos-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-02T03:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/01\/detienen-exfuncionarios-michoacan-desvio-recursos-publicos-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/01\/detienen-exfuncionarios-michoacan-desvio-recursos-publicos-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Detienen al menos tres exfuncionarios del estado mexicano de Michoac\u00e1n, acusados de presunto desv\u00edo de recursos p\u00fablicos\",\"datePublished\":\"2025-03-02T03:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/01\/detienen-exfuncionarios-michoacan-desvio-recursos-publicos-orix\/\"},\"wordCount\":545,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/01\/detienen-exfuncionarios-michoacan-desvio-recursos-publicos-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/01\/detienen-exfuncionarios-michoacan-desvio-recursos-publicos-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/01\/detienen-exfuncionarios-michoacan-desvio-recursos-publicos-orix\/\",\"name\":\"Detienen al menos tres exfuncionarios del estado mexicano de Michoac\u00e1n, acusados de presunto desv\u00edo de recursos p\u00fablicos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-02T03:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/01\/detienen-exfuncionarios-michoacan-desvio-recursos-publicos-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/01\/detienen-exfuncionarios-michoacan-desvio-recursos-publicos-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/01\/detienen-exfuncionarios-michoacan-desvio-recursos-publicos-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Detienen al menos tres exfuncionarios del estado mexicano de Michoac\u00e1n, acusados de presunto desv\u00edo de recursos p\u00fablicos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Detienen al menos tres exfuncionarios del estado mexicano de Michoac\u00e1n, acusados de presunto desv\u00edo de recursos p\u00fablicos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/01\/detienen-exfuncionarios-michoacan-desvio-recursos-publicos-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Detienen al menos tres exfuncionarios del estado mexicano de Michoac\u00e1n, acusados de presunto desv\u00edo de recursos p\u00fablicos - Noticias","og_description":"Al menos tres exfuncionarios del exgobernador del estado mexicano de Michoac\u00e1n, Silvano Aureoles Conejo (2015-2021), fueron detenidos este s\u00e1bado acusados de presunto desv\u00edo de recursos p\u00fablicos durante esa administraci\u00f3n estatal, de acuerdo con datos del Registro Nacional de Detenciones. Seg\u00fan datos de dicho registro federal, que forma parte del Sistema Nacional de Informaci\u00f3n en Seguridad [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/01\/detienen-exfuncionarios-michoacan-desvio-recursos-publicos-orix\/","og_site_name":"Noticias","article_published_time":"2025-03-02T03:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/01\/detienen-exfuncionarios-michoacan-desvio-recursos-publicos-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/01\/detienen-exfuncionarios-michoacan-desvio-recursos-publicos-orix\/"},"author":{"name":"","@id":""},"headline":"Detienen al menos tres exfuncionarios del estado mexicano de Michoac\u00e1n, acusados de presunto desv\u00edo de recursos p\u00fablicos","datePublished":"2025-03-02T03:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/01\/detienen-exfuncionarios-michoacan-desvio-recursos-publicos-orix\/"},"wordCount":545,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/01\/detienen-exfuncionarios-michoacan-desvio-recursos-publicos-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/01\/detienen-exfuncionarios-michoacan-desvio-recursos-publicos-orix\/","url":"https:\/\/noticiasya.com\/2025\/03\/01\/detienen-exfuncionarios-michoacan-desvio-recursos-publicos-orix\/","name":"Detienen al menos tres exfuncionarios del estado mexicano de Michoac\u00e1n, acusados de presunto desv\u00edo de recursos p\u00fablicos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-02T03:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/01\/detienen-exfuncionarios-michoacan-desvio-recursos-publicos-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/01\/detienen-exfuncionarios-michoacan-desvio-recursos-publicos-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/01\/detienen-exfuncionarios-michoacan-desvio-recursos-publicos-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Detienen al menos tres exfuncionarios del estado mexicano de Michoac\u00e1n, acusados de presunto desv\u00edo de recursos p\u00fablicos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/03\/01\/detienen-exfuncionarios-michoacan-desvio-recursos-publicos-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Detienen al menos tres exfuncionarios del estado mexicano de Michoac\u00e1n, acusados de presunto desv\u00edo de recursos p\u00fablicos","url":"http:\/\/noticiasya.com\/corpus-christi\/2025\/03\/01\/detienen-exfuncionarios-michoacan-desvio-recursos-publicos-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2025\/03\/01\/detienen-exfuncionarios-michoacan-desvio-recursos-publicos-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-02T03:03:49Z","datePublished":"2025-03-02T03:03:49Z","dateModified":"2025-03-02T03:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Detienen al menos tres exfuncionarios del estado mexicano de Michoac\\u00e1n, acusados de presunto desv\\u00edo de recursos p\\u00fablicos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2025\\\/03\\\/01\\\/detienen-exfuncionarios-michoacan-desvio-recursos-publicos-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2025\\\/03\\\/01\\\/detienen-exfuncionarios-michoacan-desvio-recursos-publicos-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-02T03:03:49Z\",\"datePublished\":\"2025-03-02T03:03:49Z\",\"dateModified\":\"2025-03-02T03:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1459477,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/03\/04\/exgobernador-michoacan-silvano-aureoles-profugo-corrupcion-orix\/","url_meta":{"origin":1459381,"position":0},"title":"Reportan al exgobernador de Michoac\u00e1n Silvano Aureoles como pr\u00f3fugo por acusaciones de corrupci\u00f3n","author":"","date":"marzo 4, 2025","format":false,"excerpt":"Luego de que se le dictara orden de arresto por supuesto peculado y administraci\u00f3n fraudulenta, el exgobernador de Michoac\u00e1n, Silvano Aureoles est\u00e1 pr\u00f3fugo, asegur\u00f3 este lunes el actual mandatario estatal, Alfredo Ram\u00edrez Bedolla.El gobernador agreg\u00f3 que cuatro excolaboradores de Aureoles han sido detenidos, acusados \u2014al igual que el exmandatario\u2014 de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468045,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/11\/05\/asesinato-carlos-manzo-que-sabemos-orix\/","url_meta":{"origin":1459381,"position":1},"title":"Un alcalde asesinado, un presunto atacante abatido y la sombra del crimen en Michoac\u00e1n: qu\u00e9 sabemos del caso de Carlos Manzo","author":"","date":"noviembre 5, 2025","format":false,"excerpt":"El alcalde de Uruapan, Carlos Manzo, muri\u00f3 la noche del s\u00e1bado tras ser atacado con arma de fuego en una plaza p\u00fablica del centro de este municipio del estado de Michoac\u00e1n, en el suroeste de M\u00e9xico.Manzo, de 40 a\u00f1os, encabezaba la alcald\u00eda de Uruapan desde el 1 de septiembre de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456086,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/11\/25\/sentencian-prision-exfuncionarios-ecuador-caso-metastasis-orix\/","url_meta":{"origin":1459381,"position":2},"title":"Sentencian a prisi\u00f3n a 2 ex altos funcionarios de Ecuador y a otras 18 personas por el caso Met\u00e1stasis","author":"","date":"noviembre 25, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Un tribunal de la Corte Nacional de Justicia de Ecuador conden\u00f3 este lunes por cargos de delincuencia organizada a nueve a\u00f1os y cuatro meses de prisi\u00f3n a dos ex altos funcionarios, en calidad de colaboradores dentro del caso Met\u00e1stasis.Los sentenciados son el expresidente del Consejo de la Judicatura\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469031,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/12\/06\/explosion-carro-bomba-muertos-heridos-michoacan-efe\/","url_meta":{"origin":1459381,"position":3},"title":"La explosi\u00f3n de un carro bomba deja dos muertos y siete heridos en el oeste de M\u00e9xico","author":"","date":"diciembre 6, 2025","format":false,"excerpt":"Un ataque con un carro bomba en las instalaciones de la Polic\u00eda Comunitaria del municipio de Coahuayana, en el estado mexicano de Michoac\u00e1n, dej\u00f3 un saldo preliminar de dos personas muertas y al menos siete lesionadas, inform\u00f3 este s\u00e1bado el Gabinete de Seguridad.El organismo inform\u00f3 que las autoridades realizan la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466286,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/09\/09\/mexico-decomiso-combustible-detenciones-que-sigue-orix\/","url_meta":{"origin":1459381,"position":4},"title":"Hist\u00f3rico decomiso de combustible en M\u00e9xico deja primeras detenciones. Expertos dicen que ser\u00eda solo la punta del iceberg","author":"","date":"septiembre 9, 2025","format":false,"excerpt":"El decomiso hist\u00f3rico de 10 millones de litros de gasolina en M\u00e9xico, anunciado por las autoridades locales, destap\u00f3 una compleja red de contrabando que involucra a marinos en actividad, exfuncionarios aduanales y empresarios en un momento clave para la cooperaci\u00f3n en seguridad entre M\u00e9xico y Estados Unidos.El caso ha puesto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450009,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/06\/03\/muere-en-un-supuesto-ataque-armado-la-alcaldesa-de-cotija-michoacan-mexico-orix\/","url_meta":{"origin":1459381,"position":5},"title":"Muere en un supuesto ataque armado la alcaldesa de Cotija, Michoac\u00e1n, M\u00e9xico","author":"","date":"junio 3, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La presidenta municipal de Cotija en el estado de Michoac\u00e1n, Yolanda S\u00e1nchez Figueroa, result\u00f3 muerta en un supuesto atentado, seg\u00fan confirm\u00f3 este martes la Secretar\u00eda de Gobierno del estado de Michoac\u00e1n en su cuenta de X.Seg\u00fan los primeros reportes de medios locales la funcionaria municipal habr\u00eda sido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1459381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1459381"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1459381\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1459381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1459381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1459381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}